{"id":5535,"date":"2023-08-31T11:31:29","date_gmt":"2023-08-31T09:31:29","guid":{"rendered":"https:\/\/aventouralia.com\/quads-rental-marbella\/"},"modified":"2026-04-28T11:15:39","modified_gmt":"2026-04-28T09:15:39","slug":"quads-rental-marbella","status":"publish","type":"page","link":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/","title":{"rendered":"Quads rental Marbella"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium full_height valign_center color_primary with_video with_shape\" id=\"new-header\"><style>@media(max-width:100px){#us_bg_video_wa37{display:none!important}}<\/style><div class=\"l-section-video\" id=\"us_bg_video_wa37\"><video muted loop autoplay playsinline preload=\"auto\"><source type=\"video\/mp4\" src=\"\/wp-content\/uploads\/2025\/06\/VideoPromo_Quads_Horizontal_sin-logo.mp4\" \/><\/video><\/div><div class=\"l-section-overlay\" style=\"background:rgba(0,0,0,0.49)\"><\/div><div class=\"l-section-shape type_custom pos_bottom\" style=\"height:auto;\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"380\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/white-w-e1776339624457.webp\" class=\"attachment-full size-full\" alt=\"white w\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/white-w-e1776339624457.webp 1920w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/white-w-e1776339624457-300x59.webp 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/white-w-e1776339624457-1024x203.webp 1024w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/white-w-e1776339624457-500x99.webp 500w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_b4e4ed46 align_center\"><a target=\"_blank\" href=\"https:\/\/www.tripadvisor.es\/Attraction_Review-g580271-d21179210-Reviews-Aventouralia_Quad_Bike_Tours-Mijas_Costa_del_Sol_Province_of_Malaga_Andalucia.html\" aria-label=\"Link\" class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"99\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Frame-1984077921.webp\" class=\"attachment-medium size-medium\" alt=\"Frame 1984077921\" \/><\/a><\/div><div class=\"wpb_text_column us_custom_3fb917cf has_text_color\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: center;\"><span class=\"pre-title\">Quads rental Marbella<\/span><br \/>\n<span class=\"pre-title-2\">and guided<\/span><span class=\"title\"> guided tours<\/span><\/h1>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_7 grow_ellipse green-btn icon_atleft\" href=\"https:\/\/fareharbor.com\/embeds\/book\/aventouralia\/?full-items=yes&amp;flow=1145467&amp;from-ssl=yes&amp;g4=no&amp;cp=no&amp;csp=no&amp;back=https:\/\/aventouralia.com\/inicio-2&amp;language=es-es&amp;u=d015640d-fa35-4e1a-b7bb-90b42273149d\"><span class=\"fal fa-calendar-alt\"><\/span><span class=\"w-btn-label\">Book now!<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1fab32df height_medium full_height valign_top width_custom\" style=\"--site-content-width:1600px;\" id=\"counter-boxes-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_3cf87c97 counter-box has_text_color iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:4.8rem;\"><svg width=\"96\" height=\"92\" viewBox=\"0 0 96 92\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect width=\"95.0207\" height=\"91.0615\" rx=\"7.91839\" fill=\"#1F1549\"\/>\n<path d=\"M56.044 57.3765C56.0489 57.3715 56.0686 57.3837 56.0772 57.3816C56.0675 57.4347 56.0264 57.3948 56.044 57.3765ZM56.9191 53.5199C56.912 53.533 56.905 53.5462 56.8979 53.5593C56.918 53.5678 56.945 53.5582 56.9637 53.5707C56.9667 53.5727 56.9588 53.6108 56.9661 53.6125C56.9733 53.6141 56.9719 53.5622 56.9824 53.5566C56.9942 53.5506 57.0482 53.5868 57.0669 53.5859C57.1368 53.5824 57.2073 53.5527 57.2773 53.5743C57.205 53.6127 57.2779 53.6518 57.2981 53.6352C57.3026 53.6313 57.3019 53.5347 57.3745 53.5591C57.4206 53.5745 57.378 53.7126 57.4549 53.6434C57.3958 53.5468 57.454 53.5536 57.5003 53.5504C57.5083 53.5498 57.5729 53.5643 57.6014 53.56C57.6112 53.5585 57.6261 53.5079 57.639 53.5066C57.6479 53.5057 57.6547 53.5334 57.6679 53.532C57.7296 53.5258 57.7902 53.5236 57.852 53.533C57.8159 53.663 57.8803 53.5884 57.8832 53.5946C57.898 53.6299 57.8314 53.6399 57.8577 53.662C57.8945 53.658 57.9313 53.6539 57.9681 53.6499C57.9379 53.634 58.0081 53.5404 58.021 53.583C58.0153 53.4681 58.1887 53.683 58.2151 53.6446C58.2206 53.6365 58.1846 53.5797 58.268 53.6057C58.2771 53.6086 58.2737 53.6432 58.2784 53.64C58.2812 53.6381 58.2984 53.5279 58.3167 53.5888C58.3234 53.611 58.2806 53.6834 58.3746 53.6543C58.3372 53.5421 58.5048 53.5935 58.5357 53.6216C58.5295 53.6066 58.5233 53.5915 58.5172 53.5765C58.5477 53.6171 58.5532 53.579 58.56 53.581C58.5877 53.5894 58.6258 53.6278 58.6516 53.6243C58.6817 53.6203 58.6818 53.5505 58.717 53.5777C58.7087 53.5623 58.7003 53.5469 58.692 53.5315C58.7163 53.5352 58.7406 53.5389 58.7649 53.5426C58.7086 53.6349 58.777 53.547 58.7815 53.545C58.7887 53.5417 58.7784 53.5795 58.7904 53.5748C58.7916 53.574 58.7898 53.5384 58.8084 53.5344C58.8471 53.5262 58.841 53.5709 58.8572 53.5704C58.8587 53.5702 58.8535 53.5381 58.8816 53.5305C58.9708 53.5064 58.8811 53.5551 58.8777 53.5595C58.8732 53.5654 58.9038 53.6994 58.828 53.6519C58.8534 53.667 58.856 53.7263 58.8589 53.7277C58.8614 53.7289 58.9055 53.7206 58.9079 53.7186C58.9296 53.6984 58.9105 53.6579 58.9148 53.6506C58.9182 53.6448 58.9713 53.6976 58.9838 53.5757C59.0092 53.6881 58.9692 53.6778 58.9265 53.6951C58.9203 53.7182 58.9671 53.7406 58.9696 53.7405C59.0299 53.7403 58.9965 53.6479 59.0097 53.5888C59.0167 53.5579 59.0413 53.6209 59.0185 53.538C59.0733 53.5293 59.0401 53.5773 59.0436 53.5844C59.049 53.5949 59.0682 53.5711 59.0706 53.5743C59.0741 53.579 59.0618 53.6077 59.0757 53.6178C59.078 53.6192 59.1004 53.5699 59.0716 53.5462C59.1101 53.5533 59.1069 53.5112 59.12 53.596C59.1466 53.4355 59.1393 53.6909 59.1497 53.6999C59.1775 53.7237 59.1695 53.5976 59.1709 53.5914C59.1811 53.552 59.258 53.5954 59.2771 53.5772C59.2696 53.668 59.2161 53.5782 59.2041 53.5958C59.1642 53.6544 59.2603 53.6412 59.2313 53.7553C59.2435 53.7239 59.2556 53.6926 59.2678 53.6613C59.29 53.7346 59.2585 53.7666 59.3184 53.7398C59.3282 53.6765 59.276 53.7498 59.2865 53.6999C59.2926 53.6707 59.3274 53.6644 59.3281 53.649C59.3288 53.6304 59.2974 53.6524 59.3023 53.6238C59.3131 53.5622 59.4276 53.6209 59.3405 53.6545C59.3648 53.6535 59.3773 53.7761 59.3984 53.7379C59.412 53.7131 59.3353 53.5437 59.4504 53.5748C59.4529 53.6327 59.4044 53.5919 59.4031 53.5963C59.4014 53.6027 59.4101 53.7334 59.4116 53.7398C59.417 53.7611 59.5346 53.6911 59.5594 53.7567C59.5496 53.6812 59.6482 53.7433 59.6589 53.7202C59.6618 53.7139 59.6511 53.6676 59.6542 53.6627C59.6733 53.6336 59.7248 53.7162 59.7488 53.7183C59.7756 53.7207 59.7722 53.6808 59.7737 53.6809C59.7855 53.6831 59.776 53.7102 59.7832 53.7101C59.7941 53.71 59.8689 53.7155 59.8727 53.7099C59.8738 53.7081 59.8616 53.6624 59.8779 53.6538C59.8807 53.6523 59.8789 53.7064 59.9272 53.683C59.9854 53.6549 59.8868 53.6157 59.911 53.5591C59.9483 53.6397 59.9471 53.5598 59.9573 53.5661C59.9608 53.5684 59.9869 53.6363 60.0152 53.632C59.9949 53.6431 59.9745 53.6541 59.9542 53.6651C59.9742 53.6771 60.013 53.6623 60.0295 53.6758C60.0376 53.6823 60.0309 53.7382 60.0484 53.7367C60.0521 53.7361 60.0668 53.6 60.0211 53.661C60.0174 53.6124 60.0392 53.6441 60.0493 53.6303C60.0508 53.6282 60.0568 53.547 60.0697 53.5975C60.0728 53.6099 60.0391 53.8467 60.1261 53.6753C60.1289 53.6698 60.1191 53.6401 60.1219 53.634C60.1237 53.6298 60.1459 53.6418 60.1484 53.6376C60.1509 53.6331 60.1402 53.6007 60.1432 53.5943C60.1585 53.5615 60.1786 53.6899 60.147 53.6801C60.1575 53.696 60.1681 53.7119 60.1786 53.7277C60.1674 53.631 60.1952 53.7005 60.2098 53.6975C60.3034 53.6785 60.2407 53.6155 60.2568 53.583C60.2827 53.5307 60.2629 53.6963 60.3013 53.6465C60.3049 53.6419 60.2585 53.5716 60.3491 53.6113C60.3358 53.614 60.3224 53.6167 60.309 53.6195C60.3167 53.7131 60.3573 53.6131 60.3604 53.6117C60.396 53.5989 60.372 53.6326 60.4248 53.5844C60.4296 53.5801 60.4398 53.6032 60.4499 53.5917C60.4918 53.5442 60.3947 53.5629 60.3921 53.525C60.3908 53.5064 60.4952 53.5111 60.4988 53.5199C60.514 53.559 60.4515 53.5371 60.4634 53.5856C60.4677 53.6029 60.6165 53.5675 60.6464 53.5864C60.6808 53.6083 60.6963 53.7352 60.6965 53.5926C60.7063 53.7326 60.7148 53.6371 60.7192 53.6381C60.7725 53.651 60.7726 53.6524 60.8183 53.639C60.8284 53.6361 60.8369 53.6786 60.8405 53.6714C60.8425 53.6671 60.8387 53.6217 60.8488 53.6076C60.863 53.5884 60.9479 53.6352 60.9542 53.6603C60.9605 53.6854 60.9183 53.6712 60.9259 53.7125C60.9564 53.7167 60.9857 53.7065 61.0164 53.7108C61.0292 53.7127 61.0226 53.7417 61.0281 53.7422C61.0305 53.7426 61.0746 53.7171 61.0727 53.7065C61.0683 53.6817 60.9322 53.6983 60.9681 53.6477C60.975 53.638 60.9994 53.7046 60.9955 53.6236C61.1171 53.6419 61.2387 53.6603 61.3603 53.6787C61.2904 53.7393 61.2118 53.6851 61.1386 53.6908C61.1286 53.6915 61.0947 53.6836 61.0988 53.7246C61.161 53.7352 61.2384 53.7139 61.2982 53.7405C61.3001 53.7414 61.293 53.7782 61.3002 53.784C61.3136 53.7949 61.3572 53.7356 61.3645 53.7509C61.3658 53.7545 61.341 53.803 61.3485 53.8338C61.3679 53.9129 61.3728 53.7377 61.3894 53.7398C61.4023 53.7415 61.4888 53.8262 61.5104 53.7727C61.5333 53.7156 61.4466 53.7396 61.453 53.6929C61.5117 53.6461 61.5711 53.6961 61.6265 53.6903C61.6274 53.6901 61.619 53.6536 61.6313 53.6485C61.6528 53.6396 61.6585 53.6914 61.669 53.6997C61.6803 53.7085 61.7202 53.7011 61.7255 53.72C61.7262 53.7225 61.7181 53.7739 61.7169 53.7753C61.6995 53.7965 61.6933 53.7298 61.6917 53.7289C61.6858 53.7264 61.68 53.752 61.6745 53.7505C61.6656 53.7479 61.6607 53.7243 61.6489 53.7222C61.6407 53.7206 61.6486 53.7661 61.6408 53.764C61.6379 53.763 61.6068 53.6593 61.6039 53.7652C61.603 53.7986 61.8569 53.8414 61.8823 53.8147C61.8605 53.802 61.8388 53.7893 61.817 53.7765C61.8612 53.8075 61.9143 53.723 61.9181 53.8481C62.082 53.8583 62.2459 53.8685 62.4099 53.8788C62.4391 53.8894 62.4231 53.9698 62.4712 53.9464C62.4588 53.9208 62.4464 53.8952 62.4339 53.8696C62.4586 53.8876 62.568 53.9227 62.5857 53.9061C62.588 53.9039 62.5911 53.8311 62.6185 53.8249C62.6427 53.8194 62.6466 53.8739 62.6596 53.8843C62.6705 53.8929 62.6827 53.8787 62.6859 53.8817C62.6884 53.8841 62.6894 53.9174 62.6953 53.9232C62.7142 53.9412 62.6989 53.8473 62.7176 53.9551C62.7131 53.9592 62.7085 53.9634 62.704 53.9675C62.7267 53.9831 62.7577 54.032 62.7243 54.0561C62.7185 54.0603 62.7234 54.0281 62.7192 54.0281C62.5511 54.0341 62.6853 54.0968 62.7442 54.0467C62.7593 54.0945 62.8441 54.0653 62.8469 54.0748C62.8508 54.0884 62.8363 54.1266 62.8554 54.1596C62.8594 54.1666 62.9727 54.1398 62.9319 54.2033C62.9235 54.2164 62.8691 54.2027 62.856 54.2045C62.8868 54.3058 62.9591 54.1607 62.9672 54.1644C63 54.1802 62.9043 54.2522 62.9781 54.264C63.0349 54.273 62.9816 54.2054 63.0034 54.1765C63.0157 54.1603 63.08 54.2348 63.0782 54.1383C63.1003 54.128 63.0874 54.1791 63.0901 54.1828C63.0927 54.186 63.1361 54.1571 63.1502 54.1775C63.1519 54.18 63.1465 54.2301 63.1483 54.2343C63.1517 54.2413 63.1936 54.2313 63.1952 54.227C63.1963 54.2241 63.1863 54.1801 63.1904 54.1695C63.1952 54.1572 63.2355 54.1675 63.2377 54.155C63.2408 54.136 63.1911 54.1485 63.1994 54.0994C63.2223 54.1118 63.2596 54.079 63.2747 54.0395C63.271 54.0508 63.2488 54.0524 63.2411 54.0484C63.2447 53.9765 63.2924 53.9775 63.2761 54.0344C63.2865 54.0038 63.2794 53.9876 63.2852 53.9588C63.2868 53.9515 63.3015 53.9499 63.3043 53.9375C63.3047 53.935 63.2895 53.9079 63.2926 53.8933C63.2981 53.8669 63.3427 53.8728 63.3464 53.8797C63.3566 53.8994 63.3202 53.9231 63.3172 53.9534C63.3168 53.9581 63.3477 54.0175 63.3482 54.0228C63.35 54.0791 63.3156 54.0385 63.3195 54.0893C63.328 54.1 63.3365 54.1107 63.3451 54.1214C63.3122 54.1728 63.2514 54.1463 63.2357 54.2048C63.2845 54.1874 63.3354 54.1894 63.3353 54.321C63.3353 54.3764 63.3143 54.4089 63.3151 54.423C63.3182 54.4734 63.3474 54.4186 63.3484 54.4213C63.3493 54.4244 63.3497 54.4274 63.3497 54.4303C63.3497 54.4303 63.3497 54.4303 63.3497 54.4303C63.3497 54.4598 63.3081 54.481 63.3061 54.4945C63.3026 54.5185 63.3211 54.617 63.321 54.6388C63.3204 54.6432 63.2908 54.6665 63.3008 54.7045C63.3109 54.7429 63.3368 54.7438 63.3377 54.7478C63.3427 54.7708 63.2973 54.7917 63.296 54.8053C63.2953 54.8122 63.3196 54.8543 63.3203 54.8664C63.3209 54.8786 63.3024 54.9051 63.2951 54.9435C63.2897 54.972 63.3055 54.9939 63.3027 54.9984C63.3007 55.0013 63.2579 55.0009 63.2558 55.0059C63.2527 55.0133 63.2627 55.0474 63.2612 55.0559C63.2592 55.0682 63.2453 55.0558 63.2471 55.0685C63.2485 55.0779 63.3021 55.1954 63.3018 55.2267C63.3012 55.2803 63.2444 55.1571 63.2972 55.3684C63.2976 55.3697 63.3104 55.3547 63.3108 55.356C63.3187 55.3949 63.2775 55.4547 63.3279 55.4442C63.2341 55.5117 63.3163 55.5247 63.3024 55.6149C63.297 55.6495 63.2606 55.6638 63.2605 55.669C63.264 55.7129 63.2756 55.6788 63.2795 55.7004C63.2817 55.7124 63.2492 55.7589 63.2565 55.7891C63.2603 55.8046 63.2948 55.7991 63.2962 55.8021C63.3099 55.8307 63.2932 55.8616 63.2962 55.8819C63.2981 55.8955 63.319 55.8966 63.3195 55.899C63.3204 55.9041 63.2921 55.9592 63.2862 55.9785C63.2817 55.9934 63.2986 56.0168 63.2954 56.0233C63.2766 56.0621 63.2365 55.9631 63.2751 56.1018C63.2775 56.1103 63.2921 56.1069 63.2925 56.1086C63.3016 56.1479 63.2747 56.1513 63.2698 56.1835C63.2616 56.2389 63.3002 56.208 63.2681 56.247C63.2922 56.2833 63.3057 56.2818 63.3339 56.2717C63.2557 56.2999 63.2281 56.4435 63.3149 56.4399C63.2873 56.4376 63.2904 56.5187 63.2821 56.5201C63.277 56.5209 63.237 56.4403 63.2553 56.6211C63.2576 56.6437 63.282 56.615 63.2743 56.6612C63.216 56.6494 63.2731 56.6906 63.2732 56.6968C63.2724 56.8033 63.1298 56.716 63.1053 56.7282C63.0769 56.7423 63.0517 56.8262 63.0455 56.8263C63.0251 56.8263 63.042 56.7837 63.0375 56.768C63.0329 56.7525 62.975 56.8342 62.9722 56.8297C62.961 56.8117 62.9723 56.7612 62.9712 56.7586C62.9573 56.7277 62.8797 56.7672 62.8579 56.7555C62.8586 56.7882 62.9022 56.7908 62.875 56.8434C62.8433 56.9048 62.8414 56.7604 62.8406 56.754C62.6952 56.7554 62.5499 56.7568 62.4045 56.7581C62.4063 56.835 62.5013 56.777 62.5035 56.7871C62.5162 56.847 62.3557 56.8459 62.336 56.8188C62.3509 56.8354 62.3659 56.852 62.3808 56.8686C62.3553 56.9569 62.2988 56.8422 62.2618 56.8811C62.2499 56.8938 62.2728 56.9279 62.2723 56.9302C62.2589 56.9645 62.2374 56.9381 62.2535 56.892C62.2207 56.9361 62.2255 56.8875 62.2004 56.8838C62.1991 56.8836 62.2099 56.9193 62.19 56.9341C62.1806 56.941 62.131 56.9411 62.1243 56.9722C62.1216 56.9854 62.1468 57.1236 62.1499 57.0046C62.2039 57.0626 62.1672 56.9504 62.1882 56.9532C62.1914 56.9538 62.184 57.0202 62.2368 56.9889C62.2268 57.1087 62.1659 57.0191 62.1554 57.0336C62.1339 57.0634 62.2226 57.1253 62.2389 57.0319C62.2313 57.1254 62.2452 57.0445 62.265 57.0484C62.2866 57.0525 62.2772 57.0804 62.2889 57.0805C62.3209 57.0812 62.3076 57.0153 62.334 57.0747C62.3083 56.8906 62.3793 57.0504 62.3999 57.0986C62.3663 57.108 62.3326 57.1173 62.299 57.1267C62.3009 57.1363 62.3029 57.146 62.3048 57.1557C62.2959 57.1543 62.2871 57.1529 62.2782 57.1516C62.2796 57.1423 62.281 57.133 62.2825 57.1238C62.2368 57.184 62.2256 57.1163 62.2219 57.1156C62.1739 57.1077 62.1185 57.1083 62.07 57.1081C62.0628 57.108 62.0678 57.1683 62.0147 57.1211C61.9978 57.1061 62.0138 57.0592 61.9946 57.0663C61.9706 57.1936 61.9711 57.092 61.964 57.0919C61.9435 57.0919 61.931 57.1234 61.9291 57.1238C61.9038 57.1287 61.8668 57.1234 61.839 57.1281C61.8385 57.1286 61.853 57.1677 61.8349 57.1562C61.8286 57.152 61.7718 56.985 61.7221 57.0394C61.735 57.0507 61.7479 57.062 61.7609 57.0733C61.7457 57.0575 61.6392 57.0996 61.6653 57.1443C61.6812 57.1716 61.7202 57.064 61.7244 57.1675C61.689 57.1365 61.4934 57.1829 61.4782 57.1588C61.476 57.1554 61.489 57.1218 61.4861 57.1175C61.4838 57.1142 61.439 57.1222 61.4331 57.1093C61.4295 57.1016 61.4493 57.081 61.4477 57.0689C61.4463 57.0603 61.3904 57.0459 61.3872 57.088C61.4009 57.0711 61.4395 57.0859 61.4193 57.1214C61.4167 57.1258 61.4032 57.0986 61.4 57.1042C61.3706 57.1558 61.4584 57.1434 61.472 57.1438C61.4169 57.1975 61.3316 57.1342 61.2677 57.1692C61.2419 57.1342 61.306 57.1156 61.2768 57.0866C61.2162 57.0264 61.2606 57.135 61.2588 57.1395C61.2437 57.1748 61.1925 56.9853 61.1924 57.1296C61.1705 57.1079 61.1776 57.0897 61.1466 57.1085C61.1507 57.1185 61.1547 57.1285 61.1588 57.1385C61.1244 57.2221 61.0516 57.0113 61.057 56.9952C61.0717 56.9522 61.1096 57.0193 61.1129 57.0177C61.1177 57.0153 61.1309 56.8689 61.1834 56.9998C61.2049 56.9016 61.1002 56.9335 61.1478 56.8666C61.1157 56.8776 60.9834 56.8093 60.9643 56.8524C60.962 56.858 60.9726 56.9558 60.9399 56.906C60.9244 56.8823 60.9618 56.8812 60.9547 56.8589C60.9329 56.7905 60.6357 56.8343 60.5792 56.8379C60.5756 56.838 60.5769 56.8076 60.5733 56.8079C60.5623 56.8088 60.522 56.854 60.5022 56.8401C60.5432 56.8962 60.4635 56.9006 60.4433 56.8944C60.4125 56.885 60.4144 56.8316 60.4011 56.8202C60.3499 56.7765 60.2706 56.9033 60.2308 56.7847C60.233 56.9024 60.162 56.727 60.1297 56.726C60.1044 56.7252 60.0677 56.803 60.1018 56.8505C60.0582 56.845 60.0122 56.867 59.9713 56.8741C59.9645 56.8753 59.9738 56.8405 59.9622 56.8437C59.9612 56.8442 59.9598 56.8783 59.9498 56.8819C59.868 56.9116 59.9078 56.8391 59.8925 56.8178C59.8839 56.8059 59.8776 56.8 59.8729 56.798C59.9207 56.7913 59.9757 56.778 59.9904 56.777C59.9779 56.7017 59.8846 56.7915 59.8573 56.7712C59.8564 56.7705 59.8597 56.729 59.8587 56.7287C59.8587 56.7287 59.8587 56.7287 59.8587 56.7287C59.8484 56.7255 59.7833 56.7408 59.7967 56.7903C59.8003 56.8035 59.8303 56.8035 59.8659 56.799C59.8562 56.8083 59.8634 56.8548 59.8617 56.8567C59.8411 56.8797 59.7906 56.8343 59.7727 56.8282C59.7686 56.8269 59.7689 56.8567 59.7683 56.8567C59.752 56.85 59.7587 56.7649 59.742 56.8526C59.7125 56.7466 59.7972 56.8369 59.7913 56.768C59.7867 56.715 59.5984 56.7435 59.599 56.827C59.5983 56.8181 59.5957 56.807 59.5904 56.7944C59.5786 56.7664 59.5262 56.7751 59.5172 56.7905C59.5157 56.7936 59.5163 56.8746 59.5144 56.8753C59.5096 56.8772 59.4456 56.8137 59.4217 56.8616C59.4346 56.8729 59.4475 56.8843 59.4604 56.8956C59.3824 56.8963 59.3945 56.9205 59.4205 56.9447C59.4218 56.9449 59.423 56.948 59.4243 56.9483C59.4444 56.9662 59.4702 56.9835 59.4706 56.9899C59.4721 57.0143 59.3398 57.0279 59.3652 56.9527C59.3688 56.9424 59.43 56.9759 59.3997 56.9222C59.3944 56.9128 59.3551 56.9281 59.353 56.9222C59.3392 56.8829 59.425 56.8307 59.4145 56.7748C59.3937 56.828 59.367 56.8 59.3431 56.8137C59.3322 56.8199 59.3295 56.8606 59.3282 56.8613C59.3081 56.8719 59.3194 56.8293 59.3127 56.8304C59.3091 56.8311 59.2695 56.9218 59.277 56.7968C59.1468 56.8888 59.241 56.8887 59.3209 56.8816C59.2956 56.9272 59.2462 56.9051 59.2239 56.9157C59.216 56.9195 59.2207 56.9612 59.2072 56.9696C59.1795 56.9868 59.0473 56.9388 59.0128 56.9275C59.034 56.9128 59.0278 56.8674 59.0115 56.8705C58.9951 56.8737 59.0089 56.9343 59.0057 56.9408C59.0023 56.9476 58.9256 56.919 58.9129 56.9268C58.9706 56.9049 58.9576 56.8595 58.9086 56.8548C58.9157 56.8418 58.9227 56.8287 58.9298 56.8157C58.9011 56.834 58.8408 56.7649 58.8242 56.7854C58.8216 56.7888 58.8309 56.8268 58.8295 56.8287C58.8149 56.8449 58.7654 56.806 58.7631 56.819C58.7612 56.8299 58.7823 56.8618 58.7744 56.8775C58.7728 56.8808 58.7525 56.8293 58.7324 56.842C58.725 56.8467 58.7294 56.8827 58.7276 56.8848C58.7119 56.9021 58.7212 56.8414 58.6926 56.8512C58.6717 56.8584 58.6561 56.9177 58.6272 56.8981C58.7221 56.9737 58.6423 56.9421 58.6027 56.965C58.5963 56.9687 58.6018 57.0341 58.5638 57.0022C58.6446 56.884 58.5407 56.9397 58.5194 56.9384C58.5183 56.938 58.5179 56.8949 58.5075 56.8942C58.5066 56.8942 58.5078 56.9234 58.4981 56.9256C58.4062 56.9467 58.465 56.9138 58.4476 56.885C58.4401 56.8728 58.3954 56.914 58.3834 56.915C58.3806 56.9151 58.3819 56.8848 58.3712 56.886C58.3522 56.8882 58.3353 56.9204 58.3228 56.923C58.3213 56.9231 58.3213 56.8753 58.2975 56.8908C58.2909 56.8951 58.2834 56.9121 58.2929 56.9259C58.3243 56.971 58.3838 56.8928 58.4193 56.9379C58.4516 56.979 58.3496 56.9829 58.3443 56.9831C58.3424 56.9833 58.3623 56.9595 58.342 56.9549C58.3248 56.9509 58.2932 57.0335 58.2674 57.0155C58.2654 57.0142 58.2449 56.9442 58.2458 56.9401C58.2467 56.9371 58.2783 56.9219 58.2737 56.9017C58.2731 56.8994 58.253 56.8998 58.2504 56.8848C58.2472 56.8664 58.2386 56.6863 58.2343 56.6818C58.2233 56.6706 58.2304 56.7117 58.2233 56.7088C58.208 56.7028 58.1551 56.6495 58.1533 56.712C58.1621 56.7157 58.1708 56.7194 58.1796 56.7231C58.1309 56.7295 58.1517 56.7561 58.1448 56.7678C58.1373 56.7805 58.1394 56.7256 58.123 56.7204C58.1194 56.7193 58.0508 56.7308 58.052 56.7538C58.09 56.7171 58.0759 56.785 58.0777 56.7862C58.0843 56.7906 58.0928 56.7526 58.1018 56.7533C58.1645 56.7593 58.1012 56.8193 58.116 56.8347C58.1211 56.8399 58.1313 56.8075 58.1335 56.8091C58.1405 56.8145 58.1406 56.857 58.1453 56.8536C58.1563 56.8456 58.1435 56.7854 58.1443 56.7823C58.1541 56.7446 58.1925 56.7915 58.1686 56.857C58.1829 56.8806 58.1846 56.801 58.196 56.8328C58.2186 56.8958 58.1847 56.8796 58.1755 56.8901C58.1427 56.9278 58.1329 56.8973 58.0863 56.9077C58.0696 56.9114 58.0497 56.9501 58.0419 56.9522C58.037 56.9535 57.9908 56.819 57.9894 57.0295C57.9714 57.0092 57.9432 56.8705 57.9247 56.8768C57.908 56.8826 57.9133 56.957 57.9118 56.9599C57.9094 56.9645 57.8893 56.9586 57.8825 56.9691C57.8745 56.9815 57.8785 57.01 57.8658 57.0215C57.8344 57.0503 57.8352 56.9743 57.8319 56.9694C57.7944 56.9123 57.8108 57.0204 57.8025 57.029C57.7947 57.037 57.686 56.9954 57.6631 57.0228C57.6724 57.0075 57.6818 56.9923 57.6911 56.9771C57.6744 56.9297 57.6567 57.007 57.6564 56.922C57.653 57.0592 57.6186 56.9675 57.6083 56.971C57.6042 56.9725 57.6045 56.9959 57.5995 56.9969C57.5795 57.001 57.5346 56.9824 57.5238 56.9942C57.4771 57.0453 57.5966 57.1302 57.606 57.1354C57.5872 57.1339 57.4807 57.1646 57.5296 57.2306C57.5372 57.2408 57.5506 57.1793 57.5548 57.1769C57.5836 57.1611 57.561 57.2162 57.5632 57.2214C57.5671 57.2299 57.586 57.1766 57.591 57.183C57.5927 57.185 57.5819 57.2349 57.6094 57.2359C57.5959 57.2842 57.5188 57.2449 57.5086 57.2562C57.505 57.2603 57.5276 57.3635 57.4616 57.2632C57.4624 57.2728 57.4632 57.2824 57.4639 57.292C57.4272 57.2959 57.3905 57.2999 57.3537 57.3038C57.3577 57.2817 57.3783 57.2374 57.3524 57.2468C57.3374 57.2522 57.3485 57.3014 57.3471 57.3028C57.3337 57.3164 57.0961 57.3 57.0501 57.3055C57.0344 57.3073 56.9907 57.3468 56.9874 57.3475C56.9675 57.3515 56.897 57.3258 56.883 57.3314C56.8742 57.3349 56.8825 57.3761 56.8747 57.3741C56.8674 57.3723 56.8749 57.3325 56.8728 57.3309C56.8548 57.3165 56.7186 57.3686 56.6862 57.3311C56.706 57.3424 56.8047 57.263 56.8027 57.2349C56.8023 57.2311 56.7783 57.2009 56.7733 57.2156C56.7652 57.1812 56.7371 57.286 56.7218 57.2654C56.7201 57.263 56.7269 57.2043 56.6997 57.1936C56.6903 57.19 56.6657 57.2358 56.641 57.1844C56.6052 57.2091 56.4169 57.1329 56.404 57.196C56.4036 57.1994 56.4301 57.2211 56.4122 57.247C56.3884 57.2815 56.4098 57.1654 56.382 57.1554C56.3779 57.1539 56.3007 57.1656 56.2981 57.1728C56.2747 57.2379 56.3422 57.2643 56.3413 57.2719C56.3389 57.291 56.2829 57.3025 56.2806 57.298C56.2784 57.2933 56.3241 57.2071 56.2692 57.2398C56.2755 57.2501 56.2818 57.2604 56.2881 57.2707C56.2622 57.2908 56.2598 57.2311 56.2535 57.2274C56.2341 57.2159 56.213 57.3066 56.1818 57.1946C56.1736 57.1649 56.1873 57.1319 56.1862 57.1274C56.1763 57.0874 56.1637 57.1944 56.1488 57.1146C56.1477 57.1086 56.1824 57.0608 56.1218 57.0607C56.126 57.0683 56.1301 57.076 56.1343 57.0837C56.1258 57.1007 56.0644 57.1109 56.0562 57.1069C56.0321 57.0951 56.0531 57.0401 56.0289 57.0467C56.0444 57.122 55.9707 57.1318 55.975 57.067C55.9647 57.1484 55.9021 57.0856 55.8727 57.0837C55.8541 57.0825 55.8163 57.118 55.8104 57.1139C55.8032 57.1088 55.8054 57.0532 55.7924 57.0409C55.7887 57.0374 55.7501 57.0781 55.7162 57.0206C55.7096 57.0095 55.6958 56.9153 55.708 56.8918C55.7289 56.8515 55.7685 56.9274 55.768 56.8717C55.7674 56.8122 55.7141 56.8476 55.6998 56.8398C55.6336 56.8039 55.6718 56.7406 55.6701 56.7214C55.6657 56.6749 55.6296 56.6763 55.6281 56.6721C55.6218 56.6535 55.6474 56.6167 55.6478 56.5883C55.6483 56.5513 55.6134 56.4845 55.6214 56.472C55.6327 56.4543 55.6647 56.51 55.6668 56.5073C55.6932 56.4714 55.657 56.3859 55.647 56.3439C55.6439 56.331 55.656 56.3098 55.6535 56.306C55.6152 56.2485 55.6454 56.4261 55.6199 56.4143C55.5972 56.4037 55.6265 56.3475 55.6256 56.3444C55.6245 56.341 55.5973 56.338 55.593 56.3181C55.5909 56.3081 55.6616 56.1989 55.6586 56.1499C55.6361 56.1607 55.6135 56.1715 55.591 56.1823C55.5892 56.1184 55.6217 56.1654 55.625 56.1588C55.6318 56.1456 55.6129 56.1133 55.6137 56.0931C55.6142 56.0802 55.6363 56.0344 55.6163 56.0155C55.6095 56.009 55.5951 56.0538 55.5701 56.008C55.657 55.9496 55.5968 55.9137 55.5942 55.8911C55.5917 55.8684 55.6332 55.8152 55.5828 55.8246C55.5806 55.7003 55.5839 55.7853 55.5982 55.7635C55.6158 55.7366 55.5752 55.6957 55.6393 55.7267C55.6357 55.6685 55.5842 55.6727 55.5814 55.668C55.5791 55.6638 55.5905 55.6352 55.5864 55.6255C55.5381 55.513 55.5713 55.5644 55.5573 55.4926C55.5561 55.4862 55.5104 55.4595 55.5452 55.4491C55.6085 55.4301 55.635 55.5125 55.6456 55.3362C55.5988 55.2596 55.542 55.3734 55.5278 55.3754C55.506 55.3781 55.5286 55.3422 55.5259 55.3321C55.5249 55.3289 55.5062 55.3318 55.5059 55.329C55.4925 55.1945 55.5895 55.3267 55.6201 55.3034C55.6119 55.2832 55.6037 55.2631 55.5955 55.2429C55.6066 55.2421 55.6177 55.2413 55.6288 55.2405C55.5759 55.2 55.627 55.2252 55.6401 55.1163C55.6431 55.0918 55.6084 55.1338 55.648 55.0658C55.6188 55.0501 55.6281 55.0279 55.6016 55.0586C55.6023 55.0149 55.6619 54.9657 55.6854 54.9433C55.6023 54.8942 55.6497 55.0543 55.5779 54.9696C55.5646 55.0237 55.5989 55.0131 55.5961 55.0221C55.5861 55.0541 55.5626 55.0032 55.5342 55.1156C55.5296 55.134 55.5491 55.1908 55.5202 55.1881C55.517 55.1877 55.4986 55.1392 55.4989 55.1356C55.5013 55.0976 55.5195 55.1119 55.5203 55.096C55.521 55.081 55.5007 55.09 55.5006 55.0859C55.5 55.0382 55.5176 55.0677 55.515 55.0528C55.5095 55.0203 55.4364 54.9179 55.5318 54.9479C55.4525 55.0017 55.5216 55.0005 55.5525 54.9798C55.5604 54.9746 55.5624 54.9461 55.5736 54.9363C55.588 54.9235 55.6049 54.9371 55.6124 54.9319C55.6204 54.9262 55.5748 54.8589 55.6408 54.879C55.6072 54.8121 55.5479 54.8834 55.5149 54.8365C55.4483 54.7416 55.5613 54.7212 55.5731 54.712C55.5762 54.7095 55.5657 54.6711 55.5678 54.6688C55.5712 54.6651 55.6353 54.6829 55.6416 54.6511C55.6479 54.6194 55.6181 54.6526 55.6162 54.6195C55.6148 54.5972 55.6922 54.5576 55.6503 54.5424C55.6214 54.5319 55.5682 54.6215 55.5593 54.5252C55.6017 54.5172 55.6442 54.5093 55.6866 54.5013C55.6634 54.4646 55.6401 54.428 55.6169 54.3913C55.6646 54.3797 55.7057 54.4211 55.751 54.3686C55.6423 54.2512 55.7863 54.2749 55.7879 54.2606C55.7884 54.252 55.7456 54.1567 55.7387 54.1393C55.7766 54.1026 55.8918 54.0847 55.8244 53.967C55.8367 53.9936 55.8663 53.9279 55.8659 53.923C55.8621 53.871 55.7975 53.9047 55.8081 53.8577C55.8203 53.8032 55.8374 53.8772 55.8562 53.8713C55.9526 53.8405 55.9261 53.569 56.0228 53.612C56.0209 53.6023 56.019 53.5926 56.0171 53.583C56.1221 53.5984 56.2272 53.6138 56.3323 53.6291C56.3734 53.5462 56.4829 53.4958 56.5366 53.5049C56.5474 53.5067 56.6006 53.5502 56.6046 53.5578C56.612 53.5725 56.5712 53.578 56.5896 53.6055C56.5935 53.6111 56.6835 53.6294 56.677 53.583C56.667 53.5776 56.6354 53.6009 56.6302 53.59C56.594 53.512 56.8713 53.5743 56.885 53.5429C56.8789 53.5278 56.8728 53.5127 56.8666 53.4977C56.8841 53.5051 56.9016 53.5125 56.9191 53.5199ZM56.115 57.2451C56.1045 57.2916 56.0782 57.2567 56.0626 57.2697C56.0411 57.288 56.0046 57.4672 56.0203 57.2876C56.0519 57.2734 56.0834 57.2593 56.115 57.2451ZM56.5762 57.3144C56.555 57.2894 56.5714 57.1891 56.5888 57.2308C56.5907 57.2356 56.6048 57.3481 56.5762 57.3144ZM56.3543 57.2668C56.3552 57.2655 56.3735 57.2682 56.3742 57.2697C56.3906 57.31 56.3354 57.3018 56.3543 57.2668ZM57.426 57.2154C57.4027 57.2197 57.4195 57.3109 57.434 57.2734C57.435 57.271 57.4275 57.2151 57.426 57.2154ZM57.4094 57.2129C57.3913 57.1313 57.3548 57.2968 57.3838 57.2801C57.3866 57.2784 57.4102 57.2169 57.4094 57.2129ZM56.5008 57.2746C56.5031 57.2433 56.525 57.2584 56.5343 57.2659C56.534 57.2944 56.5099 57.2711 56.5008 57.2746ZM57.0542 57.2659C57.0551 57.2413 56.9792 57.2426 56.9741 57.275C56.986 57.2613 57.0533 57.288 57.0542 57.2659ZM57.2487 57.2313C57.2468 57.2271 57.2206 57.2335 57.2214 57.2552C57.2341 57.2837 57.2574 57.2506 57.2487 57.2313ZM57.6354 57.2328C57.6368 57.2273 57.6172 57.0891 57.6637 57.1801C57.6706 57.1934 57.6462 57.2295 57.6486 57.2345C57.6537 57.2441 57.6577 57.2486 57.6609 57.2494C57.6393 57.2609 57.6168 57.2663 57.6146 57.2579C57.6044 57.2183 57.6348 57.235 57.6354 57.2328ZM57.8384 57.1298C57.8429 57.1073 57.8714 57.1193 57.8779 57.1286C57.879 57.1304 57.8742 57.1896 57.887 57.1852C57.8973 57.1815 57.8819 57.1208 57.902 57.1305C57.9223 57.1403 57.8952 57.1835 57.8969 57.1866C57.8993 57.1906 57.9307 57.1634 57.9297 57.1987C57.929 57.2248 57.8954 57.2071 57.887 57.2127C57.8764 57.2198 57.8893 57.2634 57.8715 57.254C57.8603 57.2482 57.8665 57.1716 57.8642 57.1678C57.8622 57.1646 57.8231 57.2087 57.8385 57.1301C57.8385 57.13 57.8385 57.1299 57.8384 57.1298ZM57.6668 57.246C57.6651 57.2486 57.6632 57.25 57.6609 57.2494C57.6629 57.2484 57.6648 57.2472 57.6668 57.246ZM56.1761 57.2115C56.1871 57.2351 56.1545 57.2654 56.1421 57.2345C56.1419 57.2095 56.1744 57.2078 56.1761 57.2115ZM57.6869 57.1837C57.719 57.2029 57.6954 57.2293 57.6668 57.246C57.6759 57.2316 57.6761 57.1773 57.6869 57.1837ZM56.7733 57.2156C56.7747 57.2213 56.7756 57.2302 56.7757 57.2448C56.7721 57.2288 56.7718 57.2203 56.7733 57.2156ZM56.8484 57.2417C56.8741 57.1971 56.8218 57.1989 56.8222 57.2308C56.8223 57.2429 56.8474 57.2435 56.8484 57.2417ZM57.4559 57.2197C57.4535 57.2153 57.4901 57.0808 57.437 57.1818C57.4653 57.1976 57.4354 57.2123 57.4359 57.2241C57.437 57.2579 57.4846 57.2254 57.4952 57.24C57.5034 57.1794 57.4637 57.2341 57.4559 57.2197C57.4559 57.2197 57.4559 57.2197 57.4559 57.2197ZM58.2043 57.1624C58.1979 57.1979 58.1774 57.1865 58.1636 57.1844C58.1701 57.1489 58.1905 57.1603 58.2043 57.1624ZM61.8174 57.1675C61.7228 57.2003 61.7105 57.0557 61.7971 57.1129C61.7988 57.1141 61.8231 57.1529 61.8174 57.1675ZM61.0055 57.1301C60.9965 57.067 61.026 57.0569 61.0454 57.0829C61.0498 57.0888 61.066 57.1526 61.0475 57.1651C61.0481 57.0887 61.0195 57.0595 61.0055 57.1301ZM57.7051 57.1433C57.7144 57.1013 57.7433 57.1312 57.7585 57.1375C57.7492 57.1721 57.7185 57.1565 57.7051 57.1433ZM61.5065 57.0921C61.4965 57.0873 61.4898 57.1422 61.4915 57.1467C61.4992 57.1677 61.5179 57.1233 61.5065 57.0921ZM57.612 57.1368C57.6106 57.1117 57.6488 57.0875 57.6515 57.1496C57.6433 57.1451 57.6129 57.1526 57.612 57.1368ZM58.1783 57.1436C58.1724 57.1308 58.2031 57.108 58.2124 57.1206C58.2116 57.1474 58.1822 57.1519 58.1783 57.1436ZM61.346 57.1107C61.337 57.106 61.3147 57.1045 61.3123 57.1267C61.3092 57.1544 61.3419 57.1449 61.346 57.1107ZM63.0075 57.0629C63.0086 57.0728 62.9741 57.1446 62.9587 57.1264C62.9296 57.0917 63.0063 57.0558 63.0075 57.0629ZM61.6009 57.0638C61.6291 57.116 61.5978 57.0655 61.599 57.1204C61.618 57.1224 61.6651 57.1251 61.6327 57.0711C61.6264 57.0606 61.6097 57.0674 61.6009 57.0638ZM61.5749 57.0455C61.5719 57.0633 61.5516 57.1193 61.5692 57.1153C61.5773 57.1134 61.5904 57.0511 61.5749 57.0455ZM62.7934 57.0873C62.7682 57.0387 62.8839 57.0648 62.8872 57.0733C62.889 57.0778 62.8901 57.082 62.8908 57.0856C62.895 57.0702 62.9169 57.0674 62.9194 57.1064C62.9129 57.1032 62.895 57.1066 62.8929 57.1023C62.892 57.1004 62.8913 57.0987 62.8909 57.0969C62.8832 57.1308 62.7983 57.0965 62.7934 57.0873ZM62.6017 57.0373C62.6306 56.9656 62.6357 57.0875 62.6332 57.0914C62.6018 57.1413 62.6223 57.0514 62.6213 57.0472C62.6191 57.0402 62.5968 57.0819 62.6018 57.0373C62.6018 57.0373 62.6017 57.0373 62.6017 57.0373ZM62.7541 57.0672C62.7553 57.0656 62.7796 57.0694 62.7806 57.0713C62.8004 57.1123 62.7318 57.1018 62.7541 57.0672ZM57.9915 57.0445C58.0088 57.0566 57.9918 57.1015 57.9803 57.0853C57.9793 57.0838 57.9762 57.0338 57.9915 57.0445ZM61.5611 57.0576C61.557 57.0491 61.4541 57.0171 61.4603 57.0849C61.469 57.0769 61.586 57.1117 61.5611 57.0576ZM60.7916 57.0411C60.8098 57.0416 60.79 57.1055 60.7803 57.0817C60.7767 57.0729 60.787 57.041 60.7916 57.0411ZM57.5605 57.0788C57.5416 57.1139 57.5455 56.9962 57.5618 57.0365C57.5625 57.0381 57.5612 57.0775 57.5605 57.0788ZM60.9367 57.0779C60.8741 57.1166 60.8889 56.914 60.9703 56.9824C60.9677 56.9914 60.9652 57.0004 60.9627 57.0095C61.0566 57.0399 60.9691 57.0237 60.9461 57.0351C60.9373 57.0394 60.9447 57.0732 60.9367 57.0781C60.9367 57.078 60.9367 57.0779 60.9367 57.0779ZM60.6961 57.0373C60.6358 56.8935 60.751 56.9871 60.784 56.9684C60.752 57.0278 60.7103 57.0188 60.767 57.0795C60.6841 57.0913 60.7186 57.034 60.7153 57.0293C60.7114 57.0239 60.6987 57.0434 60.6961 57.0373ZM60.8552 57.0363C60.8587 57.0321 60.885 57.0614 60.8944 57.0566C60.8812 57.1057 60.8321 57.0648 60.8552 57.0363ZM62.4007 57.0706C62.4029 57.0321 62.4083 57.0038 62.429 57.0182C62.4226 57.0375 62.4094 57.0541 62.4007 57.0706ZM56.0951 57.0426C56.0808 57.0398 56.0524 57.0253 56.0611 57.0658C56.062 57.0692 56.095 57.0653 56.0951 57.0426ZM61.262 57.0264C61.259 57.0217 61.1805 57.0185 61.2076 57.0609C61.2158 57.0737 61.2872 57.0683 61.262 57.0264ZM61.6686 57.0312C61.662 57.0308 61.6353 57.0381 61.6348 57.0472C61.633 57.0786 61.6657 57.0613 61.6686 57.0312ZM56.023 57.0032C56.0212 56.9992 55.9776 57.0063 55.9824 57.0249C55.9915 57.0602 56.0295 57.0169 56.023 57.0032ZM58.0546 56.9544C58.0583 56.9529 58.0631 56.9947 58.0644 56.9952C58.0673 56.9958 58.134 56.9797 58.1085 57.0334C58.1043 57.0424 58.0083 57.0218 57.9958 57.0165C57.991 56.9591 58.032 57.0137 58.042 57.0078C58.0437 57.0067 58.0449 56.9586 58.0546 56.9546C58.0546 56.9545 58.0546 56.9544 58.0546 56.9544ZM62.5087 57.03C62.5116 56.9935 62.5901 56.9694 62.5892 57.0136C62.5623 57.0191 62.5355 57.0245 62.5087 57.03ZM62.4689 57.024C62.4521 56.9982 62.4913 56.9896 62.5029 57.001C62.503 57.0255 62.4713 57.0277 62.4689 57.024ZM61.5198 56.8949C61.512 56.9038 61.5362 56.9571 61.5308 56.9674C61.5273 56.9739 61.5097 56.9539 61.5041 56.9706C61.5025 56.9758 61.5204 57.0259 61.5256 57.0237C61.533 57.0208 61.5259 56.9815 61.5339 56.9812C61.5607 56.9803 61.5844 57.0084 61.6094 57.0078C61.6117 57.0076 61.5941 56.9798 61.6134 56.9802C61.6164 56.9802 61.6344 57.0216 61.6575 57.0155C61.7085 56.8872 61.7459 57.0132 61.8107 56.9669C61.8082 56.9549 61.7598 56.9225 61.757 56.9213C61.7028 56.9002 61.6059 56.8979 61.5492 56.8976C61.5347 56.8975 61.5417 56.9246 61.5355 56.9256C61.5305 56.9263 61.5364 56.8761 61.5198 56.8949ZM56.1026 57.0148C56.0958 56.9646 56.072 56.9964 56.0567 56.9938C56.0621 57.039 56.0877 57.0037 56.1026 57.0148ZM62.1167 56.9851C62.1091 56.987 62.0854 56.9719 62.0834 56.987C62.0809 57.0067 62.1151 57.0192 62.1167 56.9851ZM58.4308 56.9686C58.4316 56.9673 58.4499 56.9699 58.4506 56.9715C58.4671 57.0118 58.4119 57.0036 58.4308 56.9686ZM58.8705 56.9783C58.8845 56.9721 58.8985 56.9564 58.9032 56.9971C58.8943 56.9909 58.8689 57.0067 58.8705 56.9783ZM59.4772 56.9771C59.4743 56.9237 59.5162 56.9583 59.5242 56.9631C59.5212 56.9868 59.4793 57.0155 59.4772 56.9771ZM62.3977 56.9031C62.4233 56.9063 62.4179 56.8255 62.4342 56.8621C62.4369 56.8682 62.4455 57.0365 62.4173 56.9735C62.4122 56.9621 62.432 56.9221 62.3977 56.9031ZM60.9836 56.9841C60.9901 56.9488 61.0105 56.9593 61.0242 56.9621C61.0212 56.9883 60.9934 56.9816 60.9836 56.9841ZM55.9443 56.9628C55.9323 56.913 55.8767 56.95 55.8904 56.9829C55.8924 56.9872 55.9365 56.9609 55.9443 56.9628ZM57.7703 56.9824C57.7931 56.9432 57.7458 56.931 57.7308 56.9694C57.7376 56.9668 57.7687 56.985 57.7703 56.9824ZM59.3315 56.9481C59.3325 56.9465 59.3568 56.9503 59.3579 56.9522C59.3778 56.9932 59.3091 56.9827 59.3315 56.9481ZM58.7259 56.9135C58.7347 56.8812 58.7921 56.9073 58.805 56.9396C58.7926 56.9868 58.7151 56.9539 58.7259 56.9135ZM62.2922 56.9261C62.3105 56.9244 62.3278 56.9344 62.3446 56.9483C62.3411 56.9755 62.2941 56.9464 62.2922 56.9261ZM59.4205 56.9447C59.4218 56.9449 59.423 56.948 59.4243 56.9483C59.423 56.9472 59.4217 56.9459 59.4205 56.9447ZM61.8826 56.907C61.8673 56.8963 61.8704 56.9461 61.8714 56.9476C61.8829 56.9637 61.8999 56.9191 61.8826 56.907ZM56.0851 56.9408C56.0798 56.8959 56.054 56.9307 56.0392 56.9201C56.0435 56.9556 56.0732 56.9456 56.0851 56.9408ZM60.6316 56.9452C60.6123 56.8964 60.6907 56.8398 60.7072 56.8712C60.7084 56.9014 60.6344 56.9519 60.6316 56.9452ZM57.6993 56.915C57.6977 56.8798 57.6648 56.9223 57.6718 56.9389C57.6762 56.9495 57.7002 56.9369 57.6993 56.915ZM60.7466 56.8918C60.754 56.881 60.7711 56.9158 60.7651 56.937C60.7573 56.9641 60.7447 56.8949 60.7466 56.8918ZM61.4074 56.8635C61.4042 56.8581 61.3609 56.8943 61.3787 56.9302C61.3912 56.9552 61.3931 56.9043 61.3961 56.9041C61.3993 56.9043 61.4688 56.9666 61.4074 56.8635ZM60.1925 56.9145C60.2089 56.901 60.2286 56.9167 60.2457 56.9157C60.2388 56.9375 60.1995 56.9434 60.1925 56.9145ZM57.8262 56.9056C57.8222 56.8913 57.7141 56.8827 57.7755 56.9266C57.7791 56.9291 57.8382 56.9487 57.8262 56.9056ZM62.3977 56.9031C62.3945 56.9027 62.3907 56.9011 62.3864 56.8976C62.3907 56.8989 62.3944 56.9013 62.3977 56.9031ZM62.1064 56.8978C62.1123 56.8722 62.0825 56.8653 62.0738 56.879C62.0711 56.9103 62.1056 56.9014 62.1064 56.8978ZM60.247 56.8799C60.2569 56.8653 60.2748 56.8809 60.287 56.8792C60.2849 56.903 60.2513 56.9042 60.247 56.8799ZM59.5552 56.8531C59.5747 56.8673 59.5988 56.8608 59.5992 56.8316C59.5996 56.8362 59.6005 56.841 59.6021 56.8459C59.6037 56.8507 59.6247 56.8371 59.6338 56.8471C59.6883 56.9062 59.4232 56.8818 59.5768 56.7995C59.5696 56.8173 59.5624 56.8352 59.5552 56.8531ZM58.6482 56.8449C58.6371 56.8094 58.606 56.8539 58.6141 56.8679C58.6197 56.8774 58.6593 56.8806 58.6482 56.8449ZM59.0755 56.8239C59.0722 56.8175 59.0418 56.8424 59.041 56.8611C59.0585 56.8808 59.0906 56.8533 59.0755 56.8239ZM58.5629 56.8033C58.5559 56.798 58.547 56.8552 58.5478 56.8577C58.5549 56.8786 58.5746 56.8352 58.5629 56.8033ZM62.3446 56.749C62.3342 56.7326 62.3011 56.774 62.2939 56.8118C62.2926 56.8045 62.289 56.795 62.2824 56.7835C62.2824 56.7835 62.2824 56.7835 62.2824 56.7835C62.2735 56.7682 62.0063 56.7516 62.1855 56.8244C62.1911 56.8267 62.1835 56.7928 62.2063 56.7987C62.2078 56.7992 62.2086 56.8269 62.2132 56.8282C62.224 56.8311 62.2811 56.8486 62.2925 56.8263C62.2926 56.8314 62.2934 56.8363 62.295 56.8408C62.309 56.8807 62.3526 56.7616 62.3446 56.749ZM59.1357 56.8188C59.1296 56.8085 59.1103 56.8183 59.1083 56.8427C59.1178 56.8547 59.1499 56.8427 59.1357 56.8188ZM57.8228 56.8053C57.8104 56.7852 57.7788 56.8227 57.7884 56.8427C57.7942 56.855 57.8372 56.8283 57.8228 56.8053ZM58.942 56.8318C59.0134 56.8607 58.959 56.8295 58.9699 56.7937C58.9606 56.8064 58.9513 56.8191 58.942 56.8318ZM62.675 56.8415C62.6636 56.8333 62.677 56.7625 62.6895 56.8009C62.6934 56.8131 62.6813 56.846 62.675 56.8415ZM63.189 56.8195C63.1793 56.7568 63.2267 56.7937 63.2082 56.8367C63.2074 56.8381 63.1897 56.8219 63.189 56.8195ZM62.8298 56.7939C62.8221 56.8366 62.817 56.8417 62.7953 56.8311C62.8275 56.8191 62.7976 56.7813 62.8298 56.7939ZM59.599 56.827C59.5991 56.8287 59.5992 56.83 59.5992 56.8316C59.599 56.83 59.599 56.8285 59.599 56.827ZM58.4957 56.8144C58.4868 56.7783 58.4618 56.7809 58.4692 56.8173C58.4699 56.8207 58.4921 56.8412 58.4957 56.8144ZM62.2939 56.8118C62.2951 56.8183 62.2945 56.8225 62.2925 56.8263C62.2925 56.8215 62.293 56.8169 62.2939 56.8118ZM58.6302 56.785C58.6293 56.812 58.6674 56.8225 58.669 56.8193C58.6908 56.7725 58.646 56.7833 58.6302 56.785ZM57.5708 56.7673C57.5688 56.7701 57.5815 56.8398 57.5893 56.8125C57.5953 56.7913 57.5781 56.7566 57.5708 56.7673ZM62.9037 56.7765C62.9158 56.7766 62.9328 56.7765 62.9359 56.8096C62.9278 56.8045 62.9035 56.8008 62.9037 56.7765ZM63.1704 56.7741C63.1561 56.813 63.1235 56.8129 63.1027 56.8065C63.1024 56.7553 63.157 56.7861 63.1704 56.7741ZM62.3773 56.768C62.3763 56.766 62.346 56.7507 62.3502 56.785C62.3562 56.8352 62.3858 56.7867 62.3773 56.768ZM57.6296 56.8043C57.6431 56.7807 57.6119 56.7081 57.5977 56.7642C57.5903 56.7929 57.6273 56.8083 57.6296 56.8043ZM58.4175 56.7671C58.3997 56.7869 58.4439 56.8223 58.4501 56.7864C58.4419 56.7835 58.4239 56.7601 58.4175 56.7671ZM59.0253 56.7308C58.969 56.6275 58.9997 56.816 59.0097 56.7995C59.0111 56.7971 59.0267 56.7333 59.0253 56.7308ZM55.8046 56.7562C55.7967 56.7706 55.8264 56.8226 55.8302 56.7883C55.8326 56.7669 55.8097 56.7471 55.8046 56.7562ZM59.8729 56.798C59.8706 56.7983 59.8682 56.7987 59.8659 56.799C59.8676 56.7973 59.8699 56.7967 59.8729 56.798ZM58.2554 56.6286C58.295 56.7746 58.2908 56.6621 58.2943 56.6627C58.3017 56.6643 58.319 56.7037 58.333 56.6972C58.317 56.7137 58.3009 56.7301 58.2849 56.7465C58.2975 56.7571 58.4078 56.8108 58.4101 56.7871C58.4134 56.7534 58.3787 56.764 58.3777 56.761C58.3762 56.7568 58.3708 56.6631 58.3676 56.6595C58.3623 56.6538 58.2702 56.6519 58.2554 56.6286ZM58.9076 56.747C58.9166 56.7582 58.9192 56.7953 58.9234 56.7864C58.9249 56.7834 58.9251 56.748 58.93 56.7388C58.9225 56.7415 58.9151 56.7443 58.9076 56.747ZM58.1844 56.7598C58.1732 56.7166 58.2235 56.733 58.2251 56.7378C58.2337 56.7672 58.1936 56.7952 58.1844 56.7598ZM58.6112 56.7535C58.6093 56.751 58.5707 56.7375 58.571 56.7615C58.5813 56.7798 58.6329 56.7852 58.6112 56.7535ZM58.936 56.7364C58.9496 56.7405 58.9752 56.7762 58.9723 56.7229C58.9723 56.7229 58.9723 56.7229 58.9722 56.7229C58.9602 56.7274 58.9481 56.7319 58.936 56.7364ZM57.6759 56.6917C57.6508 56.6068 57.6627 56.7141 57.6849 56.7415C57.6917 56.7033 57.68 56.7055 57.6759 56.6917ZM57.5954 56.6284C57.5884 56.6131 57.5163 56.6298 57.5273 56.6748C57.5313 56.6908 57.5727 56.6504 57.5746 56.6535C57.5775 56.6581 57.5643 56.7078 57.5864 56.698C57.5851 56.6811 57.5978 56.6335 57.5954 56.6284ZM57.6551 56.6373C57.6301 56.5727 57.6245 56.6918 57.6433 56.6922C57.6506 56.6924 57.6587 56.6466 57.6551 56.6373ZM57.7572 56.6475C57.7482 56.6362 57.7242 56.6197 57.7077 56.6593C57.7298 56.6627 57.7519 56.6661 57.774 56.6695C57.7765 56.647 57.765 56.6574 57.7571 56.6475C57.7571 56.6475 57.7571 56.6475 57.7572 56.6475ZM63.3206 56.4689C63.3007 56.4351 63.3464 56.4222 63.3484 56.4305C63.3541 56.458 63.3294 56.484 63.3206 56.4689ZM55.6495 55.6741C55.644 55.6606 55.6404 55.6163 55.6283 55.6395C55.6405 55.6722 55.6527 55.7049 55.6649 55.7376C55.6744 55.6627 55.6556 55.6889 55.6495 55.6741ZM55.6029 55.4003C55.6046 55.3984 55.5952 55.2832 55.6175 55.3601C55.6326 55.4121 55.5507 55.4627 55.5359 55.4116C55.5522 55.3879 55.5881 55.4151 55.6029 55.4003ZM55.4595 54.9015C55.4585 54.8923 55.4896 54.8788 55.4932 54.8853C55.5121 54.9194 55.4646 54.9507 55.4595 54.9015ZM55.5587 54.9235C55.5441 54.9011 55.5764 54.8867 55.5861 54.8995C55.587 54.921 55.561 54.9267 55.5587 54.9235ZM63.1195 54.8C63.1037 54.7217 63.0896 54.8902 63.1139 54.8563C63.115 54.8547 63.1202 54.8038 63.1195 54.8ZM55.4899 54.7852C55.5045 54.8076 55.4721 54.822 55.4625 54.8092C55.4616 54.7877 55.4876 54.782 55.4899 54.7852ZM63.1084 54.6134C63.0874 54.5571 63.0948 54.7462 63.0974 54.7538C63.1082 54.7839 63.1452 54.7097 63.1528 54.6912C63.0974 54.7196 63.1183 54.64 63.1084 54.6134ZM63.0117 54.727C62.9922 54.7472 63.0419 54.7858 63.0514 54.733C63.0418 54.7356 63.0172 54.7212 63.0117 54.727ZM62.8936 54.6663C62.8831 54.6596 62.852 54.6433 62.8468 54.6731C62.8582 54.6677 62.8892 54.697 62.8936 54.6663ZM62.8699 54.5772C62.8536 54.5367 62.8496 54.6545 62.8685 54.6195C62.8692 54.6181 62.8705 54.5794 62.8699 54.5772ZM62.778 54.5346C62.7673 54.4878 62.755 54.6019 62.7724 54.605C62.7776 54.6057 62.7791 54.54 62.778 54.5346ZM63.0821 54.4099C63.0668 54.3898 63.047 54.4715 63.0798 54.4805C63.0683 54.493 63.0567 54.5055 63.0452 54.518C63.0882 54.5638 63.085 54.4504 63.0974 54.4551C63.1146 54.4618 63.1132 54.5553 63.1098 54.5847C63.1239 54.5274 63.1839 54.5265 63.2186 54.5155C63.1881 54.4915 63.1387 54.4498 63.1086 54.4346C63.1 54.4302 63.0916 54.4558 63.0843 54.453C63.0726 54.4482 63.083 54.4113 63.0822 54.4099C63.0822 54.4099 63.0822 54.4099 63.0821 54.4099ZM62.6572 54.5329C62.6256 54.4799 62.6456 54.5945 62.6634 54.574C62.6642 54.5725 62.658 54.5342 62.6572 54.5329ZM55.4481 54.437C55.4902 54.4849 55.4596 54.5484 55.5477 54.452C55.5107 54.5202 55.5456 54.5011 55.5384 54.5286C55.5326 54.5504 55.5109 54.5323 55.5235 54.5762C55.5069 54.5285 55.4349 54.5417 55.4317 54.5339C55.4317 54.5339 55.4317 54.5339 55.4318 54.5339C55.4298 54.5293 55.4346 54.4218 55.4481 54.437ZM62.8934 54.3667C62.8829 54.2276 62.8788 54.4483 62.8581 54.3331C62.8306 54.5004 62.9342 54.3331 62.9467 54.4745C62.8342 54.458 63.021 54.6145 62.9425 54.4029C63.0072 54.4797 62.9637 54.3767 62.9737 54.3498C62.9843 54.321 63.0209 54.3523 63.0191 54.3005C63.019 54.3005 63.019 54.3005 63.019 54.3005C62.9966 54.3041 62.9743 54.3077 62.9519 54.3113C62.9738 54.4231 62.9281 54.3896 62.9126 54.2985C62.9062 54.3212 62.8998 54.344 62.8934 54.3667ZM63.0201 54.4716C63.0179 54.469 62.9692 54.4847 62.9723 54.5071C62.9788 54.5214 63.0479 54.5042 63.0201 54.4716ZM63.2342 54.4472C63.2168 54.4469 63.1897 54.4251 63.1802 54.4672C63.1977 54.4675 63.2247 54.4893 63.2342 54.4472ZM62.3345 54.4392C62.3123 54.4737 62.3808 54.484 62.361 54.443C62.36 54.4411 62.3356 54.4376 62.3345 54.4392ZM62.8428 54.3877C62.8201 54.3452 62.8308 54.4805 62.8476 54.4452C62.8486 54.4431 62.8438 54.3896 62.8428 54.3877ZM55.4822 54.4206C55.4837 54.3874 55.5448 54.4107 55.5557 54.4104C55.5495 54.4412 55.4805 54.4586 55.4822 54.4206ZM63.265 54.3232C63.2302 54.204 63.183 54.3417 63.1779 54.3386C63.1727 54.3356 63.1808 54.2835 63.1796 54.2821C63.1769 54.2792 63.1222 54.2836 63.1195 54.2872C63.1176 54.29 63.1275 54.3632 63.1162 54.3863C63.1383 54.3447 63.2384 54.3707 63.2436 54.3626C63.2477 54.3561 63.2173 54.2792 63.2649 54.3232C63.2649 54.3232 63.265 54.3232 63.265 54.3232ZM63.1649 54.3227C63.1786 54.3534 63.1402 54.3572 63.131 54.3459C63.1103 54.3206 63.1632 54.3191 63.1649 54.3227ZM63.0726 54.2944C63.0682 54.2875 63.0287 54.2813 63.0253 54.3154C63.044 54.3598 63.0826 54.3105 63.0726 54.2944ZM62.6325 54.299C62.6222 54.3034 62.5939 54.2771 62.5923 54.307C62.6026 54.3026 62.6308 54.3289 62.6325 54.299ZM55.6907 54.1601C55.6736 54.1351 55.7132 54.1249 55.7247 54.1369C55.7254 54.1568 55.6922 54.1622 55.6907 54.1601ZM62.839 54.1023C62.8329 54.0932 62.7088 54.1159 62.6914 54.1299C62.7084 54.1524 62.8314 54.1542 62.837 54.1431C62.8386 54.1398 62.8397 54.1037 62.839 54.1023ZM63.1073 54.0885C63.1187 54.0446 63.1261 54.0973 63.1276 54.098C63.1416 54.1047 63.1708 54.0948 63.1644 54.1371C63.1396 54.12 63.0847 54.1758 63.1073 54.0885ZM62.6236 54.1001C62.5815 54.1164 62.6624 54.1627 62.6518 54.1168C62.6511 54.114 62.628 54.0984 62.6236 54.1001ZM62.8528 54.0895C62.8621 54.054 62.9862 54.0846 63.0062 54.0847C62.9883 54.1502 62.9739 54.1004 62.95 54.1038C62.9435 54.1047 62.9452 54.132 62.9445 54.132C62.9333 54.1333 62.9417 54.1018 62.9348 54.1013C62.9304 54.1011 62.8397 54.1395 62.8528 54.0895ZM63.1138 54.0581C63.1208 54.0329 63.1983 54.0221 63.2014 54.0288C63.2247 54.0786 63.1199 54.0669 63.1138 54.0581ZM62.8414 54.0313C62.8548 53.9551 62.9164 54.0061 62.8742 54.0441C62.8702 54.0475 62.8531 54.0145 62.8414 54.0313ZM62.6281 54.0276C62.6261 54.0254 62.5821 54.0102 62.5813 54.0344C62.5877 54.0438 62.6517 54.0523 62.6281 54.0276ZM62.6509 53.9457C62.6499 53.9463 62.6602 53.9929 62.6396 53.987C62.6378 53.9865 62.6346 53.934 62.6087 53.9532C62.6035 53.9572 62.5954 53.9919 62.5959 53.994C62.6229 54.0764 62.7041 53.9186 62.6509 53.9457ZM63.1152 54.0156C63.1111 53.9934 63.1211 53.9276 63.1302 53.9609C63.1341 53.9753 63.1269 54.0148 63.1152 54.0156ZM62.4888 54.0064C62.5144 53.9665 62.4342 53.9589 62.4301 53.9692C62.4327 53.994 62.4863 54.0103 62.4888 54.0064ZM55.7307 53.8522C55.7307 53.8522 55.7306 53.8522 55.7306 53.8522C55.7521 53.8612 55.7388 53.8944 55.7398 53.8954C55.7856 53.9442 55.7734 53.869 55.7806 53.8602C55.7959 53.841 55.7934 53.9324 55.8193 53.8945C55.7765 53.9504 55.8155 53.927 55.8167 53.9595C55.8215 54.0922 55.7597 53.8974 55.7384 53.9252C55.7354 53.929 55.7574 53.9714 55.7498 53.9834C55.725 54.0224 55.6482 53.8176 55.7307 53.8522ZM63.1372 53.9551C63.1472 53.9162 63.2228 53.954 63.2028 53.9861C63.1995 53.9912 63.1226 54.0119 63.1372 53.9551ZM59.6058 53.8976C59.624 53.8639 59.5819 53.8242 59.5741 53.8505C59.5702 53.8636 59.5978 53.9124 59.6058 53.8976ZM59.3106 53.7533C59.289 53.7602 59.2662 53.9008 59.2931 53.879C59.2959 53.8766 59.3131 53.7729 59.3106 53.7533ZM60.7282 53.8256C60.7057 53.7753 60.707 53.8687 60.7236 53.8674C60.7294 53.867 60.7289 53.8272 60.7282 53.8256ZM59.8678 53.8377C59.8656 53.8344 59.8395 53.8404 59.8405 53.8619C59.8501 53.8747 59.8824 53.8601 59.8678 53.8377ZM60.7354 53.8123C60.722 53.8291 60.745 53.8967 60.7614 53.8307C60.7531 53.8361 60.7368 53.8106 60.7354 53.8123ZM62.7948 53.8249C62.7837 53.8632 62.752 53.8516 62.7338 53.8582C62.7318 53.8085 62.7819 53.8339 62.7948 53.8249ZM59.4022 53.8099C59.3818 53.8449 59.4256 53.8736 59.4216 53.8273C59.421 53.8248 59.403 53.8084 59.4022 53.8099ZM61.4555 53.8072C61.4407 53.8369 61.4878 53.8767 61.4749 53.8246C61.4742 53.8225 61.4563 53.8056 61.4555 53.8072ZM61.6615 53.8244C61.6502 53.8144 61.6022 53.8175 61.6209 53.8464C61.6238 53.8508 61.6607 53.8515 61.6615 53.8244ZM55.7818 53.8244C55.7758 53.7734 55.811 53.7855 55.8161 53.7944C55.8181 53.7981 55.7898 53.8908 55.7818 53.8244ZM60.5818 53.8176C60.5701 53.824 60.5399 53.8119 60.5346 53.8387C60.5488 53.8331 60.5856 53.871 60.5818 53.8176ZM59.4954 53.8097C59.4776 53.7542 59.4472 53.7597 59.4547 53.8321C59.4883 53.8273 59.4506 53.767 59.4954 53.8097ZM60.8105 53.7526C60.8011 53.7484 60.794 53.818 60.795 53.8213C60.8052 53.8524 60.8198 53.7797 60.8105 53.7526ZM60.1086 53.8099C60.1081 53.7802 60.0781 53.7937 60.0821 53.8128C60.0834 53.8192 60.109 53.834 60.1086 53.8099ZM62.4022 53.808C62.3884 53.7808 62.4304 53.7543 62.4428 53.786C62.4488 53.8316 62.4039 53.8111 62.4022 53.808ZM61.0699 53.77C61.0713 53.7259 61.0244 53.7508 61.0429 53.7874C61.0475 53.7966 61.0694 53.7848 61.0699 53.77ZM61.5185 53.7171C61.4871 53.7697 61.6191 53.8071 61.5844 53.7415C61.5819 53.7368 61.5213 53.7127 61.5185 53.7171ZM61.7341 53.75C61.7287 53.7442 61.7314 53.5959 61.7538 53.6531C61.7568 53.6605 61.743 53.6997 61.7454 53.7086C61.7468 53.7138 61.7956 53.7346 61.7979 53.7311C61.8003 53.7272 61.7975 53.6797 61.7999 53.6743C61.8027 53.6684 61.8327 53.7101 61.8485 53.7106C61.8781 53.7114 61.8813 53.6718 61.8837 53.6717C61.8908 53.6714 61.9027 53.6995 61.9171 53.6995C61.9895 53.6991 62.1002 53.6656 62.1575 53.7495C62.1065 53.7158 62.0578 53.7515 62.007 53.7625C62.0219 53.68 61.9323 53.8262 61.9847 53.7309C61.9605 53.7515 61.7519 53.7681 61.7342 53.75C61.7342 53.75 61.7341 53.75 61.7341 53.75ZM59.2254 53.7118C59.2386 53.6612 59.1706 53.6725 59.1648 53.7311C59.1738 53.7392 59.2237 53.7175 59.2254 53.7118ZM59.5393 53.5883C59.5457 53.5796 59.5516 53.4806 59.5848 53.5308C59.5848 53.5308 59.5849 53.5308 59.5849 53.5308C59.5946 53.5454 59.5835 53.5696 59.5853 53.5781C59.586 53.5817 59.6162 53.6309 59.5911 53.6388C59.5528 53.6509 59.5875 53.5652 59.5671 53.5641C59.5646 53.5641 59.5259 53.6176 59.5282 53.6294C59.5284 53.6307 59.54 53.6194 59.542 53.6243C59.5492 53.6427 59.5457 53.6736 59.5467 53.6751C59.55 53.6788 59.6111 53.6262 59.62 53.6722C59.6229 53.687 59.5226 53.7212 59.5187 53.7135C59.5163 53.7086 59.5173 53.6228 59.5147 53.6144C59.5134 53.6102 59.4731 53.6423 59.4679 53.6345C59.4663 53.6322 59.4652 53.6297 59.4643 53.6277C59.4704 53.6542 59.4339 53.6523 59.435 53.6224C59.4357 53.6106 59.4608 53.6174 59.4617 53.6195C59.4621 53.6203 59.4624 53.6215 59.4628 53.6224C59.4576 53.59 59.5427 53.5915 59.5243 53.5433C59.549 53.517 59.5208 53.614 59.5393 53.5883ZM59.6579 53.5354C59.6554 53.5444 59.6528 53.5534 59.6503 53.5624C59.6935 53.5404 59.7433 53.5838 59.7931 53.5835C59.8057 53.5834 59.7912 53.5283 59.8077 53.5433C59.821 53.5554 59.8356 53.6066 59.8284 53.618C59.8267 53.6209 59.7997 53.5875 59.7862 53.591C59.7463 53.6011 59.7564 53.6484 59.754 53.6497C59.7515 53.651 59.7264 53.6177 59.7127 53.6192C59.6782 53.6231 59.6624 53.6521 59.6154 53.6142C59.6425 53.583 59.6276 53.5152 59.6579 53.5354ZM61.2678 53.6361C61.2695 53.6064 61.2977 53.6328 61.308 53.6284C61.3064 53.6583 61.2781 53.6318 61.2678 53.6361ZM57.056 53.5975C57.0473 53.6464 57.1124 53.6585 57.0952 53.6178C57.0914 53.6088 57.0642 53.5978 57.056 53.5975ZM57.3483 53.6272C57.357 53.6137 57.3219 53.5785 57.322 53.6163C57.3221 53.6285 57.3472 53.629 57.3483 53.6272ZM60.2162 53.5835C60.2179 53.5819 60.2418 53.5928 60.2426 53.5953C60.2584 53.6472 60.1796 53.6172 60.2162 53.5835ZM57.7036 53.567C57.6733 53.5991 57.7646 53.6129 57.7367 53.5721C57.7353 53.5701 57.7051 53.5655 57.7036 53.567ZM57.8306 53.5581C57.8233 53.5598 57.791 53.5439 57.7906 53.5588C57.7899 53.5829 57.8269 53.5993 57.8306 53.5581ZM60.8168 53.568C60.8133 53.5129 60.8559 53.5546 60.8707 53.5477C60.8742 53.6028 60.8316 53.561 60.8168 53.568ZM60.548 53.5274C60.7275 53.484 60.688 53.6016 60.5373 53.5542C60.5371 53.5189 60.5367 53.5301 60.548 53.5274ZM60.7779 53.5339C60.7714 53.5692 60.751 53.5587 60.7372 53.5559C60.7397 53.5314 60.768 53.5403 60.7779 53.5339ZM56.9785 53.5218C56.9898 53.4773 57.0396 53.5322 57.0308 53.5506C57.0287 53.5546 56.9744 53.5463 56.9785 53.5218ZM60.2313 53.5363C60.2271 53.4828 60.281 53.5046 60.2851 53.5165C60.3018 53.5644 60.2356 53.5245 60.2313 53.5363ZM61.0716 53.5209C61.0812 53.4789 61.1082 53.5005 61.1256 53.5011C61.1177 53.5369 61.0864 53.5216 61.0716 53.5209ZM60.9461 53.488C60.9472 53.4864 60.9714 53.4902 60.9725 53.4921C60.9924 53.5331 60.9238 53.5226 60.9461 53.488ZM55.7009 53.4493C55.7017 53.448 55.7201 53.4507 55.7207 53.4522C55.7371 53.4925 55.682 53.4843 55.7009 53.4493ZM32.2889 49.4582C32.2938 49.4531 32.3135 49.4654 32.322 49.4632C32.3123 49.5163 32.2712 49.4764 32.2889 49.4582ZM33.164 45.6015C33.1569 45.6147 33.1498 45.6278 33.1427 45.6409C33.1628 45.6494 33.1899 45.6398 33.2085 45.6523C33.2116 45.6544 33.2037 45.6924 33.2109 45.6941C33.2181 45.6958 33.2167 45.6438 33.2272 45.6383C33.239 45.6322 33.293 45.6684 33.3117 45.6675C33.3816 45.664 33.4521 45.6343 33.5222 45.6559C33.4498 45.6943 33.5227 45.7334 33.543 45.7168C33.5475 45.7129 33.5468 45.6164 33.6193 45.6407C33.6654 45.6561 33.6228 45.7942 33.6998 45.725C33.6406 45.6284 33.6988 45.6352 33.7452 45.632C33.7532 45.6314 33.8178 45.6459 33.8463 45.6416C33.856 45.6401 33.8709 45.5896 33.8839 45.5882C33.8928 45.5874 33.8995 45.615 33.9127 45.6136C33.9744 45.6074 34.0351 45.6052 34.0968 45.6146C34.0607 45.7446 34.1252 45.67 34.1281 45.6762C34.1428 45.7115 34.0762 45.7215 34.1026 45.7436C34.1393 45.7396 34.1761 45.7356 34.2129 45.7315C34.1827 45.7156 34.2529 45.6221 34.2658 45.6646C34.2601 45.5497 34.4335 45.7646 34.4599 45.7262C34.4654 45.7181 34.4294 45.6613 34.5129 45.6873C34.5219 45.6902 34.5185 45.7249 34.5232 45.7216C34.5261 45.7197 34.5433 45.6095 34.5616 45.6704C34.5683 45.6926 34.5255 45.765 34.6194 45.7359C34.582 45.6238 34.7497 45.6752 34.7805 45.7033C34.7743 45.6882 34.7682 45.6731 34.762 45.6581C34.7925 45.6987 34.798 45.6606 34.8049 45.6627C34.8326 45.671 34.8706 45.7094 34.8964 45.7059C34.9266 45.7019 34.9267 45.6322 34.9619 45.6593C34.9535 45.6439 34.9452 45.6285 34.9368 45.6131C34.9611 45.6168 34.9854 45.6205 35.0097 45.6242C34.9534 45.7165 35.0218 45.6286 35.0264 45.6267C35.0335 45.6233 35.0232 45.6611 35.0352 45.6564C35.0365 45.6556 35.0347 45.62 35.0532 45.616C35.0919 45.6078 35.0858 45.6525 35.102 45.652C35.1035 45.6518 35.0983 45.6197 35.1264 45.6122C35.2156 45.588 35.126 45.6367 35.1225 45.6412C35.118 45.647 35.1486 45.781 35.0728 45.7335C35.0983 45.7486 35.1008 45.8079 35.1037 45.8093C35.1062 45.8106 35.1503 45.8022 35.1528 45.8002C35.1744 45.78 35.1554 45.7395 35.1596 45.7323C35.163 45.7264 35.2162 45.7792 35.2286 45.6573C35.254 45.7697 35.214 45.7594 35.1714 45.7767C35.1652 45.7998 35.212 45.8222 35.2144 45.8222C35.2748 45.822 35.2414 45.7295 35.2546 45.6704C35.2615 45.6395 35.2861 45.7025 35.2634 45.6196C35.3182 45.6109 35.2849 45.6589 35.2885 45.666C35.2938 45.6765 35.313 45.6527 35.3154 45.6559C35.3189 45.6606 35.3067 45.6893 35.3206 45.6994C35.3229 45.7009 35.3452 45.6515 35.3164 45.6279C35.3549 45.6349 35.3518 45.5928 35.3648 45.6776C35.3914 45.5171 35.3841 45.7726 35.3946 45.7816C35.4224 45.8053 35.4143 45.6792 35.4158 45.6731C35.4259 45.6337 35.5029 45.677 35.5219 45.6588C35.5144 45.7496 35.4609 45.6598 35.4489 45.6774C35.4091 45.736 35.5051 45.7228 35.4762 45.8369C35.4883 45.8056 35.5005 45.7742 35.5126 45.7429C35.5349 45.8162 35.5033 45.8482 35.5632 45.8214C35.573 45.7581 35.5208 45.8314 35.5313 45.7816C35.5375 45.7523 35.5722 45.746 35.5729 45.7306C35.5736 45.712 35.5422 45.734 35.5471 45.7054C35.5579 45.6438 35.6725 45.7025 35.5853 45.7361C35.6096 45.7351 35.6221 45.8577 35.6432 45.8195C35.6569 45.7947 35.5801 45.6253 35.6952 45.6564C35.6977 45.7143 35.6492 45.6735 35.648 45.6779C35.6462 45.6843 35.655 45.815 35.6565 45.8214C35.6619 45.8427 35.7794 45.7727 35.8042 45.8383C35.7944 45.7628 35.893 45.8249 35.9038 45.8019C35.9066 45.7955 35.896 45.7492 35.899 45.7443C35.9181 45.7152 35.9697 45.7978 35.9936 45.7999C36.0204 45.8023 36.017 45.7624 36.0185 45.7625C36.0303 45.7647 36.0209 45.7918 36.0281 45.7917C36.039 45.7916 36.1138 45.7971 36.1175 45.7915C36.1186 45.7897 36.1064 45.7441 36.1227 45.7354C36.1255 45.7339 36.1238 45.788 36.172 45.7646C36.2302 45.7365 36.1317 45.6973 36.1558 45.6407C36.1932 45.7214 36.192 45.6414 36.2021 45.6477C36.2056 45.65 36.2317 45.718 36.2601 45.7136C36.2397 45.7247 36.2194 45.7357 36.199 45.7468C36.219 45.7587 36.2579 45.7439 36.2744 45.7574C36.2824 45.7639 36.2758 45.8198 36.2932 45.8183C36.2969 45.8177 36.3116 45.6816 36.2659 45.7426C36.2622 45.6941 36.284 45.7257 36.2941 45.712C36.2956 45.7098 36.3017 45.6286 36.3146 45.6791C36.3177 45.6915 36.2839 45.9283 36.3709 45.7569C36.3737 45.7514 36.364 45.7217 36.3667 45.7156C36.3686 45.7114 36.3908 45.7234 36.3932 45.7192C36.3957 45.7147 36.385 45.6823 36.388 45.676C36.4033 45.6431 36.4234 45.7715 36.3918 45.7617C36.4024 45.7776 36.4129 45.7935 36.4235 45.8093C36.4122 45.7126 36.4401 45.7821 36.4547 45.7791C36.5482 45.7601 36.4856 45.6972 36.5017 45.6646C36.5275 45.6123 36.5078 45.7779 36.5462 45.7281C36.5497 45.7235 36.5033 45.6532 36.594 45.6929C36.5806 45.6956 36.5672 45.6983 36.5538 45.7011C36.5615 45.7947 36.6021 45.6947 36.6053 45.6934C36.6409 45.6805 36.6168 45.7142 36.6697 45.666C36.6744 45.6617 36.6847 45.6848 36.6948 45.6733C36.7366 45.6258 36.6395 45.6445 36.6369 45.6066C36.6356 45.588 36.74 45.5927 36.7436 45.6015C36.7588 45.6406 36.6963 45.6187 36.7082 45.6673C36.7126 45.6845 36.8613 45.6491 36.8912 45.668C36.9256 45.6899 36.9412 45.8168 36.9414 45.6743C36.9511 45.8142 36.9597 45.7187 36.9641 45.7197C37.0174 45.7326 37.0175 45.7341 37.0631 45.7207C37.0732 45.7177 37.0817 45.7602 37.0853 45.753C37.0874 45.7487 37.0835 45.7033 37.0937 45.6892C37.1078 45.6701 37.1927 45.7168 37.199 45.7419C37.2053 45.767 37.1632 45.7528 37.1707 45.7941C37.2013 45.7983 37.2305 45.7881 37.2613 45.7924C37.274 45.7944 37.2675 45.8233 37.273 45.8238C37.2753 45.8242 37.3194 45.7987 37.3175 45.7881C37.3132 45.7633 37.1771 45.78 37.2129 45.7294C37.2198 45.7196 37.2442 45.7862 37.2404 45.7052C37.3619 45.7236 37.4835 45.7419 37.6051 45.7603C37.5353 45.8209 37.4566 45.7667 37.3835 45.7724C37.3734 45.7731 37.3395 45.7653 37.3437 45.8062C37.4059 45.8168 37.4832 45.7955 37.543 45.8222C37.5449 45.823 37.5379 45.8598 37.545 45.8657C37.5584 45.8765 37.602 45.8172 37.6094 45.8325C37.6106 45.8361 37.5858 45.8846 37.5933 45.9154C37.6127 45.9945 37.6176 45.8194 37.6343 45.8214C37.6472 45.8231 37.7337 45.9078 37.7552 45.8543C37.7781 45.7973 37.6915 45.8212 37.6979 45.7745C37.7565 45.7277 37.8159 45.7777 37.8713 45.7719C37.8723 45.7717 37.8638 45.7352 37.8762 45.7301C37.8977 45.7212 37.9033 45.773 37.9138 45.7813C37.9251 45.7901 37.965 45.7827 37.9704 45.8016C37.9711 45.8041 37.963 45.8555 37.9617 45.857C37.9443 45.8781 37.9382 45.8114 37.9366 45.8106C37.9306 45.808 37.9248 45.8336 37.9194 45.8321C37.9104 45.8295 37.9055 45.8059 37.8937 45.8038C37.8856 45.8023 37.8934 45.8477 37.8856 45.8456C37.8827 45.8447 37.8517 45.741 37.8488 45.8468C37.8479 45.8802 38.1018 45.923 38.1272 45.8963C38.1054 45.8836 38.0836 45.8709 38.0618 45.8582C38.1061 45.8891 38.1592 45.8046 38.1629 45.9297C38.3268 45.9399 38.4908 45.9502 38.6547 45.9604C38.684 45.971 38.6679 46.0515 38.7161 46.028C38.7036 46.0024 38.6912 45.9768 38.6788 45.9512C38.7034 45.9692 38.8128 46.0043 38.8305 45.9877C38.8328 45.9855 38.836 45.9127 38.8633 45.9065C38.8876 45.901 38.8915 45.9555 38.9044 45.9659C38.9153 45.9746 38.9275 45.9603 38.9308 45.9633C38.9332 45.9657 38.9342 45.999 38.9402 46.0049C38.959 46.0228 38.9438 45.9289 38.9624 46.0367C38.9579 46.0409 38.9533 46.045 38.9488 46.0491C38.9715 46.0647 39.0026 46.1136 38.9691 46.1378C38.9633 46.1419 38.9683 46.1097 38.964 46.1097C38.7959 46.1157 38.9301 46.1784 38.989 46.1283C39.0042 46.1761 39.0889 46.147 39.0918 46.1564C39.0957 46.17 39.0812 46.2082 39.1002 46.2412C39.1042 46.2482 39.2176 46.2214 39.1767 46.2849C39.1683 46.298 39.114 46.2843 39.1009 46.2861C39.1317 46.3874 39.2039 46.2423 39.2121 46.246C39.2449 46.2618 39.1491 46.3338 39.2229 46.3456C39.2797 46.3546 39.2264 46.287 39.2483 46.2581C39.2605 46.2419 39.3248 46.3164 39.3231 46.2199C39.3451 46.2096 39.3322 46.2607 39.3349 46.2644C39.3376 46.2676 39.381 46.2387 39.395 46.2591C39.3967 46.2616 39.3914 46.3118 39.3931 46.3159C39.3966 46.3229 39.4384 46.3129 39.4401 46.3086C39.4411 46.3057 39.4312 46.2618 39.4353 46.2511C39.44 46.2388 39.4803 46.2492 39.4825 46.2366C39.4856 46.2176 39.436 46.2301 39.4442 46.181C39.4671 46.1934 39.5045 46.1606 39.5196 46.1211C39.5159 46.1324 39.4937 46.134 39.486 46.13C39.4896 46.0581 39.5373 46.0591 39.521 46.116C39.5313 46.0854 39.5243 46.0692 39.5301 46.0404C39.5316 46.0331 39.5463 46.0316 39.5492 46.0191C39.5495 46.0166 39.5344 45.9895 39.5374 45.9749C39.5429 45.9485 39.5875 45.9544 39.5912 45.9614C39.6015 45.981 39.5651 46.0047 39.562 46.0351C39.5616 46.0397 39.5926 46.0992 39.593 46.1044C39.5948 46.1607 39.5604 46.1201 39.5643 46.1709C39.5729 46.1816 39.5814 46.1923 39.5899 46.203C39.557 46.2544 39.4963 46.228 39.4806 46.2864C39.5293 46.269 39.5803 46.2711 39.5802 46.4026C39.5801 46.458 39.5591 46.4905 39.5599 46.5046C39.563 46.555 39.5922 46.5002 39.5933 46.5029C39.5942 46.506 39.5946 46.509 39.5946 46.5119C39.5946 46.5119 39.5946 46.5119 39.5946 46.5119C39.5946 46.5414 39.553 46.5627 39.5509 46.5761C39.5474 46.6001 39.5659 46.6986 39.5659 46.7204C39.5652 46.7248 39.5356 46.7481 39.5456 46.7861C39.5557 46.8246 39.5816 46.8254 39.5826 46.8294C39.5875 46.8524 39.5422 46.8733 39.5408 46.8869C39.5401 46.8938 39.5644 46.9359 39.5652 46.948C39.5658 46.9602 39.5473 46.9867 39.54 47.0251C39.5345 47.0537 39.5504 47.0755 39.5476 47.08C39.5456 47.083 39.5027 47.0825 39.5006 47.0875C39.4975 47.0949 39.5075 47.129 39.5061 47.1375C39.504 47.1498 39.4902 47.1375 39.492 47.1501C39.4933 47.1595 39.547 47.277 39.5466 47.3084C39.546 47.3619 39.4892 47.2387 39.542 47.45C39.5424 47.4514 39.5553 47.4363 39.5556 47.4376C39.5636 47.4765 39.5223 47.5363 39.5728 47.5259C39.479 47.5934 39.5611 47.6063 39.5472 47.6965C39.5419 47.7311 39.5055 47.7454 39.5053 47.7506C39.5089 47.7945 39.5204 47.7605 39.5244 47.782C39.5265 47.7941 39.494 47.8405 39.5013 47.8707C39.5051 47.8863 39.5397 47.8807 39.5411 47.8837C39.5547 47.9124 39.538 47.9432 39.541 47.9635C39.543 47.9771 39.5638 47.9782 39.5644 47.9807C39.5652 47.9858 39.5369 48.0408 39.5311 48.0602C39.5266 48.0751 39.5434 48.0984 39.5403 48.1049C39.5214 48.1437 39.4813 48.0447 39.52 48.1834C39.5223 48.1919 39.5369 48.1885 39.5374 48.1902C39.5464 48.2295 39.5195 48.2329 39.5147 48.2651C39.5064 48.3206 39.5451 48.2896 39.5129 48.3286C39.5371 48.3649 39.5505 48.3634 39.5787 48.3533C39.5006 48.3815 39.473 48.5251 39.5597 48.5215C39.5321 48.5192 39.5352 48.6003 39.527 48.6017C39.5219 48.6025 39.4818 48.5219 39.5002 48.7027C39.5025 48.7253 39.5268 48.6966 39.5192 48.7428C39.4608 48.7311 39.5179 48.7723 39.518 48.7784C39.5172 48.8849 39.3747 48.7976 39.3502 48.8098C39.3217 48.8239 39.2965 48.9078 39.2903 48.9079C39.27 48.9079 39.2868 48.8653 39.2823 48.8497C39.2777 48.8341 39.2199 48.9158 39.217 48.9113C39.2058 48.8933 39.2172 48.8428 39.216 48.8402C39.2021 48.8093 39.1245 48.8488 39.1028 48.8371C39.1034 48.8699 39.1471 48.8724 39.1198 48.9251C39.0881 48.9864 39.0863 48.842 39.0854 48.8356C38.9401 48.837 38.7947 48.8384 38.6493 48.8398C38.6511 48.9166 38.7462 48.8586 38.7483 48.8688C38.761 48.9286 38.6005 48.9275 38.5808 48.9004C38.5958 48.917 38.6107 48.9336 38.6257 48.9502C38.6001 49.0385 38.5436 48.9238 38.5066 48.9628C38.4947 48.9754 38.5176 49.0095 38.5171 49.0118C38.5037 49.0461 38.4822 49.0197 38.4983 48.9736C38.4655 49.0178 38.4703 48.9691 38.4452 48.9654C38.4439 48.9653 38.4547 49.0009 38.4348 49.0157C38.4255 49.0226 38.3758 49.0227 38.3691 49.0539C38.3664 49.067 38.3916 49.2052 38.3947 49.0862C38.4488 49.1442 38.412 49.032 38.433 49.0348C38.4362 49.0354 38.4288 49.1018 38.4817 49.0705C38.4716 49.1903 38.4107 49.1007 38.4003 49.1152C38.3788 49.1451 38.4675 49.2069 38.4837 49.1136C38.4761 49.207 38.49 49.1261 38.5098 49.13C38.5315 49.1342 38.522 49.162 38.5337 49.1621C38.5658 49.1628 38.5525 49.0969 38.5789 49.1563C38.5531 48.9723 38.6241 49.132 38.6448 49.1803C38.6111 49.1896 38.5775 49.1989 38.5438 49.2083C38.5458 49.218 38.5477 49.2276 38.5496 49.2373C38.5408 49.2359 38.5319 49.2345 38.523 49.2332C38.5245 49.2239 38.5259 49.2146 38.5273 49.2054C38.4816 49.2656 38.4705 49.1979 38.4667 49.1972C38.4188 49.1893 38.3634 49.1899 38.3149 49.1897C38.3076 49.1896 38.3126 49.2499 38.2596 49.2027C38.2427 49.1877 38.2586 49.1408 38.2395 49.1479C38.2155 49.2752 38.2159 49.1736 38.2088 49.1735C38.1883 49.1735 38.1758 49.2051 38.1739 49.2054C38.1487 49.2103 38.1116 49.205 38.0839 49.2097C38.0833 49.2102 38.0978 49.2493 38.0798 49.2378C38.0734 49.2336 38.0166 49.0666 37.9669 49.121C37.9799 49.1323 37.9928 49.1436 38.0057 49.1549C37.9905 49.1391 37.8841 49.1812 37.9101 49.2259C37.926 49.2533 37.965 49.1456 37.9693 49.2491C37.9338 49.2181 37.7382 49.2645 37.723 49.2404C37.7209 49.237 37.7338 49.2034 37.7309 49.1991C37.7287 49.1958 37.6839 49.2038 37.6779 49.1909C37.6744 49.1832 37.6942 49.1626 37.6926 49.1505C37.6912 49.1419 37.6352 49.1275 37.632 49.1696C37.6458 49.1527 37.6844 49.1675 37.6641 49.203C37.6615 49.2074 37.648 49.1802 37.6448 49.1858C37.6155 49.2374 37.7032 49.225 37.7168 49.2254C37.6617 49.2791 37.5764 49.2158 37.5125 49.2508C37.4867 49.2158 37.5508 49.1972 37.5216 49.1682C37.461 49.108 37.5055 49.2166 37.5036 49.2211C37.4886 49.2564 37.4373 49.067 37.4373 49.2112C37.4153 49.1895 37.4224 49.1713 37.3914 49.1902C37.3955 49.2001 37.3996 49.2101 37.4037 49.2201C37.3692 49.3037 37.2964 49.0929 37.3019 49.0768C37.3165 49.0338 37.3545 49.1009 37.3577 49.0993C37.3625 49.0969 37.3758 48.9506 37.4282 49.0814C37.4497 48.9833 37.3451 49.0152 37.3927 48.9483C37.3605 48.9592 37.2282 48.8909 37.2092 48.934C37.2069 48.9396 37.2175 49.0374 37.1848 48.9876C37.1693 48.9639 37.2067 48.9628 37.1996 48.9405C37.1777 48.8721 36.8805 48.9159 36.8241 48.9195C36.8204 48.9196 36.8218 48.8893 36.8182 48.8895C36.8071 48.8904 36.7668 48.9356 36.747 48.9217C36.788 48.9779 36.7084 48.9822 36.6881 48.976C36.6573 48.9666 36.6592 48.9132 36.646 48.9019C36.5947 48.8581 36.5154 48.9849 36.4756 48.8663C36.4778 48.984 36.4068 48.8086 36.3745 48.8076C36.3492 48.8068 36.3125 48.8846 36.3467 48.9321C36.303 48.9266 36.257 48.9486 36.2161 48.9557C36.2093 48.9569 36.2186 48.9222 36.2071 48.9253C36.206 48.9258 36.2046 48.9599 36.1947 48.9635C36.1128 48.9932 36.1526 48.9207 36.1373 48.8994C36.1287 48.8875 36.1224 48.8816 36.1178 48.8796C36.1655 48.873 36.2205 48.8596 36.2353 48.8586C36.2227 48.7833 36.1295 48.8731 36.1022 48.8528C36.1012 48.8521 36.1045 48.8106 36.1036 48.8103C36.1036 48.8103 36.1035 48.8103 36.1035 48.8103C36.0933 48.8071 36.0281 48.8224 36.0415 48.8719C36.0451 48.8851 36.0751 48.8851 36.1107 48.8806C36.1011 48.8899 36.1083 48.9364 36.1066 48.9384C36.086 48.9613 36.0355 48.916 36.0176 48.9098C36.0135 48.9085 36.0138 48.9383 36.0131 48.9384C35.9968 48.9316 36.0035 48.8465 35.9868 48.9342C35.9573 48.8282 36.0421 48.9185 36.0361 48.8497C36.0315 48.7967 35.8432 48.8251 35.8438 48.9086C35.8431 48.8997 35.8406 48.8886 35.8352 48.876C35.8235 48.848 35.7711 48.8567 35.762 48.8721C35.7605 48.8752 35.7611 48.9562 35.7592 48.957C35.7545 48.9588 35.6904 48.8953 35.6665 48.9432C35.6794 48.9545 35.6924 48.9659 35.7053 48.9773C35.6273 48.978 35.6393 49.0021 35.6653 49.0263C35.6666 49.0265 35.6679 49.0296 35.6691 49.0299C35.6893 49.0479 35.7151 49.0651 35.7155 49.0715C35.717 49.0959 35.5846 49.1095 35.6101 49.0343C35.6136 49.024 35.6748 49.0575 35.6445 49.0038C35.6392 48.9944 35.5999 49.0098 35.5978 49.0038C35.584 48.9645 35.6699 48.9123 35.6594 48.8564C35.6385 48.9096 35.6118 48.8816 35.5879 48.8953C35.577 48.9015 35.5743 48.9422 35.573 48.9429C35.5529 48.9536 35.5642 48.9109 35.5575 48.912C35.5539 48.9127 35.5144 49.0034 35.5219 48.8784C35.3916 48.9704 35.4858 48.9703 35.5657 48.9632C35.5405 49.0088 35.491 48.9867 35.4688 48.9973C35.4608 49.0012 35.4655 49.0429 35.4521 49.0512C35.4244 49.0684 35.2921 49.0205 35.2577 49.0092C35.2788 48.9944 35.2726 48.949 35.2563 48.9521C35.24 48.9553 35.2537 49.0159 35.2505 49.0224C35.2471 49.0292 35.1705 49.0006 35.1577 49.0084C35.2154 48.9865 35.2024 48.9412 35.1534 48.9364C35.1605 48.9234 35.1676 48.9103 35.1747 48.8973C35.146 48.9156 35.0856 48.8465 35.069 48.8671C35.0664 48.8704 35.0758 48.9085 35.0743 48.9103C35.0598 48.9265 35.0103 48.8877 35.008 48.9007C35.006 48.9115 35.0271 48.9434 35.0193 48.9591C35.0176 48.9624 34.9973 48.911 34.9772 48.9236C34.9698 48.9283 34.9743 48.9643 34.9724 48.9664C34.9568 48.9837 34.966 48.923 34.9375 48.9328C34.9165 48.94 34.901 48.9993 34.8721 48.9797C34.967 49.0553 34.8872 49.0237 34.8475 49.0466C34.8411 49.0503 34.8466 49.1157 34.8086 49.0838C34.8895 48.9656 34.7855 49.0213 34.7643 49.02C34.7631 49.0196 34.7627 48.9765 34.7523 48.9758C34.7514 48.9758 34.7527 49.005 34.743 49.0072C34.6511 49.0283 34.7098 48.9954 34.6924 48.9666C34.685 48.9544 34.6403 48.9956 34.6282 48.9966C34.6255 48.9967 34.6267 48.9664 34.616 48.9676C34.5971 48.9698 34.5801 49.002 34.5676 49.0046C34.5661 49.0047 34.5661 48.9569 34.5424 48.9724C34.5357 48.9768 34.5282 48.9937 34.5377 49.0075C34.5691 49.0527 34.6286 48.9744 34.6641 49.0195C34.6965 49.0606 34.5945 49.0645 34.5891 49.0647C34.5872 49.0649 34.6071 49.0412 34.5869 49.0365C34.5696 49.0326 34.538 49.1151 34.5122 49.0971C34.5103 49.0958 34.4897 49.0258 34.4906 49.0217C34.4915 49.0187 34.5231 49.0035 34.5185 48.9833C34.518 48.981 34.4979 48.9815 34.4953 48.9664C34.4921 48.948 34.4834 48.7679 34.4791 48.7634C34.4681 48.7522 34.4753 48.7933 34.4681 48.7905C34.4529 48.7844 34.3999 48.7312 34.3982 48.7936C34.4069 48.7973 34.4157 48.801 34.4244 48.8047C34.3757 48.8111 34.3965 48.8377 34.3896 48.8494C34.3822 48.8621 34.3843 48.8072 34.3679 48.8021C34.3643 48.8009 34.2956 48.8124 34.2969 48.8354C34.3348 48.7988 34.3208 48.8666 34.3225 48.8678C34.3292 48.8722 34.3377 48.8342 34.3466 48.8349C34.4094 48.8409 34.3461 48.9009 34.3609 48.9164C34.366 48.9216 34.3761 48.8891 34.3783 48.8907C34.3853 48.8961 34.3855 48.9386 34.3901 48.9352C34.4011 48.9272 34.3883 48.8671 34.3892 48.8639C34.399 48.8263 34.4373 48.8731 34.4134 48.9386C34.4278 48.9622 34.4294 48.8826 34.4408 48.9144C34.4634 48.9774 34.4296 48.9612 34.4204 48.9717C34.3875 49.0094 34.3777 48.9789 34.3312 48.9893C34.3144 48.993 34.2946 49.0317 34.2868 49.0338C34.2819 49.0351 34.2356 48.9006 34.2343 49.1111C34.2163 49.0908 34.188 48.9521 34.1695 48.9584C34.1529 48.9642 34.1582 49.0387 34.1566 49.0415C34.1542 49.0461 34.1341 49.0402 34.1273 49.0507C34.1193 49.0632 34.1233 49.0916 34.1107 49.1032C34.0792 49.1319 34.08 49.0559 34.0768 49.051C34.0392 48.9939 34.0557 49.102 34.0473 49.1107C34.0396 49.1186 33.9309 49.077 33.908 49.1044C33.9173 49.0891 33.9266 49.0739 33.9359 49.0587C33.9192 49.0113 33.9016 49.0886 33.9013 49.0036C33.8979 49.1409 33.8635 49.0491 33.8531 49.0527C33.8491 49.0541 33.8494 49.0775 33.8443 49.0785C33.8244 49.0826 33.7795 49.064 33.7687 49.0759C33.722 49.1269 33.8414 49.2119 33.8508 49.217C33.832 49.2155 33.7255 49.2462 33.7745 49.3122C33.782 49.3224 33.7954 49.261 33.7997 49.2585C33.8284 49.2427 33.8058 49.2978 33.8081 49.303C33.8119 49.3115 33.8308 49.2583 33.8358 49.2646C33.8375 49.2666 33.8268 49.3165 33.8542 49.3175C33.8407 49.3658 33.7636 49.3265 33.7535 49.3378C33.7499 49.3419 33.7725 49.4451 33.7065 49.3448C33.7073 49.3544 33.708 49.364 33.7088 49.3736C33.672 49.3775 33.6353 49.3815 33.5986 49.3854C33.6026 49.3633 33.6232 49.319 33.5972 49.3284C33.5822 49.3338 33.5933 49.383 33.5919 49.3845C33.5785 49.398 33.3409 49.3816 33.2949 49.3871C33.2792 49.3889 33.2356 49.4284 33.2322 49.4292C33.2123 49.4331 33.1419 49.4074 33.1278 49.413C33.119 49.4165 33.1274 49.4577 33.1195 49.4557C33.1122 49.4539 33.1198 49.4141 33.1176 49.4125C33.0997 49.3981 32.9634 49.4502 32.9311 49.4127C32.9508 49.424 33.0495 49.3446 33.0475 49.3165C33.0471 49.3127 33.0231 49.2825 33.0182 49.2972C33.01 49.2628 32.9819 49.3676 32.9667 49.347C32.9649 49.3447 32.9717 49.2859 32.9445 49.2752C32.9351 49.2716 32.9105 49.3174 32.8858 49.266C32.85 49.2907 32.6618 49.2145 32.6488 49.2776C32.6485 49.281 32.675 49.3027 32.6571 49.3286C32.6332 49.3631 32.6546 49.247 32.6269 49.237C32.6227 49.2355 32.5455 49.2473 32.543 49.2544C32.5196 49.3196 32.587 49.346 32.5861 49.3535C32.5838 49.3726 32.5277 49.3841 32.5254 49.3796C32.5233 49.3749 32.569 49.2887 32.514 49.3214C32.5203 49.3317 32.5266 49.342 32.5329 49.3523C32.5071 49.3724 32.5046 49.3127 32.4984 49.3091C32.4789 49.2975 32.4578 49.3882 32.4267 49.2762C32.4184 49.2465 32.4321 49.2135 32.4311 49.209C32.4212 49.169 32.4085 49.276 32.3937 49.1962C32.3925 49.1902 32.4272 49.1424 32.3666 49.1423C32.3708 49.15 32.375 49.1576 32.3791 49.1653C32.3706 49.1824 32.3093 49.1925 32.301 49.1885C32.2769 49.1767 32.2979 49.1217 32.2737 49.1283C32.2892 49.2036 32.2156 49.2134 32.2198 49.1486C32.2095 49.23 32.147 49.1672 32.1175 49.1653C32.099 49.1641 32.0611 49.1996 32.0552 49.1955C32.048 49.1904 32.0502 49.1349 32.0373 49.1225C32.0336 49.119 31.9949 49.1597 31.961 49.1022C31.9545 49.0911 31.9407 48.9969 31.9529 48.9734C31.9738 48.9331 32.0133 49.009 32.0128 48.9533C32.0122 48.8938 31.959 48.9292 31.9446 48.9214C31.8785 48.8855 31.9167 48.8222 31.915 48.803C31.9106 48.7565 31.8744 48.7579 31.8729 48.7537C31.8666 48.7351 31.8923 48.6983 31.8927 48.6699C31.8931 48.6329 31.8583 48.5661 31.8662 48.5536C31.8775 48.5359 31.9096 48.5916 31.9116 48.5889C31.938 48.553 31.9018 48.4675 31.8918 48.4256C31.8888 48.4126 31.9008 48.3914 31.8983 48.3876C31.86 48.3301 31.8903 48.5077 31.8648 48.4959C31.842 48.4853 31.8713 48.4291 31.8704 48.426C31.8693 48.4226 31.8421 48.4196 31.8379 48.3997C31.8358 48.3897 31.9064 48.2805 31.9035 48.2315C31.8809 48.2423 31.8584 48.2531 31.8358 48.2639C31.8341 48.2 31.8665 48.247 31.8699 48.2404C31.8766 48.2272 31.8578 48.1949 31.8586 48.1747C31.859 48.1619 31.8811 48.116 31.8612 48.0971C31.8543 48.0906 31.8399 48.1354 31.8149 48.0896C31.9019 48.0312 31.8416 47.9953 31.839 47.9727C31.8365 47.9501 31.878 47.8968 31.8277 47.9062C31.8255 47.7819 31.8287 47.8669 31.8431 47.8451C31.8606 47.8182 31.8201 47.7773 31.8842 47.8084C31.8805 47.7502 31.829 47.7543 31.8263 47.7496C31.8239 47.7454 31.8354 47.7168 31.8313 47.7071C31.783 47.5946 31.8162 47.646 31.8022 47.5742C31.8009 47.5678 31.7553 47.5411 31.79 47.5307C31.8533 47.5117 31.8798 47.5941 31.8905 47.4178C31.8436 47.3412 31.7869 47.455 31.7726 47.457C31.7508 47.4598 31.7734 47.4238 31.7707 47.4137C31.7698 47.4105 31.751 47.4134 31.7507 47.4106C31.7374 47.2761 31.8344 47.4083 31.8649 47.385C31.8567 47.3648 31.8485 47.3447 31.8403 47.3246C31.8514 47.3237 31.8626 47.3229 31.8737 47.3221C31.8207 47.2817 31.8718 47.3068 31.885 47.1979C31.8879 47.1735 31.8532 47.2154 31.8928 47.1474C31.8636 47.1317 31.8729 47.1095 31.8464 47.1402C31.8471 47.0965 31.9067 47.0473 31.9302 47.0249C31.8472 46.9758 31.8945 47.1359 31.8228 47.0512C31.8095 47.1053 31.8437 47.0948 31.8409 47.1037C31.8309 47.1357 31.8074 47.0848 31.7791 47.1972C31.7744 47.2156 31.794 47.2724 31.7651 47.2697C31.7619 47.2693 31.7435 47.2208 31.7437 47.2173C31.7462 47.1792 31.7644 47.1935 31.7651 47.1776C31.7658 47.1626 31.7455 47.1716 31.7454 47.1675C31.7448 47.1199 31.7624 47.1493 31.7598 47.1344C31.7543 47.1019 31.6812 46.9995 31.7766 47.0295C31.6974 47.0833 31.7665 47.0821 31.7974 47.0614C31.8052 47.0562 31.8072 47.0278 31.8184 47.0179C31.8329 47.0051 31.8498 47.0188 31.8572 47.0135C31.8653 47.0078 31.8196 46.9405 31.8856 46.9606C31.852 46.8937 31.7927 46.965 31.7597 46.9181C31.6932 46.8232 31.8061 46.8028 31.8179 46.7936C31.821 46.7911 31.8105 46.7527 31.8126 46.7504C31.816 46.7468 31.8801 46.7645 31.8865 46.7327C31.8928 46.701 31.863 46.7342 31.861 46.7011C31.8597 46.6788 31.937 46.6392 31.8951 46.624C31.8663 46.6135 31.8131 46.7032 31.8041 46.6068C31.8466 46.5988 31.889 46.5909 31.9314 46.5829C31.9082 46.5462 31.885 46.5096 31.8618 46.4729C31.9094 46.4613 31.9506 46.5027 31.9958 46.4502C31.8871 46.3328 32.0311 46.3565 32.0327 46.3422C32.0332 46.3337 31.9904 46.2383 31.9835 46.2209C32.0215 46.1842 32.1367 46.1663 32.0693 46.0486C32.0815 46.0752 32.1111 46.0096 32.1107 46.0046C32.107 45.9526 32.0424 45.9863 32.0529 45.9394C32.0651 45.8849 32.0822 45.9588 32.101 45.9529C32.1974 45.9221 32.171 45.6506 32.2677 45.6936C32.2657 45.6839 32.2638 45.6743 32.2619 45.6646C32.367 45.68 32.4721 45.6954 32.5772 45.7108C32.6183 45.6278 32.7277 45.5774 32.7814 45.5865C32.7923 45.5883 32.8454 45.6318 32.8494 45.6395C32.8568 45.6541 32.816 45.6597 32.8345 45.6871C32.8384 45.6927 32.9283 45.711 32.9219 45.6646C32.9118 45.6592 32.8803 45.6825 32.8751 45.6716C32.8388 45.5936 33.1161 45.6559 33.1299 45.6245C33.1237 45.6094 33.1176 45.5944 33.1115 45.5793C33.129 45.5867 33.1465 45.5941 33.164 45.6015ZM32.3598 49.3267C32.3493 49.3732 32.323 49.3383 32.3075 49.3513C32.286 49.3696 32.2494 49.5489 32.2652 49.3692C32.2967 49.3551 32.3283 49.3409 32.3598 49.3267ZM32.821 49.3961C32.7999 49.3711 32.8163 49.2707 32.8336 49.3124C32.8355 49.3172 32.8496 49.4297 32.821 49.3961ZM32.5992 49.3484C32.6001 49.3471 32.6184 49.3498 32.619 49.3513C32.6354 49.3916 32.5803 49.3834 32.5992 49.3484ZM33.6708 49.297C33.6475 49.3013 33.6644 49.3925 33.6789 49.355C33.6798 49.3526 33.6723 49.2968 33.6708 49.297ZM33.6542 49.2946C33.6361 49.2129 33.5997 49.3784 33.6286 49.3617C33.6315 49.3601 33.6551 49.2985 33.6542 49.2946ZM32.7456 49.3562C32.748 49.3249 32.7698 49.34 32.7791 49.3475C32.7789 49.3761 32.7547 49.3527 32.7456 49.3562ZM33.299 49.3475C33.2999 49.3229 33.2241 49.3242 33.2189 49.3567C33.2309 49.3429 33.2981 49.3696 33.299 49.3475ZM33.4936 49.3129C33.4916 49.3087 33.4654 49.3151 33.4662 49.3368C33.479 49.3653 33.5022 49.3322 33.4936 49.3129ZM33.8803 49.3144C33.8817 49.3089 33.8621 49.1708 33.9086 49.2617C33.9154 49.275 33.891 49.3111 33.8934 49.3161C33.8985 49.3257 33.9025 49.3302 33.9058 49.331C33.8841 49.3425 33.8616 49.3479 33.8594 49.3395C33.8492 49.2999 33.8796 49.3166 33.8803 49.3144ZM34.0833 49.2114C34.0877 49.1889 34.1162 49.2009 34.1227 49.2102C34.1238 49.212 34.119 49.2712 34.1318 49.2668C34.1421 49.2631 34.1267 49.2024 34.1468 49.2122C34.1671 49.2219 34.14 49.2651 34.1418 49.2682C34.1441 49.2723 34.1755 49.245 34.1745 49.2803C34.1738 49.3064 34.1402 49.2888 34.1319 49.2943C34.1212 49.3015 34.1341 49.345 34.1164 49.3356C34.1052 49.3298 34.1114 49.2532 34.109 49.2494C34.107 49.2462 34.068 49.2903 34.0833 49.2117C34.0833 49.2116 34.0833 49.2115 34.0833 49.2114ZM33.9116 49.3277C33.91 49.3302 33.9081 49.3316 33.9058 49.331C33.9077 49.33 33.9097 49.3288 33.9116 49.3277ZM32.421 49.2931C32.432 49.3167 32.3993 49.347 32.387 49.3161C32.3867 49.2911 32.4192 49.2894 32.421 49.2931ZM33.9317 49.2653C33.9639 49.2845 33.9402 49.3109 33.9116 49.3277C33.9207 49.3133 33.9209 49.2589 33.9317 49.2653ZM33.0182 49.2972C33.0195 49.3029 33.0204 49.3118 33.0205 49.3265C33.0169 49.3105 33.0166 49.3019 33.0182 49.2972ZM33.0932 49.3233C33.119 49.2788 33.0667 49.2806 33.067 49.3124C33.0672 49.3245 33.0922 49.3251 33.0932 49.3233ZM33.7007 49.3013C33.6984 49.297 33.7349 49.1624 33.6818 49.2634C33.7102 49.2792 33.6803 49.2939 33.6807 49.3057C33.6819 49.3395 33.7295 49.307 33.74 49.3216C33.7483 49.261 33.7085 49.3157 33.7008 49.3013C33.7008 49.3013 33.7007 49.3013 33.7007 49.3013ZM34.4492 49.244C34.4427 49.2796 34.4223 49.2681 34.4085 49.266C34.4149 49.2305 34.4354 49.242 34.4492 49.244ZM38.0622 49.2491C37.9676 49.2819 37.9554 49.1374 38.0419 49.1945C38.0436 49.1957 38.068 49.2345 38.0622 49.2491ZM37.2503 49.2117C37.2414 49.1487 37.2709 49.1385 37.2903 49.1645C37.2946 49.1704 37.3109 49.2342 37.2923 49.2467C37.2929 49.1703 37.2643 49.1411 37.2503 49.2117ZM33.9499 49.225C33.9593 49.1829 33.9881 49.2128 34.0033 49.2192C33.994 49.2538 33.9633 49.2381 33.9499 49.225ZM37.7514 49.1737C37.7414 49.169 37.7347 49.2238 37.7364 49.2283C37.7441 49.2493 37.7627 49.2049 37.7514 49.1737ZM33.8568 49.2184C33.8555 49.1933 33.8937 49.1691 33.8963 49.2312C33.8882 49.2267 33.8577 49.2342 33.8568 49.2184ZM34.4231 49.2252C34.4172 49.2124 34.4479 49.1896 34.4572 49.2022C34.4565 49.229 34.427 49.2335 34.4231 49.2252ZM37.5908 49.1923C37.5819 49.1876 37.5596 49.1861 37.5571 49.2083C37.554 49.236 37.5867 49.2265 37.5908 49.1923ZM39.2523 49.1445C39.2535 49.1544 39.2189 49.2262 39.2036 49.208C39.1744 49.1733 39.2511 49.1375 39.2523 49.1445ZM37.8458 49.1455C37.8739 49.1976 37.8426 49.1471 37.8439 49.202C37.8628 49.204 37.91 49.2067 37.8776 49.1527C37.8712 49.1423 37.8546 49.149 37.8458 49.1455ZM37.8198 49.1271C37.8168 49.1449 37.7965 49.2009 37.814 49.1969C37.8221 49.195 37.8352 49.1327 37.8198 49.1271ZM39.0383 49.1689C39.013 49.1203 39.1287 49.1464 39.1321 49.1549C39.1338 49.1594 39.135 49.1636 39.1356 49.1672C39.1399 49.1518 39.1617 49.149 39.1643 49.188C39.1577 49.1848 39.1398 49.1882 39.1377 49.1839C39.1368 49.182 39.1362 49.1803 39.1357 49.1786C39.128 49.2124 39.0431 49.1781 39.0383 49.1689ZM38.8465 49.1189C38.8754 49.0472 38.8805 49.1691 38.8781 49.173C38.8466 49.2229 38.8671 49.133 38.8661 49.1288C38.864 49.1218 38.8416 49.1635 38.8466 49.1189C38.8466 49.1189 38.8466 49.1189 38.8465 49.1189ZM38.999 49.1488C39.0002 49.1472 39.0244 49.151 39.0254 49.1529C39.0453 49.1939 38.9767 49.1834 38.999 49.1488ZM34.2363 49.1261C34.2537 49.1382 34.2366 49.1831 34.2251 49.167C34.2242 49.1654 34.221 49.1154 34.2363 49.1261ZM37.8059 49.1392C37.8019 49.1307 37.6989 49.0987 37.7051 49.1665C37.7139 49.1585 37.8309 49.1934 37.8059 49.1392ZM37.0365 49.1227C37.0546 49.1233 37.0348 49.1872 37.0251 49.1633C37.0215 49.1545 37.0319 49.1226 37.0365 49.1227ZM33.8053 49.1604C33.7864 49.1955 33.7903 49.0778 33.8067 49.1181C33.8073 49.1197 33.806 49.1591 33.8053 49.1604ZM37.1815 49.1595C37.1189 49.1982 37.1337 48.9956 37.2151 49.064C37.2126 49.073 37.21 49.0821 37.2075 49.0911C37.3015 49.1215 37.2139 49.1054 37.1909 49.1167C37.1822 49.121 37.1895 49.1548 37.1816 49.1597C37.1816 49.1596 37.1815 49.1595 37.1815 49.1595ZM36.941 49.1189C36.8807 48.9751 36.9958 49.0687 37.0288 49.05C36.9968 49.1094 36.9551 49.1004 37.0118 49.1612C36.9289 49.1729 36.9634 49.1157 36.9601 49.1109C36.9562 49.1056 36.9436 49.125 36.941 49.1189ZM37.1 49.1179C37.1035 49.1137 37.1298 49.143 37.1393 49.1382C37.126 49.1873 37.0769 49.1464 37.1 49.1179ZM38.6456 49.1522C38.6477 49.1137 38.6531 49.0854 38.6739 49.0998C38.6675 49.1191 38.6542 49.1357 38.6456 49.1522ZM32.3399 49.1242C32.3256 49.1214 32.2972 49.1069 32.3059 49.1474C32.3069 49.1508 32.3398 49.1469 32.3399 49.1242ZM37.5069 49.108C37.5038 49.1033 37.4253 49.1001 37.4524 49.1426C37.4606 49.1554 37.532 49.1499 37.5069 49.108ZM37.9134 49.1128C37.9069 49.1124 37.8802 49.1197 37.8796 49.1288C37.8778 49.1602 37.9106 49.1429 37.9134 49.1128ZM32.2679 49.0848C32.266 49.0808 32.2224 49.0879 32.2272 49.1065C32.2363 49.1419 32.2743 49.0985 32.2679 49.0848ZM34.2995 49.036C34.3031 49.0346 34.3079 49.0764 34.3092 49.0768C34.3122 49.0774 34.3789 49.0613 34.3534 49.115C34.3491 49.124 34.2531 49.1034 34.2407 49.0981C34.2358 49.0407 34.2768 49.0953 34.2868 49.0894C34.2886 49.0883 34.2897 49.0403 34.2994 49.0362C34.2994 49.0361 34.2995 49.0361 34.2995 49.036ZM38.7535 49.1116C38.7565 49.0751 38.8349 49.051 38.834 49.0952C38.8072 49.1007 38.7804 49.1061 38.7535 49.1116ZM38.7137 49.1056C38.697 49.0798 38.7362 49.0712 38.7477 49.0826C38.7478 49.1072 38.7161 49.1094 38.7137 49.1056ZM37.7647 48.9765C37.7568 48.9855 37.781 49.0387 37.7756 49.049C37.7721 49.0555 37.7545 49.0355 37.7489 49.0522C37.7473 49.0575 37.7653 49.1075 37.7705 49.1053C37.7779 49.1024 37.7707 49.0631 37.7788 49.0628C37.8055 49.062 37.8292 49.09 37.8543 49.0894C37.8565 49.0893 37.839 49.0614 37.8583 49.0618C37.8613 49.0618 37.8792 49.1033 37.9023 49.0971C37.9533 48.9689 37.9908 49.0948 38.0555 49.0485C38.0531 49.0365 38.0046 49.0041 38.0018 49.0029C37.9477 48.9818 37.8507 48.9795 37.7941 48.9792C37.7795 48.9791 37.7866 49.0062 37.7803 49.0072C37.7754 49.008 37.7813 48.9577 37.7647 48.9765ZM32.3475 49.0964C32.3407 49.0462 32.3168 49.078 32.3016 49.0754C32.3069 49.1207 32.3326 49.0853 32.3475 49.0964ZM38.3616 49.0667C38.3539 49.0686 38.3302 49.0535 38.3283 49.0686C38.3257 49.0883 38.3599 49.1008 38.3616 49.0667ZM34.6757 49.0502C34.6764 49.0489 34.6948 49.0516 34.6955 49.0531C34.7119 49.0934 34.6568 49.0852 34.6757 49.0502ZM35.1154 49.0599C35.1293 49.0537 35.1434 49.038 35.1481 49.0788C35.1392 49.0725 35.1137 49.0883 35.1154 49.0599ZM35.722 49.0587C35.7191 49.0053 35.7611 49.0399 35.769 49.0447C35.7661 49.0684 35.7241 49.0971 35.722 49.0587ZM38.6425 48.9847C38.6682 48.9879 38.6628 48.9071 38.6791 48.9437C38.6817 48.9498 38.6903 49.1181 38.6621 49.0551C38.657 49.0437 38.6769 49.0037 38.6425 48.9847ZM37.2284 49.0657C37.2349 49.0304 37.2553 49.0409 37.2691 49.0437C37.266 49.0699 37.2382 49.0632 37.2284 49.0657ZM32.1891 49.0444C32.1771 48.9946 32.1215 49.0316 32.1353 49.0645C32.1372 49.0688 32.1813 49.0426 32.1891 49.0444ZM34.0151 49.064C34.038 49.0248 33.9906 49.0126 33.9757 49.051C33.9824 49.0485 34.0136 49.0666 34.0151 49.064ZM35.5763 49.0297C35.5774 49.0281 35.6016 49.0319 35.6027 49.0338C35.6226 49.0748 35.554 49.0643 35.5763 49.0297ZM34.9708 48.9951C34.9795 48.9629 35.0369 48.9889 35.0498 49.0212C35.0374 49.0685 34.9599 49.0355 34.9708 48.9951ZM38.537 49.0077C38.5553 49.006 38.5727 49.016 38.5895 49.0299C38.5859 49.0571 38.5389 49.028 38.537 49.0077ZM35.6653 49.0263C35.6666 49.0265 35.6679 49.0296 35.6691 49.0299C35.6678 49.0288 35.6665 49.0275 35.6653 49.0263ZM38.1274 48.9886C38.1121 48.9779 38.1153 49.0277 38.1162 49.0292C38.1278 49.0453 38.1448 49.0007 38.1274 48.9886ZM32.33 49.0224C32.3246 48.9775 32.2988 49.0124 32.284 49.0017C32.2883 49.0372 32.318 49.0272 32.33 49.0224ZM36.8764 49.0268C36.8571 48.9781 36.9355 48.9214 36.952 48.9529C36.9533 48.983 36.8792 49.0335 36.8764 49.0268ZM33.9441 48.9966C33.9426 48.9614 33.9096 49.0039 33.9166 49.0205C33.9211 49.0311 33.945 49.0185 33.9441 48.9966ZM36.9915 48.9734C36.9988 48.9626 37.016 48.9974 37.0099 49.0186C37.0022 49.0457 36.9896 48.9765 36.9915 48.9734ZM37.6522 48.9451C37.649 48.9397 37.6057 48.9759 37.6236 49.0118C37.636 49.0368 37.638 48.9859 37.6409 48.9857C37.6442 48.9859 37.7137 49.0482 37.6522 48.9451ZM36.4374 48.9961C36.4537 48.9826 36.4735 48.9983 36.4906 48.9973C36.4836 49.0191 36.4443 49.025 36.4374 48.9961ZM34.071 48.9872C34.067 48.9729 33.959 48.9643 34.0204 49.0082C34.0239 49.0107 34.0831 49.0303 34.071 48.9872ZM38.6425 48.9847C38.6393 48.9844 38.6356 48.9827 38.6312 48.9792C38.6355 48.9806 38.6393 48.9829 38.6425 48.9847ZM38.3512 48.9794C38.3571 48.9538 38.3274 48.9469 38.3186 48.9606C38.3159 48.9919 38.3504 48.983 38.3512 48.9794ZM36.4919 48.9615C36.5017 48.9469 36.5196 48.9625 36.5318 48.9608C36.5297 48.9847 36.4961 48.9858 36.4919 48.9615ZM35.8 48.9347C35.8196 48.9489 35.8436 48.9424 35.844 48.9132C35.8444 48.9178 35.8454 48.9226 35.8469 48.9275C35.8485 48.9323 35.8695 48.9187 35.8786 48.9287C35.9331 48.9878 35.6681 48.9634 35.8217 48.8811C35.8145 48.899 35.8072 48.9168 35.8 48.9347ZM34.8931 48.9265C34.8819 48.891 34.8508 48.9355 34.8589 48.9495C34.8645 48.959 34.9042 48.9622 34.8931 48.9265ZM35.3204 48.9055C35.317 48.8991 35.2867 48.924 35.2859 48.9427C35.3033 48.9624 35.3355 48.9349 35.3204 48.9055ZM34.8077 48.8849C34.8007 48.8796 34.7918 48.9368 34.7926 48.9393C34.7997 48.9602 34.8194 48.9168 34.8077 48.8849ZM38.5894 48.8306C38.579 48.8142 38.546 48.8556 38.5388 48.8934C38.5374 48.8861 38.5338 48.8766 38.5272 48.8651C38.5272 48.8651 38.5272 48.8651 38.5273 48.8651C38.5183 48.8499 38.2511 48.8332 38.4304 48.906C38.436 48.9083 38.4283 48.8744 38.4511 48.8804C38.4527 48.8808 38.4534 48.9085 38.4581 48.9098C38.4688 48.9128 38.5259 48.9302 38.5374 48.9079C38.5375 48.913 38.5382 48.9179 38.5398 48.9224C38.5539 48.9623 38.5974 48.8432 38.5894 48.8306ZM35.3806 48.9004C35.3744 48.8901 35.3551 48.8999 35.3531 48.9243C35.3627 48.9363 35.3947 48.9244 35.3806 48.9004ZM34.0677 48.8869C34.0552 48.8668 34.0237 48.9044 34.0332 48.9243C34.039 48.9366 34.082 48.91 34.0677 48.8869ZM35.1868 48.9135C35.2582 48.9424 35.2038 48.9111 35.2148 48.8753C35.2055 48.888 35.1961 48.9007 35.1868 48.9135ZM38.9198 48.9231C38.9084 48.9149 38.9218 48.8441 38.9343 48.8825C38.9383 48.8947 38.9262 48.9276 38.9198 48.9231ZM39.4338 48.9011C39.4241 48.8384 39.4716 48.8753 39.4531 48.9183C39.4522 48.9197 39.4345 48.9035 39.4338 48.9011ZM39.0746 48.8755C39.0669 48.9182 39.0619 48.9233 39.0401 48.9127C39.0723 48.9007 39.0424 48.8629 39.0746 48.8755ZM35.8438 48.9086C35.8439 48.9104 35.844 48.9116 35.844 48.9132C35.8439 48.9116 35.8438 48.9102 35.8438 48.9086ZM34.7406 48.8961C34.7316 48.8599 34.7066 48.8625 34.714 48.899C34.7148 48.9023 34.7369 48.9228 34.7406 48.8961ZM38.5388 48.8934C38.54 48.8999 38.5394 48.9041 38.5374 48.9079C38.5373 48.9031 38.5378 48.8985 38.5388 48.8934ZM34.875 48.8666C34.8742 48.8936 34.9123 48.9041 34.9138 48.9009C34.9357 48.8541 34.8908 48.865 34.875 48.8666ZM33.8156 48.8489C33.8137 48.8518 33.8263 48.9214 33.8341 48.8941C33.8401 48.8729 33.823 48.8382 33.8156 48.8489ZM39.1485 48.8581C39.1606 48.8582 39.1776 48.8581 39.1807 48.8912C39.1727 48.8861 39.1483 48.8824 39.1485 48.8581ZM39.4152 48.8557C39.401 48.8946 39.3684 48.8945 39.3476 48.8881C39.3472 48.8369 39.4019 48.8677 39.4152 48.8557ZM38.6221 48.8497C38.6212 48.8476 38.5909 48.8323 38.595 48.8666C38.6011 48.9168 38.6307 48.8683 38.6221 48.8497ZM33.8744 48.8859C33.8879 48.8623 33.8568 48.7898 33.8425 48.8458C33.8352 48.8745 33.8721 48.8899 33.8744 48.8859ZM34.6624 48.8487C34.6445 48.8685 34.6888 48.9039 34.695 48.868C34.6867 48.8652 34.6687 48.8417 34.6624 48.8487ZM35.2701 48.8124C35.2139 48.7091 35.2445 48.8977 35.2545 48.8811C35.2559 48.8787 35.2715 48.8149 35.2701 48.8124ZM32.0495 48.8378C32.0415 48.8522 32.0712 48.9042 32.075 48.87C32.0774 48.8485 32.0546 48.8287 32.0495 48.8378ZM36.1178 48.8796C36.1154 48.88 36.113 48.8803 36.1107 48.8806C36.1125 48.8789 36.1148 48.8784 36.1178 48.8796ZM34.5002 48.7102C34.5398 48.8562 34.5357 48.7437 34.5391 48.7443C34.5466 48.7459 34.5639 48.7853 34.5779 48.7789C34.5618 48.7953 34.5458 48.8117 34.5297 48.8282C34.5424 48.8387 34.6526 48.8924 34.6549 48.8688C34.6582 48.835 34.6235 48.8456 34.6225 48.8427C34.6211 48.8384 34.6157 48.7447 34.6124 48.7412C34.6071 48.7355 34.515 48.7335 34.5002 48.7102ZM35.1524 48.8286C35.1615 48.8398 35.1641 48.8769 35.1683 48.868C35.1697 48.865 35.1699 48.8296 35.1748 48.8204C35.1674 48.8232 35.1599 48.8259 35.1524 48.8286ZM34.4293 48.8414C34.418 48.7982 34.4683 48.8146 34.47 48.8195C34.4786 48.8488 34.4384 48.8768 34.4293 48.8414ZM34.856 48.8352C34.8542 48.8326 34.8156 48.8191 34.8159 48.8431C34.8261 48.8614 34.8777 48.8668 34.856 48.8352ZM35.1809 48.818C35.1944 48.8221 35.2201 48.8578 35.2171 48.8045C35.2171 48.8045 35.2171 48.8045 35.2171 48.8045C35.205 48.809 35.1929 48.8135 35.1809 48.818ZM33.9207 48.7733C33.8956 48.6884 33.9075 48.7957 33.9298 48.8231C33.9365 48.785 33.9249 48.7871 33.9207 48.7733ZM33.8403 48.71C33.8333 48.6947 33.7612 48.7114 33.7722 48.7564C33.7761 48.7724 33.8175 48.732 33.8195 48.7351C33.8224 48.7397 33.8091 48.7894 33.8312 48.7796C33.8299 48.7627 33.8427 48.7151 33.8403 48.71ZM33.8999 48.7189C33.8749 48.6543 33.8693 48.7735 33.8881 48.7738C33.8955 48.774 33.9035 48.7282 33.8999 48.7189ZM34.002 48.7291C33.993 48.7178 33.9691 48.7013 33.9525 48.7409C33.9746 48.7443 33.9967 48.7477 34.0188 48.7511C34.0214 48.7286 34.0099 48.739 34.0019 48.7291C34.002 48.7291 34.002 48.7291 34.002 48.7291ZM39.5654 48.5505C39.5455 48.5167 39.5913 48.5038 39.5932 48.5121C39.599 48.5396 39.5743 48.5656 39.5654 48.5505ZM31.8944 47.7557C31.8889 47.7422 31.8853 47.6979 31.8731 47.7211C31.8853 47.7538 31.8975 47.7865 31.9098 47.8192C31.9192 47.7443 31.9004 47.7705 31.8944 47.7557ZM31.8477 47.4819C31.8495 47.4801 31.84 47.3648 31.8623 47.4418C31.8774 47.4937 31.7955 47.5443 31.7807 47.4932C31.797 47.4695 31.8329 47.4967 31.8477 47.4819ZM31.7043 46.9831C31.7033 46.9739 31.7345 46.9604 31.7381 46.9669C31.757 47.001 31.7094 47.0323 31.7043 46.9831ZM31.8035 47.0051C31.789 46.9827 31.8213 46.9683 31.8309 46.9812C31.8319 47.0026 31.8058 47.0083 31.8035 47.0051ZM39.3643 46.8816C39.3486 46.8033 39.3344 46.9719 39.3587 46.9379C39.3599 46.9363 39.365 46.8854 39.3643 46.8816ZM31.7347 46.8668C31.7493 46.8892 31.717 46.9036 31.7073 46.8908C31.7064 46.8693 31.7325 46.8636 31.7347 46.8668ZM39.3532 46.695C39.3323 46.6387 39.3396 46.8278 39.3423 46.8354C39.3531 46.8655 39.3901 46.7913 39.3976 46.7728C39.3422 46.8012 39.3631 46.7216 39.3532 46.695ZM39.2565 46.8086C39.2371 46.8288 39.2868 46.8674 39.2963 46.8146C39.2866 46.8172 39.262 46.8028 39.2565 46.8086ZM39.1384 46.748C39.128 46.7412 39.0969 46.725 39.0916 46.7547C39.1031 46.7493 39.134 46.7786 39.1384 46.748ZM39.1147 46.6588C39.0984 46.6183 39.0945 46.7362 39.1133 46.7011C39.1141 46.6997 39.1153 46.661 39.1147 46.6588ZM39.0228 46.6162C39.0121 46.5694 38.9999 46.6835 39.0172 46.6866C39.0224 46.6873 39.024 46.6216 39.0228 46.6162ZM39.327 46.4916C39.3116 46.4714 39.2918 46.5531 39.3246 46.5621C39.3131 46.5746 39.3016 46.5871 39.2901 46.5996C39.333 46.6454 39.3299 46.5321 39.3422 46.5367C39.3594 46.5434 39.3581 46.6369 39.3546 46.6663C39.3687 46.609 39.4288 46.6081 39.4635 46.5972C39.433 46.5731 39.3835 46.5314 39.3534 46.5162C39.3448 46.5118 39.3365 46.5374 39.3292 46.5346C39.3174 46.5298 39.3278 46.4929 39.327 46.4916C39.327 46.4916 39.327 46.4916 39.327 46.4916ZM38.902 46.6146C38.8705 46.5615 38.8904 46.6761 38.9082 46.6556C38.909 46.6541 38.9028 46.6159 38.902 46.6146ZM31.6929 46.5186C31.735 46.5665 31.7044 46.63 31.7925 46.5336C31.7555 46.6018 31.7905 46.5827 31.7832 46.6102C31.7775 46.632 31.7557 46.6139 31.7684 46.6578C31.7518 46.6101 31.6797 46.6233 31.6765 46.6155C31.6765 46.6155 31.6766 46.6155 31.6766 46.6155C31.6747 46.6109 31.6795 46.5034 31.6929 46.5186ZM39.1383 46.4483C39.1278 46.3092 39.1236 46.5299 39.103 46.4147C39.0754 46.582 39.179 46.4147 39.1915 46.5561C39.0791 46.5396 39.2658 46.6961 39.1873 46.4845C39.252 46.5613 39.2085 46.4583 39.2185 46.4314C39.2292 46.4027 39.2658 46.4339 39.2639 46.3821C39.2639 46.3821 39.2639 46.3821 39.2638 46.3821C39.2415 46.3857 39.2191 46.3893 39.1967 46.393C39.2186 46.5047 39.1729 46.4712 39.1574 46.3801C39.151 46.4029 39.1447 46.4256 39.1383 46.4483ZM39.2649 46.5532C39.2627 46.5506 39.214 46.5663 39.2172 46.5887C39.2237 46.603 39.2927 46.5859 39.2649 46.5532ZM39.4791 46.5288C39.4616 46.5285 39.4346 46.5067 39.4251 46.5488C39.4425 46.5491 39.4696 46.5709 39.4791 46.5288ZM38.5794 46.5208C38.5571 46.5554 38.6257 46.5656 38.6058 46.5247C38.6049 46.5227 38.5805 46.5192 38.5794 46.5208ZM39.0876 46.4693C39.065 46.4268 39.0757 46.5621 39.0925 46.5268C39.0934 46.5248 39.0887 46.4713 39.0876 46.4693ZM31.727 46.5022C31.7286 46.469 31.7897 46.4923 31.8005 46.492C31.7943 46.5228 31.7253 46.5402 31.727 46.5022ZM39.5098 46.4048C39.4751 46.2856 39.4279 46.4233 39.4227 46.4203C39.4176 46.4172 39.4256 46.3651 39.4245 46.3637C39.4218 46.3608 39.367 46.3652 39.3643 46.3688C39.3624 46.3716 39.3724 46.4448 39.3611 46.4679C39.3831 46.4263 39.4833 46.4523 39.4885 46.4442C39.4925 46.4377 39.4621 46.3608 39.5098 46.4048C39.5098 46.4048 39.5098 46.4048 39.5098 46.4048ZM39.4098 46.4043C39.4235 46.435 39.3851 46.4388 39.3758 46.4275C39.3552 46.4022 39.408 46.4007 39.4098 46.4043ZM39.3175 46.376C39.3131 46.3692 39.2735 46.3629 39.2702 46.3971C39.2889 46.4414 39.3274 46.3921 39.3175 46.376ZM38.8773 46.3806C38.867 46.385 38.8388 46.3588 38.8372 46.3886C38.8474 46.3843 38.8757 46.4105 38.8773 46.3806ZM31.9356 46.2417C31.9185 46.2167 31.958 46.2065 31.9696 46.2185C31.9702 46.2384 31.937 46.2438 31.9356 46.2417ZM39.0838 46.1839C39.0777 46.1748 38.9536 46.1975 38.9362 46.2115C38.9532 46.234 39.0762 46.2358 39.0818 46.2248C39.0834 46.2215 39.0846 46.1853 39.0838 46.1839ZM39.3522 46.1701C39.3635 46.1262 39.371 46.1789 39.3724 46.1796C39.3865 46.1863 39.4157 46.1764 39.4093 46.2187C39.3844 46.2016 39.3295 46.2574 39.3522 46.1701ZM38.8685 46.1817C38.8263 46.1981 38.9073 46.2444 38.8967 46.1984C38.896 46.1956 38.8728 46.18 38.8685 46.1817ZM39.0977 46.1711C39.1069 46.1356 39.2311 46.1662 39.251 46.1663C39.2332 46.2318 39.2188 46.182 39.1948 46.1854C39.1883 46.1863 39.1901 46.2136 39.1894 46.2136C39.1782 46.2149 39.1865 46.1834 39.1796 46.183C39.1753 46.1827 39.0846 46.2212 39.0977 46.1711ZM39.3587 46.1397C39.3656 46.1145 39.4431 46.1038 39.4462 46.1105C39.4696 46.1603 39.3647 46.1485 39.3587 46.1397ZM39.0863 46.1129C39.0996 46.0367 39.1613 46.0877 39.1191 46.1257C39.115 46.1291 39.098 46.0961 39.0863 46.1129ZM38.873 46.1092C38.8709 46.107 38.827 46.0918 38.8262 46.116C38.8325 46.1254 38.8966 46.1339 38.873 46.1092ZM38.8958 46.0273C38.8947 46.0279 38.905 46.0746 38.8844 46.0686C38.8827 46.0681 38.8795 46.0156 38.8536 46.0348C38.8483 46.0388 38.8402 46.0735 38.8408 46.0757C38.8677 46.158 38.9489 46.0003 38.8958 46.0273ZM39.3601 46.0972C39.3559 46.075 39.366 46.0092 39.3751 46.0425C39.379 46.0569 39.3717 46.0964 39.3601 46.0972ZM38.7337 46.088C38.7592 46.0481 38.679 46.0406 38.6749 46.0508C38.6775 46.0756 38.7311 46.0919 38.7337 46.088ZM31.9755 45.9338C31.9755 45.9338 31.9755 45.9338 31.9755 45.9338C31.9969 45.9428 31.9836 45.976 31.9846 45.9771C32.0304 46.0258 32.0183 45.9506 32.0254 45.9418C32.0408 45.9226 32.0383 46.014 32.0642 45.9761C32.0214 46.032 32.0603 46.0086 32.0615 46.0411C32.0663 46.1738 32.0046 45.979 31.9832 46.0068C31.9803 46.0106 32.0022 46.053 31.9946 46.065C31.9698 46.1041 31.8931 45.8992 31.9755 45.9338ZM39.3821 46.0367C39.392 45.9978 39.4676 46.0356 39.4476 46.0677C39.4444 46.0728 39.3674 46.0936 39.3821 46.0367ZM35.8507 45.9792C35.8688 45.9455 35.8267 45.9059 35.8189 45.9321C35.815 45.9452 35.8427 45.994 35.8507 45.9792ZM35.5554 45.835C35.5338 45.8418 35.5111 45.9825 35.5379 45.9606C35.5408 45.9582 35.5579 45.8545 35.5554 45.835ZM36.9731 45.9072C36.9505 45.857 36.9519 45.9503 36.9684 45.949C36.9742 45.9486 36.9738 45.9088 36.9731 45.9072ZM36.1127 45.9193C36.1104 45.916 36.0843 45.922 36.0853 45.9435C36.0949 45.9563 36.1273 45.9417 36.1127 45.9193ZM36.9802 45.8939C36.9669 45.9108 36.9899 45.9783 37.0062 45.9123C36.9979 45.9177 36.9816 45.8922 36.9802 45.8939ZM39.0397 45.9065C39.0285 45.9448 38.9968 45.9333 38.9786 45.9398C38.9767 45.8902 39.0267 45.9155 39.0397 45.9065ZM35.6471 45.8915C35.6266 45.9265 35.6704 45.9552 35.6664 45.9089C35.6658 45.9064 35.6479 45.89 35.6471 45.8915ZM37.7004 45.8889C37.6855 45.9185 37.7327 45.9583 37.7197 45.9063C37.7191 45.9041 37.7012 45.8872 37.7004 45.8889ZM37.9063 45.906C37.8951 45.896 37.847 45.8991 37.8657 45.928C37.8686 45.9324 37.9055 45.9332 37.9063 45.906ZM32.0267 45.906C32.0206 45.855 32.0559 45.8671 32.0609 45.876C32.0629 45.8798 32.0346 45.9724 32.0267 45.906ZM36.8266 45.8992C36.815 45.9056 36.7847 45.8935 36.7794 45.9203C36.7937 45.9147 36.8305 45.9526 36.8266 45.8992ZM35.7402 45.8913C35.7225 45.8358 35.692 45.8413 35.6996 45.9137C35.7331 45.9089 35.6954 45.8486 35.7402 45.8913ZM37.0553 45.8342C37.046 45.83 37.0388 45.8996 37.0399 45.9029C37.05 45.9341 37.0646 45.8613 37.0553 45.8342ZM36.3534 45.8915C36.3529 45.8618 36.3229 45.8753 36.3269 45.8944C36.3282 45.9008 36.3539 45.9156 36.3534 45.8915ZM38.647 45.8896C38.6333 45.8624 38.6752 45.8359 38.6876 45.8676C38.6937 45.9132 38.6487 45.8927 38.647 45.8896ZM37.3147 45.8516C37.3161 45.8075 37.2693 45.8325 37.2877 45.869C37.2923 45.8782 37.3142 45.8664 37.3147 45.8516ZM37.7634 45.7987C37.7319 45.8513 37.8639 45.8887 37.8293 45.8231C37.8268 45.8184 37.7661 45.7943 37.7634 45.7987ZM37.979 45.8316C37.9735 45.8258 37.9762 45.6775 37.9987 45.7347C38.0016 45.7421 37.9878 45.7813 37.9903 45.7903C37.9917 45.7954 38.0405 45.8162 38.0427 45.8127C38.0451 45.8088 38.0423 45.7613 38.0448 45.7559C38.0475 45.75 38.0776 45.7917 38.0933 45.7922C38.1229 45.793 38.1261 45.7534 38.1286 45.7533C38.1357 45.753 38.1476 45.7811 38.1619 45.7811C38.2343 45.7808 38.345 45.7472 38.4024 45.8311C38.3513 45.7974 38.3027 45.8332 38.2518 45.8441C38.2667 45.7616 38.1771 45.9078 38.2295 45.8125C38.2054 45.8332 37.9967 45.8497 37.979 45.8316C37.979 45.8316 37.979 45.8316 37.979 45.8316ZM35.4702 45.7934C35.4835 45.7428 35.4154 45.7542 35.4096 45.8127C35.4186 45.8209 35.4686 45.7991 35.4702 45.7934ZM35.7842 45.6699C35.7905 45.6612 35.7965 45.5622 35.8296 45.6124C35.8297 45.6124 35.8297 45.6124 35.8297 45.6124C35.8394 45.6271 35.8284 45.6512 35.8301 45.6598C35.8308 45.6633 35.861 45.7125 35.8359 45.7204C35.7976 45.7326 35.8323 45.6468 35.8119 45.6457C35.8094 45.6457 35.7708 45.6992 35.773 45.711C35.7733 45.7124 35.7849 45.701 35.7868 45.7059C35.794 45.7243 35.7905 45.7552 35.7915 45.7567C35.7949 45.7604 35.856 45.7078 35.8648 45.7538C35.8677 45.7686 35.7675 45.8028 35.7636 45.7951C35.7611 45.7902 35.7621 45.7044 35.7596 45.696C35.7583 45.6918 35.7179 45.724 35.7127 45.7161C35.7112 45.7138 35.71 45.7113 35.7092 45.7093C35.7153 45.7358 35.6787 45.7339 35.6799 45.704C35.6805 45.6922 35.7056 45.699 35.7065 45.7011C35.7069 45.702 35.7073 45.7032 35.7076 45.704C35.7024 45.6716 35.7875 45.6731 35.7691 45.625C35.7938 45.5986 35.7656 45.6956 35.7842 45.6699ZM35.9028 45.617C35.9002 45.626 35.8977 45.635 35.8951 45.6441C35.9383 45.622 35.9881 45.6654 36.0379 45.6651C36.0505 45.6651 36.036 45.6099 36.0526 45.625C36.0658 45.637 36.0805 45.6882 36.0733 45.6996C36.0715 45.7025 36.0445 45.6691 36.031 45.6726C35.9911 45.6827 36.0012 45.73 35.9989 45.7313C35.9963 45.7326 35.9712 45.6994 35.9575 45.7008C35.923 45.7047 35.9073 45.7337 35.8602 45.6958C35.8874 45.6646 35.8725 45.5968 35.9028 45.617ZM37.5127 45.7178C37.5143 45.688 37.5426 45.7144 37.5528 45.71C37.5512 45.7399 37.5229 45.7134 37.5127 45.7178ZM33.3008 45.6791C33.2921 45.728 33.3572 45.7401 33.3401 45.6994C33.3363 45.6904 33.309 45.6794 33.3008 45.6791ZM33.5931 45.7088C33.6018 45.6953 33.5668 45.6601 33.5668 45.6979C33.5669 45.7101 33.592 45.7106 33.5931 45.7088ZM36.4611 45.6651C36.4627 45.6635 36.4867 45.6744 36.4874 45.6769C36.5033 45.7288 36.4245 45.6988 36.4611 45.6651ZM33.9485 45.6486C33.9181 45.6807 34.0094 45.6946 33.9815 45.6537C33.9802 45.6517 33.9499 45.6471 33.9485 45.6486ZM34.0754 45.6397C34.0681 45.6414 34.0358 45.6255 34.0354 45.6404C34.0348 45.6645 34.0717 45.6809 34.0754 45.6397ZM37.0617 45.6496C37.0582 45.5945 37.1007 45.6362 37.1155 45.6293C37.1191 45.6844 37.0765 45.6427 37.0617 45.6496ZM36.7928 45.609C36.9724 45.5656 36.9328 45.6833 36.7822 45.6358C36.7819 45.6005 36.7815 45.6117 36.7928 45.609ZM37.0227 45.6155C37.0162 45.6508 36.9958 45.6404 36.9821 45.6375C36.9845 45.613 37.0128 45.6219 37.0227 45.6155ZM33.2233 45.6035C33.2346 45.5589 33.2845 45.6138 33.2756 45.6322C33.2735 45.6362 33.2192 45.628 33.2233 45.6035ZM36.4761 45.618C36.4719 45.5644 36.5258 45.5862 36.53 45.5981C36.5466 45.646 36.4805 45.6061 36.4761 45.618ZM37.3165 45.6025C37.326 45.5605 37.353 45.5821 37.3704 45.5827C37.3625 45.6185 37.3312 45.6032 37.3165 45.6025ZM37.1909 45.5696C37.192 45.568 37.2163 45.5718 37.2174 45.5737C37.2372 45.6147 37.1686 45.6042 37.1909 45.5696ZM31.9457 45.531C31.9465 45.5296 31.9649 45.5323 31.9655 45.5339C31.9819 45.5741 31.9268 45.5659 31.9457 45.531ZM33.5626 47.3996C33.5528 47.345 33.5425 47.1259 33.5289 47.0338C33.596 47.1311 33.5991 47.5953 33.5626 47.3996ZM27.873 39.6082C27.8936 39.6834 27.9147 39.7578 27.9362 39.8314C27.9201 39.6156 27.8846 39.3292 27.8831 39.1269C27.8828 39.0938 27.9268 39.1765 27.923 39.0985C27.9193 39.0197 27.8684 39.04 27.856 38.9286C27.8401 38.803 27.8541 38.2263 27.8537 38.0273C27.8515 37.8838 27.8499 37.7381 27.8495 37.59C27.8475 36.9883 27.8701 36.3823 27.9543 35.7873C27.9144 36.5582 28.0282 35.7884 28.0407 35.5749C28.0455 35.5278 27.936 35.5208 28.0831 34.7606C28.1856 34.2801 28.2316 34.7498 28.328 33.9366C28.1066 34.5325 28.2301 33.9271 28.3462 33.4444C28.3632 33.3607 28.554 32.6967 28.6444 32.4042C28.6739 32.3038 28.6745 32.136 28.7179 32.0031C28.7478 31.9117 28.7972 31.8521 28.8438 31.7169C29.0615 31.0883 29.3171 30.478 29.6318 29.8764C29.5707 30.2875 29.8203 29.6256 29.8449 29.6008C29.9496 29.4749 29.6239 30.1245 29.7752 29.8793C29.954 29.5207 30.149 29.1667 30.3616 28.8196C30.17 29.0951 30.5056 28.3843 30.6294 28.2909C30.4714 28.2598 31.8648 26.8498 32.0906 26.6422C32.1348 26.5953 31.7788 26.8312 32.5157 26.1966C32.5974 26.1297 32.5898 26.1822 32.6297 26.1438C32.653 26.1214 32.7371 25.9057 32.9466 25.821C33.0271 25.7961 32.6529 26.1364 33.5392 25.4756C33.088 25.6084 34.8401 24.6103 35.2244 24.5567C35.1498 24.5699 35.0754 24.5841 35.0011 24.5991C35.3559 24.4956 35.4076 24.4424 35.4854 24.4155C35.8027 24.3091 36.2531 24.2208 36.5554 24.152C36.9067 24.0738 36.8955 24.0028 37.3185 23.9687C37.2189 23.9666 37.1149 23.9667 37.0133 23.9681C37.3072 23.9228 37.5893 23.893 37.8831 23.8749C37.2185 24.0264 38.0307 23.8635 38.0796 23.8649C38.164 23.8573 38.0444 23.9008 38.1855 23.8896C38.2003 23.8887 38.1768 23.8521 38.397 23.8426C38.4828 23.8393 38.5505 23.8392 38.6048 23.8407C38.8615 23.8493 38.8393 23.88 39.0077 23.8873C39.0275 23.8897 38.9586 23.8468 39.3287 23.8721C40.5121 24.0141 39.3134 23.8824 39.2754 23.8961C39.2198 23.9051 39.5904 24.0375 38.6333 23.958C38.9578 23.9766 38.9839 24.0433 39.0198 24.0456C39.0522 24.0429 39.6129 24.0923 39.648 24.1017C39.9305 24.1273 39.6915 24.0469 39.7471 24.0487C39.7921 24.0411 40.4708 24.2472 40.6702 24.1966C40.9629 24.4195 40.4494 24.205 39.8911 24.1196C39.8073 24.1215 40.4045 24.2795 40.4374 24.2973C41.208 24.5481 40.8134 24.3267 41.0044 24.3304C41.1053 24.3349 41.3974 24.5325 41.1372 24.3295C41.8448 24.6415 41.3954 24.4921 41.4393 24.5174C41.5013 24.5574 41.751 24.6649 41.7778 24.6856C41.818 24.7142 41.656 24.6537 41.8183 24.7595C41.8441 24.7761 42.1406 24.8975 41.8039 24.6683C42.2661 24.9545 42.2446 24.9095 42.3445 25.0828C42.7376 25.1814 42.4959 25.3222 42.5987 25.4187C42.8644 25.6845 42.8661 25.5233 42.886 25.5313C43.0336 25.5869 43.6797 26.3996 43.8111 26.6004C43.6906 26.5686 43.3328 25.9597 43.1989 25.8551C42.7999 25.4998 43.6544 26.4486 43.3139 26.2316C43.4375 26.3332 43.5579 26.4401 43.6734 26.5494C43.7703 26.8272 43.5382 26.5063 43.952 27.1301C44.0726 27.2025 43.666 26.6835 43.776 26.7689C43.8467 26.8165 44.0759 27.1894 44.0905 27.1898C44.1133 27.1877 43.8926 26.8585 43.9479 26.8974C44.0999 26.979 44.6686 28.2746 44.1595 27.328C44.3008 27.5943 44.2529 27.7837 44.3876 27.9986C44.4681 28.1422 44.2905 27.2164 44.7628 28.5163C44.7218 28.5629 44.5551 28.0082 44.5403 27.996C44.5264 27.9792 44.446 28.1261 44.4464 28.1448C44.4749 28.209 44.9571 29.4862 44.9278 29.7737C44.988 29.6501 45.1264 30.7448 45.1509 30.8573C45.1612 30.8878 45.192 30.7647 45.2012 30.7976C45.2606 31.0042 45.2322 31.5764 45.2413 31.8346C45.2538 32.125 45.2901 32.0866 45.2912 32.1029C45.2934 32.2308 45.2628 32.1296 45.2654 32.2076C45.2672 32.2614 45.2714 32.4605 45.2705 32.6632C45.27 32.9039 45.2622 33.1484 45.2645 33.1702C45.2659 33.1821 45.3157 33.0528 45.3188 33.2275C45.3178 33.2574 45.2707 33.2376 45.263 33.7535C45.2475 34.374 45.3584 33.3273 45.3973 33.5876C45.2926 33.9831 45.37 33.9741 45.3554 34.0827C45.35 34.1206 45.2587 34.392 45.2269 34.6911C45.2416 34.4747 45.2524 34.2594 45.2594 34.0415C45.2311 34.254 45.2015 34.6646 45.1648 34.8362C45.1473 34.9196 45.1015 34.8433 45.0782 35.0255C45.0727 35.0636 45.1892 35.2379 45.1906 34.7491C45.2437 34.7165 45.1837 34.942 45.1822 35.0492C45.1821 35.0655 45.2539 35.1399 45.1837 35.2679C45.164 35.2973 44.9939 34.9146 45.0099 35.8398C45.0102 35.8697 45.0574 35.7744 45.0584 35.8037C45.0593 35.824 45.0051 36.0506 45.0041 36.0764C45.0036 36.103 45.0565 35.9988 45.0568 36.0307C45.0589 36.195 44.8921 36.3751 44.9651 36.0541C44.9287 36.1593 44.8917 36.2638 44.8539 36.3676C44.9725 36.2722 44.8459 36.5422 44.8155 36.6898C44.6156 37.6346 44.8229 37.0197 44.8168 37.1891C44.8034 37.4609 44.6931 37.2239 44.643 37.6175C44.637 37.6531 44.8309 37.214 44.5494 38.0979C44.5835 37.9659 44.6168 37.8333 44.6493 37.7001C44.5393 37.7529 44.5259 38.1776 44.5178 38.2085C44.4299 38.5594 44.4672 38.3165 44.3596 38.8418C44.3499 38.8887 44.2975 38.9809 44.2782 39.0811C44.1985 39.4971 44.4702 38.5589 44.5118 38.5413C44.536 38.5371 44.22 39.5408 44.1982 39.5691C44.1145 39.7022 44.3265 39.1128 44.2436 39.2117C44.2181 39.2531 43.7846 40.6647 43.6678 40.9276C43.536 41.2375 43.3662 41.3357 43.4999 41.3854C43.3365 41.4274 43.3988 41.5374 43.3837 41.5772C43.1997 42.0559 43.1977 42.056 43.0648 42.4702C43.0355 42.5616 42.9686 42.6235 42.9641 42.6578C42.9616 42.6777 43.0167 42.6583 42.9978 42.7537C42.9702 42.887 42.6652 43.6231 42.6239 43.67C42.581 43.7178 42.7219 43.3499 42.66 43.4032C42.5631 43.672 42.4859 43.9327 42.3936 44.2009C42.3552 44.3121 42.3465 44.2457 42.3302 44.2939C42.3226 44.3145 42.2243 44.7077 42.2402 44.6943C42.2705 44.6651 42.6507 43.4655 42.5945 43.7961C42.5832 43.86 42.4485 44.0535 42.5368 44.0449C42.1656 45.105 41.8423 46.148 41.6203 47.1831C41.6774 46.5737 41.9009 45.908 42.0815 45.2725C42.1057 45.1855 42.2024 44.8927 42.1525 44.9167C41.9755 45.4562 41.814 46.1302 41.6728 46.6376C41.6682 46.6539 41.6461 46.5853 41.6264 46.6457C41.5884 46.7592 41.5685 47.1459 41.5423 47.2054C41.5364 47.2157 41.5315 46.9929 41.4883 47.0516C41.3772 47.2034 41.5412 47.2793 41.5132 47.421C41.4872 47.53 41.2911 48.2584 41.3294 48.4481C41.3621 48.6492 41.4286 47.9095 41.4709 47.9706C41.4448 48.4749 41.3498 48.9685 41.3399 49.4348C41.3398 49.4429 41.3787 49.3736 41.3804 49.4768C41.3842 49.6562 41.3325 49.7027 41.3236 49.7906C41.3222 49.8045 41.3212 49.8235 41.3205 49.8461C41.3162 49.996 41.3193 50.2811 41.3031 50.3248C41.3007 50.3313 41.2492 50.2538 41.2478 50.242C41.2266 50.0753 41.2933 50.0161 41.2942 50.001C41.2966 49.9476 41.2744 49.8952 41.2727 49.8461C41.2726 49.8431 41.2726 49.8402 41.2727 49.8372C41.2754 49.7619 41.2992 49.7207 41.3031 49.6217C41.306 49.5535 41.2592 49.6185 41.2628 49.5525C41.2636 49.5277 41.3769 49.2719 41.2731 49.242C41.262 49.2392 41.2335 49.4972 41.2229 49.8461C41.2031 50.5826 41.191 51.6686 41.2084 51.8268C41.2211 51.6183 41.2339 51.4097 41.2466 51.2011C41.2156 51.6247 41.3002 52.1335 41.1751 52.1695C41.1723 52.596 41.1695 53.0225 41.1667 53.449C41.1702 55.0477 40.4217 56.6322 39.2005 57.6479C38.8894 57.8828 39.0197 57.7032 38.5051 58.0719C38.6578 58.0071 38.8084 57.9349 38.9563 57.8554C38.7083 58.0864 37.3798 58.6874 37.1416 58.7205C37.1124 58.7288 37.0942 58.8201 36.7338 58.903C36.413 58.9696 36.353 58.9167 36.1803 58.9256C36.0362 58.9317 35.8739 58.9534 35.8314 58.9516C35.7984 58.9503 35.7845 58.9177 35.7058 58.9131C35.6766 58.9113 35.6536 58.9108 35.6354 58.9113C35.4986 58.9134 35.6271 58.9788 35.4134 58.8771C35.473 58.8754 35.5327 58.8727 35.5923 58.8691C35.2945 58.8527 34.8994 58.7615 35.3322 58.7721C35.4066 58.7718 35.3413 58.8008 35.3966 58.8034C35.4818 58.8069 35.5613 58.8081 35.6354 58.8077C37.0391 58.7016 36.3452 58.7424 35.6354 58.7718C35.436 58.7742 35.2346 58.7672 35.0752 58.7608C34.881 58.7241 33.8173 58.4798 33.7931 58.4331C33.7512 58.4027 33.9368 58.4323 33.7227 58.3154C33.7001 58.3043 33.353 58.1681 33.0929 58.0167C32.8317 57.8676 32.6505 57.728 32.8822 57.8419C32.9726 57.8967 33.5717 58.223 33.7314 58.2705C33.4039 58.058 32.57 57.7041 32.4941 57.6216C32.1754 57.3644 33.1779 58.015 32.4476 57.4596C31.9173 56.9975 32.3744 57.4797 32.1499 57.3221C32.0094 57.2409 31.5327 56.5877 31.4801 56.656C31.3034 56.4384 31.4436 56.539 31.4257 56.5093C31.4039 56.4847 31.079 56.0416 31.0213 55.8697C31.0135 55.8496 31.0894 55.8858 31.0826 55.8643C31.0627 55.8264 30.8367 55.3557 30.8308 55.3349C30.8228 55.3234 30.8291 55.4561 30.7999 55.4123C30.7595 55.3632 30.6068 54.8762 30.5931 54.8508C30.5563 54.82 30.7699 55.4146 30.6928 55.3317C30.5946 55.0553 30.4438 54.601 30.3742 54.4135C30.3921 54.4589 30.4543 54.7394 30.4786 54.8363C30.3882 54.8123 30.2696 54.1968 30.366 54.3967C30.313 54.2691 30.3124 54.3626 30.2717 54.2915C30.2605 54.2728 30.2331 54.0815 30.2175 54.0452C30.2137 54.0406 30.2122 54.2434 30.1928 54.2056C30.1481 54.1371 30.113 53.5425 30.1275 53.494C30.1438 53.3581 30.1789 53.8386 30.2176 53.8753C30.2192 53.8794 30.2616 53.4743 30.2704 53.4689C30.3227 53.4457 30.3003 53.8893 30.3508 53.8354C30.3536 53.7253 30.3598 53.6172 30.3693 53.5086C30.409 53.9249 30.5252 54.6893 30.6476 54.8609C30.4552 54.2757 30.4387 53.6231 30.5716 53.6252C30.6255 53.6243 30.6732 53.8756 30.6878 53.8641C30.7318 53.8233 30.6634 53.4788 30.6689 53.4645C30.672 53.4538 30.675 53.449 30.6779 53.449C30.6779 53.449 30.6779 53.449 30.6779 53.449C30.7017 53.4505 30.747 53.9424 30.7691 53.9643C30.7963 54.0017 30.8747 53.7783 30.8977 53.778C30.8997 53.7859 30.9592 54.1202 30.9846 54.0021C31.0065 53.8837 30.9918 53.5942 30.9973 53.5839C31.0135 53.5287 31.0691 54.0311 31.0912 54.0432C31.0972 54.0497 31.1118 53.7784 31.1253 53.7704C31.1362 53.7632 31.1798 53.962 31.2295 54.0344C31.2651 54.0882 31.2657 53.9178 31.274 53.9469C31.2736 53.9686 31.3498 54.4168 31.3655 54.4366C31.3801 54.4673 31.3899 54.3563 31.4018 54.3697C31.4177 54.3885 31.4398 54.532 31.4478 54.5106C31.4441 54.4929 31.4617 53.9281 31.502 53.9309C31.551 53.9324 31.5197 54.506 31.6481 53.9587C31.6485 53.9552 31.6198 53.8318 31.6213 53.8283C31.6538 53.7495 31.7464 54.1359 31.6973 53.657C31.8573 54.5357 31.7825 53.7587 31.8869 53.8808C31.9231 53.927 31.9938 54.2465 32.0024 54.2464C32.0382 54.206 31.985 54.1117 32.0006 54.0728C32.0071 54.0533 32.1108 54.3251 32.1273 54.2546C32.1318 54.2194 32.0751 53.9256 32.0795 53.9125C32.0935 53.7916 32.1416 53.9315 32.1586 53.903C32.1688 53.8845 32.1527 53.7093 32.1559 53.7044C32.1588 53.6976 32.2373 53.9282 32.266 53.9716C32.2859 54.0055 32.2894 53.8662 32.2996 53.8907C32.3551 54.0371 32.3294 54.3708 32.4024 54.0398C32.4069 54.02 32.3856 53.906 32.3873 53.9024C32.416 53.8268 32.4498 54.0358 32.4903 54.0654C32.5559 54.1168 32.4729 53.8325 32.5553 54.0663C32.557 53.8797 32.5418 53.7823 32.5216 53.5692C32.5975 54.1617 32.7927 54.3047 32.6979 53.6983C32.7148 53.8955 32.7963 53.8606 32.8057 53.9172C32.8087 53.9519 32.7927 54.2409 32.9401 54.0764C32.9574 54.0567 32.8987 53.9037 32.9537 53.9449C33.0239 54.3225 32.9813 53.9466 32.9901 53.946C33.0432 53.9392 33.0864 54.1626 33.1702 54.3953C33.2497 54.6292 33.3765 54.8692 33.4269 54.9304C33.5417 55.0765 33.7125 55.1409 33.7377 55.1683C33.8239 55.2611 33.7212 55.2134 33.7291 55.2449C33.7353 55.2833 34.0611 55.4669 34.0743 55.4749C34.1189 55.5315 34.0319 55.5287 34.0359 55.535C34.0819 55.6242 34.5309 55.8447 34.6583 55.8939C34.6645 55.8642 34.4193 55.7483 34.5946 55.7713C34.7951 55.7915 34.7575 55.9247 34.7606 55.934C35.0404 56.0322 35.335 56.0819 35.6354 56.0814C36.2695 56.0823 36.8866 55.8487 37.362 55.4314C37.3128 55.394 36.856 55.7754 36.8284 55.7601C36.7792 55.7508 36.9807 55.6387 37.1796 55.4803C37.3817 55.3255 37.5716 55.1192 37.6199 55.0793C37.5478 55.1408 37.4728 55.1978 37.3957 55.25C37.4458 55.0847 37.7512 54.8914 37.8257 54.6681C37.8496 54.5992 37.7526 54.7028 37.7517 54.6984C37.7631 54.6133 37.8437 54.5122 37.8403 54.6187C37.89 54.4234 37.9197 54.4706 37.9798 54.3304C37.9823 54.3235 37.9277 54.3706 37.9537 54.255C37.97 54.2021 38.0424 53.9173 38.0139 53.8732C38.0041 53.8577 37.8414 53.9676 37.952 54.0113C37.8141 54.2929 37.9782 54.1226 37.9391 54.2387C37.9292 54.2554 37.8948 54.1972 37.7983 54.4872C37.7214 54.3867 37.9207 54.1019 37.9162 54.035C37.922 53.9162 37.7246 54.3616 37.7545 54.4791C37.6886 54.3996 37.73 54.5058 37.6709 54.6022C37.6053 54.7057 37.6085 54.645 37.5735 54.7004C37.4728 54.8476 37.5675 54.8277 37.4291 54.9084C37.6679 54.9091 37.2779 55.1293 37.1572 55.158C37.2908 55.0264 37.4076 54.8791 37.504 54.7215C37.4901 54.7247 37.4762 54.7278 37.4623 54.7308C37.4911 54.6923 37.5186 54.653 37.5448 54.6127C37.5487 54.6241 37.5525 54.6356 37.5562 54.6471C37.6332 54.4041 37.7069 54.3766 37.7185 54.3578C37.833 54.1207 37.9026 53.8213 37.9128 53.5518C37.9137 53.5252 37.8885 53.5274 37.8846 53.449C37.8823 53.3783 37.8859 53.2695 37.902 53.0956C37.917 52.9336 37.9639 53.0866 37.9569 52.9029C37.8295 52.6731 37.9311 52.6775 37.9313 52.6091C37.9313 52.4131 37.8997 52.2933 37.8994 52.2751C37.8944 52.0329 37.8997 51.6782 37.895 51.4121C37.8945 51.4071 37.8554 51.5456 37.867 51.3728C37.8711 51.3121 38.0382 50.7677 37.9837 50.2918C37.9724 50.4156 37.9612 50.5394 37.9499 50.6631C37.9603 50.5667 37.9454 50.0868 37.9211 49.8461C37.9089 49.7077 37.8953 49.6394 37.8792 49.7342C37.8742 49.7648 37.8734 49.8032 37.8751 49.8461C37.883 50.0218 37.9408 50.2804 37.8556 50.3141C37.8631 50.2322 37.8661 50.0609 37.8666 49.8461C37.8549 49.0818 37.964 47.8534 38.0047 47.7364C38.0109 47.7147 38.0268 47.8553 38.035 47.8252C38.0398 47.8012 38.0973 47.3318 38.1213 47.2722C38.1345 47.2366 38.1233 47.4458 38.138 47.4307C38.1466 47.4163 38.2561 46.8407 38.2228 46.8012C38.2126 46.9448 38.1333 47.3426 38.1324 47.127C38.1324 47.0991 38.1829 46.964 38.1832 46.9305C38.1842 46.6173 38.0416 47.5291 38.0281 47.6736C38.049 47.085 38.2778 46.2168 38.4014 45.5709C38.4976 45.3205 38.3622 45.9672 38.46 45.6809C38.6658 45.0908 38.452 45.5081 38.452 45.4884C38.4535 45.3276 38.7705 44.8705 38.6322 44.8333C38.7126 44.6236 38.7101 44.6976 38.7785 44.3908C38.7574 44.4276 38.7364 44.4646 38.7155 44.5016C38.7294 44.1399 39.149 43.5052 39.1483 43.5636C39.1447 43.7155 38.9694 44.0583 38.9619 44.0906C38.9508 44.1385 39.0502 44.3035 38.7816 44.7792C38.8162 45.0128 39.0758 43.9917 39.0073 44.4703C39.0812 44.1514 39.5475 42.924 39.5696 42.7374C39.5715 42.7145 39.4452 42.7812 39.5958 42.4938C39.6674 42.3576 39.55 42.705 39.5936 42.6463C39.7222 42.4508 40.6482 39.7477 40.8051 39.2568C40.816 39.2243 40.8407 39.246 40.8513 39.2139C40.8842 39.1154 40.9608 38.7442 41.0305 38.574C40.8589 38.9185 41.0846 38.2145 41.1437 38.0387C41.236 37.7713 41.2813 37.8034 41.3272 37.6898C41.506 37.2503 41.5667 36.5243 41.7602 36.2036C41.6426 36.1966 41.9522 35.6136 42.0022 35.3282C42.0443 35.1055 42.0177 34.7729 41.9224 35.0631C41.9921 34.6831 42.0227 34.2795 42.0484 33.9246C42.0526 33.8658 42.0799 33.9499 42.0858 33.8492C42.086 33.84 42.0533 33.8245 42.0568 33.7381C42.0755 33.0287 42.122 33.3767 42.1516 33.2448C42.1668 33.1703 42.1746 33.1162 42.1778 33.076C42.1733 33.4908 42.142 33.9724 42.1285 34.101C42.2206 33.9987 42.1901 33.1751 42.2082 32.9414C42.2091 32.9332 42.25 32.9628 42.2504 32.9545C42.2505 32.9543 42.2505 32.9541 42.2505 32.9539C42.2527 32.9154 42.2531 32.7872 42.2462 32.6632C42.2374 32.5021 42.2161 32.3495 42.1895 32.4158C42.1822 32.4339 42.1812 32.528 42.1807 32.6632C42.1804 32.763 42.1802 32.8847 42.1786 33.0147C42.1715 32.931 42.1234 32.9922 42.1218 32.9774C42.1141 32.9039 42.1183 32.7869 42.1245 32.6632C42.1336 32.4889 42.1456 32.3016 42.1457 32.2114C42.1457 32.1764 42.116 32.1801 42.1157 32.1744C42.1162 32.0355 42.2041 32.0874 42.1084 31.9502C42.2007 31.692 42.1478 32.4211 42.2107 32.3685C42.2904 32.3219 42.1021 30.7191 41.9929 30.7526C42.0007 30.7457 42.0079 30.7227 42.0121 30.6768C42.0242 30.5736 41.9198 30.1544 41.8833 30.0885C41.8772 30.0773 41.8001 30.1029 41.7955 30.0885C41.7877 30.0517 41.6993 29.5418 41.5824 29.3904C41.6082 29.4877 41.6313 29.5852 41.6528 29.6849C41.4475 29.1152 41.4479 29.225 41.5016 29.4121C41.505 29.4214 41.5056 29.4314 41.5087 29.4404C41.548 29.5894 41.5936 29.7852 41.5881 29.7899C41.583 29.7911 41.1926 28.8943 41.3297 29.0382C41.3538 29.0537 41.5022 29.4887 41.4631 29.2584C41.4575 29.2157 41.3201 28.9588 41.3173 28.9447C41.3106 28.8286 41.6261 29.3959 41.6427 29.3072C41.5335 29.1769 41.4753 28.9801 41.3802 28.8302C41.3368 28.7616 41.2916 28.7651 41.2862 28.7568C41.2056 28.6365 41.2825 28.6858 41.2573 28.6445C41.244 28.6186 41.0174 28.4375 41.1491 28.4114C40.5257 27.7714 40.9515 28.2316 41.2427 28.7212C41.1156 28.5837 40.9406 28.2961 40.8365 28.1951C40.7998 28.1581 40.7882 28.2077 40.7251 28.1495C40.6103 28.0023 40.0087 27.5042 39.7992 27.4442C39.9221 27.4797 39.907 27.4234 39.8127 27.3882C39.7174 27.3546 39.7749 27.4418 39.7542 27.4408C39.7385 27.4314 39.2877 27.2744 39.197 27.2784C39.5649 27.329 39.5002 27.2654 39.1802 27.2029C39.2293 27.1972 39.2774 27.1924 39.3261 27.1888C39.1468 27.1647 38.7478 27.07 38.6048 27.0899C38.6002 27.0904 38.596 27.0909 38.592 27.0915C38.5827 27.093 38.5923 27.1012 38.6048 27.11C38.6194 27.1213 38.6382 27.1338 38.6322 27.1348C38.6244 27.136 38.6152 27.1368 38.6048 27.1375C38.4595 27.143 38.1266 27.1285 38.1093 27.1436C38.0956 27.1551 38.2615 27.1763 38.2017 27.1959C38.1911 27.1997 38.0247 27.1585 37.8714 27.1893C37.8147 27.2006 37.8534 27.2323 37.8393 27.2361C37.7227 27.2688 37.7856 27.197 37.5672 27.2413C37.4083 27.2759 37.3048 27.3558 37.0865 27.3908C37.8088 27.308 37.2027 27.396 36.9259 27.5043C36.8813 27.5225 36.9371 27.5685 36.6599 27.6289C37.2003 27.3293 36.4718 27.6167 36.3269 27.6887C36.3187 27.6918 36.299 27.6528 36.2262 27.6838C36.2201 27.6866 36.2405 27.7091 36.1746 27.7412C35.5579 28.0663 35.9437 27.842 35.8112 27.8758C35.7535 27.89 35.4783 28.0991 35.4028 28.1526C35.385 28.1644 35.3765 28.1333 35.3082 28.1804C35.1873 28.2642 35.0999 28.3684 35.0243 28.4292C35.0157 28.4366 34.9852 28.397 34.8495 28.5258C34.8115 28.5622 34.7775 28.6127 34.8432 28.5762C35.0583 28.4533 35.3888 28.1232 35.6486 28.0278C35.8789 27.9351 35.221 28.3433 35.1937 28.3785C35.1814 28.3874 35.2923 28.2789 35.163 28.3658C35.0518 28.4407 34.9108 28.655 34.7498 28.7726C34.7375 28.7808 34.5708 28.8364 34.5735 28.8289C34.5759 28.8212 34.7525 28.6456 34.7125 28.6543C34.7075 28.655 34.5887 28.7601 34.5633 28.7634C34.5323 28.7665 34.3589 28.6813 34.3299 28.7025C34.2568 28.7562 34.3277 28.7457 34.2837 28.7838C34.1879 28.8625 33.8484 29.1455 33.8868 29.2001C33.9379 29.1486 33.9895 29.098 34.0415 29.0484C33.7741 29.3472 33.9111 29.2408 33.8814 29.2903C33.8506 29.3449 33.8204 29.2949 33.7284 29.3955C33.7051 29.4138 33.3611 29.8736 33.3889 29.8816C33.5496 29.6047 33.5338 29.7415 33.5432 29.7301C33.5802 29.6893 33.5939 29.6101 33.6413 29.5527C33.9778 29.1567 33.6887 29.5972 33.7791 29.5129C33.8097 29.484 33.8388 29.3997 33.8517 29.3874C33.8934 29.3473 33.9261 29.3746 33.9488 29.3436C34.002 29.2714 33.8877 29.3096 33.89 29.3024C33.9146 29.2151 34.1626 29.0187 34.0781 29.2053C34.1742 29.1367 34.1259 29.0723 34.213 29.0284C34.3859 28.9431 34.1824 29.1251 34.1406 29.1868C33.9888 29.4076 33.9125 29.4434 33.6829 29.7484C33.6012 29.8582 33.5356 30.0127 33.5002 30.066C33.477 30.0969 33.149 30.3397 33.3203 30.4656C33.2226 30.5772 32.9812 30.7052 32.9082 30.8452C32.8435 30.9695 32.9307 30.9677 32.9267 30.9804C32.9206 30.9997 32.8337 31.1446 32.8162 31.2004C32.7956 31.2655 32.8361 31.2494 32.7974 31.3485C32.7026 31.596 32.6394 31.5579 32.6225 31.5801C32.433 31.8429 32.5918 31.7633 32.5696 31.8306C32.5426 31.8882 32.1497 32.7282 32.1183 32.9275C32.1305 32.8471 32.1434 32.7668 32.1571 32.6867C32.0624 32.8043 32.0851 32.9741 32.004 32.9486C32.1234 33.0209 31.9427 33.2711 31.9199 33.3584C31.9108 33.3924 31.9339 33.3967 31.9219 33.439C31.8738 33.6034 31.7518 33.9726 31.7409 34.0665C31.6877 34.4681 32.0338 33.4966 32.0707 33.4267C32.0139 33.5774 31.812 34.4664 31.9821 34.0784C32.0082 34.0188 31.9791 33.8926 31.9866 33.8569C32.0385 33.6165 32.0386 33.8173 32.0489 33.8001C32.0657 33.7711 32.0599 33.6016 32.0786 33.5627C32.0849 33.5499 32.1052 33.651 32.1753 33.4294C32.1832 33.551 31.9689 34.1696 31.9625 34.2576C31.9604 34.289 32.1011 34.1246 31.8776 34.6487C31.8884 34.6444 31.8992 34.6401 31.9099 34.6358C31.846 34.9414 31.7917 35.2493 31.7471 35.5592C31.7305 35.5224 31.7147 35.341 31.689 35.5618C31.6749 35.6889 31.7379 35.6029 31.7375 35.6147C31.7268 35.7004 31.5671 36.9059 31.5725 37.6329C31.5693 37.8644 31.5722 38.0359 31.5753 38.131C31.5784 38.2659 31.6343 38.6323 31.6377 38.66C31.6474 38.8254 31.6763 39.4212 31.6992 39.5351C31.7118 39.6086 31.7439 39.5334 31.7503 39.5993C31.7562 39.6604 31.7087 39.6024 31.7094 39.6207C31.7021 39.7728 31.956 40.8925 31.9979 41.1739C31.9623 41.0054 31.7221 40.2003 31.7021 40.2191C31.6987 40.2236 31.705 40.4305 31.7276 40.4685C31.7065 40.5438 31.8564 40.7577 31.8651 40.8901C31.8662 40.905 31.7951 40.8609 31.8373 41.0923C31.8522 41.1728 31.9457 41.3676 31.952 41.5928C32.0381 41.8744 32.4852 43.579 32.5881 43.7028C32.5924 43.7051 32.5374 43.45 32.6134 43.6105C32.7145 43.8253 32.5424 43.6563 32.6119 43.9229C32.6234 43.9591 32.8503 44.7109 32.8622 44.7383C32.9885 44.9552 32.8306 44.2747 32.8391 44.2845C32.8649 44.2999 33.0295 44.8571 33.0299 44.8834C33.0311 44.9064 32.827 44.4661 33.0031 45.0135C32.9968 44.9468 32.9904 44.8806 32.9837 44.8145C33.0712 45.0706 33.0187 45.1124 33.0311 45.1772C33.068 45.3784 33.2085 45.5786 33.1646 45.9316C33.1524 46.0238 33.0918 45.887 33.0894 45.8984C33.0709 46.0094 33.2018 46.1228 33.151 46.2966C33.1461 46.3091 33.0394 45.9499 33.1449 46.5928C33.1456 46.5469 33.1461 46.5012 33.1465 46.4556C33.1822 46.5433 33.2801 47.2022 33.2811 47.2922C33.2947 47.5552 33.2193 47.3342 33.2483 47.5931C33.3131 47.4177 33.3751 48.2182 33.3036 48.175C33.3521 48.2385 33.3608 48.4765 33.3515 48.7375C33.3446 48.9136 33.3321 49.0972 33.3313 49.2202C33.3301 49.3981 33.3656 49.7608 33.3615 49.8173C33.3564 49.8861 33.3009 49.8652 33.2885 49.9895C33.285 50.0249 33.3257 50.3949 33.2682 50.7197C33.2571 50.7826 33.1629 50.9148 33.1394 50.7978C33.0991 50.5976 33.175 50.2188 33.1193 50.2236C33.0598 50.2293 33.0952 50.7395 33.0874 50.8768C33.0515 51.5108 32.9882 51.1447 32.969 51.161C32.9225 51.2033 32.9239 51.5497 32.9197 51.5642C32.9011 51.6241 32.8643 51.3786 32.8359 51.3749C32.7989 51.3704 32.7321 51.7043 32.7196 51.6284C32.7019 51.5198 32.7576 51.2129 32.7549 51.1934C32.719 50.9402 32.6335 51.2873 32.5915 51.383C32.5786 51.412 32.5574 51.2964 32.5536 51.3205C32.4961 51.6876 32.6737 51.3979 32.6619 51.642C32.6513 51.8599 32.5951 51.5796 32.592 51.5879C32.5886 51.5987 32.5856 51.8591 32.5657 51.8999C32.5557 51.92 32.4465 51.243 32.3975 51.2713C32.4083 51.4873 32.4191 51.7033 32.4299 51.9193C32.366 51.9362 32.413 51.6255 32.4064 51.5934C32.3932 51.5287 32.3609 51.7091 32.3407 51.7013C32.3279 51.6972 32.282 51.4855 32.2631 51.6768C32.2566 51.7425 32.3014 51.8804 32.2556 52.1198C32.1972 51.2867 32.1613 51.864 32.1387 51.8886C32.1161 51.9127 32.0628 51.5149 32.0722 51.9977C31.9479 52.0186 32.0329 51.9873 32.0111 51.8501C31.9842 51.682 31.9433 52.0705 31.9744 51.4562C31.9162 51.4912 31.9203 51.9849 31.9156 52.011C31.9114 52.0336 31.8828 51.9238 31.8731 51.963C31.7606 52.4258 31.812 52.1079 31.7402 52.242C31.7338 52.2539 31.7071 52.6914 31.6967 52.3583C31.6777 51.7516 31.7601 51.498 31.5838 51.396C31.5072 51.8448 31.621 52.3886 31.623 52.525C31.6258 52.7338 31.5898 52.5175 31.5797 52.5432C31.5765 52.5522 31.5794 52.7321 31.5766 52.7345C31.4421 52.8629 31.5743 51.9335 31.551 51.6409C31.5308 51.7193 31.5107 51.7977 31.4905 51.8762C31.4897 51.7697 31.4889 51.6633 31.4881 51.5569C31.4477 52.0639 31.4728 51.5748 31.3639 51.4484C31.3395 51.42 31.3814 51.7531 31.3134 51.3732C31.2977 51.6534 31.2755 51.564 31.3062 51.8177C31.2625 51.8111 31.2133 51.2403 31.1909 51.0152C31.1418 51.8106 31.3019 51.357 31.2172 52.0446C31.2713 52.1721 31.2608 51.8439 31.2697 51.8707C31.3017 51.9667 31.2508 52.1918 31.3632 52.4634C31.3816 52.5076 31.4384 52.3205 31.4357 52.5974C31.4353 52.628 31.3868 52.8044 31.3833 52.802C31.3452 52.7786 31.3595 52.604 31.3436 52.5968C31.3286 52.59 31.3376 52.7848 31.3335 52.7855C31.2859 52.7915 31.3153 52.623 31.3004 52.6474C31.2679 52.7003 31.1655 53.4009 31.1955 52.4865C31.2493 53.246 31.2481 52.5838 31.2274 52.288C31.2222 52.2126 31.1938 52.1935 31.1839 52.086C31.1711 51.9477 31.1848 51.7859 31.1795 51.7144C31.1738 51.6374 31.1065 52.0746 31.1266 51.4423C31.0597 51.7641 31.131 52.3325 31.0841 52.6486C30.9892 53.2863 30.9688 52.2039 30.9596 52.0912C30.9571 52.0611 30.9187 52.1619 30.9164 52.1418C30.9128 52.1091 30.9305 51.4948 30.8987 51.4342C30.867 51.3738 30.9002 51.6592 30.8671 51.6782C30.8448 51.6911 30.8052 50.95 30.79 51.3512C30.7795 51.6277 30.8692 52.1373 30.7728 52.2232C30.7648 51.8165 30.7569 51.4099 30.7489 51.0033C30.7122 51.2258 30.6756 51.4484 30.6389 51.671C30.6273 51.2146 30.6687 50.82 30.6162 50.3866C30.4988 51.4282 30.5225 50.0484 30.5082 50.0332C30.4997 50.0281 30.4043 50.4381 30.3869 50.5041C30.3502 50.1408 30.3323 49.0369 30.2146 49.6827C30.2412 49.5655 30.1756 49.2816 30.1706 49.2853C30.1186 49.3214 30.1523 49.9406 30.1054 49.8396C30.0509 49.7225 30.1248 49.5586 30.1189 49.3785C30.108 49.0531 30.0673 48.8738 30.021 48.7375C29.9333 48.5162 29.8358 48.4315 29.8287 47.9199C29.8203 47.9363 29.8118 47.9527 29.8033 47.9691C29.7585 47.1134 29.6014 46.272 29.3588 45.3635C29.1848 45.0393 28.8296 44.0761 28.6826 43.5514C28.6526 43.4488 28.545 42.9186 28.5423 42.876C28.5357 42.7995 28.6541 43.1982 28.6292 43.0097C28.6212 42.9755 28.4017 42.0689 28.3761 42.1426C28.3952 42.2464 28.5002 42.5593 28.5037 42.6123C28.4944 43.0207 27.9255 40.1333 27.9356 39.9692C27.9286 40.0374 27.922 40.1054 27.9157 40.173C27.8982 39.9829 27.8844 39.7983 27.873 39.6082ZM33.3384 46.6389C33.4016 46.7436 33.4055 47.0389 33.4357 47.2051C33.4809 47.4388 33.6874 47.8275 33.4957 47.6674C33.4561 47.3242 33.4028 46.9758 33.3384 46.6389ZM32.2309 42.1148C32.2603 42.3054 32.1221 42.1909 32.1193 42.0283C32.1193 42.0108 32.1924 41.8575 32.2309 42.1148ZM32.7974 44.1583C32.7937 44.1497 32.7443 43.9721 32.7439 43.9658C32.736 43.7957 32.8847 44.332 32.7974 44.1583ZM31.7681 34.9367C31.7341 35.1334 31.8508 35.0089 31.8386 34.8806C31.8379 34.8724 31.7705 34.9237 31.7681 34.9367ZM31.7386 35.0756C31.6286 35.2136 31.7406 35.5492 31.7656 35.3024C31.7677 35.2787 31.7436 35.0695 31.7386 35.0756ZM32.3906 42.7903C32.3541 42.778 32.3092 42.5784 32.2921 42.4947C32.3199 42.4884 32.362 42.7089 32.3906 42.7903ZM31.535 38.0963C31.5071 38.0908 31.5334 38.7373 31.5721 38.776C31.5488 38.6781 31.5548 38.1052 31.535 38.0963ZM31.5633 36.4381C31.557 36.4541 31.5443 36.6772 31.5668 36.6723C31.6034 36.5666 31.5895 36.3664 31.5633 36.4381ZM32.2404 33.2186C32.2396 33.2057 32.0533 33.3185 32.2683 32.975C32.2999 32.9249 32.2659 33.1316 32.2776 33.1138C32.3006 33.0764 32.316 33.0459 32.3258 33.0205C32.2759 33.1963 32.2232 33.3788 32.2096 33.3939C32.1454 33.4642 32.2403 33.224 32.2404 33.2186ZM32.7906 31.6017C32.7864 31.5578 32.9049 31.3521 32.9389 31.3093C32.9448 31.3021 32.9781 31.3651 33.0243 31.2696C33.0617 31.1932 32.9472 31.2757 33.0357 31.1349C33.1257 30.9937 33.0546 31.2096 33.0647 31.1984C33.077 31.1827 33.1803 30.9459 33.2074 30.9709C33.2263 30.9887 33.0757 31.2184 33.0487 31.2823C33.0137 31.3629 33.1018 31.2897 33.0252 31.4144C32.9777 31.4928 32.9332 31.4126 32.9208 31.4281C32.9096 31.4405 32.8048 31.7506 32.791 31.6013C32.7909 31.6015 32.7907 31.6016 32.7906 31.6017ZM32.3391 32.9727C32.3369 32.9866 32.3328 33.0022 32.3258 33.0205C32.3303 33.0045 32.3347 32.9885 32.3391 32.9727ZM33.1929 45.9885C33.1936 45.8669 33.2907 46.2094 33.2814 46.3475C33.2582 46.3545 33.1937 46.0066 33.1929 45.9885ZM32.3383 32.7921C32.4522 32.5452 32.4043 32.7403 32.3391 32.9727C32.3513 32.8959 32.3007 32.8756 32.3383 32.7921ZM31.7276 40.4685C31.7311 40.4561 31.7385 40.4473 31.7527 40.4437C31.7426 40.4763 31.7347 40.4806 31.7276 40.4685ZM31.6485 39.8355C31.5737 39.6269 31.6386 40.0653 31.6711 40.0574C31.6825 40.0548 31.651 39.8432 31.6485 39.8355ZM31.8246 34.6874C31.8163 34.7064 31.7505 34.371 31.754 34.8375C31.8194 34.6034 31.7809 34.8568 31.7935 34.8554C31.8274 34.8524 31.8825 34.4487 31.9194 34.3651C31.8766 34.2822 31.8516 34.6256 31.8247 34.6869C31.8247 34.6871 31.8246 34.6872 31.8246 34.6874ZM34.494 29.213C34.4837 29.2732 34.3662 29.3778 34.2924 29.4561C34.3 29.3947 34.4168 29.2868 34.494 29.213ZM37.8556 51.2049C37.8228 50.2985 37.9674 50.181 37.9102 51.0104C37.909 51.0267 37.8703 51.2599 37.8556 51.2049ZM39.1777 43.0344C39.2652 42.9703 39.1832 43.2508 39.0998 43.4268C39.0809 43.4666 38.9709 43.6018 39.0152 43.4216C39.0861 43.4501 39.201 43.1883 39.1777 43.0344ZM32.3547 32.6342C32.3434 32.5449 32.462 32.3285 32.5182 32.2142C32.5191 32.2989 32.4071 32.5322 32.3547 32.6342ZM38.0346 48.0431C38.0511 47.9389 38.0057 47.8612 37.9989 47.8788C37.9679 47.9579 37.9902 48.1594 38.0346 48.0431ZM32.0875 33.3784C32.0593 33.3814 32.1384 33.0635 32.2053 33.063C32.1779 33.1267 32.1045 33.3752 32.0875 33.3784ZM34.3401 29.3447C34.2987 29.3693 34.4476 29.1802 34.5086 29.1395C34.5227 29.162 34.3662 29.3277 34.3401 29.3447ZM38.282 46.3751C38.3048 46.2848 38.3549 46.0591 38.3391 46.0294C38.3184 45.992 38.2562 46.3266 38.282 46.3751ZM34.0643 55.1616C34.0666 55.1521 34.2571 55.2232 34.3149 55.2842C34.4256 55.4098 34.0602 55.1798 34.0643 55.1616ZM37.9801 49.0462C37.9137 49.3452 37.9798 49.0129 37.9247 49.0233C37.9099 49.2271 37.8964 49.7314 37.959 49.3858C37.9712 49.3188 37.9714 49.1406 37.9801 49.0462ZM38.0151 48.7709C37.9993 48.7378 37.9598 48.518 37.9498 48.7047C37.9454 48.7913 37.9987 48.9342 38.0151 48.7709ZM35.1221 55.6922C35.246 55.7838 34.6307 55.5689 34.6271 55.5328C34.6202 55.5244 34.6164 55.5178 34.6147 55.5129C34.5865 55.5171 34.4768 55.4605 34.4851 55.4192C34.5144 55.4409 34.6032 55.4842 34.6117 55.4928C34.6153 55.4966 34.6178 55.4998 34.6193 55.5025C34.6674 55.5025 35.0926 55.688 35.1221 55.6922ZM36.1939 55.7329C36.0482 55.8403 35.9962 55.7203 36.0103 55.715C36.1716 55.6349 36.0779 55.7433 36.0836 55.7469C36.0976 55.7522 36.2105 55.6834 36.1934 55.733C36.1936 55.733 36.1937 55.7329 36.1939 55.7329ZM35.3342 55.7503C35.3272 55.752 35.1936 55.7265 35.1889 55.7226C35.0884 55.6647 35.4604 55.7345 35.3342 55.7503ZM33.3421 30.4597C33.4307 30.3475 33.3907 30.4883 33.3264 30.5591C33.321 30.5648 33.2643 30.5597 33.3421 30.4597ZM38.0139 48.6232C38.0171 48.5777 38.1727 47.502 38.1033 47.559C38.0874 47.6473 37.9326 48.8828 38.0139 48.6232ZM39.9447 41.0904C39.8857 41.2548 39.8893 41.0538 39.943 40.9742C39.9629 40.9447 39.9596 41.0489 39.9447 41.0904ZM31.9052 33.784C31.8954 33.9493 31.7907 33.8858 31.8678 33.7609C31.8708 33.7561 31.9056 33.7775 31.9052 33.784ZM39.4436 42.4078C39.6074 41.8164 39.7496 42.0168 39.4277 42.7515C39.4271 42.7249 39.4266 42.6982 39.4261 42.6716C39.1037 43.5417 39.3914 42.7256 39.4542 42.509C39.4779 42.4263 39.4226 42.4835 39.4432 42.4083C39.4433 42.4082 39.4435 42.408 39.4436 42.4078ZM40.2541 40.2321C40.5805 39.7408 40.1279 40.7385 40.0379 41.0456C40.0852 40.7359 40.227 40.3643 39.9879 40.8545C40.2426 40.1043 40.1855 40.4349 40.2008 40.4063C40.2183 40.373 40.2402 40.2529 40.2541 40.2321ZM39.7441 41.6709C39.7368 41.704 39.6246 41.9351 39.5988 42.0241C39.5948 41.8854 39.7918 41.4497 39.7441 41.6709ZM37.1725 55.1819C37.1888 55.2183 37.185 55.2626 37.0819 55.3251C37.0995 55.2874 37.1472 55.2268 37.1725 55.1819ZM33.1679 46.8809C33.1867 47.0358 33.2045 47.3411 33.2347 47.2435C33.2381 47.233 33.1915 46.8782 33.1679 46.8809ZM38.5539 45.5478C38.5632 45.517 38.7696 44.7442 38.6582 45.0003C38.622 45.076 38.4513 45.7887 38.5539 45.5478ZM37.9921 49.7711C37.9921 49.7002 37.9906 49.4146 37.9822 49.4084C37.9505 49.3879 37.9611 49.7399 37.9921 49.7711ZM33.2099 47.6592C33.2095 47.6801 33.2434 48.1491 33.2582 48.0968C33.2909 47.9977 33.2191 47.588 33.2099 47.6592ZM33.5633 29.983C33.5799 29.958 33.6369 29.9515 33.6434 29.9437C33.6554 29.9219 33.9817 29.4924 33.8937 29.6862C33.8733 29.7121 33.3935 30.3241 33.3383 30.4144C33.268 30.415 33.5016 30.1662 33.5455 30.0982C33.553 30.086 33.5192 30.0502 33.5633 29.9833C33.5633 29.9832 33.5633 29.9831 33.5633 29.983ZM36.6903 55.558C36.6979 55.6071 36.278 55.7916 36.2689 55.7379C36.4151 55.6918 36.5563 55.6314 36.6903 55.558ZM36.8913 55.4514C36.987 55.4216 36.7993 55.5505 36.7332 55.5686C36.7223 55.5484 36.8782 55.4573 36.8913 55.4514ZM38.2155 48.2039C38.215 48.1206 38.1363 48.3687 38.1318 48.3111C38.1287 48.2738 38.1678 48.0916 38.1583 48.0312C38.1547 48.0138 38.0842 48.1964 38.0811 48.2515C38.0762 48.3295 38.1228 48.258 38.1149 48.3427C38.0889 48.6246 38.0434 48.8722 38.0317 49.1399C38.0307 49.164 38.0672 48.9784 38.0573 49.1839C38.056 49.2161 38.0059 49.4038 38.0089 49.6516C38.0237 49.7184 38.0351 49.7829 38.044 49.8461C38.1078 50.2526 38.0156 50.5957 38.0562 51.1404C38.0683 51.117 38.1007 50.6531 38.1019 50.6258C38.1104 50.4156 38.1159 50.1381 38.1194 49.8461C38.1236 49.3695 38.1523 48.8643 38.1835 48.5112C38.1971 48.3587 38.1636 48.4303 38.1686 48.3645C38.173 48.3126 38.2165 48.3788 38.2155 48.2039ZM33.1294 46.8036C33.0901 46.8825 33.1544 47.1344 33.168 47.2979C33.2076 47.2354 33.1412 46.9639 33.1294 46.8036ZM38.0086 53.8275C38.0147 53.7841 38.0442 53.6479 38.0291 53.6352C38.0121 53.6199 37.9783 53.8132 38.0086 53.8275ZM35.7399 28.0106C35.7439 28.0063 35.8673 27.9417 35.8727 27.941C35.9999 27.9172 35.6327 28.1101 35.7399 28.0106ZM38.9124 27.2962C39.007 27.2972 39.0987 27.2936 39.1241 27.3384C39.0672 27.3228 38.9007 27.323 38.9124 27.2962ZM41.6156 29.8342C41.6611 29.7956 41.7214 30.1231 41.7306 30.1866C41.7032 30.1679 41.5855 29.86 41.6156 29.8342ZM37.2974 55.2949C37.1793 55.3941 37.2535 55.4353 37.1521 55.4679C37.1345 55.4725 36.9961 55.3699 37.1632 55.3176C37.1935 55.3063 37.1284 55.4162 37.2974 55.2949ZM39.3845 42.8748C39.3976 42.9468 39.3242 43.1347 39.2794 43.2637C39.2637 43.2264 39.3561 42.967 39.3845 42.8748ZM33.2086 48.5083C33.1934 48.5498 33.1875 48.639 33.1863 48.7375C33.1838 48.9222 33.2081 49.14 33.2305 49.0503C33.2331 49.039 33.2244 48.8785 33.2177 48.7375C33.2133 48.634 33.2084 48.5411 33.2086 48.5083ZM32.4152 32.0611C32.4574 31.8664 32.2839 32.2324 32.2731 32.3664C32.2919 32.3111 32.4116 32.074 32.4152 32.0611ZM41.2218 28.8196C41.2276 28.8251 41.3053 28.9814 41.3065 28.9899C41.3357 29.1341 41.1169 28.696 41.2218 28.8196ZM37.8304 27.2662C37.8914 27.2219 38.3402 27.2135 38.4411 27.2477C38.3448 27.2894 37.7526 27.3115 37.8304 27.2662ZM37.6924 54.8007C37.6336 54.8928 37.5623 54.9699 37.4868 55.0363C37.4828 55.0054 37.6716 54.8023 37.6924 54.8007ZM41.5016 29.4121C41.505 29.4214 41.5056 29.4314 41.5087 29.4404C41.5062 29.4308 41.5039 29.4213 41.5016 29.4121ZM38.1161 51.8295C38.1269 51.6825 38.0771 51.713 38.0755 51.7221C38.0594 51.8326 38.104 51.9958 38.1161 51.8295ZM33.0808 47.0005C33.0441 47.0647 33.1098 47.3315 33.1128 47.494C33.1448 47.4438 33.1025 47.1276 33.0808 47.0005ZM40.5434 39.6865C40.6497 39.5307 40.4586 40.2481 40.3755 40.3866C40.3438 40.3868 40.5292 39.7087 40.5434 39.6865ZM32.1237 32.599C32.0854 32.5986 32.0277 32.8802 32.0643 32.8291C32.0867 32.7965 32.1467 32.5993 32.1237 32.599ZM40.2302 40.7339C40.2167 40.8038 40.1288 40.9471 40.1282 40.8855C40.1276 40.8062 40.2334 40.7158 40.2302 40.7339ZM38.4073 47.0472C38.417 47.0151 38.463 46.5684 38.3939 46.7436C38.3458 46.8657 38.3926 46.895 38.3874 46.9247C38.3794 46.957 38.2025 47.6605 38.4073 47.0472ZM41.7081 35.8412C41.6909 35.9864 41.6366 36.155 41.6019 36.3043C41.5961 36.2383 41.6677 35.8957 41.7081 35.8412ZM32.5436 31.5964C32.5098 31.6162 32.1324 32.463 32.382 31.9976C32.3945 31.9686 32.6255 31.5223 32.5436 31.5964ZM37.2974 55.2949C37.3121 55.2821 37.3299 55.2681 37.3512 55.2526C37.3314 55.2695 37.3132 55.2831 37.2974 55.2949ZM38.1037 53.7797C38.1251 53.819 38.1533 53.6394 38.1406 53.5845C38.1119 53.5672 38.1029 53.7745 38.1037 53.7797ZM41.634 36.324C41.6278 36.4135 41.574 36.5661 41.5483 36.6731C41.5303 36.6491 41.6021 36.3556 41.634 36.324ZM41.8959 30.404C41.9175 30.5626 41.9596 30.7573 41.9887 30.7551C41.9848 30.7592 41.9814 30.7678 41.9789 30.7815C41.9768 30.7949 42.0193 30.9649 42.0201 31.0417C42.059 31.4849 41.6361 29.3572 41.9855 30.5673C41.9562 30.5121 41.9264 30.4581 41.8959 30.404ZM37.2305 27.3012C37.1375 27.2844 36.9185 27.39 36.9822 27.3873C37.0248 27.3832 37.3214 27.3163 37.2305 27.3012ZM40.1881 27.5202C40.1744 27.5026 39.9955 27.4362 39.9832 27.4528C40.0711 27.5147 40.2525 27.5931 40.1881 27.5202ZM36.5875 27.4436C36.535 27.4562 36.4908 27.5339 36.4977 27.5341C36.5555 27.5341 36.6825 27.4442 36.5875 27.4436ZM37.6383 55.1659C37.6964 55.1271 37.7907 54.9315 37.7817 54.873C37.7924 54.87 37.8129 54.8566 37.8448 54.8273C37.8448 54.8274 37.8447 54.8275 37.8446 54.8277C37.8702 54.8115 38.0935 54.4311 38.1577 54.1489C38.2191 53.8662 38.2493 53.7409 38.0662 54.2652C38.0522 54.2971 38.1023 54.2637 38.046 54.3951C38.0421 54.4037 38.0148 54.3979 38.0026 54.4239C37.9802 54.4874 37.8007 54.7894 37.7744 54.8577C37.7698 54.8554 37.7632 54.8566 37.754 54.8622C37.678 54.9119 37.5985 55.1956 37.6383 55.1659ZM40.5007 27.7301C40.4773 27.6972 40.3729 27.6323 40.3486 27.6459C40.3914 27.6879 40.555 27.8046 40.5007 27.7301ZM32.4408 31.5788C32.3756 31.6661 32.298 31.9296 32.3501 31.8629C32.3806 31.8214 32.5144 31.4777 32.4408 31.5788ZM39.402 27.2214C39.8408 27.3674 39.5102 27.2464 39.5884 27.2301C39.5256 27.225 39.4648 27.2225 39.402 27.2214ZM35.795 55.9903C35.8665 55.9935 35.7871 56.0713 35.7062 56.0349C35.6815 56.0234 35.7555 55.9886 35.795 55.9903ZM33.2581 54.4223C33.2208 54.5032 33.1512 54.2111 33.2315 54.3053C33.234 54.3098 33.258 54.4176 33.2581 54.4223ZM34.8379 55.918C34.8972 55.8916 34.9264 55.8978 35.0542 55.9394C34.8588 55.9017 35.0268 55.9875 34.8379 55.918ZM41.9929 30.7526C41.9914 30.7539 41.9903 30.755 41.9887 30.7551C41.99 30.7537 41.9914 30.7529 41.9929 30.7526ZM36.1116 27.6477C36.0332 27.6428 35.8595 27.7323 35.9278 27.739C35.9342 27.7389 36.0967 27.6832 36.1116 27.6477ZM37.7817 54.873C37.7722 54.8755 37.7708 54.87 37.7744 54.8577C37.7787 54.8599 37.7808 54.8651 37.7817 54.873ZM37.0808 27.2755C37.0801 27.3018 37.3715 27.2461 37.3818 27.2427C37.5392 27.1643 37.1989 27.241 37.0808 27.2755ZM31.6305 33.612C31.6284 33.6292 31.7262 33.5423 31.7197 33.4696C31.7147 33.413 31.638 33.5467 31.6305 33.612ZM34.4047 55.7523C34.3373 55.7167 34.2455 55.66 34.2472 55.6213C34.2863 55.654 34.4169 55.7323 34.4047 55.7523ZM33.263 54.5469C33.3347 54.613 33.4311 54.7897 33.501 54.9001C33.4561 54.9336 33.303 54.6206 33.263 54.5469ZM37.482 55.306C37.489 55.3045 37.6318 55.1729 37.5877 55.1692C37.5266 55.1654 37.4316 55.3307 37.482 55.306ZM31.8178 33.1315C31.8326 33.0116 31.6777 33.2483 31.6949 33.3852C31.703 33.4548 31.8145 33.1512 31.8178 33.1315ZM35.5504 27.8874C35.4402 27.9749 35.7557 27.8313 35.7822 27.7795C35.7242 27.8066 35.5896 27.8556 35.5504 27.8874ZM39.9471 27.2929C39.6415 27.0599 39.7642 27.3122 39.8283 27.318C39.8373 27.3184 39.9537 27.2981 39.9471 27.2929ZM33.0038 49.8726C33.0182 49.9489 33.0702 49.6643 33.036 49.6274C33.0145 49.6047 32.9947 49.8237 33.0038 49.8726ZM42.1778 33.076C42.1781 33.0554 42.1784 33.035 42.1786 33.0147C42.1799 33.0299 42.1799 33.0499 42.1778 33.076ZM34.4216 28.5462C34.7609 28.4421 34.6631 28.3844 34.6852 28.3654C34.7331 28.328 34.867 28.2719 34.9535 28.2001C34.8598 28.2901 34.7683 28.3833 34.68 28.4785C34.759 28.4062 35.502 27.9506 35.5104 27.9345C35.5149 27.8911 35.2888 28.045 35.2812 28.0482C35.2694 28.0509 35.1815 27.9969 35.158 28.0086C35.1146 28.0189 34.5221 28.4727 34.4216 28.5462ZM39.1897 27.0953C39.2502 27.1159 39.2603 27.1557 39.2896 27.152C39.2997 27.1508 39.3073 27.1161 39.3421 27.1136C39.2917 27.1064 39.2416 27.1004 39.1897 27.0953ZM34.0954 29.045C33.9994 29.0806 34.3002 28.7975 34.3144 28.7945C34.3844 28.7668 34.1712 29.0139 34.0954 29.045ZM36.9301 27.2832C36.9163 27.2824 36.6224 27.3599 36.6336 27.3834C36.7136 27.3715 37.1006 27.268 36.9301 27.2832ZM39.3833 27.1196C39.4747 27.1418 39.6268 27.2226 39.6234 27.1665C39.6233 27.1665 39.6231 27.1665 39.623 27.1664C39.5434 27.1475 39.4655 27.1325 39.3833 27.1196ZM31.8438 32.7116C31.6896 32.8915 31.8252 32.8275 31.9177 32.6544C31.9024 32.5859 31.8691 32.6822 31.8438 32.7116ZM31.5593 33.3642C31.5231 33.4177 31.369 34.0388 31.4395 33.9563C31.4626 33.9267 31.5218 33.5629 31.5306 33.5477C31.5423 33.5246 31.5568 33.6502 31.6028 33.4607C31.5833 33.4668 31.5703 33.3455 31.5593 33.3642ZM31.7314 32.8661C31.5985 33.0539 31.6969 33.1387 31.7495 32.9821C31.7704 32.9212 31.7505 32.8395 31.7314 32.8661ZM32.0628 32.0329C32.0215 32.1004 31.9261 32.2891 31.9112 32.439C31.9842 32.259 32.0607 32.0819 32.1412 31.9065C32.1296 31.8771 32.0986 31.9736 32.0626 32.0333C32.0626 32.0332 32.0627 32.033 32.0628 32.0329ZM32.7237 53.656C32.6995 53.8 32.6656 53.4739 32.6781 53.4588C32.705 53.4182 32.7328 53.5925 32.7237 53.656ZM31.9217 51.3584C31.9082 51.4113 31.8639 51.4458 31.8871 51.5621C31.9198 51.4451 31.9525 51.3281 31.9852 51.2111C31.9103 51.1201 31.9365 51.3006 31.9217 51.3584ZM31.6479 51.8052C31.6461 51.7887 31.5308 51.879 31.6078 51.6655C31.6597 51.5212 31.7103 52.3058 31.6592 52.4475C31.6355 52.291 31.6627 51.9475 31.6479 51.8052ZM31.1491 53.1797C31.1399 53.1887 31.1264 52.8906 31.1329 52.8561C31.167 52.6749 31.1983 53.1307 31.1491 53.1797ZM31.1711 52.2287C31.1487 52.3685 31.1343 52.0588 31.1472 51.9664C31.1686 51.9575 31.1743 52.2071 31.1711 52.2287ZM31.7419 55.8754C31.7708 56.0676 31.9988 56.1001 31.8227 55.8976C31.8145 55.888 31.7412 55.8672 31.7419 55.8754ZM31.0328 52.8882C31.0552 52.7484 31.0696 53.0581 31.0568 53.1504C31.0353 53.159 31.0296 52.9095 31.0328 52.8882ZM31.6532 56.0822C31.7434 56.3154 31.8503 56.1336 31.8395 56.1062C31.7911 55.9941 31.515 55.6764 31.4624 55.6044C31.7927 56.1394 31.6183 55.9697 31.6532 56.0822ZM32.4498 56.8501C32.6215 56.9848 32.2457 56.5758 32.1426 56.5248C32.2146 56.6062 32.3988 56.8131 32.4498 56.8501ZM33.5094 57.665C33.6111 57.7285 33.9344 57.8827 34.0021 57.8724C33.8754 57.8355 33.5668 57.6632 33.5094 57.665ZM33.7189 57.8619C33.8795 57.9738 33.9647 57.8805 33.7508 57.8297C33.7426 57.8276 33.7134 57.8571 33.7189 57.8619ZM34.733 58.2181C34.8498 58.2876 35.0087 58.1958 34.8097 58.1605C34.7511 58.1495 34.7209 58.2103 34.733 58.2181ZM31.6663 56.4523C31.7638 56.6127 31.9757 56.7412 31.7395 56.4319C31.8326 56.5328 31.9295 56.6293 32.0299 56.7213C31.7337 56.312 31.6806 56.3989 31.5953 56.2784C31.4838 56.1047 31.5745 56.067 31.6203 56.0847C31.4736 55.9855 31.1304 55.3612 31.0056 54.9693C31.0877 55.3208 31.3094 55.8731 31.5029 56.1792C31.5561 56.2677 31.635 56.3342 31.685 56.4056C31.7661 56.5202 31.6612 56.4435 31.6659 56.4518C31.666 56.4519 31.6662 56.4521 31.6663 56.4523ZM36.1448 58.2773C36.5201 58.2833 36.2716 58.2039 36.0686 58.2434C36.0598 58.2459 36.1352 58.2771 36.1448 58.2773ZM30.6846 53.2888C30.7325 52.8852 30.796 53.1785 30.6996 52.3343C30.7678 52.689 30.7487 52.3539 30.7762 52.4231C30.798 52.4787 30.7799 52.6868 30.8238 52.5658C30.7761 52.7248 30.7893 53.4151 30.7815 53.4459C30.7815 53.4456 30.7815 53.4453 30.7815 53.4451C30.7769 53.4635 30.6694 53.4175 30.6846 53.2888ZM33.3759 57.9333C33.4309 58.1152 33.5676 57.94 33.7546 58.1414C34.1213 58.1279 32.9076 57.7561 32.8792 57.5161C34 58.2364 32.2239 56.9146 32.881 57.6034C32.2954 57.0879 32.6578 57.4748 32.5435 57.4259C32.4189 57.3727 32.1095 57.0482 32.0924 57.0986C32.0925 57.0988 32.0927 57.0989 32.0929 57.0991C32.2927 57.2881 32.5077 57.4607 32.735 57.6148C32.5829 57.3707 33.0105 57.7167 33.1374 57.8831C33.217 57.902 33.2964 57.9186 33.3759 57.9333ZM32.2031 56.9676C32.2146 56.9942 32.6643 57.3578 32.6525 57.3114C32.59 57.2664 31.9891 56.7166 32.2031 56.9676ZM30.8858 54.8123C30.9403 55.0137 31.0368 55.3259 31.1229 55.4123C31.0371 55.2218 30.9554 54.9101 30.8858 54.8123ZM39.4678 56.5787C39.6131 56.3559 39.0718 56.9641 39.2569 56.8145C39.2678 56.8087 39.4623 56.5912 39.4678 56.5787ZM33.9488 58.1568C34.1955 58.2856 34.1131 58.1177 33.9139 58.0828C33.9021 58.0807 33.9374 58.1507 33.9488 58.1568ZM30.6682 52.9617C30.635 52.9472 30.6583 52.3617 30.658 52.2579C30.6888 52.3169 30.7062 52.9784 30.6682 52.9617ZM30.6762 54.4799C30.6392 54.9324 30.9916 55.4387 31.0166 55.4901C31.0395 55.549 30.9516 55.4796 30.9562 55.4932C30.9568 55.5297 31.2771 56.1271 31.307 56.1471C31.3215 56.165 31.3199 56.0244 31.4123 56.1283C31.1956 55.9438 30.7643 54.7932 30.7742 54.7251C30.7576 54.6782 30.7683 55.061 30.6763 54.4806C30.6763 54.4804 30.6762 54.4801 30.6762 54.4799ZM31.0685 55.6405C31.0229 55.4773 31.2314 55.8961 31.2845 55.9966C31.3888 56.2284 31.0661 55.6665 31.0685 55.6405ZM31.6461 56.6147C31.6694 56.6648 31.9909 57.0333 32.0482 57.0341C31.9134 56.8459 31.5825 56.5109 31.6461 56.6147ZM36.4709 58.4692C36.5954 58.4478 36.9413 58.3934 36.9525 58.3568C36.8316 58.3975 36.486 58.439 36.4709 58.4692ZM30.4077 50.9639C30.3827 51.1275 30.3725 50.7486 30.3845 50.6381C30.4044 50.6321 30.4098 50.95 30.4077 50.9639ZM33.8988 58.4418C33.9521 58.5041 35.2004 58.7712 35.6354 58.7118C35.6889 58.7101 35.7295 58.7076 35.7538 58.7056C35.7297 58.7036 35.6889 58.7021 35.6354 58.7001C35.204 58.728 33.9902 58.4532 33.9362 58.4115C33.9155 58.4079 33.8899 58.4372 33.8988 58.4418ZM31.2231 56.3835C31.1054 56.2859 31.1014 56.1748 31.0927 56.1593C31.0025 56.0034 30.8294 55.6719 30.9041 55.7268C31.0153 56.0276 31.4565 56.5743 31.2231 56.3835ZM36.6147 58.6457C37.1391 58.5275 36.1181 58.6703 36.2561 58.6836C36.2651 58.6872 36.5603 58.6601 36.6147 58.6457ZM33.7274 58.3925C33.5761 58.4352 32.2098 57.5897 32.0623 57.3667C32.2753 57.4704 32.3824 57.6257 32.6365 57.7992C32.7053 57.8452 32.7024 57.8098 32.7097 57.8148C32.8292 57.8923 32.7228 57.8601 32.7967 57.9084C32.8298 57.9676 33.8924 58.4269 33.7274 58.3925ZM31.1519 56.3303C31.0617 56.282 30.6047 55.3824 30.6177 55.3326C30.5901 55.1813 30.682 55.4296 30.8163 55.7092C30.9478 55.9905 31.1336 56.2959 31.1519 56.3303ZM33.8451 58.4982C33.6487 58.5242 32.9418 58.128 33.455 58.3282C33.5034 58.347 33.6951 58.4641 33.8451 58.4982ZM36.5706 58.7274C36.5982 58.7326 37.1593 58.6145 37.1602 58.5814C37.0815 58.6122 36.2661 58.7599 36.5706 58.7274ZM36.288 58.8521C36.3013 58.8492 36.163 58.8218 36.4301 58.7914C36.4514 58.7869 36.5038 58.8411 36.834 58.7504C36.901 58.7315 36.9957 58.6715 36.9876 58.6712C36.6372 58.7045 35.5967 58.9437 36.288 58.8521ZM31.1062 56.3378C31.1173 56.3959 30.9892 56.3201 30.9573 56.1996C30.9442 56.1482 31.0246 56.2112 31.1062 56.3378ZM38.2766 58.1378C38.009 58.3451 38.9138 57.8072 38.936 57.7457C38.8999 57.7561 38.3093 58.1276 38.2766 58.1378ZM30.0998 50.581C30.0998 50.5812 30.0998 50.5814 30.0998 50.5816C30.1088 50.3758 30.142 50.5033 30.1431 50.4936C30.1918 50.0552 30.1166 50.1715 30.1078 50.1029C30.0886 49.9559 30.18 49.9796 30.1421 49.7316C30.198 50.1415 30.1746 49.7684 30.2071 49.7568C30.3398 49.7109 30.145 50.3026 30.1728 50.507C30.1766 50.5354 30.219 50.3252 30.231 50.3981C30.2701 50.6353 30.0652 51.3709 30.0998 50.581ZM30.9062 56.1228C30.7849 56.0379 30.4389 55.0968 30.5714 55.331C30.57 55.3795 31.0368 56.2678 30.9062 56.1228ZM44.8888 30.3061C44.9564 30.4973 44.9157 30.0334 44.87 29.9532C44.8492 29.9139 44.8606 30.2233 44.8888 30.3061ZM43.8913 27.0537C43.7463 26.8243 43.4696 26.671 43.6705 26.9354C43.6918 26.9626 43.8905 27.0893 43.8913 27.0537ZM43.178 41.5958C43.2981 41.408 43.2058 41.3888 43.1536 41.5396C43.1352 41.5928 43.1742 41.6017 43.178 41.5958ZM45.1383 33.1147C45.1428 33.0911 45.1418 32.8139 45.1197 32.8237C45.1068 32.9264 45.1115 33.2684 45.1383 33.1147ZM43.1674 41.6652C43.1947 41.5384 43.0568 41.7244 43.0665 41.894C43.0881 41.8173 43.1646 41.6783 43.1674 41.6652ZM34.379 58.8688C34.5343 58.8692 34.9498 58.9526 35.1937 58.961C35.2162 59.0207 34.5492 58.9115 34.379 58.8688ZM44.3392 28.0688C44.2137 27.8606 44.3851 28.3456 44.4082 28.2853C44.4088 28.2781 44.3451 28.0773 44.3392 28.0688ZM41.3547 47.9756C41.3431 47.844 41.2476 48.243 41.3146 48.1386C41.3173 48.1334 41.3551 47.9828 41.3547 47.9756ZM41.1993 49.7268C41.2084 49.6312 41.2204 49.2252 41.1856 49.3822C41.1793 49.4064 41.1713 49.7193 41.1993 49.7268ZM30.072 50.0908C30.021 50.149 30.0331 49.8112 30.042 49.7629C30.0458 49.7439 30.1384 50.0149 30.072 50.0908ZM43.6558 40.2548C43.6868 40.1447 43.7933 39.8659 43.7844 39.8073C43.7454 39.9432 43.5932 40.2734 43.6558 40.2548ZM44.6983 29.086C44.6967 28.8751 44.5766 28.5419 44.5361 28.6482C44.6614 29.0138 44.589 28.5824 44.6983 29.086ZM42.9826 42.3624C43.0164 42.28 42.9738 42.1922 42.9673 42.2006C42.9055 42.2813 42.9275 42.4366 42.9826 42.3624ZM44.909 35.637C44.9398 35.6368 44.977 35.3253 44.9511 35.3636C44.943 35.3764 44.8849 35.6375 44.909 35.637ZM39.3248 57.6339C39.4839 57.532 39.0707 57.9269 38.9099 57.9935C38.821 58.0087 39.31 57.6537 39.3248 57.6339ZM42.1872 44.6508C42.2249 44.6764 42.3321 44.2587 42.2456 44.4091C42.2237 44.4469 42.1743 44.6422 42.1872 44.6508ZM41.3772 48.5232C41.3465 48.2506 41.216 49.3685 41.306 49.0783C41.3094 49.0579 41.3768 48.5468 41.3772 48.5232ZM41.2732 50.407C41.279 50.355 41.4273 50.3809 41.3701 50.596C41.3627 50.6242 41.3235 50.4922 41.3145 50.5152C41.3094 50.5288 41.2886 50.9964 41.292 51.0179C41.296 51.0411 41.3435 51.0138 41.3488 51.0373C41.3548 51.0638 41.313 51.3517 41.3126 51.5024C41.3118 51.7865 41.3513 51.8172 41.3515 51.8404C41.3517 51.9083 41.3236 52.0224 41.3237 52.16C41.3238 52.5296 41.3335 53.0036 41.3297 53.449C41.3284 54.0084 41.2226 54.534 41.0903 54.878C41.2378 54.4076 41.2866 53.9262 41.2744 53.449C41.2693 53.3075 41.2639 53.1654 41.2606 53.0215C41.3432 53.1641 41.197 52.3054 41.2923 52.8077C41.2716 52.5764 41.2551 50.5773 41.2732 50.4076C41.2732 50.4074 41.2732 50.4072 41.2732 50.407ZM43.2979 26.144C43.458 26.2412 42.8407 25.5753 42.73 25.5769C42.8215 25.6582 43.2861 26.1266 43.2979 26.144ZM45.0408 29.5141C45.065 29.5816 45.1827 29.6288 45.2071 30.0088C45.2071 30.0092 45.2072 30.0095 45.2073 30.0098C45.2137 30.1208 45.1663 30.0021 45.1617 30.0236C45.1605 30.0321 45.1729 30.3749 45.1143 30.099C45.0189 29.6777 45.1797 30.0448 45.1343 29.8179C45.1307 29.7898 44.9773 29.3718 44.9704 29.4001C44.97 29.4034 45.0127 29.5291 45.0128 29.5517C45.0139 29.6363 44.9745 29.6041 44.9758 29.6158C44.9858 29.6536 45.1721 30.3184 45.1371 30.4236C45.1393 30.4575 44.8804 29.3617 44.8619 29.3162C44.8593 29.2877 44.9453 29.2772 44.9459 29.2465C44.9485 29.2309 44.7863 28.7904 44.7721 28.7307C44.7688 28.7132 44.7668 28.6993 44.7656 28.6892C44.7644 28.765 44.6259 28.3589 44.6564 28.3611C44.6711 28.3639 44.7633 28.6462 44.7636 28.6572C44.7643 28.6619 44.7644 28.6661 44.7648 28.6699C44.787 28.6013 45.0558 29.5523 45.0426 29.3352C45.1375 29.6051 44.9652 29.3138 45.0408 29.5141ZM45.3328 30.8226C45.3203 30.7955 45.3076 30.7684 45.2949 30.7414C45.3815 31.217 45.3826 31.7692 45.3948 32.3109C45.3976 32.4487 45.45 32.289 45.4378 32.4702C45.4328 32.5409 45.4179 32.615 45.4026 32.6632C45.3864 32.7139 45.37 32.736 45.3643 32.696C45.3638 32.6927 45.3644 32.681 45.3657 32.6632C45.3724 32.5794 45.3921 32.3576 45.3854 32.236C45.3604 31.801 45.3145 31.9134 45.3128 31.888C45.3105 31.8603 45.3276 31.5844 45.3128 31.434C45.2749 31.0563 45.2309 30.8884 45.186 30.363C45.2641 30.6587 45.3074 30.4839 45.3328 30.8226ZM41.8355 46.401C41.8608 46.4221 41.778 46.658 41.7632 46.7467C41.7368 46.7264 41.8181 46.4901 41.8355 46.401ZM27.8669 38.1422C27.915 38.2303 27.9248 37.5478 27.8848 37.7275C27.875 37.7691 27.8651 38.0544 27.8669 38.1422ZM28.106 35.0467C28.1062 34.9532 28.0166 35.3161 28.055 35.3209C28.0667 35.3218 28.1055 35.0588 28.106 35.0467ZM44.9123 36.7795C44.9104 36.7968 44.8438 37.0359 44.8393 37.0428C44.7527 37.1914 44.963 36.4018 44.9123 36.7795ZM29.0103 31.3673C28.9209 31.6835 29.2955 30.7717 29.1466 31.0363C29.1383 31.0492 29.0136 31.3521 29.0103 31.3673ZM29.5498 30.0983C29.5151 30.1708 29.3528 30.4829 29.3652 30.4937C29.3833 30.5093 29.5676 30.1526 29.5498 30.0983ZM43.1365 42.4807C43.1994 42.468 43.0252 42.8348 42.9859 42.9682C42.9227 42.9814 43.0957 42.616 43.1365 42.4807ZM44.0375 40.032C43.5048 41.7159 43.5224 41.3141 44.0457 39.9229C44.0799 39.932 44.0706 39.9246 44.0375 40.032ZM43.2928 42.1429C43.2805 42.0723 43.3559 41.8918 43.4031 41.7678C43.4181 41.7986 43.3187 42.0514 43.2928 42.1429ZM27.8238 38.972C27.7696 38.8556 27.804 38.3175 27.8265 38.413C27.8287 38.4321 27.8492 39.0163 27.8238 38.972ZM44.9235 36.9423C44.9867 36.9125 44.834 37.4515 44.8106 37.4886C44.7228 37.6437 44.9268 36.9907 44.9235 36.9423ZM42.4202 44.7406C42.4341 44.8358 42.3415 45.0632 42.2967 45.2132C42.2822 45.1347 42.379 44.8684 42.4202 44.7406ZM42.8113 43.6543C42.8094 43.6645 42.7337 43.8762 42.7288 43.885C42.6309 44.0465 42.8451 43.447 42.8113 43.6543ZM29.697 50.8664C29.6956 50.8587 29.6983 50.6827 29.6999 50.6765C29.7401 50.5195 29.7319 51.0476 29.697 50.8664ZM65.3426 55.6787C65.341 55.6382 65.3695 55.4811 65.3758 55.4136C65.4181 55.495 65.3475 55.823 65.3426 55.6787ZM63.354 47.1515C63.3612 47.2125 63.368 47.2731 63.3745 47.3334C63.4022 47.1658 63.413 46.9394 63.4364 46.7813C63.4403 46.7554 63.4735 46.8258 63.4795 46.7641C63.4855 46.7018 63.4329 46.7116 63.4327 46.6231C63.4344 46.5243 63.4882 46.0679 63.487 45.9063C63.4876 45.7908 63.4858 45.6729 63.4823 45.5528C63.4683 45.0762 63.4224 44.5975 63.3862 44.119C63.4869 44.7286 63.4659 44.1055 63.4258 43.9357C63.415 43.8984 63.3302 43.915 63.256 43.3022C63.2016 42.9137 63.4091 43.2436 63.2088 42.6123C63.2161 43.1265 63.1288 42.6375 63.0312 42.2566C63.0167 42.1904 62.8906 41.6574 62.8122 41.4299C62.7864 41.3515 62.7001 41.2478 62.6643 41.1457C62.6396 41.0753 62.6476 41.0129 62.6091 40.9088C62.4299 40.4248 62.2311 39.962 62.0114 39.5068C62.2608 39.7135 61.956 39.2739 61.9481 39.2518C61.9236 39.1274 62.1849 39.6093 62.1051 39.4065C61.9631 39.1376 61.8112 38.8767 61.6495 38.6262C61.7652 38.8407 61.3859 38.4123 61.3602 38.3082C61.3093 38.3963 60.6339 37.2016 60.4381 37.1089C60.4008 37.0887 60.5642 37.3067 60.1176 36.8657C60.0683 36.8193 60.1102 36.8097 60.0811 36.7891C60.063 36.7763 59.8962 36.7793 59.8275 36.6494C59.7996 36.6056 60.1045 36.7245 59.5204 36.348C59.69 36.576 58.6874 35.9103 58.4767 35.8374C58.5122 35.8676 58.5471 35.8981 58.5814 35.9289C58.3972 35.8083 58.344 35.8332 58.3001 35.8145C58.1196 35.74 57.8693 35.6286 57.6857 35.5925C57.4722 35.5516 57.4612 35.6193 57.214 35.5559C57.2708 35.579 57.3292 35.6034 57.3851 35.6284C57.2126 35.5958 57.0447 35.572 56.8664 35.5551C57.2843 35.4994 56.7764 35.541 56.7466 35.5451C56.6944 35.5458 56.7714 35.5116 56.6836 35.5123C56.6743 35.513 56.6865 35.5479 56.5504 35.5485C56.4972 35.5489 56.4551 35.5484 56.4211 35.5469C56.2925 35.5413 56.3027 35.5124 56.2204 35.5165C56.2119 35.5179 56.2431 35.5451 56.0746 35.5677C55.5654 35.6635 56.07 35.538 56.095 35.5366C56.1255 35.5322 55.9104 35.3988 56.4061 35.4298C56.2366 35.4165 56.2204 35.3611 56.2012 35.36C56.1816 35.3571 55.9062 35.394 55.8929 35.4011C55.766 35.4422 55.887 35.4633 55.8628 35.4747C55.8438 35.4795 55.5248 35.4978 55.5027 35.6387C55.3389 35.578 55.5386 35.5073 55.7865 35.4432C55.8175 35.4112 55.5425 35.4504 55.5298 35.4579C55.2014 35.565 55.4164 35.594 55.369 35.6728C55.3467 35.7141 55.206 35.7072 55.3459 35.7369C55.0971 35.8596 55.2292 35.7476 55.2096 35.7478C55.1801 35.7499 55.1041 35.8178 55.0926 35.8214C55.0745 35.8264 55.1152 35.7697 55.0478 35.7971C55.036 35.8023 54.9651 35.9028 55.1022 35.8482C54.9313 35.9429 54.9732 35.9725 54.8675 35.9429C54.8566 36.1534 54.7285 35.9313 54.6768 35.9624C54.5428 36.0489 54.6643 36.112 54.6621 36.1215C54.6468 36.1775 54.3245 36.482 54.276 36.602C54.2261 36.5066 54.4961 36.305 54.5292 36.2503C54.6411 36.0384 54.2789 36.4696 54.3026 36.2686C54.2792 36.3467 54.2582 36.4263 54.24 36.5064C54.1005 36.5838 54.1821 36.3872 53.996 36.7423C54.0161 36.829 54.135 36.4969 54.1408 36.5834C54.1424 36.6308 54.0306 36.831 54.0428 36.8438C54.0561 36.8557 54.1421 36.6673 54.1502 36.7105C54.1594 36.7861 53.7618 37.4641 53.998 36.9144C53.9228 37.0595 53.7738 37.0891 53.7479 37.2451C53.7366 37.3458 54.0903 36.9014 53.7636 37.6567C53.7012 37.6527 53.864 37.3383 53.865 37.3317C53.864 37.3174 53.7192 37.3252 53.709 37.3335C53.6622 37.3522 53.456 38.2208 53.364 38.4093C53.4482 38.3452 53.2442 39.1099 53.2645 39.2057C53.2679 39.2295 53.3249 39.1492 53.3265 39.1745C53.3334 39.3295 53.2109 39.7424 53.1999 39.9425C53.1861 40.1648 53.2287 40.1384 53.2278 40.1507C53.2221 40.2485 53.1977 40.1694 53.1959 40.2294C53.1946 40.2707 53.1894 40.4242 53.1889 40.5816C53.1877 40.7708 53.1935 40.9643 53.1971 40.9814C53.1992 40.9905 53.2416 40.8866 53.2546 41.0233C53.258 41.0468 53.1984 41.0338 53.2464 41.4416C53.309 41.9305 53.2912 41.0967 53.3618 41.2975C53.3002 41.6161 53.382 41.6008 53.3822 41.6864C53.3824 41.7161 53.3333 41.9422 53.3667 42.1828C53.335 42.011 53.3066 41.8407 53.2813 41.6686C53.2825 41.8397 53.3328 42.1673 53.3383 42.3097C53.3408 42.3791 53.2776 42.3298 53.2994 42.4789C53.3051 42.5106 53.4546 42.6167 53.3439 42.2359C53.3882 42.1989 53.3799 42.3878 53.4058 42.4717C53.4098 42.4846 53.4969 42.5235 53.4635 42.6406C53.4574 42.6687 53.1704 42.417 53.4665 43.1336C53.4762 43.1565 53.4904 43.068 53.5007 43.0903C53.5073 43.1055 53.5308 43.2975 53.5392 43.3177C53.5477 43.3383 53.562 43.2406 53.5732 43.2649C53.6302 43.3889 53.5386 43.5863 53.4952 43.3138C53.4969 43.4073 53.4994 43.5009 53.5027 43.5948C53.5774 43.4783 53.5586 43.7316 53.5899 43.8569C53.7958 44.6584 53.7316 44.1038 53.7956 44.2347C53.9013 44.4442 53.6971 44.3143 53.8308 44.6333C53.8446 44.6629 53.8022 44.2442 53.9766 45.0367C53.9416 44.9219 53.9075 44.8071 53.8743 44.6924C53.8007 44.783 53.9942 45.1081 54.0037 45.1345C54.105 45.4392 54.0103 45.2401 54.1943 45.6849C54.2109 45.7246 54.2163 45.8208 54.2547 45.9053C54.4133 46.255 54.1334 45.4167 54.1661 45.3839C54.1772 45.3669 54.4534 46.2739 54.4586 46.3091C54.4639 46.4538 54.3099 45.9019 54.2972 46.0205C54.2869 46.0618 54.7554 47.355 54.8358 47.6291C54.9222 47.9423 54.8523 48.1238 54.9873 48.0781C54.8861 48.2117 55.0035 48.2568 55.0166 48.2967C55.1745 48.7795 55.1741 48.7813 55.334 49.1917C55.3694 49.2826 55.3569 49.3745 55.3752 49.4047C55.3859 49.4223 55.4163 49.3716 55.4623 49.46C55.5264 49.5812 55.7551 50.3824 55.7506 50.451C55.7469 50.5177 55.6261 50.1206 55.6111 50.2045C55.7046 50.4891 55.8067 50.7594 55.8976 51.0512C55.9351 51.1724 55.8874 51.1194 55.9038 51.1717C55.9111 51.1934 56.0688 51.6053 56.073 51.5847C56.0872 51.5306 55.6467 50.2552 55.8063 50.5765C55.8375 50.638 55.8508 50.8886 55.9155 50.8267C56.2777 51.9775 56.6123 53.1747 56.8397 54.4266C56.6405 53.722 56.4947 52.9257 56.2805 52.2159C56.2518 52.1183 56.1603 51.7886 56.1331 51.8406C56.3066 52.4409 56.5356 53.1978 56.6451 53.8075C56.6486 53.8269 56.5967 53.7644 56.6074 53.8378C56.6284 53.974 56.7788 54.405 56.7773 54.4838C56.7765 54.497 56.6783 54.2537 56.6636 54.3367C56.6254 54.5487 56.8068 54.5655 56.8362 54.7377C56.8639 54.8695 56.9165 55.7806 56.9883 56.003C57.0746 56.2379 56.9391 55.3285 56.9903 55.3904C57.1263 55.9988 57.1347 56.6381 57.1605 57.2341C57.161 57.2447 57.1945 57.1521 57.204 57.2851C57.2196 57.5171 57.1675 57.5795 57.16 57.6928C57.1588 57.7107 57.158 57.7353 57.1572 57.7645C57.153 57.9144 57.156 58.1995 57.1399 58.2432C57.1374 58.2497 57.086 58.1722 57.0846 58.1604C57.0634 57.9937 57.1301 57.9345 57.131 57.9193C57.1333 57.866 57.1111 57.8136 57.1095 57.7645C57.1094 57.7607 57.1094 57.7569 57.1095 57.7531C57.1118 57.6565 57.1352 57.6031 57.135 57.476C57.1348 57.3884 57.0912 57.4738 57.0913 57.3896C57.0925 57.3592 57.1837 57.0218 57.0755 56.9955C57.0632 56.9935 57.0702 57.3202 57.0597 57.7645C57.0399 58.501 57.0278 59.587 57.0452 59.7452C57.0579 59.5367 57.0706 59.3281 57.0834 59.1195C57.0524 59.5431 57.137 60.0519 57.0118 60.0879C57.0091 60.5144 57.0063 60.9409 57.0035 61.3674C56.9924 62.0628 57.3 62.7445 57.8326 63.2044C57.9593 63.3192 57.8316 63.3326 58.0864 63.4732C58.0366 63.412 57.9903 63.3491 57.9479 63.285C58.0376 63.4052 58.6073 63.719 58.7206 63.711C58.7344 63.7117 58.7714 63.6509 58.9237 63.6768C59.0594 63.697 59.0744 63.7516 59.1492 63.7705C59.2116 63.7855 59.2849 63.7746 59.3034 63.7781C59.3179 63.781 59.3226 63.8147 59.3584 63.821C59.3717 63.8233 59.3822 63.8239 59.3905 63.8234C59.4536 63.8193 59.3914 63.7589 59.4934 63.851C59.4661 63.8563 59.4386 63.861 59.4107 63.8654C59.548 63.8808 59.7465 63.9091 59.5392 63.95C59.5032 63.956 59.5326 63.9222 59.5059 63.9236C59.4649 63.9256 59.4265 63.9267 59.3905 63.9271C58.7153 63.8874 59.037 63.9596 59.3905 63.9629C59.4893 63.9609 59.5875 63.9491 59.6629 63.9306C59.7659 63.9832 60.2788 63.8212 60.2931 63.8122C60.3215 63.816 60.2469 63.8852 60.3737 63.8722C60.4115 63.8908 61.0356 63.4954 60.8404 63.6851C60.8028 63.7313 60.4761 63.8853 60.3942 63.9124C60.6332 63.9401 60.9769 63.5534 61.0097 63.5211C61.1947 63.403 60.7211 63.8421 61.1279 63.5555C61.427 63.3135 61.1096 63.4971 61.2004 63.3796C61.2541 63.3223 61.5926 63.0508 61.504 62.9963C61.5816 62.8762 61.5725 62.9729 61.5861 62.961C61.6022 62.9499 61.7333 62.6973 61.7899 62.6236C61.7974 62.6148 61.8252 62.6696 61.8342 62.6613C61.8546 62.6458 61.9618 62.387 61.9585 62.3741C61.9584 62.3667 61.8932 62.4111 61.8934 62.3821C61.8969 62.3499 61.9899 62.1055 61.9787 62.0873C61.9698 62.064 61.8793 62.3712 61.8493 62.3028C61.9156 62.1716 61.9434 61.9314 61.9188 61.8327C61.9267 61.8573 61.899 61.9932 61.8816 62.0381C61.8223 61.9979 61.8778 61.7164 61.9153 61.8233C61.8961 61.755 61.8727 61.7953 61.8499 61.7558C61.8445 61.7456 61.8549 61.658 61.8439 61.6396C61.842 61.6375 61.8037 61.7234 61.7914 61.7034C61.7734 61.6682 61.7972 61.41 61.8008 61.3874C61.8219 61.3263 61.8406 61.543 61.867 61.5642C61.8729 61.5684 61.9403 61.3815 61.9439 61.377C62.0023 61.3663 61.9528 61.5816 62.0035 61.5602C62.0181 61.5067 62.0311 61.453 62.0424 61.3978C62.0994 61.6145 62.0012 62.0004 62.0232 62.1129C62.0982 61.7996 62.1094 61.4649 62.2405 61.4675C62.2967 61.4688 62.3202 61.6202 62.3339 61.6158C62.3879 61.5975 62.3415 61.3838 62.3424 61.3767C62.3455 61.3703 62.3485 61.3674 62.3514 61.3674C62.3514 61.3674 62.3514 61.3674 62.3514 61.3674C62.3844 61.3671 62.391 61.6709 62.399 61.6875C62.4205 61.7165 62.5313 61.5879 62.5524 61.5881C62.5584 61.5931 62.5571 61.823 62.6032 61.7507C62.6526 61.6768 62.6647 61.4701 62.6676 61.4632C62.6955 61.4238 62.6915 61.7881 62.6985 61.801C62.7058 61.8084 62.7679 61.6155 62.7791 61.6097C62.7922 61.6055 62.8057 61.7597 62.8347 61.8259C62.8571 61.8754 62.8956 61.7447 62.897 61.7685C62.9026 61.7866 62.8405 62.1469 62.8366 62.1649C62.8379 62.193 62.8902 62.1162 62.8957 62.1301C62.9044 62.1506 62.8642 62.2644 62.8799 62.2522C62.8984 62.2486 63.0986 61.8015 63.1229 61.8029C63.1801 61.8145 62.974 62.3152 63.2584 61.862C63.2607 61.8587 63.2591 61.7361 63.2602 61.7332C63.3052 61.6603 63.3313 62.0616 63.36 61.577C63.3324 62.4852 63.4344 61.6999 63.5091 61.8415C63.5419 61.899 63.4923 62.2649 63.4932 62.2676C63.5444 62.2414 63.5336 62.1187 63.5612 62.0827C63.5798 62.0624 63.5571 62.401 63.6014 62.334C63.6294 62.2994 63.6862 61.9413 63.6874 61.9266C63.7333 61.7872 63.7425 61.9664 63.7664 61.9378C63.7841 61.9185 63.807 61.6964 63.8085 61.6907C63.8165 61.6809 63.8408 61.9904 63.8471 62.0573C63.8548 62.1082 63.9042 61.9293 63.9056 61.9638C63.9207 62.1767 63.725 62.5927 63.9483 62.1989C63.9622 62.1746 63.9842 62.0116 63.9858 62.0071C64.0394 61.9115 63.9992 62.2129 64.0175 62.2728C64.0551 62.3772 64.1043 61.9327 64.076 62.3048C64.1634 62.0371 64.184 61.8787 64.1894 61.5513C64.1467 62.4511 64.1924 62.8225 64.3436 61.7851C64.3094 62.1146 64.3872 62.0888 64.3745 62.1892C64.3708 62.2534 64.1823 62.7114 64.4092 62.5337C64.4401 62.5109 64.4695 62.2067 64.4969 62.3087C64.3293 63.0234 64.5277 62.3312 64.5292 62.3297C64.5807 62.3421 64.5067 62.8003 64.3182 63.2615C64.1376 63.7261 63.8389 64.1704 63.755 64.3005C63.5668 64.6077 63.4132 64.9051 63.3587 64.9648C63.1799 65.1576 63.2975 64.9687 63.246 65.0009C63.2053 65.0409 62.7076 65.5992 62.665 65.6106C62.5389 65.6842 62.6252 65.555 62.6114 65.5622C62.467 65.6643 61.6321 66.2055 61.355 66.2756C61.3765 66.3087 61.8909 66.0745 61.5923 66.2702C61.235 66.4921 61.1572 66.3525 61.1469 66.3524C60.583 66.5521 59.9853 66.6532 59.3905 66.6533C58.1298 66.66 56.8637 66.1857 55.9159 65.3537C55.8627 65.4535 56.9116 66.0995 56.9468 66.0907C57.008 66.1537 56.5649 65.9595 56.1401 65.6365C55.7092 65.3213 55.3267 64.8733 55.2595 64.765C55.3696 64.9249 55.4889 65.0794 55.6168 65.2277C55.3057 65.0616 54.9212 64.4099 54.6646 64.0044C54.5772 63.8734 54.6946 64.1534 54.6911 64.1487C54.5692 64.0137 54.464 63.7464 54.6026 63.9136C54.368 63.5494 54.4416 63.5821 54.3227 63.2755C54.3173 63.259 54.3321 63.4064 54.2288 63.1638C54.171 63.0523 54.0079 62.4132 53.9718 62.3293C53.9502 62.2937 53.8817 62.6576 54.0102 62.6709C54.1477 63.3871 54.1222 62.8794 54.2029 63.1473C54.2231 63.1847 54.0969 63.1275 54.4166 63.7611C54.2347 63.6968 54.0322 62.8846 54.0001 62.7504C53.8826 62.4751 54.1747 63.6601 54.39 63.8047C54.262 63.752 54.4116 63.8902 54.5397 64.1233C54.6838 64.3774 54.596 64.2822 54.6805 64.4167C54.9245 64.7772 54.8727 64.5897 55.0456 64.9077C54.969 64.5271 55.446 65.3572 55.6456 65.5693C55.2981 65.2719 54.986 64.9316 54.7185 64.557C54.7254 64.5842 54.7325 64.6114 54.7398 64.6386C54.6707 64.5381 54.605 64.4357 54.5425 64.331C54.5606 64.3428 54.5788 64.3545 54.5969 64.366C54.2197 63.8598 54.2412 63.6731 54.2171 63.6303C53.9562 63.0278 53.7812 62.278 53.7574 61.6178C53.7552 61.553 53.7271 61.5616 53.7214 61.3674C53.7191 61.2967 53.7227 61.1879 53.7388 61.014C53.7538 60.852 53.8007 61.005 53.7937 60.8213C53.6663 60.5915 53.7679 60.5958 53.768 60.5275C53.768 60.3315 53.7365 60.2117 53.7361 60.1935C53.7312 59.9513 53.7365 59.5966 53.7318 59.3305C53.7313 59.3255 53.6922 59.464 53.7038 59.2911C53.7079 59.2304 53.8749 58.6861 53.8205 58.2102C53.8092 58.334 53.7979 58.4577 53.7866 58.5815C53.7971 58.4851 53.7821 58.0051 53.7579 57.7645C53.7454 57.6565 53.7296 57.6038 53.7153 57.6777C53.7106 57.7015 53.7102 57.7313 53.7119 57.7645C53.7198 57.9402 53.7776 58.1988 53.6924 58.2325C53.6999 58.1506 53.7029 57.9793 53.7034 57.7645C53.716 57.1758 53.5902 56.2026 53.5897 56.1015C53.5909 56.0831 53.6382 56.189 53.6393 56.1637C53.6414 56.1441 53.5803 55.7642 53.5837 55.711C53.5867 55.6795 53.633 55.8457 53.6427 55.8301C53.6513 55.8172 53.5863 55.3345 53.5381 55.3147C53.5772 55.4296 53.6161 55.7625 53.5528 55.595C53.545 55.5735 53.5521 55.4536 53.5418 55.4274C53.4483 55.1858 53.5879 55.9325 53.5977 56.0472C53.4852 55.5877 53.4103 54.8488 53.2405 54.3062C53.2211 54.0757 53.371 54.6233 53.3395 54.365C53.2704 53.8274 53.2589 54.2377 53.2506 54.2222C53.1862 54.1023 53.2519 53.6098 53.1117 53.647C53.0801 53.4511 53.1154 53.5076 53.02 53.2437C53.0207 53.2819 53.0213 53.32 53.0217 53.3581C52.8591 53.0847 52.8616 52.3871 52.8909 52.4289C52.9734 52.545 53.0109 52.8966 53.0205 52.9243C53.0345 52.965 53.2136 53.0411 53.2153 53.5343C53.3642 53.6962 53.0711 52.7895 53.2556 53.1875C53.1706 52.9104 52.861 51.7236 52.7585 51.5673C52.7462 51.5489 52.6858 51.6742 52.6342 51.3686C52.6096 51.2232 52.724 51.5547 52.7236 51.4846C52.7355 51.2772 51.7334 48.6215 51.5529 48.0843C51.5412 48.0504 51.5742 48.0531 51.5626 48.0198C51.5267 47.9179 51.3579 47.5566 51.311 47.3658C51.3833 47.7685 51.1345 47.0217 51.0821 46.8256C51.0008 46.5298 51.0581 46.5321 51.0309 46.4019C50.9252 45.9021 50.5972 45.1581 50.6235 44.7347C50.5122 44.7832 50.5258 44.0386 50.4712 43.7135C50.425 43.4597 50.2893 43.0979 50.2991 43.4532C50.2294 43.0081 50.1454 42.5367 50.0989 42.1117C50.0913 42.0413 50.1347 42.1352 50.1208 42.0152C50.1193 42.0044 50.0838 41.9924 50.0718 41.8888C49.9837 41.0345 50.0872 41.4463 50.0984 41.2853C50.1064 41.1944 50.1101 41.1289 50.1106 41.0802C50.1308 41.5804 50.1973 42.1496 50.2153 42.3008C50.2701 42.1663 50.1106 41.2038 50.1331 40.9167C50.1336 40.9068 50.1758 40.9403 50.1759 40.9303C50.1759 40.9301 50.1759 40.9299 50.1759 40.9297C50.1762 40.8836 50.1712 40.7305 50.1646 40.5816C50.1554 40.3865 50.1435 40.1988 50.1135 40.2787C50.1055 40.3005 50.0996 40.416 50.0991 40.5816C50.0987 40.7025 50.1013 40.8497 50.1074 41.0064C50.0956 40.9059 50.051 40.9823 50.0486 40.9645C50.037 40.8756 50.0366 40.7327 50.0429 40.5816C50.0514 40.3663 50.0749 40.1356 50.083 40.0243C50.086 39.9809 50.0561 39.9828 50.0563 39.9757C50.0708 39.8027 50.1521 39.8787 50.0746 39.6963C50.1971 39.39 50.0609 40.2834 50.137 40.2218C50.1567 40.1764 50.3254 38.1883 50.2806 38.174C50.2907 38.1686 50.3065 38.1432 50.3296 38.0886C50.3768 37.9677 50.4947 37.4098 50.5099 37.3082C50.5113 37.2911 50.4312 37.2768 50.436 37.2562C50.4426 37.2041 50.7106 36.5371 50.7739 36.2662C50.7092 36.4007 50.6489 36.5343 50.5913 36.6701C50.8915 35.8317 50.8428 35.9537 50.7016 36.2229C50.6959 36.2369 50.6877 36.2494 50.6822 36.2627C50.5802 36.4736 50.4724 36.7492 50.4654 36.7512C50.4052 36.7581 50.994 35.3177 50.9533 35.627C50.9365 35.6685 50.6263 36.3133 50.8135 36.0083C50.8428 35.9544 51.0253 35.5292 51.0451 35.5104C51.142 35.3818 50.7751 36.3141 50.8845 36.2225C50.923 35.9824 51.0764 35.7097 51.1953 35.4563C51.25 35.3399 51.2308 35.2927 51.2377 35.2783C51.3468 35.0651 51.3174 35.2033 51.3565 35.1338C51.3731 35.0958 51.5599 34.6438 51.6147 34.79C52.5398 33.4733 51.7378 34.3516 51.2629 35.1927C51.3678 34.9047 51.7369 34.4131 51.9156 34.1962C51.9784 34.117 51.9064 34.1347 52.015 34.0005C52.187 33.679 53.6504 32.6675 54.1085 32.581C53.8585 32.7016 53.9532 32.7098 54.1461 32.6274C54.3424 32.5479 54.1547 32.5554 54.1909 32.5344C54.2297 32.4903 55.1925 32.2495 55.348 32.2392C54.632 32.4037 54.8104 32.4056 55.4125 32.3019C55.3268 32.3282 55.2436 32.3561 55.1597 32.3861C55.5003 32.2896 56.2016 32.3043 56.4211 32.2977C56.4275 32.2973 56.4334 32.2967 56.439 32.2961C56.452 32.2947 56.4387 32.2865 56.4211 32.2776C56.3974 32.2663 56.3662 32.2541 56.3761 32.253C56.3889 32.2518 56.4041 32.2508 56.4211 32.2502C56.6266 32.2384 57.0997 32.2965 57.1265 32.289C57.1486 32.2792 56.9138 32.2319 57.0026 32.2218C57.0193 32.2194 57.2505 32.2854 57.4767 32.2992C57.5609 32.3044 57.5148 32.2627 57.5361 32.2631C57.7147 32.269 57.6013 32.3117 57.927 32.3533C58.1637 32.3866 58.3511 32.3615 58.6717 32.4629C57.6165 32.1515 58.5157 32.3614 58.9631 32.4736C59.0346 32.4928 58.9966 32.4044 59.4077 32.5774C58.4744 32.3989 59.6448 32.7083 59.8672 32.8225C59.8795 32.8283 59.8674 32.8693 59.9772 32.9178C59.9865 32.922 59.9848 32.8888 60.0881 32.9329C61.0537 33.3817 60.4264 33.1131 60.5936 33.2283C60.6651 33.2763 61.1281 33.4999 61.2427 33.5781C61.2693 33.5954 61.2409 33.6124 61.3432 33.6793C61.5238 33.7979 61.6985 33.8862 61.8134 33.9706C61.8263 33.9811 61.7998 34.0171 62.0187 34.173C62.0799 34.2171 62.1558 34.2581 62.0819 34.1793C61.8371 33.9131 61.2357 33.5816 60.9037 33.3418C60.6051 33.111 61.6133 33.7252 61.6514 33.7756C61.6697 33.7883 61.47 33.6746 61.6559 33.8137C61.8136 33.9315 62.1514 34.0897 62.3608 34.2977C62.3777 34.3132 62.5049 34.5214 62.4936 34.5174C62.4854 34.5118 62.207 34.2871 62.2325 34.3372C62.2361 34.3425 62.4066 34.4917 62.4178 34.5232C62.4328 34.5614 62.3813 34.7588 62.4119 34.794C62.4919 34.8849 62.4632 34.8011 62.5178 34.8572C62.6392 34.9758 62.9948 35.4315 63.0511 35.406C62.9902 35.3324 62.9283 35.2596 62.8653 35.1876C63.2308 35.5737 63.0952 35.3914 63.1552 35.4391C63.2183 35.4922 63.1626 35.5103 63.2737 35.6493C63.303 35.6763 63.7682 36.2541 63.7745 36.2327C63.5002 35.9261 63.6435 36.0079 63.6337 35.9915C63.5933 35.9318 63.5064 35.8825 63.446 35.8066C63.0141 35.2772 63.5016 35.768 63.4102 35.6343C63.3785 35.5878 63.2817 35.5241 63.2675 35.5052C63.2214 35.4435 63.2524 35.4146 63.2156 35.3779C63.1295 35.2926 63.178 35.4382 63.1691 35.433C63.0719 35.3763 62.8184 35.0368 63.0456 35.1845C62.9547 35.0521 62.8844 35.0942 62.8195 34.9818C62.6875 34.7587 62.9418 35.0378 63.0174 35.1056C63.2926 35.3489 63.3443 35.4481 63.6718 35.8424C63.788 35.9841 63.9481 36.1366 63.9996 36.2051C64.0357 36.2485 64.2056 36.7369 64.3883 36.636C64.48 36.8128 64.521 37.1448 64.6252 37.3138C64.7189 37.4652 64.7553 37.3798 64.7661 37.3927C64.783 37.4126 64.8828 37.605 64.9262 37.665C64.9775 37.7349 64.983 37.6839 65.0562 37.7991C65.2366 38.0874 65.1618 38.1146 65.1731 38.1475C65.2954 38.5342 65.3162 38.3296 65.3623 38.4068C65.4147 38.4766 65.8192 39.5624 65.9142 39.7846C65.867 39.6965 65.819 39.6089 65.7703 39.5219C65.7876 39.7032 65.9218 39.8536 65.8426 39.8848C65.9848 39.8732 66.0137 40.2477 66.0485 40.3503C66.0627 40.3908 66.0841 40.3806 66.101 40.4317C66.1687 40.6307 66.2773 41.0908 66.3158 41.1978C66.4911 41.6618 66.2492 40.4208 66.2127 40.3245C66.2802 40.5132 66.5972 41.5984 66.529 41.079C66.5184 40.9982 66.4215 40.8767 66.4069 40.834C66.3082 40.5441 66.4269 40.7602 66.4254 40.7358C66.4226 40.694 66.3148 40.5154 66.3051 40.4629C66.3016 40.4453 66.384 40.5404 66.2977 40.2599C66.3925 40.3822 66.5771 41.1867 66.6094 41.2889C66.6207 41.3253 66.6708 41.066 66.731 41.7747C66.7386 41.7647 66.7462 41.7547 66.7538 41.7446C66.8427 42.1261 66.9194 42.5098 66.984 42.8966C66.9557 42.8578 66.877 42.6485 66.9299 42.9197C66.9595 43.0759 66.9902 42.9523 66.9938 42.9664C67.0303 43.0708 67.2147 44.5803 67.2052 45.5099C67.2081 45.7918 67.2048 46.0062 67.2037 46.1252C67.2039 46.2928 67.2226 46.7602 67.22 46.7964C67.2166 47.0071 67.1212 47.765 67.1045 47.9122C67.0965 48.0074 67.1484 47.9224 67.1359 48.0068C67.1241 48.0849 67.095 47.9987 67.0904 48.0217C67.0672 48.2124 66.859 49.6643 66.728 49.9805C66.7951 49.7842 66.9217 48.7361 66.8843 48.7497C66.88 48.7543 66.8051 49.0009 66.8095 49.0541C66.7601 49.1328 66.8041 49.4453 66.7483 49.5995C66.7419 49.6163 66.7009 49.5358 66.6267 49.8112C66.601 49.9063 66.5858 50.1668 66.4706 50.4027C66.408 50.7897 65.7881 52.5333 65.8209 52.6461C65.8229 52.6507 65.916 52.4198 65.8919 52.5876C65.8607 52.8095 65.8067 52.5863 65.7235 52.8288C65.7082 52.8682 65.5289 53.5387 65.5334 53.5595C65.5424 53.7751 65.7241 53.2083 65.7313 53.2169C65.742 53.244 65.6227 53.7232 65.6154 53.7396C65.6059 53.7574 65.6231 53.3497 65.5345 53.8205C65.5579 53.7703 65.5815 53.7202 65.6054 53.6699C65.5683 53.8915 65.5066 53.8972 65.4899 53.949C65.4393 54.1088 65.487 54.301 65.3263 54.5352C65.2838 54.5969 65.2735 54.4786 65.2676 54.4857C65.2119 54.56 65.2971 54.6832 65.1971 54.7925C65.1905 54.8006 65.1898 54.5061 65.1074 55.0066C65.1203 54.9731 65.1333 54.9398 65.1465 54.9066C65.1486 54.9809 65.0917 55.4861 65.0839 55.5531C65.0528 55.7512 65.0139 55.5737 65.0032 55.7732C65.086 55.6514 65.0563 56.2582 64.9966 56.2219C65.0404 56.274 65.0339 56.4547 65.0251 56.6559C65.0181 56.832 65.0057 57.0156 65.0048 57.1386C65.0037 57.3164 65.0392 57.6792 65.035 57.7357C65.0299 57.8045 64.9744 57.7836 64.962 57.9079C64.9585 57.9433 64.9992 58.3133 64.9417 58.6381C64.9307 58.701 64.8365 58.8332 64.8129 58.7162C64.7727 58.516 64.8485 58.1372 64.7929 58.142C64.7333 58.1477 64.7688 58.6579 64.761 58.7952C64.725 59.4292 64.6618 59.0631 64.6426 59.0794C64.596 59.1217 64.5975 59.4681 64.5933 59.4826C64.5747 59.5425 64.5378 59.297 64.5094 59.2933C64.4724 59.2888 64.4056 59.6227 64.3932 59.5468C64.3755 59.4381 64.4311 59.1313 64.4285 59.1118C64.3926 58.8586 64.3071 59.2057 64.2651 59.3014C64.2522 59.3304 64.2309 59.2148 64.2272 59.2389C64.1697 59.6059 64.3473 59.3162 64.3354 59.5604C64.3248 59.7782 64.2687 59.498 64.2656 59.5063C64.2622 59.517 64.2591 59.7775 64.2392 59.8183C64.2293 59.8384 64.12 59.1614 64.071 59.1897C64.0818 59.4057 64.0926 59.6217 64.1034 59.8377C64.0396 59.8546 64.0866 59.5439 64.08 59.5118C64.0668 59.4471 64.0345 59.6275 64.0143 59.6197C64.0014 59.6156 63.9556 59.4039 63.9367 59.5951C63.9302 59.6609 63.9749 59.7988 63.9292 60.0382C63.8708 59.2051 63.8349 59.7824 63.8122 59.807C63.7896 59.831 63.7364 59.4333 63.7458 59.9161C63.6215 59.937 63.7065 59.9057 63.6846 59.7685C63.6578 59.6004 63.6168 59.9889 63.6479 59.3746C63.5897 59.4095 63.5938 59.9033 63.5892 59.9294C63.585 59.952 63.5563 59.8422 63.5466 59.8814C63.4342 60.3442 63.4855 60.0263 63.4137 60.1604C63.4073 60.1723 63.3807 60.6097 63.3702 60.2767C63.3512 59.67 63.4337 59.4164 63.2574 59.3144C63.1808 59.7632 63.2946 60.307 63.2965 60.4434C63.2993 60.6522 63.2633 60.4359 63.2533 60.4616C63.25 60.4706 63.253 60.6505 63.2501 60.6529C63.1157 60.7812 63.2479 59.8519 63.2245 59.5592C63.2044 59.6377 63.1842 59.7161 63.1641 59.7945C63.1633 59.6881 63.1625 59.5817 63.1617 59.4753C63.1212 59.9822 63.1464 59.4932 63.0375 59.3668C63.013 59.3384 63.055 59.6714 62.987 59.2915C62.9713 59.5717 62.949 59.4824 62.9797 59.7361C62.9361 59.7295 62.8868 59.1587 62.8644 58.9335C62.8154 59.7289 62.9755 59.2754 62.8908 59.963C62.9448 60.0905 62.9343 59.7623 62.9432 59.789C62.9753 59.8851 62.9244 60.1102 63.0367 60.3818C63.0552 60.426 63.112 60.2389 63.1092 60.5158C63.1089 60.5464 63.0603 60.7228 63.0568 60.7204C63.0188 60.697 63.033 60.5224 63.0172 60.5152C63.0022 60.5084 63.0112 60.7032 63.007 60.7039C62.9594 60.7099 62.9888 60.5413 62.9739 60.5658C62.9415 60.6187 62.839 61.3193 62.869 60.4049C62.9229 61.1644 62.9216 60.5022 62.9009 60.2064C62.8957 60.1309 62.8673 60.1118 62.8574 60.0044C62.8447 59.8661 62.8583 59.7043 62.8531 59.6328C62.8473 59.5558 62.7801 59.993 62.8002 59.3607C62.7333 59.6825 62.8046 60.2509 62.7576 60.567C62.6627 61.2047 62.6424 60.1223 62.6332 60.0096C62.6307 59.9795 62.5923 60.0802 62.5899 60.0602C62.5863 60.0275 62.6041 59.4132 62.5723 59.3526C62.5405 59.2922 62.5737 59.5776 62.5406 59.5966C62.5183 59.6094 62.4788 58.8684 62.4635 59.2696C62.4531 59.546 62.5427 60.0557 62.4464 60.1415C62.4384 59.7349 62.4304 59.3283 62.4224 58.9217C62.3858 59.1442 62.3491 59.3668 62.3125 59.5893C62.3009 59.133 62.3422 58.7384 62.2898 58.3049C62.1723 59.3465 62.196 57.9667 62.1818 57.9516C62.1732 57.9465 62.0779 58.3565 62.0604 58.4224C62.0238 58.0592 62.0058 56.9552 61.8881 57.6011C61.9147 57.4839 61.8491 57.2 61.8442 57.2037C61.7922 57.2398 61.8259 57.8589 61.7789 57.758C61.7244 57.6409 61.7983 57.477 61.7924 57.2969C61.7816 56.9715 61.7409 56.7922 61.6946 56.6559C61.6128 56.3697 61.4997 56.2478 61.5746 55.5615C61.5633 55.5818 61.5521 55.6022 61.541 55.6227C61.636 54.4677 61.8941 53.3309 62.2041 52.3027C62.2373 51.8671 62.5105 50.8287 62.6572 50.3679C62.6889 50.2713 62.8633 49.8237 62.8788 49.7926C62.9111 49.7325 62.8172 50.0856 62.8886 49.9337C62.9075 49.9004 63.127 49.1376 63.0646 49.1832C63.0394 49.2659 62.9925 49.5403 62.9698 49.5813C62.8452 49.8585 63.4126 47.5588 63.3458 47.4379C63.3246 47.4881 63.3032 47.5377 63.2815 47.5868C63.3082 47.4406 63.3321 47.2986 63.354 47.1515ZM65.2813 55.0902C65.3144 55.1806 65.2512 55.3917 65.2514 55.5176C65.2494 55.6965 65.408 56.0014 65.238 55.8619C65.2427 55.6069 65.2575 55.3469 65.2813 55.0902ZM66.4194 51.0771C66.3357 51.2755 66.2858 51.0896 66.3743 50.9306C66.3839 50.9136 66.532 50.8053 66.4194 51.0771ZM65.759 53.1026C65.7598 53.0946 65.8092 52.936 65.8125 52.9307C65.893 52.7993 65.7444 53.2767 65.759 53.1026ZM66.7622 42.1556C66.814 42.3978 66.8698 42.2043 66.8021 42.06C66.7978 42.0509 66.7589 42.1397 66.7622 42.1556ZM66.7935 42.3289C66.7497 42.5315 66.9763 42.8851 66.9082 42.5841C66.9019 42.5547 66.7961 42.3192 66.7935 42.3289ZM66.1665 51.7864C66.1433 51.7554 66.2204 51.5538 66.254 51.4672C66.2807 51.478 66.1893 51.7002 66.1665 51.7864ZM67.1649 46.0803C67.1445 46.0715 67.1147 46.8781 67.139 46.9335C67.1374 46.8073 67.1899 46.0914 67.1649 46.0803ZM67.0518 44.0141C67.0501 44.0349 67.0804 44.3115 67.101 44.3018C67.1191 44.164 67.0622 43.9203 67.0518 44.0141ZM66.2086 39.9955C66.1978 39.983 66.1367 40.2249 66.0604 39.7261C66.0488 39.6525 66.1692 39.8874 66.1651 39.8613C66.1566 39.8067 66.1466 39.7645 66.1358 39.7315C66.2241 39.9471 66.3027 40.1751 66.3018 40.1999C66.2976 40.3161 66.2136 40.001 66.2086 39.9955ZM65.2864 38.014C65.2454 37.9802 65.1163 37.7005 65.0904 37.6339C65.0861 37.6223 65.1638 37.6414 65.0934 37.5196C65.0363 37.4224 65.0638 37.5987 64.9669 37.4022C64.8675 37.2043 65.0496 37.4414 65.0426 37.4234C65.0345 37.3979 64.8413 37.1133 64.8762 37.105C64.9039 37.0984 65.0704 37.4278 65.1173 37.506C65.1787 37.6055 65.1508 37.4599 65.2338 37.6369C65.2852 37.7479 65.1858 37.7231 65.1943 37.7477C65.2026 37.7674 65.431 38.1282 65.2863 38.0133C65.2863 38.0136 65.2863 38.0138 65.2864 38.014ZM66.1117 39.6732C66.12 39.6888 66.1281 39.7078 66.1358 39.7315C66.1279 39.7119 66.1197 39.6924 66.1117 39.6732ZM65.3337 54.5851C65.3742 54.4996 65.3523 54.7725 65.3059 54.8673C65.2801 54.8659 65.3266 54.5983 65.3337 54.5851ZM65.9795 39.4918C65.8755 39.1625 65.9924 39.3891 66.1117 39.6732C66.0652 39.5861 66.0135 39.6026 65.9795 39.4918ZM66.8095 49.0541C66.8178 49.0411 66.8282 49.0338 66.8428 49.0354C66.8201 49.0695 66.811 49.0711 66.8095 49.0541ZM66.967 48.268C66.9616 47.9909 66.884 48.5433 66.9141 48.5446C66.9266 48.5458 66.9678 48.2784 66.967 48.268ZM66.7017 41.844C66.7023 41.8691 66.4899 41.5195 66.706 42.0476C66.6599 41.7506 66.7395 42.0575 66.7498 42.0507C66.7821 42.0317 66.642 41.544 66.6279 41.4321C66.549 41.3608 66.6995 41.7598 66.7015 41.8433C66.7016 41.8435 66.7016 41.8438 66.7017 41.844ZM62.9876 34.683C63.0656 34.7102 63.2205 34.8862 63.3245 35.004C63.2489 34.9733 63.099 34.7967 62.9876 34.683ZM53.6924 59.1233C53.6596 58.2168 53.8042 58.0994 53.747 58.9288C53.7458 58.945 53.7071 59.1783 53.6924 59.1233ZM52.6162 52.018C52.6502 51.9199 52.7456 52.1763 52.7749 52.3537C52.7817 52.3941 52.7658 52.5551 52.7024 52.397C52.777 52.3791 52.7241 52.1191 52.6162 52.018ZM65.8731 39.324C65.7987 39.2454 65.7119 38.9474 65.6531 38.7951C65.7246 38.8727 65.8348 39.1848 65.8731 39.324ZM53.6852 56.3345C53.6804 56.2492 53.6187 56.1983 53.616 56.2136C53.6035 56.2815 53.6649 56.4343 53.6852 56.3345ZM66.1949 40.2634C66.1761 40.2838 66.0265 39.9063 66.0748 39.8596C66.0997 39.943 66.2075 40.2489 66.1949 40.2634ZM63.1809 34.9094C63.2183 34.9666 62.961 34.7303 62.8929 34.6477C62.9186 34.6338 63.1581 34.871 63.1809 34.9094ZM53.4475 54.9656C53.4369 54.8881 53.397 54.696 53.3704 54.6795C53.338 54.6593 53.4075 54.9376 53.4475 54.9656ZM63.1726 65.4875C63.1939 65.4858 62.8854 65.8507 62.6992 65.9554C62.3614 66.1632 63.1712 65.5094 63.1726 65.4875ZM53.7796 57.1333C53.7389 57.3746 53.7769 57.107 53.7223 57.1204C53.7305 57.2814 53.7362 57.6765 53.7834 57.4026C53.7924 57.3492 53.7802 57.2086 53.7796 57.1333ZM53.7847 56.9118C53.7653 56.8872 53.6964 56.7201 53.7115 56.8679C53.7185 56.936 53.7877 57.043 53.7847 56.9118ZM60.6405 66.8452C60.467 66.8566 60.7689 66.7959 61.107 66.6876C61.4468 66.5832 61.8155 66.4164 61.837 66.4095C61.8605 66.403 61.8764 66.3999 61.886 66.3991C61.9322 66.3614 62.1902 66.2175 62.2389 66.2318C62.161 66.2756 61.9471 66.3933 61.9192 66.4011C61.9075 66.405 61.8985 66.4075 61.8921 66.4087C61.8247 66.5146 60.7127 66.8687 60.6405 66.8452ZM58.0701 66.7771C58.4638 66.7951 58.5116 66.9143 58.478 66.9153C58.0469 66.8873 58.3396 66.8493 58.3268 66.8434C58.2995 66.8332 57.9943 66.8058 58.0713 66.7774C58.0709 66.7773 58.0705 66.7772 58.0701 66.7771ZM60.1114 66.919C60.1272 66.9178 60.4527 66.8688 60.4658 66.8658C60.7409 66.8624 59.8152 66.9992 60.1114 66.919ZM64.3885 36.6089C64.2934 36.443 64.4348 36.5742 64.4897 36.6902C64.4938 36.6997 64.4712 36.7559 64.3885 36.6089ZM53.764 56.7951C53.777 56.7611 53.7078 55.8774 53.6424 55.9394C53.6703 56.0143 53.7319 57.0118 53.764 56.7951ZM52.0428 50.09C52.1003 50.2534 51.9769 50.097 51.9682 50.0017C51.965 49.9664 52.0282 50.0489 52.0428 50.09ZM66.2963 40.8032C66.3839 40.9858 66.2594 40.9773 66.2517 40.8006C66.2513 40.7937 66.2929 40.796 66.2963 40.8032ZM52.4618 51.3953C52.2331 50.8531 52.473 50.9192 52.6531 51.6617C52.637 51.6421 52.6209 51.6225 52.6047 51.6029C52.8522 52.4407 52.6118 51.6647 52.5307 51.4646C52.5002 51.3886 52.4903 51.4644 52.4617 51.3959C52.4618 51.3957 52.4618 51.3955 52.4618 51.3953ZM51.739 49.2244C51.6799 48.6265 51.9635 49.7081 52.0868 49.9969C51.9282 49.7285 51.8022 49.348 51.9275 49.8809C51.6495 49.1351 51.8144 49.4272 51.8083 49.3961C51.8007 49.3587 51.7414 49.2499 51.739 49.2244ZM52.2492 50.658C52.2642 50.6878 52.3188 50.9314 52.3524 51.0138C52.2655 50.9127 52.1495 50.461 52.2492 50.658ZM55.6722 65.5554C55.7207 65.5455 55.7895 65.5758 55.999 65.7583C55.919 65.7216 55.7704 65.6215 55.6722 65.5554ZM65.0578 55.2248C65.0385 55.3437 64.9993 55.5759 65.0472 55.5085C65.0506 55.5012 65.0795 55.2284 65.0578 55.2248ZM53.3674 54.2235C53.3684 54.1965 53.1924 53.5142 53.2134 53.7605C53.2224 53.8349 53.3804 54.4512 53.3674 54.2235ZM53.8286 57.7053C53.8293 57.6495 53.8175 57.4237 53.8078 57.4193C53.7766 57.4049 53.7991 57.6808 53.8286 57.7053ZM64.9561 55.8181C64.9493 55.8337 64.9356 56.1976 64.9572 56.1585C64.9944 56.0852 64.9732 55.7656 64.9561 55.8181ZM63.9193 36.0911C63.8945 36.0598 63.8962 35.9923 63.8882 35.9809C63.8742 35.9519 63.3963 35.386 63.6161 35.5718C63.6642 35.5982 64.2791 36.4621 64.3389 36.5844C64.3211 36.6593 64.1161 36.2578 64.0445 36.1724C64.0322 36.1573 63.9863 36.1751 63.9197 36.0913C63.9196 36.0912 63.9194 36.0912 63.9193 36.0911ZM56.8974 66.3381C56.9411 66.3468 57.9286 66.694 57.9125 66.7117C57.5634 66.6209 57.2226 66.4955 56.8974 66.3381ZM56.4338 66.0694C56.2581 65.9281 56.7055 66.2013 56.8408 66.2766C56.8295 66.3026 56.4573 66.0937 56.4338 66.0694ZM53.8936 56.4271C53.8778 56.3604 53.8461 56.574 53.831 56.5284C53.8219 56.4993 53.8259 56.3462 53.8036 56.2999C53.797 56.287 53.7643 56.446 53.7706 56.49C53.7798 56.5527 53.8129 56.4877 53.8199 56.5566C53.8426 56.7862 53.8286 56.9894 53.8392 57.203C53.8402 57.2224 53.861 57.0711 53.8682 57.2361C53.8692 57.2621 53.8348 57.4149 53.8434 57.6106C53.8597 57.6632 53.8719 57.7143 53.8807 57.7645C53.9445 58.171 53.8524 58.5141 53.893 59.0588C53.9051 59.0353 53.9375 58.5715 53.9387 58.5442C53.9472 58.334 53.9527 58.0565 53.9562 57.7645C53.9621 57.3817 53.9405 56.9707 53.9151 56.6807C53.9042 56.5553 53.8825 56.6186 53.8765 56.5648C53.8716 56.5223 53.927 56.5681 53.8936 56.4271ZM65.0388 55.1583C64.9809 55.2076 64.9869 55.4114 64.9718 55.537C65.021 55.4971 65.01 55.2807 65.0388 55.1583ZM53.9425 62.2314C53.9219 62.1312 53.904 61.8153 53.889 61.7906C53.8628 61.7581 53.9007 62.2162 53.9425 62.2314ZM60.8033 33.2486C60.7956 33.245 60.6096 33.1399 60.603 33.1353C60.4543 33.0078 61.0129 33.3249 60.8033 33.2486ZM55.8693 32.1247C55.6948 32.1444 55.5261 32.1825 55.4589 32.1511C55.5748 32.1385 55.886 32.0937 55.8693 32.1247ZM50.4552 36.8258C50.5136 36.8105 50.347 37.2543 50.3233 37.3397C50.3056 37.3022 50.4084 36.8371 50.4552 36.8258ZM55.7539 65.4038C56.0057 65.6284 56.0036 65.5168 56.1484 65.676C56.173 65.7001 56.16 65.9094 55.9041 65.6256C55.861 65.5732 56.0823 65.7136 55.7539 65.4038ZM52.6908 51.7792C52.7435 51.8256 52.7933 52.0089 52.8299 52.1308C52.7963 52.1119 52.7223 51.865 52.6908 51.7792ZM64.8854 56.4756C64.869 56.5077 64.861 56.5779 64.8598 56.6559C64.8574 56.8406 64.8816 57.0584 64.904 56.9687C64.9067 56.9573 64.898 56.7969 64.8912 56.6559C64.8868 56.5744 64.8843 56.5014 64.8854 56.4756ZM65.4606 38.7403C65.3273 38.533 65.5179 38.9987 65.6106 39.1319C65.5823 39.0658 65.4705 38.7545 65.4606 38.7403ZM51.1427 35.2707C51.1363 35.2829 50.9983 35.5379 50.9922 35.5489C50.8448 35.742 51.2386 35.0169 51.1427 35.2707ZM57.5581 32.2368C57.4559 32.2507 56.8055 32.1745 56.6597 32.1449C56.8011 32.0893 57.6891 32.2048 57.5581 32.2368ZM54.8336 64.3687C54.9681 64.5693 55.099 64.7572 55.2333 64.9351C55.175 64.9227 54.8231 64.4052 54.8336 64.3687ZM50.7016 36.2229C50.6959 36.2369 50.6877 36.2494 50.6822 36.2627C50.6887 36.2491 50.6953 36.2359 50.7016 36.2229ZM53.9529 59.7478C53.9636 59.6009 53.9138 59.6314 53.9123 59.6405C53.8962 59.751 53.9408 59.9142 53.9529 59.7478ZM64.9462 55.2947C64.8954 55.3354 64.9056 55.5522 64.8843 55.6773C64.9223 55.6435 64.9375 55.3957 64.9462 55.2947ZM51.618 48.6024C51.6021 48.4098 51.9072 49.1102 51.9311 49.2696C51.9066 49.2916 51.6204 48.6316 51.618 48.6024ZM65.6817 39.4629C65.6553 39.4901 65.8141 39.8009 65.8045 39.7263C65.7991 39.6785 65.6991 39.4458 65.6817 39.4629ZM52.0389 49.634C52.0727 49.697 52.0952 49.8636 52.0558 49.8161C52.0053 49.7552 52.0299 49.6178 52.0389 49.634ZM53.7899 55.4499C53.7915 55.4209 53.6863 55.0516 53.6798 55.2135C53.6752 55.3254 53.7281 55.3333 53.7328 55.3586C53.7395 55.387 53.7753 55.9989 53.7899 55.4499ZM50.4119 44.382C50.4602 44.5431 50.4894 44.7433 50.5309 44.9128C50.4924 44.8492 50.3977 44.4583 50.4119 44.382ZM65.1427 38.2309C65.1571 38.2721 65.6057 39.326 65.3871 38.7113C65.3771 38.6742 65.1277 38.096 65.1427 38.2309ZM55.7539 65.4038C55.7226 65.375 55.6877 65.3406 55.649 65.299C55.6888 65.3388 55.7234 65.3738 55.7539 65.4038ZM54.0092 62.0836C54.0429 62.1567 54.0041 61.7706 53.9886 61.6561C53.9516 61.6227 53.9996 62.074 54.0092 62.0836ZM50.5688 44.9174C50.6062 45.0116 50.6345 45.1917 50.667 45.311C50.6382 45.297 50.5547 44.9655 50.5688 44.9174ZM50.3498 37.6997C50.2882 37.9064 50.2474 38.1669 50.2757 38.1755C50.2704 38.179 50.2638 38.1883 50.2561 38.2042C50.2479 38.2203 50.2233 38.4473 50.1996 38.5428C50.0101 39.1193 50.6335 36.2788 50.3529 37.9428C50.3509 37.8621 50.3498 37.7816 50.3498 37.6997ZM58.4239 32.4575C58.5414 32.5184 58.8949 32.5683 58.8099 32.531C58.7519 32.5016 58.3069 32.393 58.4239 32.4575ZM53.4211 33.0343C53.4587 33.0151 53.7956 32.8088 53.798 32.7907C53.5822 32.8678 53.2372 33.1101 53.4211 33.0343ZM59.3516 32.7685C59.4244 32.7996 59.5398 32.7818 59.5321 32.7763C59.4625 32.727 59.2359 32.6944 59.3516 32.7685ZM55.3841 64.8047C55.3071 64.6971 55.022 64.3849 54.9418 64.3249C54.9383 64.3064 54.9202 64.2625 54.8846 64.1843C54.8847 64.1846 54.8849 64.1848 54.885 64.185C54.852 64.1388 54.4208 63.3569 54.2811 62.7844C54.2014 62.5028 54.1639 62.2886 54.155 62.2904C54.1517 62.2909 54.1516 62.513 54.3137 63.0732C54.3361 63.1425 54.3309 63.0392 54.43 63.3173C54.4368 63.3355 54.4144 63.3549 54.4362 63.4114C54.4739 63.5467 54.8069 64.213 54.9198 64.318C54.9162 64.3218 54.9174 64.3326 54.925 64.3521C54.9886 64.5346 55.4406 64.8956 55.3841 64.8047ZM52.7856 33.4795C52.8517 33.4375 53.0461 33.282 53.0544 33.248C52.9422 33.3066 52.6284 33.5752 52.7856 33.4795ZM65.0678 38.3065C65.1075 38.4332 65.2783 38.7207 65.2551 38.6209C65.2426 38.5587 65.0233 38.1592 65.0678 38.3065ZM55.0061 32.4021C54.1232 32.606 54.7982 32.4572 54.6742 32.5271C54.7857 32.4814 54.8939 32.4405 55.0061 32.4021ZM59.0573 66.7293C58.9105 66.7105 59.0884 66.6547 59.2464 66.697C59.2967 66.7105 59.1404 66.7395 59.0573 66.7293ZM64.3411 63.3978C64.2402 63.4919 64.4881 62.9322 64.4467 63.1705C64.4455 63.1819 64.3477 63.3912 64.3411 63.3978ZM61.0279 66.4347C60.9455 66.5048 60.8845 66.5341 60.6069 66.59C61.0092 66.4745 60.6261 66.5415 61.0279 66.4347ZM50.2806 38.174C50.2787 38.1751 50.2772 38.176 50.2757 38.1755C50.2775 38.1742 50.2791 38.1739 50.2806 38.174ZM60.0674 33.0456C60.1463 33.1199 60.402 33.2444 60.3424 33.1742C60.3372 33.1668 60.1174 33.0379 60.0674 33.0456ZM54.9418 64.3249C54.9449 64.3413 54.937 64.3371 54.9198 64.318C54.9231 64.3143 54.9306 64.3173 54.9418 64.3249ZM58.6105 32.564C58.6285 32.5381 58.2031 32.4304 58.1866 32.4331C57.9342 32.4315 58.4358 32.5171 58.6105 32.564ZM65.9671 40.7849C65.9755 40.8038 66.0056 40.6574 65.9558 40.5876C65.9174 40.5338 65.9358 40.7144 65.9671 40.7849ZM61.896 66.0461C62.0335 65.9737 62.2187 65.8591 62.2704 65.8644C62.181 65.919 61.9053 66.0707 61.896 66.0461ZM64.2034 63.5993C64.1646 63.7836 63.9613 64.1562 63.8012 64.372C63.7642 64.3526 64.1531 63.7682 64.2034 63.5993ZM55.6549 65.124C55.6446 65.1158 55.393 64.822 55.4041 64.8825C55.4154 64.9771 55.7192 65.2161 55.6549 65.124ZM65.8214 40.1891C65.7548 40.0628 65.7878 40.3927 65.8841 40.5181C65.9347 40.5827 65.8337 40.2102 65.8214 40.1891ZM60.8344 33.4992C61.0195 33.5848 60.6027 33.2999 60.5212 33.3014C60.603 33.3475 60.7694 33.4684 60.8344 33.4992ZM54.0365 32.8244C54.732 32.6584 54.31 32.6247 54.1939 32.6849C54.1771 32.693 54.0194 32.8285 54.0365 32.8244ZM64.6774 57.7909C64.6917 57.8673 64.7438 57.5827 64.7095 57.5458C64.6881 57.5231 64.6682 57.7421 64.6774 57.7909ZM50.1106 41.0802C50.1094 41.0554 50.1084 41.0308 50.1074 41.0064C50.1096 41.0247 50.1108 41.0487 50.1106 41.0802ZM62.2055 34.6767C61.9743 34.279 61.93 34.398 61.9029 34.3729C61.8407 34.3196 61.7149 34.1691 61.5853 34.0815C61.7385 34.1747 61.8895 34.273 62.0367 34.3747C61.952 34.2613 60.9652 33.5029 60.9172 33.5252C60.8688 33.5334 61.206 33.7319 61.2127 33.7424C61.2242 33.7551 61.2227 33.8666 61.2501 33.8896C61.3049 33.9169 62.1115 34.5409 62.2055 34.6767ZM55.4409 32.4066C55.3296 32.4125 55.2921 32.382 55.2429 32.3999C55.226 32.4062 55.2305 32.4411 55.1728 32.4618C55.2622 32.4413 55.3505 32.423 55.4409 32.4066ZM62.8555 35.124C62.9109 35.2416 62.5359 34.836 62.5235 34.8225C62.4757 34.7343 62.8138 35.0252 62.8555 35.124ZM58.811 32.6499C58.8298 32.6548 59.2472 32.7992 59.2499 32.7776C59.1474 32.7175 58.5818 32.5526 58.811 32.6499ZM55.0994 32.4794C54.934 32.5074 54.6153 32.5616 54.6656 32.6035C54.6658 32.6034 54.6661 32.6033 54.6663 32.6032C54.8119 32.5554 54.9528 32.5152 55.0994 32.4794ZM65.5573 39.7697C65.5649 40.0441 65.6259 39.8919 65.5718 39.6643C65.5116 39.6116 65.5558 39.7247 65.5573 39.7697ZM65.761 40.58C65.7717 40.6523 65.9852 41.3632 65.9975 41.2431C66.004 41.1996 65.8504 40.7978 65.8467 40.7785C65.8425 40.7485 65.9293 40.8658 65.8547 40.6491C65.8425 40.6667 65.7587 40.5548 65.761 40.58ZM65.5783 39.9914C65.601 40.2561 65.7312 40.2742 65.6698 40.0893C65.6456 40.017 65.5749 39.9535 65.5783 39.9914ZM65.2074 38.9993C65.2339 39.0897 65.313 39.3256 65.4113 39.4716C65.3317 39.2558 65.2476 39.0422 65.1581 38.8294C65.1269 38.814 65.1848 38.9202 65.2076 38.9998C65.2075 38.9997 65.2074 38.9995 65.2074 38.9993ZM64.3778 61.7194C64.3281 61.9549 64.3503 61.4069 64.3516 61.3836C64.3802 61.3144 64.403 61.6125 64.3778 61.7194ZM63.5952 59.2768C63.5818 59.3296 63.5374 59.3642 63.5607 59.4805C63.5934 59.3635 63.6261 59.2465 63.6588 59.1295C63.5838 59.0385 63.6101 59.219 63.5952 59.2768ZM63.3214 59.7236C63.3196 59.7071 63.2044 59.7974 63.2813 59.5839C63.3332 59.4396 63.3839 60.2242 63.3328 60.3658C63.309 60.2093 63.3362 59.8659 63.3214 59.7236ZM62.8226 61.098C62.8134 61.1071 62.8 60.809 62.8064 60.7745C62.8406 60.5933 62.8719 61.0491 62.8226 61.098ZM62.8446 60.147C62.8222 60.2868 62.8078 59.9771 62.8207 59.8848C62.8421 59.8759 62.8479 60.1254 62.8446 60.147ZM62.2178 63.1278C62.085 63.1914 62.1584 63.3811 62.2408 63.1965C62.2448 63.1875 62.224 63.1251 62.2178 63.1278ZM62.7064 60.8066C62.7288 60.6668 62.7432 60.9765 62.7303 61.0688C62.7089 61.0774 62.7031 60.8279 62.7064 60.8066ZM62.0137 63.1001C61.8782 63.1994 62.0626 63.2627 62.0816 63.2497C62.1596 63.1974 62.2474 62.9053 62.254 62.8448C62.068 63.237 62.0739 63.0493 62.0137 63.1001ZM61.6167 63.7446C61.5175 63.8663 61.8337 63.6197 61.8397 63.5234C61.792 63.5838 61.6454 63.7117 61.6167 63.7446ZM60.8288 64.2229C60.7541 64.256 60.5284 64.3338 60.4999 64.3737C60.5814 64.3407 60.8126 64.2677 60.8288 64.2229ZM60.6276 64.2189C60.4997 64.2291 60.515 64.3497 60.6345 64.262C60.6392 64.2586 60.6326 64.2192 60.6276 64.2189ZM59.9617 64.3795C59.8767 64.3478 59.8024 64.4742 59.9331 64.4562C59.972 64.4501 59.971 64.3832 59.9617 64.3795ZM61.7359 63.1402C61.6544 63.2136 61.6252 63.3776 61.7818 63.1965C61.7405 63.2708 61.6958 63.3439 61.6478 63.4153C61.8926 63.2041 61.7798 63.1461 61.8369 63.0785C61.9128 62.9801 61.9851 63.037 61.9955 63.0754C62.0123 62.9581 62.2243 62.5678 62.2855 62.3177C62.1965 62.5261 62.0008 62.8316 61.8654 63.0002C61.8278 63.049 61.8139 63.1128 61.7797 63.1536C61.7246 63.2183 61.7409 63.136 61.7362 63.1399C61.7361 63.14 61.736 63.1401 61.7359 63.1402ZM59.0676 64.4141C58.8431 64.3322 58.9727 64.4671 59.1098 64.4595C59.1154 64.4585 59.0732 64.4161 59.0676 64.4141ZM62.3582 61.2072C62.4061 60.8036 62.4695 61.0969 62.3731 60.2527C62.4414 60.6074 62.4222 60.2723 62.4498 60.3415C62.4715 60.3971 62.4535 60.6052 62.4974 60.4842C62.4496 60.6432 62.4628 61.3335 62.4551 61.3643C62.4551 61.364 62.4551 61.3637 62.4551 61.3634C62.4505 61.3819 62.3429 61.3359 62.3582 61.2072ZM60.6927 63.9559C60.5667 63.8629 60.6345 64.0773 60.4551 64.0266C60.3432 64.2626 60.9363 63.8092 61.0748 63.8558C60.3694 64.2776 61.6062 63.672 61.0098 63.8132C61.4302 63.6055 61.1159 63.7044 61.157 63.6418C61.1998 63.5764 61.4086 63.428 61.3619 63.3983C61.3618 63.3984 61.3617 63.3985 61.3616 63.3986C61.2538 63.5083 61.1369 63.6094 61.0126 63.7005C61.2036 63.7026 60.9166 63.8652 60.7773 63.8334C60.7504 63.8747 60.7223 63.9155 60.6927 63.9559ZM61.4862 63.516C61.4767 63.529 61.2173 63.7712 61.2459 63.7719C61.2999 63.7616 61.6569 63.3973 61.4862 63.516ZM62.2534 62.1893C62.2199 62.3111 62.1305 62.4831 62.1405 62.5624C62.1927 62.4478 62.2764 62.2671 62.2534 62.1893ZM57.0901 63.2446C56.9578 63.1433 57.2775 63.5274 57.2125 63.3908C57.2081 63.3851 57.0953 63.2504 57.0901 63.2446ZM60.3744 64.1156C60.2103 64.1266 60.3237 64.2326 60.4264 64.1579C60.4321 64.1536 60.3818 64.1151 60.3744 64.1156ZM62.3417 60.8801C62.3086 60.8656 62.3319 60.2801 62.3316 60.1763C62.3624 60.2352 62.3797 60.8968 62.3417 60.8801ZM62.185 61.9495C62.026 62.155 62.0376 62.4901 62.0161 62.526C61.9988 62.5571 61.9738 62.4852 61.9692 62.4922C61.9648 62.5101 61.7948 62.8415 61.7828 62.8561C61.7781 62.869 61.8772 62.8485 61.8545 62.9282C61.9246 62.7856 62.2064 62.1474 62.1895 62.1027C62.1889 62.0742 62.067 62.2577 62.1849 61.9499C62.1849 61.9498 62.185 61.9497 62.185 61.9495ZM61.9642 62.6003C62.0337 62.528 61.9197 62.7704 61.8739 62.819C61.7809 62.9297 61.9606 62.6122 61.9642 62.6003ZM61.6039 63.122C61.5822 63.1436 61.3979 63.3401 61.403 63.3787C61.5298 63.3198 61.6605 63.0777 61.6039 63.122ZM58.9243 64.1588C58.8532 64.1535 58.6724 64.084 58.6544 64.1086C58.7224 64.1245 58.908 64.1878 58.9243 64.1588ZM62.0812 58.8823C62.0562 59.0458 62.046 58.667 62.058 58.5564C62.0779 58.5504 62.0834 58.8684 62.0812 58.8823ZM60.2551 63.8551C60.2251 63.8742 59.6168 64.0315 59.3905 64.023C59.3632 64.0247 59.3423 64.0259 59.3299 64.0272C59.3421 64.0299 59.3629 64.0326 59.3905 64.0346C59.6139 64.073 60.2345 63.9328 60.2564 63.8979C60.2653 63.8913 60.2602 63.8548 60.2551 63.8551ZM61.5725 62.8157C61.5755 62.7319 61.6436 62.7198 61.6491 62.712C61.7027 62.6394 61.7755 62.4681 61.7955 62.5229C61.7174 62.6616 61.5636 62.9855 61.5725 62.8157ZM58.9016 63.9529C58.6336 63.9176 59.1368 64.0582 59.0767 63.9965C59.0723 63.9941 58.9287 63.9574 58.9016 63.9529ZM60.3331 63.8128C60.3863 63.7851 61.0743 63.4128 61.1519 63.2996C61.1109 63.4248 61.0063 63.4478 60.8837 63.5373C60.8502 63.5615 60.8744 63.5778 60.8708 63.5803C60.8112 63.6212 60.8391 63.5653 60.8018 63.5888C60.7873 63.6169 60.2777 63.9 60.3331 63.8128ZM61.5695 62.7648C61.5828 62.719 61.7848 62.2857 61.7878 62.2661C61.8969 62.1508 61.6159 62.748 61.5695 62.7648ZM60.2461 63.7829C60.2991 63.6904 60.6574 63.5744 60.4394 63.7193C60.4177 63.7332 60.3084 63.7437 60.2461 63.7829ZM58.9423 63.8866C58.9289 63.8856 58.6704 63.8084 58.6598 63.8269C58.6925 63.8547 59.0821 63.9381 58.9423 63.8866ZM59.0913 63.8259C59.0848 63.8254 59.1414 63.8805 59.018 63.8578C59.0078 63.8548 58.9961 63.8041 58.8414 63.7904C58.81 63.7876 58.754 63.8091 58.7568 63.812C58.9006 63.9465 59.4156 63.8291 59.0913 63.8259ZM61.5384 62.7344C61.5061 62.7436 61.4838 62.6576 61.5397 62.6279C61.5639 62.6148 61.5765 62.6732 61.5384 62.7344ZM58.1476 63.5792C58.2995 63.6239 57.8889 63.3671 57.8696 63.3505C57.863 63.3835 58.1291 63.5792 58.1476 63.5792ZM61.7733 58.4994C61.7733 58.4996 61.7733 58.4998 61.7733 58.5C61.7824 58.2942 61.8156 58.4217 61.8166 58.412C61.8653 57.9736 61.7902 58.0899 61.7813 58.0213C61.7621 57.8743 61.8535 57.898 61.8156 57.65C61.8716 58.0599 61.8481 57.6868 61.8806 57.6752C62.0133 57.6292 61.8185 58.221 61.8463 58.4253C61.8502 58.4538 61.8925 58.2436 61.9046 58.3165C61.9436 58.5537 61.7388 59.2893 61.7733 58.4994ZM61.5558 62.5885C61.5611 62.5227 61.7661 62.1227 61.7506 62.2433C61.7591 62.2668 61.5671 62.6976 61.5558 62.5885ZM53.1536 38.7497C53.1614 38.9014 53.2594 38.5704 53.2479 38.5047C53.2411 38.4707 53.1494 38.6823 53.1536 38.7497ZM54.011 36.6901C54.0788 36.5631 54.0488 36.359 53.9666 36.523C53.9575 36.5408 53.9852 36.6948 54.011 36.6901ZM54.8685 48.44C54.844 48.2208 54.7603 48.2641 54.8143 48.4122C54.8334 48.4646 54.8693 48.4469 54.8685 48.44ZM53.0681 40.9439C53.0704 40.9247 53.0605 40.7024 53.0395 40.7106C53.0266 40.7935 53.0493 41.0691 53.0681 40.9439ZM54.9039 48.4999C54.8453 48.3854 54.8552 48.6147 54.9699 48.74C54.9381 48.6669 54.9099 48.5117 54.9039 48.4999ZM59.9238 63.6624C59.8706 63.7157 59.688 63.7356 59.5835 63.7486C59.569 63.7033 59.8543 63.693 59.9238 63.6624ZM53.6706 37.2429C53.6971 37.0894 53.5452 37.3789 53.6006 37.3692C53.6043 37.3656 53.6693 37.2488 53.6706 37.2429ZM56.8809 55.4329C56.8301 55.2827 56.8585 55.7785 56.8915 55.6367C56.8929 55.6297 56.884 55.441 56.8809 55.4329ZM57.0348 57.6132C57.0459 57.4913 57.0239 56.9801 57.0023 57.1801C57.0003 57.2108 57.0087 57.6039 57.0348 57.6132ZM61.7456 58.0092C61.6945 58.0674 61.7067 57.7296 61.7156 57.6813C61.7193 57.6623 61.812 57.9333 61.7456 58.0092ZM54.4194 47.1329C54.3779 47.0317 54.2998 46.7609 54.259 46.7225C54.3056 46.8463 54.3804 47.1839 54.4194 47.1329ZM53.4366 37.909C53.5275 37.7904 53.5965 37.573 53.5098 37.603C53.4337 37.8502 53.5786 37.5899 53.4366 37.909ZM55.2018 49.1588C55.1756 49.0724 55.087 49.0308 55.0873 49.0415C55.0906 49.1437 55.2063 49.2523 55.2018 49.1588ZM53.3075 43.0071C53.3355 42.9974 53.2801 42.7418 53.267 42.7791C53.262 42.7914 53.2841 43.0149 53.3075 43.0071ZM57.8453 63.1218C57.8053 63.0512 57.9988 63.1846 58.0385 63.2479C58.0383 63.3072 57.848 63.133 57.8453 63.1218ZM56.0039 51.5769C56.0507 51.5765 55.8846 51.1386 55.9058 51.3252C55.9113 51.3716 55.9885 51.5765 56.0039 51.5769ZM57.0528 56.0831C56.9735 55.7554 57.0526 57.1576 57.0875 56.7856C57.0936 56.7587 57.0633 56.1108 57.0528 56.0831ZM57.1099 58.3254C57.1157 58.2734 57.264 58.2993 57.2069 58.5144C57.1994 58.5426 57.1602 58.4105 57.1513 58.4336C57.1462 58.4472 57.1253 58.9148 57.1288 58.9363C57.1327 58.9595 57.1803 58.9322 57.1856 58.9557C57.1915 58.9822 57.1498 59.27 57.1493 59.4208C57.1486 59.7049 57.1881 59.7355 57.1882 59.7588C57.1885 59.8267 57.1604 59.9408 57.1605 60.0783C57.1606 60.448 57.1702 60.922 57.1665 61.3674C57.1626 61.5904 57.1845 61.794 57.1843 61.9461C57.1577 61.7497 57.1237 61.5648 57.1112 61.3674C57.106 61.2259 57.1006 61.0838 57.0974 60.9399C57.18 61.0825 57.0338 60.2238 57.129 60.726C57.1084 60.4948 57.0918 58.4957 57.1099 58.326C57.1099 58.3258 57.1099 58.3256 57.1099 58.3254ZM54.3594 36.2681C54.3459 36.3565 54.6034 36.0545 54.5921 35.9959C54.5465 36.0206 54.3597 36.2533 54.3594 36.2681ZM53.5633 38.2941C53.561 38.3441 53.6441 38.4087 53.5448 38.6507C53.5448 38.6509 53.5447 38.6511 53.5447 38.6514C53.516 38.7231 53.5086 38.6336 53.4976 38.6456C53.4927 38.6494 53.4014 38.876 53.4294 38.679C53.4759 38.3801 53.5066 38.6647 53.5396 38.5088C53.5423 38.4894 53.5585 38.1868 53.544 38.201C53.5421 38.2026 53.5317 38.292 53.5236 38.3054C53.4928 38.3559 53.469 38.3223 53.4658 38.3297C53.4528 38.3533 53.4102 38.8357 53.357 38.9005C53.3309 38.9174 53.4569 38.1311 53.4809 38.109C53.4905 38.0917 53.5714 38.1215 53.5846 38.1048C53.5897 38.0955 53.6447 37.7931 53.6657 37.76C53.6714 37.75 53.6765 37.7424 53.6804 37.737C53.6401 37.7711 53.7305 37.5156 53.7566 37.5353C53.7656 37.543 53.698 37.7145 53.6944 37.721C53.6926 37.7235 53.6907 37.7256 53.6891 37.7276C53.7265 37.6964 53.5494 38.3141 53.6348 38.1933C53.6146 38.3822 53.5723 38.15 53.5633 38.2941ZM53.449 39.2208C53.4426 39.1994 53.4363 39.178 53.4301 39.1565C53.4057 39.5012 53.3291 39.9026 53.3203 40.3141C53.3182 40.4184 53.3755 40.2996 53.3583 40.4357C53.3517 40.4889 53.3363 40.5449 53.321 40.5816C53.3049 40.6207 53.2887 40.6381 53.2827 40.607C53.2822 40.6045 53.2828 40.5954 53.2841 40.5816C53.2901 40.5172 53.3142 40.349 53.3143 40.2571C53.3154 39.9283 53.2672 40.0089 53.2661 39.9896C53.2655 39.9681 53.3109 39.7638 53.3193 39.6523C53.3406 39.3726 53.3238 39.2388 53.4202 38.8731C53.4172 39.0927 53.5013 38.9838 53.449 39.2208ZM56.6752 53.4783C56.7084 53.4876 56.75 53.779 56.7769 53.8825C56.7445 53.8724 56.7049 53.5803 56.6752 53.4783ZM63.4974 45.9991C63.5469 46.073 63.5608 45.5173 63.5196 45.6639C63.5112 45.6981 63.4994 45.9287 63.4974 45.9991ZM63.3589 43.5121C63.3347 43.4409 63.3439 43.7413 63.3806 43.7356C63.3929 43.7334 63.3625 43.5213 63.3589 43.5121ZM53.7136 43.8869C53.7179 43.9006 53.7548 44.108 53.7542 44.1152C53.7343 44.2631 53.6099 43.5805 53.7136 43.8869ZM62.5384 40.6162C62.661 40.8413 62.3933 40.1248 62.4415 40.3573C62.4446 40.3684 62.5332 40.6053 62.5384 40.6162ZM62.1121 39.6533C62.1409 39.7063 62.2382 39.9539 62.2528 39.9516C62.2777 39.9461 62.1635 39.6621 62.1121 39.6533ZM55.3962 49.1544C55.4368 49.1039 55.5352 49.5065 55.5895 49.6407C55.5489 49.691 55.4507 49.2866 55.3962 49.1544ZM54.5937 46.7421C55.179 48.3117 54.9433 47.9988 54.5369 46.6569C54.5698 46.6438 54.5578 46.6436 54.5937 46.7421ZM55.3028 48.79C55.2485 48.7427 55.1927 48.5551 55.1514 48.4305C55.1824 48.4444 55.2647 48.702 55.3028 48.79ZM63.396 46.6535C63.3591 46.5582 63.4302 46.138 63.4453 46.2138C63.4506 46.2298 63.4197 46.6919 63.396 46.6535ZM53.7889 44.005C53.8316 43.957 53.9216 44.4227 53.9206 44.4613C53.9096 44.6157 53.8069 44.0391 53.7889 44.005ZM56.2469 51.5192C56.3158 51.598 56.3756 51.8655 56.4251 52.0353C56.3681 51.968 56.2909 51.6609 56.2469 51.5192ZM55.8879 50.3198C55.893 50.3294 55.9664 50.5578 55.9679 50.5688C55.9921 50.7679 55.7844 50.1223 55.8879 50.3198ZM61.3705 58.7848C61.3692 58.777 61.3718 58.6011 61.3734 58.5949C61.4137 58.4379 61.4054 58.966 61.3705 58.7848Z\" fill=\"white\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><strong>+15,000<\/strong> <span class=\"custom-title\">customers<\/span><br \/>\nhave already had the experience.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_31725fbb counter-box has_text_color iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:4.8rem;\"><svg width=\"96\" height=\"92\" viewBox=\"0 0 96 92\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect width=\"95.0207\" height=\"91.0615\" rx=\"7.91839\" fill=\"#1F1549\"\/>\n<path d=\"M51.5064 35.4859C51.5114 35.5042 51.4992 35.5781 51.5013 35.6101C51.4482 35.5739 51.4882 35.4196 51.5064 35.4859ZM55.3631 38.7674C55.3499 38.7408 55.3368 38.7143 55.3237 38.6878C55.3151 38.7632 55.3248 38.8646 55.3123 38.9346C55.3102 38.946 55.2722 38.9163 55.2705 38.9434C55.2688 38.9705 55.3208 38.9653 55.3263 39.0047C55.3324 39.0489 55.2962 39.2513 55.2971 39.3214C55.3006 39.5836 55.3303 39.848 55.3087 40.1107C55.2702 39.8395 55.2311 40.1128 55.2478 40.1888C55.2516 40.2056 55.3482 40.2029 55.3239 40.475C55.3085 40.6479 55.1704 40.4882 55.2396 40.7768C55.3362 40.5549 55.3294 40.7731 55.3326 40.947C55.3332 40.977 55.3187 41.2192 55.3229 41.3261C55.3244 41.3627 55.375 41.4185 55.3763 41.467C55.3772 41.5005 55.3496 41.5257 55.351 41.5753C55.3572 41.8066 55.3594 42.0341 55.35 42.2657C55.22 42.1303 55.2946 42.372 55.2884 42.3829C55.2531 42.4381 55.243 42.1884 55.221 42.2871C55.225 42.4251 55.229 42.5631 55.233 42.701C55.249 42.5878 55.3425 42.851 55.3 42.8994C55.4149 42.8781 55.2 43.5282 55.2384 43.6272C55.2465 43.6478 55.3032 43.5129 55.2773 43.8259C55.2744 43.8598 55.2397 43.8469 55.2429 43.8647C55.2449 43.8754 55.3551 43.9398 55.2942 44.0085C55.272 44.0335 55.1996 43.8731 55.2287 44.2254C55.3408 44.0851 55.2894 44.7138 55.2613 44.8295C55.2764 44.8064 55.2914 44.7832 55.3065 44.7601C55.2659 44.8745 55.304 44.8951 55.3019 44.9209C55.2936 45.0247 55.2551 45.1674 55.2587 45.2641C55.2627 45.3773 55.3324 45.3776 55.3053 45.5096C55.3207 45.4783 55.3361 45.447 55.3514 45.4157C55.3477 45.5068 55.344 45.5979 55.3403 45.689C55.248 45.478 55.3359 45.7345 55.3379 45.7514C55.3413 45.7784 55.3035 45.7396 55.3082 45.7847C55.309 45.7894 55.3446 45.7826 55.3486 45.8521C55.3568 45.9973 55.312 45.9743 55.3125 46.0353C55.3128 46.0408 55.3448 46.0213 55.3524 46.1266C55.3766 46.4611 55.3278 46.1249 55.3234 46.1121C55.3176 46.0952 55.1836 46.2099 55.2311 45.9257C55.216 46.0212 55.1567 46.0307 55.1552 46.0415C55.154 46.051 55.1624 46.2163 55.1644 46.2254C55.1845 46.3067 55.2251 46.2352 55.2323 46.251C55.2382 46.264 55.1854 46.4632 55.3072 46.5099C55.1948 46.6052 55.2051 46.455 55.1878 46.2952C55.1648 46.2719 55.1424 46.4474 55.1424 46.4566C55.1426 46.683 55.2351 46.5577 55.2942 46.6072C55.3251 46.6332 55.262 46.7254 55.3449 46.6403C55.3537 46.8457 55.3056 46.7211 55.2985 46.7344C55.2881 46.7544 55.3118 46.8263 55.3087 46.8353C55.304 46.8485 55.2753 46.8026 55.2652 46.8547C55.2637 46.8633 55.3131 46.9473 55.3367 46.8391C55.3297 46.9836 55.3718 46.9717 55.2869 47.0207C55.4475 47.1203 55.192 47.093 55.183 47.1322C55.1593 47.2365 55.2854 47.2062 55.2915 47.2117C55.3309 47.2497 55.2876 47.5383 55.3058 47.6098C55.215 47.5816 55.3048 47.381 55.2872 47.3361C55.2286 47.1865 55.2418 47.5469 55.1277 47.4383C55.159 47.4838 55.1903 47.5293 55.2217 47.5749C55.1483 47.6584 55.1163 47.5399 55.1431 47.7646C55.2065 47.8014 55.1331 47.6058 55.183 47.645C55.2123 47.6681 55.2186 47.7984 55.234 47.801C55.2526 47.8035 55.2306 47.6858 55.2591 47.7043C55.3208 47.7449 55.2621 48.1744 55.2284 47.8474C55.2295 47.9386 55.1069 47.9856 55.1451 48.0647C55.1699 48.1158 55.3393 47.8281 55.3082 48.2597C55.2503 48.2689 55.2911 48.0872 55.2867 48.0825C55.2803 48.0758 55.1496 48.1087 55.1431 48.1144C55.1219 48.1345 55.1919 48.5753 55.1262 48.6684C55.2018 48.6315 55.1397 49.0015 55.1627 49.0418C55.1691 49.0525 55.2153 49.0124 55.2202 49.0239C55.2494 49.0954 55.1668 49.2889 55.1646 49.3786C55.1622 49.4791 55.2022 49.4664 55.2021 49.472C55.1999 49.5162 55.1728 49.4809 55.1729 49.5079C55.173 49.5487 55.1675 49.8292 55.1731 49.8433C55.1749 49.8474 55.2205 49.8016 55.2292 49.8628C55.2307 49.8734 55.1766 49.8667 55.1999 50.0478C55.228 50.2659 55.2672 49.8963 55.3239 49.9869C55.2432 50.127 55.3232 50.1225 55.3169 50.1605C55.3146 50.1736 55.2466 50.2715 55.2509 50.3778C55.2399 50.3015 55.2288 50.2252 55.2178 50.1489C55.2059 50.2239 55.2206 50.3696 55.2072 50.4314C55.2006 50.4616 55.1448 50.4367 55.1463 50.5022C55.1469 50.5161 55.283 50.5713 55.2219 50.3997C55.2705 50.386 55.2389 50.4676 55.2526 50.5055C55.2548 50.5112 55.3359 50.5338 55.2855 50.5822C55.2731 50.5938 55.0363 50.4674 55.2077 50.7934C55.2132 50.8039 55.2428 50.7674 55.249 50.7777C55.2531 50.7847 55.2412 50.8679 55.2454 50.8771C55.2499 50.8866 55.2822 50.8463 55.2886 50.8575C55.3214 50.915 55.193 50.9903 55.2028 50.8719C55.187 50.9115 55.1711 50.9511 55.1552 50.9906C55.252 50.9483 55.1824 51.0528 55.1854 51.1075C55.2045 51.4584 55.2674 51.2235 55.3 51.2838C55.3523 51.3808 55.1867 51.3067 55.2364 51.4508C55.2411 51.4641 55.3114 51.29 55.2717 51.63C55.269 51.5798 55.2662 51.5296 55.2635 51.4794C55.1699 51.5084 55.2699 51.6606 55.2712 51.6723C55.2841 51.8058 55.2503 51.7156 55.2985 51.9138C55.3029 51.9315 55.2798 51.9701 55.2913 52.008C55.3387 52.1649 55.3201 51.8009 55.358 51.7909C55.3765 51.7862 55.3719 52.1777 55.3631 52.1911C55.324 52.2482 55.3458 52.0137 55.2973 52.0584C55.2801 52.0747 55.3155 52.6326 55.2966 52.7446C55.2746 52.8737 55.1477 52.9319 55.2903 52.9327C55.1503 52.9692 55.2458 53.0014 55.2449 53.0179C55.2319 53.2177 55.2305 53.218 55.2439 53.3893C55.2468 53.4272 55.2044 53.4591 55.2115 53.4725C55.2159 53.4803 55.2613 53.4657 55.2753 53.5039C55.2945 53.5568 55.2478 53.8753 55.2226 53.8989C55.1975 53.9226 55.2118 53.7645 55.1704 53.7928C55.1663 53.9073 55.1765 54.0171 55.1721 54.1323C55.1702 54.1802 55.1413 54.1556 55.1407 54.1762C55.1404 54.185 55.1658 54.3503 55.1765 54.3433C55.2013 54.3269 55.1846 53.8165 55.2352 53.9509C55.245 53.9769 55.1784 54.0685 55.2594 54.0539C55.241 54.5099 55.2226 54.9658 55.2043 55.4218C55.1437 55.1598 55.1979 54.865 55.1922 54.5906C55.1915 54.553 55.1993 54.4258 55.1584 54.4413C55.1478 54.6746 55.1691 54.9647 55.1424 55.1888C55.1415 55.196 55.1047 55.1696 55.0989 55.1965C55.088 55.2467 55.1474 55.4102 55.132 55.4377C55.1284 55.4424 55.08 55.3493 55.0491 55.3776C54.97 55.4502 55.1452 55.4687 55.1431 55.5311C55.1415 55.5794 55.0568 55.9038 55.1103 55.9847C55.1673 56.0706 55.1434 55.7455 55.19 55.7696C55.2369 55.9895 55.1868 56.2122 55.1927 56.42C55.1928 56.4236 55.2294 56.3918 55.2345 56.4382C55.2434 56.5189 55.1915 56.5401 55.1833 56.5793C55.1744 56.6217 55.1819 56.7715 55.163 56.7915C55.1605 56.7941 55.1091 56.7637 55.1076 56.7591C55.0864 56.6939 55.1532 56.6707 55.154 56.6648C55.1565 56.6424 55.131 56.6205 55.1325 56.6002C55.135 56.5667 55.1587 56.5482 55.1608 56.504C55.1623 56.4735 55.1169 56.503 55.119 56.4735C55.1199 56.4628 55.2236 56.3463 55.1178 56.3355C55.0844 56.3321 55.0415 57.2842 55.0682 57.3794C55.081 57.2978 55.0937 57.2161 55.1064 57.1345C55.0754 57.3003 55.16 57.4994 55.0349 57.5135C55.0246 58.1283 55.0144 58.743 55.0042 59.3577C54.9935 59.4675 54.9131 59.4073 54.9365 59.5879C54.9621 59.5412 54.9878 59.4946 55.0134 59.4479C54.9954 59.5404 54.9603 59.9506 54.9769 60.017C54.9791 60.0256 55.0518 60.0375 55.0581 60.14C55.0636 60.2309 55.0091 60.2455 54.9986 60.2942C54.99 60.335 55.0043 60.3808 55.0013 60.3929C54.9989 60.4022 54.9655 60.4059 54.9597 60.4283C54.9417 60.4989 55.0356 60.4417 54.9278 60.5118C54.9237 60.4947 54.9196 60.4776 54.9155 60.4606C54.8999 60.5458 54.851 60.6622 54.8268 60.5367C54.8226 60.5151 54.8549 60.5336 54.8548 60.5175C54.8488 59.8872 54.7861 60.3905 54.8362 60.6114C54.7884 60.6682 54.8176 60.9861 54.8082 60.9967C54.7946 61.0114 54.7564 60.957 54.7234 61.0283C54.7164 61.0433 54.7432 61.4684 54.6796 61.3153C54.6665 61.2837 54.6803 61.0799 54.6784 61.0308C54.5771 61.1464 54.7223 61.4174 54.7185 61.4478C54.7028 61.5708 54.6308 61.2117 54.619 61.4886C54.6099 61.7016 54.6776 61.5017 54.7065 61.5836C54.7227 61.6296 54.6481 61.8706 54.7446 61.864C54.7549 61.9467 54.7039 61.8983 54.7002 61.9085C54.6969 61.9185 54.7258 62.0812 54.7055 62.1339C54.703 62.1404 54.6528 62.1202 54.6487 62.1268C54.6417 62.1397 54.6517 62.2965 54.656 62.3028C54.6589 62.3068 54.7028 62.2695 54.7135 62.2848C54.7257 62.3027 54.7154 62.4537 54.728 62.462C54.7469 62.4737 54.7344 62.2874 54.7836 62.3185C54.7712 62.4044 54.804 62.5443 54.8435 62.601C54.8322 62.5871 54.8306 62.5038 54.8345 62.4749C54.9065 62.4885 54.9055 62.6673 54.8486 62.6062C54.8791 62.645 54.8953 62.6185 54.9242 62.6404C54.9315 62.6461 54.933 62.7013 54.9455 62.712C54.9479 62.7134 54.9751 62.6564 54.9897 62.6678C55.0161 62.6885 55.0101 62.8559 55.0032 62.8695C54.9836 62.9081 54.9598 62.7716 54.9295 62.7602C54.9249 62.7586 54.8654 62.8747 54.8602 62.8765C54.8038 62.8832 54.8444 62.7541 54.7937 62.7688C54.783 62.8008 54.7723 62.8327 54.7616 62.8647C54.7102 62.7415 54.7366 62.5135 54.6782 62.4547C54.6956 62.6374 54.6935 62.8286 54.5619 62.8282C54.5065 62.8281 54.4741 62.7493 54.46 62.7523C54.4096 62.7639 54.4643 62.8733 54.4617 62.8774C54.4586 62.8807 54.4556 62.8822 54.4527 62.8822C54.4527 62.8822 54.4527 62.8822 54.4527 62.8822C54.4232 62.8822 54.4019 62.7262 54.3884 62.7184C54.3645 62.7053 54.266 62.7747 54.2442 62.7746C54.2398 62.7722 54.2165 62.6611 54.1784 62.6986C54.14 62.7365 54.1392 62.8338 54.1352 62.8372C54.1122 62.8557 54.0912 62.6857 54.0777 62.6806C54.0708 62.6779 54.0286 62.7692 54.0165 62.7719C54.0044 62.7742 53.9778 62.7048 53.9394 62.6774C53.9109 62.657 53.889 62.7164 53.8846 62.706C53.8816 62.6985 53.8821 62.5379 53.8771 62.53C53.8697 62.5182 53.8356 62.5558 53.8271 62.5503C53.8148 62.5426 53.8271 62.4907 53.8145 62.4974C53.8051 62.5025 53.6876 62.7037 53.6562 62.7024C53.6027 62.7001 53.7258 62.4871 53.5146 62.6853C53.5132 62.6866 53.5282 62.7349 53.5269 62.7362C53.4881 62.766 53.4283 62.6113 53.4387 62.8004C53.3712 62.4487 53.3582 62.7567 53.2681 62.7046C53.2335 62.6845 53.2192 62.5481 53.214 62.5475C53.17 62.5608 53.2041 62.6042 53.1826 62.619C53.1705 62.6271 53.124 62.5051 53.0939 62.5326C53.0783 62.5468 53.0839 62.6763 53.0808 62.6816C53.0522 62.7329 53.0214 62.67 53.0011 62.6813C52.9874 62.6888 52.9864 62.7669 52.9839 62.769C52.9788 62.7723 52.9238 62.6661 52.9044 62.644C52.8895 62.6272 52.8662 62.6903 52.8597 62.6786C52.8209 62.6079 52.9199 62.4576 52.7812 62.6024C52.7727 62.6113 52.7761 62.6661 52.7744 62.6677C52.7351 62.7016 52.7317 62.6007 52.6995 62.5826C52.644 62.5516 52.6749 62.6966 52.6359 62.5761C52.5996 62.6665 52.6012 62.7169 52.6113 62.8228C52.5831 62.5297 52.4395 62.4262 52.4431 62.7516C52.4453 62.6481 52.3643 62.6596 52.3629 62.6287C52.3621 62.6095 52.4426 62.4594 52.2618 62.5283C52.2393 62.5369 52.2679 62.6281 52.2217 62.5995C52.2335 62.3807 52.1923 62.5949 52.1862 62.5951C52.0797 62.5923 52.1669 62.0576 52.1548 61.9657C52.1407 61.8591 52.0568 61.7644 52.0567 61.7412C52.0566 61.665 52.0992 61.7283 52.1149 61.7112C52.1304 61.6939 52.0488 61.4771 52.0533 61.4663C52.0713 61.4243 52.1218 61.4669 52.1243 61.4626C52.1553 61.4106 52.1157 61.1194 52.1275 61.0379C52.0947 61.0404 52.0921 61.2041 52.0395 61.1019C51.9782 60.9829 52.1226 60.9761 52.1289 60.973C52.1276 60.4279 52.1262 59.8827 52.1248 59.3376C52.048 59.3444 52.1059 59.7008 52.0958 59.7089C52.0359 59.7565 52.037 59.1544 52.0642 59.0805C52.0476 59.1366 52.031 59.1928 52.0144 59.2489C51.9261 59.1531 52.0408 58.941 52.0018 58.8025C51.9892 58.7577 51.9551 58.8437 51.9528 58.8419C51.9185 58.7916 51.9449 58.7108 51.9909 58.7712C51.9468 58.6484 51.9955 58.6663 51.9992 58.5721C51.9993 58.5672 51.9637 58.6077 51.9489 58.5331C51.942 58.4982 51.9419 58.3118 51.9107 58.2868C51.8976 58.2766 51.7594 58.3711 51.8783 58.3828C51.8203 58.5855 51.9325 58.4475 51.9298 58.5263C51.9292 58.5384 51.8628 58.5106 51.894 58.7089C51.7743 58.6711 51.8638 58.4428 51.8493 58.4036C51.8195 58.3229 51.7577 58.6556 51.851 58.7166C51.7576 58.6881 51.8384 58.7402 51.8346 58.8144C51.8304 58.8955 51.8026 58.8601 51.8024 58.9041C51.8017 59.0242 51.8677 58.9744 51.8082 59.0734C51.9923 58.9769 51.8325 59.2429 51.7843 59.3205C51.775 59.1943 51.7656 59.0682 51.7563 58.942C51.7466 58.9492 51.737 58.9564 51.7273 58.9636C51.7287 58.9304 51.73 58.8972 51.7314 58.864C51.7407 58.8693 51.7499 58.8746 51.7592 58.8799C51.699 58.7086 51.7666 58.6668 51.7674 58.6528C51.7753 58.473 51.7747 58.2652 51.7749 58.0834C51.7749 58.0561 51.7147 58.0748 51.7618 57.876C51.7769 57.8126 51.8237 57.8724 51.8167 57.8006C51.6893 57.7106 51.7909 57.7123 51.7911 57.6856C51.7911 57.6089 51.7595 57.5619 51.7592 57.5549C51.7543 57.4601 51.7595 57.3212 51.7548 57.2171C51.7544 57.2151 51.7152 57.2693 51.7268 57.2017C51.7309 57.1779 51.898 56.9648 51.8435 56.7786C51.8322 56.827 51.821 56.8755 51.8097 56.9239C51.8255 56.867 51.7834 56.4678 51.7386 56.5654C51.7113 56.6252 51.819 56.7713 51.7154 56.7873C51.7464 56.6545 51.7001 55.9209 51.7241 55.8638C51.7276 55.8559 51.7612 55.9045 51.7655 55.8936C51.7687 55.8851 51.7608 55.7171 51.7737 55.6948C51.7814 55.6815 51.8019 55.7558 51.814 55.7497C51.8227 55.7444 51.8371 55.5346 51.795 55.5226C51.8119 55.5742 51.7971 55.719 51.7616 55.643C51.7572 55.6333 51.7844 55.5826 51.7788 55.5708C51.7272 55.4606 51.7396 55.7898 51.7391 55.8407C51.6855 55.6339 51.7487 55.3142 51.7138 55.0746C51.7488 54.9778 51.7674 55.2181 51.7964 55.1086C51.8566 54.8814 51.7479 55.0481 51.7435 55.0411C51.7081 54.9847 51.8976 54.7924 51.7534 54.7923C51.7751 54.71 51.7933 54.7366 51.7744 54.6204C51.7644 54.6357 51.7544 54.651 51.7444 54.6663C51.6609 54.5372 51.8717 54.2641 51.8877 54.2845C51.9308 54.3396 51.8637 54.4818 51.8653 54.494C51.8677 54.512 52.014 54.5617 51.8832 54.7585C51.9813 54.8391 51.9494 54.4466 52.0163 54.6251C52.0053 54.5045 52.0737 54.0083 52.0306 53.9369C52.0249 53.9284 51.9271 53.9681 51.9769 53.8455C52.0006 53.7873 52.0018 53.9276 52.024 53.901C52.0924 53.819 52.0487 52.7046 52.0451 52.4929C52.045 52.4791 52.0753 52.4842 52.075 52.4707C52.0742 52.4292 52.0289 52.278 52.0429 52.2038C51.9867 52.3576 51.9823 52.0589 51.9885 51.9829C51.9979 51.8676 52.0514 51.8747 52.0627 51.8249C52.1065 51.6329 51.9797 51.3353 52.0982 51.1862C51.9806 51.1943 52.1559 50.9281 52.157 50.807C52.1578 50.7122 52.0799 50.5746 52.0325 50.7026C52.0379 50.5389 52.016 50.3665 52.0088 50.2129C52.0076 50.1875 52.0424 50.2225 52.0393 50.1792C52.0387 50.1752 52.0046 50.1698 52.0011 50.1326C51.9714 49.8255 52.0438 49.9749 52.0651 49.9175C52.0771 49.8853 52.083 49.8616 52.0849 49.8442C52.0916 50.0232 52.105 50.2296 52.106 50.2848C52.1813 50.2377 52.0915 49.8881 52.1118 49.7858C52.1125 49.7822 52.154 49.7946 52.1543 49.791C52.1543 49.7909 52.1543 49.7908 52.1543 49.7907C52.1575 49.7524 52.1422 49.508 52.0927 49.5583C52.0795 49.5718 52.0795 49.6843 52.084 49.8177C52.0747 49.7816 52.0282 49.8085 52.0262 49.8022C52.0032 49.7249 52.0486 49.5356 52.0547 49.4685C52.0561 49.4531 52.0263 49.4542 52.0262 49.4517C52.033 49.3906 52.118 49.4157 52.0303 49.353C52.1363 49.2425 52.0461 49.5603 52.1149 49.5379C52.1679 49.5207 52.1394 48.8147 52.0559 48.8168C52.0649 48.8144 52.076 48.8047 52.0886 48.7848C52.1166 48.7406 52.1078 48.5441 52.0924 48.5102C52.0894 48.5045 52.0084 48.5067 52.0076 48.4996C52.0058 48.4819 52.0693 48.2417 52.0214 48.152C52.01 48.2004 51.9987 48.2489 51.9873 48.2973C51.9866 48.0048 51.9625 48.05 51.9383 48.1475C51.938 48.1523 51.935 48.1571 51.9346 48.1617C51.9167 48.2373 51.8995 48.3342 51.8931 48.3356C51.8687 48.3412 51.8551 47.8448 51.9303 47.9403C51.9406 47.9536 51.9071 48.1832 51.9607 48.0695C51.9701 48.0497 51.9548 47.9022 51.9607 47.8944C52 47.8426 52.0523 48.1646 52.1081 48.1253C52.055 48.0471 52.083 47.9468 52.0692 47.8572C52.063 47.8164 52.0224 47.8063 52.0216 47.8013C52.011 47.7261 52.0536 47.7683 52.0526 47.7432C52.0518 47.7297 51.9612 47.5815 52.0862 47.6095C51.9942 47.1212 51.9943 47.4745 52.0013 47.774C51.9558 47.6794 51.9778 47.4938 51.9673 47.4105C51.9634 47.3806 51.9217 47.3983 51.9134 47.3479C51.8962 47.244 51.9441 46.7481 51.9554 46.6188C51.9701 46.6982 52.0156 46.675 52.0124 46.6138C52.0093 46.5525 51.9486 46.6039 51.9421 46.592C51.9354 46.5792 51.964 46.2918 51.9561 46.244C51.9781 46.4604 52.0234 46.4116 52.0282 46.2279C52.0412 46.2545 52.0543 46.281 52.0673 46.3076C52.049 46.1999 52.1181 45.9737 52.0975 45.9115C52.0942 45.9017 52.0561 45.9368 52.0543 45.9313C52.0381 45.8767 52.0769 45.6911 52.0639 45.6824C52.0531 45.6751 52.0212 45.7543 52.0054 45.7249C52.0021 45.7188 52.0536 45.6424 52.041 45.5672C52.0363 45.5393 52.0003 45.5561 51.9982 45.5491C51.9809 45.4905 52.0415 45.5251 52.0318 45.418C52.0246 45.3396 51.9653 45.2812 51.9849 45.1728C51.9093 45.5287 51.9409 45.2295 51.918 45.0807C51.9143 45.0569 51.8489 45.0773 51.8807 44.9348C51.999 45.238 51.9432 44.8483 51.9445 44.7686C51.9449 44.7643 51.9881 44.7628 51.9888 44.7237C51.9887 44.7204 51.9596 44.7251 51.9573 44.6888C51.9363 44.3442 51.9692 44.5645 51.9979 44.499C52.0102 44.4712 51.969 44.3036 51.968 44.2584C51.9679 44.2481 51.9982 44.2528 51.997 44.2127C51.9948 44.1416 51.9626 44.078 51.96 44.0311C51.9599 44.0256 52.0076 44.0254 51.9921 43.9365C51.9878 43.9115 51.9708 43.8835 51.9571 43.919C51.9119 44.0367 51.9901 44.26 51.945 44.393C51.9039 44.5143 51.9001 44.1318 51.8998 44.1119C51.8997 44.1046 51.9234 44.1793 51.9281 44.1034C51.932 44.0386 51.8495 43.9201 51.8674 43.8235C51.8688 43.8161 51.9388 43.7389 51.9428 43.7425C51.9458 43.7457 51.961 43.8643 51.9813 43.847C51.9836 43.845 51.9831 43.7697 51.9982 43.7598C52.0165 43.7478 52.1967 43.7153 52.2012 43.6992C52.2123 43.6579 52.1713 43.6848 52.1741 43.6581C52.1801 43.6008 52.2334 43.4022 52.171 43.3958C52.1673 43.4286 52.1636 43.4614 52.1599 43.4942C52.1534 43.3116 52.1269 43.3895 52.1152 43.3636C52.1025 43.3357 52.1574 43.3436 52.1625 43.282C52.1636 43.2686 52.1522 43.0112 52.1292 43.0158C52.1658 43.1582 52.098 43.1054 52.0968 43.112C52.0924 43.137 52.1304 43.1688 52.1297 43.2023C52.1237 43.4377 52.0637 43.2003 52.0482 43.2559C52.043 43.275 52.0755 43.3131 52.0738 43.3212C52.0684 43.3476 52.0259 43.348 52.0294 43.3656C52.0373 43.4067 52.0975 43.3587 52.1007 43.362C52.1383 43.3987 52.0915 43.5425 52.026 43.453C52.0024 43.5067 52.082 43.513 52.0501 43.5556C51.9872 43.6403 52.0033 43.5134 51.9929 43.479C51.9551 43.3557 51.9857 43.3191 51.9752 43.1445C51.9715 43.0816 51.9329 43.0072 51.9308 42.978C51.9294 42.9596 52.0639 42.7861 51.8534 42.781C51.8738 42.7136 52.0125 42.6078 52.0062 42.5383C52.0004 42.4759 51.9259 42.4957 51.923 42.4899C51.9185 42.481 51.9244 42.4055 51.9138 42.38C51.9014 42.3501 51.873 42.3651 51.8614 42.3176C51.8327 42.1996 51.9087 42.2027 51.9136 42.1905C51.9707 42.0497 51.8626 42.1113 51.8539 42.0801C51.8459 42.051 51.8876 41.6433 51.8602 41.5574C51.8754 41.5924 51.8906 41.6273 51.9059 41.6622C51.9533 41.5997 51.876 41.5335 51.961 41.5323C51.8237 41.5196 51.9155 41.3906 51.9119 41.3518C51.9105 41.3366 51.8871 41.3378 51.8861 41.3187C51.882 41.244 51.9006 41.0756 51.8887 41.0351C51.8377 40.86 51.7527 41.3079 51.7476 41.3431C51.7491 41.2725 51.7184 40.8732 51.6524 41.0568C51.6422 41.0851 51.7036 41.1354 51.706 41.1514C51.7218 41.2592 51.6668 41.1744 51.6616 41.1828C51.6531 41.1972 51.7063 41.2682 51.7 41.2869C51.6979 41.2932 51.6481 41.2529 51.6471 41.3558C51.5987 41.3052 51.6381 41.0161 51.6268 40.9782C51.6227 40.9646 51.5195 41.0493 51.6197 40.8019C51.6102 40.8048 51.6006 40.8076 51.591 40.8105C51.587 40.6727 51.5831 40.535 51.5791 40.3972C51.6012 40.4121 51.6456 40.4895 51.6362 40.3921C51.6307 40.336 51.5815 40.3775 51.5801 40.3724C51.5666 40.322 51.5829 39.4311 51.5775 39.2584C51.5757 39.1997 51.5361 39.036 51.5354 39.0235C51.5315 38.9489 51.5572 38.6845 51.5516 38.6318C51.548 38.5989 51.5069 38.6302 51.5088 38.6008C51.5107 38.5734 51.5504 38.6017 51.5521 38.5936C51.5665 38.5264 51.5144 38.0154 51.5518 37.8941C51.5406 37.9682 51.62 38.3383 51.648 38.3308C51.6519 38.3292 51.6821 38.2393 51.6674 38.2207C51.7018 38.1901 51.597 38.0848 51.6176 38.0276C51.6199 38.0211 51.6787 38.0466 51.6893 37.9445C51.693 37.9093 51.6472 37.8171 51.6985 37.7244C51.6739 37.5901 51.7501 36.8842 51.6869 36.8357C51.6836 36.8343 51.6619 36.9337 51.6359 36.8665C51.6015 36.7773 51.7175 36.8574 51.7275 36.7534C51.7291 36.7377 51.7173 36.4482 51.7101 36.4387C51.645 36.351 51.6186 36.604 51.611 36.6005C51.592 36.5916 51.5805 36.3814 51.5849 36.3729C51.5896 36.3648 51.6759 36.5362 51.6432 36.3302C51.6329 36.3538 51.6226 36.3774 51.6123 36.401C51.5922 36.3041 51.6519 36.2949 51.6555 36.2714C51.6671 36.1984 51.5764 36.1195 51.6884 36.0026C51.7181 35.9717 51.7511 36.023 51.7556 36.0191C51.7956 35.982 51.6886 35.9346 51.7684 35.8788C51.7743 35.8746 51.8221 36.0045 51.8223 35.7774C51.8146 35.7931 51.807 35.8087 51.7993 35.8243C51.7822 35.7923 51.7721 35.5623 51.7761 35.5314C51.7879 35.441 51.8428 35.5198 51.8363 35.429C51.761 35.4873 51.7512 35.211 51.816 35.2269C51.7346 35.1883 51.7974 34.9537 51.7993 34.8434C51.8005 34.7738 51.7649 34.6318 51.7691 34.6097C51.7742 34.5827 51.8297 34.5909 51.8421 34.5423C51.8456 34.5284 51.8049 34.3836 51.8624 34.2565C51.8734 34.2319 51.9676 34.1801 51.9912 34.2259C52.0315 34.3043 51.9556 34.4525 52.0112 34.4506C52.0708 34.4484 52.0354 34.2487 52.0431 34.195C52.0791 33.9468 52.1424 34.0901 52.1615 34.0838C52.2081 34.0672 52.2067 33.9316 52.2108 33.926C52.2294 33.9025 52.2663 33.9986 52.2947 34C52.3317 34.0018 52.3985 33.8711 52.4109 33.9008C52.4287 33.9433 52.373 34.0634 52.3757 34.0711C52.4116 34.1702 52.497 34.0343 52.539 33.9969C52.5519 33.9855 52.5732 34.0307 52.577 34.0213C52.6345 33.8777 52.4568 33.9911 52.4687 33.8955C52.4793 33.8102 52.5354 33.9199 52.5385 33.9167C52.5419 33.9125 52.545 33.8105 52.5649 33.7946C52.5748 33.7867 52.6841 34.0517 52.7331 34.0406C52.7223 33.9561 52.7115 33.8715 52.7007 33.787C52.7646 33.7803 52.7175 33.9019 52.7241 33.9145C52.7373 33.9398 52.7697 33.8692 52.7899 33.8723C52.8027 33.8739 52.8485 33.9568 52.8674 33.8819C52.874 33.8562 52.8292 33.8022 52.8749 33.7085C52.9334 34.0346 52.9693 33.8086 52.9919 33.799C53.0145 33.7896 53.0678 33.9452 53.0583 33.7563C53.1826 33.7481 53.0976 33.7603 53.1195 33.814C53.1463 33.8798 53.1873 33.7278 53.1562 33.9682C53.2144 33.9545 53.2103 33.7613 53.2149 33.7511C53.2191 33.7422 53.2478 33.7852 53.2575 33.7699C53.3699 33.5887 53.3186 33.7131 53.3904 33.6607C53.3968 33.656 53.4234 33.4848 53.4339 33.6151C53.4529 33.8526 53.3704 33.9519 53.5467 33.9918C53.6233 33.8161 53.5095 33.6033 53.5076 33.5499C53.5048 33.4682 53.5408 33.5528 53.5508 33.5428C53.5541 33.5393 53.5511 33.4688 53.554 33.4679C53.6885 33.4177 53.5562 33.7814 53.5796 33.8959C53.5997 33.8652 53.6199 33.8345 53.64 33.8039C53.6408 33.8455 53.6416 33.8871 53.6424 33.9288C53.6829 33.7304 53.6578 33.9218 53.7666 33.9713C53.7911 33.9824 53.7492 33.852 53.8172 34.0007C53.8329 33.8911 53.8551 33.926 53.8244 33.8267C53.868 33.8293 53.9173 34.0527 53.9397 34.1408C53.9887 33.8295 53.8286 34.0071 53.9133 33.7379C53.8593 33.688 53.8698 33.8165 53.8609 33.806C53.8288 33.7684 53.8797 33.6803 53.7674 33.574C53.7489 33.5567 53.6921 33.6299 53.6949 33.5216C53.6953 33.5096 53.7438 33.4405 53.7473 33.4415C53.7853 33.4506 53.7711 33.519 53.7869 33.5218C53.802 33.5244 53.7929 33.4482 53.7971 33.4479C53.8447 33.4456 53.8153 33.5116 53.8302 33.502C53.8626 33.4813 53.9651 33.2071 53.9351 33.565C53.8812 33.2677 53.8825 33.5269 53.9032 33.6427C53.9084 33.6722 53.9368 33.6797 53.9467 33.7217C53.9595 33.7758 53.9458 33.8392 53.951 33.8672C53.9568 33.8973 54.024 33.7262 54.004 33.9736C54.0708 33.8477 53.9995 33.6252 54.0465 33.5015C54.1414 33.2519 54.1617 33.6756 54.1709 33.7197C54.1734 33.7314 54.2118 33.692 54.2142 33.6999C54.2178 33.7127 54.2001 33.9531 54.2318 33.9768C54.2636 34.0005 54.2304 33.8888 54.2635 33.8813C54.2858 33.8763 54.3253 34.1663 54.3406 34.0093C54.351 33.9011 54.2614 33.7016 54.3577 33.668C54.3657 33.8272 54.3737 33.9863 54.3817 34.1455C54.4183 34.0584 54.455 33.9713 54.4916 33.8842C54.5033 34.0628 54.4619 34.2172 54.5143 34.3869C54.6318 33.9792 54.6081 34.5192 54.6224 34.5252C54.6309 34.5272 54.7262 34.3667 54.7437 34.3409C54.7803 34.4831 54.7983 34.9151 54.916 34.6624C54.8894 34.7082 54.955 34.8193 54.96 34.8179C55.012 34.8038 54.9782 34.5614 55.0252 34.601C55.0797 34.6468 55.0058 34.7109 55.0117 34.7814C55.0425 35.143 55.3139 35.0438 55.271 35.4063C55.2806 35.3991 55.2903 35.3919 55.3 35.3847C55.2846 35.7788 55.2692 36.1729 55.2538 36.5669C55.3367 36.7211 55.3872 37.1315 55.378 37.333C55.3762 37.3736 55.3327 37.5728 55.3251 37.5879C55.3105 37.6157 55.3049 37.4626 55.2775 37.5318C55.2719 37.5464 55.2536 37.8837 55.3 37.8596C55.3054 37.8218 55.282 37.7035 55.293 37.6842C55.371 37.5482 55.3087 38.5881 55.3401 38.6396C55.3552 38.6166 55.3702 38.5936 55.3853 38.5705C55.3779 38.6361 55.3705 38.7018 55.3631 38.7674ZM51.6379 35.7519C51.5913 35.7125 51.6263 35.6138 51.6132 35.5555C51.5949 35.4749 51.4157 35.338 51.5953 35.3969C51.6095 35.5153 51.6237 35.6336 51.6379 35.7519ZM51.5685 37.4814C51.5935 37.402 51.6938 37.4636 51.6521 37.5286C51.6474 37.5358 51.5349 37.5888 51.5685 37.4814ZM51.6161 36.6495C51.6175 36.6529 51.6148 36.7214 51.6132 36.7238C51.5729 36.7853 51.5812 36.5786 51.6161 36.6495ZM51.6676 40.6681C51.6633 40.5807 51.5721 40.644 51.6096 40.6984C51.612 40.7018 51.6678 40.6739 51.6676 40.6681ZM51.67 40.6059C51.7517 40.538 51.5862 40.4013 51.6028 40.51C51.6045 40.5205 51.666 40.6091 51.67 40.6059ZM51.6084 37.1986C51.6397 37.2075 51.6246 37.2893 51.6171 37.3243C51.5885 37.3233 51.6119 37.2328 51.6084 37.1986ZM51.6171 39.2738C51.6417 39.2773 51.6403 38.9928 51.6079 38.9734C51.6217 39.0183 51.595 39.2706 51.6171 39.2738ZM51.6516 40.0034C51.6559 39.9962 51.6494 39.8979 51.6277 39.9008C51.5992 39.9488 51.6324 40.0359 51.6516 40.0034ZM51.6502 41.4536C51.6557 41.4589 51.7938 41.3853 51.7029 41.5597C51.6896 41.5853 51.6535 41.4939 51.6485 41.503C51.6388 41.522 51.6343 41.5371 51.6335 41.5492C51.6221 41.4679 51.6167 41.3836 51.6251 41.3754C51.6646 41.3371 51.6479 41.4512 51.6502 41.4536ZM51.7531 42.2149C51.7757 42.2316 51.7636 42.3385 51.7544 42.3628C51.7526 42.367 51.6934 42.3488 51.6978 42.3969C51.7015 42.4355 51.7621 42.3778 51.7524 42.4531C51.7427 42.5292 51.6994 42.4275 51.6964 42.4342C51.6923 42.4431 51.7196 42.5607 51.6843 42.5571C51.6581 42.5543 51.6758 42.4283 51.6703 42.3971C51.6631 42.3572 51.6196 42.4056 51.6289 42.3389C51.6348 42.297 51.7113 42.3202 51.7152 42.3114C51.7183 42.304 51.6743 42.1575 51.7529 42.2151C51.753 42.215 51.7531 42.215 51.7531 42.2149ZM51.6369 41.5711C51.6343 41.565 51.6329 41.5579 51.6335 41.5492C51.6346 41.5565 51.6358 41.5639 51.6369 41.5711ZM51.6715 35.9812C51.6479 36.0224 51.6176 35.9 51.6485 35.8537C51.6735 35.8529 51.6751 35.9746 51.6715 35.9812ZM51.6993 41.6465C51.6801 41.7671 51.6537 41.6784 51.6369 41.5711C51.6513 41.6052 51.7057 41.606 51.6993 41.6465ZM51.6674 38.2207C51.6616 38.2258 51.6527 38.229 51.6381 38.2295C51.6541 38.2161 51.6627 38.2149 51.6674 38.2207ZM51.6413 38.5022C51.6858 38.5987 51.684 38.4027 51.6521 38.4039C51.6401 38.4045 51.6395 38.4984 51.6413 38.5022ZM51.6632 40.7803C51.6676 40.7714 51.8022 40.9086 51.7012 40.7095C51.6853 40.8157 51.6707 40.7036 51.6589 40.7053C51.625 40.7096 51.6576 40.8881 51.6429 40.9276C51.7035 40.9586 51.6489 40.8094 51.6632 40.7805C51.6632 40.7804 51.6632 40.7803 51.6632 40.7803ZM51.7205 43.587C51.685 43.5628 51.6964 43.486 51.6985 43.4343C51.734 43.4585 51.7226 43.5352 51.7205 43.587ZM51.7154 57.136C51.6826 56.7812 51.8272 56.7352 51.7701 57.0599C51.7689 57.0662 51.7301 57.1575 51.7154 57.136ZM51.7529 54.0912C51.8159 54.0577 51.8261 54.1684 51.8 54.241C51.7942 54.2575 51.7303 54.3183 51.7179 54.2489C51.7942 54.2511 51.8234 54.1437 51.7529 54.0912ZM51.7396 41.7147C51.7816 41.7498 51.7517 41.8579 51.7454 41.9149C51.7108 41.8802 51.7265 41.7651 51.7396 41.7147ZM51.7908 55.9702C51.7956 55.9328 51.7408 55.9075 51.7362 55.914C51.7153 55.9429 51.7596 56.0128 51.7908 55.9702ZM51.7461 41.3656C51.7712 41.3606 51.7954 41.5039 51.7333 41.5138C51.7378 41.4832 51.7304 41.3691 51.7461 41.3656ZM51.7394 43.4893C51.7521 43.4671 51.775 43.5823 51.7623 43.6171C51.7356 43.6143 51.7311 43.5039 51.7394 43.4893ZM51.7722 55.3681C51.777 55.3346 51.7785 55.251 51.7563 55.2417C51.7286 55.2302 51.738 55.3529 51.7722 55.3681ZM51.8201 61.5988C51.8101 61.6031 51.7384 61.4735 51.7565 61.4159C51.7913 61.3065 51.8271 61.5943 51.8201 61.5988ZM51.8191 56.3241C51.767 56.4297 51.8175 56.3125 51.7626 56.3171C51.7606 56.3882 51.7579 56.565 51.8119 56.4434C51.8223 56.4197 51.8156 56.3573 51.8191 56.3241ZM51.8375 56.2267C51.8197 56.2154 51.7636 56.1393 51.7676 56.2051C51.7696 56.2355 51.8319 56.2845 51.8375 56.2267ZM51.7957 60.7961C51.8443 60.7014 51.8182 61.1353 51.8097 61.1478C51.8052 61.1544 51.801 61.1587 51.7974 61.1612C51.8128 61.1771 51.8155 61.259 51.7766 61.2685C51.7798 61.244 51.7764 61.1769 51.7807 61.1691C51.7825 61.1657 51.7843 61.1632 51.786 61.1615C51.7522 61.1326 51.7865 60.8142 51.7957 60.7961ZM51.8457 60.0771C51.9174 60.1854 51.7955 60.2046 51.7916 60.1953C51.7417 60.0774 51.8316 60.1543 51.8358 60.1506C51.8428 60.1424 51.8011 60.0586 51.8457 60.0775C51.8457 60.0773 51.8457 60.0772 51.8457 60.0771ZM51.8157 60.6487C51.8173 60.6532 51.8136 60.7441 51.8116 60.7478C51.7707 60.8223 51.7811 60.5651 51.8157 60.6487ZM51.8384 42.7887C51.8263 42.8538 51.7815 42.79 51.7976 42.7467C51.7992 42.7431 51.8492 42.7313 51.8384 42.7887ZM51.8254 56.1747C51.8339 56.1596 51.8658 55.7735 51.7981 55.7967C51.8061 55.8295 51.7712 56.2684 51.8254 56.1747ZM51.8418 53.2893C51.8413 53.3574 51.7774 53.2832 51.8012 53.2468C51.8101 53.2334 51.8419 53.2721 51.8418 53.2893ZM51.8041 41.1724C51.769 41.1017 51.8868 41.1163 51.8464 41.1776C51.8448 41.18 51.8055 41.1752 51.8041 41.1724ZM51.8051 53.8333C51.7664 53.5984 51.9689 53.654 51.9006 53.9593C51.8915 53.9498 51.8825 53.9402 51.8735 53.9307C51.8431 54.283 51.8592 53.9548 51.8479 53.8685C51.8436 53.8357 51.8098 53.8632 51.8049 53.8335C51.8049 53.8334 51.805 53.8333 51.8051 53.8333ZM51.8457 52.9313C51.9895 52.7051 51.8958 53.1368 51.9146 53.2607C51.8552 53.1406 51.8642 52.9843 51.8034 53.1969C51.7917 52.8861 51.8489 53.0155 51.8537 53.0031C51.859 52.9884 51.8395 52.9409 51.8457 52.9313ZM51.8467 53.5278C51.8509 53.5408 51.8216 53.6393 51.8264 53.6748C51.7773 53.6252 51.8181 53.441 51.8467 53.5278ZM51.8124 59.3234C51.8508 59.3316 51.8792 59.3518 51.8648 59.4295C51.8455 59.4055 51.8288 59.3559 51.8124 59.3234ZM51.8404 35.6772C51.8431 35.6236 51.8576 35.5171 51.8172 35.5497C51.8137 35.5533 51.8177 35.677 51.8404 35.6772ZM51.8566 55.0533C51.8613 55.0419 51.8645 54.7475 51.822 54.8492C51.8092 54.8799 51.8146 55.1478 51.8566 55.0533ZM51.8517 56.578C51.8521 56.5533 51.8449 56.4532 51.8358 56.4511C51.8043 56.4444 51.8216 56.5672 51.8517 56.578ZM51.8798 35.4071C51.8838 35.4001 51.8767 35.2366 51.858 35.2545C51.8227 35.2887 51.866 35.4313 51.8798 35.4071ZM51.9286 43.0256C51.93 43.0392 51.8882 43.0573 51.8877 43.0621C51.8872 43.0732 51.9032 43.3234 51.8496 43.2278C51.8406 43.2118 51.8612 42.8519 51.8665 42.805C51.9239 42.7869 51.8693 42.9407 51.8752 42.9781C51.8763 42.9847 51.9243 42.9889 51.9283 43.0255C51.9284 43.0255 51.9285 43.0255 51.9286 43.0256ZM51.8529 59.7284C51.8894 59.7394 51.9136 60.0335 51.8694 60.0301C51.8639 59.9295 51.8584 59.8289 51.8529 59.7284ZM51.859 59.5789C51.8848 59.5162 51.8933 59.6632 51.8819 59.7065C51.8574 59.707 51.8552 59.5881 51.859 59.5789ZM51.988 56.0201C51.9791 55.9906 51.9259 56.0814 51.9155 56.0611C51.9091 56.0481 51.929 55.982 51.9124 55.961C51.9071 55.955 51.8571 56.0224 51.8592 56.0419C51.8621 56.0695 51.9015 56.0427 51.9018 56.0729C51.9026 56.1732 51.8745 56.2621 51.8752 56.3561C51.8753 56.3646 51.9031 56.2987 51.9027 56.3711C51.9027 56.3823 51.8613 56.4496 51.8674 56.5362C51.9957 56.7275 51.8698 56.8679 51.916 57.1107C51.9281 57.1016 51.9605 56.92 51.9617 56.9093C51.9828 56.7064 51.9851 56.3429 51.9854 56.1303C51.9855 56.0758 51.9583 56.1023 51.9573 56.0788C51.9566 56.0602 52.0069 56.0823 51.988 56.0201ZM51.8682 35.7056C51.9184 35.6801 51.8866 35.5906 51.8892 35.5334C51.8439 35.5535 51.8793 35.6497 51.8682 35.7056ZM51.8979 58.2584C51.896 58.2297 51.9111 58.1409 51.896 58.1336C51.8762 58.1241 51.8638 58.2523 51.8979 58.2584ZM51.9143 44.4363C51.9157 44.4391 51.913 44.508 51.9114 44.5106C51.8711 44.5722 51.8794 44.3654 51.9143 44.4363ZM51.9047 46.0852C51.9109 46.1375 51.9266 46.1902 51.8858 46.2078C51.8921 46.1745 51.8763 46.0791 51.9047 46.0852ZM51.9059 48.3601C51.9592 48.3493 51.9247 48.5066 51.9199 48.5363C51.8962 48.5253 51.8674 48.368 51.9059 48.3601ZM51.9798 59.3121C51.9767 59.4083 52.0575 59.388 52.0209 59.449C52.0147 59.459 51.8465 59.4912 51.9095 59.3855C51.9208 59.3664 51.9608 59.4409 51.9798 59.3121ZM51.8989 54.0091C51.9342 54.0335 51.9237 54.11 51.9209 54.1616C51.8946 54.15 51.9014 54.0458 51.8989 54.0091ZM51.9201 35.1118C51.97 35.0667 51.933 34.8583 51.9001 34.9099C51.8958 34.9172 51.922 35.0826 51.9201 35.1118ZM51.9006 41.9592C51.9398 42.045 51.9519 41.8674 51.9136 41.8113C51.9161 41.8367 51.898 41.9534 51.9006 41.9592ZM51.9349 47.8137C51.9365 47.8178 51.9327 47.9087 51.9308 47.9128C51.8898 47.9873 51.9003 47.73 51.9349 47.8137ZM51.9694 45.543C52.0017 45.5757 51.9757 45.7911 51.9433 45.8394C51.8961 45.793 51.9291 45.5023 51.9694 45.543ZM51.9569 58.9163C51.9585 58.9849 51.9486 59.05 51.9346 59.1131C51.9074 59.0998 51.9366 58.9235 51.9569 58.9163ZM51.9383 48.1475C51.938 48.1523 51.935 48.1571 51.9346 48.1617C51.9358 48.1569 51.9371 48.1521 51.9383 48.1475ZM51.976 57.3804C51.9867 57.3229 51.9369 57.3348 51.9354 57.3384C51.9192 57.3817 51.9638 57.4455 51.976 57.3804ZM51.9421 35.6399C51.9871 35.62 51.9522 35.5233 51.9629 35.4676C51.9274 35.4838 51.9374 35.5951 51.9421 35.6399ZM51.9378 52.6891C51.9865 52.6168 52.0431 52.9108 52.0117 52.9727C51.9816 52.9773 51.9311 52.6996 51.9378 52.6891ZM51.968 41.6929C52.0032 41.6871 51.9607 41.5637 51.9441 41.5899C51.9335 41.6066 51.9461 41.6964 51.968 41.6929ZM51.9912 53.1205C52.0019 53.1481 51.9672 53.2125 51.946 53.1899C51.9188 53.1608 51.9881 53.1134 51.9912 53.1205ZM52.0195 55.5984C52.0248 55.5863 51.9887 55.4239 51.9528 55.491C51.9278 55.5376 51.9787 55.545 51.9789 55.5559C51.9787 55.5681 51.9164 55.8288 52.0195 55.5984ZM51.9685 51.0428C51.982 51.104 51.9663 51.1781 51.9673 51.2422C51.9455 51.2161 51.9395 51.0688 51.9685 51.0428ZM51.9774 42.1689C51.9916 42.154 52.0002 41.7487 51.9564 41.9789C51.9539 41.9924 51.9343 42.2141 51.9774 42.1689ZM51.9798 59.3121C51.9802 59.2999 51.9819 59.2859 51.9854 59.2697C51.984 59.2858 51.9816 59.2999 51.9798 59.3121ZM51.9851 58.2197C52.0108 58.2418 52.0176 58.1302 52.004 58.0973C51.9727 58.0872 51.9816 58.2166 51.9851 58.2197ZM52.003 51.2471C52.0177 51.284 52.002 51.3511 52.0037 51.3968C51.9799 51.3891 51.9788 51.2631 52.003 51.2471ZM52.0298 48.6526C52.0157 48.7259 52.0222 48.8162 52.0514 48.8176C52.0468 48.8191 52.042 48.8227 52.0371 48.8286C52.0323 48.8346 52.0458 48.9132 52.0359 48.9473C51.9768 49.1517 52.0012 48.1578 52.0835 48.7339C52.0656 48.7068 52.0477 48.6797 52.0298 48.6526ZM52.0381 45.2515C52.0736 45.2099 52.0291 45.0933 52.0151 45.1235C52.0055 45.1446 52.0023 45.2932 52.0381 45.2515ZM52.0591 46.8539C52.0654 46.8414 52.0406 46.7276 52.0219 46.7246C52.0022 46.7901 52.0297 46.9106 52.0591 46.8539ZM52.0796 44.9314C52.085 44.9053 52.0278 44.8719 52.0253 44.875C52.0044 44.9016 52.0478 44.9753 52.0796 44.9314ZM52.134 59.1128C52.1504 59.0739 52.109 58.95 52.0712 58.923C52.0785 58.918 52.088 58.9044 52.0994 58.8796C52.0994 58.8797 52.0994 58.8797 52.0994 58.8798C52.1147 58.8463 52.1314 57.8444 52.0586 58.5164C52.0563 58.5375 52.0902 58.5087 52.0842 58.5944C52.0838 58.6 52.0561 58.6028 52.0547 58.6203C52.0518 58.6605 52.0344 58.8747 52.0567 58.9178C52.0515 58.9181 52.0466 58.9209 52.0422 58.9268C52.0022 58.9796 52.1214 59.143 52.134 59.1128ZM52.0642 47.0796C52.0744 47.0567 52.0647 46.9842 52.0402 46.9767C52.0283 47.0127 52.0402 47.1328 52.0642 47.0796ZM52.0777 42.1563C52.0978 42.1096 52.0602 41.9913 52.0402 42.0271C52.0279 42.049 52.0546 42.2102 52.0777 42.1563ZM52.0511 46.3531C52.0222 46.6208 52.0534 46.417 52.0893 46.458C52.0766 46.423 52.0638 46.3881 52.0511 46.3531ZM52.0414 60.3518C52.0497 60.3091 52.1204 60.3593 52.082 60.4063C52.0699 60.421 52.037 60.3757 52.0414 60.3518ZM52.0634 62.2794C52.1262 62.243 52.0893 62.4209 52.0463 62.3515C52.0448 62.3483 52.061 62.282 52.0634 62.2794ZM52.0891 60.9325C52.0463 60.9035 52.0413 60.8846 52.0518 60.803C52.0639 60.9238 52.1016 60.8118 52.0891 60.9325ZM52.0559 48.8168C52.0542 48.8173 52.0529 48.8177 52.0514 48.8176C52.0529 48.8171 52.0544 48.8168 52.0559 48.8168ZM52.0685 44.6797C52.1047 44.6462 52.102 44.5523 52.0656 44.5803C52.0622 44.583 52.0418 44.666 52.0685 44.6797ZM52.0712 58.923C52.0647 58.9274 52.0605 58.9252 52.0567 58.9178C52.0615 58.9174 52.0661 58.9193 52.0712 58.923ZM52.098 45.184C52.071 45.1807 52.0605 45.3236 52.0637 45.3293C52.1105 45.4114 52.0996 45.243 52.098 45.184ZM52.1156 41.2112C52.1128 41.2038 52.0431 41.2513 52.0704 41.2805C52.0916 41.3031 52.1264 41.2388 52.1156 41.2112ZM52.1065 61.2096C52.1064 61.2549 52.1064 61.3186 52.0733 61.3304C52.0784 61.3001 52.0822 61.2087 52.1065 61.2096ZM52.1089 62.2097C52.07 62.1562 52.0701 62.034 52.0765 61.956C52.1277 61.9546 52.0968 62.1595 52.1089 62.2097ZM52.1149 59.2356C52.117 59.2319 52.1323 59.1184 52.098 59.1339C52.0477 59.1565 52.0963 59.2676 52.1149 59.2356ZM52.0787 41.4316C52.1023 41.4823 52.1748 41.3655 52.1188 41.312C52.0901 41.2845 52.0747 41.423 52.0787 41.4316ZM52.1159 44.3864C52.096 44.3195 52.0607 44.4855 52.0965 44.5087C52.0994 44.4778 52.1229 44.4102 52.1159 44.3864ZM52.1521 46.6656C52.2555 46.4545 52.0669 46.5695 52.0835 46.607C52.0859 46.6122 52.1497 46.6708 52.1521 46.6656ZM52.1267 34.588C52.1124 34.5582 52.0604 34.6696 52.0946 34.684C52.116 34.6929 52.1359 34.6072 52.1267 34.588ZM52.0849 49.8442C52.0846 49.8353 52.0843 49.8265 52.084 49.8177C52.0857 49.8243 52.0862 49.8329 52.0849 49.8442ZM52.2543 43.7784C52.1084 43.927 52.2209 43.9114 52.2203 43.9243C52.2187 43.9522 52.1792 44.017 52.1857 44.0696C52.1693 44.0094 52.1528 43.9492 52.1364 43.889C52.1259 43.9365 52.0722 44.3498 52.0958 44.3585C52.1295 44.3709 52.1189 44.2408 52.1219 44.237C52.1261 44.2316 52.2199 44.2113 52.2234 44.1992C52.2291 44.1794 52.2311 43.8338 52.2543 43.7784ZM52.1359 46.2242C52.1248 46.2581 52.0877 46.2678 52.0965 46.2836C52.0996 46.2889 52.135 46.2898 52.1441 46.3081C52.1414 46.2802 52.1387 46.2522 52.1359 46.2242ZM52.1231 43.5123C52.1664 43.4703 52.15 43.6588 52.1451 43.6649C52.1158 43.6972 52.0878 43.5467 52.1231 43.5123ZM52.1294 45.1126C52.1319 45.1058 52.1454 44.9609 52.1214 44.9621C52.1031 45.0004 52.0978 45.1941 52.1294 45.1126ZM52.1466 46.3308C52.1424 46.3817 52.1068 46.4779 52.1601 46.4668C52.1601 46.4668 52.1601 46.4667 52.1601 46.4666C52.1556 46.4213 52.1511 46.3761 52.1466 46.3308ZM52.1913 41.6054C52.2762 41.5111 52.1689 41.5557 52.1415 41.6392C52.1796 41.6645 52.1775 41.6208 52.1913 41.6054ZM52.2546 41.3036C52.2699 41.2774 52.2531 41.007 52.2082 41.0483C52.1922 41.0629 52.2326 41.2184 52.2295 41.2255C52.2248 41.2364 52.1751 41.1868 52.185 41.2697C52.2018 41.2649 52.2495 41.3126 52.2546 41.3036ZM52.2456 41.5273C52.3102 41.4336 52.1911 41.4125 52.1908 41.483C52.1906 41.5106 52.2363 41.5407 52.2456 41.5273ZM52.2355 41.9101C52.2468 41.8763 52.2633 41.7865 52.2237 41.7246C52.2203 41.8075 52.2169 41.8903 52.2135 41.9732C52.2359 41.9827 52.2256 41.9396 52.2355 41.9098C52.2355 41.9099 52.2355 41.91 52.2355 41.9101ZM52.4141 62.7728C52.4479 62.6984 52.4608 62.8699 52.4525 62.8771C52.425 62.8987 52.399 62.8061 52.4141 62.7728ZM53.2089 34.0065C53.2224 33.9858 53.2667 33.9723 53.2435 33.9268C53.2108 33.9726 53.178 34.0184 53.1453 34.0642C53.2203 34.0997 53.194 34.0291 53.2089 34.0065ZM53.4827 33.8316C53.4845 33.8381 53.5997 33.8027 53.5228 33.8863C53.4709 33.9428 53.4202 33.6357 53.4713 33.5802C53.4951 33.6415 53.4679 33.7759 53.4827 33.8316ZM53.9815 33.2937C53.9907 33.2901 54.0042 33.4068 53.9977 33.4203C53.9635 33.4912 53.9323 33.3128 53.9815 33.2937ZM53.9595 33.6659C53.9819 33.6112 53.9963 33.7324 53.9834 33.7685C53.962 33.772 53.9562 33.6743 53.9595 33.6659ZM54.083 62.0189C54.1613 61.9597 53.9927 61.9067 54.0267 61.9978C54.0283 62.0021 54.0791 62.0214 54.083 62.0189ZM54.0977 33.4077C54.0753 33.4625 54.0609 33.3412 54.0738 33.3051C54.0952 33.3017 54.101 33.3994 54.0977 33.4077ZM54.2695 61.9772C54.3259 61.8985 54.1368 61.9262 54.1291 61.9361C54.099 61.9765 54.1733 62.1153 54.1917 62.1437C54.1633 61.9359 54.243 62.0142 54.2695 61.9772ZM54.156 61.6145C54.1358 61.5415 54.0972 61.728 54.1499 61.7635C54.1474 61.7273 54.1618 61.6352 54.156 61.6145ZM54.2166 61.1717C54.2234 61.1325 54.2396 61.0158 54.2099 60.9962C54.2152 61.039 54.186 61.1551 54.2166 61.1717ZM54.3058 61.0829C54.3462 61.0216 54.2284 61.0069 54.2635 61.0776C54.2649 61.0803 54.3035 61.0851 54.3058 61.0829ZM54.3483 60.7382C54.3952 60.698 54.2811 60.6521 54.278 60.7172C54.2773 60.7366 54.343 60.7425 54.3483 60.7382ZM54.473 61.8787C54.4931 61.8211 54.4114 61.7469 54.4025 61.8699C54.39 61.8267 54.3775 61.7835 54.365 61.7403C54.3192 61.9014 54.4325 61.8896 54.4278 61.9358C54.4212 62.0005 54.3277 61.9954 54.2983 61.9824C54.3556 62.0354 54.3565 62.2605 54.3674 62.3906C54.3915 62.2763 54.4331 62.0907 54.4484 61.9779C54.4528 61.9456 54.4271 61.9144 54.43 61.8869C54.4347 61.8429 54.4717 61.882 54.473 61.879C54.473 61.8789 54.473 61.8788 54.473 61.8787ZM54.35 60.2851C54.4031 60.1669 54.2885 60.2416 54.3089 60.3084C54.3105 60.3113 54.3487 60.288 54.35 60.2851ZM54.446 33.251C54.3981 33.4089 54.3346 33.2941 54.431 33.6245C54.3627 33.4857 54.3819 33.6169 54.3544 33.5898C54.3326 33.568 54.3506 33.4866 54.3068 33.5339C54.3545 33.4717 54.3413 33.2015 54.349 33.1895C54.349 33.1896 54.349 33.1897 54.349 33.1898C54.3536 33.1826 54.4612 33.2006 54.446 33.251ZM54.5163 61.1711C54.6553 61.1317 54.4346 61.1162 54.5499 61.0387C54.3825 60.9355 54.5498 61.3238 54.4085 61.3708C54.4249 60.9491 54.2684 61.6494 54.48 61.3551C54.4032 61.5976 54.5062 61.4345 54.5332 61.472C54.5619 61.512 54.5307 61.6492 54.5825 61.6422C54.5825 61.6422 54.5825 61.6421 54.5825 61.642C54.5789 61.5581 54.5752 61.4742 54.5716 61.3903C54.4599 61.4724 54.4934 61.301 54.5844 61.2428C54.5617 61.2189 54.539 61.195 54.5163 61.1711ZM54.4114 61.646C54.414 61.6377 54.3983 61.4552 54.3759 61.467C54.3616 61.4914 54.3787 61.7504 54.4114 61.646ZM54.4358 62.4491C54.4361 62.3836 54.4579 62.2822 54.4157 62.2465C54.4155 62.3121 54.3937 62.4134 54.4358 62.4491ZM54.4438 59.0752C54.4092 58.9917 54.399 59.2488 54.4399 59.1744C54.4418 59.1708 54.4454 59.0793 54.4438 59.0752ZM54.4953 60.9812C54.5377 60.8963 54.4025 60.9364 54.4377 60.9993C54.4398 61.0029 54.4933 60.9851 54.4953 60.9812ZM54.4624 33.379C54.4955 33.3846 54.4722 33.6138 54.4725 33.6544C54.4417 33.6314 54.4244 33.3724 54.4624 33.379ZM54.5598 62.5644C54.6789 62.434 54.5413 62.2571 54.5443 62.2377C54.5474 62.2184 54.5995 62.2487 54.6009 62.2443C54.6038 62.2342 54.5994 62.0288 54.5958 62.0189C54.593 62.0117 54.5198 62.0489 54.4967 62.0065C54.5383 62.0892 54.5123 62.4648 54.5204 62.4843C54.5269 62.4994 54.6037 62.3856 54.5598 62.5642C54.5598 62.5642 54.5598 62.5643 54.5598 62.5644ZM54.5603 62.1892C54.5296 62.2406 54.5257 62.0966 54.5371 62.0618C54.5624 61.9844 54.5639 62.1826 54.5603 62.1892ZM54.5885 61.8431C54.5954 61.8266 54.6017 61.6783 54.5675 61.6657C54.5232 61.7359 54.5725 61.8803 54.5885 61.8431ZM54.5839 60.1924C54.5796 60.1539 54.6058 60.048 54.576 60.0419C54.5803 60.0805 54.5541 60.1864 54.5839 60.1924ZM54.7229 34.1609C54.7479 34.0969 54.7581 34.2452 54.7461 34.2884C54.7262 34.2908 54.7207 34.1663 54.7229 34.1609ZM54.7807 60.9668C54.7897 60.944 54.7671 60.4786 54.7531 60.4133C54.7305 60.4772 54.7288 60.9384 54.7398 60.9593C54.7431 60.9654 54.7792 60.9697 54.7807 60.9668ZM54.7944 61.9732C54.8384 62.0159 54.7857 62.0437 54.785 62.0491C54.7783 62.1019 54.7882 62.2113 54.7459 62.1873C54.7629 62.0942 54.7071 61.8883 54.7944 61.9732ZM54.7828 60.1594C54.7665 60.0013 54.7202 60.3049 54.7662 60.265C54.7689 60.2625 54.7845 60.1757 54.7828 60.1594ZM54.7935 61.0188C54.829 61.0536 54.7983 61.5191 54.7983 61.5939C54.7328 61.5269 54.7825 61.473 54.7792 61.3831C54.7782 61.3588 54.751 61.3653 54.7509 61.3627C54.7497 61.3207 54.7811 61.3521 54.7816 61.3262C54.7818 61.3098 54.7434 60.9697 54.7935 61.0188ZM54.8249 61.9976C54.8501 62.0236 54.8608 62.3143 54.8541 62.3259C54.8043 62.4134 54.8161 62.0202 54.8249 61.9976ZM54.8517 60.9761C54.9278 61.0261 54.8768 61.2573 54.8389 61.0991C54.8354 61.084 54.8684 61.02 54.8517 60.9761ZM54.8553 60.1762C54.8576 60.1685 54.8728 60.0037 54.8486 60.0008C54.8391 60.0246 54.8307 60.2647 54.8553 60.1762ZM54.9372 60.2616C54.9367 60.2577 54.89 60.2963 54.8959 60.2191C54.8965 60.2126 54.949 60.2006 54.9298 60.1035C54.9258 60.0838 54.8911 60.0533 54.8889 60.0555C54.8065 60.1566 54.9643 60.4611 54.9372 60.2616ZM54.8674 62.0029C54.8896 61.9872 54.9553 62.025 54.922 62.0591C54.9076 62.0737 54.8682 62.0464 54.8674 62.0029ZM54.8766 59.6538C54.9165 59.7496 54.924 59.4489 54.9138 59.4336C54.889 59.4433 54.8727 59.6442 54.8766 59.6538ZM55.0308 34.3108C55.0308 34.3107 55.0308 34.3106 55.0308 34.3105C55.0217 34.3911 54.9886 34.3412 54.9875 34.345C54.9388 34.5166 55.0139 34.471 55.0228 34.4979C55.042 34.5554 54.9506 34.5461 54.9885 34.6432C54.9325 34.4828 54.956 34.6288 54.9235 34.6334C54.7908 34.6513 54.9856 34.4197 54.9578 34.3397C54.9539 34.3286 54.9116 34.4109 54.8995 34.3823C54.8605 34.2895 55.0653 34.0016 55.0308 34.3108ZM54.9278 62.0854C54.9668 62.1227 54.929 62.4062 54.8969 62.331C54.8917 62.319 54.871 62.0304 54.9278 62.0854ZM54.9853 48.8425C55.0191 48.9107 55.0587 48.7527 55.0325 48.7235C55.0194 48.7089 54.9705 48.8126 54.9853 48.8425ZM55.1296 47.7354C55.1228 47.6544 54.9821 47.5691 55.0039 47.6698C55.0063 47.6805 55.1101 47.7447 55.1296 47.7354ZM55.0574 53.0515C55.1076 52.967 55.0142 52.972 55.0155 53.0341C55.016 53.056 55.0558 53.0542 55.0574 53.0515ZM55.0453 49.8251C55.0485 49.8166 55.0426 49.7189 55.0211 49.7224C55.0082 49.7586 55.0229 49.8798 55.0453 49.8251ZM55.0706 53.0784C55.0538 53.0283 54.9863 53.1145 55.0523 53.1758C55.0469 53.1447 55.0724 53.0835 55.0706 53.0784ZM55.0581 60.8014C55.0197 60.7594 55.0313 60.6407 55.0247 60.5725C55.0744 60.5651 55.0491 60.7527 55.0581 60.8014ZM55.0731 48.0791C55.038 48.0024 55.0094 48.1666 55.0557 48.1516C55.0582 48.1495 55.0746 48.0821 55.0731 48.0791ZM55.0757 55.779C55.0461 55.7232 55.0062 55.9001 55.0583 55.8514C55.0604 55.849 55.0774 55.782 55.0757 55.779ZM55.0586 56.5514C55.0686 56.5091 55.0655 56.3289 55.0366 56.399C55.0321 56.4099 55.0314 56.5482 55.0586 56.5514ZM55.0586 34.5026C55.1096 34.4799 55.0974 34.6121 55.0885 34.631C55.0848 34.6384 54.9922 34.5323 55.0586 34.5026ZM55.0653 52.5025C55.0589 52.4588 55.0711 52.3453 55.0443 52.3254C55.0498 52.3789 55.012 52.5169 55.0653 52.5025ZM55.0733 48.4285C55.1288 48.3618 55.1233 48.2477 55.0508 48.2759C55.0557 48.4019 55.116 48.2604 55.0733 48.4285ZM55.1303 53.3601C55.1346 53.325 55.065 53.2981 55.0617 53.3021C55.0305 53.3401 55.1033 53.395 55.1303 53.3601ZM55.0731 50.728C55.1028 50.7259 55.0893 50.6135 55.0702 50.6285C55.0637 50.6334 55.049 50.7296 55.0731 50.728ZM55.075 59.3288C55.1021 59.2773 55.1287 59.4347 55.097 59.4812C55.0513 59.5038 55.0719 59.3354 55.075 59.3288ZM55.1129 54.3328C55.1571 54.338 55.1321 54.1623 55.0955 54.2315C55.0864 54.2489 55.0982 54.331 55.1129 54.3328ZM55.1659 56.0152C55.1132 55.8974 55.0759 56.3924 55.1414 56.2623C55.1461 56.253 55.1703 56.0255 55.1659 56.0152ZM55.133 56.8237C55.1388 56.8033 55.2871 56.8135 55.2299 56.8976C55.2225 56.9087 55.1833 56.857 55.1743 56.866C55.1692 56.8713 55.1484 57.0544 55.1518 57.0628C55.1558 57.0719 55.2033 57.0612 55.2086 57.0704C55.2146 57.0808 55.1728 57.1934 55.1724 57.2524C55.1716 57.3636 55.2112 57.3756 55.2113 57.3847C55.2115 57.4113 55.1835 57.4559 55.1835 57.5098C55.1838 57.7812 55.2173 58.1963 55.1335 58.4114C55.1672 58.22 55.1314 58.0375 55.1204 57.847C55.203 57.9028 55.0568 57.5667 55.1521 57.7633C55.1314 57.6728 55.1149 56.8903 55.133 56.8239C55.133 56.8238 55.133 56.8238 55.133 56.8237ZM55.1712 47.4158C55.2218 47.4656 55.2104 47.2104 55.1518 47.1887C55.1437 47.2224 55.1654 47.4097 55.1712 47.4158ZM55.2947 48.5932C55.3034 48.6169 55.4024 48.6394 55.3522 48.7637C55.3522 48.7638 55.3522 48.7639 55.3522 48.764C55.3375 48.8004 55.3134 48.759 55.3048 48.7656C55.3013 48.768 55.2521 48.8814 55.2442 48.7872C55.232 48.6437 55.3178 48.7737 55.3188 48.6972C55.3189 48.6878 55.2653 48.543 55.2536 48.5514C55.2522 48.5523 55.2635 48.5959 55.2587 48.6031C55.2403 48.6302 55.2094 48.617 55.2079 48.6208C55.2041 48.6334 55.2568 48.8624 55.2108 48.8958C55.196 48.9066 55.1618 48.5306 55.1695 48.516C55.1743 48.5067 55.2601 48.5106 55.2686 48.501C55.2728 48.4961 55.2406 48.3448 55.2485 48.3252C55.2508 48.3195 55.2532 48.3151 55.2553 48.3119C55.2287 48.3348 55.2306 48.1979 55.2606 48.2021C55.2724 48.2045 55.2655 48.2987 55.2635 48.3021C55.2626 48.3036 55.2614 48.3049 55.2606 48.3061C55.2929 48.2865 55.2915 48.6057 55.3396 48.5368C55.366 48.6293 55.269 48.5237 55.2947 48.5932ZM55.3476 49.0379C55.3386 49.0284 55.3295 49.0188 55.3205 49.0093C55.3426 49.1712 55.2992 49.3581 55.2995 49.5447C55.2995 49.592 55.3547 49.5376 55.3396 49.5996C55.3275 49.6494 55.2763 49.7044 55.2649 49.6773C55.2621 49.6708 55.2954 49.5695 55.292 49.5189C55.2819 49.3693 55.2346 49.4071 55.2333 49.3984C55.2319 49.3887 55.2652 49.2946 55.2637 49.2432C55.2599 49.1139 55.2308 49.0549 55.2688 48.8783C55.3 48.9802 55.3677 48.9244 55.3476 49.0379ZM55.2468 55.0751C55.2766 55.0812 55.2502 55.1872 55.2545 55.2257C55.2247 55.2197 55.2512 55.1136 55.2468 55.0751ZM55.2855 39.2806C55.2366 39.2481 55.2245 39.4921 55.2652 39.4278C55.2742 39.4135 55.2851 39.3113 55.2855 39.2806ZM55.2558 40.3768C55.2693 40.4094 55.3045 40.278 55.2666 40.2782C55.2545 40.2784 55.254 40.3726 55.2558 40.3768ZM55.2995 51.1316C55.301 51.1377 55.2901 51.2275 55.2877 51.2303C55.2358 51.2898 55.2658 50.9943 55.2995 51.1316ZM55.3159 41.7093C55.2839 41.5956 55.27 41.938 55.3109 41.8334C55.3128 41.8282 55.3175 41.7148 55.3159 41.7093ZM55.3249 42.1853C55.3232 42.158 55.3391 42.0369 55.3241 42.0353C55.3001 42.0329 55.2836 42.1716 55.3249 42.1853ZM55.315 53.3838C55.37 53.3706 55.3283 53.5303 55.3353 53.5859C55.2802 53.599 55.3219 53.4393 55.315 53.3838ZM55.3556 52.3758C55.399 53.049 55.2813 52.9006 55.3287 52.3357C55.3641 52.3348 55.3528 52.3333 55.3556 52.3758ZM55.349 53.2379C55.3138 53.2134 55.3242 53.137 55.327 53.0853C55.3516 53.0946 55.3427 53.2006 55.349 53.2379ZM55.3611 38.9901C55.4057 39.0323 55.3507 39.2193 55.3324 39.1861C55.3284 39.1783 55.3366 38.9746 55.3611 38.9901ZM55.3466 51.188C55.4002 51.1723 55.3783 51.3745 55.3664 51.3899C55.3186 51.4523 55.3584 51.2043 55.3466 51.188ZM55.3621 54.3394C55.404 54.3751 55.3825 54.4764 55.3819 54.5417C55.346 54.512 55.3613 54.3947 55.3621 54.3394ZM55.3949 53.8686C55.3966 53.8727 55.3928 53.9636 55.3908 53.9677C55.3499 54.0422 55.3604 53.7849 55.3949 53.8686ZM55.4336 34.1991C55.435 34.2021 55.4323 34.271 55.4307 34.2734C55.3904 34.3348 55.3987 34.1281 55.4336 34.1991ZM39.6288 30.4814C39.6339 30.4998 39.6216 30.5737 39.6238 30.6057C39.5706 30.5694 39.6106 30.4152 39.6288 30.4814ZM43.4855 33.763C43.4723 33.7364 43.4592 33.7099 43.4461 33.6833C43.4375 33.7588 43.4472 33.8602 43.4347 33.9302C43.4326 33.9416 43.3946 33.9119 43.3929 33.939C43.3912 33.9661 43.4432 33.9609 43.4487 34.0003C43.4548 34.0445 43.4186 34.2469 43.4195 34.317C43.423 34.5792 43.4527 34.8436 43.4311 35.1063C43.3927 34.8351 43.3535 35.1084 43.3702 35.1843C43.3741 35.2012 43.4706 35.1985 43.4463 35.4706C43.4309 35.6435 43.2928 35.4838 43.362 35.7723C43.4586 35.5504 43.4518 35.7686 43.455 35.9426C43.4556 35.9726 43.4411 36.2147 43.4454 36.3217C43.4468 36.3583 43.4974 36.4141 43.4988 36.4626C43.4996 36.496 43.472 36.5213 43.4734 36.5709C43.4796 36.8022 43.4818 37.0296 43.4724 37.2613C43.3424 37.1259 43.417 37.3676 43.4108 37.3784C43.3755 37.4336 43.3654 37.184 43.3434 37.2827C43.3474 37.4207 43.3514 37.5587 43.3555 37.6966C43.3714 37.5834 43.4649 37.8465 43.4224 37.895C43.5373 37.8736 43.3224 38.5238 43.3608 38.6228C43.3689 38.6434 43.4257 38.5084 43.3997 38.8214C43.3968 38.8553 43.3621 38.8425 43.3654 38.8603C43.3673 38.8709 43.4775 38.9354 43.4166 39.004C43.3944 39.0291 43.322 38.8687 43.3511 39.221C43.4632 39.0807 43.4118 39.7094 43.3837 39.825C43.3988 39.8019 43.4139 39.7788 43.4289 39.7557C43.3883 39.8701 43.4264 39.8907 43.4243 39.9165C43.416 40.0203 43.3776 40.163 43.3811 40.2597C43.3851 40.3728 43.4548 40.3732 43.4277 40.5051C43.4431 40.4738 43.4585 40.4425 43.4739 40.4112C43.4702 40.5023 43.4665 40.5935 43.4628 40.6846C43.3704 40.4736 43.4583 40.7301 43.4603 40.747C43.4637 40.7739 43.4259 40.7352 43.4306 40.7803C43.4314 40.7849 43.467 40.7782 43.471 40.8477C43.4792 40.9928 43.4345 40.9699 43.435 41.0308C43.4352 41.0364 43.4673 41.0169 43.4748 41.1221C43.499 41.4567 43.4503 41.1205 43.4458 41.1076C43.44 41.0908 43.306 41.2055 43.3535 40.9213C43.3384 41.0167 43.2791 41.0263 43.2776 41.0371C43.2764 41.0466 43.2848 41.2119 43.2868 41.221C43.307 41.3023 43.3475 41.2308 43.3547 41.2466C43.3606 41.2596 43.3078 41.4588 43.4296 41.5055C43.3172 41.6008 43.3275 41.4506 43.3103 41.2908C43.2872 41.2675 43.2648 41.443 43.2648 41.4522C43.265 41.6786 43.3575 41.5533 43.4166 41.6028C43.4475 41.6288 43.3844 41.721 43.4673 41.6358C43.4761 41.8413 43.4281 41.7167 43.4209 41.73C43.4105 41.75 43.4343 41.8219 43.4311 41.8309C43.4264 41.8441 43.3977 41.7982 43.3876 41.8503C43.3861 41.8589 43.4355 41.9428 43.4591 41.8346C43.4521 41.9792 43.4942 41.9673 43.4093 42.0163C43.5699 42.1159 43.3144 42.0886 43.3054 42.1278C43.2817 42.232 43.4078 42.2018 43.4139 42.2073C43.4533 42.2452 43.41 42.5339 43.4282 42.6053C43.3374 42.5771 43.4272 42.3765 43.4096 42.3317C43.351 42.1821 43.3642 42.5425 43.2501 42.4338C43.2814 42.4794 43.3128 42.5249 43.3441 42.5705C43.2707 42.6539 43.2388 42.5355 43.2656 42.7602C43.3289 42.7969 43.2556 42.6013 43.3054 42.6406C43.3347 42.6637 43.341 42.794 43.3564 42.7966C43.375 42.7991 43.353 42.6814 43.3816 42.6999C43.4432 42.7404 43.3845 43.1699 43.3509 42.843C43.3519 42.9342 43.2293 42.9812 43.2675 43.0603C43.2923 43.1114 43.4617 42.8237 43.4306 43.2553C43.3727 43.2645 43.4135 43.0827 43.4091 43.078C43.4027 43.0714 43.272 43.1043 43.2656 43.11C43.2443 43.1301 43.3143 43.5709 43.2486 43.664C43.3242 43.6271 43.2621 43.9971 43.2851 44.0374C43.2915 44.0481 43.3378 44.008 43.3426 44.0195C43.3718 44.091 43.2892 44.2845 43.2871 44.3742C43.2846 44.4747 43.3246 44.4619 43.3245 44.4676C43.3223 44.5118 43.2952 44.4765 43.2953 44.5035C43.2954 44.5443 43.2899 44.8248 43.2955 44.8389C43.2973 44.843 43.3429 44.7972 43.3516 44.8584C43.3531 44.869 43.299 44.8622 43.3223 45.0433C43.3505 45.2614 43.3896 44.8919 43.4463 44.9825C43.3656 45.1226 43.4456 45.1181 43.4393 45.156C43.437 45.1692 43.369 45.2671 43.3733 45.3734C43.3623 45.2971 43.3513 45.2208 43.3402 45.1445C43.3283 45.2195 43.3431 45.3652 43.3296 45.427C43.323 45.4571 43.2672 45.4323 43.2687 45.4978C43.2693 45.5117 43.4054 45.5668 43.3443 45.3953C43.3929 45.3816 43.3613 45.4632 43.375 45.5011C43.3772 45.5068 43.4583 45.5294 43.4079 45.5778C43.3955 45.5894 43.1587 45.4629 43.3301 45.789C43.3356 45.7995 43.3653 45.763 43.3714 45.7733C43.3756 45.7803 43.3636 45.8635 43.3678 45.8727C43.3723 45.8821 43.4047 45.8419 43.411 45.8531C43.4439 45.9105 43.3155 45.9859 43.3252 45.8675C43.3094 45.9071 43.2935 45.9467 43.2776 45.9862C43.3744 45.9439 43.3049 46.0484 43.3078 46.1031C43.3269 46.454 43.3898 46.2191 43.4224 46.2794C43.4747 46.3764 43.3091 46.3023 43.3588 46.4463C43.3635 46.4597 43.4338 46.2855 43.3941 46.6255C43.3914 46.5754 43.3886 46.5252 43.3859 46.475C43.2923 46.5039 43.3923 46.6562 43.3936 46.6679C43.4065 46.8014 43.3727 46.7112 43.4209 46.9094C43.4253 46.9271 43.4022 46.9657 43.4137 47.0035C43.4612 47.1605 43.4425 46.7965 43.4804 46.7865C43.499 46.7818 43.4943 47.1733 43.4855 47.1867C43.4464 47.2438 43.4683 47.0092 43.4197 47.0539C43.4025 47.0703 43.4379 47.6282 43.419 47.7402C43.397 47.8693 43.2701 47.9275 43.4127 47.9283C43.2728 47.9648 43.3683 47.997 43.3673 48.0135C43.3543 48.2132 43.3529 48.2136 43.3663 48.3849C43.3692 48.4227 43.3268 48.4547 43.3339 48.4681C43.3383 48.4758 43.3837 48.4613 43.3977 48.4994C43.4169 48.5524 43.3702 48.8709 43.3451 48.8945C43.3199 48.9182 43.3342 48.76 43.2929 48.7884C43.2887 48.9029 43.2989 49.0126 43.2946 49.1279C43.2926 49.1757 43.2637 49.1511 43.2631 49.1718C43.2628 49.1806 43.2882 49.3459 43.2989 49.3389C43.3237 49.3225 43.307 48.8121 43.3576 48.9465C43.3674 48.9724 43.3008 49.0641 43.3818 49.0495C43.3634 49.5055 43.3451 49.9614 43.3267 50.4174C43.2661 50.1554 43.3203 49.8606 43.3146 49.5862C43.3139 49.5486 43.3217 49.4214 43.2808 49.4369C43.2702 49.6702 43.2915 49.9603 43.2648 50.1844C43.264 50.1916 43.2272 50.1652 43.2213 50.1921C43.2105 50.2423 43.2698 50.4058 43.2544 50.4332C43.2509 50.4379 43.2024 50.3449 43.1716 50.3732C43.0925 50.4458 43.2676 50.4643 43.2656 50.5267C43.2639 50.575 43.1792 50.8994 43.2327 50.9802C43.2897 51.0662 43.2658 50.7411 43.3124 50.7651C43.3593 50.9851 43.3093 51.2077 43.3151 51.4155C43.3152 51.4192 43.3518 51.3874 43.3569 51.4338C43.3658 51.5145 43.314 51.5357 43.3057 51.5749C43.2968 51.6173 43.3043 51.7671 43.2854 51.7871C43.2829 51.7896 43.2315 51.7593 43.23 51.7547C43.2088 51.6894 43.2756 51.6663 43.2764 51.6603C43.279 51.638 43.2534 51.6161 43.2549 51.5958C43.2575 51.5623 43.2811 51.5438 43.2832 51.4996C43.2847 51.4691 43.2393 51.4985 43.2414 51.4691C43.2423 51.4583 43.346 51.3419 43.2402 51.331C43.2068 51.3277 43.164 52.2798 43.1906 52.375C43.2034 52.2933 43.2161 52.2117 43.2288 52.1301C43.1978 52.2959 43.2824 52.495 43.1573 52.5091C43.1471 53.1238 43.1368 53.7386 43.1266 54.3533C43.1159 54.4631 43.0355 54.4029 43.0589 54.5835C43.0846 54.5368 43.1102 54.4901 43.1358 54.4435C43.1178 54.536 43.0827 54.9462 43.0993 55.0126C43.1015 55.0211 43.1742 55.0331 43.1805 55.1356C43.186 55.2265 43.1315 55.2411 43.121 55.2897C43.1124 55.3306 43.1267 55.3764 43.1237 55.3885C43.1213 55.3978 43.088 55.4015 43.0821 55.4239C43.0642 55.4945 43.158 55.4372 43.0502 55.5073C43.0461 55.4903 43.042 55.4732 43.0379 55.4561C43.0223 55.5414 42.9734 55.6578 42.9492 55.5323C42.9451 55.5107 42.9773 55.5292 42.9773 55.5131C42.9713 54.8828 42.9086 55.3861 42.9587 55.607C42.9109 55.6638 42.94 55.9817 42.9306 55.9923C42.917 56.007 42.8788 55.9525 42.8458 56.0239C42.8388 56.0389 42.8656 56.464 42.8021 56.3109C42.789 56.2793 42.8027 56.0755 42.8008 56.0264C42.6995 56.142 42.8447 56.413 42.841 56.4434C42.8252 56.5664 42.7532 56.2073 42.7414 56.4842C42.7324 56.6972 42.8 56.4972 42.8289 56.5791C42.8451 56.6252 42.7706 56.8661 42.8671 56.8596C42.8774 56.9423 42.8263 56.8939 42.8226 56.9041C42.8194 56.9141 42.8483 57.0767 42.8279 57.1295C42.8254 57.1359 42.7752 57.1158 42.7711 57.1224C42.7641 57.1353 42.7741 57.2921 42.7784 57.2984C42.7813 57.3024 42.8252 57.265 42.8359 57.2804C42.8482 57.2983 42.8378 57.4493 42.8504 57.4576C42.8694 57.4693 42.8569 57.283 42.906 57.3141C42.8936 57.3999 42.9264 57.5399 42.9659 57.5966C42.9546 57.5827 42.953 57.4994 42.957 57.4705C43.0289 57.4841 43.0279 57.6629 42.971 57.6018C43.0015 57.6406 43.0178 57.6141 43.0466 57.636C43.0539 57.6417 43.0554 57.6969 43.0679 57.7076C43.0704 57.709 43.0975 57.652 43.1121 57.6634C43.1385 57.684 43.1326 57.8514 43.1256 57.8651C43.106 57.9037 43.0823 57.7672 43.0519 57.7558C43.0473 57.7542 42.9878 57.8703 42.9826 57.872C42.9262 57.8788 42.9668 57.7497 42.9161 57.7644C42.9054 57.7964 42.8947 57.8283 42.884 57.8603C42.8326 57.737 42.859 57.5091 42.8006 57.4503C42.818 57.633 42.8159 57.8242 42.6844 57.8238C42.629 57.8237 42.5965 57.7448 42.5824 57.7479C42.532 57.7595 42.5867 57.8689 42.5841 57.8729C42.581 57.8763 42.578 57.8778 42.5751 57.8778C42.5751 57.8778 42.5751 57.8778 42.5751 57.8778C42.5456 57.8778 42.5243 57.7218 42.5109 57.714C42.4869 57.7009 42.3884 57.7703 42.3666 57.7702C42.3622 57.7678 42.3389 57.6567 42.3009 57.6942C42.2624 57.7321 42.2616 57.8293 42.2576 57.8327C42.2346 57.8513 42.2137 57.6813 42.2001 57.6762C42.1932 57.6735 42.1511 57.7648 42.1389 57.7675C42.1268 57.7698 42.1002 57.7004 42.0619 57.673C42.0333 57.6526 42.0115 57.712 42.007 57.7016C42.004 57.6941 42.0045 57.5334 41.9995 57.5255C41.9921 57.5138 41.958 57.5514 41.9495 57.5459C41.9372 57.5382 41.9495 57.4863 41.9369 57.493C41.9275 57.4981 41.81 57.6992 41.7786 57.6979C41.7251 57.6956 41.8483 57.4826 41.637 57.6808C41.6356 57.6822 41.6506 57.7305 41.6493 57.7318C41.6105 57.7616 41.5507 57.6069 41.5611 57.796C41.4936 57.4442 41.4807 57.7523 41.3905 57.7002C41.3559 57.6801 41.3416 57.5437 41.3364 57.5431C41.2924 57.5563 41.3265 57.5998 41.305 57.6146C41.2929 57.6227 41.2465 57.5007 41.2163 57.5281C41.2007 57.5423 41.2063 57.6719 41.2032 57.6772C41.1746 57.7285 41.1438 57.6656 41.1235 57.6769C41.1099 57.6843 41.1088 57.7625 41.1063 57.7645C41.1012 57.7678 41.0462 57.6617 41.0268 57.6396C41.0119 57.6228 40.9886 57.6859 40.9821 57.6741C40.9433 57.6035 41.0423 57.4532 40.9036 57.598C40.8951 57.6069 40.8985 57.6617 40.8968 57.6633C40.8575 57.6971 40.8541 57.5963 40.8219 57.5782C40.7664 57.5472 40.7974 57.6922 40.7583 57.5716C40.7221 57.6621 40.7236 57.7125 40.7337 57.8183C40.7055 57.5253 40.5619 57.4218 40.5655 57.7472C40.5677 57.6437 40.4867 57.6552 40.4853 57.6243C40.4845 57.6051 40.5651 57.455 40.3843 57.5238C40.3617 57.5325 40.3904 57.6236 40.3441 57.5951C40.3559 57.3763 40.3147 57.5904 40.3086 57.5907C40.2021 57.5878 40.2893 57.0532 40.2772 56.9613C40.2631 56.8547 40.1792 56.76 40.1791 56.7368C40.1791 56.6606 40.2217 56.7238 40.2373 56.7068C40.2529 56.6895 40.1712 56.4727 40.1757 56.4619C40.1937 56.4199 40.2442 56.4625 40.2468 56.4582C40.2777 56.4062 40.2382 56.115 40.2499 56.0335C40.2171 56.036 40.2145 56.1997 40.1619 56.0975C40.1006 55.9785 40.245 55.9717 40.2513 55.9686C40.25 55.4234 40.2486 54.8783 40.2472 54.3331C40.1704 54.3399 40.2283 54.6963 40.2182 54.7045C40.1584 54.7521 40.1595 54.15 40.1866 54.0761C40.17 54.1322 40.1534 54.1883 40.1368 54.2444C40.0485 54.1486 40.1632 53.9366 40.1242 53.798C40.1116 53.7533 40.0775 53.8392 40.0752 53.8375C40.0409 53.7871 40.0673 53.7064 40.1134 53.7668C40.0692 53.6439 40.1179 53.6619 40.1216 53.5676C40.1217 53.5628 40.0861 53.6032 40.0713 53.5287C40.0644 53.4937 40.0643 53.3074 40.0331 53.2824C40.02 53.2721 39.8818 53.3667 40.0007 53.3784C39.9428 53.5811 40.0549 53.4431 40.0522 53.5219C40.0516 53.534 39.9852 53.5062 40.0165 53.7045C39.8967 53.6667 39.9862 53.4383 39.9717 53.3992C39.9419 53.3185 39.8801 53.6511 39.9734 53.7122C39.88 53.6837 39.9608 53.7358 39.957 53.8099C39.9528 53.8911 39.925 53.8557 39.9249 53.8996C39.9242 54.0198 39.9901 53.97 39.9307 54.069C40.1147 53.9724 39.955 54.2385 39.9067 54.316C39.8974 54.1899 39.888 54.0637 39.8787 53.9376C39.869 53.9448 39.8594 53.952 39.8497 53.9592C39.8511 53.926 39.8524 53.8928 39.8538 53.8595C39.8631 53.8649 39.8723 53.8702 39.8816 53.8755C39.8214 53.7042 39.8891 53.6624 39.8898 53.6484C39.8977 53.4686 39.8971 53.2608 39.8973 53.079C39.8973 53.0517 39.8371 53.0704 39.8843 52.8716C39.8993 52.8081 39.9462 52.868 39.9391 52.7961C39.8118 52.7062 39.9133 52.7079 39.9135 52.6812C39.9135 52.6044 39.8819 52.5575 39.8816 52.5504C39.8767 52.4556 39.8819 52.3168 39.8773 52.2127C39.8768 52.2107 39.8376 52.2649 39.8492 52.1973C39.8534 52.1735 40.0204 51.9604 39.9659 51.7742C39.9547 51.8226 39.9434 51.8711 39.9321 51.9195C39.9479 51.8625 39.9058 51.4634 39.8611 51.561C39.8337 51.6208 39.9414 51.7669 39.8379 51.7829C39.8689 51.6501 39.8225 50.9165 39.8466 50.8594C39.85 50.8515 39.8836 50.9001 39.8879 50.8892C39.8912 50.8807 39.8832 50.7127 39.8961 50.6904C39.9038 50.6771 39.9244 50.7513 39.9365 50.7453C39.9451 50.74 39.9595 50.5302 39.9174 50.5182C39.9343 50.5697 39.9195 50.7146 39.884 50.6386C39.8796 50.6288 39.9068 50.5782 39.9012 50.5663C39.8496 50.4562 39.862 50.7853 39.8615 50.8363C39.8079 50.6295 39.8711 50.3097 39.8362 50.0702C39.8712 49.9734 39.8898 50.2137 39.9188 50.1042C39.979 49.877 39.8704 50.0437 39.8659 50.0367C39.8305 49.9802 40.02 49.788 39.8758 49.7879C39.8975 49.7056 39.9157 49.7322 39.8968 49.616C39.8868 49.6313 39.8769 49.6466 39.8669 49.6618C39.7833 49.5328 39.9941 49.2596 40.0102 49.2801C40.0532 49.3352 39.9861 49.4774 39.9877 49.4896C39.9901 49.5075 40.1364 49.5573 40.0056 49.754C40.1037 49.8346 40.0718 49.4421 40.1387 49.6207C40.1278 49.5001 40.1961 49.0039 40.153 48.9325C40.1474 48.924 40.0496 48.9637 40.0993 48.8411C40.123 48.7829 40.1242 48.9232 40.1465 48.8966C40.2148 48.8146 40.1711 47.7002 40.1675 47.4885C40.1674 47.4747 40.1977 47.4798 40.1975 47.4663C40.1966 47.4248 40.1513 47.2736 40.1653 47.1994C40.1091 47.3532 40.1048 47.0545 40.1109 46.9785C40.1204 46.8632 40.1738 46.8703 40.1851 46.8205C40.2289 46.6285 40.1021 46.3309 40.2207 46.1817C40.103 46.1899 40.2783 45.9237 40.2794 45.8026C40.2802 45.7078 40.2024 45.5701 40.1549 45.6982C40.1603 45.5344 40.1384 45.3621 40.1312 45.2085C40.13 45.1831 40.1648 45.218 40.1617 45.1747C40.1612 45.1708 40.1271 45.1654 40.1235 45.1282C40.0938 44.8211 40.1662 44.9705 40.1875 44.9131C40.1995 44.8809 40.2054 44.8572 40.2074 44.8398C40.214 45.0188 40.2274 45.2252 40.2284 45.2804C40.3037 45.2333 40.2139 44.8837 40.2342 44.7813C40.2349 44.7778 40.2764 44.7901 40.2767 44.7865C40.2767 44.7865 40.2767 44.7864 40.2767 44.7863C40.2799 44.7479 40.2646 44.5036 40.2151 44.5539C40.2019 44.5674 40.2019 44.6799 40.2064 44.8133C40.1971 44.7772 40.1506 44.8041 40.1486 44.7978C40.1257 44.7205 40.171 44.5312 40.1772 44.4641C40.1785 44.4487 40.1487 44.4498 40.1486 44.4473C40.1554 44.3862 40.2405 44.4113 40.1527 44.3486C40.2587 44.238 40.1685 44.5559 40.2373 44.5335C40.2903 44.5163 40.2619 43.8103 40.1784 43.8124C40.1873 43.81 40.1984 43.8002 40.211 43.7803C40.239 43.7362 40.2302 43.5397 40.2149 43.5058C40.2118 43.5 40.1308 43.5023 40.13 43.4952C40.1282 43.4775 40.1917 43.2373 40.1438 43.1476C40.1324 43.196 40.1211 43.2445 40.1097 43.2929C40.109 43.0004 40.0849 43.0456 40.0607 43.1431C40.0605 43.1479 40.0574 43.1527 40.057 43.1573C40.0391 43.2329 40.0219 43.3297 40.0155 43.3312C39.9911 43.3367 39.9775 42.8404 40.0527 42.9359C40.063 42.9492 40.0295 43.1788 40.0831 43.0651C40.0925 43.0452 40.0772 42.8977 40.0831 42.89C40.1225 42.8382 40.1747 43.1602 40.2306 43.1209C40.1774 43.0427 40.2054 42.9424 40.1917 42.8527C40.1854 42.8119 40.1448 42.8019 40.144 42.7969C40.1334 42.7217 40.176 42.7639 40.175 42.7388C40.1742 42.7253 40.0836 42.5771 40.2086 42.6051C40.1166 42.1168 40.1167 42.47 40.1237 42.7696C40.0782 42.6749 40.1002 42.4894 40.0897 42.4061C40.0858 42.3762 40.0441 42.3939 40.0358 42.3435C40.0186 42.2396 40.0665 41.7436 40.0778 41.6144C40.0926 41.6938 40.138 41.6706 40.1349 41.6093C40.1317 41.5481 40.0711 41.5995 40.0645 41.5876C40.0578 41.5748 40.0864 41.2874 40.0786 41.2396C40.1005 41.4559 40.1458 41.4071 40.1506 41.2235C40.1636 41.2501 40.1767 41.2766 40.1897 41.3032C40.1714 41.1955 40.2405 40.9693 40.2199 40.907C40.2166 40.8973 40.1785 40.9323 40.1767 40.9269C40.1605 40.8723 40.1993 40.6866 40.1863 40.678C40.1755 40.6707 40.1436 40.7499 40.1279 40.7205C40.1245 40.7143 40.176 40.638 40.1634 40.5628C40.1587 40.5349 40.1227 40.5517 40.1206 40.5447C40.1033 40.4861 40.1639 40.5207 40.1542 40.4136C40.147 40.3352 40.0877 40.2768 40.1073 40.1684C40.0317 40.5243 40.0633 40.2251 40.0404 40.0763C40.0367 40.0524 39.9713 40.0729 40.0032 39.9304C40.1214 40.2336 40.0657 39.8439 40.067 39.7642C40.0674 39.7598 40.1105 39.7583 40.1112 39.7192C40.1111 39.7159 40.082 39.7207 40.0798 39.6844C40.0587 39.3397 40.0916 39.5601 40.1204 39.4946C40.1326 39.4667 40.0914 39.2992 40.0904 39.254C40.0903 39.2436 40.1206 39.2484 40.1194 39.2083C40.1172 39.1372 40.085 39.0736 40.0824 39.0267C40.0823 39.0212 40.1301 39.021 40.1146 38.9321C40.1102 38.9071 40.0933 38.8791 40.0795 38.9145C40.0343 39.0323 40.1125 39.2555 40.0674 39.3886C40.0264 39.5099 40.0225 39.1274 40.0223 39.1075C40.0221 39.1002 40.0458 39.1749 40.0505 39.099C40.0544 39.0341 39.9719 38.9157 39.9899 38.8191C39.9912 38.8117 40.0612 38.7345 40.0653 38.7381C40.0682 38.7413 40.0834 38.8598 40.1037 38.8426C40.106 38.8406 40.1055 38.7652 40.1206 38.7554C40.139 38.7434 40.3191 38.7109 40.3236 38.6948C40.3348 38.6535 40.2937 38.6804 40.2965 38.6537C40.3026 38.5964 40.3558 38.3978 40.2934 38.3913C40.2897 38.4241 40.286 38.457 40.2823 38.4898C40.2759 38.3072 40.2493 38.385 40.2376 38.3592C40.2249 38.3313 40.2798 38.3391 40.2849 38.2776C40.2861 38.2642 40.2746 38.0067 40.2516 38.0114C40.2882 38.1538 40.2204 38.101 40.2192 38.1076C40.2148 38.1325 40.2528 38.1644 40.2521 38.1979C40.2461 38.4333 40.1861 38.1959 40.1706 38.2514C40.1654 38.2706 40.1979 38.3087 40.1962 38.3168C40.1909 38.3432 40.1483 38.3436 40.1518 38.3612C40.1598 38.4023 40.2199 38.3543 40.2231 38.3576C40.2607 38.3943 40.2139 38.538 40.1484 38.4485C40.1248 38.5023 40.2044 38.5086 40.1726 38.5512C40.1096 38.6359 40.1257 38.509 40.1153 38.4746C40.0776 38.3513 40.1081 38.3147 40.0976 38.1401C40.094 38.0772 40.0553 38.0028 40.0532 37.9736C40.0518 37.9552 40.1863 37.7817 39.9759 37.7766C39.9962 37.7092 40.1349 37.6033 40.1286 37.5339C40.1228 37.4715 40.0483 37.4913 40.0455 37.4855C40.0409 37.4766 40.0468 37.4011 40.0363 37.3756C40.0238 37.3457 39.9954 37.3606 39.9838 37.3132C39.9551 37.1951 40.0311 37.1982 40.036 37.1861C40.0931 37.0452 39.985 37.1069 39.9763 37.0757C39.9684 37.0466 40.01 36.6388 39.9826 36.553C39.9978 36.5879 40.0131 36.6229 40.0283 36.6578C40.0757 36.5953 39.9984 36.529 40.0834 36.5279C39.9461 36.5152 40.0379 36.3862 40.0343 36.3474C40.0329 36.3322 40.0095 36.3334 40.0085 36.3142C40.0044 36.2396 40.023 36.0712 40.0111 36.0307C39.9601 35.8556 39.8751 36.3034 39.87 36.3387C39.8715 36.2681 39.8408 35.8688 39.7748 36.0523C39.7646 36.0807 39.826 36.131 39.8284 36.1469C39.8443 36.2548 39.7892 36.17 39.784 36.1784C39.7755 36.1928 39.8287 36.2638 39.8224 36.2825C39.8204 36.2888 39.7705 36.2485 39.7695 36.3514C39.7212 36.3008 39.7605 36.0117 39.7492 35.9737C39.7451 35.9602 39.6419 36.0449 39.7422 35.7975C39.7326 35.8004 39.723 35.8032 39.7134 35.8061C39.7095 35.6683 39.7055 35.5305 39.7016 35.3928C39.7237 35.4077 39.768 35.4851 39.7586 35.3877C39.7532 35.3316 39.704 35.3731 39.7025 35.3679C39.689 35.3176 39.7054 34.4267 39.6999 34.254C39.6981 34.1953 39.6586 34.0316 39.6578 34.0191C39.6539 33.9444 39.6796 33.6801 39.674 33.6274C39.6704 33.5945 39.6293 33.6258 39.6312 33.5963C39.6331 33.569 39.6728 33.5973 39.6745 33.5892C39.6889 33.5219 39.6368 33.011 39.6743 32.8896C39.663 32.9638 39.7424 33.3339 39.7704 33.3264C39.7743 33.3248 39.8045 33.2349 39.7898 33.2163C39.8242 33.1857 39.7194 33.0804 39.74 33.0232C39.7423 33.0167 39.8011 33.0422 39.8118 32.94C39.8154 32.9048 39.7696 32.8127 39.8209 32.7199C39.7963 32.5857 39.8725 31.8797 39.8093 31.8313C39.806 31.8299 39.7843 31.9293 39.7584 31.8621C39.7239 31.7728 39.8399 31.853 39.8499 31.749C39.8515 31.7333 39.8397 31.4438 39.8325 31.4343C39.7674 31.3466 39.741 31.5996 39.7335 31.596C39.7144 31.5872 39.7029 31.377 39.7074 31.3685C39.712 31.3603 39.7983 31.5318 39.7656 31.3258C39.7553 31.3494 39.745 31.373 39.7347 31.3966C39.7146 31.2997 39.7743 31.2905 39.7779 31.267C39.7895 31.194 39.6988 31.1151 39.8108 30.9982C39.8405 30.9673 39.8735 31.0186 39.878 31.0147C39.918 30.9776 39.811 30.9302 39.8908 30.8744C39.8967 30.8702 39.9446 31.0001 39.9447 30.773C39.937 30.7886 39.9294 30.8043 39.9217 30.8199C39.9046 30.7879 39.8945 30.5579 39.8985 30.527C39.9103 30.4366 39.9653 30.5154 39.9587 30.4246C39.8834 30.4828 39.8736 30.2066 39.9384 30.2225C39.857 30.1839 39.9198 29.9493 39.9217 29.8389C39.9229 29.7693 39.8874 29.6274 39.8915 29.6053C39.8966 29.5783 39.9521 29.5865 39.9645 29.5379C39.968 29.524 39.9273 29.3792 39.9848 29.2521C39.9959 29.2274 40.0901 29.1757 40.1136 29.2215C40.1539 29.2999 40.078 29.4481 40.1337 29.4462C40.1932 29.444 40.1578 29.2443 40.1656 29.1906C40.2015 28.9424 40.2648 29.0857 40.284 29.0793C40.3305 29.0628 40.3291 28.9272 40.3333 28.9215C40.3519 28.8981 40.3887 28.9942 40.4171 28.9956C40.4541 28.9974 40.5209 28.8667 40.5334 28.8964C40.5511 28.9389 40.4954 29.059 40.4981 29.0666C40.534 29.1658 40.6194 29.0299 40.6614 28.9924C40.6744 28.9811 40.6956 29.0263 40.6994 29.0169C40.7569 28.8732 40.5793 28.9866 40.5911 28.8911C40.6017 28.8058 40.6579 28.9155 40.661 28.9123C40.6644 28.908 40.6674 28.8061 40.6873 28.7901C40.6972 28.7823 40.8065 29.0472 40.8555 29.0362C40.8447 28.9516 40.8339 28.8671 40.8231 28.7826C40.887 28.7759 40.84 28.8975 40.8465 28.9101C40.8598 28.9354 40.8921 28.8648 40.9123 28.8678C40.9251 28.8695 40.971 28.9523 40.9899 28.8775C40.9964 28.8517 40.9516 28.7978 40.9973 28.7041C41.0558 29.0302 41.0917 28.8042 41.1143 28.7946C41.1369 28.7851 41.1902 28.9408 41.1808 28.7519C41.3051 28.7437 41.2201 28.7559 41.2419 28.8096C41.2688 28.8754 41.3097 28.7234 41.2786 28.9638C41.3368 28.9501 41.3327 28.7569 41.3374 28.7466C41.3416 28.7378 41.3702 28.7808 41.3799 28.7654C41.4923 28.5843 41.441 28.7087 41.5128 28.6563C41.5192 28.6516 41.5458 28.4804 41.5563 28.6107C41.5753 28.8482 41.4928 28.9474 41.6692 28.9874C41.7457 28.8117 41.6319 28.5989 41.63 28.5455C41.6272 28.4637 41.6632 28.5484 41.6733 28.5383C41.6765 28.5348 41.6736 28.4644 41.6764 28.4635C41.8109 28.4132 41.6786 28.777 41.702 28.8915C41.7222 28.8608 41.7423 28.8301 41.7624 28.7994C41.7632 28.8411 41.764 28.8827 41.7649 28.9244C41.8053 28.726 41.7802 28.9174 41.8891 28.9668C41.9135 28.978 41.8716 28.8476 41.9396 28.9963C41.9553 28.8866 41.9775 28.9216 41.9468 28.8223C41.9905 28.8249 42.0397 29.0483 42.0621 29.1364C42.1111 28.8251 41.9511 29.0026 42.0358 28.7335C41.9817 28.6836 41.9922 28.8121 41.9833 28.8016C41.9512 28.764 42.0022 28.6759 41.8898 28.5696C41.8713 28.5523 41.8146 28.6255 41.8173 28.5172C41.8177 28.5052 41.8662 28.4361 41.8697 28.4371C41.9077 28.4462 41.8935 28.5146 41.9094 28.5174C41.9244 28.52 41.9154 28.4438 41.9195 28.4435C41.9671 28.4412 41.9377 28.5071 41.9526 28.4976C41.985 28.4769 42.0875 28.2026 42.0575 28.5605C42.0037 28.2633 42.0049 28.5225 42.0256 28.6382C42.0308 28.6678 42.0592 28.6752 42.0691 28.7173C42.0819 28.7714 42.0682 28.8348 42.0735 28.8627C42.0792 28.8929 42.1464 28.7218 42.1264 28.9692C42.1933 28.8433 42.122 28.6208 42.1689 28.4971C42.2638 28.2475 42.2842 28.6711 42.2934 28.7153C42.2959 28.727 42.3343 28.6876 42.3366 28.6954C42.3402 28.7083 42.3225 28.9487 42.3543 28.9724C42.386 28.996 42.3528 28.8843 42.3859 28.8769C42.4082 28.8719 42.4478 29.1619 42.463 29.0049C42.4735 28.8967 42.3838 28.6972 42.4802 28.6636C42.4881 28.8228 42.4961 28.9819 42.5041 29.1411C42.5407 29.054 42.5774 28.9668 42.614 28.8797C42.6257 29.0584 42.5843 29.2128 42.6368 29.3824C42.7542 28.9748 42.7305 29.5148 42.7448 29.5208C42.7533 29.5227 42.8487 29.3623 42.8661 29.3365C42.9028 29.4787 42.9207 29.9107 43.0384 29.6579C43.0118 29.7038 43.0774 29.8149 43.0824 29.8135C43.1344 29.7993 43.1007 29.557 43.1476 29.5965C43.2021 29.6423 43.1282 29.7065 43.1341 29.777C43.1649 30.1386 43.4364 30.0394 43.3934 30.4019C43.4031 30.3947 43.4127 30.3875 43.4224 30.3803C43.407 30.7744 43.3916 31.1684 43.3762 31.5625C43.4591 31.7167 43.5096 32.127 43.5005 32.3286C43.4987 32.3692 43.4552 32.5684 43.4475 32.5835C43.4329 32.6113 43.4273 32.4582 43.3999 32.5274C43.3943 32.542 43.376 32.8793 43.4224 32.8552C43.4278 32.8174 43.4045 32.6991 43.4154 32.6797C43.4934 32.5437 43.4311 33.5837 43.4625 33.6352C43.4776 33.6122 43.4926 33.5891 43.5077 33.5661C43.5003 33.6317 43.4929 33.6973 43.4855 33.763ZM39.7603 30.7475C39.7138 30.7081 39.7487 30.6094 39.7356 30.5511C39.7173 30.4705 39.5381 30.3335 39.7178 30.3925C39.7319 30.5108 39.7461 30.6292 39.7603 30.7475ZM39.6909 32.477C39.7159 32.3976 39.8163 32.4592 39.7745 32.5242C39.7698 32.5314 39.6573 32.5843 39.6909 32.477ZM39.7385 31.6451C39.7399 31.6484 39.7372 31.717 39.7356 31.7194C39.6954 31.7809 39.7036 31.5742 39.7385 31.6451ZM39.79 35.6637C39.7857 35.5763 39.6945 35.6396 39.732 35.6939C39.7344 35.6974 39.7902 35.6695 39.79 35.6637ZM39.7924 35.6015C39.8741 35.5336 39.7086 35.3969 39.7253 35.5056C39.7269 35.5161 39.7885 35.6047 39.7924 35.6015ZM39.7308 32.1941C39.7621 32.2031 39.747 32.2849 39.7395 32.3199C39.7109 32.3189 39.7343 32.2284 39.7308 32.1941ZM39.7395 34.2694C39.7641 34.2729 39.7628 33.9884 39.7303 33.969C39.7441 34.0139 39.7174 34.2661 39.7395 34.2694ZM39.7741 34.999C39.7783 34.9918 39.7719 34.8935 39.7501 34.8964C39.7217 34.9444 39.7548 35.0315 39.7741 34.999ZM39.7726 36.4491C39.7781 36.4545 39.9162 36.3809 39.8253 36.5553C39.812 36.5809 39.7759 36.4894 39.7709 36.4985C39.7613 36.5176 39.7567 36.5326 39.7559 36.5447C39.7445 36.4635 39.7391 36.3791 39.7475 36.371C39.7871 36.3327 39.7703 36.4468 39.7726 36.4491ZM39.8756 37.2105C39.8981 37.2272 39.8861 37.3341 39.8768 37.3584C39.875 37.3626 39.8158 37.3444 39.8202 37.3925C39.8239 37.4311 39.8845 37.3734 39.8748 37.4487C39.8651 37.5247 39.8219 37.4231 39.8188 37.4298C39.8147 37.4387 39.842 37.5563 39.8067 37.5527C39.7806 37.5499 39.7982 37.4239 39.7927 37.3927C39.7855 37.3528 39.742 37.4012 39.7514 37.3345C39.7572 37.2926 39.8338 37.3158 39.8376 37.307C39.8407 37.2995 39.7967 37.153 39.8753 37.2107C39.8754 37.2106 39.8755 37.2105 39.8756 37.2105ZM39.7593 36.5667C39.7567 36.5606 39.7554 36.5534 39.7559 36.5447C39.757 36.5521 39.7582 36.5595 39.7593 36.5667ZM39.7939 30.9768C39.7703 31.018 39.74 30.8956 39.7709 30.8492C39.7959 30.8484 39.7976 30.9702 39.7939 30.9768ZM39.8217 36.642C39.8025 36.7627 39.7761 36.674 39.7593 36.5667C39.7737 36.6008 39.8281 36.6015 39.8217 36.642ZM39.7898 33.2163C39.7841 33.2214 39.7752 33.2246 39.7605 33.225C39.7765 33.2117 39.7851 33.2105 39.7898 33.2163ZM39.7637 33.4978C39.8082 33.5943 39.8064 33.3982 39.7745 33.3995C39.7625 33.4001 39.7619 33.4939 39.7637 33.4978ZM39.7857 35.7758C39.79 35.767 39.9246 35.9041 39.8236 35.705C39.8077 35.8113 39.7931 35.6992 39.7813 35.7009C39.7475 35.7052 39.78 35.8837 39.7654 35.9232C39.826 35.9542 39.7713 35.805 39.7857 35.7761C39.7857 35.776 39.7857 35.7759 39.7857 35.7758ZM39.8429 38.5825C39.8074 38.5584 39.8189 38.4816 39.8209 38.4298C39.8565 38.454 39.845 38.5308 39.8429 38.5825ZM39.8379 52.1316C39.805 51.7768 39.9496 51.7308 39.8925 52.0554C39.8913 52.0618 39.8525 52.1531 39.8379 52.1316ZM39.8753 49.0868C39.9383 49.0533 39.9485 49.164 39.9224 49.2366C39.9166 49.2531 39.8528 49.3139 39.8403 49.2444C39.9167 49.2466 39.9458 49.1393 39.8753 49.0868ZM39.862 36.7102C39.9041 36.7454 39.8741 36.8535 39.8678 36.9105C39.8332 36.8757 39.8489 36.7606 39.862 36.7102ZM39.9133 50.9657C39.918 50.9284 39.8632 50.9031 39.8586 50.9096C39.8377 50.9385 39.8821 51.0083 39.9133 50.9657ZM39.8686 36.3611C39.8937 36.3562 39.9178 36.4994 39.8557 36.5094C39.8602 36.4788 39.8528 36.3647 39.8686 36.3611ZM39.8618 38.4849C39.8746 38.4627 39.8974 38.5778 39.8847 38.6127C39.858 38.6099 39.8535 38.4995 39.8618 38.4849ZM39.8947 50.3637C39.8994 50.3302 39.9009 50.2465 39.8787 50.2373C39.851 50.2258 39.8604 50.3484 39.8947 50.3637ZM39.9425 56.5944C39.9325 56.5986 39.8608 56.4691 39.8789 56.4115C39.9137 56.3021 39.9495 56.5898 39.9425 56.5944ZM39.9415 51.3197C39.8894 51.4253 39.9399 51.3081 39.885 51.3127C39.883 51.3838 39.8803 51.5605 39.9343 51.439C39.9447 51.4153 39.938 51.3528 39.9415 51.3197ZM39.9599 51.2223C39.9421 51.211 39.886 51.1349 39.8901 51.2007C39.892 51.2311 39.9543 51.2801 39.9599 51.2223ZM39.9181 55.7917C39.9667 55.697 39.9406 56.1309 39.9321 56.1434C39.9276 56.15 39.9234 56.1543 39.9198 56.1567C39.9352 56.1727 39.938 56.2546 39.899 56.2641C39.9022 56.2395 39.8988 56.1724 39.9031 56.1647C39.905 56.1613 39.9067 56.1588 39.9084 56.1571C39.8746 56.1282 39.9089 55.8098 39.9181 55.7917ZM39.9681 55.0727C40.0398 55.181 39.9179 55.2002 39.914 55.1908C39.8641 55.0729 39.954 55.1498 39.9582 55.1462C39.9652 55.138 39.9235 55.0542 39.9681 55.073C39.9681 55.0729 39.9681 55.0728 39.9681 55.0727ZM39.9382 55.6443C39.9397 55.6487 39.936 55.7397 39.934 55.7434C39.8931 55.8179 39.9036 55.5606 39.9382 55.6443ZM39.9609 37.7843C39.9488 37.8494 39.9039 37.7855 39.92 37.7423C39.9216 37.7387 39.9716 37.7269 39.9609 37.7843ZM39.9478 51.1703C39.9563 51.1552 39.9883 50.7691 39.9205 50.7923C39.9285 50.8251 39.8936 51.264 39.9478 51.1703ZM39.9643 48.2849C39.9637 48.353 39.8998 48.2787 39.9237 48.2424C39.9325 48.2289 39.9643 48.2677 39.9643 48.2849ZM39.9266 36.168C39.8915 36.0973 40.0092 36.1119 39.9688 36.1732C39.9673 36.1756 39.9279 36.1708 39.9266 36.168ZM39.9275 48.8288C39.8888 48.594 40.0914 48.6496 40.023 48.9549C40.014 48.9454 40.0049 48.9358 39.9959 48.9262C39.9655 49.2786 39.9816 48.9503 39.9703 48.8641C39.966 48.8313 39.9322 48.8588 39.9273 48.8291C39.9274 48.829 39.9274 48.8289 39.9275 48.8288ZM39.9681 47.9268C40.1119 47.7007 40.0183 48.1324 40.037 48.2562C39.9776 48.1362 39.9866 47.9799 39.9258 48.1925C39.9141 47.8817 39.9713 48.011 39.9761 47.9986C39.9814 47.984 39.9619 47.9365 39.9681 47.9268ZM39.9691 48.5233C39.9733 48.5364 39.944 48.6349 39.9488 48.6704C39.8997 48.6208 39.9406 48.4365 39.9691 48.5233ZM39.9348 54.319C39.9732 54.3272 40.0016 54.3474 39.9872 54.4251C39.9679 54.4011 39.9512 54.3515 39.9348 54.319ZM39.9628 30.6728C39.9656 30.6192 39.9801 30.5126 39.9396 30.5453C39.9362 30.5489 39.9401 30.6726 39.9628 30.6728ZM39.979 50.0489C39.9837 50.0375 39.9869 49.7431 39.9444 49.8448C39.9316 49.8755 39.9371 50.1433 39.979 50.0489ZM39.9742 51.5736C39.9746 51.5489 39.9673 51.4488 39.9582 51.4467C39.9267 51.4399 39.944 51.5628 39.9742 51.5736ZM40.0022 30.4027C40.0062 30.3957 39.9991 30.2322 39.9804 30.2501C39.9451 30.2842 39.9884 30.4269 40.0022 30.4027ZM40.051 38.0212C40.0524 38.0348 40.0106 38.0529 40.0102 38.0576C40.0096 38.0687 40.0256 38.3189 39.972 38.2234C39.963 38.2074 39.9836 37.8474 39.9889 37.8006C40.0463 37.7825 39.9917 37.9363 39.9976 37.9737C39.9987 37.9803 40.0467 37.9845 40.0508 38.021C40.0508 38.0211 40.0509 38.0211 40.051 38.0212ZM39.9754 54.7239C40.0118 54.735 40.036 55.0291 39.9918 55.0257C39.9863 54.9251 39.9808 54.8245 39.9754 54.7239ZM39.9814 54.5745C40.0072 54.5118 40.0158 54.6587 40.0044 54.7021C39.9798 54.7025 39.9776 54.5837 39.9814 54.5745ZM40.1105 51.0157C40.1015 50.9861 40.0483 51.077 40.038 51.0567C40.0315 51.0437 40.0515 50.9776 40.0348 50.9566C40.0295 50.9506 39.9795 51.018 39.9817 51.0374C39.9845 51.0651 40.0239 51.0383 40.0242 51.0685C40.025 51.1688 39.9969 51.2577 39.9976 51.3517C39.9977 51.3602 40.0255 51.2943 40.0252 51.3667C40.0251 51.3779 39.9837 51.4451 39.9899 51.5318C40.1181 51.7231 39.9922 51.8635 40.0384 52.1063C40.0505 52.0971 40.0829 51.9156 40.0841 51.9049C40.1052 51.702 40.1075 51.3384 40.1078 51.1259C40.1079 51.0714 40.0808 51.0979 40.0798 51.0744C40.079 51.0558 40.1293 51.0779 40.1105 51.0157ZM39.9906 30.7012C40.0408 30.6757 40.009 30.5862 40.0116 30.529C39.9663 30.5491 40.0017 30.6453 39.9906 30.7012ZM40.0203 53.254C40.0184 53.2253 40.0335 53.1365 40.0184 53.1292C39.9986 53.1197 39.9862 53.2479 40.0203 53.254ZM40.0367 39.4319C40.0381 39.4346 40.0354 39.5036 40.0339 39.5062C39.9936 39.5678 40.0018 39.361 40.0367 39.4319ZM40.0271 41.0808C40.0333 41.1331 40.049 41.1858 40.0082 41.2034C40.0145 41.17 39.9987 41.0747 40.0271 41.0808ZM40.0283 43.3557C40.0816 43.3449 40.0471 43.5022 40.0423 43.5319C40.0186 43.5209 39.9899 43.3636 40.0283 43.3557ZM40.1022 54.3077C40.0991 54.4038 40.1799 54.3835 40.1433 54.4446C40.1371 54.4546 39.9689 54.4868 40.0319 54.3811C40.0433 54.362 40.0832 54.4365 40.1022 54.3077ZM40.0213 49.0046C40.0566 49.0291 40.0461 49.1055 40.0433 49.1572C40.0171 49.1456 40.0238 49.0414 40.0213 49.0046ZM40.0426 30.1074C40.0924 30.0623 40.0554 29.8539 40.0225 29.9054C40.0182 29.9128 40.0444 30.0782 40.0426 30.1074ZM40.023 36.9548C40.0622 37.0406 40.0744 36.8629 40.036 36.8069C40.0385 36.8322 40.0204 36.949 40.023 36.9548ZM40.0573 42.8092C40.0589 42.8134 40.0551 42.9043 40.0532 42.9084C40.0122 42.9829 40.0227 42.7256 40.0573 42.8092ZM40.0918 40.5386C40.1241 40.5713 40.0981 40.7867 40.0657 40.835C40.0185 40.7885 40.0515 40.4979 40.0918 40.5386ZM40.0793 53.9119C40.081 53.9805 40.071 54.0456 40.057 54.1086C40.0299 54.0954 40.059 53.9191 40.0793 53.9119ZM40.0607 43.1431C40.0605 43.1479 40.0574 43.1527 40.057 43.1573C40.0582 43.1525 40.0595 43.1477 40.0607 43.1431ZM40.0984 52.376C40.1091 52.3185 40.0593 52.3304 40.0578 52.334C40.0416 52.3772 40.0863 52.4411 40.0984 52.376ZM40.0645 30.6355C40.1095 30.6155 40.0746 30.5188 40.0853 30.4632C40.0498 30.4793 40.0598 30.5907 40.0645 30.6355ZM40.0602 47.6847C40.1089 47.6124 40.1655 47.9064 40.1341 47.9683C40.104 47.9729 40.0535 47.6952 40.0602 47.6847ZM40.0904 36.6885C40.1256 36.6827 40.0831 36.5593 40.0665 36.5855C40.0559 36.6021 40.0685 36.6919 40.0904 36.6885ZM40.1136 48.1161C40.1243 48.1437 40.0896 48.2081 40.0684 48.1854C40.0413 48.1563 40.1105 48.109 40.1136 48.1161ZM40.1419 50.594C40.1473 50.5819 40.1111 50.4195 40.0752 50.4866C40.0502 50.5331 40.1011 50.5406 40.1013 50.5515C40.1011 50.5637 40.0388 50.8244 40.1419 50.594ZM40.0909 46.0383C40.1044 46.0996 40.0887 46.1737 40.0897 46.2378C40.0679 46.2117 40.0619 46.0644 40.0909 46.0383ZM40.0998 37.1645C40.1141 37.1496 40.1226 36.7442 40.0788 36.9745C40.0763 36.9879 40.0567 37.2097 40.0998 37.1645ZM40.1022 54.3077C40.1026 54.2955 40.1043 54.2815 40.1078 54.2653C40.1064 54.2814 40.104 54.2954 40.1022 54.3077ZM40.1076 53.2152C40.1332 53.2374 40.1401 53.1258 40.1264 53.0929C40.0951 53.0828 40.104 53.2122 40.1076 53.2152ZM40.1254 46.2427C40.1401 46.2796 40.1245 46.3467 40.1262 46.3924C40.1023 46.3847 40.1012 46.2587 40.1254 46.2427ZM40.1523 43.6481C40.1381 43.7215 40.1446 43.8118 40.1738 43.8132C40.1692 43.8147 40.1644 43.8183 40.1595 43.8242C40.1547 43.8301 40.1683 43.9087 40.1583 43.9429C40.0992 44.1473 40.1236 43.1534 40.2059 43.7295C40.188 43.7024 40.1701 43.6753 40.1523 43.6481ZM40.1605 40.2471C40.196 40.2055 40.1515 40.0888 40.1375 40.1191C40.1279 40.1402 40.1247 40.2888 40.1605 40.2471ZM40.1815 41.8495C40.1878 41.837 40.163 41.7232 40.1443 41.7202C40.1246 41.7857 40.1521 41.9062 40.1815 41.8495ZM40.202 39.927C40.2074 39.9009 40.1502 39.8675 40.1477 39.8706C40.1268 39.8971 40.1702 39.9709 40.202 39.927ZM40.2564 54.1084C40.2728 54.0695 40.2314 53.9455 40.1936 53.9186C40.2009 53.9135 40.2104 53.9 40.2219 53.8752C40.2219 53.8753 40.2219 53.8753 40.2219 53.8754C40.2371 53.8419 40.2538 52.84 40.181 53.512C40.1787 53.5331 40.2126 53.5043 40.2066 53.59C40.2062 53.5956 40.1785 53.5984 40.1772 53.6159C40.1742 53.6561 40.1568 53.8703 40.1791 53.9133C40.174 53.9137 40.1691 53.9165 40.1646 53.9224C40.1246 53.9752 40.2438 54.1386 40.2564 54.1084ZM40.1866 42.0752C40.1968 42.0523 40.1871 41.9798 40.1627 41.9723C40.1507 42.0082 40.1626 42.1284 40.1866 42.0752ZM40.2001 37.1519C40.2202 37.1052 40.1826 36.9869 40.1627 37.0226C40.1504 37.0446 40.177 37.2057 40.2001 37.1519ZM40.1735 41.3487C40.1446 41.6164 40.1759 41.4126 40.2117 41.4536C40.199 41.4186 40.1863 41.3837 40.1735 41.3487ZM40.1639 55.3474C40.1721 55.3047 40.2428 55.3549 40.2045 55.4019C40.1923 55.4166 40.1594 55.3713 40.1639 55.3474ZM40.1859 57.275C40.2486 57.2385 40.2117 57.4165 40.1687 57.3471C40.1672 57.3439 40.1835 57.2776 40.1859 57.275ZM40.2115 55.928C40.1688 55.8991 40.1637 55.8802 40.1743 55.7986C40.1863 55.9194 40.2241 55.8073 40.2115 55.928ZM40.1784 43.8124C40.1766 43.8129 40.1754 43.8133 40.1738 43.8132C40.1753 43.8127 40.1768 43.8124 40.1784 43.8124ZM40.1909 39.6753C40.2271 39.6418 40.2244 39.5479 40.188 39.5758C40.1847 39.5785 40.1642 39.6616 40.1909 39.6753ZM40.1936 53.9186C40.1871 53.923 40.1829 53.9207 40.1791 53.9133C40.1839 53.913 40.1885 53.9149 40.1936 53.9186ZM40.2204 40.1796C40.1934 40.1762 40.1829 40.3192 40.1861 40.3249C40.2329 40.407 40.222 40.2386 40.2204 40.1796ZM40.2381 36.2067C40.2352 36.1994 40.1656 36.2469 40.1929 36.2761C40.214 36.2986 40.2488 36.2344 40.2381 36.2067ZM40.2289 56.2052C40.2288 56.2505 40.2289 56.3142 40.1958 56.326C40.2008 56.2956 40.2046 56.2043 40.2289 56.2052ZM40.2313 57.2053C40.1924 57.1518 40.1925 57.0296 40.1989 56.9516C40.2501 56.9501 40.2192 57.1551 40.2313 57.2053ZM40.2373 54.2312C40.2394 54.2275 40.2547 54.114 40.2204 54.1295C40.1701 54.1521 40.2187 54.2632 40.2373 54.2312ZM40.2011 36.4272C40.2247 36.4779 40.2972 36.3611 40.2412 36.3076C40.2125 36.2801 40.1971 36.4186 40.2011 36.4272ZM40.2383 39.382C40.2185 39.315 40.1831 39.4811 40.219 39.5043C40.2218 39.4734 40.2453 39.4058 40.2383 39.382ZM40.2745 41.6612C40.3779 41.4501 40.1893 41.5651 40.2059 41.6025C40.2083 41.6078 40.2721 41.6664 40.2745 41.6612ZM40.2492 29.5836C40.2348 29.5537 40.1828 29.6651 40.217 29.6796C40.2385 29.6885 40.2583 29.6027 40.2492 29.5836ZM40.2074 44.8398C40.207 44.8309 40.2067 44.822 40.2064 44.8133C40.2081 44.8198 40.2086 44.8285 40.2074 44.8398ZM40.3768 38.774C40.2308 38.9226 40.3433 38.907 40.3427 38.9199C40.3411 38.9478 40.3017 39.0126 40.3081 39.0652C40.2917 39.005 40.2753 38.9448 40.2588 38.8845C40.2483 38.9321 40.1946 39.3454 40.2182 39.354C40.2519 39.3665 40.2414 39.2364 40.2443 39.2326C40.2486 39.2272 40.3423 39.2068 40.3458 39.1948C40.3515 39.1749 40.3535 38.8294 40.3768 38.774ZM40.2584 41.2198C40.2472 41.2537 40.2101 41.2634 40.219 41.2791C40.222 41.2845 40.2574 41.2854 40.2666 41.3037C40.2638 41.2757 40.2611 41.2478 40.2584 41.2198ZM40.2455 38.5079C40.2888 38.4658 40.2724 38.6544 40.2675 38.6605C40.2382 38.6927 40.2102 38.5423 40.2455 38.5079ZM40.2518 40.1082C40.2544 40.1013 40.2679 39.9565 40.2439 39.9577C40.2255 39.996 40.2202 40.1896 40.2518 40.1082ZM40.269 41.3264C40.2649 41.3773 40.2292 41.4734 40.2825 41.4624C40.2825 41.4623 40.2825 41.4623 40.2825 41.4622C40.278 41.4169 40.2735 41.3716 40.269 41.3264ZM40.3137 36.6009C40.3986 36.5066 40.2913 36.5513 40.2639 36.6348C40.302 36.6601 40.2999 36.6164 40.3137 36.6009ZM40.377 36.2992C40.3923 36.2729 40.3755 36.0026 40.3306 36.0439C40.3146 36.0585 40.355 36.214 40.3519 36.2211C40.3473 36.232 40.2976 36.1824 40.3074 36.2653C40.3243 36.2605 40.3719 36.3082 40.377 36.2992ZM40.3681 36.5229C40.4326 36.4292 40.3135 36.4081 40.3132 36.4786C40.313 36.5061 40.3587 36.5363 40.3681 36.5229ZM40.3579 36.9056C40.3692 36.8719 40.3857 36.7821 40.3461 36.7202C40.3427 36.803 40.3393 36.8859 40.3359 36.9687C40.3584 36.9783 40.348 36.9351 40.3579 36.9054C40.3579 36.9055 40.3579 36.9056 40.3579 36.9056ZM40.5365 57.7684C40.5703 57.6939 40.5832 57.8655 40.5749 57.8727C40.5474 57.8943 40.5214 57.8017 40.5365 57.7684ZM41.3313 29.0021C41.3448 28.9814 41.3891 28.9679 41.3659 28.9223C41.3332 28.9681 41.3005 29.0139 41.2678 29.0597C41.3427 29.0953 41.3165 29.0247 41.3313 29.0021ZM41.6051 28.8272C41.6069 28.8337 41.7222 28.7983 41.6452 28.8819C41.5933 28.9384 41.5427 28.6313 41.5938 28.5758C41.6175 28.6371 41.5903 28.7715 41.6051 28.8272ZM42.1039 28.2892C42.1131 28.2857 42.1266 28.4024 42.1201 28.4159C42.0859 28.4868 42.0547 28.3084 42.1039 28.2892ZM42.0819 28.6615C42.1043 28.6067 42.1187 28.728 42.1058 28.7641C42.0844 28.7676 42.0787 28.6699 42.0819 28.6615ZM42.2054 57.0144C42.2837 56.9552 42.1151 56.9023 42.1491 56.9934C42.1507 56.9977 42.2016 57.017 42.2054 57.0144ZM42.2201 28.4033C42.1978 28.458 42.1833 28.3368 42.1962 28.3007C42.2176 28.2973 42.2234 28.395 42.2201 28.4033ZM42.392 56.9728C42.4483 56.8941 42.2592 56.9218 42.2516 56.9316C42.2215 56.9721 42.2957 57.1109 42.3141 57.1393C42.2858 56.9315 42.3654 57.0098 42.392 56.9728ZM42.2784 56.6101C42.2582 56.5371 42.2196 56.7235 42.2723 56.7591C42.2698 56.7229 42.2842 56.6308 42.2784 56.6101ZM42.339 56.1673C42.3458 56.128 42.362 56.0114 42.3323 55.9918C42.3377 56.0346 42.3084 56.1507 42.339 56.1673ZM42.4282 56.0785C42.4686 56.0171 42.3508 56.0024 42.3859 56.0731C42.3873 56.0759 42.426 56.0807 42.4282 56.0785ZM42.4707 55.7338C42.5176 55.6935 42.4035 55.6476 42.4004 55.7128C42.3997 55.7322 42.4654 55.738 42.4707 55.7338ZM42.5954 56.8743C42.6156 56.8167 42.5338 56.7425 42.5249 56.8655C42.5124 56.8223 42.4999 56.7791 42.4874 56.7359C42.4416 56.897 42.5549 56.8852 42.5502 56.9314C42.5436 56.996 42.4501 56.9909 42.4207 56.978C42.478 57.031 42.4789 57.2561 42.4898 57.3862C42.5139 57.2719 42.5556 57.0863 42.5708 56.9734C42.5752 56.9412 42.5496 56.91 42.5524 56.8825C42.5572 56.8384 42.5941 56.8775 42.5954 56.8746C42.5954 56.8745 42.5954 56.8744 42.5954 56.8743ZM42.4724 55.2807C42.5255 55.1624 42.4109 55.2372 42.4314 55.304C42.4329 55.3069 42.4711 55.2836 42.4724 55.2807ZM42.5684 28.2465C42.5205 28.4045 42.457 28.2897 42.5534 28.6201C42.4851 28.4813 42.5043 28.6124 42.4768 28.5853C42.455 28.5636 42.473 28.4822 42.4292 28.5295C42.4769 28.4673 42.4637 28.1971 42.4715 28.185C42.4715 28.1851 42.4715 28.1853 42.4715 28.1854C42.4761 28.1781 42.5836 28.1961 42.5684 28.2465ZM42.6387 56.1667C42.7777 56.1273 42.557 56.1118 42.6723 56.0343C42.5049 55.9311 42.6723 56.3194 42.5309 56.3664C42.5473 55.9447 42.3909 56.645 42.6024 56.3507C42.5257 56.5932 42.6287 56.4301 42.6556 56.4676C42.6843 56.5076 42.6531 56.6448 42.7049 56.6378C42.7049 56.6377 42.7049 56.6377 42.7049 56.6376C42.7013 56.5537 42.6977 56.4698 42.694 56.3859C42.5823 56.468 42.6158 56.2966 42.7068 56.2384C42.6841 56.2145 42.6614 56.1906 42.6387 56.1667ZM42.5338 56.6415C42.5364 56.6333 42.5207 56.4508 42.4983 56.4626C42.484 56.4869 42.5011 56.7459 42.5338 56.6415ZM42.5582 57.4447C42.5585 57.3791 42.5803 57.2778 42.5382 57.2421C42.5379 57.3077 42.5161 57.409 42.5582 57.4447ZM42.5662 54.0708C42.5316 53.9873 42.5214 54.2444 42.5623 54.17C42.5643 54.1664 42.5678 54.0749 42.5662 54.0708ZM42.6177 55.9767C42.6602 55.8918 42.5249 55.932 42.5602 55.9949C42.5622 55.9985 42.6157 55.9807 42.6177 55.9767ZM42.5848 28.3745C42.6179 28.3802 42.5947 28.6094 42.595 28.65C42.5642 28.6269 42.5468 28.368 42.5848 28.3745ZM42.6822 57.56C42.8013 57.4296 42.6637 57.2527 42.6667 57.2333C42.6698 57.214 42.7219 57.2443 42.7233 57.2399C42.7262 57.2298 42.7218 57.0244 42.7182 57.0144C42.7154 57.0073 42.6422 57.0445 42.6191 57.0021C42.6607 57.0848 42.6347 57.4604 42.6428 57.4799C42.6493 57.495 42.7261 57.3812 42.6822 57.5597C42.6822 57.5598 42.6822 57.5599 42.6822 57.56ZM42.6827 57.1848C42.652 57.2361 42.6482 57.0922 42.6595 57.0574C42.6848 56.98 42.6863 57.1782 42.6827 57.1848ZM42.711 56.8386C42.7178 56.8222 42.7241 56.6739 42.6899 56.6613C42.6456 56.7315 42.6949 56.8759 42.711 56.8386ZM42.7064 55.188C42.702 55.1495 42.7282 55.0436 42.6984 55.0375C42.7027 55.076 42.6765 55.182 42.7064 55.188ZM42.8453 29.1565C42.8703 29.0925 42.8805 29.2408 42.8685 29.284C42.8486 29.2864 42.8432 29.1619 42.8453 29.1565ZM42.9031 55.9624C42.9121 55.9396 42.8895 55.4742 42.8755 55.4089C42.8529 55.4728 42.8512 55.9339 42.8622 55.9549C42.8655 55.961 42.9016 55.9653 42.9031 55.9624ZM42.9168 56.9688C42.9608 57.0115 42.9081 57.0393 42.9074 57.0447C42.9007 57.0975 42.9106 57.2069 42.8683 57.1829C42.8854 57.0898 42.8296 56.8839 42.9168 56.9688ZM42.9052 55.1549C42.8889 54.9969 42.8426 55.3004 42.8886 55.2606C42.8913 55.2581 42.907 55.1713 42.9052 55.1549ZM42.9159 56.0143C42.9514 56.0492 42.9208 56.5147 42.9207 56.5894C42.8552 56.5225 42.905 56.4685 42.9016 56.3786C42.9006 56.3544 42.8734 56.3609 42.8733 56.3582C42.8721 56.3162 42.9036 56.3477 42.904 56.3218C42.9043 56.3054 42.8658 55.9653 42.9159 56.0143ZM42.9473 56.9931C42.9725 57.0192 42.9832 57.3098 42.9765 57.3215C42.9267 57.409 42.9385 57.0157 42.9473 56.9931ZM42.9741 55.9716C43.0503 56.0217 42.9993 56.2529 42.9613 56.0947C42.9579 56.0795 42.9909 56.0156 42.9741 55.9716ZM42.9777 55.1718C42.98 55.164 42.9952 54.9993 42.971 54.9964C42.9616 55.0202 42.9531 55.2603 42.9777 55.1718ZM43.0597 55.2572C43.0591 55.2533 43.0124 55.2919 43.0183 55.2146C43.0189 55.2082 43.0714 55.1962 43.0522 55.0991C43.0482 55.0794 43.0135 55.0489 43.0113 55.0511C42.929 55.1522 43.0867 55.4567 43.0597 55.2572ZM42.9898 56.9985C43.012 56.9828 43.0777 57.0206 43.0444 57.0547C43.0301 57.0693 42.9906 57.042 42.9898 56.9985ZM42.999 54.6494C43.0389 54.7452 43.0464 54.4445 43.0362 54.4292C43.0114 54.4388 42.9951 54.6398 42.999 54.6494ZM43.1532 29.3063C43.1532 29.3063 43.1532 29.3062 43.1532 29.3061C43.1441 29.3867 43.111 29.3368 43.1099 29.3405C43.0612 29.5121 43.1363 29.4666 43.1452 29.4935C43.1644 29.551 43.073 29.5417 43.1109 29.6388C43.0549 29.4783 43.0784 29.6244 43.0459 29.6289C42.9132 29.6469 43.108 29.4153 43.0802 29.3353C43.0764 29.3242 43.034 29.4065 43.022 29.3779C42.9829 29.2851 43.1877 28.9972 43.1532 29.3063ZM43.0502 57.0809C43.0892 57.1183 43.0514 57.4018 43.0193 57.3266C43.0142 57.3145 42.9934 57.026 43.0502 57.0809ZM43.1078 43.8381C43.1415 43.9062 43.1811 43.7483 43.1549 43.7191C43.1418 43.7045 43.093 43.8082 43.1078 43.8381ZM43.252 42.731C43.2452 42.65 43.1045 42.5647 43.1264 42.6654C43.1287 42.6761 43.2325 42.7402 43.252 42.731ZM43.1798 48.0471C43.23 47.9626 43.1366 47.9676 43.138 48.0297C43.1384 48.0516 43.1782 48.0498 43.1798 48.0471ZM43.1677 44.8206C43.1709 44.8122 43.165 44.7144 43.1435 44.718C43.1306 44.7541 43.1453 44.8754 43.1677 44.8206ZM43.1931 48.074C43.1762 48.0239 43.1087 48.1101 43.1747 48.1714C43.1693 48.1403 43.1948 48.0791 43.1931 48.074ZM43.1805 55.797C43.1421 55.755 43.1537 55.6363 43.1471 55.5681C43.1968 55.5607 43.1715 55.7482 43.1805 55.797ZM43.1955 43.0746C43.1605 42.998 43.1318 43.1622 43.1781 43.1471C43.1806 43.145 43.197 43.0777 43.1955 43.0746ZM43.1981 50.7745C43.1685 50.7188 43.1286 50.8957 43.1807 50.847C43.1829 50.8446 43.1998 50.7776 43.1981 50.7745ZM43.181 51.5469C43.191 51.5047 43.1879 51.3244 43.159 51.3946C43.1545 51.4055 43.1538 51.5438 43.181 51.5469ZM43.181 29.4982C43.232 29.4754 43.2199 29.6076 43.2109 29.6266C43.2072 29.634 43.1146 29.5279 43.181 29.4982ZM43.1877 47.4981C43.1814 47.4544 43.1935 47.3409 43.1667 47.3209C43.1723 47.3744 43.1344 47.5125 43.1877 47.4981ZM43.1957 43.4241C43.2512 43.3573 43.2457 43.2433 43.1732 43.2715C43.1781 43.3975 43.2384 43.2559 43.1957 43.4241ZM43.2528 48.3557C43.257 48.3206 43.1874 48.2937 43.1841 48.2977C43.1529 48.3357 43.2257 48.3905 43.2528 48.3557ZM43.1955 45.7235C43.2252 45.7215 43.2117 45.6091 43.1926 45.6241C43.1862 45.629 43.1714 45.7252 43.1955 45.7235ZM43.1974 54.3244C43.2246 54.2729 43.2511 54.4302 43.2194 54.4768C43.1737 54.4994 43.1943 54.3309 43.1974 54.3244ZM43.2354 49.3284C43.2795 49.3336 43.2545 49.1579 43.218 49.2271C43.2088 49.2444 43.2206 49.3265 43.2354 49.3284ZM43.2883 51.0108C43.2356 50.8929 43.1983 51.3879 43.2639 51.2579C43.2685 51.2486 43.2927 51.0211 43.2883 51.0108ZM43.2554 51.8193C43.2612 51.7989 43.4095 51.8091 43.3523 51.8932C43.3449 51.9043 43.3057 51.8526 43.2967 51.8616C43.2916 51.8669 43.2708 52.0499 43.2743 52.0584C43.2782 52.0674 43.3257 52.0568 43.331 52.066C43.337 52.0763 43.2953 52.189 43.2948 52.248C43.294 52.3592 43.3336 52.3712 43.3337 52.3803C43.334 52.4069 43.3059 52.4515 43.3059 52.5054C43.3062 52.7768 43.3398 53.1919 43.2559 53.407C43.2896 53.2155 43.2538 53.0331 43.2428 52.8426C43.3254 52.8984 43.1792 52.5623 43.2745 52.7589C43.2538 52.6684 43.2373 51.8859 43.2554 51.8195C43.2554 51.8194 43.2554 51.8193 43.2554 51.8193ZM43.2936 42.4114C43.3442 42.4612 43.3328 42.206 43.2743 42.1843C43.2661 42.218 43.2879 42.4053 43.2936 42.4114ZM43.4171 43.5888C43.4258 43.6125 43.5248 43.635 43.4746 43.7593C43.4746 43.7594 43.4746 43.7595 43.4746 43.7596C43.4599 43.7959 43.4358 43.7545 43.4272 43.7612C43.4237 43.7636 43.3745 43.8769 43.3666 43.7828C43.3544 43.6393 43.4402 43.7693 43.4412 43.6928C43.4413 43.6834 43.3878 43.5386 43.376 43.547C43.3746 43.5479 43.386 43.5914 43.3811 43.5986C43.3627 43.6258 43.3318 43.6126 43.3303 43.6164C43.3266 43.629 43.3792 43.858 43.3332 43.8913C43.3184 43.9022 43.2842 43.5262 43.2919 43.5115C43.2968 43.5023 43.3825 43.5062 43.391 43.4966C43.3952 43.4916 43.363 43.3404 43.3709 43.3208C43.3732 43.3151 43.3757 43.3107 43.3777 43.3075C43.3511 43.3304 43.3531 43.1935 43.383 43.1977C43.3948 43.2 43.388 43.2943 43.3859 43.2977C43.385 43.2992 43.3838 43.3004 43.383 43.3016C43.4153 43.2821 43.4139 43.6013 43.462 43.5324C43.4884 43.6249 43.3914 43.5192 43.4171 43.5888ZM43.47 44.0335C43.461 44.0239 43.452 44.0144 43.4429 44.0048C43.465 44.1668 43.4216 44.3537 43.4219 44.5403C43.4219 44.5876 43.4771 44.5332 43.462 44.5952C43.4499 44.6449 43.3988 44.7 43.3874 44.6729C43.3845 44.6663 43.4178 44.5651 43.4144 44.5145C43.4043 44.3649 43.357 44.4027 43.3557 44.3939C43.3544 44.3843 43.3876 44.2902 43.3861 44.2388C43.3823 44.1095 43.3533 44.0505 43.3912 43.8739C43.4224 43.9758 43.4902 43.92 43.47 44.0335ZM43.3692 50.0707C43.399 50.0768 43.3726 50.1828 43.377 50.2213C43.3471 50.2152 43.3736 50.1092 43.3692 50.0707ZM43.4079 34.2762C43.359 34.2437 43.3469 34.4877 43.3876 34.4234C43.3966 34.4091 43.4075 34.3069 43.4079 34.2762ZM43.3782 35.3724C43.3917 35.405 43.4269 35.2736 43.389 35.2738C43.3769 35.274 43.3764 35.3682 43.3782 35.3724ZM43.4219 46.1271C43.4234 46.1333 43.4126 46.2231 43.4101 46.2259C43.3582 46.2854 43.3882 45.9899 43.4219 46.1271ZM43.4383 36.7049C43.4063 36.5911 43.3924 36.9336 43.4333 36.829C43.4353 36.8237 43.4399 36.7104 43.4383 36.7049ZM43.4473 37.1809C43.4456 37.1536 43.4615 37.0325 43.4466 37.0309C43.4225 37.0285 43.4061 37.1671 43.4473 37.1809ZM43.4374 48.3794C43.4924 48.3662 43.4507 48.5259 43.4577 48.5814C43.4026 48.5946 43.4443 48.4349 43.4374 48.3794ZM43.478 47.3713C43.5214 48.0446 43.4037 47.8962 43.4512 47.3312C43.4865 47.3304 43.4752 47.3288 43.478 47.3713ZM43.4715 48.2335C43.4362 48.209 43.4466 48.1325 43.4495 48.0809C43.474 48.0902 43.4651 48.1962 43.4715 48.2335ZM43.4835 33.9857C43.5281 34.0279 43.4732 34.2149 43.4548 34.1816C43.4508 34.1739 43.459 33.9702 43.4835 33.9857ZM43.469 46.1835C43.5226 46.1679 43.5007 46.37 43.4889 46.3855C43.441 46.4479 43.4809 46.1999 43.469 46.1835ZM43.4845 49.3349C43.5265 49.3706 43.5049 49.472 43.5043 49.5372C43.4684 49.5076 43.4837 49.3903 43.4845 49.3349ZM43.5174 48.8642C43.519 48.8683 43.5152 48.9592 43.5133 48.9633C43.4723 49.0378 43.4828 48.7805 43.5174 48.8642ZM43.556 29.1946C43.5574 29.1977 43.5547 29.2665 43.5531 29.2689C43.5129 29.3304 43.5211 29.1237 43.556 29.1946ZM61.9936 31.5629C62.0647 31.5217 62.3655 31.385 62.4923 31.3192C62.3712 31.4391 61.737 31.7117 61.9936 31.5629ZM67.2406 40.0473C67.2275 39.9287 67.2144 39.8102 67.2012 39.6916C67.1927 40.0286 67.2023 40.4815 67.1899 40.7942C67.1878 40.8453 67.1498 40.7127 67.1481 40.8337C67.1464 40.9547 67.1983 40.9314 67.2039 41.1074C67.21 41.3049 67.1738 42.2091 67.1747 42.5223C67.1782 43.6935 67.2078 44.8747 67.1863 46.0483C67.1478 44.8367 67.1087 46.0576 67.1254 46.3969C67.1292 46.4721 67.2258 46.4601 67.2015 47.6756C67.1861 48.4481 67.048 47.7346 67.1171 49.0237C67.2137 48.0324 67.207 49.0072 67.2102 49.7842C67.2108 49.9182 67.1962 51 67.2005 51.4779C67.202 51.6414 67.2526 51.8905 67.2539 52.1074C67.2548 52.2566 67.2271 52.3695 67.2285 52.5911C67.2348 53.6243 67.2369 54.6404 67.2276 55.6754C67.1024 55.0928 67.167 56.073 67.1663 56.1892C67.1663 56.1987 67.1662 56.2048 67.1659 56.2083C67.1563 56.3165 67.1505 56.2878 67.1453 56.1902C67.1254 56.0169 67.1156 55.4307 67.0985 55.771C67.0994 55.9104 67.1004 56.0498 67.1013 56.1892C67.1068 57.0936 66.7686 57.9964 66.1698 58.6755C66.7178 58.026 65.7784 59.3731 65.0668 59.619C65.0183 59.6416 64.9776 59.6583 64.9502 59.6659C65.0868 59.726 62.3931 60.833 62.0148 61.065C61.9361 61.1135 62.5006 60.8946 61.2384 61.4968C61.1017 61.562 61.1374 61.5053 61.0678 61.5438C61.0262 61.5668 60.818 61.7941 60.5164 61.8768C60.4063 61.9071 61.0148 61.5218 59.6204 62.2517C60.2311 62.0717 57.6961 63.2819 57.2214 63.4879C57.3205 63.4552 57.4195 63.4225 57.5186 63.3898C57.0436 63.582 56.9782 63.6573 56.8743 63.7069C56.6283 63.8245 56.3239 63.9596 56.0365 64.0909C55.7439 64.2289 55.4526 64.3359 55.206 64.4158C54.5016 64.6168 54.5045 64.7014 53.6392 64.732C53.8447 64.7409 54.0515 64.7388 54.2585 64.7257C53.6617 64.8048 53.0535 64.7909 52.4619 64.6852C53.849 64.7598 52.1649 64.6655 52.0596 64.5987C51.8867 64.5578 52.1421 64.5869 51.8555 64.5137C51.8267 64.5031 51.8558 64.563 51.4214 64.4139C51.1311 64.3083 50.958 64.2199 50.8403 64.1562C50.6739 64.0611 50.672 64.0373 50.5068 63.955C50.4843 63.9441 50.5481 64.0118 50.1241 63.8083C48.7765 63.1615 50.1418 63.7897 50.195 63.8113C50.2631 63.839 49.8883 63.5098 50.8916 64.0525C50.9337 64.0746 50.9772 64.0971 51.0227 64.1198C50.9754 64.0962 50.9321 64.0734 50.8926 64.0515C50.6041 63.8848 50.5909 63.8227 50.5522 63.8019C50.5147 63.7818 49.8504 63.459 49.8131 63.4426C49.4793 63.2982 49.747 63.4773 49.6804 63.4522C49.626 63.4315 48.8538 62.9864 48.6127 63.0021C48.2822 62.7111 48.8775 63.0203 49.5238 63.3241C49.6273 63.3501 48.936 62.9794 48.8992 62.961C47.9945 62.5089 48.454 62.842 48.2298 62.796C48.1121 62.7717 47.7717 62.5311 48.0749 62.7753C47.25 62.3727 47.7694 62.5786 47.7196 62.5458C47.6442 62.4964 47.3463 62.374 47.3118 62.3532C47.2611 62.3226 47.4574 62.3887 47.2538 62.2756C47.2199 62.257 46.8625 62.1335 47.2843 62.3708C46.7098 62.0757 46.7385 62.1372 46.5806 61.9633C46.1109 61.908 46.3343 61.7341 46.1817 61.6477C45.7757 61.4182 45.8402 61.5914 45.8154 61.5859C45.6462 61.5453 44.5123 60.93 44.2186 60.8034C44.3719 60.7785 45.1333 61.2596 45.3204 61.3335C45.9442 61.5799 44.4985 60.8718 44.9835 60.9867C44.7875 60.9238 44.5916 60.8608 44.3956 60.7979C44.0948 60.5655 44.5824 60.7735 43.6726 60.3486C43.4975 60.3318 44.3119 60.657 44.1328 60.6232C44.0272 60.6032 43.5039 60.3485 43.4867 60.3572C43.4682 60.3687 43.9485 60.5843 43.8616 60.5727C43.6721 60.5469 41.9822 59.6364 43.3036 60.2595C42.9863 60.1018 42.8445 59.9273 42.5938 59.8031C42.5724 59.7926 42.5488 59.7837 42.5228 59.7772C42.4743 59.7655 42.5286 59.8218 42.5593 59.8728C42.6163 59.9316 42.6497 59.9804 42.5255 59.9395C42.4573 59.9288 42.3198 59.8582 42.016 59.78C42.0089 59.7094 42.4182 59.8783 42.4247 59.8885C42.4429 59.8892 42.4189 59.737 42.4063 59.7256C42.3871 59.7063 42.1038 59.6061 41.7856 59.5865C41.4673 59.559 41.1319 59.6225 41.0085 59.6234C41.0694 59.6521 40.8092 59.7086 40.5708 59.8258C40.235 59.9894 39.8986 60.1503 39.8314 60.1953C39.7914 60.2225 39.9723 60.1837 39.9287 60.211C39.6559 60.38 38.8459 60.6928 38.4863 60.8702C38.0839 61.0688 38.1526 61.0791 38.1302 61.0902C37.9526 61.1766 38.0815 61.0818 37.9736 61.1358C37.8106 61.2175 36.6874 61.7731 36.6336 61.8063C36.618 61.8161 36.8213 61.7654 36.5809 61.8954C36.5392 61.9179 36.5419 61.856 35.8287 62.2388C34.9699 62.6998 36.464 61.9964 36.1272 62.2282C35.5314 62.4359 35.5853 62.4984 35.4308 62.5687C35.3772 62.5929 34.9556 62.7277 34.5327 62.944C34.8327 62.7817 35.1326 62.6193 35.4326 62.457C35.1275 62.5962 34.5521 62.9005 34.2991 63.012C34.1757 63.0663 34.25 62.9668 33.989 63.099C33.9337 63.1273 33.7742 63.3592 34.4324 62.9618C34.509 62.9778 34.1686 63.1127 34.0234 63.2006C34.0015 63.214 33.9476 63.3317 33.7318 63.3833C33.6881 63.3934 33.9632 63.067 33.3241 63.4404C33.0949 63.5642 32.7872 63.7113 32.3609 63.8194C32.2746 63.8425 32.5836 63.8097 32.4999 63.8332C32.4446 63.8669 31.7381 63.9334 31.6594 63.9198C31.5787 63.9261 31.9231 63.952 31.8277 63.9602C31.3257 64.0055 30.7117 63.8016 31.7035 63.8773C31.3706 63.8636 31.0418 63.8052 30.7283 63.7049C31.0503 63.8876 30.2032 63.6146 29.8186 63.36C29.786 63.3414 29.7542 63.3226 29.7234 63.3038C29.1329 62.9349 28.8782 62.6051 28.733 62.4424C28.592 62.2727 28.5663 62.2439 28.5759 62.2794C28.5932 62.3503 28.799 62.6505 28.6288 62.4579C28.3604 62.1341 28.3735 62.0645 28.3478 61.9663C28.3327 61.8617 28.2551 61.7344 28.0546 61.1571C28.0365 61.1068 28.1064 61.3962 28.1086 61.4312C28.1371 61.4639 27.9081 61.2647 27.8757 60.1399C27.8774 60.0666 27.8794 59.9806 27.8819 59.8856C27.883 59.9719 27.884 60.0581 27.8851 60.1444C27.8861 60.4039 27.9147 60.668 27.9706 60.9261C27.9881 60.8061 27.932 60.4777 27.9248 60.14C27.9126 59.9357 27.8831 59.7246 27.8824 59.6963C27.8695 59.0999 27.9033 59.5031 27.8551 58.6175C27.8508 58.5384 27.8739 58.3661 27.8623 58.197C27.8149 57.4959 27.8335 59.1221 27.7956 59.1665C27.7771 59.1876 27.7817 57.4388 27.7906 57.3787C27.8296 57.1238 27.8078 58.1715 27.8563 57.9718C27.8735 57.8989 27.8381 55.4064 27.857 54.9063C27.879 54.3293 28.0059 54.0695 27.8633 54.0658C28.0033 53.9029 27.9078 53.7591 27.9087 53.6853C27.9217 52.7929 27.9231 52.7913 27.9097 52.026C27.9068 51.857 27.9493 51.7144 27.9421 51.6546C27.9378 51.6198 27.8923 51.6848 27.8783 51.5144C27.8591 51.2777 27.9058 49.8552 27.931 49.7494C27.9561 49.6437 27.9419 50.3502 27.9832 50.2236C27.9873 49.7122 27.9771 49.2218 27.9815 48.707C27.9834 48.4932 28.0123 48.6031 28.0129 48.5107C28.0132 48.4713 27.9878 47.733 27.9771 47.7643C27.9523 47.8376 27.969 50.1175 27.9184 49.5172C27.9086 49.4013 27.9752 48.9921 27.8942 49.0572C27.9126 47.0203 27.931 44.9833 27.9493 42.9464C28.0099 44.1168 27.9557 45.4338 27.9614 46.6596C27.9621 46.8277 27.9543 47.3956 27.9952 47.3266C28.0058 46.2842 27.9845 44.9883 28.0112 43.9873C28.0121 43.9553 28.0489 44.0729 28.0547 43.9529C28.0656 43.7286 28.0062 42.9984 28.0216 42.8756C28.0252 42.8546 28.0737 43.2702 28.1045 43.1438C28.1836 42.8194 28.0084 42.737 28.0105 42.4581C28.0122 42.2424 28.0968 40.793 28.0433 40.432C27.9863 40.0481 28.0102 41.5002 27.9636 41.3929C27.9167 40.4105 27.9668 39.4157 27.9609 38.4873C27.9608 38.471 27.9242 38.613 27.9191 38.4059C27.9102 38.0454 27.9621 37.9508 27.9704 37.7754C27.9792 37.5862 27.9718 36.9171 27.9907 36.8276C27.9931 36.8162 28.0446 36.9517 28.046 36.9723C28.0672 37.2638 28.0005 37.3673 27.9996 37.3938C27.9971 37.4935 28.0226 37.5914 28.0211 37.6823C28.0186 37.8319 27.9949 37.9143 27.9928 38.1119C27.9913 38.2482 28.0367 38.1166 28.0346 38.248C28.0337 38.2962 27.93 38.8163 28.0358 38.8648C28.0624 38.8768 28.0949 36.1953 28.0937 34.8788C28.0944 34.2589 28.2487 33.8215 28.2945 33.6718C28.149 34.0552 28.0696 34.4661 28.0617 34.878C28.0569 35.0177 28.052 35.1565 28.0472 35.2953C28.0529 35.1595 28.0547 35.0187 28.0546 34.8788C28.0267 33.7136 28.7006 32.7313 28.8348 32.7384C29.1647 32.3011 29.599 31.9412 30.089 31.6983C32.2761 30.6147 34.4638 29.5308 36.6514 28.4469C37.0947 28.2371 36.8902 28.4293 37.6013 28.0475C37.4034 28.1178 37.2054 28.1882 37.0075 28.2585C37.3353 28.112 38.6239 27.4994 39.1279 27.2434C39.2349 27.1893 39.3179 27.1507 39.3668 27.1267C39.4166 27.1095 39.4445 26.9846 40.0601 26.791C40.6117 26.6395 40.7158 26.6956 41.0154 26.6684C41.2681 26.6496 41.5524 26.6327 41.6278 26.6373C41.6855 26.6406 41.7078 26.6732 41.8451 26.6852C42.2768 26.7346 41.9376 26.6076 42.3527 26.7662C42.2486 26.7553 42.1442 26.7475 42.0399 26.7427C42.5622 26.7985 43.2307 27.0264 42.4864 26.8897C42.3575 26.8724 42.473 26.8586 42.3768 26.8435C41.4296 26.7129 40.9021 26.8362 40.6791 26.8719C40.4546 26.9193 40.5196 26.9119 40.7417 26.8797C41.1846 26.795 42.2803 26.8033 42.9282 26.9759C43.0722 27.034 43.5256 27.173 43.9516 27.3907C44.339 27.5856 44.7353 27.7765 44.7562 27.7927C44.8088 27.8343 44.5743 27.7597 44.8445 27.9317C44.9013 27.968 46.6119 28.7933 45.9718 28.5443C45.8398 28.4929 45.0316 28.0734 44.8344 27.9769C45.251 28.2985 46.3987 28.7101 46.5188 28.7743C47.0029 29.034 45.5359 28.381 46.6372 28.9448C47.484 29.3783 46.7154 28.9184 47.0556 29.0562C47.2467 29.1336 48.1763 29.6817 48.1933 29.5824C48.5284 29.7384 48.3121 29.6874 48.3513 29.7111C48.3898 29.7339 49.0525 30.033 49.2544 30.1566C49.2788 30.1717 49.1758 30.1763 49.2004 30.1932C49.2488 30.2252 49.8799 30.5296 49.907 30.5384C49.9244 30.5437 49.7946 30.4298 49.8608 30.4509C49.9378 30.4757 50.5363 30.7865 50.5751 30.7919C50.6306 30.7984 49.8805 30.4374 50.0266 30.4555C50.3642 30.6381 50.938 30.8884 51.1821 30.9663C51.1216 30.9486 50.7881 30.7837 50.6744 30.7224C50.7609 30.6852 51.4749 31.0433 51.2052 30.9721C51.3741 31.0224 51.2754 30.9549 51.3757 30.9728C51.4019 30.9778 51.6232 31.0867 51.6713 31.0968C51.6779 31.0974 51.4625 30.9593 51.5146 30.969C51.6089 30.9867 52.2751 31.3264 52.3267 31.36C52.472 31.4545 51.916 31.2031 51.857 31.2075C51.8484 31.2084 52.2857 31.4935 52.2903 31.5017C52.2923 31.5657 51.7943 31.2713 51.8306 31.3462C51.9535 31.4196 52.0763 31.493 52.1992 31.5664C51.6839 31.3661 50.7849 30.8871 50.5239 30.822C51.2616 31.1714 52.0246 31.5552 51.9642 31.672C51.9389 31.7213 51.6094 31.5929 51.6153 31.6116C51.6392 31.6799 52.1009 31.8495 52.1157 31.86C52.1277 31.8693 52.1324 31.8751 52.1311 31.8777C52.1311 31.8777 52.1311 31.8777 52.1311 31.8777C52.1179 31.904 51.4852 31.6115 51.448 31.6079C51.3849 31.6031 51.6181 31.8299 51.608 31.8492C51.5963 31.8483 51.1421 31.6473 51.2749 31.7562C51.4092 31.8663 51.7972 32.0613 51.8091 32.0716C51.873 32.1293 51.1842 31.8083 51.1578 31.8103C51.1441 31.8111 51.4901 32.0313 51.4953 32.0474C51.4989 32.0628 51.2098 31.9479 51.0833 31.9276C50.9891 31.9124 51.2166 32.0506 51.1729 32.0337C51.1417 32.0215 50.5 31.7 50.4662 31.6887C50.4159 31.6719 50.551 31.7775 50.5253 31.7742C50.4888 31.7697 50.287 31.655 50.3083 31.6798C50.3244 31.6983 51.0755 32.2053 51.0563 32.2307C51.0231 32.274 50.2271 31.7383 50.9246 32.3232C50.9295 32.3272 51.129 32.4102 51.1338 32.414C51.2353 32.5083 50.5906 32.2528 51.3509 32.6212C49.9151 31.9788 51.14 32.6058 50.8917 32.5824C50.7959 32.5732 50.2446 32.3135 50.2398 32.3169C50.2731 32.3827 50.4619 32.439 50.5113 32.4878C50.5384 32.5148 50.0301 32.3126 50.1263 32.3945C50.1761 32.4368 50.6961 32.6906 50.7161 32.704C50.9081 32.832 50.6432 32.7339 50.6791 32.7746C50.7029 32.8017 51.0147 32.9589 51.0217 32.9651C51.0326 32.9763 50.5839 32.8135 50.487 32.7866C50.4131 32.7664 50.6548 32.9132 50.605 32.8956C50.3053 32.7892 49.749 32.4003 50.2657 32.8138C50.2973 32.8391 50.5177 32.9455 50.5234 32.9502C50.6411 33.053 50.2365 32.8545 50.15 32.8473C50.0014 32.835 50.5946 33.097 50.0953 32.891C50.4405 33.1041 50.6426 33.2035 51.0701 33.4059C49.8864 32.8456 49.4089 32.7674 50.7106 33.4142C50.298 33.2054 50.3077 33.3009 50.1837 33.2405C50.1066 33.2028 49.5429 32.8309 49.737 33.1301C49.7614 33.1675 50.1385 33.324 50.0038 33.3083C49.1348 32.8606 49.9721 33.3253 49.9702 33.3312C49.9113 33.4208 47.814 32.2747 47.4415 32.102C47.0093 31.9016 46.5932 31.7874 46.5006 31.7412C46.196 31.589 46.4678 31.6773 46.4067 31.6292C46.3446 31.5808 45.4419 31.2207 45.4006 31.195C45.2409 31.095 45.4338 31.135 45.4175 31.124C45.2235 30.9925 44.0425 30.4462 43.7221 30.2728C43.7175 30.3071 44.3702 30.6364 43.9384 30.4793C43.4356 30.2965 43.473 30.1537 43.4634 30.1418C43.2268 30.0237 42.9902 29.9056 42.7536 29.7875C42.0265 29.4195 41.1269 29.4204 40.4007 29.7894C39.5536 30.2137 38.7062 30.6381 37.8587 31.0625C37.9202 31.1176 39.3184 30.3536 39.3553 30.3465C39.5723 30.3049 37.1662 31.507 36.859 31.6303C37.0906 31.533 37.3222 31.4357 37.5538 31.3385C37.2105 31.6089 36.312 31.9299 35.7758 32.2417C35.6025 32.3425 35.9613 32.2012 35.9552 32.2068C35.7695 32.3381 35.4351 32.4757 35.6557 32.3139C35.1847 32.5988 35.2346 32.5194 34.8564 32.7045C34.8369 32.714 35.0145 32.6651 34.7232 32.8273C34.5867 32.9033 33.8421 33.2758 33.7564 33.3535C33.7212 33.3858 34.1608 33.3205 34.1542 33.1908C34.99 32.8376 34.3887 33.0129 34.7046 32.8579C34.7531 32.8344 34.6718 32.9493 35.4501 32.5251C35.3528 32.7076 34.4003 33.0838 34.2504 33.175C33.9412 33.363 35.298 32.7536 35.5001 32.5482C35.428 32.6887 35.6001 32.5123 35.8981 32.3675C36.2242 32.2091 36.0953 32.3046 36.2709 32.217C36.7511 31.9776 36.5227 32.0181 36.9449 31.8734C36.4769 31.9017 37.6114 31.513 37.9427 31.4012C37.4428 31.6616 36.943 31.922 36.4432 32.1825C36.4763 32.1767 36.5094 32.1709 36.5426 32.1652C36.4092 32.2303 36.2758 32.2955 36.1425 32.3607C36.1596 32.3418 36.1767 32.3228 36.1938 32.3039C35.5362 32.7001 35.3389 32.7231 35.2827 32.7504C34.5606 33.1027 33.7309 33.5183 33.0043 33.8815C32.8953 33.936 32.997 33.9524 32.1814 34.3076C31.9213 34.4209 32.1396 34.2593 31.8555 34.4093C31.7001 34.5601 31.6144 34.6086 31.5532 34.6273C31.5405 34.6224 31.5249 34.6036 31.5167 34.6083C31.4686 34.6377 31.4714 34.6855 31.4687 34.6882C31.431 34.7335 31.3924 34.8127 31.3983 34.8797C31.3985 34.8949 31.3986 34.9108 31.3988 34.9265C31.3989 34.9295 31.4037 34.9028 31.4093 34.8788C31.4172 34.8751 31.4268 34.8718 31.4286 34.8798C31.4294 34.9025 31.4289 34.9397 31.4268 34.9953C31.4227 35.1014 31.2556 36.0532 31.3101 36.8853C31.3214 36.6689 31.3326 36.4525 31.3439 36.236C31.3282 36.4905 31.3703 38.2736 31.415 37.8376C31.4423 37.5704 31.3346 36.9179 31.4382 36.8463C31.4072 37.4397 31.4535 40.7168 31.4295 40.9719C31.426 41.0072 31.3924 40.7901 31.3881 40.8388C31.3849 40.8766 31.3928 41.6272 31.3799 41.7269C31.3723 41.7862 31.3517 41.4545 31.3396 41.4815C31.3309 41.5051 31.3166 42.4426 31.3587 42.4961C31.3418 42.2658 31.3565 41.6188 31.392 41.9582C31.3964 42.0018 31.3693 42.228 31.3749 42.281C31.4264 42.773 31.4141 41.3027 31.4145 41.0752C31.4681 41.9988 31.4049 43.4273 31.4399 44.4974C31.4048 44.9298 31.3862 43.8563 31.3572 44.3456C31.297 45.3606 31.4057 44.6156 31.4101 44.6472C31.4455 44.8993 31.256 45.758 31.4002 45.7584C31.3785 46.1264 31.3603 46.0073 31.3792 46.5265C31.3892 46.4582 31.3992 46.3899 31.4092 46.3216C31.4927 46.8981 31.2819 48.1184 31.2659 48.0269C31.2228 47.781 31.29 47.1455 31.2883 47.0913C31.2859 47.0109 31.1396 46.7889 31.2705 45.9097C31.1723 45.5497 31.2042 47.3031 31.1373 46.5053C31.1483 47.0441 31.08 49.2608 31.123 49.5799C31.1287 49.618 31.2265 49.4406 31.1767 49.9883C31.153 50.2482 31.1518 49.6213 31.1296 49.7403C31.0612 50.1064 31.1049 55.085 31.1085 56.0307C31.1087 56.0921 31.0783 56.0695 31.0786 56.1299C31.0794 56.3151 31.1247 56.9904 31.1107 57.3221C31.1669 56.635 31.1713 57.9694 31.1651 58.3088C31.1557 58.824 31.1023 58.7921 31.0909 59.0147C31.0741 59.3434 31.0824 59.7412 31.0923 60.1444C31.1074 60.347 31.2261 60.4908 31.2759 60.6251C31.2986 60.5935 31.3279 60.6115 31.3702 60.6471C31.4468 60.7253 31.6507 60.8506 31.783 60.8235C31.8576 60.8137 31.9376 60.7619 31.9634 60.7188C32.0429 60.6573 32.0554 60.6256 31.9351 60.6633C31.9235 60.6626 31.9085 60.6636 31.89 60.6655C31.903 60.6606 31.9158 60.655 31.9284 60.6489C32.543 60.3435 33.172 60.0071 33.7415 59.7148C33.8424 59.663 33.7183 59.764 33.89 59.6746C33.9054 59.6662 33.9119 59.6249 34.0589 59.5474C35.2725 58.9072 34.7079 59.2706 34.947 59.1748C35.0808 59.1213 35.1782 59.0792 35.2487 59.0461C34.5365 59.4097 33.7177 59.8342 33.4975 59.9454C33.7194 59.9187 35.0761 59.1398 35.4942 58.9533C35.5087 58.9469 35.4779 59.0087 35.4924 59.0018C35.4927 59.0016 35.493 59.0015 35.4933 59.0013C35.648 58.9275 36.6176 58.4255 36.3944 58.4817C36.3346 58.4969 35.8851 58.7217 35.3541 58.9923C35.4942 58.9118 35.3657 58.9241 35.3903 58.9096C35.6887 58.7347 36.4653 58.397 36.7363 58.2683C36.7983 58.2388 36.7805 58.2144 36.7906 58.2093C37.0376 58.0933 36.9755 58.2194 37.1866 58.0158C37.6759 57.8896 36.3655 58.444 36.4858 58.4609C36.5648 58.472 38.6261 57.4252 39.1962 57.0761C39.329 56.9992 39.4062 56.9544 39.3995 56.9438C39.4166 56.9462 39.4744 56.9317 39.5901 56.8986C39.8364 56.7909 40.9835 56.5284 41.1914 56.5319C41.2255 56.5265 41.2062 56.4465 41.2494 56.443C41.3611 56.3921 42.8151 56.5504 43.3326 56.7407C43.0576 56.634 42.7728 56.5495 42.4822 56.4889C43.3648 56.6517 43.7029 56.8502 43.7822 56.864C43.8588 56.8896 43.6666 56.7825 43.3861 56.6713C43.3577 56.6611 43.331 56.6488 43.3038 56.6394C42.8678 56.4664 42.2704 56.3654 42.262 56.3612C42.241 56.3293 43.382 56.5037 44.0512 56.8874C44.363 57.051 44.5704 57.1724 44.4075 57.1239C44.3822 57.1163 44.1949 57.0183 44.0285 56.9337C43.7308 56.7849 43.4731 56.6892 43.8237 56.8707C43.8505 56.8854 43.9216 56.9185 44.0128 56.9641C44.2137 57.0645 44.5559 57.2272 44.5772 57.2428C44.6858 57.3223 44.3021 57.1604 43.9794 57.0318C43.656 56.8936 43.368 56.8208 43.4548 56.8771C43.6167 56.9182 43.7893 56.9829 43.9624 57.0651C44.1973 57.1746 44.4424 57.3067 44.6776 57.4143C44.8433 57.4903 44.9015 57.4739 44.922 57.4833C45.2272 57.6241 45.0395 57.5778 45.1403 57.6271C45.1945 57.6533 45.8272 57.8683 45.6594 57.9241C47.6516 58.8175 46.2402 58.1118 45.0401 57.5197C45.4387 57.6681 46.1703 58.0585 46.5078 58.2154C46.6289 58.2717 46.5768 58.199 46.7822 58.2923C47.2049 58.4845 49.1651 59.5182 49.6763 59.7864C49.3527 59.6411 49.4251 59.7281 49.6712 59.8476C49.9173 59.9672 49.7389 59.8101 49.7895 59.8282C49.8437 59.8477 50.9791 60.4474 51.1736 60.5359C50.2994 60.1233 50.4741 60.2614 51.2057 60.6325C51.0938 60.5911 50.9819 60.5497 50.87 60.5084C51.2441 60.6779 51.9351 61.0771 52.2897 61.2563C52.3296 61.2765 52.3637 61.2911 52.3894 61.2993C52.4165 61.3081 52.3396 61.2308 52.3551 61.2358C52.497 61.304 53.0058 61.48 53.0369 61.4595C53.0583 61.454 52.8425 61.3778 52.9282 61.3794C52.9444 61.3799 53.1509 61.4764 53.3697 61.4692C53.45 61.4666 53.4023 61.4293 53.4224 61.4277C53.5872 61.4071 53.4916 61.4806 53.7961 61.4383C54.0185 61.3974 54.1646 61.3059 54.4508 61.2065C53.5758 61.4184 54.1662 61.2922 54.5397 61.0968C54.604 61.0631 54.666 61.0302 54.7221 60.9997C54.8158 60.9488 54.7049 60.9311 55.2884 60.6749C54.1297 61.3866 55.6618 60.558 55.9809 60.3999C55.9985 60.3915 56.0238 60.4271 56.1803 60.3496C56.1935 60.343 56.1615 60.3264 56.3057 60.2518C57.6732 59.5443 56.8075 60.0141 57.0819 59.909C57.1988 59.8642 57.8499 59.4925 58.0298 59.4014C58.0712 59.3806 58.0657 59.4172 58.2256 59.3359C58.5085 59.192 58.7484 59.036 58.9346 58.94C58.9564 58.929 58.9786 58.9713 59.3268 58.7798C59.4248 58.726 59.5293 58.6547 59.3813 58.7134C58.8908 58.9082 58.0336 59.4243 57.4819 59.6498C56.9787 59.8555 58.5056 59.0876 58.585 59.0476C58.6141 59.0329 58.3262 59.2034 58.6315 59.0559C58.8923 58.9299 59.3287 58.6193 59.7227 58.4424C59.7528 58.4289 60.0925 58.3372 60.0801 58.348C60.0685 58.3571 59.6017 58.6075 59.6795 58.5913C59.6888 58.5892 59.9895 58.4383 60.0356 58.4321C60.0919 58.4245 60.3022 58.5207 60.3685 58.4926C60.5384 58.4201 60.4127 58.437 60.5207 58.3862C60.7522 58.2772 61.5696 57.9279 61.5675 57.8592C61.4347 57.9214 61.3019 57.9837 61.1692 58.0459C61.8957 57.6754 61.5729 57.8071 61.671 57.745C61.7766 57.678 61.7699 57.7427 62.0181 57.6244C62.0721 57.5986 63.0957 57.0739 63.0667 57.0626C62.5142 57.3799 62.6948 57.2138 62.668 57.2258C62.5663 57.2717 62.456 57.3694 62.322 57.4356C61.3787 57.9007 62.3004 57.3726 62.0715 57.4699C61.9927 57.5034 61.855 57.6086 61.8218 57.6234C61.714 57.6713 61.6933 57.6341 61.6245 57.6723C61.464 57.7615 61.6825 57.7195 61.6709 57.7288C61.5411 57.8358 60.9457 58.0812 61.274 57.8438C61.0488 57.9301 61.0593 58.0138 60.8748 58.0705C60.5082 58.1834 61.0225 57.9443 61.1551 57.8662C61.631 57.5861 61.7909 57.5403 62.4837 57.1821C62.7333 57.0532 63.0135 56.8698 63.1291 56.8096C63.1664 56.7902 63.382 56.7214 63.5737 56.6322C63.6235 56.6142 63.6503 56.5664 63.5867 56.4856C63.6386 56.4763 63.8254 56.4642 63.8505 56.3731C63.8691 56.2998 63.7874 56.3048 63.7871 56.2976C63.7863 56.2885 63.8036 56.2155 63.7917 56.1884C63.7916 56.1881 63.7915 56.187 63.7914 56.1859C63.779 56.0524 63.7506 56.119 63.739 55.9071C63.7102 55.3797 63.7863 55.3936 63.7912 55.3394C63.8483 54.7101 63.7402 54.9856 63.7315 54.846C63.7235 54.7161 63.7651 52.8946 63.7378 52.5112C63.753 52.6672 63.7682 52.8232 63.7835 52.9793C63.8309 52.7001 63.7535 52.4041 63.8386 52.3989C63.7013 52.3422 63.793 51.7659 63.7895 51.5928C63.788 51.5245 63.7646 51.5299 63.7636 51.4445C63.7595 51.1109 63.7782 50.3588 63.7663 50.1779C63.7152 49.3954 63.6303 51.3962 63.6252 51.5538C63.6267 51.2385 63.5959 49.4546 63.53 50.2746C63.5198 50.4013 63.5812 50.6259 63.5836 50.6971C63.5994 51.1789 63.5444 50.8 63.5391 50.8378C63.5307 50.902 63.5839 51.2191 63.5776 51.3028C63.5755 51.3307 63.5257 51.1509 63.5246 51.6105C63.4763 51.3845 63.5157 50.0928 63.5043 49.9234C63.5003 49.863 63.397 50.2414 63.4973 49.136C63.4877 49.1488 63.4782 49.1616 63.4686 49.1745C63.4646 48.559 63.4607 47.9435 63.4567 47.328C63.4788 47.3949 63.5232 47.7405 63.5138 47.3052C63.5083 47.0546 63.4591 47.24 63.4577 47.2172C63.4442 46.9923 63.4605 43.0123 63.455 42.2409C63.4533 41.9786 63.4137 41.2472 63.413 41.1914C63.409 40.858 63.4348 39.6772 63.4292 39.4416C63.4256 39.2945 63.3845 39.4344 63.3864 39.303C63.3883 39.1808 63.428 39.3073 63.4297 39.2711C63.4441 38.9706 63.3919 36.6879 63.4294 36.1459C63.4182 36.4772 63.4976 38.1303 63.5256 38.0971C63.5294 38.0899 63.5597 37.6881 63.5449 37.6052C63.5793 37.4683 63.4746 36.9982 63.4952 36.7425C63.4975 36.7136 63.5563 36.8274 63.5669 36.3711C63.5706 36.2138 63.5248 35.8022 63.5761 35.3878C63.5514 34.788 63.6277 31.6345 63.5645 31.4181C63.5612 31.4117 63.5394 31.8558 63.5135 31.5557C63.4791 31.1569 63.5951 31.5151 63.6051 31.0502C63.6054 31.0384 63.6052 30.9915 63.6048 30.9216C63.6101 30.8716 63.5514 30.7732 63.5405 30.7773C63.4701 30.7885 63.4987 30.8834 63.4834 30.8814C63.4664 30.8805 63.4296 30.8422 63.4298 30.8403C63.4273 30.8307 63.5382 30.8222 63.4587 30.7881C63.4591 30.8017 63.4577 30.8148 63.4548 30.827C63.4232 30.8217 63.4521 30.7773 63.4473 30.7655C63.4471 30.7651 63.4469 30.7648 63.4467 30.7646C63.4159 30.7366 63.3888 30.8155 63.34 30.7055C63.3216 30.6769 63.348 30.6422 63.3467 30.638C63.3162 30.5992 63.3095 30.7068 63.2556 30.6415C63.2485 30.6392 63.3182 30.5676 63.1974 30.6086C63.145 30.6342 63.085 30.6639 63.0172 30.6978C63.0806 30.6744 63.144 30.6509 63.2074 30.6274C63.2075 30.6277 63.208 30.6278 63.2085 30.6278C63.2083 30.6283 63.208 30.6287 63.2077 30.6292C63.0643 30.7194 62.1782 31.1735 62.0549 31.2307C61.6885 31.4008 61.9788 31.1942 61.6188 31.3815C61.8853 31.3325 60.786 31.8932 60.8205 31.8035C60.7028 31.9534 59.7371 32.3662 59.2956 32.5848C59.0169 32.7229 58.4656 33.0384 58.3754 33.0788C58.2655 33.1281 58.2734 33.0621 58.0735 33.1482C58.0165 33.1728 57.4561 33.4986 56.9225 33.7012C56.8192 33.7405 56.5703 33.7596 56.7427 33.6471C57.0378 33.4544 57.6641 33.2261 57.6317 33.1801C57.5962 33.1312 56.8142 33.5619 56.5959 33.6624C55.5884 34.1261 56.1326 33.7832 56.0985 33.7788C56.0586 33.7748 55.9226 33.8302 55.785 33.892C55.5732 33.9908 55.3486 34.0774 55.3309 34.0815C55.1984 34.1171 55.7021 33.8676 55.6927 33.8325C55.6879 33.8077 54.9724 34.02 55.1256 33.9442C55.2469 33.892 55.4963 33.8056 55.6975 33.7177C55.8292 33.6635 55.9389 33.6205 55.9521 33.6126C56.2966 33.4039 55.851 33.5448 55.6393 33.6007C55.6126 33.6089 55.5892 33.6156 55.5702 33.6204C55.5378 33.6284 55.5815 33.5976 55.6228 33.5684C55.6531 33.5455 55.682 33.5246 55.6633 33.5319C55.6462 33.5387 55.63 33.5452 55.6147 33.5514C54.9733 33.7953 55.5643 33.7242 55.0783 33.8996C54.6238 34.0369 55.1866 33.7955 55.1649 33.7941C55.1445 33.8062 54.6074 33.969 54.5159 33.9601C54.4863 33.9715 55.2772 33.6818 55.5656 33.4539C55.6419 33.3977 55.686 33.359 55.6705 33.3538C55.6298 33.3756 55.5892 33.3974 55.5486 33.4192C55.2018 33.6032 54.8306 33.7439 54.4467 33.8362C54.4012 33.7901 55.031 33.6653 55.0891 33.6242C55.2098 33.5664 54.8491 33.6619 54.8579 33.6345C54.8644 33.6219 55.2506 33.4356 54.8813 33.5454C54.7554 33.5778 54.4985 33.716 54.0138 33.733C54.8356 33.5772 54.9287 33.4511 54.8455 33.4736C54.7589 33.4849 54.4701 33.5464 54.4439 33.5385C54.396 33.5272 55.1253 33.297 54.2234 33.5158C54.1621 33.3989 54.2372 33.4791 54.4864 33.3972C54.7818 33.2755 54.0852 33.4904 55.1773 33.1221C55.1011 33.1198 54.2262 33.386 54.1715 33.3659C54.13 33.3696 54.3237 33.3041 54.2509 33.308C53.4 33.318 53.981 33.2866 53.7343 33.2424C53.7113 33.2507 52.9406 33.2122 53.5271 33.208C54.5897 33.1437 55.028 32.9371 55.1127 32.7221C54.4006 33.005 53.4789 33.1557 53.2383 33.1289C52.8791 33.1044 53.2537 33.0981 53.2096 33.0839C53.1944 33.0827 52.889 33.0527 52.8856 33.0464C52.7894 32.9602 53.1198 33.0306 53.5453 33.033C53.9709 33.0434 54.4866 32.9478 54.7153 32.8497C54.5832 32.8743 54.4509 32.8918 54.3191 32.9021C54.4915 32.8607 54.6609 32.8071 54.8257 32.7419C54.0115 32.967 54.8056 32.7533 54.9418 32.5588C54.9732 32.5193 54.5021 32.7682 55.0295 32.4621C54.6164 32.6289 54.7425 32.5553 54.3668 32.7003C54.3664 32.6722 54.7184 32.5493 55.022 32.3661C55.2164 32.2538 55.4081 32.145 55.5313 32.0744C55.29 32.1846 55.1231 32.2661 55.0033 32.329C54.5486 32.5331 54.8591 32.5677 54.001 32.6863C53.8131 32.7728 54.3169 32.674 54.2769 32.6851C54.1347 32.7516 53.7878 32.7745 53.3518 32.8737C53.2788 32.8879 53.584 32.9627 53.1301 32.9335C53.0787 32.9317 52.8006 32.8425 52.8064 32.8375C52.85 32.8097 53.1257 32.8592 53.139 32.8418C53.1508 32.8308 52.8412 32.8005 52.8411 32.7931C52.8396 32.7468 53.0994 32.8117 53.063 32.7909C52.9746 32.751 51.9382 32.4862 53.321 32.7049C52.1517 32.6108 53.1644 32.796 53.6275 32.7351C53.744 32.723 53.7714 32.6937 53.9332 32.6626C54.141 32.6226 54.3836 32.5731 54.4864 32.5342C54.5919 32.4866 53.9562 32.6513 54.8533 32.3384C54.3981 32.4981 53.5554 32.6983 53.0849 32.5757C52.6234 32.4588 52.7974 32.4597 53.0914 32.4815C53.3883 32.5041 53.8164 32.4618 53.8948 32.4415C53.9368 32.4336 53.7898 32.4137 53.818 32.4076C53.8677 32.4274 54.7158 32.219 54.7702 32.1259C54.8358 32.0652 54.4792 32.2496 54.4412 32.2205C54.4292 32.2136 54.6863 32.1074 54.8431 32.0081C55.0276 31.9004 55.1282 31.8359 54.8278 31.978C54.8277 31.978 54.8274 31.9782 54.827 31.9783C54.4998 32.157 53.8196 32.3785 53.6924 32.2755C54.0836 32.2394 54.4658 32.1271 54.8127 31.9472C54.9923 31.8548 55.1722 31.7623 55.3521 31.6698C55.1627 31.7432 54.9732 31.8167 54.7838 31.8901C54.6505 31.937 54.5149 31.974 54.3785 32.0009C54.5122 31.9534 54.639 31.9006 54.76 31.8416C55.2747 31.5887 55.7605 31.3617 56.2572 31.0688C54.5758 31.7784 56.7441 30.7204 56.7615 30.6958C56.7656 30.6842 56.0818 30.9196 55.9709 30.9556C56.5226 30.6386 58.2408 29.7592 57.1782 30.1591C57.3734 30.0912 57.788 29.8105 57.7799 29.8089C57.7003 29.7906 56.7471 30.305 56.8841 30.1841C57.0427 30.0438 57.3322 29.9817 57.6111 29.8356C59.0419 29.0855 58.5242 29.041 59.9919 28.3549C59.9588 28.3607 59.9257 28.3664 59.8925 28.3722C60.4782 28.0856 61.0639 27.7991 61.6496 27.5125C62.8084 26.9294 64.259 27.0036 65.3479 27.696C66.0583 28.138 66.6126 28.8233 66.8966 29.6073C67.0311 29.9088 67.1726 30.3709 67.1874 30.9243C67.2359 31.7696 67.2625 32.9658 67.2556 33.6395C67.2538 33.8208 67.2103 34.7109 67.2027 34.7781C67.1881 34.9025 67.1825 34.2185 67.1551 34.5276C67.1495 34.5929 67.1312 36.0998 67.1776 35.992C67.1829 35.8232 67.1596 35.2947 67.1706 35.2082C67.2486 34.6006 67.1862 39.2464 67.2177 39.4765C67.2327 39.3736 67.2478 39.2707 67.2629 39.1678C67.2555 39.461 67.248 39.7542 67.2406 40.0473ZM62.9979 30.9137C62.8613 31.034 62.4513 31.2 62.2241 31.3282C61.9104 31.5056 61.4432 31.9396 61.5985 31.6611C62.065 31.412 62.5314 31.1628 62.9979 30.9137ZM63.4461 34.3024C63.4711 33.9479 63.5714 34.2229 63.5297 34.5134C63.525 34.5457 63.4125 34.782 63.4461 34.3024ZM63.4917 30.895C63.4936 30.8957 63.4928 30.9178 63.4908 30.9187C63.4906 30.9188 63.4905 30.9188 63.4903 30.9189C63.4794 30.9941 63.4721 30.9774 63.468 30.9216C63.4579 30.9105 63.4643 30.8859 63.4917 30.895ZM63.5452 48.5384C63.5408 48.1478 63.4496 48.4307 63.4872 48.6735C63.4896 48.6888 63.5454 48.5641 63.5452 48.5384ZM63.5476 48.2606C63.6293 47.9572 63.4637 47.3463 63.4804 47.832C63.4821 47.8791 63.5436 48.2746 63.5476 48.2606ZM63.486 33.0389C63.5173 33.0788 63.5022 33.4444 63.4947 33.6006C63.4661 33.5963 63.4895 33.192 63.486 33.0389ZM63.4947 42.3097C63.5193 42.3253 63.5179 41.0543 63.4855 40.9678C63.4992 41.1684 63.4726 42.2951 63.4947 42.3097ZM63.5292 45.569C63.5335 45.5368 63.527 45.0978 63.5053 45.1106C63.4768 45.3249 63.51 45.7141 63.5292 45.569ZM63.5278 52.0472C63.5332 52.071 63.6714 51.7422 63.5805 52.5213C63.5671 52.6357 63.531 52.2272 63.5261 52.2678C63.5164 52.3529 63.5119 52.4202 63.5111 52.4743C63.4997 52.1114 63.4943 51.7345 63.5026 51.698C63.5422 51.5268 63.5255 52.0366 63.5278 52.0472ZM63.6307 55.4482C63.6533 55.5229 63.6412 56.0004 63.6319 56.109C63.6304 56.1251 63.586 56.0666 63.5768 56.1892C63.5754 56.1905 63.5748 56.1933 63.5752 56.1966C63.5773 56.2175 63.6417 56.1882 63.6263 56.2337C63.6079 56.2762 63.5771 56.2099 63.5723 56.2153C63.5702 56.2178 63.5791 56.2848 63.5456 56.2692C63.5237 56.2582 63.5546 56.212 63.5477 56.1957C63.5461 56.1913 63.5422 56.1892 63.5375 56.1882C63.5227 56.1588 63.4994 56.2278 63.5065 56.0022C63.5124 55.815 63.5889 55.9188 63.5928 55.8793C63.5959 55.8461 63.5518 55.1916 63.6305 55.4492C63.6306 55.4488 63.6306 55.4485 63.6307 55.4482ZM63.5145 52.5724C63.5119 52.5451 63.5105 52.513 63.5111 52.4743C63.5121 52.5072 63.5134 52.54 63.5145 52.5724ZM63.3315 30.7231C63.348 30.7451 63.3117 30.7788 63.286 30.7581C63.2746 30.734 63.3279 30.7179 63.3315 30.7231ZM63.5768 52.9089C63.5577 53.4479 63.5313 53.0515 63.5145 52.5724C63.5289 52.7245 63.5832 52.7279 63.5768 52.9089ZM63.5449 37.6052C63.5392 37.628 63.5303 37.6424 63.5157 37.6442C63.5317 37.5845 63.5403 37.5791 63.5449 37.6052ZM63.5188 38.8627C63.5634 39.2938 63.5616 38.4179 63.5297 38.4235C63.5177 38.4261 63.5171 38.8455 63.5188 38.8627ZM63.5408 49.0394C63.5452 48.9999 63.6797 49.6125 63.5788 48.7231C63.5629 49.1978 63.5483 48.697 63.5365 48.7044C63.5026 48.7237 63.5352 49.5211 63.5205 49.6977C63.5811 49.8359 63.5265 49.1695 63.5408 49.0404C63.5408 49.04 63.5408 49.0397 63.5408 49.0394ZM60.602 57.8384C60.6828 57.7583 60.9944 57.6152 61.2023 57.5136C61.1215 57.5937 60.8098 57.7368 60.602 57.8384ZM31.4382 35.2888C31.471 36.8737 31.3264 37.079 31.3836 35.6288C31.3848 35.6004 31.4235 35.1926 31.4382 35.2888ZM31.4007 48.8907C31.3377 49.04 31.3276 48.5458 31.3536 48.2212C31.3594 48.1478 31.4233 47.8762 31.4357 48.1863C31.3594 48.1764 31.3302 48.656 31.4007 48.8907ZM63.6172 53.2136C63.6592 53.3705 63.6293 53.8536 63.623 54.1082C63.5884 53.9529 63.604 53.4387 63.6172 53.2136ZM31.3628 40.4968C31.358 40.6638 31.4128 40.7766 31.4174 40.7478C31.4383 40.6186 31.394 40.3064 31.3628 40.4968ZM63.6237 51.654C63.6488 51.6319 63.673 52.2718 63.6109 52.3164C63.6154 52.1796 63.608 51.6698 63.6237 51.654ZM61.0006 57.6601C61.0951 57.6271 60.6452 57.8777 60.5003 57.936C60.4996 57.9065 60.9386 57.6818 61.0006 57.6601ZM31.3814 43.1863C31.3766 43.3359 31.3752 43.7096 31.3973 43.751C31.425 43.8024 31.4156 43.2544 31.3814 43.1863ZM45.8259 31.6684C45.8383 31.6857 45.2885 31.4911 45.0665 31.3598C44.645 31.1102 45.8107 31.653 45.8259 31.6684ZM31.3345 38.9154C31.3866 38.4437 31.3361 38.9675 31.391 38.9468C31.393 38.6294 31.3957 37.8397 31.3417 38.3826C31.3313 38.4884 31.338 38.7675 31.3345 38.9154ZM31.3161 39.3506C31.3339 39.4012 31.39 39.7412 31.386 39.4473C31.384 39.3114 31.3217 39.0923 31.3161 39.3506ZM42.6074 30.0864C42.6065 30.0859 42.6057 30.0854 42.6049 30.0848C42.5667 30.0553 42.5752 30.052 42.6145 30.0665C42.8763 30.1775 43.9822 30.7506 44.019 30.7766C44.0433 30.7937 44.0586 30.8062 44.0669 30.8143C44.1374 30.8323 44.4661 30.9936 44.4866 31.0474C44.3899 30.9954 44.1203 30.8645 44.0911 30.845C44.0785 30.8367 44.0693 30.8301 44.0631 30.8251C43.9325 30.7976 42.6757 30.1309 42.6074 30.0864ZM40.7774 29.9328C41.0306 29.7708 41.1149 29.8928 41.0896 29.899C40.8072 30.0212 40.9753 29.8866 40.9657 29.8837C40.9413 29.8802 40.7462 29.9899 40.7782 29.9324C40.7779 29.9325 40.7776 29.9327 40.7774 29.9328ZM42.2578 29.9247C42.2704 29.9238 42.4923 30.0099 42.4994 30.0184C42.6633 30.1229 42.0442 29.8863 42.2578 29.9247ZM63.5725 56.4777C63.523 56.4974 63.5397 56.4336 63.571 56.4257C63.5735 56.425 63.6164 56.4561 63.5725 56.4777ZM31.3282 39.5829C31.3197 39.6503 31.2878 41.3751 31.3555 41.2715C31.3475 41.125 31.3824 39.1645 31.3282 39.5829ZM31.3118 52.4728C31.3123 52.1687 31.3762 52.5003 31.3524 52.6626C31.3435 52.7228 31.3117 52.5495 31.3118 52.4728ZM63.6817 50.7912C63.6466 50.4754 63.7644 50.5407 63.724 50.8145C63.7224 50.8252 63.6831 50.8036 63.6817 50.7912ZM31.3485 50.0429C31.3872 51.0919 31.1847 50.8435 31.2531 49.4797C31.2621 49.5224 31.2711 49.5651 31.2801 49.6077C31.3105 48.0336 31.2944 49.5001 31.3057 49.8855C31.31 50.032 31.3439 49.9092 31.3488 50.0419C31.3487 50.0422 31.3486 50.0426 31.3485 50.0429ZM31.3079 54.0724C31.1641 55.0826 31.2578 53.154 31.239 52.6009C31.2984 53.1371 31.2894 53.8353 31.3502 52.8857C31.362 54.2741 31.3047 53.6961 31.2999 53.7516C31.2946 53.8172 31.3141 54.0293 31.3079 54.0724ZM31.3069 51.4077C31.3028 51.3493 31.332 50.9093 31.3272 50.7508C31.3764 50.9725 31.3355 51.7953 31.3069 51.4077ZM37.9419 31.3702C37.9574 31.3195 38.0255 31.2537 38.3425 31.1112C38.2552 31.1765 38.0643 31.2906 37.9419 31.3702ZM62.6086 30.8819C62.3935 30.9864 61.9611 31.1865 62.1098 31.1573C62.1257 31.1533 62.6181 30.9026 62.6086 30.8819ZM31.297 44.5925C31.2923 44.6434 31.2891 45.9587 31.3316 45.5044C31.3444 45.3674 31.339 44.1706 31.297 44.5925ZM31.3019 37.7814C31.3015 37.8915 31.3087 38.3387 31.3178 38.3482C31.3493 38.3785 31.332 37.8295 31.3019 37.7814ZM61.512 31.3863C61.4821 31.3968 60.832 31.7299 60.9121 31.7107C61.0642 31.6741 61.6147 31.3503 61.512 31.3863ZM62.9381 56.9027C62.8841 56.9313 62.7932 56.93 62.7741 56.9391C62.7294 56.9607 61.737 57.4751 62.0949 57.2361C62.1418 57.2047 63.0483 56.7639 63.5247 56.5342C63.5517 56.5231 63.5701 56.5125 63.5779 56.5084C63.6014 56.5268 63.576 56.5472 63.538 56.5596C63.3721 56.6361 63.177 56.7202 63.1038 56.7601C63.078 56.7743 63.0826 56.8257 62.9384 56.9023C62.9383 56.9024 62.9382 56.9026 62.9381 56.9027ZM39.5417 30.5248C39.5616 30.4856 40.1629 30.1628 40.506 29.9991C40.589 29.9608 40.6497 29.944 40.6521 29.9564C40.6064 29.9769 40.5613 29.9988 40.5169 30.0221C40.1922 30.1895 39.867 30.3571 39.5417 30.5248ZM38.9421 30.8179C38.6798 30.9202 39.2632 30.6189 39.4414 30.5425C39.4542 30.5635 38.9803 30.803 38.9421 30.8179ZM31.1656 40.2736C31.1745 40.4056 31.2277 39.9996 31.2381 40.0904C31.2445 40.1486 31.2246 40.4437 31.2412 40.5378C31.2465 40.5644 31.2965 40.2635 31.2944 40.1765C31.2915 40.0528 31.2521 40.1727 31.2518 40.0378C31.251 39.5898 31.2791 39.1927 31.2784 38.7727C31.2783 38.7348 31.2505 39.0289 31.2509 38.7054C31.2509 38.6555 31.2923 38.3551 31.2862 37.9682C31.1579 37.1136 31.2838 36.4861 31.2376 35.4016C31.2255 35.4425 31.1931 36.2536 31.1919 36.3013C31.1708 37.2078 31.1685 38.8318 31.1682 39.7812C31.1681 40.0249 31.1953 39.9066 31.1963 40.0115C31.197 40.0944 31.1467 39.9958 31.1656 40.2736ZM62.7098 30.8003C62.5854 30.8063 62.242 31.0136 62.0124 31.1255C62.1131 31.1258 62.4816 30.9019 62.7098 30.8003ZM33.6485 33.4218C33.5348 33.4808 33.1732 33.6447 33.1506 33.6729C33.1216 33.7095 33.6395 33.4644 33.6485 33.4218ZM57.2952 59.7088C57.2848 59.7156 57.0082 59.8509 56.9971 59.8547C56.733 59.9417 57.5628 59.536 57.2952 59.7088ZM51.8312 60.8071C51.6196 60.7083 51.4019 60.617 51.3499 60.5454C51.4802 60.6175 51.8684 60.794 51.8312 60.8071ZM42.1093 56.3572C42.1716 56.4 41.2023 56.3353 41.0174 56.3739C41.0798 56.3215 42.065 56.2927 42.1093 56.3572ZM37.8218 31.2431C38.2075 31.0537 38.0902 31.022 38.3506 30.9327C38.3931 30.9183 38.5971 31.0044 38.1465 31.1593C38.0654 31.1872 38.3449 31.0027 37.8218 31.2431ZM31.2547 49.2576C31.2195 49.1483 31.2299 48.8067 31.2328 48.5759C31.259 48.6277 31.2522 49.0934 31.2547 49.2576ZM60.3141 31.9403C60.1116 31.9859 59.2953 32.4355 59.5161 32.3619C59.5474 32.351 60.1964 31.9971 60.3141 31.9403ZM63.7781 54.3061C63.8174 54.6892 63.8295 53.8957 63.7912 53.6452C63.7937 53.7586 63.7756 54.2802 63.7781 54.3061ZM44.9114 57.381C44.8943 57.3743 44.5326 57.1892 44.5173 57.1793C44.2378 56.9938 45.2612 57.5172 44.9114 57.381ZM53.4398 61.3991C53.3462 61.4499 52.7444 61.327 52.6372 61.2326C52.7651 61.2662 53.5467 61.381 53.4398 61.3991ZM36.2507 32.0545C36.5241 31.9158 36.7887 31.7946 37.0468 31.6812C37.006 31.732 36.2888 32.0581 36.2507 32.0545ZM43.3861 56.6713C43.3577 56.6611 43.331 56.6488 43.3038 56.6394C43.3319 56.65 43.3593 56.6607 43.3861 56.6713ZM31.2071 34.7105C31.1764 34.7698 31.2308 34.7689 31.2325 34.7659C31.2577 34.729 31.2457 34.6479 31.2071 34.7105ZM62.4142 30.8654C62.3144 30.865 61.9436 31.0895 61.7165 31.1911C61.7969 31.1906 62.2372 30.9592 62.4142 30.8654ZM31.2158 55.1543C31.1671 55.477 31.1105 54.1639 31.1419 53.8872C31.172 53.8667 31.2225 55.107 31.2158 55.1543ZM63.8456 53.1164C63.8808 53.0906 63.8383 52.5393 63.8216 52.6564C63.8111 52.7306 63.8237 53.1318 63.8456 53.1164ZM31.1624 53.2268C31.1517 53.1035 31.1864 52.8159 31.2076 52.9171C31.2348 53.0471 31.1655 53.2587 31.1624 53.2268ZM31.1342 42.1575C31.1288 42.2115 31.1649 42.9369 31.2009 42.6372C31.2258 42.4293 31.1749 42.3962 31.1748 42.3473C31.1749 42.2927 31.2372 41.1281 31.1342 42.1575ZM31.4963 60.608C31.4691 60.603 31.4417 60.5904 31.416 60.5733C31.3771 60.5475 31.3449 60.5132 31.3158 60.4821C31.3365 60.4866 31.3839 60.5233 31.4289 60.5524C31.4606 60.5739 31.4894 60.5924 31.4963 60.608ZM63.855 55.2427C63.8692 55.1762 63.8778 53.3654 63.834 54.3941C63.8315 54.4541 63.8118 55.4446 63.855 55.2427ZM37.8218 31.2431C37.7731 31.267 37.7164 31.2934 37.65 31.3228C37.715 31.2918 37.7721 31.2659 37.8218 31.2431ZM33.4547 33.4212C33.5317 33.354 33.0829 33.5708 32.9575 33.6487C32.931 33.697 33.4441 33.4305 33.4547 33.4212ZM31.2855 60.502C31.2438 60.4793 31.2109 60.4013 31.1901 60.3517C31.2118 60.3545 31.286 60.4742 31.2855 60.502ZM40.3329 56.601C39.8927 56.6835 39.3867 56.9099 39.3933 56.9416C39.383 56.9412 39.3613 56.9455 39.3267 56.9561C39.3145 56.9599 39.254 56.9882 39.1735 57.0296C39.0636 57.0866 38.9017 57.1715 38.8102 57.21C38.5309 57.3278 38.781 57.1911 39.1581 57C40.2094 56.4425 42.1389 56.2601 39.8752 56.7879C40.024 56.7189 40.1768 56.6564 40.3329 56.601ZM54.2614 61.3363C54.3529 61.3352 54.5344 61.2406 54.5879 61.1933C54.6212 61.1699 54.6292 61.159 54.5945 61.1721C54.5906 61.1736 54.5856 61.1756 54.5798 61.1781C54.502 61.2166 54.1444 61.342 54.2614 61.3363ZM48.6908 59.4096C48.7377 59.4401 49.2038 59.6454 49.2239 59.6345C48.9711 59.4861 48.4774 59.27 48.6908 59.4096ZM55.3909 60.846C55.4978 60.7986 55.6054 60.6807 55.592 60.6846C55.4765 60.719 55.2013 60.9052 55.3909 60.846ZM36.9567 31.5033C36.794 31.5664 36.3172 31.8511 36.2263 31.9389C36.2029 31.9424 36.1446 31.9609 36.0403 32.0003C36.0406 32.0001 36.0409 32 36.0412 31.9998C35.9005 32.0531 31.8898 34.0402 34.6076 32.7624C34.6927 32.7225 34.5627 32.7496 34.9075 32.5838C34.9303 32.5729 34.9539 32.592 35.0243 32.5583C35.1863 32.4806 36.0499 32.0682 36.2119 31.9622C36.2157 31.9661 36.229 31.9649 36.2546 31.9571C36.4834 31.8873 37.0829 31.4543 36.9567 31.5033ZM47.7865 58.9631C47.8734 59.0181 48.1676 59.1543 48.2086 59.1474C48.0702 59.0648 47.5847 58.8354 47.7865 58.9631ZM63.9553 55.1865C63.9754 54.978 63.9378 54.4494 63.9178 54.6092C63.9055 54.7071 63.9322 55.4271 63.9553 55.1865ZM50.6953 60.4029C49.6386 59.8423 50.439 60.2774 50.2591 60.2275C50.4045 60.286 50.5499 60.3445 50.6953 60.4029ZM41.4822 29.5987C41.3584 29.5972 41.5013 29.5149 41.6398 29.5571C41.6821 29.5703 41.5504 29.5996 41.4822 29.5987ZM48.6539 32.8103C48.5364 32.6815 49.2309 33.0699 48.9346 32.9698C48.921 32.9647 48.6633 32.8177 48.6539 32.8103ZM43.2835 30.0965C43.1486 30.0768 43.071 30.0436 42.7495 29.8711C43.2377 30.1018 42.8068 29.8441 43.2835 30.0965ZM39.3995 56.9438C39.3962 56.9434 39.3935 56.9432 39.3933 56.9416C39.3968 56.9417 39.3987 56.9425 39.3995 56.9438ZM56.3916 60.3331C56.5417 60.2985 56.9158 60.1085 56.7877 60.1318C56.7754 60.1342 56.4345 60.2818 56.3916 60.3331ZM36.2263 31.9389C36.247 31.9358 36.2398 31.944 36.2119 31.9622C36.2084 31.9586 36.214 31.9507 36.2263 31.9389ZM54.4658 61.3231C54.4659 61.3019 54.0704 61.4237 54.0529 61.4227C53.8291 61.5219 54.3104 61.4047 54.4658 61.3231ZM63.9932 50.9643C63.9904 50.9313 63.9207 51.1437 63.948 51.274C63.9692 51.3748 64.0039 51.0876 63.9932 50.9643ZM44.3988 30.6347C44.5796 30.7252 44.8343 30.8525 44.8665 30.9055C44.7475 30.8404 44.3842 30.6545 44.3988 30.6347ZM48.3959 32.6305C48.1647 32.5584 47.6765 32.3142 47.3676 32.1526C47.3847 32.1039 48.1899 32.541 48.3959 32.6305ZM37.4558 31.275C37.4401 31.2806 36.9797 31.4938 37.057 31.4934C37.17 31.4931 37.5921 31.2277 37.4558 31.275ZM63.9562 51.949C63.9799 52.1757 64.0524 51.6539 63.9964 51.4146C63.9677 51.2918 63.9523 51.9108 63.9562 51.949ZM57.5845 59.7895C57.8433 59.6379 57.1642 59.938 57.0875 60.0164C57.2121 59.9573 57.4926 59.8433 57.5845 59.7895ZM49.4014 59.8689C50.1986 60.3831 49.8236 59.9847 49.6665 59.9247C49.6444 59.9163 49.3819 59.8564 49.4014 59.8689ZM58.129 32.8022C58.016 32.8747 58.4844 32.6987 58.5267 32.6392C58.5527 32.6022 58.2012 32.7558 58.129 32.8022ZM35.2487 59.0461C35.2841 59.028 35.3193 59.01 35.3541 58.9923C35.3287 59.0069 35.2944 59.0246 35.2487 59.0461ZM60.0759 58.6983C59.4169 58.8647 59.5296 58.9341 59.4778 58.9594C59.3656 59.0137 59.0888 59.108 58.8816 59.2189C59.1149 59.0838 59.3482 58.9488 59.5815 58.8138C59.3867 58.8994 57.7114 59.6772 57.6873 59.7156C57.6529 59.7706 58.1677 59.5013 58.1842 59.4963C58.2079 59.4892 58.331 59.5324 58.3808 59.5115C58.4626 59.477 59.8442 58.7882 60.0759 58.6983ZM51.1724 60.7363C51.0418 60.6586 51.0198 60.6061 50.9529 60.5825C50.9301 60.5745 50.9108 60.6044 50.8334 60.576C50.9464 60.6294 51.0594 60.6829 51.1724 60.7363ZM61.0803 58.0493C61.2678 58.0039 60.5069 58.3661 60.4806 58.3738C60.3385 58.4121 60.9272 58.0864 61.0803 58.0493ZM54.6891 61.2526C54.7177 61.2412 55.3024 60.9639 55.287 60.9447C55.169 60.9887 54.7222 61.205 54.6235 61.2654C54.6073 61.2763 54.6063 61.2809 54.6288 61.2751C54.6422 61.2707 54.6621 61.2633 54.6891 61.2526ZM50.7418 60.5329C50.5403 60.4275 50.1719 60.2035 50.1922 60.2732C50.1925 60.2734 50.1928 60.2735 50.1931 60.2737C50.376 60.3601 50.5589 60.4465 50.7418 60.5329ZM64.0689 52.7252C64.1538 52.304 64.0465 52.5036 64.0191 52.8765C64.0572 52.9895 64.055 52.7943 64.0689 52.7252ZM64.1322 51.3772C64.1475 51.26 64.1307 50.0523 64.0858 50.2366C64.0698 50.3021 64.1101 50.9966 64.107 51.0285C64.1024 51.077 64.0527 50.8555 64.0626 51.2259C64.0794 51.2042 64.1271 51.4173 64.1322 51.3772ZM64.1232 52.3766C64.1878 51.958 64.0687 51.8639 64.0684 52.1787C64.0682 52.3017 64.1139 52.4363 64.1232 52.3766ZM64.1131 54.0864C64.1244 53.9358 64.1409 53.5346 64.1012 53.2581C64.0979 53.6281 64.0945 53.9982 64.0911 54.3683C64.1135 54.411 64.1031 54.2182 64.1131 54.0854C64.1131 54.0858 64.1131 54.0861 64.1131 54.0864ZM50.7823 33.4825C50.4999 33.3035 51.191 33.6346 51.2163 33.6565C51.2901 33.7242 50.9085 33.5625 50.7823 33.4825ZM55.3205 32.9968C55.2257 33.0275 55.152 33.0168 54.9619 33.1171C55.0902 33.0885 55.2181 33.0535 55.3449 33.0122C55.4234 32.9874 55.5018 32.9627 55.5802 32.938C55.6842 32.8058 55.4408 32.951 55.3347 32.9916C55.3296 32.9936 55.3249 32.9954 55.3205 32.9968ZM54.4745 33.0252C54.5011 33.0139 54.3228 32.9523 54.694 32.917C54.8196 32.8988 54.5701 33.0263 54.236 33.1061C53.9033 33.191 53.4932 33.2015 53.3712 33.1703C53.6434 33.1643 54.2406 33.1152 54.4745 33.0252ZM52.2954 32.4595C52.2843 32.4525 52.7191 32.5667 52.7704 32.5757C53.0344 32.6673 52.3446 32.5483 52.2954 32.4595ZM53.715 32.6732C53.502 32.6662 53.9687 32.6194 54.1067 32.5965C54.1254 32.6194 53.7488 32.6794 53.715 32.6732ZM48.5161 30.4835C48.3146 30.2952 48.0275 30.3402 48.4068 30.4918C48.4248 30.499 48.5245 30.492 48.5161 30.4835ZM52.7445 32.4679C52.9413 32.5333 52.4901 32.4521 52.3673 32.3869C52.3614 32.3668 52.7135 32.4632 52.7445 32.4679ZM48.433 30.2334C48.144 30.0259 48.1701 30.2504 48.2059 30.2768C48.3542 30.3846 48.942 30.5955 49.0635 30.6356C48.2207 30.246 48.5691 30.3311 48.433 30.2334ZM46.933 29.6103C46.6324 29.4826 47.3601 29.8896 47.5259 29.9136C47.3799 29.8434 47.0185 29.6466 46.933 29.6103ZM45.1909 28.6715C45.0372 28.5871 44.5783 28.3395 44.4868 28.327C44.6603 28.4077 45.111 28.6658 45.1909 28.6715ZM44.8759 28.4143C44.649 28.2556 44.5376 28.3316 44.8357 28.4415C44.8473 28.4458 44.8839 28.4208 44.8759 28.4143ZM43.4615 27.6709C43.2738 27.5416 43.0002 27.5681 43.3295 27.6931C43.4259 27.7321 43.4808 27.6852 43.4615 27.6709ZM48.1307 29.8547C47.9095 29.7217 47.5765 29.6465 48.0638 29.9002C47.8856 29.8251 47.7075 29.7499 47.5293 29.6748C48.1524 30.0376 48.1559 29.9126 48.3386 30.0092C48.5938 30.1443 48.5317 30.2177 48.4667 30.2181C48.704 30.2727 49.604 30.7216 50.1288 30.9718C49.6826 30.7219 48.9598 30.3139 48.5157 30.0748C48.3889 30.0065 48.2525 29.9669 48.144 29.9095C47.9702 29.8173 48.143 29.8624 48.1316 29.8552C48.1313 29.855 48.131 29.8549 48.1307 29.8547ZM41.0322 27.319C40.3825 27.3634 40.8065 27.4011 41.1629 27.3472C41.1785 27.344 41.0486 27.318 41.0322 27.319ZM52.3189 31.9708C52.5559 32.0906 52.5872 32.1207 52.6906 32.1603C52.7939 32.1896 52.9822 32.2625 53.5405 32.2103C53.0699 32.2752 53.5146 32.2617 53.4227 32.288C53.3472 32.3124 53.0655 32.2702 53.2266 32.3274C53.0037 32.3039 52.1111 32.0281 52.0882 31.9721C52.0886 31.9723 52.089 31.9725 52.0893 31.9726C52.0697 31.9567 52.1708 31.8919 52.3189 31.9708ZM45.3226 28.4023C45.2273 28.1992 45.0668 28.3657 44.8086 28.1077C44.3213 28.0512 45.9477 28.6774 46.0724 28.8977C44.3947 28.0405 47.123 29.5796 46.0414 28.8023C46.976 29.3554 46.3707 28.9376 46.5323 28.9883C46.7052 29.0426 47.2393 29.3445 47.2346 29.2843C47.2343 29.2841 47.234 29.284 47.2337 29.2838C46.8969 29.1195 46.56 28.9551 46.2232 28.7907C46.5013 29.0547 45.8312 28.6822 45.6396 28.4846C45.5339 28.4572 45.4283 28.4298 45.3226 28.4023ZM47.173 29.4448C47.1411 29.426 46.405 29.0754 46.442 29.119C46.533 29.1805 47.5755 29.6826 47.173 29.4448ZM50.3929 31.0274C50.1312 30.8963 49.7362 30.6744 49.5747 30.6407C49.8364 30.7719 50.2315 30.9939 50.3929 31.0274ZM35.7733 29.5126C35.4551 29.7104 36.487 29.2058 36.1715 29.3178C36.156 29.3234 35.789 29.503 35.7733 29.5126ZM44.5542 28.0416C44.2339 27.834 44.3338 28.0351 44.6009 28.1293C44.6164 28.1347 44.569 28.0512 44.5542 28.0416ZM52.7293 32.0897C52.7514 32.0842 53.5009 32.2002 53.6385 32.1642C53.5653 32.233 52.6927 32.1486 52.7293 32.0897ZM50.9091 31.1469C50.4414 30.7799 49.673 30.5496 49.5969 30.5081C49.5212 30.4668 49.6653 30.4807 49.6484 30.4707C49.6096 30.448 48.7868 30.0415 48.7454 30.0249C48.7158 30.0132 48.8315 30.1529 48.6518 30.0888C49.0009 30.2169 50.49 30.9905 50.5715 31.0222C50.6347 31.0465 50.2143 30.7504 50.9082 31.1465C50.9085 31.1466 50.9088 31.1468 50.9091 31.1469ZM49.4103 30.397C49.6016 30.527 49.0248 30.2429 48.8907 30.1631C48.5928 29.9859 49.3856 30.3806 49.4103 30.397ZM48.0398 29.6801C47.9772 29.6411 47.3873 29.3392 47.3216 29.3445C47.5823 29.5245 48.1816 29.769 48.0398 29.6801ZM40.4814 27.1737C40.264 27.2147 39.6783 27.3898 39.66 27.4378C39.8605 27.3396 40.4524 27.2027 40.4814 27.1737ZM55.261 31.3338C54.9941 31.4394 55.582 31.1339 55.7602 31.0582C55.7785 31.0713 55.2838 31.3248 55.261 31.3338ZM44.6244 27.7576C44.5913 27.7372 44.3011 27.5934 43.9392 27.4163C43.1558 26.9953 41.9837 26.8665 41.7464 26.888C41.9817 26.8886 43.1525 27.0382 43.9182 27.4576C44.2659 27.6312 44.5432 27.7673 44.5762 27.7792C44.6021 27.7885 44.6353 27.7647 44.6244 27.7576ZM48.6519 29.756C48.842 29.8019 48.9297 29.9047 48.9509 29.916C49.1587 30.0275 49.6004 30.2372 49.4856 30.2271C49.1212 30.0258 48.2735 29.6644 48.6519 29.756ZM40.2466 27.0255C39.7957 27.1635 40.0085 27.113 40.3036 27.0437C40.5992 26.9741 40.9874 26.9277 40.8672 26.9202C40.8513 26.9137 40.3394 26.9923 40.2466 27.0255ZM44.8378 27.85C44.993 27.8879 46.8393 28.8453 47.1379 28.9946C46.8411 28.9195 46.6478 28.7672 46.287 28.5906C46.1897 28.543 46.2033 28.5803 46.1929 28.5751C46.0245 28.4923 46.1642 28.527 46.0609 28.4748C45.9956 28.4419 44.6195 27.7968 44.8378 27.85ZM48.7628 29.7774C48.8781 29.8069 50.0442 30.3779 50.088 30.4073C50.4152 30.6266 48.8491 29.8304 48.7628 29.7774ZM44.6932 27.7126C44.9273 27.7445 45.8282 28.252 45.179 27.9699C45.1171 27.9427 44.8762 27.7854 44.6932 27.7126ZM40.3275 26.9306C40.2754 26.9171 39.327 27.2346 39.3293 27.2844C39.4477 27.185 40.8495 26.8193 40.3275 26.9306ZM40.8235 26.7535C40.8003 26.7594 41.038 26.7643 40.5732 26.8365C40.5365 26.8487 40.4461 26.7851 39.8811 26.9799C39.7669 27.0206 39.6051 27.12 39.6187 27.1174C40.1939 26.8948 42.0368 26.6136 40.8235 26.7535ZM48.8031 29.75C48.7504 29.6989 48.9308 29.7155 49.052 29.8134C49.1039 29.8554 48.9774 29.8363 48.8031 29.75ZM37.8915 27.9694C38.2563 27.7424 37.0517 28.3364 36.995 28.3761C37.0447 28.379 37.855 27.992 37.8915 27.9694ZM55.7221 30.759C55.7218 30.7591 55.7215 30.7593 55.7212 30.7594C56.0471 30.6065 55.8626 30.7359 55.8781 30.7293C56.5855 30.43 56.37 30.4537 56.4733 30.3922C56.6946 30.2601 56.6984 30.3603 57.0693 30.1325C56.4533 30.5031 57.0263 30.1903 57.059 30.2103C57.1902 30.293 56.1777 30.5816 55.8706 30.7663C55.8278 30.792 56.1755 30.6655 56.0668 30.7333C55.7133 30.9537 54.4715 31.3458 55.7221 30.759ZM49.1596 29.8607C49.3263 29.9005 50.4422 30.5007 50.1275 30.3792C50.0769 30.3597 48.9147 29.8018 49.1596 29.8607ZM40.5261 59.6499C40.5106 59.6612 40.5009 59.6699 40.496 59.6762C40.483 59.6885 40.487 59.6922 40.5033 59.6895C40.5554 59.6865 40.7924 59.607 40.8433 59.5737C40.8772 59.5463 40.5933 59.5958 40.5261 59.6499ZM43.7955 60.3949C44.122 60.5505 44.5259 60.5952 44.1137 60.4135C44.0699 60.3942 43.7671 60.3589 43.7955 60.3949ZM28.0963 53.535C28.046 53.9126 28.1394 53.8901 28.1381 53.6129C28.1376 53.515 28.0979 53.5231 28.0963 53.535ZM36.6493 61.6555C36.6846 61.6415 37.0724 61.4409 37.0486 61.4288C36.8985 61.4895 36.4207 61.7448 36.6493 61.6555ZM28.083 53.4151C28.0998 53.639 28.1673 53.2536 28.1013 52.9799C28.1067 53.1189 28.0812 53.392 28.083 53.4151ZM44.0876 27.1791C44.0795 27.1769 44.0708 27.1743 44.0616 27.1714C43.7914 27.0617 43.1427 26.8061 42.7394 26.7372C42.7099 26.6615 43.7562 26.9853 44.063 27.1678C44.0722 27.172 44.0803 27.1758 44.0876 27.1791ZM42.5181 59.6962C42.7206 59.7466 42.3254 59.5461 42.3456 59.61C42.3509 59.6128 42.5111 59.6929 42.5181 59.6962ZM28.0779 41.3509C28.1075 41.5998 28.1474 40.8096 28.0953 41.0271C28.0932 41.0378 28.0762 41.3373 28.0779 41.3509ZM28.0951 37.9004C28.0851 38.0891 28.0881 38.8943 28.117 38.581C28.1215 38.5323 28.1222 37.9145 28.0951 37.9004ZM56.4763 30.3507C56.3625 30.3506 56.8961 30.0973 56.9757 30.0674C57.007 30.0559 56.6247 30.3507 56.4763 30.3507ZM28.0883 55.9877C28.0947 56.1831 28.0825 56.6899 28.1093 56.7791C28.1038 56.5401 28.1416 55.9234 28.0883 55.9877ZM41.6228 59.4993C41.7981 59.5526 42.0842 59.6039 42.0273 59.5197C41.6948 59.4757 42.0615 59.5725 41.6228 59.4993ZM28.0233 52.1566C28.019 52.3133 28.0886 52.4333 28.0919 52.4157C28.1231 52.2459 28.0504 52.0009 28.0233 52.1566ZM32.8502 63.5516C32.863 63.564 33.0988 63.4859 33.2947 63.383C33.3963 63.3296 33.4836 63.277 33.4503 63.2833C33.4408 63.285 33.3651 63.3181 33.2824 63.3571C33.0801 63.4575 32.8387 63.5414 32.8502 63.5516ZM36.5043 28.4413C36.2863 28.52 36.9031 28.1819 37.1032 28.1172C37.214 28.1128 36.5317 28.4311 36.5043 28.4413ZM28.0407 47.8113C27.9965 47.788 28.0215 48.5731 28.0581 48.2637C28.0672 48.1863 28.0554 47.8195 28.0407 47.8113ZM27.9878 40.2954C28.0404 40.822 28.0777 38.6106 28.0122 39.1917C28.0075 39.2333 27.9833 40.2495 27.9878 40.2954ZM28.0206 36.6839C28.0148 36.7747 27.8665 36.7295 27.9237 36.3534C27.9311 36.3041 27.9703 36.535 27.9793 36.4946C27.9844 36.4709 28.0052 35.6533 28.0018 35.6157C27.9978 35.5752 27.9503 35.6229 27.945 35.5818C27.9398 35.5413 27.971 35.1523 27.9793 34.8788C27.9805 34.8038 27.9835 34.7346 27.987 34.6723C28.0773 33.749 28.1686 33.6572 28.1751 33.5815C28.2526 33.3711 28.4292 33.0356 28.6974 32.6741C29.0095 32.2494 29.4619 31.8379 30.0194 31.559C30.9963 31.0639 32.1242 30.4945 32.8127 30.2221C32.0326 30.5746 31.3196 30.9711 30.5633 31.3617C30.6795 31.2459 30.2249 31.5153 30.048 31.6176C29.9061 31.6968 29.8615 31.7213 30.0451 31.6105C30.0821 31.5862 30.1375 31.5503 30.2147 31.5006C30.1802 31.5201 30.1193 31.5528 30.0372 31.596C29.3244 31.8808 27.9651 33.2383 28.0267 34.8779C28.0299 35.7476 28.0289 36.5476 28.0206 36.6829C28.0206 36.6832 28.0206 36.6835 28.0206 36.6839ZM45.0537 61.0704C44.8323 61.0164 45.8571 61.516 45.9698 61.5069C45.8388 61.4323 45.0809 61.0776 45.0537 61.0704ZM41.2262 59.7494C41.1709 59.7711 41.1391 59.8615 40.8536 59.9087C40.8533 59.9088 40.8531 59.9089 40.8528 59.909C40.7684 59.9258 40.8501 59.8684 40.8327 59.8659C40.8267 59.8614 40.5543 59.9268 40.762 59.8285C41.0878 59.6981 40.8169 59.8831 40.9909 59.8279C41.0083 59.8153 41.3387 59.698 41.3202 59.6944C41.3177 59.6927 41.2145 59.719 41.1966 59.7179C41.1282 59.712 41.1536 59.676 41.1442 59.6762C41.1164 59.6727 40.7673 59.8011 40.5997 59.8837C40.5251 59.9181 40.4665 59.9416 40.4363 59.9466C40.4256 59.9484 40.4858 59.9137 40.5875 59.858C40.7839 59.7153 41.3677 59.5823 41.3996 59.602C41.4234 59.6051 41.4198 59.6913 41.4435 59.6982C41.4543 59.6943 41.8239 59.6712 41.8709 59.6941C41.8844 59.6982 41.8946 59.7022 41.902 59.7054C41.8507 59.6662 42.1819 59.7355 42.1617 59.767C42.1537 59.774 41.9329 59.7177 41.9243 59.7172C41.9209 59.7158 41.918 59.7141 41.9153 59.7128C41.9569 59.7224 41.1942 59.7246 41.3644 59.776C41.1528 59.8297 41.3863 59.6998 41.2262 59.7494ZM39.9295 60.353C39.9636 60.3258 39.9978 60.2987 40.0319 60.2715C39.3947 60.6149 38.6285 60.9495 37.8832 61.3227C37.694 61.4173 37.9363 61.3578 37.6816 61.4683C37.4776 61.5569 37.2349 61.621 37.3378 61.5568C37.3628 61.5411 37.7821 61.3686 37.983 61.2644C38.576 60.9564 38.4039 60.9896 38.4383 60.971C38.4762 60.9505 38.8672 60.7922 39.0719 60.6881C39.5866 60.4264 39.8095 60.2825 40.532 59.9636C40.1388 60.1951 40.3921 60.1442 39.9295 60.353ZM27.9068 44.4954C27.877 44.4679 27.9034 43.9944 27.8991 43.8224C27.9289 43.8494 27.9024 44.3232 27.9068 44.4954ZM67.1631 42.3401C67.1142 42.1947 67.1021 43.2847 67.1428 42.9974C67.1518 42.9339 67.1627 42.4771 67.1631 42.3401ZM67.1333 47.2369C67.1468 47.3827 67.182 46.7956 67.1442 46.7967C67.1321 46.7975 67.1316 47.2181 67.1333 47.2369ZM29.5852 63.3501C29.5278 63.3381 28.9395 62.8323 28.9378 62.7998C28.7436 62.5517 29.315 63.1627 29.681 63.3721C29.8857 63.5021 29.9716 63.5632 29.6652 63.3976C29.6408 63.3837 29.6142 63.3679 29.5852 63.3501ZM67.1935 53.1898C67.1615 52.6815 67.1476 54.2113 67.1884 53.7439C67.1904 53.7206 67.1951 53.2142 67.1935 53.1898ZM67.2024 55.3161C67.2007 55.1942 67.2166 54.6532 67.2017 54.6461C67.1777 54.6353 67.1612 55.2546 67.2024 55.3161ZM27.8387 52.0508C27.7836 52.1095 27.8253 51.3961 27.8184 51.1481C27.8735 51.0892 27.8317 51.8029 27.8387 52.0508ZM27.7981 56.5539C27.7546 53.5463 27.8723 54.2093 27.8249 56.733C27.7895 56.7367 27.8008 56.7437 27.7981 56.5539ZM27.8046 52.7026C27.8399 52.8119 27.8294 53.1534 27.8266 53.3842C27.802 53.3427 27.8109 52.869 27.8046 52.7026ZM67.2387 41.0422C67.2833 41.2308 67.2283 42.0661 67.2099 41.9176C67.206 41.883 67.2142 40.9729 67.2387 41.0422ZM29.1652 63.0943C29.2025 63.1588 28.8714 62.9073 28.5992 62.5525C28.3192 62.2034 28.1262 61.7599 28.1074 61.6952C28.0301 61.4307 28.1578 61.8205 28.4214 62.2356C28.6765 62.6579 29.1047 63.0567 29.1652 63.0943ZM27.7915 47.782C27.7496 47.6225 27.7712 47.1696 27.7717 46.8782C27.8076 47.0109 27.7923 47.5348 27.7915 47.782ZM27.7587 49.885C27.7571 49.8667 27.7608 49.4604 27.7628 49.4423C27.8037 49.1094 27.7933 50.2587 27.7587 49.885ZM55.0956 30.6219C55.1071 30.6146 55.3835 30.4794 55.3938 30.476C55.6575 30.3892 54.8278 30.7949 55.0956 30.6219Z\" fill=\"white\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><strong>+60 km<\/strong> <span class=\"custom-title\">of off-road routes<\/span><br \/>\nExclusive routes through natural landscapes.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_c7758dd6 counter-box has_text_color iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:4.8rem;\"><svg width=\"96\" height=\"92\" viewBox=\"0 0 96 92\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect width=\"95.0207\" height=\"91.0615\" rx=\"7.91839\" fill=\"#1F1549\"\/>\n<path d=\"M42.7059 38.2848C42.7491 38.3601 42.8942 38.6776 42.9636 38.8117C42.8396 38.6824 42.5497 38.0132 42.7059 38.2848ZM52.2677 36.1004C52.1884 36.1983 52.1091 36.2961 52.0298 36.394C52.2875 36.1483 52.6191 35.8031 52.8616 35.5782C52.9013 35.5415 52.829 35.6675 52.9206 35.5783C53.0123 35.4891 52.9581 35.4698 53.0857 35.3343C53.2289 35.1825 53.9301 34.5325 54.1634 34.2979C54.8087 33.649 55.4479 32.9858 56.098 32.336C57.1658 31.2117 58.6532 31.6059 59.1812 33.0638C59.2835 33.3709 59.3838 33.6785 59.4806 33.9867C59.0393 32.7845 59.4101 34.0206 59.5393 34.3554C59.5681 34.4296 59.6557 34.387 60.0388 35.6131C60.2822 36.3923 59.9129 35.7208 60.4092 36.991C60.1696 35.9669 60.4889 36.9461 60.7516 37.7239C60.7969 37.858 61.1446 38.947 61.3083 39.4247C61.3643 39.5881 61.4955 39.8218 61.5693 40.0387C61.62 40.1881 61.6314 40.31 61.7068 40.5317C62.0579 41.5653 62.3995 42.5831 62.7364 43.6235C62.411 43.0583 62.8425 44.1168 62.8528 44.1674C62.9017 44.4257 62.5195 43.3111 62.6459 43.7601C62.8557 44.3767 63.0654 44.9932 63.2752 45.6097C63.1213 45.0976 63.6028 46.2463 63.6347 46.4767C63.7119 46.3449 64.4785 49.324 64.6626 49.755C64.701 49.8448 64.5535 49.2226 64.996 50.6324C65.0439 50.7851 64.9919 50.7386 65.0215 50.8172C65.0392 50.8643 65.2399 51.118 65.2846 51.4447C65.301 51.564 64.9929 50.8686 65.5463 52.4367C65.4433 51.7731 66.3329 54.6046 66.4789 55.1314C66.4587 55.0232 66.4385 54.9149 66.4183 54.8067C66.5504 55.3315 66.6174 55.4119 66.6539 55.5279C66.8009 55.9953 66.9774 56.6465 67.1251 57.0784C67.2978 57.5839 67.3646 57.5635 67.5357 58.1628C67.5036 58.0178 67.4715 57.8728 67.4394 57.7277C67.5718 58.1369 67.7043 58.546 67.8368 58.9552C67.4343 58.0396 67.9005 59.1604 67.9277 59.2354C67.9711 59.355 67.8774 59.1936 67.9492 59.3939C67.9569 59.4146 67.9806 59.3731 68.088 59.683C68.3125 60.3304 68.2358 60.2418 68.3273 60.5145C68.3358 60.5395 68.3371 60.4418 68.5014 60.9107C69.0237 62.4012 68.4756 60.9111 68.4522 60.855C68.4215 60.7813 68.4656 61.3374 68.0865 60.0498C68.2146 60.4819 68.1727 60.5436 68.1873 60.5922C68.2004 60.6352 68.4551 61.3728 68.4706 61.413C68.611 61.7706 68.5427 61.4375 68.5732 61.5061C68.5981 61.5623 68.8454 62.4709 69.0306 62.6415C69.0358 62.7081 69.0357 62.7512 69.0311 62.7738C69.4968 64.0531 68.6736 65.1208 67.3126 65.158C67.2922 65.1462 67.2934 65.1366 67.3126 65.1287C68.6516 65.0921 69.4615 64.0417 69.0033 62.7831C68.9379 62.7072 68.7777 62.2213 68.597 61.718C68.5403 61.6209 68.781 62.4139 68.7948 62.4552C68.8455 62.6071 68.8864 62.723 68.9196 62.811C69.3551 64.0073 68.5853 65.0057 67.3126 65.0405C66.7799 65.0618 67.1777 65.1362 66.9791 65.1864C66.8564 65.2173 66.421 65.1543 66.8229 65.2372C65.8531 65.2459 66.4413 65.1979 66.3786 65.1908C66.2841 65.1803 65.9448 65.2041 65.9023 65.2009C65.8399 65.1962 66.0567 65.1675 65.8108 65.1574C65.77 65.1559 65.3739 65.2053 65.8846 65.2289C65.2023 65.2219 65.2585 65.264 65.027 65.1792C64.5571 65.3397 64.686 65.0842 64.5009 65.0752C64.0088 65.0515 64.1516 65.1776 64.1256 65.1837C63.9465 65.2231 62.5842 65.1798 62.2468 65.198C62.3799 65.1072 63.3268 65.197 63.5386 65.1794C64.2444 65.1208 62.5437 65.134 63.0563 65.0199C62.8414 65.0512 62.6264 65.0826 62.4115 65.1139C62.0174 65.0406 62.5765 65.0086 61.516 65.0354C61.3425 65.0987 62.2658 65.0254 62.0806 65.0752C61.9714 65.1045 61.3564 65.1108 61.3443 65.1262C61.3322 65.1448 61.888 65.1228 61.8004 65.1514C61.6091 65.213 59.5819 65.1543 61.1251 65.1207C60.6947 65.1217 60.4729 64.9991 60.0997 65.0373C59.8583 65.0621 61.2162 65.2315 59.179 65.2004C59.1356 65.1425 59.9935 65.1833 60.0157 65.1789C60.047 65.1725 59.8918 65.0418 59.8649 65.0354C59.77 65.0141 57.6895 65.0841 57.25 65.0185C57.424 65.094 55.6779 65.0319 55.4877 65.0549C55.4371 65.0613 55.6263 65.1076 55.5722 65.1125C55.2346 65.1416 54.3213 65.059 53.8977 65.0569C53.4235 65.0545 53.4836 65.0944 53.4571 65.0943C53.2485 65.0921 53.4152 65.065 53.2876 65.0651C53.095 65.0652 51.771 65.0597 51.7045 65.0653C51.6851 65.0671 51.9012 65.1127 51.6125 65.1214C51.5625 65.1229 51.5943 65.0688 50.7395 65.0922C49.71 65.1203 51.4543 65.1595 51.0266 65.2161C50.3653 65.1354 50.3868 65.2154 50.2075 65.2091C50.1454 65.2068 49.6833 65.1388 49.1815 65.1431C49.5416 65.1321 49.9018 65.1211 50.262 65.11C49.9079 65.0981 49.2203 65.1129 48.9286 65.0994C48.7863 65.0929 48.9036 65.037 48.5944 65.0385C48.5288 65.0391 48.2685 65.1752 49.0783 65.1141C49.143 65.1627 48.7577 65.1311 48.5789 65.1448C48.5519 65.147 48.4453 65.2281 48.217 65.1777C48.1622 65.1653 48.7589 64.9285 47.2198 65.0999C47.1703 65.1054 47.3426 65.1351 47.2941 65.1412C47.261 65.1454 46.8681 65.1334 46.8247 65.1376C46.7803 65.1421 46.9701 65.1745 46.9172 65.1808C46.6462 65.2137 46.2905 65.0853 46.8493 65.0951C46.6625 65.0792 46.4758 65.0633 46.289 65.0475C46.4889 65.1442 45.9956 65.0747 45.7372 65.0777C44.081 65.0967 45.19 65.1596 44.9053 65.1922C44.4473 65.2445 44.7971 65.0789 44.1172 65.1286C44.0543 65.1333 44.8762 65.2036 43.2714 65.1639C43.5082 65.1612 43.7451 65.1585 43.982 65.1557C43.8454 65.0621 43.1267 65.1621 43.0714 65.1634C42.4413 65.1763 42.8673 65.1426 41.9315 65.1908C41.848 65.1951 41.6659 65.172 41.4873 65.1835C40.7465 65.231 42.4647 65.2123 42.5116 65.2502C42.5339 65.2688 40.6861 65.2641 40.6227 65.2553C40.3534 65.2162 41.4603 65.2381 41.2493 65.1895C41.1723 65.1723 38.5388 65.2077 38.0104 65.1888C37.4007 65.1669 37.1262 65.04 37.1223 65.1825C36.9503 65.0426 36.7983 65.1381 36.7203 65.1371C35.7774 65.1241 35.7757 65.1227 34.9671 65.1361C34.7886 65.1391 34.6378 65.0966 34.5747 65.1038C34.538 65.1081 34.6066 65.1535 34.4266 65.1676C34.1765 65.1867 32.6734 65.14 32.5617 65.1149C32.45 65.0898 33.1965 65.104 33.0627 65.0627C32.5224 65.0585 32.0042 65.0687 31.4603 65.0644C31.2344 65.0624 31.3505 65.0335 31.2529 65.033C31.2113 65.0326 30.4312 65.0581 30.4643 65.0687C30.5417 65.0935 32.9507 65.0768 32.3163 65.1274C32.1939 65.1372 31.7615 65.0706 31.8303 65.1516C30.4604 65.1399 29.0906 65.1282 27.7207 65.1165C26.3909 65.1529 25.6556 64.06 26.0416 62.7869C26.2953 62.0469 26.549 61.3068 26.8028 60.5668C26.602 61.2845 26.3439 62.0424 26.0822 62.8004C25.7055 64.0427 26.423 65.1093 27.7207 65.0738C28.2509 65.0795 28.7816 65.0867 29.2971 65.0844C29.4746 65.0837 30.0748 65.0915 30.0018 65.0506C29.3002 65.0438 28.4899 65.05 27.7207 65.0485C26.442 65.0835 25.7349 64.0326 26.1061 62.8084C26.2455 62.3929 26.3831 61.9908 26.5137 61.6297C26.5252 61.5979 26.5208 61.7274 26.5664 61.609C26.6517 61.3876 26.8394 60.6369 26.895 60.5186C26.9054 60.4987 26.8125 60.9306 26.884 60.8137C27.0674 60.5135 26.9288 60.3756 27.0239 60.0967C27.0976 59.881 27.6622 58.4549 27.7321 58.0762C27.8062 57.6734 27.3437 59.1364 27.3353 59.0141C27.6191 58.0145 27.999 57.0332 28.3036 56.1009C28.309 56.0844 28.2268 56.2152 28.2912 56.006C28.4032 55.6419 28.484 55.5634 28.5505 55.3902C28.622 55.2033 28.8386 54.5303 28.8864 54.4466C28.8926 54.4359 28.896 54.5881 28.8905 54.6091C28.8133 54.908 28.7154 54.9907 28.7057 55.017C28.67 55.1161 28.6615 55.2223 28.6297 55.3129C28.5773 55.4621 28.5273 55.5372 28.4593 55.7346C28.4124 55.8707 28.4994 55.7532 28.4535 55.8843C28.4365 55.9323 28.1644 56.4208 28.2486 56.5029C28.2752 56.5286 29.737 52.2787 29.8537 51.8441C29.7198 52.2056 29.5859 52.5671 29.452 52.9286C29.7288 52.1961 29.9458 51.2777 30.0856 51.2541C31.0128 48.5046 31.9401 45.7552 32.8674 43.0058C33.0413 42.5176 33.0277 42.8126 33.2751 41.9965C33.1811 42.1974 33.0872 42.3982 32.9932 42.5991C33.1484 42.1903 33.7939 40.3649 33.8773 40.0624C33.888 40.0232 33.8368 39.9468 33.9838 39.4859C34.1143 39.0769 34.1879 39.0287 34.2704 38.8143C34.3395 38.6343 34.3943 38.4245 34.4153 38.3712C34.4314 38.3303 34.4685 38.3244 34.5074 38.2261C34.6299 37.9156 34.4554 38.1422 34.6623 37.8624C34.6407 37.9401 34.6192 38.0178 34.5976 38.0955C34.7396 37.7189 34.9598 37.213 34.7953 37.7827C34.7671 37.8807 34.7641 37.7875 34.7402 37.8596C33.805 40.684 34.6158 38.45 34.898 37.445C35.028 37.2061 35.4749 35.7731 35.4996 35.7288C35.5345 35.6673 35.4895 35.923 35.6272 35.6141C35.6563 35.5491 36.2654 33.6371 36.0972 34.3426C36.0624 34.4882 35.7452 35.3965 35.6736 35.6172C35.9423 35.1315 36.2091 33.8722 36.2581 33.7369C36.4565 33.1914 35.9889 34.8221 36.4134 33.5858C36.7398 32.6351 36.3772 33.5089 36.4721 33.1331C36.5254 32.9219 36.9558 31.8663 36.8545 31.8651C36.9682 31.4915 36.9444 31.7244 36.9631 31.6798C36.9811 31.6362 37.1964 30.8988 37.2945 30.6688C37.3065 30.6409 37.324 30.7471 37.3377 30.7187C37.3636 30.6633 37.5882 29.9578 37.5936 29.9282C37.5968 29.9093 37.4993 30.0629 37.5122 29.9907C37.5272 29.9066 37.7623 29.234 37.7628 29.1928C37.7624 29.1341 37.4961 29.9724 37.4959 29.8179C37.6358 29.4372 37.8136 28.8002 37.8607 28.5339C37.8507 28.5997 37.7279 28.9731 37.681 29.1013C37.6331 29.0176 37.9009 28.2172 37.8637 28.509C37.8927 28.3253 37.8377 28.439 37.843 28.3319C37.8446 28.3039 37.9256 28.0562 37.9296 28.0046C37.9294 27.9976 37.8186 28.2441 37.8218 28.1884C37.8275 28.0876 38.083 27.3399 38.11 27.2808C38.1862 27.1144 38.005 27.733 38.0168 27.7936C38.0188 27.8023 38.2485 27.3013 38.2561 27.2951C38.3196 27.2825 38.0883 27.848 38.1585 27.7979C38.2163 27.6583 38.2742 27.5186 38.332 27.379C38.1968 27.947 37.8315 28.9593 37.7992 29.241C38.0554 28.4175 38.3427 27.5621 38.4669 27.6055C38.5193 27.6236 38.4325 27.9867 38.4504 27.9775C38.5156 27.9414 38.6269 27.4342 38.6355 27.417C38.6433 27.4031 38.6485 27.3973 38.6512 27.3982C38.6512 27.3982 38.6512 27.3982 38.6512 27.3982C38.6792 27.4075 38.4666 28.1126 38.4677 28.1518C38.4708 28.2181 38.6679 27.9385 38.6885 27.9459C38.689 27.9581 38.5453 28.4628 38.6374 28.307C38.7304 28.1494 38.8763 27.7143 38.8852 27.7003C38.9347 27.6245 38.7008 28.3925 38.7061 28.4195C38.7086 28.4336 38.8849 28.0381 38.9004 28.03C38.9153 28.0237 38.8369 28.3428 38.8325 28.4774C38.8291 28.5777 38.9385 28.3188 38.9271 28.3669C38.9188 28.4013 38.6785 29.1206 38.6715 29.1575C38.661 29.2125 38.7495 29.0548 38.7494 29.0821C38.7494 29.1207 38.6603 29.3491 38.6824 29.3229C38.6988 29.3031 39.1105 28.4396 39.1384 28.4554C39.1857 28.4826 38.7509 29.3975 39.2472 28.5768C39.2506 28.571 39.3083 28.3502 39.3116 28.3446C39.3929 28.2236 39.2188 28.935 39.4911 28.0849C39.0301 29.6815 39.5021 28.3064 39.5099 28.568C39.5128 28.6689 39.3228 29.2841 39.3268 29.2886C39.3883 29.2432 39.4208 29.0378 39.4633 28.9785C39.4868 28.9459 39.3488 29.507 39.4184 29.3935C39.4544 29.3349 39.6424 28.7532 39.6533 28.7302C39.7569 28.5097 39.6924 28.8009 39.7284 28.7569C39.7525 28.7277 39.8702 28.3781 39.8756 28.3697C39.8853 28.3566 39.7792 28.8492 39.7645 28.9543C39.7536 29.0343 39.8698 28.7592 39.8585 28.8138C39.7899 29.1424 39.4716 29.7842 39.8194 29.1795C39.8407 29.1426 39.9192 28.8961 39.9232 28.8895C40.011 28.7503 39.8637 29.2031 39.8673 29.2941C39.8737 29.4504 40.0608 28.7913 39.9178 29.3436C40.0872 28.95 40.161 28.7238 40.3094 28.2467C39.8987 29.5679 39.8805 30.0766 40.3628 28.6184C40.2062 29.0812 40.3002 29.0554 40.2555 29.1941C40.2275 29.2803 39.9271 29.9269 40.2013 29.6759C40.2356 29.6444 40.3445 29.2271 40.3457 29.3696C40.0079 30.3456 40.3667 29.3996 40.3728 29.4006C40.4696 29.4469 39.5889 31.8134 39.4633 32.2286C39.3175 32.7104 39.2557 33.1612 39.2212 33.265C39.1075 33.6064 39.1615 33.3096 39.1212 33.381C39.0807 33.4534 38.8345 34.45 38.8141 34.497C38.7344 34.6794 38.7501 34.4726 38.7411 34.4913C38.6342 34.7144 38.2371 36.0306 38.1043 36.3919C38.1391 36.3909 38.3859 35.659 38.2833 36.1331C38.1639 36.6853 38.0167 36.6701 38.006 36.6821C37.1937 39.1236 36.3813 41.5651 35.5689 44.0066C35.6519 44.0005 36.1289 42.3862 36.1506 42.3531C36.2785 42.1588 35.3788 44.8545 35.2428 45.1766C35.3423 44.9306 35.4418 44.6846 35.5413 44.4387C35.482 44.8956 35.0567 45.8087 34.8869 46.4416C34.832 46.646 34.9927 46.2719 34.9922 46.2806C34.9497 46.5167 34.8041 46.8699 34.8505 46.585C34.709 47.149 34.6896 47.0532 34.5455 47.4741C34.5381 47.4958 34.6323 47.3259 34.535 47.6645C34.4894 47.8231 34.2113 48.6577 34.2037 48.7792C34.2008 48.8294 34.473 48.4497 34.3776 48.3599C34.7352 47.4706 34.4228 48.0527 34.543 47.7009C34.5616 47.6471 34.5831 47.7925 34.8495 46.8946C34.9067 47.1016 34.4809 48.0958 34.4362 48.2757C34.344 48.6466 34.8992 47.1766 34.9018 46.8737C34.9478 47.031 34.9489 46.7721 35.0633 46.4412C35.1884 46.0791 35.162 46.2463 35.2277 46.0496C35.4076 45.512 35.2707 45.7141 35.4749 45.2895C35.1562 45.6636 35.7049 44.5228 35.8664 44.1908C35.6869 44.7587 35.5075 45.3265 35.3281 45.8943C35.348 45.8651 35.368 45.8359 35.3879 45.8066C35.337 45.955 35.2861 46.1033 35.2352 46.2517C35.2344 46.2249 35.2335 46.1981 35.2327 46.1714C35.0341 46.9576 34.9075 47.1234 34.8859 47.1857C34.61 47.9886 34.3005 48.919 34.0289 49.7332C33.9881 49.8553 34.0732 49.7905 33.7317 50.666C33.6228 50.9453 33.6677 50.6623 33.567 50.9865C33.5536 51.4294 33.4598 51.3897 33.4197 51.5094C33.3052 51.853 33.2651 52.0729 33.2549 52.1048C33.118 52.5308 32.9058 53.1509 32.7548 53.6187C32.7524 53.6276 32.8704 53.3973 32.7584 53.6966C32.719 53.8016 32.2426 54.7029 32.0162 55.5541C32.0992 55.3407 32.1822 55.1274 32.2652 54.914C32.1652 55.1641 31.6094 56.9648 31.7975 56.5419C31.9127 56.2826 32.0286 55.5945 32.1507 55.5555C31.9231 56.1405 30.8721 59.44 30.764 59.6881C30.749 59.7224 30.7897 59.4942 30.7693 59.5417C30.7536 59.5785 30.5103 60.3334 30.4648 60.4292C30.4377 60.4863 30.529 60.1473 30.5085 60.1705C30.4924 60.1914 30.1655 61.1265 30.1876 61.1935C30.2485 60.9574 30.4787 60.3135 30.399 60.6649C30.3886 60.71 30.2872 60.9281 30.2748 60.9831C30.1594 61.4925 30.6389 60.0148 30.7153 59.7869C30.4576 60.7296 29.9203 62.1415 29.596 63.2252C29.4182 63.6476 29.7593 62.5657 29.5683 63.0469C29.1721 64.0453 29.524 63.3329 29.5177 63.366C29.4967 63.4751 29.4046 63.6761 29.3135 63.8775L27.7207 61.6677C28.0325 61.7 28.3446 61.7302 28.3449 61.6456C28.7337 61.6673 28.6078 61.6855 29.1565 61.6666C29.0843 61.6567 29.0121 61.6467 28.94 61.6367C29.5491 61.5531 30.8384 61.7639 30.7418 61.78C30.4819 61.823 29.8105 61.7559 29.7532 61.7575C29.6683 61.7599 29.4337 61.9062 28.5048 61.7754C28.1244 61.8735 29.977 61.8416 29.134 61.9085C29.7034 61.8976 32.0455 61.9659 32.3826 61.9228C32.4228 61.9172 32.2355 61.8194 32.8141 61.8691C33.0888 61.8929 32.4264 61.894 32.5521 61.9163C32.9389 61.9847 38.1992 61.9409 39.1984 61.9373C39.2632 61.9372 39.2394 61.9675 39.3032 61.9673C39.4989 61.9664 40.2124 61.9212 40.5628 61.9351C39.8369 61.8789 41.2468 61.8746 41.6054 61.8807C42.1498 61.8902 42.1161 61.9436 42.3513 61.9549C43.2576 61.9987 44.662 61.8719 45.3662 61.9905C45.3276 61.8728 46.5841 62.0482 47.1557 62.0492C47.6034 62.05 48.2529 61.9722 47.6486 61.9247C48.4214 61.9301 49.235 61.9082 49.9599 61.901C50.0798 61.8998 49.9148 61.9346 50.1193 61.9315C50.1378 61.931 50.1634 61.8969 50.339 61.8933C51.7884 61.8636 51.0831 61.9361 51.3543 61.9574C51.5061 61.9693 51.618 61.9752 51.7002 61.9772C50.8554 61.9838 49.881 61.9972 49.6204 61.9982C49.8427 62.0735 51.4929 61.9837 51.9761 62.004C51.9929 62.0047 51.9345 62.0462 51.9515 62.0465C51.9519 62.0465 51.9522 62.0465 51.9526 62.0465C52.1337 62.0497 53.2872 62.0344 53.0497 61.9849C52.986 61.9717 52.455 61.9717 51.8253 61.9762C51.9958 61.9669 51.8685 61.9204 51.8986 61.9184C52.2633 61.8955 53.1567 61.9408 53.4737 61.947C53.5461 61.9483 53.5409 61.9185 53.5528 61.9184C53.8411 61.9252 53.7228 62.0103 54.0185 61.9226C54.5405 62.0286 53.0402 61.9383 53.1459 62.0071C53.2271 62.0601 56.5595 62.0317 56.5496 61.9482C56.561 61.9571 56.6069 61.9682 56.7009 61.9808C56.9093 62.0088 57.8368 62 57.9969 61.9847C58.0239 61.9816 58.0131 61.9006 58.0466 61.8998C58.1304 61.898 59.264 61.9615 59.6874 61.9136C59.4588 61.9023 59.2301 61.8909 59.0015 61.8795C60.3823 61.8788 60.1689 61.8547 59.7088 61.8305C59.6858 61.8303 59.6634 61.8272 59.6415 61.8269C59.2849 61.8089 58.8277 61.7917 58.8208 61.7853C58.7946 61.7609 61.1373 61.7473 60.6867 61.8225C60.6239 61.8328 59.54 61.7993 60.0767 61.853C60.1706 61.8624 60.8667 61.847 60.9032 61.853C61.1479 61.8923 59.6278 61.9445 59.8136 62.0004C60.1825 61.9472 60.656 61.9752 61.0791 61.9615C61.2717 61.9553 61.319 61.9146 61.3427 61.9139C61.6977 61.9032 61.4985 61.9459 61.617 61.9448C61.6806 61.9441 62.3801 61.8534 62.2479 61.9784C64.5528 61.8864 62.8855 61.8865 61.4716 61.8936C61.9183 61.848 62.7942 61.8701 63.1873 61.8595C63.3283 61.8556 63.2447 61.8139 63.483 61.8056C63.9733 61.7884 66.3141 61.8363 66.924 61.8476C66.5495 61.8624 66.659 61.9078 66.9481 61.9047C67.2372 61.9015 66.9943 61.8409 67.0507 61.8344C67.0662 61.8326 67.1672 61.8332 67.3126 61.8349L65.8785 63.8246C65.7502 63.424 65.5133 62.668 65.4547 62.5107C65.7985 63.4725 65.7686 63.2396 65.499 62.4159C65.551 62.5307 65.603 62.6454 65.655 62.7601C65.477 62.284 65.2048 61.2489 65.0924 60.9768C65.0747 60.9342 65.0909 61.1032 65.081 61.0793C64.9842 60.84 64.7439 59.9964 64.7187 59.9618C64.6975 59.9325 64.7854 60.2972 64.7266 60.1705C64.7143 60.1441 64.6492 59.786 64.525 59.4533C64.4789 59.3298 64.4698 59.4164 64.4573 59.3856C64.3535 59.1288 64.4626 59.2644 64.2936 58.7882C64.1697 58.4393 64.0262 58.1964 63.8831 57.7049C64.3425 59.3224 63.926 57.9727 63.6821 57.3137C63.6431 57.208 63.6115 57.3202 63.429 56.6721C63.9939 57.9926 63.3593 56.2652 63.2415 55.9079C63.2354 55.8881 63.2741 55.8678 63.2164 55.6925C63.2114 55.6777 63.1908 55.7082 63.1345 55.5462C62.6001 54.0098 62.9603 54.986 62.8898 54.6838C62.8598 54.5551 62.5706 53.8177 62.5023 53.6159C62.4867 53.5695 62.5225 53.5813 62.4615 53.4019C62.3534 53.0844 62.2278 52.8096 62.1554 52.6005C62.1471 52.576 62.1921 52.5599 62.0447 52.1668C62.0033 52.0562 61.9453 51.936 61.9852 52.0992C62.1181 52.6406 62.5256 53.6157 62.6814 54.2258C62.8235 54.782 62.2488 53.0702 62.2188 52.9812C62.2078 52.9485 62.3418 53.2756 62.233 52.9342C62.1399 52.6427 61.8848 52.1383 61.7577 51.7C61.7479 51.6666 61.6991 51.2989 61.7083 51.3135C61.7159 51.327 61.9073 51.853 61.9008 51.7695C61.8999 51.7596 61.787 51.4224 61.7867 51.3736C61.7861 51.3139 61.9085 51.1115 61.8888 51.0381C61.8378 50.8497 61.8389 50.983 61.8017 50.8625C61.722 50.6042 61.4761 49.698 61.4072 49.6888C61.4526 49.8369 61.4981 49.985 61.5436 50.1331C61.265 49.3176 61.3559 49.6745 61.3062 49.5624C61.2526 49.4417 61.3164 49.4594 61.2294 49.1822C61.2105 49.1219 60.8153 47.9725 60.8005 48.0008C61.0478 48.6268 60.9046 48.4119 60.9133 48.4417C60.9463 48.5548 61.03 48.6854 61.0792 48.8355C61.4249 49.8916 61.0136 48.8474 61.0819 49.1012C61.1055 49.1885 61.1932 49.3489 61.2038 49.3857C61.238 49.5056 61.1983 49.5209 61.2279 49.5986C61.2967 49.78 61.2823 49.5463 61.2901 49.5599C61.3806 49.7122 61.5507 50.3708 61.355 49.9908C61.4128 50.2388 61.4977 50.2418 61.5311 50.4427C61.5978 50.8419 61.4237 50.2685 61.3625 50.1179C61.1426 49.5776 61.117 49.4041 60.8465 48.6257C60.7491 48.3453 60.6013 48.0241 60.5558 47.8941C60.5271 47.8122 60.3957 46.9928 60.1884 47.0365C60.107 46.7281 60.0807 46.2104 59.971 45.9013C59.8724 45.6237 59.8313 45.7361 59.8199 45.711C59.8023 45.6724 59.6953 45.3328 59.6472 45.2219C59.5908 45.0919 59.5861 45.1677 59.5043 44.959C59.3008 44.4394 59.3775 44.4293 59.3641 44.3734C59.208 43.7245 59.1975 44.0349 59.1426 43.8977C59.0917 43.7701 58.5225 41.9311 58.3685 41.5554C58.4351 41.707 58.5016 41.8586 58.5682 42.0101C58.5199 41.7153 58.3476 41.443 58.4265 41.4109C58.2774 41.3975 58.1719 40.7909 58.1107 40.6185C58.0865 40.5505 58.0661 40.5633 58.0366 40.478C57.9213 40.1449 57.6876 39.3852 57.6159 39.2076C57.3061 38.4394 57.894 40.4718 57.9418 40.6314C57.8378 40.3148 57.2126 38.5364 57.424 39.3792C57.4567 39.5095 57.59 39.7152 57.6161 39.7858C57.7921 40.2638 57.6133 39.9013 57.6209 39.9409C57.6343 40.0079 57.7908 40.309 57.8127 40.3948C57.8201 40.4235 57.7128 40.259 57.8653 40.72C57.744 40.5087 57.3498 39.2016 57.2824 39.0353C57.2584 38.9761 57.2868 39.388 57.0127 38.2483C57.0078 38.2642 57.003 38.2801 56.9982 38.2959C56.7888 37.6802 56.5794 37.0645 56.37 36.4488C56.4133 36.5089 56.5709 36.8413 56.4165 36.408C56.3276 36.1585 56.3429 36.3599 56.3339 36.3375C56.2925 36.2334 55.9794 35.2933 55.6322 34.2468L58.7432 34.9812C57.8653 35.8568 56.8864 36.8312 56.5834 37.1383C56.3886 37.3356 55.8702 37.91 55.829 37.9521C55.5827 38.2041 54.6823 39.0681 54.5102 39.248C54.4029 39.3604 54.5364 39.285 54.4369 39.3818C54.3443 39.4718 54.4108 39.3492 54.3825 39.3751C54.1478 39.5894 52.4793 41.3317 52.0478 41.7101C52.3032 41.4706 53.4822 40.1793 53.4376 40.1843C53.4295 40.187 53.1079 40.4658 53.0564 40.5381C52.9298 40.6161 52.6526 41.0414 52.447 41.2179C52.4238 41.2379 52.4673 41.1112 52.1188 41.4447C51.9988 41.5595 51.7236 41.8995 51.3777 42.1727C51.0362 42.5419 49.4504 44.0657 48.7499 44.7839C47.798 45.6851 46.5107 45.5186 45.9568 44.3306C45.8367 44.0977 45.7496 43.9394 45.7167 43.9029C45.7107 43.8984 45.9011 44.3277 45.7362 44.0558C45.5169 43.6943 45.7899 43.9809 45.5792 43.5371C45.5475 43.4702 44.9259 42.2532 44.8994 42.2164C44.6561 41.8754 45.1665 42.9552 45.1522 42.9436C45.1166 42.9149 44.6625 42.0326 44.6485 41.9946C44.6356 41.9581 45.0746 42.6433 44.6105 41.7882C44.6511 41.8925 44.6917 41.9967 44.7323 42.1009C44.5098 41.7009 44.5437 41.6352 44.4974 41.5345C44.3537 41.2213 44.106 40.9287 43.9594 40.385C43.9207 40.2413 44.0586 40.4431 44.0544 40.4248C44.0118 40.2502 43.8161 40.098 43.7696 39.8266C43.7661 39.8062 44.0831 40.3334 43.6038 39.3745C43.63 39.4439 43.6561 39.5133 43.6823 39.5827C43.5994 39.4552 43.1049 38.4889 43.0432 38.3565C42.863 37.9696 43.0785 38.2778 42.8809 37.8972C42.9365 38.1769 42.3446 37.0151 42.4361 37.0532C42.2819 36.9267 41.8427 35.908 41.6116 35.4414C41.4657 35.1471 41.1343 34.5636 41.0913 34.4684C41.039 34.3524 41.106 34.3621 41.0143 34.1512C40.9882 34.0911 40.6461 33.4979 40.4292 32.9356C40.3871 32.8267 40.3622 32.5661 40.4799 32.7489C40.6813 33.0617 40.9264 33.7216 40.9722 33.6887C41.0208 33.6527 40.5676 32.8255 40.4611 32.5951C39.9694 31.5315 40.3285 32.1081 40.3322 32.0726C40.3389 31.9819 40.0514 31.4101 40.0432 31.3844C40.0103 31.2771 40.2461 31.6662 40.2746 31.6596C40.3114 31.6505 40.0952 31.0689 40.1691 31.1887C40.2747 31.3603 40.4785 31.8923 40.4969 31.9232C40.7383 32.3257 40.5279 31.7138 40.4864 31.537C40.474 31.4833 40.5885 31.6647 40.572 31.6233C40.3202 30.991 40.4006 31.5491 40.2095 31.1404C40.039 30.7757 40.3208 31.2137 40.3167 31.1986C40.3109 31.1793 40.0984 30.7476 40.0825 30.6713C40.0748 30.6337 40.7318 31.7034 40.7523 31.6348C40.5642 31.2827 40.3761 30.9306 40.188 30.5785C40.2311 30.522 40.4457 31.0564 40.4782 31.1065C40.5434 31.2075 40.4233 30.895 40.4478 30.8987C40.4627 30.8999 40.6786 31.2292 40.5375 30.9047C40.489 30.7932 40.335 30.5853 40.1781 30.1692C40.9187 31.5198 40.4738 30.5497 40.4738 30.499C40.4741 30.4491 40.8504 31.0826 40.4431 30.289C40.5369 30.1988 40.4868 30.2886 40.6197 30.5055C40.7826 30.7712 40.4983 30.1111 40.978 31.14C41.0011 31.0562 40.5896 30.2422 40.5721 30.197C40.5572 30.1578 40.6735 30.3263 40.6499 30.2573C40.368 29.4423 40.5848 29.9905 40.5382 29.7369C40.5341 29.7143 40.1965 28.9796 40.481 29.5252C40.9993 30.5193 41.1351 30.9751 41.377 31.0648C41.0747 30.289 40.5237 29.4413 40.4092 29.2168C40.2342 28.873 40.4451 29.2143 40.4329 29.1673C40.4284 29.1511 40.2771 28.8551 40.2776 28.8498C40.2919 28.5777 40.9414 30.1725 41.2041 30.6455C41.1573 30.5069 41.1105 30.3683 41.0637 30.2297C41.1524 30.4052 41.241 30.5806 41.3296 30.7561C40.947 29.9004 41.3286 30.7197 41.5304 30.8799C41.5757 30.9158 41.2631 30.3843 41.6377 30.9816C41.4203 30.5116 41.514 30.6493 41.277 30.2438C41.3214 30.2351 41.8371 31.1564 42.0431 31.5184C41.4298 30.1821 41.6614 31.0032 41.169 29.8292C41.0154 29.6426 41.2959 30.1802 41.2658 30.14C41.1578 29.9957 41.0174 29.601 40.6925 29.2025C40.6395 29.1376 40.7433 29.4722 40.517 29.0135C40.492 28.9627 40.3897 28.6495 40.3948 28.6519C40.4481 28.6736 40.5796 28.9684 40.5998 28.9733C40.6188 28.9777 40.4498 28.6599 40.453 28.6569C40.4906 28.6257 40.6035 28.9173 40.5966 28.8702C40.582 28.7684 40.0948 27.5648 40.8234 29.0892C40.1477 27.8583 40.696 28.952 40.9589 29.4315C41.0258 29.5538 41.0671 29.5727 41.1647 29.7459C41.2903 29.9686 41.4118 30.2421 41.4756 30.3579C41.5443 30.4825 41.2433 29.7301 41.7477 30.7838C41.5416 30.2222 41.0083 29.3149 40.7891 28.7716C40.3471 27.6754 41.2596 29.4548 41.361 29.637C41.388 29.6855 41.3392 29.5019 41.3578 29.5339C41.3881 29.5864 41.8797 30.6094 41.9582 30.6953C42.0365 30.7809 41.771 30.3241 41.785 30.278C41.7943 30.2468 42.4419 31.4535 42.1241 30.7839C41.905 30.3223 41.4038 29.5203 41.419 29.3354C41.7621 30.0037 42.1052 30.672 42.4482 31.3403C42.2972 30.9562 42.1461 30.572 41.995 30.1879C42.3824 30.9368 42.6714 31.6073 43.0764 32.3C42.3209 30.5264 43.4397 32.8169 43.465 32.8356C43.4768 32.8402 43.2234 32.1201 43.1845 32.0033C43.5174 32.5872 44.4455 34.4032 44.0172 33.2834C44.0903 33.489 44.3835 33.9287 44.3848 33.9203C44.4015 33.8375 43.8598 32.8295 43.9853 32.9754C44.1307 33.1444 44.2001 33.4484 44.3541 33.7432C45.1448 35.2559 45.1783 34.7157 45.9051 36.2656C45.8986 36.2308 45.892 36.196 45.8854 36.1613C46.7035 37.8318 47.5216 39.5024 48.3397 41.173C48.5428 41.485 48.8781 42.0801 49.2135 42.7022L46.1752 42.2092C46.6435 41.711 47.1358 41.2047 47.4697 40.8771C47.6065 40.7429 48.3022 40.1087 48.3578 40.0639C48.4611 39.9813 47.954 40.4963 48.2043 40.2847C48.257 40.24 49.3958 39.127 49.2825 39.1747C49.1526 39.2971 48.7742 39.7084 48.7019 39.7653C48.1928 40.1641 51.7077 36.7372 51.8575 36.5431C51.7699 36.6093 51.6824 36.6755 51.5949 36.7417C51.8192 36.5279 52.0434 36.3142 52.2677 36.1004ZM43.3851 39.3493C43.2603 39.2039 43.0832 38.7715 42.9484 38.5312C42.762 38.1991 42.3125 37.701 42.5977 37.8697C42.8602 38.3629 43.1226 38.8561 43.3851 39.3493ZM50.6587 43.0756C50.3762 43.3228 50.5107 43.0464 50.7573 42.8588C50.7847 42.8381 51.0408 42.7411 50.6587 43.0756ZM45.2603 43.1484C45.2686 43.1619 45.4109 43.4526 45.4146 43.4634C45.5084 43.741 45.0793 42.8646 45.2603 43.1484ZM56.8584 37.6341C56.7238 37.244 56.7318 37.5564 56.8485 37.7879C56.8559 37.8025 56.8672 37.6598 56.8584 37.6341ZM56.7678 37.3549C56.744 37.025 56.3828 36.465 56.5609 36.9465C56.5782 36.9932 56.7688 37.3702 56.7678 37.3549ZM49.6865 43.9914C49.6942 43.9395 49.9781 43.677 50.1 43.5656C50.117 43.589 49.7984 43.8746 49.6865 43.9914ZM56.6068 37.0589C56.601 37.0299 55.6524 37.9804 55.6107 38.068C55.7508 37.9084 56.6115 37.0854 56.6068 37.0589ZM55.8511 34.6628C55.8454 34.634 55.732 34.3074 55.6896 34.2277L58.7004 34.9384C58.6917 34.9506 58.6883 34.958 58.6918 34.9588C58.6971 34.9547 58.7025 34.9504 58.708 34.946L55.6795 34.231C55.7292 34.4566 55.8804 34.8098 55.8511 34.6628ZM58.0142 41.1567C58.0274 41.1789 58.0486 40.8056 58.2226 41.6153C58.2482 41.7342 58.0775 41.3361 58.0863 41.3784C58.1056 41.4668 58.1238 41.5356 58.1411 41.5901C58.009 41.23 57.8779 40.8539 57.8737 40.8147C57.8541 40.6305 58.0085 41.1468 58.0142 41.1567ZM59.2482 44.5332C59.2946 44.601 59.4427 45.0833 59.4702 45.1952C59.4748 45.2145 59.3914 45.1517 59.4674 45.3658C59.5286 45.5376 59.5 45.26 59.6031 45.6001C59.7074 45.9437 59.5147 45.5024 59.5217 45.5331C59.5311 45.5742 59.7326 46.0925 59.6936 46.0872C59.6648 46.0833 59.4934 45.5133 59.4416 45.3755C59.3753 45.199 59.4062 45.4295 59.3155 45.1278C59.2585 44.9383 59.3658 45.0181 59.3563 44.9773C59.3482 44.9431 59.0877 44.301 59.2483 44.5342C59.2483 44.5339 59.2483 44.5335 59.2482 44.5332ZM58.1771 41.6874C58.1655 41.6608 58.1535 41.6291 58.1411 41.5901C58.1531 41.6227 58.1652 41.6552 58.1771 41.6874ZM43.8991 40.3022C43.965 40.4869 43.6795 39.9836 43.6093 39.774C43.6299 39.7595 43.8885 40.2729 43.8991 40.3022ZM58.3487 42.005C58.5106 42.5513 58.3531 42.1623 58.1771 41.6874C58.2416 41.8353 58.2943 41.8215 58.3487 42.005ZM53.0564 40.5381C53.0774 40.5252 53.0945 40.5207 53.1062 40.5297C53.0503 40.563 53.0402 40.561 53.0564 40.5381ZM54.0144 39.6171C54.3049 39.2635 53.6518 39.9192 53.6785 39.9376C53.689 39.9441 54.0027 39.6313 54.0144 39.6171ZM57.0216 38.1377C57.0126 38.0968 57.3449 38.6683 56.952 37.8087C57.0955 38.2895 56.9143 37.7921 56.9056 37.8033C56.8799 37.8334 57.1772 38.6224 57.2223 38.804C57.326 38.9234 57.0515 38.2727 57.022 38.1387C57.0219 38.1383 57.0217 38.138 57.0216 38.1377ZM61.2652 50.6874C61.1955 50.5903 61.0918 50.2431 61.0165 50.0106C61.0863 50.1077 61.1899 50.4549 61.2652 50.6874ZM32.6711 53.9943C32.1727 55.5933 31.967 55.7534 32.5057 54.3179C32.5163 54.2898 32.6894 53.8933 32.6711 53.9943ZM31.6544 61.6451C31.8122 61.7081 31.29 61.7183 30.9471 61.6923C30.8695 61.6864 30.5825 61.6226 30.9102 61.6101C30.8997 61.6865 31.4064 61.7156 31.6544 61.6451ZM58.4888 42.2976C58.5811 42.4416 58.7141 42.9353 58.7932 43.1925C58.7084 43.0477 58.5515 42.5273 58.4888 42.2976ZM30.8595 59.1908C30.7992 59.3567 30.8135 59.4871 30.8275 59.4596C30.8905 59.3368 30.9527 59.0098 30.8595 59.1908ZM57.9739 40.7322C57.9903 40.7022 58.227 41.3359 58.183 41.4002C58.1416 41.2617 57.9642 40.7531 57.9739 40.7322ZM61.1374 50.2442C61.1163 50.1406 61.3099 50.6491 61.3499 50.8091C61.3203 50.805 61.1513 50.3121 61.1374 50.2442ZM29.9785 61.8925C29.924 62.041 29.7978 62.4151 29.805 62.4636C29.8141 62.5239 29.9882 61.9716 29.9785 61.8925ZM39.2332 33.9773C39.2489 33.9616 39.1236 34.5644 39.0204 34.8166C38.8242 35.2954 39.2197 33.9956 39.2332 33.9773ZM31.361 57.5968C31.5681 57.1404 31.3452 57.6494 31.4042 57.6461C31.5121 57.3285 31.7786 56.5378 31.546 57.065C31.5007 57.1677 31.4139 57.4496 31.361 57.5968ZM31.1982 58.0272C31.1982 58.0835 31.1378 58.4421 31.2322 58.1461C31.2757 58.0093 31.2898 57.7701 31.1982 58.0272ZM38.0581 37.5797C37.8707 37.9882 38.5431 36.0535 38.5698 36.0004C38.5839 35.9723 38.5943 35.9543 38.6014 35.9444C38.6106 35.8682 38.7303 35.5003 38.7814 35.4701C38.7417 35.5792 38.6448 35.8807 38.6291 35.9142C38.6223 35.9286 38.6169 35.9393 38.6127 35.9465C38.6016 36.0867 38.0939 37.5014 38.0581 37.5797ZM36.9375 40.7832C37.0312 40.2756 37.1754 40.2283 37.1652 40.2713C37.0366 40.8151 37.0661 40.4423 37.0567 40.4572C37.0377 40.4918 36.9523 40.8801 36.938 40.7817C36.9379 40.7822 36.9377 40.7827 36.9375 40.7832ZM37.8191 38.2333C37.8242 38.2128 37.9635 37.8069 37.9709 37.7908C38.121 37.47 37.7271 38.6188 37.8191 38.2333ZM60.1857 47.0757C60.2713 47.3711 60.1335 47.0993 60.0842 46.9005C60.0804 46.8841 60.1101 46.8152 60.1857 47.0757ZM31.1321 58.2638C31.1015 58.3287 30.4949 60.0475 30.5938 59.965C30.6351 59.8157 31.3233 57.8616 31.1321 58.2638ZM35.4392 61.7341C35.1179 61.7335 35.4682 61.6696 35.6397 61.6935C35.7033 61.7023 35.5202 61.7342 35.4392 61.7341ZM57.7406 39.8491C57.6018 39.5436 57.7353 39.5719 57.7885 39.8591C57.7906 39.8703 57.7461 39.8611 57.7406 39.8491ZM32.8718 61.6973C33.9801 61.6586 33.7177 61.8612 32.2767 61.7928C32.3218 61.7838 32.3669 61.7747 32.412 61.7657C30.7489 61.7353 32.2983 61.7514 32.7055 61.7401C32.8603 61.7358 32.7305 61.702 32.8708 61.6971C32.8711 61.6972 32.8715 61.6973 32.8718 61.6973ZM37.1293 61.7379C38.1966 61.8817 36.159 61.7881 35.5745 61.8068C36.1411 61.7474 36.8788 61.7564 35.8755 61.6956C37.3424 61.6839 36.7317 61.7411 36.7903 61.7459C36.8596 61.7512 37.0838 61.7318 37.1293 61.7379ZM34.3138 61.7389C34.2521 61.7431 33.7872 61.7138 33.6198 61.7186C33.854 61.6695 34.7234 61.7104 34.3138 61.7389ZM35.8442 44.1688C35.8199 44.12 35.8232 44.0205 35.9528 43.6769C35.9353 43.7906 35.877 44.0182 35.8442 44.1688ZM43.4084 38.9432C43.2979 38.7159 43.0859 38.2595 43.1187 38.4156C43.1231 38.4322 43.3878 38.9526 43.4084 38.9432ZM29.4287 63.2754C29.4188 63.2981 29.3204 63.5875 29.2353 63.8515L27.7207 61.7501C28.0482 61.7468 28.3364 61.7372 28.0765 61.7142C28.0331 61.7104 27.8891 61.7082 27.7207 61.7081L29.2751 63.8647C29.3996 63.4916 29.5552 62.9886 29.4287 63.2754ZM31.709 56.4498C31.6718 56.56 31.5293 57.0105 31.5348 57.0229C31.5545 57.0632 31.7215 56.5075 31.709 56.4498ZM42.8736 37.7855C42.8623 37.754 42.5109 37.0668 42.5321 37.1511C42.5725 37.3109 42.9123 37.8937 42.8736 37.7855ZM60.6247 48.1078C60.6465 48.1686 60.6338 48.2628 60.6404 48.2841C60.6564 48.334 61.0451 49.4493 60.8515 49.0382C60.8192 48.9697 60.3015 47.3513 60.2366 47.1399C60.264 47.0407 60.4418 47.7465 60.5032 47.9122C60.5141 47.9414 60.566 47.9451 60.6243 48.1074C60.6244 48.1075 60.6246 48.1077 60.6247 48.1078ZM36.4101 42.3426C36.392 42.2817 36.8081 40.957 36.8449 40.9862C36.7 41.4384 36.555 41.8905 36.4101 42.3426ZM36.1813 43.0098C36.0632 43.2826 36.2745 42.6218 36.3499 42.4314C36.3739 42.4371 36.1986 42.97 36.1813 43.0098ZM30.747 58.9047C30.7113 59.0399 30.8975 58.6497 30.877 58.744C30.8636 58.8044 30.7461 59.0938 30.7305 59.1934C30.7266 59.2219 30.8746 58.936 30.9017 58.8481C30.9402 58.7232 30.8628 58.831 30.9076 58.6957C31.0565 58.2464 31.2158 57.8572 31.3555 57.436C31.3681 57.398 31.2434 57.684 31.3519 57.3598C31.3686 57.3097 31.5082 57.0218 31.6317 56.632C31.7955 55.7348 32.1247 55.1457 32.4431 54.044C32.418 54.0812 32.1163 54.8839 32.0992 54.9314C31.7763 55.8334 31.2315 57.4605 30.914 58.4121C30.8325 58.6562 30.8978 58.5462 30.8637 58.6517C30.8367 58.7351 30.8219 58.6203 30.747 58.9047ZM43.4933 39.0508C43.4843 38.9206 43.267 38.557 43.1487 38.3145C43.1506 38.4197 43.3853 38.81 43.4933 39.0508ZM34.1734 48.9106C34.1325 49.0395 33.9855 49.4325 33.9889 49.4702C33.9935 49.5188 34.1967 48.9485 34.1734 48.9106ZM62.7168 54.4292C62.7222 54.4412 62.8226 54.7507 62.825 54.7629C62.8787 55.0514 62.5779 54.123 62.7168 54.4292ZM65.1688 61.8159C65.2527 62.048 65.3463 62.2791 65.3339 62.3706C65.2901 62.2195 65.1328 61.7974 65.1688 61.8159ZM58.7053 61.7981C58.7562 61.8514 58.0136 61.8169 57.8734 61.8121C57.9253 61.7884 58.6679 61.7597 58.7053 61.7981ZM35.6684 44.1666C35.8149 43.7369 35.708 43.8022 35.8338 43.5403C35.8546 43.4977 36.0623 43.4066 35.8447 43.8601C35.8055 43.9417 35.8787 43.5958 35.6684 44.1666ZM32.042 61.7911C31.9266 61.8264 31.5657 61.8159 31.3219 61.8131C31.3765 61.7869 31.8686 61.7936 32.042 61.7911ZM42.2864 36.5208C42.2357 36.308 41.7627 35.4446 41.8421 35.6771C41.8538 35.71 42.2263 36.3965 42.2864 36.5208ZM59.0065 43.3417C59.1717 43.7134 58.9181 42.9141 58.798 42.6752C58.8383 42.7881 58.9954 43.3167 59.0065 43.3417ZM61.2845 61.8271C61.265 61.8287 60.8358 61.8249 60.8166 61.823C60.4649 61.782 61.6793 61.7925 61.2845 61.8271ZM64.4209 59.3673C64.5005 59.5038 64.7973 60.4766 64.8386 60.703C64.7245 60.5099 64.322 59.198 64.4209 59.3673ZM35.0994 45.946C35.2003 45.6383 35.3069 45.3499 35.4142 45.072C35.4202 45.14 35.1295 45.92 35.0994 45.946ZM59.7088 61.8305C59.6858 61.8303 59.6634 61.8272 59.6415 61.8269C59.6644 61.828 59.6869 61.8293 59.7088 61.8305ZM32.7889 52.8174C32.6928 53.0715 32.7579 53.0338 32.7646 53.0184C32.8445 52.8297 32.8975 52.5297 32.7889 52.8174ZM43.4208 38.7403C43.4189 38.6361 43.1835 38.2434 43.0757 38.0037C43.078 38.0877 43.3219 38.5532 43.4208 38.7403ZM38.2724 61.83C38.6134 61.8787 37.2259 61.9354 36.9336 61.9039C36.912 61.8738 38.2225 61.8233 38.2724 61.83ZM58.6729 42.128C58.6978 42.091 58.4732 41.5518 58.4966 41.6745C58.5113 41.7522 58.6573 42.1503 58.6729 42.128ZM36.2359 61.8834C36.1055 61.8942 35.8017 61.8594 35.9087 61.8382C36.046 61.8111 36.2696 61.8803 36.2359 61.8834ZM30.0877 60.7832C30.0646 60.8356 29.8565 61.5741 29.9907 61.2851C30.0839 61.0846 30.0467 61.0353 30.0628 60.9862C30.0813 60.9315 30.5295 59.7839 30.0877 60.7832ZM46.043 61.8607C45.7539 61.8742 45.4042 61.8585 45.1015 61.8595C45.2248 61.8377 45.92 61.8318 46.043 61.8607ZM59.3923 44.2563C59.3836 44.1852 58.7867 42.3674 59.0888 43.4123C59.1065 43.4733 59.4189 44.4723 59.3923 44.2563ZM35.6684 44.1666C35.6499 44.2208 35.6274 44.2829 35.5999 44.3545C35.6252 44.2827 35.6484 44.2207 35.6684 44.1666ZM34.0328 49.0565C34.0415 48.9492 33.8685 49.4466 33.8323 49.5983C33.8469 49.6536 34.0317 49.0713 34.0328 49.0565ZM45.0785 61.8952C44.9041 61.9099 44.5876 61.8943 44.3717 61.896C44.4083 61.8721 45.0031 61.871 45.0785 61.8952ZM57.3248 61.9221C56.9785 61.9079 56.5524 61.9144 56.5458 61.9436C56.5386 61.939 56.5218 61.9342 56.4939 61.9293C56.4658 61.9245 56.0948 61.9381 55.9336 61.9281C54.9687 61.869 59.6599 61.8934 56.9409 61.9757C57.0689 61.9578 57.1968 61.94 57.3248 61.9221ZM64.051 58.0406C64.0225 57.8429 63.8063 57.3347 63.8382 57.4747C63.8606 57.5721 64.0793 58.2385 64.051 58.0406ZM65.8146 61.9513C65.8733 61.9576 66.4108 61.9328 66.4246 61.9141C66.1157 61.8944 65.5469 61.9219 65.8146 61.9513ZM63.6126 56.594C63.5787 56.4753 63.4747 56.3441 63.4769 56.3586C63.4967 56.4842 63.6479 56.8007 63.6126 56.594ZM35.2247 45.01C35.1511 45.1789 35.0054 45.7472 35.001 45.88C34.9865 45.9001 34.9573 45.9578 34.9094 46.0653C34.9095 46.065 34.9096 46.0646 34.9097 46.0643C34.8452 46.2095 33.3339 50.6907 34.4061 47.7043C34.4397 47.6109 34.3646 47.7288 34.4981 47.3473C34.507 47.3221 34.5374 47.3182 34.5648 47.2404C34.6276 47.0613 34.9638 46.1077 35.0069 45.9079C35.0124 45.9079 35.0211 45.897 35.0342 45.8719C35.1509 45.6481 35.2817 44.8789 35.2247 45.01ZM64.749 61.9564C64.8572 61.9667 65.1995 61.9569 65.235 61.9325C65.0652 61.9205 64.498 61.9324 64.749 61.9564ZM59.4687 44.1683C59.4181 43.9529 59.2058 43.435 59.2403 43.6014C59.2613 43.7035 59.5272 44.4167 59.4687 44.1683ZM65.7076 62.9691C66.0798 64.177 65.8052 63.2545 65.9004 63.4267C65.8362 63.2742 65.7719 63.1217 65.7076 62.9691ZM37.1618 39.4913C37.0903 39.6798 37.0981 39.4328 37.2047 39.2345C37.2382 39.1723 37.2017 39.3858 37.1618 39.4913ZM40.0181 30.853C39.9042 30.9963 40.2048 30.2112 40.1421 30.5354C40.1386 30.5502 40.0242 30.8421 40.0181 30.853ZM37.9833 36.8763C37.9806 37.0195 37.9573 37.1056 37.8254 37.4678C37.9944 36.9229 37.7912 37.4128 37.9833 36.8763ZM56.5496 61.9482C56.5473 61.9464 56.5455 61.9452 56.5458 61.9436C56.5483 61.9451 56.5494 61.9466 56.5496 61.9482ZM63.2264 55.4705C63.2107 55.309 63.068 54.8893 63.0752 55.0261C63.0761 55.0392 63.1806 55.4175 63.2264 55.4705ZM35.001 45.88C35.0138 45.8621 35.0143 45.8736 35.0069 45.9079C35.0018 45.9079 35.0004 45.8979 35.001 45.88ZM64.0071 57.7193C63.9765 57.7128 64.1799 58.3562 64.1915 58.3809C64.3583 58.7335 64.0967 57.9831 64.0071 57.7193ZM58.094 39.9241C58.0803 39.8919 58.0851 40.1269 58.1546 40.2488C58.2083 40.3431 58.1453 40.0443 58.094 39.9241ZM38.3806 35.6296C38.4482 35.4269 38.5433 35.1415 38.5922 35.0994C38.5421 35.2336 38.4022 35.6415 38.3806 35.6296ZM39.871 31.1506C39.8281 31.4025 39.6456 31.9496 39.523 32.297C39.4723 32.2873 39.8075 31.3792 39.871 31.1506ZM35.4261 44.4662C35.4186 44.4822 35.2347 44.9856 35.2903 44.927C35.3718 44.8415 35.4916 44.3287 35.4261 44.4662ZM58.3879 40.9228C58.486 41.1426 58.3805 40.5966 58.2474 40.3745C58.1791 40.2604 58.3714 40.8857 58.3879 40.9228ZM62.8336 54.1423C62.7148 53.8486 62.9291 54.6032 62.9977 54.6957C62.9544 54.5567 62.8758 54.2467 62.8336 54.1423ZM66.7032 62.0444C67.6995 62.1477 67.1569 61.9591 66.9801 61.9757C66.9552 61.9781 66.6788 62.0419 66.7032 62.0444ZM41.3656 34.2171C41.2896 34.0974 41.4783 34.591 41.5393 34.6365C41.5773 34.6645 41.4141 34.2937 41.3656 34.2171ZM51.7002 61.9772C51.7423 61.9768 51.784 61.9765 51.8253 61.9762C51.7944 61.9779 51.7536 61.9784 51.7002 61.9772ZM62.0574 51.3758C62.1407 52.0873 62.2242 51.9819 62.2429 52.0399C62.283 52.1653 62.3424 52.4682 62.427 52.7016C62.3215 52.4371 62.216 52.1726 62.1105 51.9081C62.1716 52.1245 62.7375 53.9921 62.7728 54.0234C62.8233 54.0683 62.6192 53.4893 62.6164 53.4714C62.6122 53.4456 62.6708 53.325 62.6562 53.2699C62.632 53.1792 62.118 51.6312 62.0574 51.3758ZM65.5957 62.3651C65.6358 62.5206 65.615 62.5755 65.6469 62.6433C65.6578 62.6664 65.6927 62.6591 65.7288 62.7383C65.6844 62.6139 65.6401 62.4895 65.5957 62.3651ZM61.5358 50.2258C61.514 50.0238 61.7799 50.8735 61.7844 50.9021C61.8047 51.0558 61.5535 50.3909 61.5358 50.2258ZM63.9304 57.3898C63.9225 57.3582 63.7192 56.7054 63.6981 56.7183C63.738 56.8956 64.0219 57.7644 63.9304 57.3898ZM65.7649 62.839C65.8369 63.0682 65.9467 63.5102 65.9808 63.4439C65.9807 63.4436 65.9805 63.4432 65.9804 63.4429C65.9086 63.2416 65.8367 63.0403 65.7649 62.839ZM58.7541 41.6653C58.6939 41.2162 58.6588 41.4501 58.7574 41.8327C58.8313 41.9339 58.764 41.7388 58.7541 41.6653ZM58.3637 40.294C58.3391 40.1717 57.9197 38.9665 57.9386 39.1654C57.9453 39.2361 58.2157 39.9194 58.2234 39.9525C58.2352 40.0026 58.1141 39.7962 58.2472 40.1644C58.2559 40.1373 58.3723 40.3359 58.3637 40.294ZM58.6892 41.2986C58.6106 40.8586 58.4662 40.802 58.571 41.1176C58.6119 41.241 58.7003 41.3614 58.6892 41.2986ZM59.2508 43.0157C59.2112 42.8611 59.0928 42.4538 58.9628 42.1891C59.0833 42.5611 59.2037 42.9332 59.3242 43.3052C59.3597 43.3408 59.2855 43.1509 59.2505 43.0147C59.2506 43.015 59.2507 43.0154 59.2508 43.0157ZM40.4219 28.5327C40.2787 28.8554 40.5225 28.0833 40.5412 28.0534C40.5995 27.9657 40.4859 28.3884 40.4219 28.5327ZM41.1059 31.278C41.0743 31.1847 41.0854 31.1078 40.9685 30.9259C41.0359 31.1339 41.1033 31.3419 41.1708 31.5499C41.3129 31.6666 41.1403 31.3801 41.1059 31.278ZM40.9816 30.4172C40.9969 30.4437 41.0254 30.243 41.133 30.6303C41.2057 30.8919 40.5122 29.618 40.4409 29.3612C40.5914 29.6091 40.8508 30.1887 40.9816 30.4172ZM40.2922 27.9231C40.293 27.9041 40.5513 28.3906 40.574 28.4505C40.6932 28.7652 40.2886 28.026 40.2922 27.9231ZM41.0583 29.5044C40.9628 29.2634 41.2316 29.7687 41.2963 29.9269C41.2845 29.9513 41.0732 29.5415 41.0583 29.5044ZM37.7133 31.381C37.5506 31.6214 37.6315 31.9118 37.7353 31.4931C37.7403 31.4732 37.7207 31.3709 37.7133 31.381ZM40.637 28.3527C40.7325 28.5937 40.4637 28.0884 40.399 27.9302C40.411 27.9064 40.6223 28.3161 40.637 28.3527ZM37.4741 31.5087C37.3033 31.843 37.524 31.7788 37.5459 31.7372C37.6349 31.5654 37.7716 30.9205 37.7965 30.7876C37.5133 31.7269 37.5546 31.3513 37.4741 31.5087ZM37.0405 33.1687C36.9507 33.5017 37.2656 32.6791 37.2687 32.5031C37.217 32.6663 37.0659 33.0739 37.0405 33.1687ZM36.322 35.1322C36.2571 35.3057 36.0675 35.823 36.0666 35.92C36.1254 35.7266 36.3264 35.216 36.322 35.1322ZM36.1049 35.5017C35.975 35.7634 36.0648 35.8666 36.1371 35.5389C36.1399 35.5262 36.1104 35.4923 36.1049 35.5017ZM35.5501 37.0317C35.4456 37.197 35.4853 37.4387 35.5855 37.1478C35.6151 37.0613 35.5615 37.0143 35.5501 37.0317ZM37.1341 31.8851C37.0291 32.1366 36.9958 32.4948 37.1879 31.947C37.1353 32.1443 37.0826 32.3417 37.03 32.5391C37.3139 31.8322 37.1888 31.8494 37.2622 31.6437C37.365 31.3564 37.4461 31.4088 37.4546 31.4762C37.4793 31.2208 37.8145 30.2124 37.9984 29.6264C37.8049 30.1308 37.4884 30.9486 37.3055 31.4491C37.2532 31.5919 37.2309 31.7401 37.1871 31.8622C37.1169 32.0579 37.1403 31.871 37.1345 31.8841C37.1344 31.8844 37.1343 31.8847 37.1341 31.8851ZM34.8722 39.06C34.6453 39.5726 34.8656 39.2741 34.946 38.9685C34.9487 38.9552 34.8778 39.0473 34.8722 39.06ZM40.6175 27.5351C40.9081 28.2234 40.609 27.7671 41.3927 29.119C41.0386 28.5634 41.3326 29.1085 41.2508 29.0064C41.1854 28.9244 41.0296 28.5725 41.0903 28.792C41.0016 28.5079 40.4195 27.3731 40.401 27.3188C40.4013 27.3193 40.4015 27.3198 40.4017 27.3202C40.3906 27.2876 40.5248 27.3155 40.6175 27.5351ZM36.0369 35.04C35.8461 35.1726 36.0324 35.3116 35.8074 35.6223C35.8121 36.1374 36.233 34.3457 36.4372 34.1798C35.7922 36.063 36.986 32.9765 36.3459 34.2277C36.7807 33.1661 36.4396 33.8636 36.4699 33.6875C36.5024 33.4991 36.7368 32.8947 36.6773 32.9095C36.6772 32.9099 36.677 32.9102 36.6769 32.9105C36.5551 33.2874 36.4334 33.6642 36.3116 34.041C36.5401 33.7086 36.2524 34.4658 36.0793 34.6974C36.0652 34.8116 36.051 34.9258 36.0369 35.04ZM36.8452 32.9469C36.8304 32.9831 36.5729 33.8052 36.6117 33.7595C36.6617 33.6549 37.032 32.4898 36.8452 32.9469ZM38.0207 29.343C37.9227 29.6363 37.7508 30.0831 37.7375 30.2563C37.8355 29.9629 38.0075 29.5161 38.0207 29.343ZM32.9773 44.448C32.8855 44.8329 33.279 43.6847 33.1291 44.0049C33.1218 44.0207 32.9819 44.4291 32.9773 44.448ZM35.7733 35.8972C35.6063 36.264 35.7945 36.1271 35.8549 35.8343C35.8584 35.8173 35.781 35.8803 35.7733 35.8972ZM40.9024 28.0682C40.944 28.0773 41.407 29.0553 41.493 29.2266C41.4167 29.143 40.8547 28.0576 40.9024 28.0682ZM38.0752 28.7875C37.7676 29.3335 37.6341 30.1692 37.6023 30.2552C37.5706 30.3406 37.5664 30.1886 37.5585 30.2079C37.5407 30.2518 37.2382 31.1732 37.2268 31.2188C37.2189 31.2516 37.3438 31.1083 37.3024 31.3054C37.3864 30.9219 37.9717 29.2483 37.9931 29.1585C38.0095 29.0888 37.7667 29.5742 38.0749 28.7885C38.075 28.7881 38.0751 28.7878 38.0752 28.7875ZM37.5148 30.4672C37.6205 30.2471 37.4093 30.8928 37.3466 31.0452C37.2071 31.3837 37.5015 30.4955 37.5148 30.4672ZM36.9713 32.0083C36.9402 32.0798 36.7129 32.742 36.7265 32.8093C36.8733 32.5089 37.0422 31.8464 36.9713 32.0083ZM34.5119 39.401C34.4586 39.5749 34.2755 40.041 34.2948 40.0776C34.3482 39.9035 34.5312 39.4375 34.5119 39.401ZM42.786 31.2527C42.6732 30.9714 42.9953 31.5928 43.0759 31.7808C43.0631 31.7997 42.7955 31.2767 42.786 31.2527ZM35.4811 35.8714C35.4384 35.9707 34.7653 38.0617 34.6811 38.3584C34.7979 38.0796 35.4879 36.015 35.5087 35.9178C35.5147 35.8894 35.4868 35.8588 35.4811 35.8714ZM36.9702 31.3604C36.9922 31.1555 37.0838 31.0475 37.0925 31.0236C37.1776 30.7894 37.3315 30.2963 37.3359 30.4171C37.1807 30.8287 36.9263 31.7684 36.9702 31.3604ZM34.2739 39.4862C34.0535 40.1989 34.5505 38.8545 34.4474 39.0182C34.441 39.0288 34.2966 39.4125 34.2739 39.4862ZM35.5466 35.6345C35.5649 35.4673 36.2888 33.3925 36.4003 33.0579C36.3626 33.3783 36.2349 33.6042 36.1038 34.0078C36.0685 34.1168 36.1041 34.0964 36.1002 34.1081C36.0387 34.2966 36.0558 34.1458 36.0166 34.2617C35.992 34.3349 35.5208 35.87 35.5466 35.6345ZM36.9777 31.2417C36.9927 31.1172 37.4163 29.8123 37.4401 29.7621C37.6179 29.3861 37.0197 31.1434 36.9777 31.2417ZM35.4276 35.8074C35.43 35.5592 35.8235 34.5401 35.6233 35.2606C35.604 35.3293 35.4772 35.6054 35.4276 35.8074ZM34.2303 39.3877C34.2166 39.4218 33.9563 40.1546 33.9748 40.1755C34.0193 40.0719 34.3857 38.9993 34.2303 39.3877ZM34.2801 38.9793C34.2747 38.9973 34.3766 38.8391 34.2557 39.1831C34.2456 39.2118 34.1778 39.2489 34.0511 39.6898C34.0255 39.7792 34.0129 39.9269 34.0182 39.9177C34.2473 39.491 34.5521 38.0776 34.2801 38.9793ZM36.9453 31.2045C36.9009 31.2676 36.8949 31.0776 36.9774 30.9356C37.0128 30.8748 37.0096 31.0092 36.9453 31.2045ZM33.4304 41.7202C33.5355 41.2788 33.0796 42.6227 33.0664 42.6945C33.1044 42.6591 33.4198 41.7644 33.4304 41.7202ZM43.3777 31.7477C43.3775 31.7474 43.3773 31.7471 43.3772 31.7468C43.5392 32.0909 43.4042 31.8951 43.4112 31.9115C43.7298 32.6577 43.701 32.432 43.7655 32.5413C43.9041 32.7756 43.8028 32.7774 44.0416 33.1702C43.6529 32.5179 43.9822 33.1239 43.9627 33.1577C43.882 33.2929 43.5673 32.2281 43.3736 31.9028C43.3466 31.8575 43.4825 32.2238 43.4114 32.1086C43.1805 31.7341 42.756 30.4272 43.3777 31.7477ZM37.0111 30.8161C37.0299 30.6365 37.4889 29.379 37.4071 29.7257C37.394 29.7815 36.983 31.08 37.0111 30.8161ZM56.4282 64.8776C56.1066 64.9113 56.8519 64.9509 56.9901 64.9247C57.0587 64.9116 56.5694 64.8628 56.4282 64.8776ZM61.6539 65.0218C62.036 65.015 62.4389 64.8743 61.9635 64.8962C61.9129 64.8986 61.6101 65.0023 61.6539 65.0218ZM36.5615 64.9496C36.9605 64.9998 36.9367 64.9065 36.6438 64.9078C36.5404 64.9082 36.5489 64.948 36.5615 64.9496ZM51.7906 64.9375C51.8305 64.9408 52.2918 64.9348 52.275 64.9133C52.1045 64.9005 51.5323 64.9151 51.7906 64.9375ZM36.4348 64.9629C36.6714 64.946 36.2641 64.8785 35.975 64.9445C36.1218 64.9391 36.4104 64.9646 36.4348 64.9629ZM34.9711 36.5242C34.9448 36.7243 34.7566 37.2524 34.661 37.5599C34.6029 37.5771 34.9069 36.7453 34.9711 36.5242ZM60.0318 64.9653C60.3935 64.9303 59.6185 64.9016 59.6896 64.9479C59.6995 64.9504 60.0175 64.9668 60.0318 64.9653ZM27.4578 59.0082C27.4028 59.267 27.7046 58.4876 27.5825 58.6891C27.5769 58.6992 27.4608 58.994 27.4578 59.0082ZM28.627 55.5549C28.5544 55.741 28.2883 56.549 28.4205 56.2441C28.4409 56.1967 28.648 55.5777 28.627 55.5549ZM43.8076 32.5454C43.8051 32.4264 44.0733 32.9899 44.1053 33.0738C44.1176 33.1069 43.8109 32.7005 43.8076 32.5454ZM39.1529 64.9576C39.3594 64.9512 39.8949 64.9633 39.9891 64.9365C39.7366 64.9421 39.085 64.9042 39.1529 64.9576ZM58.3823 64.9655C58.6974 65.021 59.2356 65.0155 59.1025 64.9431C58.508 64.9479 59.176 65.0082 58.3823 64.9655ZM35.1051 65.0226C35.2706 65.0268 35.3975 64.9572 35.3788 64.9539C35.1994 64.9227 34.9406 64.9955 35.1051 65.0226ZM47.5289 64.9653C47.5384 64.995 48.0691 64.9815 47.9983 64.9624C47.975 64.956 47.5211 64.9412 47.5289 64.9653ZM32.7571 43.1127C32.6544 43.3348 32.8641 42.6219 32.9636 42.4235C33.0407 42.3367 32.7697 43.0845 32.7571 43.1127ZM30.514 65.0052C30.4893 65.0493 31.3188 65.0243 30.992 64.9878C30.9102 64.9786 30.5226 64.9904 30.514 65.0052ZM27.725 57.9216C27.599 58.4661 28.3733 56.2614 28.1169 56.8231C28.0986 56.8633 27.7361 57.8743 27.725 57.9216ZM28.9628 54.312C28.927 54.4012 28.8014 54.309 28.9813 53.9502C29.0048 53.903 28.9649 54.1468 28.9869 54.1092C28.9996 54.0871 29.2926 53.2742 29.3019 53.2353C29.3117 53.1935 29.2506 53.2262 29.2593 53.1834C29.2691 53.1351 29.4769 52.6438 29.5654 52.3797C29.7321 51.8821 29.7125 51.8158 29.726 51.775C29.7654 51.656 29.8587 51.4649 29.939 51.2238C30.3438 50.0084 30.9316 48.1391 31.3323 47.2022C31.0145 48.0489 30.7761 48.8772 30.5022 49.7338C30.5071 49.4578 30.1442 51.0089 30.3472 50.0986C30.2317 50.5104 29.0795 54.0192 28.9632 54.311C28.9631 54.3113 28.9629 54.3117 28.9628 54.312ZM63.1622 65.0634C62.9274 65.114 64.1319 65.1026 64.2341 65.0441C64.0751 65.0359 63.1913 65.0577 63.1622 65.0634ZM57.605 65.1869C57.4931 65.1956 57.3869 65.2946 56.8003 65.2444C56.7998 65.2444 56.7992 65.2444 56.7987 65.2444C56.6272 65.2297 56.8226 65.2056 56.7912 65.197C56.7798 65.1935 56.2448 65.1443 56.6891 65.1364C57.3666 65.1242 56.7529 65.21 57.1141 65.2111C57.1583 65.2111 57.842 65.1576 57.8022 65.1458C57.7981 65.1444 57.5924 65.1558 57.5584 65.1509C57.4301 65.1325 57.4926 65.1016 57.4745 65.1001C57.4153 65.0964 56.3341 65.149 56.1769 65.103C56.1258 65.0882 57.9004 65.054 57.9696 65.0617C58.0133 65.0666 57.9949 65.1524 58.0402 65.1608C58.0635 65.165 58.7773 65.1328 58.87 65.1407C58.8969 65.143 58.9174 65.1455 58.9325 65.1475C58.8245 65.121 59.4709 65.1229 59.4511 65.1528C59.4399 65.1646 58.9949 65.1578 58.979 65.1557C58.972 65.1548 58.966 65.1536 58.9603 65.1528C59.0524 65.1852 57.546 65.1837 57.8712 65.2318C57.4345 65.2582 57.9332 65.1612 57.605 65.1869ZM55.5059 65.2398C55.551 65.2308 55.5961 65.2218 55.6412 65.2127C54.8767 65.2348 53.9945 65.1914 53.1139 65.1917C52.8904 65.1917 53.1475 65.2469 52.8546 65.2318C52.6199 65.2198 52.3602 65.1686 52.4878 65.1572C52.5189 65.1543 52.9967 65.1877 53.2358 65.1842C53.9417 65.1741 53.7634 65.1268 53.8046 65.1255C53.8502 65.1242 54.2945 65.1574 54.5371 65.156C55.1471 65.1521 55.4258 65.1231 56.2592 65.161C55.7782 65.1922 56.0417 65.26 55.5059 65.2398ZM26.2449 62.1059C26.2258 62.069 26.4091 61.6027 26.4624 61.4289C26.4817 61.4655 26.2982 61.932 26.2449 62.1059ZM54.0355 34.4422C53.9614 34.5855 54.7844 33.7796 54.541 33.9655C54.4871 34.0066 54.1381 34.3402 54.0355 34.4422ZM59.8275 35.1949C59.8891 35.3368 59.7263 34.7371 59.6908 34.7502C59.6795 34.7549 59.8196 35.1766 59.8275 35.1949ZM45.6239 65.1917C45.5947 65.1933 45.1709 65.1824 45.1577 65.1799C44.8769 65.128 46.2718 65.158 45.6239 65.1917ZM61.8736 41.1428C61.6734 40.6435 62.1714 42.1813 62.0539 41.6998C62.048 41.6758 61.8832 41.1668 61.8736 41.1428ZM62.5925 43.2713C62.5502 43.1497 62.3845 42.6024 62.368 42.6C62.3416 42.5968 62.5329 43.2227 62.5925 43.2713ZM34.9933 65.2072C35.0554 65.2623 34.3016 65.2206 34.0395 65.2275C33.9773 65.1724 34.7314 65.2141 34.9933 65.2072ZM39.7512 65.2478C36.5734 65.2912 37.274 65.1735 39.9405 65.221C39.9443 65.2563 39.9518 65.2451 39.7512 65.2478ZM35.682 65.2413C35.7975 65.206 36.1583 65.2164 36.4021 65.2193C36.3583 65.2438 35.8578 65.2349 35.682 65.2413ZM53.0123 35.3585C53.1217 35.186 53.7846 34.6008 53.6867 34.7248C53.6637 34.7534 52.9779 35.4276 53.0123 35.3585ZM45.3576 65.2388C45.4316 65.2924 44.4774 65.2706 44.4043 65.2587C44.1098 65.2108 45.2803 65.2507 45.3576 65.2388ZM30.483 65.2543C30.3145 65.2963 29.8359 65.2747 29.5281 65.2741C29.6682 65.2383 30.2218 65.2536 30.483 65.2543ZM32.705 65.2872C32.6857 65.2888 32.2564 65.285 32.2372 65.2831C31.8854 65.2421 33.0999 65.2526 32.705 65.2872ZM43.5022 31.0961C43.5098 31.1083 43.6528 31.4002 43.6565 31.4111C43.7502 31.6886 43.3212 30.8122 43.5022 31.0961Z\" fill=\"white\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><strong>+10<\/strong> <span class=\"custom-title\">years<\/span><br \/>\nOrganizing adventure routes.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_d90834ca counter-box has_text_color iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:4.8rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"92\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Background.png\" class=\"attachment-full size-full\" alt=\"Background\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><strong>98%<\/strong> <span class=\"custom-title\">satisfaction<\/span><br \/>\nExperiences that exceed expectations.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_45d70206 height_huge width_custom\" style=\"--site-content-width:1670px;\" id=\"our-trips-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_88065556 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"212\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4.png\" class=\"attachment-large size-large\" alt=\"fondo bg 4\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4.png 472w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4-300x135.png 300w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/div><\/div><h2 class=\"w-text us_custom_867cd28e has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Our quad excursions<\/span><\/span><\/h2><div class=\"wpb_text_column us_custom_166589fe custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"normal-text\">Choose your quad route in Marbella<\/span> <span class=\"script\">and live the adventure<\/span><\/h2>\n<\/div><\/div><div class=\"w-html us_custom_37b15231\"><!-- FareHarbor calendar of flow #1145467 -->\n<script src=\"https:\/\/fareharbor.com\/embeds\/script\/calendar-small\/aventouralia\/?fallback=simple&amp;full-items=yes&amp;flow=1145467\"><\/script><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_4e32f780 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"556\" height=\"212\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5.png\" class=\"attachment-large size-large\" alt=\"fondo bg 5\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5.png 556w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5-300x114.png 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5-500x191.png 500w\" sizes=\"auto, (max-width: 556px) 100vw, 556px\" \/><\/div><\/div><div class=\"w-hwrapper us_custom_a2ebf4ae valign_top align_none\" style=\"--hwrapper-gap:1.90rem\"><div class=\"w-vwrapper us_custom_8765f6f2 trip-wrapper align_none valign_bottom\"><div class=\"w-text us_custom_c686e436 category has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">More in demand<\/span><\/span><\/div><h2 class=\"w-text us_custom_956f9e68 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Quad Safari<\/span><\/span><\/h2><div class=\"w-text us_custom_2a6a4656 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">(3h)<\/span><\/span><\/div><div class=\"w-text us_custom_57d467f1 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">180\u20ac<\/span><\/span><\/div><div class=\"w-text us_custom_f74583b5 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Price per Quad (2 persons)<\/span><\/span><\/div>[vc_raw_html css=&#8221;&#8221;]PGEgaHJlZj0iaHR0cHM6Ly9mYXJlaGFyYm9yLmNvbS9lbWJlZHMvYm9vay9hdmVudG91cmFsaWEvaXRlbXMvNTMyOTE3Lz9mdWxsLWl0ZW1zPXllcyZhbXA7YmFjaz1odHRwcyUzQSUyRiUyRnJhbmdlcnNzYWZhcml0b3Vycy5jb20lMkZxdWFkLXRvdXJzJTJGJmFtcDtnND15ZXMmYW1wO2Zyb20tc3NsPXllcyZhbXA7Y3A9eWVzJmFtcDtjc3A9eWVzJmFtcDtsYW5ndWFnZT1lcyZhbXA7Z2E0dD1BVy0xNjU0MDI1MDY5MSUyQ3VuZGVmaW5lZF9fdW5kZWZpbmVkJTNCRy1TS0MzRDY1N1dRJTJDMjAyOTgwMzIzOC4xNzQ5NTY0MjU2X18xNzc3Mjc5NTAwJTNCJmFtcDt1PTVkNDk2MGI1LWRlMDMtNDFjZC1hYzM5LTg3MWIzYzQxOGQ2NCIgdGFyZ2V0PSJfYmxhbmsiPjwvYT4=[\/vc_raw_html]<\/div><div class=\"w-vwrapper us_custom_3ad7f806 trip-wrapper align_none valign_bottom\"><div class=\"w-text us_custom_c686e436 category has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">More in demand<\/span><\/span><\/div><h2 class=\"w-text us_custom_956f9e68 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Quad Safari<\/span><\/span><\/h2><div class=\"w-text us_custom_2a6a4656 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">(2h)<\/span><\/span><\/div><div class=\"w-text us_custom_57d467f1 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">130\u20ac<\/span><\/span><\/div><div class=\"w-text us_custom_f74583b5 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Price per Quad (2 persons)<\/span><\/span><\/div>[vc_raw_html css=&#8221;&#8221;]PGEgaHJlZj0iaHR0cHM6Ly9mYXJlaGFyYm9yLmNvbS9lbWJlZHMvYm9vay9hdmVudG91cmFsaWEvaXRlbXMvNTMyOTA4Lz9mdWxsLWl0ZW1zPXllcyZhbXA7YmFjaz1odHRwcyUzQSUyRiUyRnJhbmdlcnNzYWZhcml0b3Vycy5jb20lMkZxdWFkLXRvdXJzJTJGJmFtcDtnND15ZXMmYW1wO2Zyb20tc3NsPXllcyZhbXA7Y3A9eWVzJmFtcDtjc3A9eWVzJmFtcDtsYW5ndWFnZT1lcyZhbXA7Z2E0dD1BVy0xNjU0MDI1MDY5MSUyQ3VuZGVmaW5lZF9fdW5kZWZpbmVkJTNCRy1TS0MzRDY1N1dRJTJDMjAyOTgwMzIzOC4xNzQ5NTY0MjU2X18xNzc3Mjc5NTAwJTNCJmFtcDt1PTVkNDk2MGI1LWRlMDMtNDFjZC1hYzM5LTg3MWIzYzQxOGQ2NCIgdGFyZ2V0PSJfYmxhbmsiPjwvYT4=[\/vc_raw_html]<\/div><div class=\"w-vwrapper us_custom_97dad3b4 trip-wrapper align_none valign_bottom\"><div class=\"w-text us_custom_c686e436 category has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">More in demand<\/span><\/span><\/div><h2 class=\"w-text us_custom_956f9e68 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Quad Safari<\/span><\/span><\/h2><div class=\"w-text us_custom_2a6a4656 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">(1h)<\/span><\/span><\/div><div class=\"w-text us_custom_57d467f1 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">85\u20ac<\/span><\/span><\/div><div class=\"w-text us_custom_f74583b5 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Price per Quad (2 persons)<\/span><\/span><\/div>[vc_raw_html css=&#8221;&#8221;]PGEgaHJlZj0iaHR0cHM6Ly9mYXJlaGFyYm9yLmNvbS9lbWJlZHMvYm9vay9hdmVudG91cmFsaWEvaXRlbXMvNTMyOTAwLz9mdWxsLWl0ZW1zPXllcyZhbXA7YmFjaz1odHRwcyUzQSUyRiUyRnJhbmdlcnNzYWZhcml0b3Vycy5jb20lMkZxdWFkLXRvdXJzJTJGJmFtcDtnND15ZXMmYW1wO2Zyb20tc3NsPXllcyZhbXA7Y3A9eWVzJmFtcDtjc3A9eWVzJmFtcDtsYW5ndWFnZT1lcyZhbXA7Z2E0dD1BVy0xNjU0MDI1MDY5MSUyQ3VuZGVmaW5lZF9fdW5kZWZpbmVkJTNCRy1TS0MzRDY1N1dRJTJDMjAyOTgwMzIzOC4xNzQ5NTY0MjU2X18xNzc3Mjc5NTAwJTNCJmFtcDt1PTVkNDk2MGI1LWRlMDMtNDFjZC1hYzM5LTg3MWIzYzQxOGQ2NCIgdGFyZ2V0PSJfYmxhbmsiPjwvYT4=[\/vc_raw_html]<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_ed322796 height_medium with_shape\" id=\"buggy-4-row\"><div class=\"l-section-shape type_custom pos_bottom\" style=\"height:auto;\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"102\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-e1776346769469.webp\" class=\"attachment-full size-full\" alt=\"Vector\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-e1776346769469.webp 1920w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-e1776346769469-300x16.webp 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-e1776346769469-1024x54.webp 1024w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-e1776346769469-500x27.webp 500w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_a7e5e97b custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"script\">New!<\/span> <span class=\"normal-text\">4-seater buggy now available at Aventouralia<\/span><\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_d92d739d align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"718\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/buggy-4-plazas.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/buggy-4-plazas.jpg 1024w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/buggy-4-plazas-300x210.jpg 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/buggy-4-plazas-500x351.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_6df4bc3a has_text_color\"><div class=\"wpb_wrapper\"><p>Do you want to experience the thrill of off-road all together? In AvenTouralia we release the 4-seater Buggy, a novelty designed for families and groups of friends who want to share the route in the same vehicle.<\/p>\n<ul>\n<li><strong>Up to 4 people in the same buggy<\/strong>, more comfortable and without booking several vehicles.<\/li>\n<li><strong>Shared experience<\/strong>, group fun, laughter and adrenaline throughout the route.<\/li>\n<li><strong>For all levels<\/strong>, ideal whether it is your first time or if you already have experience.<\/li>\n<li><strong>Unique routes and spectacular views in a group<\/strong>, tour Mijas and the Costa del Sol with expert guides.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-hwrapper valign_top wrap align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_3 us_custom_37c9ec7a grow_ellipse\" href=\"https:\/\/fareharbor.com\/embeds\/book\/aventouralia\/?full-items=yes&amp;flow=1145467&amp;from-ssl=yes&amp;ga4t=AW-wCbxCL6P-N4aEK6X898o,undefined__undefined;G-MX9K54BSLT,658275196.1749540374__1773919462;AW-10938534830,undefined__undefined;&amp;g4=yes&amp;cp=yes&amp;csp=yes&amp;back=https:\/\/aventouralia.com\/&amp;language=es-es&amp;u=eaabd7ff-81f7-453f-969d-739011a3eb02\"><span class=\"w-btn-label\">Dare!<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_3 us_custom_37c9ec7a grow_ellipse\" href=\"\/buggies\/\"><span class=\"w-btn-label\">More information<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_c86ae86f height_medium width_full\" id=\"included-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-image us_custom_fb49e985 oval-img align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"527\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1.webp\" class=\"attachment-large size-large\" alt=\"Img 1\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1.webp 350w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1-199x300.webp 199w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><div class=\"w-vwrapper us_custom_11fed9ef video-wrapper align_none valign_top\"><div class=\"w-image us_custom_9a89a719 top-decoration align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-9.svg\" class=\"attachment-large size-large\" alt=\"Vector 9\" \/><\/div><\/div><div class=\"w-video us_custom_25a18ef5 square-video align_none ratio_16x9 has_border_radius\"><div class=\"w-video-h\"><video  preload=\"auto\" playsinline autoplay loop muted><source type=\"video\/mp4\" src=\"\/wp-content\/uploads\/2025\/06\/VideoPromo_Quads_Horizontal_sin-logo.mp4\" \/><\/video><\/div><div class=\"w-video-icon\" style=\"font-size:1.5rem;background:rgba(0,0,0,0.5);color:#fff\"><\/div><\/div><div class=\"w-image us_custom_e52f4b8f bottom-decoration align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-8.svg\" class=\"attachment-large size-large\" alt=\"Vector 8\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_e1bc0b2c has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Everything included in your quad biking experience<\/span><\/span><\/h2><div class=\"w-text us_custom_99b6b1d9 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">What do our quad biking tours in Marbella include?<\/span><\/span><\/div><div class=\"g-cols wpb_row advantages-inner-row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group.svg\" class=\"attachment-large size-large\" alt=\"Group\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Experience in adventure tourism<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Years organizing quad and buggy tours with thousands of satisfied customers.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector.svg\" class=\"attachment-large size-large\" alt=\"Vector\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Routes for all levels<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>From 1, 2 or 3 hour routes to customized itineraries.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-1.svg\" class=\"attachment-large size-large\" alt=\"Vector (1)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Prepared facilities<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Equipped departure area and complete briefing before each route.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group-1.svg\" class=\"attachment-large size-large\" alt=\"Group (1)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Personalized service<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>We advise you to choose the perfect route according to your level.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group-2.svg\" class=\"attachment-large size-large\" alt=\"Group (2)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Vehicles checked daily<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Quads and buggies powerful, safe and ready for any terrain.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/stash_pin-location.svg\" class=\"attachment-large size-large\" alt=\"stash pin location\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Strategic location<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Direct access to nature trails and unique off-road trails.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_c86ae86f height_medium width_full\" id=\"included-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-image us_custom_fb49e985 oval-img align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"527\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1.webp\" class=\"attachment-large size-large\" alt=\"Img 1\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1.webp 350w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Img_1-199x300.webp 199w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><div class=\"w-vwrapper us_custom_11fed9ef video-wrapper align_none valign_top\"><div class=\"w-image us_custom_9a89a719 top-decoration align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-9.svg\" class=\"attachment-large size-large\" alt=\"Vector 9\" \/><\/div><\/div><div class=\"w-video us_custom_25a18ef5 square-video align_none ratio_16x9 has_border_radius\"><div class=\"w-video-h\"><video  preload=\"auto\" playsinline autoplay loop muted><source type=\"video\/mp4\" src=\"\/wp-content\/uploads\/2025\/06\/VideoPromo_Quads_Horizontal_sin-logo.mp4\" \/><\/video><\/div><div class=\"w-video-icon\" style=\"font-size:1.5rem;background:rgba(0,0,0,0.5);color:#fff\"><\/div><\/div><div class=\"w-image us_custom_e52f4b8f bottom-decoration align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-8.svg\" class=\"attachment-large size-large\" alt=\"Vector 8\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_e1bc0b2c has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Everything included in your quad biking experience<\/span><\/span><\/h2><div class=\"w-text us_custom_99b6b1d9 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">What do our quad biking tours in Marbella include?<\/span><\/span><\/div><div class=\"g-cols wpb_row advantages-inner-row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group.svg\" class=\"attachment-large size-large\" alt=\"Group\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Experience in adventure tourism<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Years organizing quad and buggy tours with thousands of satisfied customers.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector.svg\" class=\"attachment-large size-large\" alt=\"Vector\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Routes for all levels<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>From 1, 2 or 3 hour routes to customized itineraries.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Vector-1.svg\" class=\"attachment-large size-large\" alt=\"Vector (1)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Prepared facilities<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Equipped departure area and complete briefing before each route.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group-1.svg\" class=\"attachment-large size-large\" alt=\"Group (1)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Personalized service<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>We advise you to choose the perfect route according to your level.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Group-2.svg\" class=\"attachment-large size-large\" alt=\"Group (2)\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Vehicles checked daily<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Quads and buggies powerful, safe and ready for any terrain.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper valign_top align_none\" style=\"--hwrapper-gap:0.4rem\"><div class=\"w-image us_custom_4d0158f6 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/stash_pin-location.svg\" class=\"attachment-large size-large\" alt=\"stash pin location\" \/><\/div><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:6px\"><div class=\"w-text us_custom_74e89ec4 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Strategic location<\/span><\/span><\/div><div class=\"wpb_text_column us_custom_bdfc5b43 has_text_color\"><div class=\"wpb_wrapper\"><p>Direct access to nature trails and unique off-road trails.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_f3f68ac4 height_medium width_custom with_shape\" style=\"--site-content-width:1300px;\" id=\"reservation-process-row\"><div class=\"l-section-shape type_curve pos_top\" style=\"height:5vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L64 0 Q32 15.8 0 0 L0 8 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-shape type_curve pos_bottom on_front\" style=\"height:5vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L64 0 Q32 15.8 0 0 L0 8 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_d940b615 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Reservation process<\/span><\/span><\/h2><div class=\"wpb_text_column us_custom_a52a5a63 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"script\">How can you book <\/span> <span class=\"normal-text\">your quads tour in Marbella?<\/span><\/h2>\n<\/div><\/div><div class=\"w-hwrapper steps-wrapper valign_top align_center\" style=\"--hwrapper-gap:8rem\"><div class=\"w-vwrapper us_custom_f19a772e step align_center valign_top\"><div class=\"w-image us_custom_9f7541fa align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/\ud83e\udd86-icon-_page-edit_.svg\" class=\"attachment-large size-large\" alt=\"\ud83e\udd86 icon page edit\" \/><\/div><\/div><div class=\"w-text us_custom_befd4605 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Choose your adventure<\/span><\/span><\/div><div class=\"w-text us_custom_7a8df469 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Start your adventure trip by choosing one of our available routes.<\/span><\/span><\/div><\/div><div class=\"w-image arrow-down-img align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down.png\" class=\"attachment-large size-large\" alt=\"arrow down\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down.png 102w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down-30x300.png 30w\" sizes=\"auto, (max-width: 102px) 100vw, 102px\" \/><\/div><\/div><div class=\"w-vwrapper us_custom_f19a772e step align_center valign_top\"><div class=\"w-image us_custom_9f7541fa align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/i2.svg\" class=\"attachment-large size-large\" alt=\"i2\" \/><\/div><\/div><div class=\"w-text us_custom_befd4605 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Select day and time<\/span><\/span><\/div><div class=\"w-text us_custom_7a8df469 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Indicate the day and time you would like to participate in the adventure and leave us your contact information.<\/span><\/span><\/div><\/div><div class=\"w-image arrow-down-img align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down.png\" class=\"attachment-large size-large\" alt=\"arrow down\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down.png 102w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/arrow-down-30x300.png 30w\" sizes=\"auto, (max-width: 102px) 100vw, 102px\" \/><\/div><\/div><div class=\"w-vwrapper us_custom_f19a772e step align_center valign_top\"><div class=\"w-image us_custom_9f7541fa align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/i3.svg\" class=\"attachment-large size-large\" alt=\"i3\" \/><\/div><\/div><div class=\"w-text us_custom_befd4605 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Let&#8217;s hit the road!<\/span><\/span><\/div><div class=\"w-text us_custom_7a8df469 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">After payment, we will send you all the details. We will meet on the agreed day and time, and then&#8230; your adventure begins!<\/span><\/span><\/div><\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_8 us_custom_37c9ec7a grow_ellipse\" href=\"\/contacto\"><span class=\"w-btn-label\">More information<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_large with_img with_shape\" id=\"advantages-row\"><div class=\"l-section-img\" role=\"img\" data-img-width=\"1919\" data-img-height=\"833\" style=\"background-image: url(https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/image-9.webp);background-repeat: no-repeat;\"><\/div><div class=\"l-section-shape type_custom pos_top\" style=\"height:auto;\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"285\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapeup_1-scaled-e1776842945653.webp\" class=\"attachment-full size-full\" alt=\"shapeup 1\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapeup_1-scaled-e1776842945653.webp 1920w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapeup_1-scaled-e1776842945653-300x45.webp 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapeup_1-scaled-e1776842945653-1024x152.webp 1024w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapeup_1-scaled-e1776842945653-500x74.webp 500w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"l-section-shape type_custom pos_bottom\" style=\"height:auto;\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"176\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapebot-scaled.webp\" class=\"attachment-full size-full\" alt=\"shapebot\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapebot-scaled.webp 1920w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapebot-300x28.webp 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapebot-1024x94.webp 1024w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/shapebot-500x46.webp 500w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row us_custom_39390cfa via_flex valign_top type_default stacking_default\" id=\"custom-carousel-inner-row\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2a86e6a7 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"normal-text\">Why choose our routes<\/span> <span class=\"script\"> quads in Marbella?<\/span><\/h2>\n<\/div><\/div><div class=\"w-hwrapper custom-carousel desktop valign_top align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-vwrapper group-1 active align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"28\" height=\"44\" viewBox=\"0 0 28 44\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.9535 23.78L23.9835 40.832C24.053 41.2432 23.8601 41.6543 23.4994 41.8636C23.1387 42.0729 22.686 42.0364 22.3635 41.772L15.2035 36.398C14.4937 35.8677 13.5194 35.8677 12.8095 36.398L5.63755 41.77C5.31533 42.0339 4.8633 42.0705 4.50287 41.8618C4.14245 41.6531 3.9491 41.2428 4.01755 40.832L7.04555 23.78\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M2 14C2 20.623 7.37702 26 14 26C20.623 26 26 20.623 26 14C26 7.37702 20.623 2 14 2C7.37702 2 2 7.37702 2 14H2\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Experience and professionalism<\/h3><div class=\"w-iconbox-text\"><p>With years of experience in the quad biking industry, Aventuraalia has a team of highly trained and qualified professional guides, offering a safe and exciting quad biking experience that exceeds the expectations of our customers.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"46\" height=\"48\" viewBox=\"0 0 46 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M8.6542 23.8365H3.5234C1.58063 23.8365 0 25.4172 0 27.36V44.4765C0 46.4193 1.58063 48 3.5234 48H8.6542C10.597 48 12.1776 46.4193 12.1776 44.4765V27.36C12.1776 25.4172 10.597 23.8365 8.6542 23.8365ZM8.6542 46.468H3.5234C2.42533 46.468 1.53191 45.5746 1.53191 44.4765V42.3421H3.53351C3.95663 42.3421 4.29947 41.9992 4.29947 41.5761C4.29947 41.153 3.95663 40.8102 3.53351 40.8102H1.53191V36.6842H3.53351C3.95663 36.6842 4.29947 36.3414 4.29947 35.9183C4.29947 35.4951 3.95663 35.1523 3.53351 35.1523H1.53191V31.0263H3.53351C3.95663 31.0263 4.29947 30.6835 4.29947 30.2604C4.29947 29.8373 3.95663 29.4944 3.53351 29.4944H1.53191V27.36C1.53191 26.2619 2.42533 25.3685 3.5234 25.3685H8.6542C9.75227 25.3685 10.6457 26.2619 10.6457 27.36V29.4944H8.64408C8.22097 29.4944 7.87813 29.8373 7.87813 30.2604C7.87813 30.6835 8.22097 31.0263 8.64408 31.0263H10.6457V35.1523H8.64408C8.22097 35.1523 7.87813 35.4951 7.87813 35.9183C7.87813 36.3414 8.22097 36.6842 8.64408 36.6842H10.6457V40.8102H8.64408C8.22097 40.8102 7.87813 41.153 7.87813 41.5761C7.87813 41.9992 8.22097 42.3421 8.64408 42.3421H10.6457V44.4765C10.6457 45.5746 9.75227 46.468 8.6542 46.468Z\" fill=\"#8EC640\"\/>\n<path d=\"M30.9579 35.1523H14.4749C14.0518 35.1523 13.709 35.4952 13.709 35.9183C13.709 36.3414 14.0518 36.6843 14.4749 36.6843H30.9579C31.3811 36.6843 31.7239 36.3414 31.7239 35.9183C31.7239 35.4952 31.3811 35.1523 30.9579 35.1523Z\" fill=\"#8EC640\"\/>\n<path d=\"M13.8133 13.3267H4.32447C3.93363 13.3267 3.60549 13.6209 3.56301 14.0095L3.15889 17.7067C3.11436 18.1141 3.39858 18.4845 3.80372 18.5469L13.6963 20.0711C13.7351 20.0771 13.7741 20.0801 13.8129 20.0801C13.9945 20.0801 14.1718 20.0154 14.3116 19.8955C14.4813 19.75 14.5789 19.5376 14.5789 19.3141L14.5792 14.0927C14.5792 13.8896 14.4985 13.6948 14.3549 13.5511C14.2112 13.4073 14.0165 13.3267 13.8133 13.3267ZM13.0471 18.421L4.76137 17.1445L5.01118 14.8586H13.0473L13.0471 18.421Z\" fill=\"#8EC640\"\/>\n<path d=\"M19.0319 13.3267C18.6089 13.3267 18.2659 13.6695 18.2659 14.0926L18.2656 19.314C18.2656 19.737 18.6085 20.08 19.0316 20.08C19.4546 20.08 19.7975 19.7371 19.7975 19.314L19.7978 14.0926C19.7978 13.6697 19.455 13.3267 19.0319 13.3267Z\" fill=\"#8EC640\"\/>\n<path d=\"M22.7171 13.3267C22.294 13.3267 21.9512 13.6695 21.9512 14.0926V19.3078C21.9512 19.7309 22.294 20.0737 22.7171 20.0737C23.1402 20.0737 23.4831 19.7309 23.4831 19.3078V14.0926C23.4831 13.6696 23.1402 13.3267 22.7171 13.3267Z\" fill=\"#8EC640\"\/>\n<path d=\"M41.9101 23.8365H36.7793C34.8365 23.8365 33.2559 25.4172 33.2559 27.36V44.4765C33.2559 46.4193 34.8365 48 36.7793 48H41.9101C43.8528 48 45.4335 46.4193 45.4335 44.4765V27.36C45.4335 25.4172 43.8528 23.8365 41.9101 23.8365ZM41.9101 46.468H36.7793C35.6812 46.468 34.7878 45.5746 34.7878 44.4765V42.3421H36.7894C37.2125 42.3421 37.5553 41.9992 37.5553 41.5761C37.5553 41.153 37.2125 40.8102 36.7894 40.8102H34.7878V36.6842H36.7894C37.2125 36.6842 37.5553 36.3414 37.5553 35.9183C37.5553 35.4951 37.2125 35.1523 36.7894 35.1523H34.7878V31.0263H36.7894C37.2125 31.0263 37.5553 30.6835 37.5553 30.2604C37.5553 29.8373 37.2125 29.4944 36.7894 29.4944H34.7878V27.36C34.7878 26.2619 35.6812 25.3685 36.7793 25.3685H41.9101C43.0081 25.3685 43.9015 26.2619 43.9015 27.36V29.4944H41.8999C41.4768 29.4944 41.134 29.8373 41.134 30.2604C41.134 30.6835 41.4768 31.0263 41.8999 31.0263H43.9015V35.1523H41.8999C41.4768 35.1523 41.134 35.4951 41.134 35.9183C41.134 36.3414 41.4768 36.6842 41.8999 36.6842H43.9015V40.8102H41.8999C41.4768 40.8102 41.134 41.153 41.134 41.5761C41.134 41.9992 41.4768 42.3421 41.8999 42.3421H43.9015V44.4765C43.9015 45.5746 43.008 46.468 41.9101 46.468Z\" fill=\"#8EC640\"\/>\n<path d=\"M45.4173 18.2579L44.84 12.9758C44.6764 11.4799 43.3189 10.2627 41.814 10.2627H28.073L27.8177 8.73079H31.3634C32.4726 8.73079 33.7703 7.97515 34.3176 7.01045L35.6879 4.59574H41.8141C42.2372 4.59574 42.58 4.2529 42.58 3.82979C42.58 3.40667 42.2372 3.06383 41.8141 3.06383H36.5572L36.8907 2.47629C37.1711 1.98199 37.9441 1.53191 38.5124 1.53191H41.8141C42.2372 1.53191 42.58 1.18907 42.58 0.765957C42.58 0.342843 42.2372 0 41.8141 0H38.5124C37.4033 0 36.1057 0.755642 35.5583 1.72034L34.5693 3.46305C34.5679 3.4655 32.9851 6.2546 32.9851 6.2546C32.7048 6.7489 31.9318 7.19898 31.3633 7.19898H27.5623L27.1582 4.77518C27.0965 4.40589 26.7771 4.13515 26.4027 4.13515H19.0311C18.6567 4.13515 18.3372 4.40579 18.2756 4.77518L17.8716 7.19898H14.0704C13.5021 7.19898 12.729 6.7489 12.4486 6.2546L10.8659 3.46519C10.865 3.46356 9.87578 1.72034 9.87578 1.72034C9.32827 0.755642 8.03064 0 6.92153 0H3.61995C3.19684 0 2.85399 0.342843 2.85399 0.765957C2.85399 1.18907 3.19684 1.53191 3.61995 1.53191H6.92153C7.48977 1.53191 8.26288 1.98199 8.54342 2.47629L8.87677 3.06383H3.61995C3.19684 3.06383 2.85399 3.40667 2.85399 3.82979C2.85399 4.2529 3.19684 4.59574 3.61995 4.59574H9.74608L11.1163 7.01055C11.6636 7.97515 12.9613 8.73089 14.0705 8.73089H17.6163L17.361 10.2628H3.61995C2.1151 10.2628 0.75762 11.48 0.594011 12.976L0.0166839 18.2579C-0.14958 19.7793 0.945739 21.2066 2.45825 21.4396L13.2207 23.0977L16.2556 33.0774C16.3537 33.3999 16.6512 33.6204 16.9885 33.6204H28.4457C28.7829 33.6204 29.0804 33.3999 29.1785 33.0774L32.2136 23.0977L42.9759 21.4396C44.4884 21.2065 45.5836 19.7793 45.4173 18.2579ZM19.6801 5.66696H25.754L26.5199 10.2627H18.9143L19.6801 5.66696ZM31.5041 21.6571C31.213 21.7018 30.9735 21.9095 30.8878 22.1911L27.8778 32.0885H17.5561L14.5462 22.1912C14.4605 21.9094 14.2209 21.7018 13.9299 21.6571L2.69151 19.9255C1.98999 19.8174 1.4624 19.1299 1.53961 18.4243L2.11684 13.1424C2.1967 12.4118 2.88504 11.7946 3.61995 11.7946H27.421C27.4244 11.7946 41.8141 11.7946 41.8141 11.7946C42.549 11.7946 43.2374 12.4118 43.3173 13.1423L43.8945 18.4243C43.9717 19.1299 43.4441 19.8175 42.7426 19.9255L31.5041 21.6571Z\" fill=\"#8EC640\"\/>\n<path d=\"M41.8717 14.0095C41.8292 13.6209 41.501 13.3267 41.1102 13.3267H31.6214C31.4183 13.3267 31.2235 13.4073 31.0797 13.551C30.9361 13.6946 30.8555 13.8894 30.8555 14.0926L30.8558 19.314C30.8558 19.5375 30.9534 19.75 31.123 19.8954C31.2629 20.0153 31.44 20.08 31.6217 20.08C31.6605 20.08 31.6996 20.077 31.7384 20.071L41.631 18.5468C42.0362 18.4845 42.3203 18.1141 42.2758 17.7066L41.8717 14.0095ZM32.3876 18.421L32.3874 14.8586H40.4235L40.6733 17.1445L32.3876 18.421Z\" fill=\"#8EC640\"\/>\n<path d=\"M26.4027 13.3267C25.9796 13.3267 25.6367 13.6696 25.6367 14.0926L25.6369 19.314C25.6369 19.7371 25.9799 20.08 26.4029 20.08C26.826 20.08 27.1688 19.737 27.1688 19.314L27.1686 14.0926C27.1686 13.6696 26.8256 13.3267 26.4027 13.3267Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">High-end quads<\/h3><div class=\"w-iconbox-text\"><p>At Aventuraalia, we have a team of high quality quads in perfect condition. Each of our vehicles is perfectly maintained to ensure the safety of our customers.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-2 align_none valign_top\" style=\"--vwrapper-gap:0rem\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"44\" height=\"48\" viewBox=\"0 0 44 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M42.2837 34.4233C44.5297 29.0015 44.5299 23.0295 42.2841 17.6072C40.2651 12.7325 36.628 8.81223 31.963 6.44136L33.0125 3.89213C33.3076 3.17535 32.9669 2.35501 32.2508 2.05819C25.6308 -0.68569 18.3386 -0.686064 11.7178 2.05707C11.0016 2.35379 10.6608 3.17423 10.956 3.8911L12.0054 6.44023C7.34637 8.80792 3.71344 12.7212 1.69365 17.5872C1.69056 17.5942 1.68756 17.6012 1.68465 17.6084C-0.56138 23.0301 -0.561567 29.0022 1.68419 34.4245C3.92788 39.8407 8.143 44.0592 13.554 46.3056C18.9805 48.5616 24.9636 48.5644 30.3929 46.3156C35.8095 44.0717 40.0283 39.8561 42.2745 34.4445C42.2777 34.4375 42.2807 34.4304 42.2837 34.4233ZM32.0981 28.6837C32.5646 26.9302 32.5646 25.1014 32.0981 23.348L40.1776 20.0015C41.4808 23.9245 41.4806 28.1076 40.1768 32.0302L32.0981 28.6837ZM24.9111 33.0806C24.911 33.0806 24.911 33.0806 24.9109 33.0806C23.0237 33.8624 20.9452 33.8626 19.0576 33.0808C17.1704 32.2992 15.7008 30.8296 14.9192 28.9426C14.1571 27.1032 14.1388 25.0699 14.8676 23.2174C15.5946 21.3695 16.9861 19.8963 18.7816 19.0711C20.7824 18.1433 23.1814 18.1404 25.1821 19.0699C26.9367 19.8768 28.31 21.3041 29.0492 23.0889C29.831 24.9761 29.8311 27.0548 29.0493 28.9422C28.2676 30.8295 26.798 32.2992 24.9111 33.0806ZM3.79067 32.0301C2.48747 28.1072 2.48766 23.9242 3.79142 20.0015L11.8708 23.3482C11.4054 25.1019 11.406 26.9327 11.8706 28.6835L3.79067 32.0301ZM39.1008 17.4042L31.0207 20.7509C30.1708 19.2891 28.9822 18.0608 27.5493 17.1622L30.8892 9.04944C34.4465 10.9102 37.3 13.8142 39.1008 17.4042ZM29.8632 4.15549L24.9876 15.999C23.041 15.4164 20.9275 15.4155 18.9808 15.9982L14.1052 4.15474C19.2333 2.36597 24.7359 2.36626 29.8632 4.15549ZM13.079 9.04841L16.4181 17.1595C14.983 18.0585 13.7961 19.2869 12.9465 20.7506L4.86809 17.4042C6.66839 13.8135 9.52164 10.9091 13.079 9.04841ZM4.86668 34.6278L12.9461 31.2814C13.8561 32.8508 15.149 34.1438 16.7186 35.0539L13.3721 43.1327C9.67703 41.2816 6.71918 38.3239 4.86668 34.6278ZM15.9698 44.2085L19.3162 36.1298C21.0696 36.597 22.8984 36.5969 24.6519 36.1298L27.9984 44.2093C24.0756 45.5125 19.8926 45.5123 15.9698 44.2085ZM30.5961 43.1333L27.2496 35.0538C28.819 34.1438 30.1121 32.8508 31.0221 31.2813L39.1011 34.6278C37.2499 38.323 34.2922 41.2808 30.5961 43.1333Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Variety of options<\/h3><div class=\"w-iconbox-text\"><p>We offer a wide variety of tours for our clients. From 1, 2 or 3 hour tours to customized tours, we can adapt to the needs and preferences of our clients, ensuring they have the best possible experience.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_4734_12539)\">\n<path d=\"M46.4985 23.6802C44.8936 22.3574 42.3569 22.244 40.692 24.0308L36.5588 28.4677C36.0245 26.7503 34.4205 25.4998 32.5298 25.4998H25.154C24.5943 25.4998 24.4069 25.286 23.4347 24.537C19.728 21.3057 14.1606 21.316 10.4651 24.568L7.75406 26.9547C6.53541 26.3097 5.11238 26.2937 3.88706 26.9059L0.777563 28.4602C0.0828757 28.808 -0.198281 29.6526 0.148501 30.3473L8.58553 47.2213C8.93334 47.9159 9.77794 48.1971 10.4726 47.8503L13.5821 46.2951C15.1148 45.5293 15.9679 43.9655 15.9126 42.3738H32.5297C35.611 42.3738 38.5555 40.902 40.4042 38.4366L47.1548 29.4353C48.4643 27.6906 48.2572 25.1323 46.4985 23.6802ZM12.324 43.7799L10.4725 44.706L3.29269 30.3473L5.14509 29.4211C5.83978 29.0743 6.68344 29.3546 7.03125 30.0502L12.9531 41.8938C13.2999 42.5884 13.0187 43.4321 12.324 43.7799ZM44.9048 27.7478L38.1544 36.7491C36.8335 38.5106 34.7308 39.5614 32.5298 39.5614H14.9311L9.66169 29.0218L12.3231 26.6791C14.9713 24.3495 18.9649 24.3495 21.6131 26.6791C23.173 28.0525 24.1433 28.3122 25.1539 28.3122H32.5297C33.305 28.3122 33.9358 28.9431 33.9358 29.7183C33.9358 30.4935 33.3049 31.1245 32.5297 31.1245H25.3479C24.5717 31.1245 23.9418 31.7545 23.9418 32.5306C23.9418 33.3068 24.5718 33.9368 25.3479 33.9368H33.4718C34.6389 33.9368 35.7639 33.4474 36.5588 32.5934L42.7497 25.9479C43.316 25.3404 44.184 25.391 44.7165 25.8569C45.2733 26.3443 45.3334 27.1778 44.9048 27.7478Z\" fill=\"#8EC640\"\/>\n<path d=\"M29.5679 9.59691C30.5306 8.58731 31.1241 7.22241 31.1241 5.7196C31.1241 2.62416 28.623 0.0012207 25.4994 0.0012207C22.3993 0.0012207 19.7811 2.61947 19.7811 5.7196C19.7811 7.17638 20.352 8.5516 21.3888 9.60816C18.8174 11.0499 16.9688 13.8173 16.9688 17.0627V18.4688C16.9688 19.245 17.5987 19.875 18.3749 19.875H32.5303C33.3065 19.875 33.9365 19.245 33.9365 18.4688V17.0627C33.9364 13.881 32.1863 11.0706 29.5679 9.59691ZM25.4994 2.81363C27.0237 2.81363 28.3117 4.14478 28.3117 5.71969C28.3117 7.27022 27.05 8.532 25.4994 8.532C23.9245 8.532 22.5934 7.24397 22.5934 5.71969C22.5934 4.17197 23.9517 2.81363 25.4994 2.81363ZM19.7811 17.0627C19.7811 13.9626 22.3993 11.3443 25.4994 11.3443C28.6005 11.3443 31.1241 13.9091 31.1241 17.0627H19.7811Z\" fill=\"#8EC640\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_4734_12539\">\n<rect width=\"48\" height=\"48\" fill=\"white\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Personalized service<\/h3><div class=\"w-iconbox-text\"><p>We believe that each client is unique and deserves personalized service. That is why, at Aventuraalia, we strive to provide an exceptional and personalized service to each of our clients, making sure they have an unforgettable experience.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-3 align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"42\" height=\"48\" viewBox=\"0 0 42 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.625 40.1333C19.2548 40.1333 17.9304 39.6314 16.8956 38.72C11.9861 34.3958 3.75 25.8078 3.75 16.875C3.75 7.57013 11.3201 0 20.625 0C29.9299 0 37.5 7.57013 37.5 16.875C37.5 25.8078 29.2638 34.3958 24.3543 38.72C23.3196 39.6314 21.9952 40.1333 20.625 40.1333ZM20.625 3.75C13.3879 3.75 7.5 9.63787 7.5 16.875C7.5 24.612 15.804 32.7613 19.3742 35.906C19.7238 36.2138 20.168 36.3834 20.625 36.3834C21.082 36.3834 21.5262 36.2138 21.8757 35.906C25.446 32.7613 33.75 24.612 33.75 16.875C33.75 9.63787 27.8621 3.75 20.625 3.75Z\" fill=\"#8EC640\"\/>\n<path d=\"M20.625 48C15.4392 48 10.5394 47.3868 6.828 46.2734C4.91034 45.6982 3.37481 45.0069 2.26378 44.2189C0.392719 42.8919 0 41.4641 0 40.5C0 39.4767 0.440906 37.9679 2.54128 36.592C3.79434 35.7711 5.5185 35.0637 7.66594 34.4892C8.66606 34.2217 9.69422 34.8155 9.96178 35.8159C10.2293 36.8162 9.63544 37.8441 8.63503 38.1118C4.97672 39.0905 3.88903 40.1984 3.75741 40.5C3.88519 40.7911 4.92272 41.8589 8.39503 42.8229C11.7102 43.7432 16.0536 44.25 20.625 44.25C25.1964 44.25 29.5398 43.7432 32.855 42.8229C36.3274 41.8589 37.3648 40.7911 37.4926 40.5C37.3611 40.1985 36.2732 39.0905 32.615 38.1119C31.6147 37.8442 31.0207 36.8163 31.2883 35.8159C31.5559 34.8156 32.5834 34.2215 33.5842 34.4893C35.7315 35.0637 37.4557 35.7712 38.7087 36.5921C40.8091 37.9679 41.25 39.4767 41.25 40.5C41.25 41.4641 40.8573 42.8919 38.9863 44.2189C37.8753 45.0069 36.3397 45.6982 34.422 46.2734C30.7106 47.3868 25.8107 48 20.625 48Z\" fill=\"#8EC640\"\/>\n<path d=\"M20.625 24.375C16.4895 24.375 13.125 21.0105 13.125 16.875C13.125 12.7395 16.4895 9.375 20.625 9.375C24.7605 9.375 28.125 12.7395 28.125 16.875C28.125 21.0105 24.7605 24.375 20.625 24.375ZM20.625 13.125C18.5573 13.125 16.875 14.8073 16.875 16.875C16.875 18.9427 18.5573 20.625 20.625 20.625C22.6927 20.625 24.375 18.9427 24.375 16.875C24.375 14.8073 22.6927 13.125 20.625 13.125Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Privileged location<\/h3><div class=\"w-iconbox-text\"><p>Our location in Mijas (M\u00e1laga) gives us the opportunity to offer our clients some of the most beautiful panoramic views in Spain. Our quad routes take you through some of the most breathtaking scenery in Malaga making the experience even more memorable.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"28\" height=\"44\" viewBox=\"0 0 28 44\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.9535 23.78L23.9835 40.832C24.053 41.2432 23.8601 41.6543 23.4994 41.8636C23.1387 42.0729 22.686 42.0364 22.3635 41.772L15.2035 36.398C14.4937 35.8677 13.5194 35.8677 12.8095 36.398L5.63755 41.77C5.31533 42.0339 4.8633 42.0705 4.50287 41.8618C4.14245 41.6531 3.9491 41.2428 4.01755 40.832L7.04555 23.78\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M2 14C2 20.623 7.37702 26 14 26C20.623 26 26 20.623 26 14C26 7.37702 20.623 2 14 2C7.37702 2 2 7.37702 2 14H2\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">The best facilities<\/h3><div class=\"w-iconbox-text\"><p>We have 1000m2 facilities located in the best area of the city, which makes them the most comfortable option for our customers. We have easy access and ample parking spaces for the attention of our customers.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-hwrapper custom-carousel mobile valign_top align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-vwrapper group-1 active align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"28\" height=\"44\" viewBox=\"0 0 28 44\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.9535 23.78L23.9835 40.832C24.053 41.2432 23.8601 41.6543 23.4994 41.8636C23.1387 42.0729 22.686 42.0364 22.3635 41.772L15.2035 36.398C14.4937 35.8677 13.5194 35.8677 12.8095 36.398L5.63755 41.77C5.31533 42.0339 4.8633 42.0705 4.50287 41.8618C4.14245 41.6531 3.9491 41.2428 4.01755 40.832L7.04555 23.78\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M2 14C2 20.623 7.37702 26 14 26C20.623 26 26 20.623 26 14C26 7.37702 20.623 2 14 2C7.37702 2 2 7.37702 2 14H2\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Experience and professionalism<\/h3><div class=\"w-iconbox-text\"><p>With years of experience in the quad biking industry, Aventuraalia has a team of highly trained and qualified professional guides, offering a safe and exciting quad biking experience that exceeds the expectations of our customers.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-1 align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"46\" height=\"48\" viewBox=\"0 0 46 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M8.6542 23.8365H3.5234C1.58063 23.8365 0 25.4172 0 27.36V44.4765C0 46.4193 1.58063 48 3.5234 48H8.6542C10.597 48 12.1776 46.4193 12.1776 44.4765V27.36C12.1776 25.4172 10.597 23.8365 8.6542 23.8365ZM8.6542 46.468H3.5234C2.42533 46.468 1.53191 45.5746 1.53191 44.4765V42.3421H3.53351C3.95663 42.3421 4.29947 41.9992 4.29947 41.5761C4.29947 41.153 3.95663 40.8102 3.53351 40.8102H1.53191V36.6842H3.53351C3.95663 36.6842 4.29947 36.3414 4.29947 35.9183C4.29947 35.4951 3.95663 35.1523 3.53351 35.1523H1.53191V31.0263H3.53351C3.95663 31.0263 4.29947 30.6835 4.29947 30.2604C4.29947 29.8373 3.95663 29.4944 3.53351 29.4944H1.53191V27.36C1.53191 26.2619 2.42533 25.3685 3.5234 25.3685H8.6542C9.75227 25.3685 10.6457 26.2619 10.6457 27.36V29.4944H8.64408C8.22097 29.4944 7.87813 29.8373 7.87813 30.2604C7.87813 30.6835 8.22097 31.0263 8.64408 31.0263H10.6457V35.1523H8.64408C8.22097 35.1523 7.87813 35.4951 7.87813 35.9183C7.87813 36.3414 8.22097 36.6842 8.64408 36.6842H10.6457V40.8102H8.64408C8.22097 40.8102 7.87813 41.153 7.87813 41.5761C7.87813 41.9992 8.22097 42.3421 8.64408 42.3421H10.6457V44.4765C10.6457 45.5746 9.75227 46.468 8.6542 46.468Z\" fill=\"#8EC640\"\/>\n<path d=\"M30.9579 35.1523H14.4749C14.0518 35.1523 13.709 35.4952 13.709 35.9183C13.709 36.3414 14.0518 36.6843 14.4749 36.6843H30.9579C31.3811 36.6843 31.7239 36.3414 31.7239 35.9183C31.7239 35.4952 31.3811 35.1523 30.9579 35.1523Z\" fill=\"#8EC640\"\/>\n<path d=\"M13.8133 13.3267H4.32447C3.93363 13.3267 3.60549 13.6209 3.56301 14.0095L3.15889 17.7067C3.11436 18.1141 3.39858 18.4845 3.80372 18.5469L13.6963 20.0711C13.7351 20.0771 13.7741 20.0801 13.8129 20.0801C13.9945 20.0801 14.1718 20.0154 14.3116 19.8955C14.4813 19.75 14.5789 19.5376 14.5789 19.3141L14.5792 14.0927C14.5792 13.8896 14.4985 13.6948 14.3549 13.5511C14.2112 13.4073 14.0165 13.3267 13.8133 13.3267ZM13.0471 18.421L4.76137 17.1445L5.01118 14.8586H13.0473L13.0471 18.421Z\" fill=\"#8EC640\"\/>\n<path d=\"M19.0319 13.3267C18.6089 13.3267 18.2659 13.6695 18.2659 14.0926L18.2656 19.314C18.2656 19.737 18.6085 20.08 19.0316 20.08C19.4546 20.08 19.7975 19.7371 19.7975 19.314L19.7978 14.0926C19.7978 13.6697 19.455 13.3267 19.0319 13.3267Z\" fill=\"#8EC640\"\/>\n<path d=\"M22.7171 13.3267C22.294 13.3267 21.9512 13.6695 21.9512 14.0926V19.3078C21.9512 19.7309 22.294 20.0737 22.7171 20.0737C23.1402 20.0737 23.4831 19.7309 23.4831 19.3078V14.0926C23.4831 13.6696 23.1402 13.3267 22.7171 13.3267Z\" fill=\"#8EC640\"\/>\n<path d=\"M41.9101 23.8365H36.7793C34.8365 23.8365 33.2559 25.4172 33.2559 27.36V44.4765C33.2559 46.4193 34.8365 48 36.7793 48H41.9101C43.8528 48 45.4335 46.4193 45.4335 44.4765V27.36C45.4335 25.4172 43.8528 23.8365 41.9101 23.8365ZM41.9101 46.468H36.7793C35.6812 46.468 34.7878 45.5746 34.7878 44.4765V42.3421H36.7894C37.2125 42.3421 37.5553 41.9992 37.5553 41.5761C37.5553 41.153 37.2125 40.8102 36.7894 40.8102H34.7878V36.6842H36.7894C37.2125 36.6842 37.5553 36.3414 37.5553 35.9183C37.5553 35.4951 37.2125 35.1523 36.7894 35.1523H34.7878V31.0263H36.7894C37.2125 31.0263 37.5553 30.6835 37.5553 30.2604C37.5553 29.8373 37.2125 29.4944 36.7894 29.4944H34.7878V27.36C34.7878 26.2619 35.6812 25.3685 36.7793 25.3685H41.9101C43.0081 25.3685 43.9015 26.2619 43.9015 27.36V29.4944H41.8999C41.4768 29.4944 41.134 29.8373 41.134 30.2604C41.134 30.6835 41.4768 31.0263 41.8999 31.0263H43.9015V35.1523H41.8999C41.4768 35.1523 41.134 35.4951 41.134 35.9183C41.134 36.3414 41.4768 36.6842 41.8999 36.6842H43.9015V40.8102H41.8999C41.4768 40.8102 41.134 41.153 41.134 41.5761C41.134 41.9992 41.4768 42.3421 41.8999 42.3421H43.9015V44.4765C43.9015 45.5746 43.008 46.468 41.9101 46.468Z\" fill=\"#8EC640\"\/>\n<path d=\"M45.4173 18.2579L44.84 12.9758C44.6764 11.4799 43.3189 10.2627 41.814 10.2627H28.073L27.8177 8.73079H31.3634C32.4726 8.73079 33.7703 7.97515 34.3176 7.01045L35.6879 4.59574H41.8141C42.2372 4.59574 42.58 4.2529 42.58 3.82979C42.58 3.40667 42.2372 3.06383 41.8141 3.06383H36.5572L36.8907 2.47629C37.1711 1.98199 37.9441 1.53191 38.5124 1.53191H41.8141C42.2372 1.53191 42.58 1.18907 42.58 0.765957C42.58 0.342843 42.2372 0 41.8141 0H38.5124C37.4033 0 36.1057 0.755642 35.5583 1.72034L34.5693 3.46305C34.5679 3.4655 32.9851 6.2546 32.9851 6.2546C32.7048 6.7489 31.9318 7.19898 31.3633 7.19898H27.5623L27.1582 4.77518C27.0965 4.40589 26.7771 4.13515 26.4027 4.13515H19.0311C18.6567 4.13515 18.3372 4.40579 18.2756 4.77518L17.8716 7.19898H14.0704C13.5021 7.19898 12.729 6.7489 12.4486 6.2546L10.8659 3.46519C10.865 3.46356 9.87578 1.72034 9.87578 1.72034C9.32827 0.755642 8.03064 0 6.92153 0H3.61995C3.19684 0 2.85399 0.342843 2.85399 0.765957C2.85399 1.18907 3.19684 1.53191 3.61995 1.53191H6.92153C7.48977 1.53191 8.26288 1.98199 8.54342 2.47629L8.87677 3.06383H3.61995C3.19684 3.06383 2.85399 3.40667 2.85399 3.82979C2.85399 4.2529 3.19684 4.59574 3.61995 4.59574H9.74608L11.1163 7.01055C11.6636 7.97515 12.9613 8.73089 14.0705 8.73089H17.6163L17.361 10.2628H3.61995C2.1151 10.2628 0.75762 11.48 0.594011 12.976L0.0166839 18.2579C-0.14958 19.7793 0.945739 21.2066 2.45825 21.4396L13.2207 23.0977L16.2556 33.0774C16.3537 33.3999 16.6512 33.6204 16.9885 33.6204H28.4457C28.7829 33.6204 29.0804 33.3999 29.1785 33.0774L32.2136 23.0977L42.9759 21.4396C44.4884 21.2065 45.5836 19.7793 45.4173 18.2579ZM19.6801 5.66696H25.754L26.5199 10.2627H18.9143L19.6801 5.66696ZM31.5041 21.6571C31.213 21.7018 30.9735 21.9095 30.8878 22.1911L27.8778 32.0885H17.5561L14.5462 22.1912C14.4605 21.9094 14.2209 21.7018 13.9299 21.6571L2.69151 19.9255C1.98999 19.8174 1.4624 19.1299 1.53961 18.4243L2.11684 13.1424C2.1967 12.4118 2.88504 11.7946 3.61995 11.7946H27.421C27.4244 11.7946 41.8141 11.7946 41.8141 11.7946C42.549 11.7946 43.2374 12.4118 43.3173 13.1423L43.8945 18.4243C43.9717 19.1299 43.4441 19.8175 42.7426 19.9255L31.5041 21.6571Z\" fill=\"#8EC640\"\/>\n<path d=\"M41.8717 14.0095C41.8292 13.6209 41.501 13.3267 41.1102 13.3267H31.6214C31.4183 13.3267 31.2235 13.4073 31.0797 13.551C30.9361 13.6946 30.8555 13.8894 30.8555 14.0926L30.8558 19.314C30.8558 19.5375 30.9534 19.75 31.123 19.8954C31.2629 20.0153 31.44 20.08 31.6217 20.08C31.6605 20.08 31.6996 20.077 31.7384 20.071L41.631 18.5468C42.0362 18.4845 42.3203 18.1141 42.2758 17.7066L41.8717 14.0095ZM32.3876 18.421L32.3874 14.8586H40.4235L40.6733 17.1445L32.3876 18.421Z\" fill=\"#8EC640\"\/>\n<path d=\"M26.4027 13.3267C25.9796 13.3267 25.6367 13.6696 25.6367 14.0926L25.6369 19.314C25.6369 19.7371 25.9799 20.08 26.4029 20.08C26.826 20.08 27.1688 19.737 27.1688 19.314L27.1686 14.0926C27.1686 13.6696 26.8256 13.3267 26.4027 13.3267Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">High-end quads<\/h3><div class=\"w-iconbox-text\"><p>At Aventuraalia, we have a team of high quality quads in perfect condition. Each of our vehicles is perfectly maintained to ensure the safety of our customers.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-2 align_none valign_top\" style=\"--vwrapper-gap:0rem\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"44\" height=\"48\" viewBox=\"0 0 44 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M42.2837 34.4233C44.5297 29.0015 44.5299 23.0295 42.2841 17.6072C40.2651 12.7325 36.628 8.81223 31.963 6.44136L33.0125 3.89213C33.3076 3.17535 32.9669 2.35501 32.2508 2.05819C25.6308 -0.68569 18.3386 -0.686064 11.7178 2.05707C11.0016 2.35379 10.6608 3.17423 10.956 3.8911L12.0054 6.44023C7.34637 8.80792 3.71344 12.7212 1.69365 17.5872C1.69056 17.5942 1.68756 17.6012 1.68465 17.6084C-0.56138 23.0301 -0.561567 29.0022 1.68419 34.4245C3.92788 39.8407 8.143 44.0592 13.554 46.3056C18.9805 48.5616 24.9636 48.5644 30.3929 46.3156C35.8095 44.0717 40.0283 39.8561 42.2745 34.4445C42.2777 34.4375 42.2807 34.4304 42.2837 34.4233ZM32.0981 28.6837C32.5646 26.9302 32.5646 25.1014 32.0981 23.348L40.1776 20.0015C41.4808 23.9245 41.4806 28.1076 40.1768 32.0302L32.0981 28.6837ZM24.9111 33.0806C24.911 33.0806 24.911 33.0806 24.9109 33.0806C23.0237 33.8624 20.9452 33.8626 19.0576 33.0808C17.1704 32.2992 15.7008 30.8296 14.9192 28.9426C14.1571 27.1032 14.1388 25.0699 14.8676 23.2174C15.5946 21.3695 16.9861 19.8963 18.7816 19.0711C20.7824 18.1433 23.1814 18.1404 25.1821 19.0699C26.9367 19.8768 28.31 21.3041 29.0492 23.0889C29.831 24.9761 29.8311 27.0548 29.0493 28.9422C28.2676 30.8295 26.798 32.2992 24.9111 33.0806ZM3.79067 32.0301C2.48747 28.1072 2.48766 23.9242 3.79142 20.0015L11.8708 23.3482C11.4054 25.1019 11.406 26.9327 11.8706 28.6835L3.79067 32.0301ZM39.1008 17.4042L31.0207 20.7509C30.1708 19.2891 28.9822 18.0608 27.5493 17.1622L30.8892 9.04944C34.4465 10.9102 37.3 13.8142 39.1008 17.4042ZM29.8632 4.15549L24.9876 15.999C23.041 15.4164 20.9275 15.4155 18.9808 15.9982L14.1052 4.15474C19.2333 2.36597 24.7359 2.36626 29.8632 4.15549ZM13.079 9.04841L16.4181 17.1595C14.983 18.0585 13.7961 19.2869 12.9465 20.7506L4.86809 17.4042C6.66839 13.8135 9.52164 10.9091 13.079 9.04841ZM4.86668 34.6278L12.9461 31.2814C13.8561 32.8508 15.149 34.1438 16.7186 35.0539L13.3721 43.1327C9.67703 41.2816 6.71918 38.3239 4.86668 34.6278ZM15.9698 44.2085L19.3162 36.1298C21.0696 36.597 22.8984 36.5969 24.6519 36.1298L27.9984 44.2093C24.0756 45.5125 19.8926 45.5123 15.9698 44.2085ZM30.5961 43.1333L27.2496 35.0538C28.819 34.1438 30.1121 32.8508 31.0221 31.2813L39.1011 34.6278C37.2499 38.323 34.2922 41.2808 30.5961 43.1333Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Variety of options<\/h3><div class=\"w-iconbox-text\"><p>We offer a wide variety of tours for our clients. From 1, 2 or 3 hour tours to customized tours, we can adapt to the needs and preferences of our clients, ensuring they have the best possible experience.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-2 align_none valign_top\" style=\"--vwrapper-gap:0rem\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_4734_12539)\">\n<path d=\"M46.4985 23.6802C44.8936 22.3574 42.3569 22.244 40.692 24.0308L36.5588 28.4677C36.0245 26.7503 34.4205 25.4998 32.5298 25.4998H25.154C24.5943 25.4998 24.4069 25.286 23.4347 24.537C19.728 21.3057 14.1606 21.316 10.4651 24.568L7.75406 26.9547C6.53541 26.3097 5.11238 26.2937 3.88706 26.9059L0.777563 28.4602C0.0828757 28.808 -0.198281 29.6526 0.148501 30.3473L8.58553 47.2213C8.93334 47.9159 9.77794 48.1971 10.4726 47.8503L13.5821 46.2951C15.1148 45.5293 15.9679 43.9655 15.9126 42.3738H32.5297C35.611 42.3738 38.5555 40.902 40.4042 38.4366L47.1548 29.4353C48.4643 27.6906 48.2572 25.1323 46.4985 23.6802ZM12.324 43.7799L10.4725 44.706L3.29269 30.3473L5.14509 29.4211C5.83978 29.0743 6.68344 29.3546 7.03125 30.0502L12.9531 41.8938C13.2999 42.5884 13.0187 43.4321 12.324 43.7799ZM44.9048 27.7478L38.1544 36.7491C36.8335 38.5106 34.7308 39.5614 32.5298 39.5614H14.9311L9.66169 29.0218L12.3231 26.6791C14.9713 24.3495 18.9649 24.3495 21.6131 26.6791C23.173 28.0525 24.1433 28.3122 25.1539 28.3122H32.5297C33.305 28.3122 33.9358 28.9431 33.9358 29.7183C33.9358 30.4935 33.3049 31.1245 32.5297 31.1245H25.3479C24.5717 31.1245 23.9418 31.7545 23.9418 32.5306C23.9418 33.3068 24.5718 33.9368 25.3479 33.9368H33.4718C34.6389 33.9368 35.7639 33.4474 36.5588 32.5934L42.7497 25.9479C43.316 25.3404 44.184 25.391 44.7165 25.8569C45.2733 26.3443 45.3334 27.1778 44.9048 27.7478Z\" fill=\"#8EC640\"\/>\n<path d=\"M29.5679 9.59691C30.5306 8.58731 31.1241 7.22241 31.1241 5.7196C31.1241 2.62416 28.623 0.0012207 25.4994 0.0012207C22.3993 0.0012207 19.7811 2.61947 19.7811 5.7196C19.7811 7.17638 20.352 8.5516 21.3888 9.60816C18.8174 11.0499 16.9688 13.8173 16.9688 17.0627V18.4688C16.9688 19.245 17.5987 19.875 18.3749 19.875H32.5303C33.3065 19.875 33.9365 19.245 33.9365 18.4688V17.0627C33.9364 13.881 32.1863 11.0706 29.5679 9.59691ZM25.4994 2.81363C27.0237 2.81363 28.3117 4.14478 28.3117 5.71969C28.3117 7.27022 27.05 8.532 25.4994 8.532C23.9245 8.532 22.5934 7.24397 22.5934 5.71969C22.5934 4.17197 23.9517 2.81363 25.4994 2.81363ZM19.7811 17.0627C19.7811 13.9626 22.3993 11.3443 25.4994 11.3443C28.6005 11.3443 31.1241 13.9091 31.1241 17.0627H19.7811Z\" fill=\"#8EC640\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_4734_12539\">\n<rect width=\"48\" height=\"48\" fill=\"white\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Personalized service<\/h3><div class=\"w-iconbox-text\"><p>We believe that each client is unique and deserves personalized service. That is why, at Aventuraalia, we strive to provide an exceptional and personalized service to each of our clients, making sure they have an unforgettable experience.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-3 align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"42\" height=\"48\" viewBox=\"0 0 42 48\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.625 40.1333C19.2548 40.1333 17.9304 39.6314 16.8956 38.72C11.9861 34.3958 3.75 25.8078 3.75 16.875C3.75 7.57013 11.3201 0 20.625 0C29.9299 0 37.5 7.57013 37.5 16.875C37.5 25.8078 29.2638 34.3958 24.3543 38.72C23.3196 39.6314 21.9952 40.1333 20.625 40.1333ZM20.625 3.75C13.3879 3.75 7.5 9.63787 7.5 16.875C7.5 24.612 15.804 32.7613 19.3742 35.906C19.7238 36.2138 20.168 36.3834 20.625 36.3834C21.082 36.3834 21.5262 36.2138 21.8757 35.906C25.446 32.7613 33.75 24.612 33.75 16.875C33.75 9.63787 27.8621 3.75 20.625 3.75Z\" fill=\"#8EC640\"\/>\n<path d=\"M20.625 48C15.4392 48 10.5394 47.3868 6.828 46.2734C4.91034 45.6982 3.37481 45.0069 2.26378 44.2189C0.392719 42.8919 0 41.4641 0 40.5C0 39.4767 0.440906 37.9679 2.54128 36.592C3.79434 35.7711 5.5185 35.0637 7.66594 34.4892C8.66606 34.2217 9.69422 34.8155 9.96178 35.8159C10.2293 36.8162 9.63544 37.8441 8.63503 38.1118C4.97672 39.0905 3.88903 40.1984 3.75741 40.5C3.88519 40.7911 4.92272 41.8589 8.39503 42.8229C11.7102 43.7432 16.0536 44.25 20.625 44.25C25.1964 44.25 29.5398 43.7432 32.855 42.8229C36.3274 41.8589 37.3648 40.7911 37.4926 40.5C37.3611 40.1985 36.2732 39.0905 32.615 38.1119C31.6147 37.8442 31.0207 36.8163 31.2883 35.8159C31.5559 34.8156 32.5834 34.2215 33.5842 34.4893C35.7315 35.0637 37.4557 35.7712 38.7087 36.5921C40.8091 37.9679 41.25 39.4767 41.25 40.5C41.25 41.4641 40.8573 42.8919 38.9863 44.2189C37.8753 45.0069 36.3397 45.6982 34.422 46.2734C30.7106 47.3868 25.8107 48 20.625 48Z\" fill=\"#8EC640\"\/>\n<path d=\"M20.625 24.375C16.4895 24.375 13.125 21.0105 13.125 16.875C13.125 12.7395 16.4895 9.375 20.625 9.375C24.7605 9.375 28.125 12.7395 28.125 16.875C28.125 21.0105 24.7605 24.375 20.625 24.375ZM20.625 13.125C18.5573 13.125 16.875 14.8073 16.875 16.875C16.875 18.9427 18.5573 20.625 20.625 20.625C22.6927 20.625 24.375 18.9427 24.375 16.875C24.375 14.8073 22.6927 13.125 20.625 13.125Z\" fill=\"#8EC640\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">Privileged location<\/h3><div class=\"w-iconbox-text\"><p>Our location in Mijas (M\u00e1laga) gives us the opportunity to offer our clients some of the most beautiful panoramic views in Spain. Our quad routes take you through some of the most breathtaking scenery in Malaga making the experience even more memorable.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-vwrapper group-3 align_none valign_top\" style=\"--vwrapper-gap:0px\"><div class=\"w-iconbox us_custom_1972ce9d slide-item has_text_color iconpos_top style_default color_custom align_center icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><svg width=\"28\" height=\"44\" viewBox=\"0 0 28 44\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.9535 23.78L23.9835 40.832C24.053 41.2432 23.8601 41.6543 23.4994 41.8636C23.1387 42.0729 22.686 42.0364 22.3635 41.772L15.2035 36.398C14.4937 35.8677 13.5194 35.8677 12.8095 36.398L5.63755 41.77C5.31533 42.0339 4.8633 42.0705 4.50287 41.8618C4.14245 41.6531 3.9491 41.2428 4.01755 40.832L7.04555 23.78\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M2 14C2 20.623 7.37702 26 14 26C20.623 26 26 20.623 26 14C26 7.37702 20.623 2 14 2C7.37702 2 2 7.37702 2 14H2\" stroke=\"#8DC63F\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\" style=\"font-size:22px;\">The best facilities<\/h3><div class=\"w-iconbox-text\"><p>We have 1000m2 facilities located in the best area of the city, which makes them the most comfortable option for our customers. We have easy access and ample parking spaces for the attention of our customers.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-html\"><div class=\"dots desktop\">\n<span class=\"dot\" data-group=\"1\"><\/span>\n<span class=\"dot\" data-group=\"2\"><\/span>\n<span class=\"dot\" data-group=\"3\"><\/span>\n<\/div><\/div><div class=\"w-html\"><div class=\"dots mobile\">\n<span class=\"dot\" data-group=\"1\"><\/span>\n<span class=\"dot\" data-group=\"2\"><\/span>\n<span class=\"dot\" data-group=\"3\"><\/span>\n<span class=\"dot\" data-group=\"4\"><\/span>\n<span class=\"dot\" data-group=\"5\"><\/span>\n<span class=\"dot\" data-group=\"6\"><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_51587432 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_56e31fea align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"494\" height=\"187\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5-1.png\" class=\"attachment-large size-large\" alt=\"fondo bg 5\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5-1.png 494w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-5-1-300x114.png 300w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><\/div><\/div><h2 class=\"w-text us_custom_0f416522 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">What our customers say<\/span><\/span><\/h2><div class=\"wpb_text_column us_custom_1c3ba9c0 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"normal-text\">Satisfied adventurers tell of their <\/span> <span class=\"script\">their experience<\/span><\/h2>\n<\/div><\/div><div class=\"w-image align_center\"><a target=\"_blank\" href=\"https:\/\/www.google.com\/search?sa=X&amp;sca_esv=da0365bf5fc892c6&amp;sxsrf=ANbL-n6m0j8lkc6kVukZbgLsecrxXxrywQ:1777276282010&amp;q=AvenTouralia+\u26f0\ufe0f+Quad,+ATV+&amp;+Buggy+Adventures+|+Mijas,+Costa+del+Sol,+M\u00e1laga+Rese\u00f1as&amp;rflfq=1&amp;num=20&amp;stick=H4sIAAAAAAAAAONgkxI2NjY2NTQ0MTUwMDY1NjSxNDIx3sDI-Iox0rEsNS8kv7QoMSczUeHR7A3vd_QrBJYmpugoOIaEKagpOJWmp1cqOKYAlZWUFqUWK9Qo-GZmJRbrKDjnF5ckKqSk5igE5-foKPgeXpiTmJ6oEJRanHp4Y2LxIlbamQ0ANo0FutIAAAA&amp;rldimm=3335114500353149243&amp;tbm=lcl&amp;hl=es-ES&amp;ved=2ahUKEwiMzdOLxo2UAxX3-AIHHdiOHWEQ9fQKegQIZxAG&amp;biw=1728&amp;bih=1270&amp;dpr=1#lkt=LocalPoiReviews\" aria-label=\"Link\" class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"116\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/Frame-1984077921.png\" class=\"attachment-large size-large\" alt=\"Frame 1984077921\" \/><\/a><\/div><div class=\"w-html us_custom_0a40804c\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-disable-font ti-review-text-mode-readmore ti-content-align-center\" data-no-translation=\"true\" data-layout-id=\"36\" data-layout-category=\"slider\" data-set-id=\"drop-shadow\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKi3bcMlmWGiNHHClckAkuVmMk_gUJ9CFL9aiv1S35HR6MmeQ=w64-h64-c-rp-mo-br100\" alt=\"Beatriz Lapied Fern\u00e1ndez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Beatriz Lapied Fern\u00e1ndez <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Una experiencia muy divertida! Me ha encantado, muchas gracias a Gabriel y Leandro!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocITaBnFtwi0UN9o22imFGJTo--X-hOROrbnlE1lNoP-c_0aaA=w64-h64-c-rp-mo-br100\" alt=\"Linnea Klasson profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Linnea Klasson <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->It was amazing and the views were amazing! Gabriel was a very good guide who helped and encouraged us!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLzcpwIra8mBzbq_KxgbMGy4dp1gd_LFDiFp-pbOAOfzE8fFg=w64-h64-c-rp-mo-br100\" alt=\"Madde N profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Madde N <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->I had so fun and the view was amazing! Gabriel was a very good and encouraging instructor\/guide<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJepK5REimueo3wafM6CxQD7wXtKijkkQFjeJndtSznM6kHJQ=w64-h64-c-rp-mo-br100\" alt=\"Jasmijn Massaar profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jasmijn Massaar <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->It was a very nice ride. Nice view, nice route and a very kind instructor.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWadSR0pOLfrF6UGOEYVjhz5Lo0W40VUvfTvaVmHIWdkLY3Zg2V=w64-h64-c-rp-mo-br100\" alt=\"A R profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> A R <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Amazing experience and amazing guide Gabriel!!! I am for sure gonna do this again.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIWabVcRdntVd5kuwVxBVpIhY4auhCm-m_bRMW36S4iyJKVzg=w64-h64-c-rp-mo-br100\" alt=\"Seybae profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Seybae <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Most amazing experience!!! In the winter and in the summer, great view with the mountains, animals and the water. And super nice guide, thank you Gabriel ! See you soon back in the summer with an extra long ride :)<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLE2bhSLp16nkx6xFk1U0BMUhzIr7L-5w6-m0ZuMLdiQmju8Q=w64-h64-c-rp-mo-br100\" alt=\"Audrey Caussignac profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Audrey Caussignac <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->On a pass\u00e9e une super exp\u00e9rience avec notre Guide Gabriel, qui a \u00e9t\u00e9 vraiment g\u00e9nial !\nJe recommande vivement cette activit\u00e9, c\u2019est \u00e0 la fois magique et partage d\u2019adr\u00e9naline !\nEncore merci beaucoup \u00e0 notre guide Gabriel, le meilleur !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWwRuZzQyDJBlX0ht6GlG6Pq-xKZieuOJ2um2rZfwYqJAHTVBU3=w64-h64-c-rp-mo-br100\" alt=\"Jonathan Nsimba Mpasi profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jonathan Nsimba Mpasi <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Good guide Gabriel \ud83d\udd25\ud83d\udd25<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWatu7xZqTORTVxnXKVBtBiHToxCLhpnkt496J9RHIcMIooP6Wp=w64-h64-c-rp-mo-br100\" alt=\"Babyhgo profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Babyhgo <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Grabiel nos ayud\u00f3 demasiado\nCumplieron con la hora de duraci\u00f3n 100% recomiendo de hecho nos sacaron fotos tambi\u00e9n<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\">  <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKRBQCGoOM6PTl1YOSzIMb8U75Jck18CSBhS0dP0gq2CxeuRg=w64-h64-c-rp-mo-br100\" alt=\"Phoebe Jae Harris profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Phoebe Jae Harris <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Experiencia incre\u00edble!\nMuchas gracias en especial a Gabriel por ser un gu\u00eda genial, repetiremos muy pronto!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>    <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/aventouralia.com\/wp-content\/uploads\/trustindex-google-widget.css?1765173668\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_ac8338d8 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"536\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4-2.png\" class=\"attachment-large size-large\" alt=\"fondo bg 4\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4-2.png 709w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4-2-300x227.png 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-4-2-500x378.png 500w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/div><\/div><div class=\"w-vwrapper us_custom_b96863db align_none valign_top\" style=\"--vwrapper-gap:0rem\"><div class=\"w-image us_custom_3eab0aa4 align_none\"><div url class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"115\" height=\"85\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fondo-bg-6.png\" class=\"attachment-large size-large\" alt=\"fondo bg 6\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_41d9ffb4 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"normal-text\">Follow us on Instagram to see our tours<\/span><\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_9009bdb4 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><a href=\"https:\/\/www.instagram.com\/aventouralia\/\" target=\"_blank\" rel=\"noopener\"><span class=\"script\">@aventouralia<\/span><\/a><\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_33b9ee00\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">\n<div id=\"sb_instagram\"  class=\"sbi sbi_mob_col_2 sbi_tab_col_3 sbi_col_6 sbi_width_resp\" style=\"padding-bottom: 10px;\"\t data-feedid=\"*1\"  data-res=\"auto\" data-cols=\"6\" data-colsmobile=\"2\" data-colstablet=\"3\" data-num=\"6\" data-nummobile=\"8\" data-item-padding=\"5\"\t data-shortcode-atts=\"{&quot;feed&quot;:&quot;1&quot;}\"  data-postid=\"5535\" data-locatornonce=\"9359a0cc62\" data-imageaspectratio=\"1:1\" data-sbi-flags=\"favorLocal,gdpr\">\n\t\n\t<div id=\"sbi_images\"  style=\"gap: 10px;\">\n\t\t<div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18099831292940139\" data-date=\"1773352798\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DVzN9m_CIsE\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax3-2.cdninstagram.com\/v\/t51.71878-15\/651453464_1667227374713433_8970711430485938976_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=100&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=gruoTi_jQQ0Q7kNvwHQlq7Z&#038;_nc_oc=AdqjL0NtLYDOFjHQbi1ChCer1dQaIvAeMR5Y2TnwmoX16a-NP_xa4Un4OBZHcOZxOZE&#038;_nc_zt=23&#038;_nc_ht=scontent-lax3-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQE1oI-mZJH0yPeZu9z64A-y9LOkzrKwsZT2VE-Fgayz0u1B-qRC8x-H2lKoFRSGmc3FT2qTgYIMrQ&#038;oh=00_Af46BE-mggo6xCQr5Q564bsSGdFb8WkRc9VbdXnHuF8wBA&#038;oe=6A0A740B\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/651453464_1667227374713433_8970711430485938976_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=gruoTi_jQQ0Q7kNvwHQlq7Z&amp;_nc_oc=AdqjL0NtLYDOFjHQbi1ChCer1dQaIvAeMR5Y2TnwmoX16a-NP_xa4Un4OBZHcOZxOZE&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE1oI-mZJH0yPeZu9z64A-y9LOkzrKwsZT2VE-Fgayz0u1B-qRC8x-H2lKoFRSGmc3FT2qTgYIMrQ&amp;oh=00_Af46BE-mggo6xCQr5Q564bsSGdFb8WkRc9VbdXnHuF8wBA&amp;oe=6A0A740B&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/651453464_1667227374713433_8970711430485938976_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=gruoTi_jQQ0Q7kNvwHQlq7Z&amp;_nc_oc=AdqjL0NtLYDOFjHQbi1ChCer1dQaIvAeMR5Y2TnwmoX16a-NP_xa4Un4OBZHcOZxOZE&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE1oI-mZJH0yPeZu9z64A-y9LOkzrKwsZT2VE-Fgayz0u1B-qRC8x-H2lKoFRSGmc3FT2qTgYIMrQ&amp;oh=00_Af46BE-mggo6xCQr5Q564bsSGdFb8WkRc9VbdXnHuF8wBA&amp;oe=6A0A740B&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/651453464_1667227374713433_8970711430485938976_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=gruoTi_jQQ0Q7kNvwHQlq7Z&amp;_nc_oc=AdqjL0NtLYDOFjHQbi1ChCer1dQaIvAeMR5Y2TnwmoX16a-NP_xa4Un4OBZHcOZxOZE&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE1oI-mZJH0yPeZu9z64A-y9LOkzrKwsZT2VE-Fgayz0u1B-qRC8x-H2lKoFRSGmc3FT2qTgYIMrQ&amp;oh=00_Af46BE-mggo6xCQr5Q564bsSGdFb8WkRc9VbdXnHuF8wBA&amp;oe=6A0A740B&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/651453464_1667227374713433_8970711430485938976_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=gruoTi_jQQ0Q7kNvwHQlq7Z&amp;_nc_oc=AdqjL0NtLYDOFjHQbi1ChCer1dQaIvAeMR5Y2TnwmoX16a-NP_xa4Un4OBZHcOZxOZE&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE1oI-mZJH0yPeZu9z64A-y9LOkzrKwsZT2VE-Fgayz0u1B-qRC8x-H2lKoFRSGmc3FT2qTgYIMrQ&amp;oh=00_Af46BE-mggo6xCQr5Q564bsSGdFb8WkRc9VbdXnHuF8wBA&amp;oe=6A0A740B&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\ud83d\udc9c Oferta especial Semana Santa\n15% de descuento\n\n\ud83c\udf10<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\ud83d\udc9c Oferta especial Semana Santa\n15% de descuento\n\n\ud83c\udf10 Utiliza el C\u00f3digo web: MESSANTO26\n\ud83d\udcc5 V\u00e1lido hasta 12 de abril\n\u23f3 Reserva antes de que se llenen las plazas\n\n\ud83d\udce9 Escr\u00edbenos por privado para m\u00e1s informaci\u00f3n o reserva directamente en nuestra web\n\n#Mijas #CostaDelSol #Malaga #VisitMalaga #QuadTour BuggyTour AdventureSpain ThingsToDoMalaga OutdoorMalaga SemanaSanta SemanaSantaMalaga\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18057473732356496\" data-date=\"1770195985\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DUVJBXMiGTb\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax3-1.cdninstagram.com\/v\/t51.82787-15\/625680917_18083298602223238_6315191221567823393_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=Xb6JkeF4cYMQ7kNvwHoMGH5&#038;_nc_oc=AdrW0GXCLQauJ8uK-OLuCUdPM2274TShrDY1nydtjZjgl2Or8QmtModl2sJqnuREGx0&#038;_nc_zt=23&#038;_nc_ht=scontent-lax3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQGeuhBrovX7ZenFJugo_hUX1os-Zf7t5T8WolG4N_mfdsw3QjkrckkLk--u7g61KTzaxNA1mShK0Q&#038;oh=00_Af4lP__0kEMdpLQcfuDiulSVIbMmvK1DYaIp6YacqAlBNQ&#038;oe=6A0A5D4A\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/625680917_18083298602223238_6315191221567823393_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Xb6JkeF4cYMQ7kNvwHoMGH5&amp;_nc_oc=AdrW0GXCLQauJ8uK-OLuCUdPM2274TShrDY1nydtjZjgl2Or8QmtModl2sJqnuREGx0&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQGeuhBrovX7ZenFJugo_hUX1os-Zf7t5T8WolG4N_mfdsw3QjkrckkLk--u7g61KTzaxNA1mShK0Q&amp;oh=00_Af4lP__0kEMdpLQcfuDiulSVIbMmvK1DYaIp6YacqAlBNQ&amp;oe=6A0A5D4A&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/625680917_18083298602223238_6315191221567823393_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Xb6JkeF4cYMQ7kNvwHoMGH5&amp;_nc_oc=AdrW0GXCLQauJ8uK-OLuCUdPM2274TShrDY1nydtjZjgl2Or8QmtModl2sJqnuREGx0&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQGeuhBrovX7ZenFJugo_hUX1os-Zf7t5T8WolG4N_mfdsw3QjkrckkLk--u7g61KTzaxNA1mShK0Q&amp;oh=00_Af4lP__0kEMdpLQcfuDiulSVIbMmvK1DYaIp6YacqAlBNQ&amp;oe=6A0A5D4A&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/625680917_18083298602223238_6315191221567823393_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Xb6JkeF4cYMQ7kNvwHoMGH5&amp;_nc_oc=AdrW0GXCLQauJ8uK-OLuCUdPM2274TShrDY1nydtjZjgl2Or8QmtModl2sJqnuREGx0&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQGeuhBrovX7ZenFJugo_hUX1os-Zf7t5T8WolG4N_mfdsw3QjkrckkLk--u7g61KTzaxNA1mShK0Q&amp;oh=00_Af4lP__0kEMdpLQcfuDiulSVIbMmvK1DYaIp6YacqAlBNQ&amp;oe=6A0A5D4A&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/625680917_18083298602223238_6315191221567823393_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Xb6JkeF4cYMQ7kNvwHoMGH5&amp;_nc_oc=AdrW0GXCLQauJ8uK-OLuCUdPM2274TShrDY1nydtjZjgl2Or8QmtModl2sJqnuREGx0&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQGeuhBrovX7ZenFJugo_hUX1os-Zf7t5T8WolG4N_mfdsw3QjkrckkLk--u7g61KTzaxNA1mShK0Q&amp;oh=00_Af4lP__0kEMdpLQcfuDiulSVIbMmvK1DYaIp6YacqAlBNQ&amp;oe=6A0A5D4A&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">Real adventure. No filters.\nMountains \u00b7 Dust \u00b7 Vie<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Real adventure. No filters.\nMountains \u00b7 Dust \u00b7 Views\n\ud83d\udccd Mijas \u00b7 M\u00e1laga\nQuad &amp; Buggy Tours\n\ud83d\udc49 Link in bio\n\n#quad #buggy #offroad\n#adventuretravel #outdoorlife\nvisitmalaga costadelsol\nspaintrip reelsinstagram\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18040338635516067\" data-date=\"1768475619\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DTh3lLEiLYE\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax7-1.cdninstagram.com\/v\/t51.71878-15\/616509352_1283701900457834_3149621531908542823_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=111&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=kOFhUFjwPgAQ7kNvwGQ8sjc&#038;_nc_oc=AdpvOWDh0gfT1ud3Rij9mooy1LxF04qn9YuQO6Zsts8QGq6tE5ePs-tusOrRO-9njNY&#038;_nc_zt=23&#038;_nc_ht=scontent-lax7-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQFrLOitr8byuWMinVLWsiyoYB1t_RMMbAe9pIkSHVnomKwMw43rmslo8nz59dEAAvL-JGPkYGL7Gw&#038;oh=00_Af7Ze75BhO0oXCOQOsUIhN3_tej7oXlN9pfYZSJs3AzCpA&#038;oe=6A0A6BB2\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/616509352_1283701900457834_3149621531908542823_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=111&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=kOFhUFjwPgAQ7kNvwGQ8sjc&amp;_nc_oc=AdpvOWDh0gfT1ud3Rij9mooy1LxF04qn9YuQO6Zsts8QGq6tE5ePs-tusOrRO-9njNY&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQFrLOitr8byuWMinVLWsiyoYB1t_RMMbAe9pIkSHVnomKwMw43rmslo8nz59dEAAvL-JGPkYGL7Gw&amp;oh=00_Af7Ze75BhO0oXCOQOsUIhN3_tej7oXlN9pfYZSJs3AzCpA&amp;oe=6A0A6BB2&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/616509352_1283701900457834_3149621531908542823_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=111&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=kOFhUFjwPgAQ7kNvwGQ8sjc&amp;_nc_oc=AdpvOWDh0gfT1ud3Rij9mooy1LxF04qn9YuQO6Zsts8QGq6tE5ePs-tusOrRO-9njNY&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQFrLOitr8byuWMinVLWsiyoYB1t_RMMbAe9pIkSHVnomKwMw43rmslo8nz59dEAAvL-JGPkYGL7Gw&amp;oh=00_Af7Ze75BhO0oXCOQOsUIhN3_tej7oXlN9pfYZSJs3AzCpA&amp;oe=6A0A6BB2&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/616509352_1283701900457834_3149621531908542823_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=111&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=kOFhUFjwPgAQ7kNvwGQ8sjc&amp;_nc_oc=AdpvOWDh0gfT1ud3Rij9mooy1LxF04qn9YuQO6Zsts8QGq6tE5ePs-tusOrRO-9njNY&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQFrLOitr8byuWMinVLWsiyoYB1t_RMMbAe9pIkSHVnomKwMw43rmslo8nz59dEAAvL-JGPkYGL7Gw&amp;oh=00_Af7Ze75BhO0oXCOQOsUIhN3_tej7oXlN9pfYZSJs3AzCpA&amp;oe=6A0A6BB2&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/616509352_1283701900457834_3149621531908542823_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=111&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=kOFhUFjwPgAQ7kNvwGQ8sjc&amp;_nc_oc=AdpvOWDh0gfT1ud3Rij9mooy1LxF04qn9YuQO6Zsts8QGq6tE5ePs-tusOrRO-9njNY&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQFrLOitr8byuWMinVLWsiyoYB1t_RMMbAe9pIkSHVnomKwMw43rmslo8nz59dEAAvL-JGPkYGL7Gw&amp;oh=00_Af7Ze75BhO0oXCOQOsUIhN3_tej7oXlN9pfYZSJs3AzCpA&amp;oe=6A0A6BB2&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\ud83c\udf39 FLORES\u2026 Y QUE EMPIECE LA AVENTURA 15%Off\ud83c\udfc1\n\nEste <\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\ud83c\udf39 FLORES\u2026 Y QUE EMPIECE LA AVENTURA 15%Off\ud83c\udfc1\n\nEste San Valent\u00edn sorprende con un plan diferente: barro, motor, paisajes y pura diversi\u00f3n.\nConsigue un \u201315% de descuento en nuestras rutas en quad y buggy usando el c\u00f3digo SANVALENTIN26 \u2764\ufe0f\ud83d\udca5\n\nPorque las mejores historias no se envuelven\u2026 se viven juntos\n\n\ud83d\udce9 Reserva por mensaje privado o directamente desde nuestra web\n\n#SanValent\u00edn #SanValentin2026 #CodigoDescuento #FloresYAventura #RegalaAventura PlanEnPareja AventuraEnPareja ExperienciasUnicas RegaloOriginal AmorConAdrenalina PlanesDiferentes Buggy Quad CostaDelSol Mijas Malaga Aventouralia RangersSafariTours\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18060712421647644\" data-date=\"1767196331\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DS7vqwUiCwJ\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax3-1.cdninstagram.com\/v\/t51.71878-15\/607012768_3261757527320580_5306669396799923219_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=Fg8dLbn2Uh8Q7kNvwGjC3-5&#038;_nc_oc=AdpChQ8WJ507bk3vEWLmrY4IJVgs9TMJKgUisZEbxgCaQvSnpURARnmk99KObXfF4JU&#038;_nc_zt=23&#038;_nc_ht=scontent-lax3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQECakcFzkRYOCP7kmReWPN_zUWkogfZ30U7fyK7pQ9RjVhciTmc-sY7t0Se8YYZnLR0rA6wsQADjw&#038;oh=00_Af7pTimTBheKaDe4IfnJjt4tPHwv3UhmCN5TS0d1eeiqAQ&#038;oe=6A0A7883\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/607012768_3261757527320580_5306669396799923219_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Fg8dLbn2Uh8Q7kNvwGjC3-5&amp;_nc_oc=AdpChQ8WJ507bk3vEWLmrY4IJVgs9TMJKgUisZEbxgCaQvSnpURARnmk99KObXfF4JU&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQECakcFzkRYOCP7kmReWPN_zUWkogfZ30U7fyK7pQ9RjVhciTmc-sY7t0Se8YYZnLR0rA6wsQADjw&amp;oh=00_Af7pTimTBheKaDe4IfnJjt4tPHwv3UhmCN5TS0d1eeiqAQ&amp;oe=6A0A7883&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/607012768_3261757527320580_5306669396799923219_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Fg8dLbn2Uh8Q7kNvwGjC3-5&amp;_nc_oc=AdpChQ8WJ507bk3vEWLmrY4IJVgs9TMJKgUisZEbxgCaQvSnpURARnmk99KObXfF4JU&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQECakcFzkRYOCP7kmReWPN_zUWkogfZ30U7fyK7pQ9RjVhciTmc-sY7t0Se8YYZnLR0rA6wsQADjw&amp;oh=00_Af7pTimTBheKaDe4IfnJjt4tPHwv3UhmCN5TS0d1eeiqAQ&amp;oe=6A0A7883&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/607012768_3261757527320580_5306669396799923219_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Fg8dLbn2Uh8Q7kNvwGjC3-5&amp;_nc_oc=AdpChQ8WJ507bk3vEWLmrY4IJVgs9TMJKgUisZEbxgCaQvSnpURARnmk99KObXfF4JU&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQECakcFzkRYOCP7kmReWPN_zUWkogfZ30U7fyK7pQ9RjVhciTmc-sY7t0Se8YYZnLR0rA6wsQADjw&amp;oh=00_Af7pTimTBheKaDe4IfnJjt4tPHwv3UhmCN5TS0d1eeiqAQ&amp;oe=6A0A7883&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/607012768_3261757527320580_5306669396799923219_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=Fg8dLbn2Uh8Q7kNvwGjC3-5&amp;_nc_oc=AdpChQ8WJ507bk3vEWLmrY4IJVgs9TMJKgUisZEbxgCaQvSnpURARnmk99KObXfF4JU&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQECakcFzkRYOCP7kmReWPN_zUWkogfZ30U7fyK7pQ9RjVhciTmc-sY7t0Se8YYZnLR0rA6wsQADjw&amp;oh=00_Af7pTimTBheKaDe4IfnJjt4tPHwv3UhmCN5TS0d1eeiqAQ&amp;oe=6A0A7883&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\u2728 Gracias por formar parte de este incre\u00edble 2025 <\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\u2728 Gracias por formar parte de este incre\u00edble 2025 \u2728\nHa sido un a\u00f1o lleno de aventura, risas, barro, paisajes brutales y momentos que se quedan para siempre.\nNada de esto habr\u00eda sido posible sin vosotros: clientes, amigos y amantes de la adrenalina.\nSeguimos sumando experiencias, kil\u00f3metros y recuerdos. \u00a1Vamos a por un 2026 a\u00fan m\u00e1s salvaje! \ud83d\ude80\n\n#Gracias2025 #AventuraSinL\u00edmites #ExperienciasInolvidables\n#QuadTours #BuggyTours CostaDelSol MijasAdventure\nOutdoorExperience AdventureLovers TravelSpain OffRoadLife\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_17850451038608414\" data-date=\"1765904612\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DSVPuG6CFjO\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax7-1.cdninstagram.com\/v\/t51.71878-15\/588643413_1534001727906563_8669117924486123604_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=105&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=K8ma4MzXMBAQ7kNvwFzTBiH&#038;_nc_oc=AdrH2J7MMNrMvCyx4SrQ3uCOjcQubNCi6raLMqCCzIoPbWQdm_tUhYlN4ZuqOn-cJj4&#038;_nc_zt=23&#038;_nc_ht=scontent-lax7-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQG2DyuR3TAJQHJgnSrBn6QyYdKSdr55IfTrpdccbJQkdVGK4DAtZHXivdKng2ftN0BeTIu22Op4Sg&#038;oh=00_Af4hq_swxBUVCfdFbLBe10oU4r-7fvHNiIQVFjXQeaDEWw&#038;oe=6A0A5512\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/588643413_1534001727906563_8669117924486123604_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=105&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=K8ma4MzXMBAQ7kNvwFzTBiH&amp;_nc_oc=AdrH2J7MMNrMvCyx4SrQ3uCOjcQubNCi6raLMqCCzIoPbWQdm_tUhYlN4ZuqOn-cJj4&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQG2DyuR3TAJQHJgnSrBn6QyYdKSdr55IfTrpdccbJQkdVGK4DAtZHXivdKng2ftN0BeTIu22Op4Sg&amp;oh=00_Af4hq_swxBUVCfdFbLBe10oU4r-7fvHNiIQVFjXQeaDEWw&amp;oe=6A0A5512&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/588643413_1534001727906563_8669117924486123604_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=105&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=K8ma4MzXMBAQ7kNvwFzTBiH&amp;_nc_oc=AdrH2J7MMNrMvCyx4SrQ3uCOjcQubNCi6raLMqCCzIoPbWQdm_tUhYlN4ZuqOn-cJj4&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQG2DyuR3TAJQHJgnSrBn6QyYdKSdr55IfTrpdccbJQkdVGK4DAtZHXivdKng2ftN0BeTIu22Op4Sg&amp;oh=00_Af4hq_swxBUVCfdFbLBe10oU4r-7fvHNiIQVFjXQeaDEWw&amp;oe=6A0A5512&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/588643413_1534001727906563_8669117924486123604_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=105&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=K8ma4MzXMBAQ7kNvwFzTBiH&amp;_nc_oc=AdrH2J7MMNrMvCyx4SrQ3uCOjcQubNCi6raLMqCCzIoPbWQdm_tUhYlN4ZuqOn-cJj4&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQG2DyuR3TAJQHJgnSrBn6QyYdKSdr55IfTrpdccbJQkdVGK4DAtZHXivdKng2ftN0BeTIu22Op4Sg&amp;oh=00_Af4hq_swxBUVCfdFbLBe10oU4r-7fvHNiIQVFjXQeaDEWw&amp;oe=6A0A5512&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/588643413_1534001727906563_8669117924486123604_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=105&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=K8ma4MzXMBAQ7kNvwFzTBiH&amp;_nc_oc=AdrH2J7MMNrMvCyx4SrQ3uCOjcQubNCi6raLMqCCzIoPbWQdm_tUhYlN4ZuqOn-cJj4&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQG2DyuR3TAJQHJgnSrBn6QyYdKSdr55IfTrpdccbJQkdVGK4DAtZHXivdKng2ftN0BeTIu22Op4Sg&amp;oh=00_Af4hq_swxBUVCfdFbLBe10oU4r-7fvHNiIQVFjXQeaDEWw&amp;oe=6A0A5512&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\ud83d\ude99\ud83d\ude04 BUGGIES 4 PLAZAS \u00b7 MORE PEOPLE, MORE FUN\nFriend<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\ud83d\ude99\ud83d\ude04 BUGGIES 4 PLAZAS \u00b7 MORE PEOPLE, MORE FUN\nFriends or family, one ride, lots of laughs.\nEasy vibes, dirt roads &amp; good memories.\n\n\ud83d\udccd Mijas \u00b7 Costa del Sol\n\ud83d\udc49 Who would you bring?\n#Buggy4Plazas\n#4SeaterBuggy\n#BuggyToursMijas\n#BuggyToursCostaDelSol\n#BuggyToursMalaga\n#BuggyFun\n#FamilyAndFriends\n#ThingsToDoInMalaga\n#CostaDelSolExperience\n#RangersSafariTours\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18551534695032758\" data-date=\"1764569475\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DRtc7CvkaZR\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax3-1.cdninstagram.com\/v\/t51.82787-15\/589917289_18077211191223238_3565582021828482453_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=104&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=6Cr_D8KyVU0Q7kNvwFeY0RO&#038;_nc_oc=Adr0ThMDapB5uxSgUwA6yG3bCF6zMyruCFV0b6UoV1PZqp44PjVh9djy-fbf04JZ2fA&#038;_nc_zt=23&#038;_nc_ht=scontent-lax3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQE8n1VtKyrWeAaEnqKf-RIJ2FHfBlEkBOTRcNtnz37s1cZHC3Zfh-RyAvTAewFyykKsy4MUxFk7uA&#038;oh=00_Af4S3Laj0taNbrJpvdLWtrzrtQTA2kwVbWmNeRfI6o9BQg&#038;oe=6A0A6289\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/589917289_18077211191223238_3565582021828482453_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=6Cr_D8KyVU0Q7kNvwFeY0RO&amp;_nc_oc=Adr0ThMDapB5uxSgUwA6yG3bCF6zMyruCFV0b6UoV1PZqp44PjVh9djy-fbf04JZ2fA&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8n1VtKyrWeAaEnqKf-RIJ2FHfBlEkBOTRcNtnz37s1cZHC3Zfh-RyAvTAewFyykKsy4MUxFk7uA&amp;oh=00_Af4S3Laj0taNbrJpvdLWtrzrtQTA2kwVbWmNeRfI6o9BQg&amp;oe=6A0A6289&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/589917289_18077211191223238_3565582021828482453_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=6Cr_D8KyVU0Q7kNvwFeY0RO&amp;_nc_oc=Adr0ThMDapB5uxSgUwA6yG3bCF6zMyruCFV0b6UoV1PZqp44PjVh9djy-fbf04JZ2fA&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8n1VtKyrWeAaEnqKf-RIJ2FHfBlEkBOTRcNtnz37s1cZHC3Zfh-RyAvTAewFyykKsy4MUxFk7uA&amp;oh=00_Af4S3Laj0taNbrJpvdLWtrzrtQTA2kwVbWmNeRfI6o9BQg&amp;oe=6A0A6289&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/589917289_18077211191223238_3565582021828482453_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=6Cr_D8KyVU0Q7kNvwFeY0RO&amp;_nc_oc=Adr0ThMDapB5uxSgUwA6yG3bCF6zMyruCFV0b6UoV1PZqp44PjVh9djy-fbf04JZ2fA&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8n1VtKyrWeAaEnqKf-RIJ2FHfBlEkBOTRcNtnz37s1cZHC3Zfh-RyAvTAewFyykKsy4MUxFk7uA&amp;oh=00_Af4S3Laj0taNbrJpvdLWtrzrtQTA2kwVbWmNeRfI6o9BQg&amp;oe=6A0A6289&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/589917289_18077211191223238_3565582021828482453_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=6Cr_D8KyVU0Q7kNvwFeY0RO&amp;_nc_oc=Adr0ThMDapB5uxSgUwA6yG3bCF6zMyruCFV0b6UoV1PZqp44PjVh9djy-fbf04JZ2fA&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8n1VtKyrWeAaEnqKf-RIJ2FHfBlEkBOTRcNtnz37s1cZHC3Zfh-RyAvTAewFyykKsy4MUxFk7uA&amp;oh=00_Af4S3Laj0taNbrJpvdLWtrzrtQTA2kwVbWmNeRfI6o9BQg&amp;oe=6A0A6289&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\ud83c\udf85\u2728 Esta Navidad\u2026 \u00a1REGALA AVENTURA!\n\nCambia los reg<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\ud83c\udf85\u2728 Esta Navidad\u2026 \u00a1REGALA AVENTURA!\n\nCambia los regalos t\u00edpicos por quads y buggies, que Santa ya est\u00e1 cansado de calcetines \ud83d\ude0e\ud83d\udca8\n\nAprovecha el 15% de descuento con el c\u00f3digo REGALAVENTURA25 hasta el 6 de enero y vive la experiencia off-road m\u00e1s divertida de Mijas.\n\n\u203c\ufe0fBUGGIES 4plazas  DISPONIBLES \n\n\ud83d\udc49 Reserva antes de que Santa se quede con tu buggy.\n\n\u2705Utiliza el c\u00f3digo en nuestra web: www.aventouralia.com\n\u2705 REGALAVENTURA25\n\u2705M\u00e1s info por WhatsApp: 615 890 084\n\u2705Tendr\u00e1s 1 a\u00f1o entero para elegir la fecha de tu aventura\n\n#RegalaAventura #RegalosNavidad2025 #PlanNavidad #OffRoadAdventure #BuggyMijas #QuadMijas #Aventouralia #RangersSafariTours #CostaDelSol #Mijas #VisitSpain #MalagaExperience #AdventureLovers #OutdoorExperience #FamilyAdventure #BuggyTour #QuadTour #TravelSpain #AndaluciaTurismo\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18093505270702323\" data-date=\"1759857444\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DPhBwF6CEz0\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax3-1.cdninstagram.com\/v\/t51.71878-15\/559981387_1498320484747407_7789877467844954692_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=T5d5vgsTPaQQ7kNvwHvYk13&#038;_nc_oc=AdrmAO1T_KicTayD7-A_pEkDX4t6HCPtpoQ6vk3Zjhq86WO-qJiI_SvJhmfzU6QCwSk&#038;_nc_zt=23&#038;_nc_ht=scontent-lax3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQE8DtmrDJAMlW0oPRAmSDKDgYPkAmzbQzgl6e_V1wMPWGB_kGM2clWFq9zA1rZng-ala_iQqNtkmA&#038;oh=00_Af4szagny_2oX129Gyp-dxXLPyVty_hqQkHKuOsbA2JeCA&#038;oe=6A0A4CB7\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/559981387_1498320484747407_7789877467844954692_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=T5d5vgsTPaQQ7kNvwHvYk13&amp;_nc_oc=AdrmAO1T_KicTayD7-A_pEkDX4t6HCPtpoQ6vk3Zjhq86WO-qJiI_SvJhmfzU6QCwSk&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8DtmrDJAMlW0oPRAmSDKDgYPkAmzbQzgl6e_V1wMPWGB_kGM2clWFq9zA1rZng-ala_iQqNtkmA&amp;oh=00_Af4szagny_2oX129Gyp-dxXLPyVty_hqQkHKuOsbA2JeCA&amp;oe=6A0A4CB7&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/559981387_1498320484747407_7789877467844954692_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=T5d5vgsTPaQQ7kNvwHvYk13&amp;_nc_oc=AdrmAO1T_KicTayD7-A_pEkDX4t6HCPtpoQ6vk3Zjhq86WO-qJiI_SvJhmfzU6QCwSk&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8DtmrDJAMlW0oPRAmSDKDgYPkAmzbQzgl6e_V1wMPWGB_kGM2clWFq9zA1rZng-ala_iQqNtkmA&amp;oh=00_Af4szagny_2oX129Gyp-dxXLPyVty_hqQkHKuOsbA2JeCA&amp;oe=6A0A4CB7&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/559981387_1498320484747407_7789877467844954692_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=T5d5vgsTPaQQ7kNvwHvYk13&amp;_nc_oc=AdrmAO1T_KicTayD7-A_pEkDX4t6HCPtpoQ6vk3Zjhq86WO-qJiI_SvJhmfzU6QCwSk&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8DtmrDJAMlW0oPRAmSDKDgYPkAmzbQzgl6e_V1wMPWGB_kGM2clWFq9zA1rZng-ala_iQqNtkmA&amp;oh=00_Af4szagny_2oX129Gyp-dxXLPyVty_hqQkHKuOsbA2JeCA&amp;oe=6A0A4CB7&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/559981387_1498320484747407_7789877467844954692_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=T5d5vgsTPaQQ7kNvwHvYk13&amp;_nc_oc=AdrmAO1T_KicTayD7-A_pEkDX4t6HCPtpoQ6vk3Zjhq86WO-qJiI_SvJhmfzU6QCwSk&amp;_nc_zt=23&amp;_nc_ht=scontent-lax3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQE8DtmrDJAMlW0oPRAmSDKDgYPkAmzbQzgl6e_V1wMPWGB_kGM2clWFq9zA1rZng-ala_iQqNtkmA&amp;oh=00_Af4szagny_2oX129Gyp-dxXLPyVty_hqQkHKuOsbA2JeCA&amp;oe=6A0A4CB7&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\ud83c\udfc1 Get Dirty, Feel Alive\n\nAdrenalina, polvo y sonri<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\ud83c\udfc1 Get Dirty, Feel Alive\n\nAdrenalina, polvo y sonrisas guaranteed \ud83d\ude0e\nFeel the freedom driving our Quads &amp; Buggies in Mijas, exploring the wild side of the Costa del Sol \ud83c\udf04\nDesde la monta\u00f1a hasta el mar, cada ruta es pura emoci\u00f3n \u2014 no necesitas experiencia, solo ganas de vivir la aventura \ud83d\udd25\n\n#GetDirtyFeelAlive #QuadMijas #BuggyMijas #CostaDelSolAdventure #OffRoadExperience #QuadTourMalaga #BuggyTourMalaga #ExploreCostaDelSol #WildAdventureGroup #AdrenalineTour #RangersSafariTours #Aventouralia #GoWildSpain #MijasMountains #OutdoorExperience\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18388656424143972\" data-date=\"1749588367\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DKu_HgNMJbe\/\" target=\"_blank\" rel=\"noopener nofollow\"\n\t\t\tdata-full-res=\"https:\/\/scontent-lax7-1.cdninstagram.com\/v\/t51.75761-15\/505802219_18059816423223238_8232769456528263977_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=101&#038;cb=8438d1d6-89aba764&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=0u-pWVBm7vkQ7kNvwFXtUGC&#038;_nc_oc=Adq3tpPTRZqs5-sGXn9a83xD7CAbehwzM6odYbMfU3vDcjneoNURe6cWLjGXRvPfYLg&#038;_nc_zt=23&#038;_nc_ht=scontent-lax7-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=8TjM6FVS-3ig20DKuse13w&#038;_nc_tpa=Q5bMBQHjAldd8JTnY3wIfQfr3Lx_ZULmQdIEEU87Tf1kZWOrGLmJDJCBaEWygYvYisul6uGy8jKgpwkbvw&#038;oh=00_Af6eOKMLbsfJOltiU7Cmn_Hy2KiFKaa2UQkipEP-Ap0OyQ&#038;oe=6A0A7E81\"\n\t\t\tdata-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.75761-15\\\/505802219_18059816423223238_8232769456528263977_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=101&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=0u-pWVBm7vkQ7kNvwFXtUGC&amp;_nc_oc=Adq3tpPTRZqs5-sGXn9a83xD7CAbehwzM6odYbMfU3vDcjneoNURe6cWLjGXRvPfYLg&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQHjAldd8JTnY3wIfQfr3Lx_ZULmQdIEEU87Tf1kZWOrGLmJDJCBaEWygYvYisul6uGy8jKgpwkbvw&amp;oh=00_Af6eOKMLbsfJOltiU7Cmn_Hy2KiFKaa2UQkipEP-Ap0OyQ&amp;oe=6A0A7E81&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.75761-15\\\/505802219_18059816423223238_8232769456528263977_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=101&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=0u-pWVBm7vkQ7kNvwFXtUGC&amp;_nc_oc=Adq3tpPTRZqs5-sGXn9a83xD7CAbehwzM6odYbMfU3vDcjneoNURe6cWLjGXRvPfYLg&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQHjAldd8JTnY3wIfQfr3Lx_ZULmQdIEEU87Tf1kZWOrGLmJDJCBaEWygYvYisul6uGy8jKgpwkbvw&amp;oh=00_Af6eOKMLbsfJOltiU7Cmn_Hy2KiFKaa2UQkipEP-Ap0OyQ&amp;oe=6A0A7E81&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.75761-15\\\/505802219_18059816423223238_8232769456528263977_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=101&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=0u-pWVBm7vkQ7kNvwFXtUGC&amp;_nc_oc=Adq3tpPTRZqs5-sGXn9a83xD7CAbehwzM6odYbMfU3vDcjneoNURe6cWLjGXRvPfYLg&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQHjAldd8JTnY3wIfQfr3Lx_ZULmQdIEEU87Tf1kZWOrGLmJDJCBaEWygYvYisul6uGy8jKgpwkbvw&amp;oh=00_Af6eOKMLbsfJOltiU7Cmn_Hy2KiFKaa2UQkipEP-Ap0OyQ&amp;oe=6A0A7E81&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lax7-1.cdninstagram.com\\\/v\\\/t51.75761-15\\\/505802219_18059816423223238_8232769456528263977_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=101&amp;cb=8438d1d6-89aba764&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=0u-pWVBm7vkQ7kNvwFXtUGC&amp;_nc_oc=Adq3tpPTRZqs5-sGXn9a83xD7CAbehwzM6odYbMfU3vDcjneoNURe6cWLjGXRvPfYLg&amp;_nc_zt=23&amp;_nc_ht=scontent-lax7-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=8TjM6FVS-3ig20DKuse13w&amp;_nc_tpa=Q5bMBQHjAldd8JTnY3wIfQfr3Lx_ZULmQdIEEU87Tf1kZWOrGLmJDJCBaEWygYvYisul6uGy8jKgpwkbvw&amp;oh=00_Af6eOKMLbsfJOltiU7Cmn_Hy2KiFKaa2UQkipEP-Ap0OyQ&amp;oe=6A0A7E81&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">Ready to ride the wild side? \ud83d\ude80\n\n\ud83d\udc49 Quads &amp; Buggies <\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/aventouralia.com\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Ready to ride the wild side? \ud83d\ude80\n\n\ud83d\udc49 Quads &amp; Buggies en Mijas \ud83c\uddea\ud83c\uddf8\n\n\ud83d\udc49 Book now &amp; feel the adrenaline! \ud83d\udd25\n\n#BuggyTourSpain #QuadTourSpain #CostaDelSol #OffRoadSpain #SpainTravel #ThingsToDoSpain #Aventouralia\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div>\t<\/div>\n\n\t<div id=\"sbi_load\" >\n\n\t\n\t\n<\/div>\n\t\t<span class=\"sbi_resized_image_data\" data-feed-id=\"*1\"\n\t\t  data-resized=\"{&quot;18057473732356496&quot;:{&quot;id&quot;:&quot;625680917_18083298602223238_6315191221567823393_n&quot;,&quot;ratio&quot;:&quot;1.33&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18040338635516067&quot;:{&quot;id&quot;:&quot;616509352_1283701900457834_3149621531908542823_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18060712421647644&quot;:{&quot;id&quot;:&quot;607012768_3261757527320580_5306669396799923219_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;17850451038608414&quot;:{&quot;id&quot;:&quot;588643413_1534001727906563_8669117924486123604_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18551534695032758&quot;:{&quot;id&quot;:&quot;589917289_18077211191223238_3565582021828482453_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18093505270702323&quot;:{&quot;id&quot;:&quot;559981387_1498320484747407_7789877467844954692_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18388656424143972&quot;:{&quot;id&quot;:&quot;505802219_18059816423223238_8232769456528263977_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18099831292940139&quot;:{&quot;id&quot;:&quot;651453464_1667227374713433_8970711430485938976_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;}}\">\n\t<\/span>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_b2fc8d50 has_text_color height_huge\" id=\"cta-form-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_b7f3b662 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Contact with Aventouralia<\/span><\/span><\/h2><div class=\"wpb_text_column us_custom_93f7dcb7 custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"normal-text\">Do you have any doubts?<\/span><\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_fa027fff custom-title has_text_color\"><div class=\"wpb_wrapper\"><h2><span class=\"script\">We are here to help you<\/span><\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_d01db1f5 has_text_color\"><div class=\"wpb_wrapper\"><p>Do not hesitate to contact us for further information about our services. You can do it by phone, whatsapp or by sending your inquiry through the form on this page.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js contact-form-home\" id=\"wpcf7-f14746-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"14746\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/5535#wpcf7-f14746-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"14746\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f14746-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"cf7-row\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n<\/div>\n\n<div class=\"cf7-row\">\n  <span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00famero de tel\u00e9fono*\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span>\n  <span class=\"wpcf7-form-control-wrap\" data-name=\"asunto\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Asunto*\" value=\"\" type=\"text\" name=\"asunto\" \/><\/span>\n<\/div>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensaje*\" name=\"mensaje\"><\/textarea><\/span>\n\n<div class=\"cf7-footer\">\n  <label class=\"cf7-privacy\">\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"acepto\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acepto\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> He le\u00eddo y acepto la <a href=\"\/politica-de-privacidad\">Pol\u00edtica de Privacidad<\/a>\n  <\/label>\n  <input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><div class=\"vc_col-sm-2\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row us_custom_cdf14ffd contact-inner-row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-vwrapper us_custom_a5de249e align_none valign_top\"><div class=\"w-text us_custom_1beee54a has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Find us<\/span><\/span><\/div><div class=\"w-text us_custom_b0f46463 has_text_color\"><a href=\"tel:+34851800801\" class=\"w-text-h\"><span class=\"w-text-value\">+34 851 800 801<\/span><\/a><\/div><div class=\"w-text us_custom_b0f46463 has_text_color\"><a href=\"https:\/\/wa.me\/+34604478168\" class=\"w-text-h\"><span class=\"w-text-value\">+34 604 478 168<\/span><\/a><\/div><div class=\"w-text us_custom_b0f46463 has_text_color\"><a href=\"mailto:info@aventouralia.com\" class=\"w-text-h\"><span class=\"w-text-value\">info@aventouralia.com<\/span><\/a><\/div><div class=\"w-text us_custom_b0f46463 has_text_color\"><a target=\"_blank\" href=\"https:\/\/maps.app.goo.gl\/frakQiWAbxSq88B37\" class=\"w-text-h\"><span class=\"w-text-value\">Arrabal Sector 33, 20C 295651 &#8211; Las Lagunas de Mijas M\u00e1laga<\/span><\/a><\/div><\/div><div class=\"w-hwrapper us_custom_d3c6354d valign_top align_none\" style=\"--hwrapper-gap:11px\"><span class=\"w-text us_custom_f73f4019\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Follow us on:<\/span><\/span><\/span><div class=\"w-image us_custom_f3ab010d align_none\"><a target=\"_blank\" href=\"https:\/\/www.facebook.com\/aventouralia\/\" aria-label=\"Link\" class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/fb.svg\" class=\"attachment-medium size-medium\" alt=\"fb\" \/><\/a><\/div><div class=\"w-image us_custom_f3ab010d align_none\"><a target=\"_blank\" href=\"https:\/\/www.instagram.com\/aventouralia\/\" aria-label=\"Link\" class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/insta.svg\" class=\"attachment-medium size-medium\" alt=\"insta\" \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_raw_html css=&#8221;&#8221;]PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3Lmdvb2dsZS5jb20vbWFwcy9lbWJlZD9wYj0hMW0xNCExbTghMW0zITFkMTI4MjAuNDc5OTczMjQxMzghMmQtNC42MzkxOTgyITNkMzYuNTUxMjE5NiEzbTIhMWkxMDI0ITJpNzY4ITRmMTMuMSEzbTMhMW0yITFzMHhkNzJlMzg1NmQ5MDkzOGYlM0EweDJlNDhiNGY3YzZjZGM5M2IhMnNBdmVuVG91cmFsaWElMjBRdWFkcyUyMCUyNiUyMEFUViUyMFRvdXJzJTIwaW4lMjBNaWphcyUyQyUyME1hbGFnYSE1ZTAhM20yITFzZXMhMnNlcyE0djE2OTQ2MDgxNzEyNzghNW0yITFzZXMhMnNlcyIgd2lkdGg9IjEwMCUiIGhlaWdodD0iNDUwIiBzdHlsZT0iYm9yZGVyOjA7IiBhbGxvd2Z1bGxzY3JlZW49IiIgbG9hZGluZz0ibGF6eSIgcmVmZXJyZXJwb2xpY3k9Im5vLXJlZmVycmVyLXdoZW4tZG93bmdyYWRlIj48L2lmcmFtZT4=[\/vc_raw_html]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1f166698 height_huge\" id=\"faqs-row\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_d940b615 has_text_color\"><span url class=\"w-text-h\"><span class=\"w-text-value\">Frequently Asked Questions<\/span><\/span><\/h2><div class=\"wpb_text_column us_custom_0b7f1d93 has_text_color\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Do you have any doubts?<br \/>\n<span class=\"script\">here we solve them for you<\/span><\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_c6ab4e7f\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Everything you need to know before you go on the road with us<\/p>\n<\/div><\/div><div class=\"g-cols wpb_row inner-row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-tabs us_custom_10679678 style_default switch_click accordion\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section\" id=\"a273\"><button class=\"w-tabs-section-header\" aria-controls=\"content-a273\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">What does it take to drive a quad bike?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-a273\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>To have a valid driver&#8217;s license &#8221; Type B &#8221; ( Automobile ). It will be requested prior to the activity.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"w341\"><button class=\"w-tabs-section-header\" aria-controls=\"content-w341\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">What should we bring?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-w341\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Valid driver&#8217;s license type B, sunscreen and lots of fun.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"d3f3\"><button class=\"w-tabs-section-header\" aria-controls=\"content-d3f3\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Can children do the adventure?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-d3f3\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Yes, as long as they are older than 6 years old and accompanied by their parents or a guardian of legal age and with a &#8220;type B&#8221; license.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"s493\"><button class=\"w-tabs-section-header\" aria-controls=\"content-s493\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Can I go without a reservation?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-s493\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>No, it is necessary to make a reservation in advance due to the limited number of places.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"w534\"><button class=\"w-tabs-section-header\" aria-controls=\"content-w534\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">How can I make a reservation?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-w534\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>You can contact us by calling or sending a Whatsapp to +34 608591184. Visit us at our office. You can send us an email to gestionaventouralia@gmail.com or through our website in the Reservations section.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"f5e2\"><button class=\"w-tabs-section-header\" aria-controls=\"content-f5e2\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">How do I make the payment?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-f5e2\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>A deposit of 30% of the total amount will be required to secure your reservation. The rest can be paid on the day of the appointment or if you prefer, you can pay 100% of the activity.<\/p>\n<p>Once we receive your deposit or full payment, we will reserve the quads for the date and time indicated.<\/p>\n<p>Payments can be made by bank transfer, paypal or cash (at our office).<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"y6a3\"><button class=\"w-tabs-section-header\" aria-controls=\"content-y6a3\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Can the reservation be cancelled?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-y6a3\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Cancellations can be made at least 24 hours prior to the day of the reservation.<\/p>\n<p>In the case of groups, cancellations must be made at least 72 hours prior to the day of the reservation. Otherwise, they will lose the right to return the same.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-tabs us_custom_b8bcc896 style_default switch_click accordion\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section\" id=\"ie3e\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ie3e\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Do I have insurance?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ie3e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Our company has liability insurance, accident insurance and third party insurance for the vehicle. Damage caused to the vehicle due to misuse is NOT covered and will be borne by the renter.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"lf10\"><button class=\"w-tabs-section-header\" aria-controls=\"content-lf10\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">What clothes should I wear?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-lf10\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>This will always depend on the season of the year, so we recommend the use of comfortable clothes and sports shoes.<br \/>\nDriving in &#8220;flip-flops&#8221; or &#8220;high heels&#8221; is strictly forbidden.<\/p>\n<p>It is advisable to wear a mask or bandana for protection against dust. If you do not have it, we can offer you to purchase bandanas in our office for 2,50\u20ac each.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"pfba\"><button class=\"w-tabs-section-header\" aria-controls=\"content-pfba\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Is racing or skidding possible?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-pfba\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Definitely not, our activity is based on a route of initiation in quad to observe nature and enjoy driving the vehicle, so we must respect the environment as much as possible with the utmost safety.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"d058\"><button class=\"w-tabs-section-header\" aria-controls=\"content-d058\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Can we rent the quads without a guide?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-d058\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>No, it is only possible to rent quads in Malaga for a guided tour<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"y0f2\"><button class=\"w-tabs-section-header\" aria-controls=\"content-y0f2\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Do you have a pick-up service?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-y0f2\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Yes, we have a pick-up service for groups, subject to availability and for an additional fee.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"c19d\"><button class=\"w-tabs-section-header\" aria-controls=\"content-c19d\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Would you dare to discover the nature of the Costa del Sol by quad?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-c19d\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Maybe you are on vacation or visiting here looking for a great experience to remember, maybe you need to celebrate a special moment with the people you love or you are probably looking for that adrenaline charged adventure that will make you feel free and for these reasons we think you are in the best place!<\/p>\n<p>At AvenTouralia Tours we offer you the opportunity to know the wild nature of the Costa del Sol in a unique way with our Quad Rental service in Malaga.<\/p>\n<p>Hop on one of our two-seater quads and together with one of our experienced guides, we will ride along mountain trails with panoramic views, cross riverbeds, spot wildlife such as sheep, horses and rarely wild boars.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"t24e\"><button class=\"w-tabs-section-header\" aria-controls=\"content-t24e\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Have you ever driven a quad bike?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-t24e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>You don&#8217;t have to worry if you have never driven a quad, we will provide you with practical and safety training. In addition, we will provide you with the necessary materials for the quad excursion. All you need is to be 18 years old or older, a valid driver&#8217;s license and a lot of fun!<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"o2ec\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o2ec\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Are provisional driver&#8217;s licenses allowed?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o2ec\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Driving with provisional driver&#8217;s licenses is not allowed.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_5c316805 cesped height_medium with_shape\" id=\"curiosity\"><div class=\"l-section-shape type_curve pos_top on_front\" style=\"height:15vmin;color:var(--color-header-middle-text)\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L64 0 Q32 15.8 0 0 L0 8 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-shape type_custom pos_bottom on_front\" style=\"height:auto;\"><?xml version=\"1.0\" encoding=\"utf-8\"?>\r\n<!-- Generator: Adobe Illustrator 27.1.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<svg version=\"1.1\" id=\"Capa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 1898 85\" style=\"enable-background:new 0 0 1898 85;\" xml:space=\"preserve\">\r\n<style type=\"text\/css\">\r\n\t.st0{fill:#FFFFFF;}\r\n<\/style>\r\n<path class=\"st0\" d=\"M1358.3,35.6c-5.8,1.8-10.1,5-13.3,9.1c-1.5,1.9-2.7,4.1-3.9,6.2c-0.7,1.2-0.7,1.3-2.9,1.9\r\n\tc-1.1-1.1-2.2-2.3-3.5-3.7c4.6-3.7,9.1-7.4,13.6-11.1c-4.4,0.7-8.1,2.6-11.8,4.4c-0.2-0.6-0.4-1-0.6-1.4c-2.3,0.9-2,3.6-4.3,4\r\n\tc-3-2.2-5.8-4.2-8.9-6.3c2.2-3,4.2-5.8,6.4-8.6c2.2-2.7,4.6-5.4,7.2-7.9c2.6-2.4,5.6-4.6,8.4-6.9c-0.8-0.8-1.4-0.5-2.1-0.1\r\n\tc-9.5,4.9-18.1,10.4-23.8,18.3c-0.2,0.2-0.5,0.5-0.9,1c-3.6-2.4-7.1-4.8-11-7.4c1.8-2.6,1.5-5.4,0.1-8.2c-0.7-1.4-1.3-2.8-3.6-3.2\r\n\tc-0.4-0.1-0.7-0.8-1.1-1.2c-1.2-1.7-2.1-3.4-3.5-4.9c-1.4-1.5-2.1-1.4-4.1-0.2c-0.7-0.9-1.4-1.8-2.1-2.6c-0.4-0.5-0.9-0.9-1.4-1.2\r\n\tc-1.8-1.1-3.1-0.7-4.1,1.3c-1.4-0.6-2.6-1.7-4.3-0.9c-1.3,0.6-1.5,1.6-0.7,2.9c-1,0.1-1.8,0.2-2.5,0.3c-1.2,1-0.3,2.7,2.1,4.4\r\n\tc-1.1,1.3-0.5,2.3,1,3c1.2,0.6,2.6,1.1,3.9,1.7c-0.3,2.5,0.3,3,4.8,3.8c-1.2,2.3-0.9,3.1,1.8,4.4c2.9,1.4,6.1,2,9.4,1.5\r\n\tc1.5-0.2,2.5,0.2,3.3,0.9c3,2.5,6,5.1,8.9,7.7c0.3,0.3,0.6,0.6,0.6,0.6c-2.6,6-5.1,11.8-7.6,17.6c-0.4-0.1-0.9-0.2-1.5-0.3\r\n\tc-0.1,0.2-0.3,0.3-0.3,0.4c2,3.9-0.5,7.6-0.9,11.4c-0.2,1.5-1,2.9-2.2,4.1c-2.1,2.3-4,4.7-6.1,7.1c-2.4-2.9-2.9-5-2.4-8.3\r\n\tc1.1-6.9,2.1-13.7,3-20.6c0.2-1.8,0-3.6-0.2-5.4c-5.1,10.2-7.5,20.8-10.1,32c-2.3-2.3-4.6-4-5.4-6.8c-1.1-4-2.3-8.1-5.2-11.6\r\n\tc-0.2-0.3-0.5-0.6-1.3-0.7c0.2,2.7,0.3,5.4,0.5,8.3c-2.2-0.5-2-1.8-2.1-3c-0.3-4.2-0.6-8.4-0.9-12.7c-0.2-3.4-0.6-6.8-0.6-10.3\r\n\tc0-2.4,0.6-4.7,0.9-7.1c0.1-0.6,0-1.1,0-1.9c-1.6,1.4-5.4,10.7-5.7,13.9c-0.5,4.8-0.9,9.6-1.3,14.7c-1.4-0.8-2.6-1.7-3.9-2.3\r\n\tc-3.2-1.5-6.3-3-9.6-4.3c-2.6-1-5.3-1.8-8-2.6c-0.6-0.2-1.3-0.4-2-0.5c-0.3,0-0.8,0.2-0.9,0.5c-0.1,0.2,0,0.7,0.2,0.8\r\n\tc0.5,0.3,1.2,0.5,1.8,0.8c1.8,0.9,3.7,1.5,5.3,2.6c5.5,3.7,10.8,7.5,16.2,11.3c0.9,0.6,1.6,1.3,1.6,2.4c0.1,3.6,0.3,7.1,0.5,10.7\r\n\tc0,0.2-0.1,0.2-0.3,0.6c-2.3-1-4.1-2.8-7.3-3c0.2,0.7,0.2,1.4,0.5,1.8c1.4,1.8,2.8,3.5,4.5,5c2.4,2.2,3.7,4.6,3.6,7.5\r\n\tc-0.1,2.4,0.7,4.9,1,7.4c10.8,0,21.5,0,32.2,0c-0.3-1.3-0.3-2.6-0.8-3.7c-1.4-3,0.5-5,2.9-7.5c0.3,4,0.5,7.4,0.7,11.3\r\n\tc1.5,0.1,2.6,0.1,3.8,0.1c1.6,0,3.2-0.1,4.8,0c1.7,0.1,3.3-0.1,4.6-1c-0.1-0.6-0.5-1.1-0.4-1.6c0.8-3.2,1.7-6.4,2.7-9.9\r\n\tc1.5,1.4,1.6,2.5,0.8,3.8c-1.3,2.5-3,4.8-3.1,7.6c0.1,0.3,0.1,0.9,0.2,0.9c1.3,0.1,2.6,0,3.9,0c0.6-1.1,1.1-2.2,1.9-3.6\r\n\tc0.8,1.4,1.5,2.5,2.1,3.6c2.4,0,4.8,0,7.3,0c0.2-1.1,0.3-2.2,0.5-3.5c0.3,1.4,0.5,2.4,0.7,3.5c1.7,0,3.1,0,5,0\r\n\tc0.4-6,0.8-12,1.3-18.5c0.6,0.8,1,1.2,1.2,1.6c1.1,2.6,2.1,5.1,3.1,7.7c0.5,1.2,0.4,2.3-0.2,3.4c-0.9,1.8-1.5,3.6-1.1,5.7\r\n\tc3.3,0,6.4,0,9.8,0c-0.2-1.3-0.5-2.5-0.7-3.6c-0.2-1.1-0.3-2.3-0.1-3.4c1.8,2.1,1.1,4.6,2,7.2c1.4,0,2.9,0,4.4,0s2.9,0,4.8,0\r\n\tc-0.4-7-0.5-13.7,1.1-20.4c0.6,2.2,1.3,4.3,1.7,6.5c0.5,2.2,0.8,4.6,1.1,6.9c0.3,2.2,0.6,4.6,0.9,7c1.5,0,2.9,0,4.5,0\r\n\tc0.1-0.9,0.2-1.6,0.2-2.4c-0.8-9.8-2.8-19.4-6.7-28.8c-0.3-0.8-0.3-1.8-0.2-2.7c3.4,1.8,6.1,3.8,8.7,6.2c0.4,0.4,0.6,1.2,0.5,1.8\r\n\tc-0.3,4.4-0.7,8.7-1.1,13.1c-0.3,3.3-0.5,6.5-0.6,9.8c-0.1,1,0.1,1.9,0.2,3c1.4,0,2.6,0,4.2,0c1.4-7.4,1.5-14.9,2.1-22.4\r\n\tc2,0.5,1.8,1.6,1.8,2.6c0,4.7,0,9.4,0,14.1c0,1.9,0.2,3.8,0.3,5.8c1.4,0,2.5,0,3.7,0c1.4-4.5,0.3-9,1.1-14.2\r\n\tc3.4,4.7,4.5,9.5,6.5,14.2c2.8,0,5.5,0,8.1,0c2.2-5.5,4.3-10.9,6.5-16.7c1.2,1.3,1.3,2.2,1.1,3.3c-0.7,4.1-1.1,8.2-1.6,12.3\r\n\tc0,0.3,0.1,0.6,0.2,1c1.3,0,2.6,0,3.9,0c0.3-0.6,0.6-1.4,1-2.2c0.4,0.8,0.7,1.5,1.1,2.2c1,0,1.9,0,3.2,0c0.3-4.3-0.8-8.4-1.8-12.6\r\n\tc2.1,4,3.1,8.2,4.1,12.6c3.2,0,6.4,0,9.7,0c0.5-2,1.1-4,1.6-6c0.1,0,0.3,0,0.4-0.1c0.3,1.9,0.6,3.9,1,6.1c1.6,0,3.1,0,4.8,0\r\n\tc0.8-1.8,1-3.8,0.6-5.8c-0.6-3.3,0.1-6.5,0.5-9.8c0.1-0.9,0.3-1.7,0.7-2.6c0.5,6,1,12,1.5,18.2c1.4,0,2.6,0,3.9,0\r\n\tc0.8-2.1,0.7-4.2,0.6-6.3c-0.2-5.3-0.1-10.5-0.2-15.8c0,0,0.2-0.1,0.4-0.2c1.7,1.4,2.9,2.8,2.7,5.3c-0.4,4.1,0.2,8.2,0.5,12.4\r\n\tc0.1,1.4,0.4,2.8,0.7,4.5c1.1,0,2.4,0,3.8,0c0.7-2.4-0.3-4.9-0.5-7.3c-0.1-2.4-0.6-4.9-0.5-7.4c0.3,0.8,0.8,1.6,0.9,2.5\r\n\tc0.5,3.4,0.9,7,1.3,10.4c0.2,1.8,0.4,2,3.2,1.8c0.2-1.8,0.4-3.5,0.5-5.3c0.2-0.1,0.4-0.1,0.6-0.2c1.2,1.8,2.3,3.6,3.6,5.4\r\n\tc1.6,0,3.2,0,5,0c-0.2-2.2-0.7-4.2-1.9-6.2c-2.4-3.7-4.9-7.3-7.3-11c-0.7-1-1.3-2.2-1.7-3.3c-0.7-2.1-1.2-4.2-1.8-6.2\r\n\tc-0.1-0.5-0.2-1-0.3-1.9c3.7,2.4,6.8,4.6,9.5,7.3c0.7,0.6,1,1.6,1.2,2.4c1.1,5.4,2,10.8,3,16.3c0.2,0.9,0.4,1.7,0.6,2.6\r\n\tc1.6,0,3.1,0,4.6,0c-0.1-1.3-0.2-2.4-0.3-3.6c0.1,0,0.2,0,0.3,0c0.6,1.2,1.1,2.3,1.8,3.8c1.8,0,3.7,0,5.6,0c1.4,0,2.4-0.5,3.2-1.4\r\n\tc1.5-1.8,3.1-3.5,4.9-5.4c0.7,2.4,1.4,4.6,2.1,6.8c1.1,0,1.9,0,2.8,0c0.1-0.2,0.3-0.5,0.3-0.7c-0.1-3.4,0-6.6-0.3-10\r\n\tc-0.2-2.1,1-3.3,3.1-4.5c2.2,5.2,4.4,10.2,6.6,15.2c3.4,0,6.5,0,9.9,0c0.1-0.7,0.2-1.4,0.2-1.9c0.5-9,1-18.2,1.3-27.2\r\n\tc0.1-1.8,0.7-3.2,2.4-4.3c0.7-0.5,1.1-1,2.2-2.1c0.2,1.1,0.3,1.6,0.3,2.1c0.2,7.8,0.3,15.8,0.6,23.6c0.1,2.4,1,4.8,1.6,7.3\r\n\tc0.1,0.3,0.5,0.6,0.7,1c1.7-0.5,1.7-1.6,1.7-2.6c0.2-5.4,0.5-10.8,0.6-16.3c0.1-5.2,0-10.3,0-15.5c0-1.8-0.2-3.5,2.8-4.6\r\n\tc-1.2-0.3-1.9-0.6-2.4-0.7c-0.7-2.5-1.3-5-2-7.4c-0.2,0-0.5,0-0.7,0c-0.6,2.2-1.3,4.5-1.8,6.8c-0.8,3.5-0.7,3.5-5.5,5.4\r\n\tc-0.3-8.4,1.9-16.5,4.1-24.7c0.7,1,1.5,2,1.9,3.1c2.3,5.1,4.4,10.3,6.6,15.3c0.9,2.1,1.2,4.3,1.2,6.6c-0.1,5.4,0,10.7-0.2,16\r\n\tc-0.2,4.7-0.7,9.4-1,14.1c-0.1,1.9,0.2,3.9,0.3,5.9c1.8,0,3.2,0,4.8,0c0.3-3.8,0.7-7.4,1-11.1c0.2,0,0.4,0,0.6-0.1\r\n\tc0.3,1.4,0.8,2.9,1,4.4c0.2,1.3,0.3,2.6,0.5,3.8c0.1,0.4,0.1,0.8,0.3,1.2c1,2.2,2.5,2.5,4.7,0.8c1.5,2.3,4,0.5,6.1,1.4\r\n\tc0.2-1.3,0.4-2.2,0.6-3.4c0.6,1.2,1,2.2,1.5,3.1c2.2,0,4.4,0,7,0c2.8-17,6.5-33.8,14.3-50.3c-0.9,0.6-1.5,0.9-2,1.4\r\n\tc-3.9,3.8-7.5,7.7-9.1,12.5c-1.8,5.3-3.5,10.6-5.4,16c0.1-17.9,2.4-35.2,13.7-51.2c-1.4-0.4-2.3,0.2-3.2,0.8c-3.5,1.9-6.1,4.6-8,7.6\r\n\tc-4.4,6.9-7.2,14.2-7.9,21.9c-0.5,4.5-1,9-1.5,14c-0.5-3.1-0.7-5.8-1.4-8.4c-0.9-3.3-2.2-6.6-3.6-9.9c-0.7-1.5-2.1-2.9-3.3-4.2\r\n\tc-0.5-0.6-1.4-0.9-2.8-1.8c0.1,1.7,0.1,2.8,0.3,3.8c1,5.2,2.1,10.3,3.1,15.5c0.3,1.5,0.5,3.1,0.7,4.6c0,1.3,0,2.6,0,3.9\r\n\tc-0.4-1-0.4-1.8-0.4-2.8c0-0.4,0.3-0.7,0.4-1.1c-0.3-0.3-0.9-0.6-0.9-1c-1.9-9.5-4.6-18.7-9.8-27.5c-2-3.3-4.5-6.4-7-9.4\r\n\tc-1-1.2-1.3-2.2-0.6-3.4c1.2-2.2,2.3-4.4,3.3-6.6c-0.5-0.5-1.1-1-1.7-1.7c1.7-0.9,3.2-1.6,4.5-2.4c2.2-1.3,2.4-2.3,1.2-4.2\r\n\tc0.8-0.5,1.7-0.9,2.2-1.5c0.6-0.6,1.4-1.7,1.1-2.3c-0.4-1.1-0.1-1.8,0.5-2.8c0.9-1.5,1.4-2.9-0.7-4.5c-2.8-2.1-2.8-2.2-5.3-0.1\r\n\tc-0.7,0.6-1.4,1.4-2.1,2c-2.4-1.1-2.9-0.9-5.2,2.1c-3.1-1.3-4.5-0.8-5.7,1.9c-0.5,1-0.8,2.2-1.2,3.2c-3.7,0.6-5.3,2.1-5.9,5.3\r\n\tc-0.2,1.1-0.2,2.2-1.5,2.9c0.8,1.9,1.5,3.8,2.3,5.8c-5.1,4.8-9,10.3-12.1,16.2c-3,5.8-4.1,12.1-6.1,18.1c-0.4-0.1-0.5-0.1-0.6-0.2\r\n\tc-2.9-1.5-4.2-3.4-3.3-6.3c1.7-5.9,2.8-12,4.2-18c1.5-0.4,2.8-0.7,4.1-1.1c2.5-0.7,4.4-2,5.4-3.9c1.2-2.4,1.1-3.3-1.2-4.3\r\n\tc1.3-1.1,2.7-2.2,4-3.4c2.1-1.9,2.1-2.8,0.2-4.7c0.5-1,1.1-2,1.5-3.1c0.9-2.4,0.4-3-2.8-3.8c0-1.4,0-2.7,0-4.2\r\n\tc-2.2,0.6-2.8,1.9-3.7,3c-1,0-2.1-0.2-2.8,0.1c-0.8,0.3-1.4,1.1-1.8,1.8c-0.8,1.4-1.3,3-2,4.5c-2.7-0.5-4,0.2-4.3,2.8\r\n\tc-0.1,0.7,0,1.4,0,2.2c0,0.6,0,1.3,0,1.9c-0.9,0.1-1.9-0.1-2.6,0.2c-0.7,0.3-1.2,1.1-1.3,1.8c-0.6,2.9-0.6,6.5,4.4,8.8\r\n\tc-1.7,7-3.5,14-5.2,21c-3.1-0.6-6-1.1-9.3-1.8c2.9,2.6,5.5,5,8,7.4c0.3,0.3,0.5,0.9,0.5,1.3c-0.5,3.4-1.2,6.8-1.8,10.2\r\n\tc0,0.2-0.2,0.2-0.5,0.6c-2.9-8.2-6.3-16.2-14.7-22c1.9,3.5,4,7,5.6,10.6c1.7,3.7,3.4,7.5,4.5,11.4c1.1,3.8,1.6,7.6,2,11.5\r\n\tc-0.3-0.4-0.5-0.8-0.8-1.2c-1.7-2.5-3.5-5-5.2-7.5c-1-1.4-2.2-2.9-2.8-4.5c-2.9-7.3-6.9-14.1-12.9-20c-0.2-0.2-0.3-0.4-0.4-0.7\r\n\tc4.2-4.5,9.3-8.2,14.8-11.7c1.2-0.8,2.8-1.2,4.2-1.8c0.7-0.3,1.5-0.6,1-1.4s-1.3-0.5-2.1-0.2c-4.2,1.4-8.6,2.6-12.7,4.2\r\n\tc-5.5,2-9.2,5.7-13,9.3c-0.5,0.5-1,1-1.5,1.4c-0.1,0.1-0.4,0.2-0.7,0.2c-5.3-6.2-11.6-11.9-19.4-16.3c-2.8-1.6-5.9-3-8.9-4.3\r\n\tc-0.7-0.3-1.6-0.4-2.7-0.2c2.8,1.9,5.7,3.8,8.3,5.7c7,5.2,13.1,11.1,18.4,17.5c1.2,1.4,1.4,2.6,0.3,4.2c-1,1.4-1.7,3-2.5,4.4\r\n\tc-3.8-1.8-7.3-3.5-10.9-5.2c2.1,2.4,4,5,6.2,7.2c1.7,1.8,3,3.3,1.3,5.4c-0.6,0.8-0.7,1.8-0.9,2.7c-0.7,3-1.3,6.1-1.9,9.3\r\n\tc-0.2-0.3-0.3-0.5-0.4-0.7c-1.4-5.5-3.8-10.9-6.7-16c-0.2-0.3-0.5-0.8-0.4-1.1c0.8-2.3,1.7-4.6,2.5-7c0.2-1.2,0.4-2.5,0.7-3.7\r\n\tc0.3-1.3,0.7-2.6,1.1-4.2c-2.5,1.1-3,3-4.5,4.2c1-2.7,3.3-5,3.7-8c-4.5,3-7.3,7.2-10.8,11.1c-2.8-2.2-5.4-4.2-8.5-6.6\r\n\tc0.5-2.8,1-5.8,1.6-9.2c-0.5,0.3-0.8,0.5-0.8,0.6c-0.8,3.8-3.5,6.9-5.4,10.3c-3.7,6.6-6,13.6-7,20.9c-0.3,2-0.6,4.1-1,6.5\r\n\tc-0.5-0.8-0.8-1.2-1-1.7c-1.5-3.1-2.9-6.2-4.5-9.4c-0.5-1-0.7-2.1-0.4-3.2c1.2-6,2.3-12.1,3.4-18.2c-3.9,4.2-5,9.2-7,14.3\r\n\tc-1.6-1.9-3.3-3.5-4.3-5.4c-0.7-1.2-0.3-2.8-0.3-4.2c0-1.1,0.2-2.2,0.3-3.4c-0.2,0-0.5,0-0.7-0.1c-0.3,1.8-0.6,3.4-1,5.5\r\n\tc-1.7-1.4-3.1-2.7-4.5-4c-0.2,0.1-0.3,0.2-0.5,0.2c1,1.8,1.8,3.7,2.9,5.4c0.8,1.2,0.8,2.4,0.5,3.7c-0.6,2.4-1,4.8-1.6,7.4\r\n\tc-3-1.3-5.8-2.6-9-3.9c0.8-1.6,1.6-3.3,2.6-4.9c0.4-0.7,1-1.4,1.5-2.1c0.4-0.6,1.2-1.3,0.2-1.8c-0.4-0.2-1.3,0.3-1.9,0.6\r\n\tc-0.2,0.1-0.3,0.2-0.7,0.3c2.1-8.2,4.3-16.3,8.2-24c-7.9,8.3-12.6,17.7-15.7,28c-2.6-2.4-3.8-5.4-7.3-7c0.1,1.5,0.9,2.7,1.4,4\r\n\tc1.2,2.9,2.5,5.7,3.7,8.6c0.3,0.6,0.4,1.4,0,2c-1.8,2.8-3.7,5.6-5.7,8.6c-1.1-1.3-2.2-2.4-3.1-3.6c-1.8-2.4-3.4-4.9-5.2-7.2\r\n\tc-0.8-1.1-1.1-2.2-0.5-3.4c0.7-1.6,1.5-3.1,1.9-4.8c0.5-1.6,1.5-2.5,3.7-2.5c0.4,0,0.8-0.2,1.2-0.6c-1,0.1-2.1,0.1-3.4,0.2\r\n\tc1-2.9,2.5-5.3,4.4-7.6c1.7-2.2,3.5-4.2,5.3-6.3C1358,36.1,1358.1,35.8,1358.3,35.6z M1503.3,68c3.5-1.9,4.5-4.4,4.5-7.8\r\n\tc0.2-9.5,3.1-18.7,7.5-27.6c0.5-1,0.6-1.8-0.2-2.6c-0.4-0.5-0.8-1-1.2-1.4c-1.7-1.8-2.3-1.8-4.2,0.1c-2.5,2.5-4,5.3-5.6,8.1\r\n\tc-4.9,8.7-7.3,17.9-9.5,27.2c-0.1,0.6-0.3,1.4,0,1.8c1.1,2,2.4,3.9,3.7,6.2C1500.2,70.6,1501.5,69,1503.3,68z M1480.9,91.1\r\n\tc0.2,0.1,0.5,0.1,0.7,0.2c0.8-1.1,1.4-2.4,2.3-3.4c2.7-2.9,3.7-5.9,3.3-9.5c-0.2-2.7,0.1-5.6,0.5-8.3c0.4-2.6-1.1-4.3-3.9-6.2\r\n\tC1482.7,73.1,1480.5,82,1480.9,91.1z M1404.7,63.9c-0.6,2.2,0.1,3.5,2.6,4.7c2.3-3.9,4.6-7.8,7-11.9c-1.9-2.5-3-5.3-6.4-7.4\r\n\tC1406.9,54.5,1406,59.2,1404.7,63.9z M1448.1,55.7c-0.3,0.5-0.1,1.2,0.1,1.8c0.4,0.9,1.1,1.7,1.4,2.6c0.9,2.3,2.1,4.1,5.5,4.6\r\n\tc1.7,0.2,3.3,1.4,5.4,2.3c-1.6-5.8-5.3-10.7-7.8-15.9c-0.3-0.1-0.5-0.1-0.8-0.2C1450.6,52.5,1449.2,54.1,1448.1,55.7z M1324,49.8\r\n\tc0.8-0.6,1.7-1.2,2.8-1.9c-2-1.8-3.8-3.5-6-5.5c-2.7,5-4.6,10-5.7,15.2c2.1-1.8,4.3-3.6,6.5-5.5c-0.5-1-0.9-1.9-1.6-3.4\r\n\tC1321.6,49,1322.7,49.4,1324,49.8z M1327.7,72c-0.2-2.8-0.1-5.7-0.1-8.8c-2.3,1.4-4.2,2.7-4.2,5c0,0.8-0.2,1.6-0.5,2.3\r\n\tc-1.3,3-0.2,5.8,2,8.6C1326.8,77,1328,74.7,1327.7,72z M1506.5,71.6c-1.7,1.6-3.5,3.1-5,4.8c-0.3,0.4-0.1,1.2,0.1,1.8\r\n\tc1.5,3.8,3.2,7.7,4.8,11.7C1506.8,83.9,1507.3,77.9,1506.5,71.6z M1278.7,91.8c-0.5-5-1.1-10.2-1.7-15.2c-0.3-2.4-0.2-2.4-2.8-4.4\r\n\tc0,1.5-0.1,2.9,0,4.2c0.1,2.7,0.5,5.4,0.5,8.1c0,2.1,0.6,3.9,1.8,5.7c0.6,1,1.2,1.9,1.8,3c0.1,0,0.3-0.1,0.4-0.1\r\n\tC1278.7,92.7,1278.7,92.2,1278.7,91.8z M1417.4,78c-0.1,0.3,0.1,0.8,0.2,1.1c1.6,3.8,3.3,7.8,5.3,11.6c-0.3-2-0.8-4-1-6\r\n\tc-0.4-3.7-0.8-7.4-0.1-11.1c0.2-1.4-0.5-2.8-0.8-4.2c-0.3,0-0.5,0-0.8,0C1419.3,72.3,1418.3,75.1,1417.4,78z M1342.5,68.7\r\n\tc2,3.9,4.1,7.9,6.2,11.9c0.1,0.2,0.3,0.3,0.7,0.7c0.7-1.1,1.4-2,0.7-3.2c-2.1-3.5-4.2-7-6.3-10.5c-0.2-0.4-0.7-0.7-1-1\r\n\tc-0.2,0.1-0.4,0.1-0.7,0.2C1342.3,67.4,1342.2,68.1,1342.5,68.7z M1382.3,69.3c2.2-3.5,1.7-6.5-1.2-9.2\r\n\tC1381.4,63.1,1379.7,66.2,1382.3,69.3z M1310.9,80.4c0.3,2,0.1,4,0.6,6.1c0.9-3.9,1.9-7.8,2.9-12\r\n\tC1312.1,76.2,1310.6,77.9,1310.9,80.4z M1443.6,63.5c-0.7,1.1-0.4,2.1,0.8,3c1.3,1,2.4,2,4,2.9c-0.2-0.6-0.4-1.4-0.7-2\r\n\tc-0.8-1.8-1.7-3.7-2.6-5.4c-0.2,0-0.4,0-0.6,0C1444.2,62.3,1444,62.9,1443.6,63.5z M1402.4,79c3.4-3.5,3.8-6.6,1.4-9.6\r\n\tC1403.3,72.6,1402.9,75.6,1402.4,79z M1283.9,82.7c0.2,2.3,0.3,4.6,0.5,7C1284.6,87.3,1286.9,84.9,1283.9,82.7z M1516.7,26.5\r\n\tc0.5,0.5,0.9,0.9,1.6,1.4c1.2-1.3,2.2-2.5,3.3-3.7c-0.1-0.1-0.2-0.2-0.3-0.2C1519.8,24.9,1518.3,25.7,1516.7,26.5z M1335.1,68.7\r\n\tc-0.2,0-0.4,0-0.7-0.1c-1.3,2.3-0.4,4.8-0.3,7.2C1334.4,73.4,1334.8,71,1335.1,68.7z M1540.6,84.2c0.1,0,0.3,0,0.4,0\r\n\tc-0.3-2.8-0.5-5.7-0.8-8.5c-0.2,0-0.3-0.1-0.5-0.1C1540.1,78.5,1540.4,81.4,1540.6,84.2z M1336,57.7c-0.2-0.2-0.9,0.2-1.7,0.4\r\n\tc0.9,1,1.6,1.8,2.5,3C1337.9,59.4,1337,58.5,1336,57.7z M1387.9,72c-1,1.5-0.1,2.4,0.9,3.2c0,0,0.2-0.1,0.5-0.2\r\n\tC1388.9,74.2,1388.4,73.2,1387.9,72z M1325.6,56.3c-1,0.6-0.7,1.3-0.4,2.2C1327.2,57.9,1326.7,57.1,1325.6,56.3z M1292.4,82.4\r\n\tc0.3,0,0.6,0,0.9-0.1c-0.1-0.8-0.1-1.6-0.2-2.5c-0.3,0-0.6,0.1-0.9,0.1C1292.2,80.8,1292.3,81.6,1292.4,82.4z M1413.9,69.6\r\n\tc-0.2-0.1-0.3-0.1-0.5-0.2c-0.4,0.7-0.8,1.4-1.2,2.2c0.3,0.1,0.5,0.2,0.8,0.2C1413.3,71.1,1413.6,70.3,1413.9,69.6z M1411.6,72.8\r\n\tc0,1,0,1.5,0,2.3C1412.3,74,1412.3,74,1411.6,72.8z M1318.9,62.7c-0.1-0.1-0.2-0.2-0.3-0.2c-0.4,0.4-0.8,0.7-1.2,1.1\r\n\tc0.1,0.1,0.3,0.2,0.4,0.2C1318.1,63.4,1318.5,63,1318.9,62.7z M1690,97.1c2.2,0,4.3,0,6.5,0c0.2-0.6,0.4-1.4,0.7-2.2\r\n\tc0.3,0.9,0.5,1.5,0.7,2.2c2.4,0,4.6,0,7.1,0c0.1-1.6,0.2-3,0.3-4.6c0.1,0,0.3,0,0.4,0c0.3,1.4,0.5,3,0.8,4.6c1.9,0,3.6,0,5.8,0\r\n\tc0.8-6-0.9-11.9-0.4-18c0.4,1.3,0.9,2.6,1.1,3.8c0.5,3,0.8,6,1.2,9c0.3,1.7,0.8,3.4,1.2,5.3c1.9,0,3.5,0.1,5,0s3.1-0.4,4.6-0.3\r\n\tc1.4,0,2.9,0.3,4.4,0.5c1.5-3,0.9-5.8,1.2-9.1c0.9,2.6,1.6,4.6,2.3,6.8c0.2,0.5,0.3,1,0.6,1.4c0.2,0.2,0.6,0.6,0.9,0.5\r\n\tc0.4-0.1,1-0.3,1.1-0.6c0.3-0.7,0.4-1.6,0.4-2.3c0-6.5-0.1-12.9-0.2-19.4c0-0.6,0-1.1,0.5-1.7c0.3,1.5,0.8,3,1,4.6\r\n\tc0.4,3.8,0.7,7.8,0.8,11.7c0.1,1.8-0.3,3.7-0.3,5.4c0,0.8,0.2,1.5,0.3,2.5c2.3,0,4.5,0.9,6.5-0.6c1.9,1.5,4.1,0.3,6.3,0.8\r\n\tc0-1.7,0-3,0-4.3c0.1,0,0.2,0,0.3,0c0.4,1.4,0.8,2.7,1.2,4.4c1.6-0.2,3.1-0.3,4.7-0.3c1.7,0,3.3,0.2,5,0.3s3.3,0,5.2,0\r\n\tc0.2-7.2,0.1-14-0.7-21c-0.8-6.8-3.2-13.4-5.9-19.8c0.3-0.1,0.5-0.2,0.8-0.2c0.3,0.3,0.7,0.6,0.9,1c4.2,7,7.9,14.1,10.8,21.5\r\n\tc0.4,1,0.4,2,0.4,3c0,4.7-0.2,9.4,1.2,14c0.1,0.5,0.4,0.9,0.5,1.4c2.9,0,5.8,0,8.9,0c-0.3-2.1-0.3-4-0.8-5.8c-1-4-2.2-7.9-3.2-11.9\r\n\tc-0.3-1.1-0.4-2.4-0.1-3.5c1-3.7,2.2-7.4,3.7-11.1c3.1,10.7,3.3,21.5,4.5,32.5c1.9-0.2,3.9,0.7,5.1-1.1c1.1,1.9,3,0.8,4.7,1.1\r\n\tc0.9-4.3,0.8-8.5,2.8-12.5c0.5,4,1,8.1,1.6,12.3c7.3,0.2,14.5,0.1,22,0.1c0-3.4,0-6.6,0-9.2c0.5,2.6,1.1,5.8,1.7,9\r\n\tc2.6,0,4.9,0,7.5,0c0.6-7.4-0.1-14.8-2.2-22.3c2.5,0.7,3.6,1.6,3.6,3.7c0,4.2,0.3,8.2,0.4,12.4c0,1-0.3,2.1-0.3,3c0,1,0.2,2,0.3,3.1\r\n\tc2,0,3.8,0.7,5.2-0.6c1.4,1.3,3,0.6,4.7,0.6c1-4.3-0.1-8.6,1-13.1c2.1,1.4,3.3,2.7,3.1,4.8c-0.2,2.8,0.4,5.5,1.5,8.4\r\n\tc2.8,0,5.5,0,8.2,0c2.3,0,4.6,0,6.9,0c1.5,0,2.8,0,3.3-2.1c0.7,1.9,1.9,2.2,3.4,2.2c2.8-0.1,5.7,0,8.6,0c0.9-3.4,0.7-6.6,0.9-9.9\r\n\tc0.3-6.2,1-12.3,3.3-18.1c2.4-6.1,5.6-11.9,9.8-17.4c0.6-0.8,1.2-1.7,1.7-2.5c0.3-0.4,0.4-0.9,0.3-1.4c-2.6,1-4.9,2.5-6.8,4.2\r\n\tc-1.8,1.7-3.5,3.5-4.7,5.4c-2.1,3.3-3.7,6.6-5.5,10c-0.1,0.2-0.3,0.6-0.5,0.7c1.8-16.4,8.8-32,13.1-48.3c-1.9,0.7-2.8,1.8-3.4,2.8\r\n\tc-2.2,3.7-4.4,7.3-6.3,11.1c-2.9,5.6-5.3,11.4-6.8,17.3c-1.2,4.6-2.3,9.4-3.2,14.1c-0.8,3.9-1.2,7.8-1.8,12\r\n\tc-0.3-0.5-0.6-0.9-0.8-1.2c-1.8-5.4-4.4-10.4-8.1-15.1c-1.9-2.4-2.4-4.6-1.3-7.4c3-7.5,6-15.1,11-21.9c0.2-0.3,0.5-0.7,0.7-1.1\r\n\tc-2.8,0.5-7.3,3.7-10.7,8.1c-2.6,3.4-4.6,7-6.7,10.4c-3.6-4.1-6.9-8.4-10.9-12.4c-4-4.1-8.2-8-12.8-11.6c-4.5-3.5-9.5-6.6-14.3-9.9\r\n\tc1.1-1.4,4.1-1.8,2.5-4c0.8-0.4,1.5-0.8,2.2-1.2c0.1-0.2,0.2-0.4,0.1-0.5c-0.5-0.9-0.6-1.8,0.2-2.6c0.5-0.6,0.8-1.3,1.1-1.9\r\n\tc0.8-1.8,0.6-2.2-1.3-3.6c-2.9,0.1-3.6,2.2-5.2,3.8c-0.3-0.2-0.7-0.5-0.9-0.4c-3,1.3-7.7,0.6-8.4,4.6c0,0.2-0.2,0.4-0.3,0.6\r\n\tc-0.2,0-0.5,0.1-0.6,0.1c-3.4-1.5-4.7-1.1-5.7,2c-0.1,0.3-0.1,0.6-0.2,0.9c-3.6,0.9-3.6,0.9-4.1,4.5c-3.1,0.4-3.5,0.8-3.6,3.4\r\n\tc0,2.1,0,4.2,0,6.2c0,0.3-0.1,0.7,0,1c1.7,3-1.2,5-2.5,7.7c-1.5-1-2.8-1.8-4.2-2.8c-0.4,1.1,0.5,1.5,1.1,2c1.7,1.4,2.1,3,0.9,4.8\r\n\tc-1.3,2.1-2.5,4.2-3.8,6.4c-2.4-1.5-4.5-3-6.9-4.3c-2.7-1.4-5.5-2.8-8.4-4.1c-2.1-1-4.2-1.8-6.3-2.7c-0.8-0.3-1.6-0.9-2.3,0\r\n\tc-0.7,0.8,0.1,1.3,0.8,1.8c7.2,4.6,13.3,10,19.9,15.1c0.1,0.1,0.1,0.2,0.7,0.6c-0.5,0.3-1,0.6-1.6,1c-0.1,0.8-0.2,2-0.6,3.1\r\n\tc-1.4,4-2.8,8-4.5,12.7c-3.7-6.2-6.3-12.3-14-15.5c1.5-4.4,2.9-8.6,4.5-13.3c-3.1,1.2-4.4,3-5.6,4.7c-1.2,1.8-2.4,3.6-3.7,5.7\r\n\tc-1.3-1.8-2.5-3.6-3.8-5.4c2.6-2.6,2.1-5.7,2.4-8.6c0.1-1.4-1.1-1.8-3.3-1.4c-0.4-1.5-0.2-3.2-2.3-4.2c-0.4-0.2-0.2-1.2-0.3-1.8\r\n\tc0-2.3,0-2.3-2.6-3c-0.2-0.7-0.4-1.5-0.6-2.4c-0.9,0.3-1.6,0.6-2.4,0.8c-0.4-1.7,0.6-4.1-3.2-3.8c-0.6-1.7-1.2-3.4-1.9-5.1\r\n\tc-1.7,1-0.3,1.9-0.8,2.9c-1.5-0.8-2.5-2.3-4.8-1.9c-1,2.4,1,4.4,1.6,6.6c-0.5,0.2-1,0.5-1.9,0.8c1.9,2.5,1.5,5.6,4,7.9\r\n\tc0.6,0.6,1.3,1-0.2,1.6c-0.3,0.1,0.1,1.4,0.3,2.2c-0.3,0.1-0.6,0.2-0.9,0.3c-2.3,0.6-2.9,1.4-1.6,2.9c1.6,1.7,3.4,3.4,5.6,4.6\r\n\tc2.8,1.5,5.9,2.6,9.4,3.9c1.2,2.9,2.6,6.2,4,9.5c0.2,0.5,0.1,1.1,0,1.6c-0.9,4.5-1.9,9-2.8,13.4c-0.2,0.8-0.4,1.7-0.7,2.9\r\n\tc-1.9-2.1-3.4-3.9-5.1-5.7c-2.5-2.5-5-5-7.7-7.3c-1.2-1-2-2-1.9-3.5c0.1-3.1-0.2-6.2-1.1-9.2c-0.4-1.4-0.1-2.8-0.4-4.2\r\n\tc-1.3,4-2.5,8-3.8,12.2c-2.7-0.6-5.1-2.5-8.5-1.8c-0.9-1.1-1.8-2.4-2.8-3.5c-0.4-0.4-1.2-1-1.7-1c-1,0.2-0.8,0.9-0.5,1.6\r\n\tc0.3,1.1,0.5,2.3,0.7,3.4c0.5,2.6,0.9,5.2,1.7,7.8c0.5,1.9,0.8,3.7,0.1,5.6c-0.5,1.5-0.8,3.1-1.2,4.6c-0.1,0.5-0.4,1-0.7,1.9\r\n\tc-1-2.4-1.8-4.5-2.7-6.5c-0.7-1.6-1.4-3.2-2.3-4.6c-1.3-2-1.8-4-1.8-6.2c0.1-4.6-0.1-9.2,0-13.9c0-2.2,0.4-4.2,0.7-6.8\r\n\tc-2.3,1.4-2.4,3.3-3.3,4.7c-0.9,1.6-1.6,3.3-2.2,5c-0.6,1.7-0.9,3.4-1.5,5.4c-1.6-1.4-3.1-2.6-4.3-3.8c-0.5-0.5-0.4-1.4-0.4-2\r\n\tc0.1-2,0.3-3.9,0.4-6.2c-1.4,0.7-1.7,1.8-2.3,2.6c-0.7,0.9-1.2,1.8-1.9,2.9c-2-1-3.9-2-5.8-3c-0.1,0.1-0.2,0.2-0.3,0.2\r\n\tc0.3,0.3,0.5,0.7,0.8,1c0.6,0.6,1.3,1,1.9,1.5c1.7,1.7,2.5,3.4,1.1,5.7c-1,1.7-1.4,3.6-2.1,5.8c-1.2-1.7-2.2-3.1-3.4-4.6\r\n\tc-1.3-1.5-2.6-3-4-4.4c-1.3-1.4-2.8-2.6-4.4-4.2c3.2-5.4,7.6-10.3,12-15.5c-3.2,0.2-5.2,1.4-7.1,2.6c-3.4,2-6.2,4.4-8.6,7.2\r\n\tc-4.5,5.1-8,10.7-11.2,16.8c-1.4-1.5-2.5-3-3.9-4.2c-2.1-1.8-2.2-3.4-1-5.5c2.2-3.7,4-7.4,6-11.2c0.5-1,1.4-1.8,2.1-2.6\r\n\tc0.5-0.6,0.9-1.1,1.4-1.7c-1.3-0.9-1.9-0.1-2.4,0.4c-4.5,4.3-9.7,8.2-12.5,13.6c-0.1,0.2-0.3,0.2-0.5,0.4c-2.6-1.2-4.9-2.9-8.5-3.3\r\n\tc2.1,2.8,4.1,5.3,5.9,7.6c-2.2,4.8-4.3,9.4-6.4,14.2c-0.8-1-1.6-1.9-2.3-2.9c-0.2,0.1-0.4,0.1-0.6,0.2c0,0.5-0.1,1,0.1,1.4\r\n\tc1.3,2.7,1.4,5.6,1,8.4c-0.6,4.6-1.6,9.3-2,14c-0.3,3.7,0.1,7.4,0.2,11.2c0,0.5,0.3,0.9,0.5,1.4c1.5,0,2.9,0,4.5,0\r\n\tc1.4-3.8,0.4-7.5,1.1-11.8c1.1,4.2,1.2,7.8,1.8,11.9c3.3,0.2,6.5,0.1,9.8,0.1c2.2-8.2,4.4-16.3,6.6-24.4c0.2,0,0.5-0.1,0.7-0.1\r\n\tc0.7,1.5,1.4,3,2.1,4.6c1.3,2.5,1.4,5,0.6,7.7c-1,3.5-1.5,7-1,10.7c0.1,0.5,0.2,0.9,0.3,1.5c4.2,0,8.3,0,12.7,0\r\n\tc0.1-0.5,0.2-1,0.2-1.5c-0.4-4.8-1.3-9.5-2.9-14.1c-0.4-1.2-0.4-2.3,0.1-3.4c0.9-2.2,1.9-4.2,2.9-6.4c-0.1,8.5-0.8,17,1.4,25.5\r\n\tc1.8,0,3.5,0,5.4,0c0.6-5.3-0.1-10.5,0.1-15.7c0.1-5.3,0-10.5,0-15.5c1.3,1.2,1.9,3,1.8,5c-0.5,8.5-1.2,17-0.5,25.5\r\n\tC1689.7,96.5,1689.8,96.7,1690,97.1z M1730.1,79.8c-0.1-1.3-0.1-2.6-0.1-3.9c0-3.7-0.4-7.4-0.1-11c0.3-2.8-1.2-4.5-3.9-6\r\n\tc-0.7,1.1-0.5,2.2-0.2,3.3c1.1,4.3,2.3,8.6,3.5,13.1c0.1,0.2,0.5,0.4,0.8,0.6C1730.1,77.2,1730.1,78.5,1730.1,79.8z M1824.8,39.5\r\n\tc0.2-0.4,0.3-1,0-1.4c-3-4.6-5.3-9.5-9.4-13.5c-0.2-0.2-0.6-0.4-1-0.7c-2.2,0.9-4.4,1.8-6.5,2.7c1.1,3,1.5,3.3-2.7,5\r\n\tc-2.1,0.9-4.6,1.3-7.4,1.9c-0.3,0.5-0.7,1.4-1.2,2.3c1.5,0.9,3.1,1.1,4.9,1.3c6.7,0.8,13.2,2.2,18.8,5.5c0.6,0.3,1.2,0.6,2.1,1\r\n\tC1823.2,42.2,1824.1,40.9,1824.8,39.5z M1845.4,50.6c0-0.1-0.1-0.2,0-0.2c0.5-2.6,0.7-2.7-1.1-4.7c-5-5.6-10-11.1-15.1-16.6\r\n\tc-3.2-3.4-6.4-6.9-9.6-10.3c-0.8-0.8-1.4-1.9-3-0.8c0.9,2,2.8,3.4,4.3,5c2.5,2.6,4.6,5.4,6.8,8.1c5.2,6.3,7.8,13.5,10,20.8\r\n\tc0.8,2.7,2.9,4.4,5.5,6.2C1843.9,55.4,1844.7,53,1845.4,50.6z M1684.3,56.9c-2.1-3-4.1-5.9-6.4-9.5c-1.6,2.6-2.9,4.8-4.1,7\r\n\tc-1.2,2.2-2.2,4.4-3.2,6.6c-0.2,0.5-0.5,1.1-0.3,1.6c1.3,2.6,2.6,5.3,4.1,8.1c2.9-3.4,4.7-7.4,9.9-8.6\r\n\tC1685.9,60.4,1685.7,58.7,1684.3,56.9z M1660,67c1.2-3.2,1-5.8-1.5-8.4c-0.9-1-1.5-2.1-2.3-3c-0.1-0.1-0.3-0.2-0.7-0.3\r\n\tc-1.7,2.9-2.7,5.9-3.9,8.9c-1.3,3.4-1.7,6.6-0.1,9.9c1.4,3.1,2.1,6.4,3.3,10.1C1656.6,78.1,1657.9,72.4,1660,67z M1797,73.5\r\n\tc0.2-0.9,0.2-1.9-0.2-2.7c-2.3-4.9-5.6-9.3-9-13.7c-0.2-0.2-0.3-0.6-0.8-0.7c-0.5,2.3,1.6,4,2.1,6c0.5,2.1,1.4,4.2,1.9,6.2\r\n\tc0.5,2.2,0.8,4.4,1.1,6.6c0.3,2.2,0.5,4.2,0.8,6.4c0.2,2.2,0.4,4.2,0.6,7C1794.7,83.2,1795.9,78.4,1797,73.5z M1826.9,63.5\r\n\tc1.3,2.2,2,4.6,3,7c0.9,2.2,1,2.2,4.6,2.4c-0.4-3.4-0.7-6.6-1.1-9.9c-0.1-0.5-0.2-1-0.2-1.4c0.2-3.4-2.7-5.2-6.2-7\r\n\tC1826.7,57.6,1825.1,60.4,1826.9,63.5z M1697.7,70.6c0,2.1,1,4.2,1.8,6.3c0.9-3.4,0.3-6.9,2.9-9.8c0.5,0.1,1,0.2,1.3,0.2\r\n\tc1.6-4.9-2.1-8.3-4.3-12.2c-0.2,0.1-0.4,0.1-0.6,0.2C1698.5,60.4,1697.9,65.5,1697.7,70.6z M1817.8,60.1\r\n\tc-3.8-5.8-8.6-11.1-15.1-15.7c0.3,0.8,0.3,1.2,0.6,1.5c1.7,2.9,3.4,5.7,5.2,8.6c0.3,0.5,0.6,1,1.1,1.4c2.7,2.2,5.5,4.3,8.9,6.9\r\n\tC1818.1,61.6,1818.2,60.7,1817.8,60.1z M1789.7,49.3c3.6,4.4,7.1,8.7,10.6,13c2-2.3,1.6-4.7-1-6.6c-2.1-1.5-4.2-3-6.2-4.5\r\n\tc-0.8-0.6-1.4-1.3-1.9-2.3c1.8,0.2,3.5,0.4,5.6,0.6c-1.2-2.2-2.4-4.2-3.5-6.1c-0.2,0-0.4,0-0.7,0\r\n\tC1791.6,45.4,1790.6,47.4,1789.7,49.3z M1758.4,70.6c-0.1,0-0.3,0-0.4-0.1c-0.2,0.4-0.6,0.8-0.6,1.1c-0.3,3.4-0.5,6.8-0.8,10.2\r\n\tc-0.2,2.6,1.8,4.5,3,6.6c0.2-0.1,0.5-0.1,0.7-0.2C1759.7,82.5,1759,76.6,1758.4,70.6z M1848.4,60.4c-0.7,2.2,0.6,3.5,2.8,5\r\n\tc0.5-2.3,1.2-4.4,1.5-6.4c0.1-0.7-0.5-1.5-0.9-2.2c-0.6-0.8-1.3-1.5-2-2.3c-0.3,0-0.5,0-0.8,0C1848.8,56.5,1849,58.5,1848.4,60.4z\r\n\t M1859,75.8c1,1.1,1.6,2.5,2.5,3.7c-0.4-3.6-1.4-7.1-3.4-10.4C1857.4,71.4,1857,73.6,1859,75.8z M1846.5,77.2\r\n\tc-0.1,1.4,1.4,1.8,2.5,2.6c1.1-2.9,1.6-5.4-1.9-7.6C1846.8,74.1,1846.6,75.6,1846.5,77.2z M1804.4,70.1c1.3,4.8,2.8,9.6,4.1,14.4\r\n\tc-0.2-5.6-1.6-11-4.2-16.3C1804.3,68.8,1804.2,69.5,1804.4,70.1z M1818.9,49c-1-0.5-1.9-1-3.1-1.2c1.2,1.4,2.5,2.9,3.9,4.5\r\n\tC1820.7,50.8,1820.5,49.8,1818.9,49z M1749.8,84.7c-0.1,0.3-0.3,0.5-0.2,0.6c0.2,1.1,0.5,2.3,0.7,3.4\r\n\tC1750.7,87.4,1750.9,86,1749.8,84.7z M1841,69.5c0.8-1.4,1.6-2.4,0-3.7C1841,67.1,1841,68,1841,69.5z M1856.4,85.7\r\n\tc-0.6,1.4,0.2,2,1.3,2.4C1857.3,87.5,1857,86.8,1856.4,85.7z M1607.8,24.1c-4.5,1.1-7.3,3.5-10.5,5.7c-6.9-8.8-16.4-15.1-27.9-19.6\r\n\tc-5.5-2.1-11.4-3-17-4.8c-0.1,0.2-0.2,0.3-0.3,0.5c0.5,0.3,0.9,0.6,1.4,0.8c13.1,4.7,24.5,11.2,33.4,20.3c2,2,3.4,4.5,5,6.7\r\n\tc0.3,0.5,0.3,1.3,0,1.8c-3.4,4.6-5.4,9.5-6.8,14.7c-0.1,0.3-0.3,0.6-0.6,1.1c-1.5-1-2.8-1.8-4.1-2.7c-0.2,0.1-0.4,0.2-0.6,0.2\r\n\tc0,0.4-0.1,1,0.2,1.3c0.8,1.2,1.8,2.3,2.7,3.4c1,1.2,1,2.5,0.6,3.8c-0.5,2-0.9,4.1-1.4,6.3c-0.4-1.5-0.7-2.9-1.2-4.8\r\n\tc-1.2,1.3-2.1,2.2-3,3.1c-1.5-0.8-3-1.6-4.5-2.3c-0.9-0.5-1.1-1-1-1.8c0.2-1.4,0.5-2.6,0.7-4c0-0.4-0.4-0.8-0.6-1.2\r\n\tc-0.5,0.2-1.3,0.5-1.5,0.8c-0.7,1.4-1.3,2.8-2,4.3c-1-0.2-1.6-0.4-3-0.6c0.9,0.9,1.4,1.4,1.9,1.8c0,0.2,0,0.5-0.1,0.6\r\n\tc-3.8,7.5-6.2,15.3-7.4,23.3c-0.6,4.3-0.7,8.7,1,13.1c0.1,0.4,0.3,0.7,0.5,1.2c1.6,0,3,0,4.9,0c0.2-0.9,0.7-1.9,0.6-2.9\r\n\tc-0.6-7.6,1.2-14.9,3.1-22.3c0.7-2.7,1.2-5.4,1.9-8.4c2.2,2.2,3.7,3.8,2.9,6.8c-1.8,6.5-2.3,13.1-1.4,19.7c0.2,1.8,0.1,3.5,0.3,5.3\r\n\tc0,0.6,0.2,1,0.4,1.8c1.6,0,3.2,0,5.1,0c0.3-7,0.6-13.9,0.9-20.7c0.2,0,0.4,0,0.6,0c0.1,1.1,0.1,2.2,0.2,3.4\r\n\tc0.2,3.2,0.2,6.4,0.6,9.5c0.2,1.9,1,3.8,1.6,5.8c0.1,0.5,0.4,1,0.9,1.2c0.5,0.4,1.3,0.6,1.9,0.9c0.3-0.5,0.7-1,0.8-1.4\r\n\tc0.2-1.8,0.2-3.6,0.3-5.4c0-0.6,0.3-1,0.5-1.9c1.9,3.2,2.8,6.6,6,8.7c0.3,0.2,0.9,0,1.5,0c0.1-0.5,0.2-0.9,0.1-1.3\r\n\tc-1.4-6.5-3.1-13-6.5-19.1c-0.3-0.6-0.7-1.4-0.6-2c0.3-3.1,0.7-6.2,1.7-9.5c1.2,1.8,2.5,3.7,3.7,5.6c2.7,4.3,4.2,8.9,5.1,13.7\r\n\tc0.5,2.8,0.9,5.7,1.5,8.5c0.3,1.4,0.7,2.6,1.1,4.1c1.4,0,2.6,0,4,0c0.3-2.3,0.5-4.6,0.8-6.8c0.1,0,0.1,0,0.2,0\r\n\tc0.4,2.2,0.9,4.5,1.3,6.8c2.4,0,4.5,0,6.7,0c0.2-0.6,0.5-1,0.5-1.6c0-3.9,0-7.8-0.1-11.7c0-1.3-0.3-2.6-0.3-3.8\r\n\tc0-8.9-0.4-17.9,0.3-26.7c0.8-9.7,4.2-18.8,12.3-26.4c0.3-0.3,0.6-0.6,1.2-1.3c-4.5,0.7-7.9,2.4-10.5,4.9c-3.7,3.4-5.9,7.4-7.4,11.6\r\n\tc-1.2,3.4-2.1,7-3.3,10.7c-0.7-2-1.3-3.7-1.9-5.4c-1.4-3.8-2.8-7.4-4.3-11.1c-0.4-1-0.3-1.6,0.3-2.4\r\n\tC1603.3,30.6,1605.4,27.4,1607.8,24.1z M1596.1,42.5c-0.4,0.6-0.9,1-1,1.5c-1.3,3.8-2.5,7.7-3.6,11.5c-0.2,0.6,0.3,1.5,0.8,2.2\r\n\tc2.9,4.5,6.1,9,8.9,13.5c1.2,2,1.9,4.2,2.8,6.2C1602.2,65.8,1600.9,54.1,1596.1,42.5z M1617.3,94c-0.3-1.9-0.5-3.8-0.5-5.7\r\n\tc0-4.9-0.1-9.7,0.4-14.6c0.6-5.9,2.4-11.8,4.4-17.5c2.4-7,5.6-13.6,9.9-19.9c2.5-3.6,5.2-7.1,7.8-10.7c0.1-0.2,0.5-0.3,0.8-0.4\r\n\tc0.1,0.9-0.3,1.4-0.6,2.1c-1.2,2.4-2.6,4.8-3.5,7.3c-1.8,5-3.4,10-5.1,15c-1.4,4.2-2.9,8.4-4.2,12.7c-0.3,1-0.6,2.2-0.1,3\r\n\tc3.1,4.9,4.5,10.2,6.2,15.5c0.2,0.6,0.3,1,0.7,2.1c0.4-3.8,0.5-7.1,1-10.3c0.5-3.3,1.4-6.6,2.2-9.9c0.1-0.5,0.7-0.8,1-1.2\r\n\tc0.4,0.4,1,0.7,1.1,1.2c0.4,1.4,0.7,2.8,1,4.2c0.8,3.1,0.8,6.3,0.5,9.5c-0.5,6.1-0.6,12.3-0.9,18.4c0,0.8-0.1,1.5-0.2,2.4\r\n\tc-3.5,0-6.9,0-10.2,0c-2.3-6.4-2.5-13.1-5.4-19.4c-0.5,5.7-0.7,11.3-1,17c0,0.8-0.3,1.7-0.5,2.5c-1.4,0-2.5,0-3.9,0\r\n\tC1617.9,96,1617.4,94.9,1617.3,94z M1358.3,35.6c0.6-0.5,1.2-1,1.8-1.5c0.2,0.2,0.3,0.3,0.5,0.5C1359.7,34.8,1359,35.2,1358.3,35.6z\r\n\t M540.2,44.2c0.1,0.3,0.2,0.6,0.4,0.9c1.7,2.2,3.6,4.2,5.3,6.3c1.9,2.3,3.4,4.8,4.4,7.6c-1.4-0.1-2.4-0.1-3.4-0.2\r\n\tc0.3,0.4,0.7,0.6,1.2,0.6c2.1,0,3.2,0.8,3.7,2.5c0.5,1.6,1.2,3.2,1.9,4.8c0.6,1.2,0.4,2.2-0.5,3.4c-1.8,2.4-3.4,4.9-5.2,7.2\r\n\tc-0.9,1.2-2,2.3-3.1,3.6c-2-3-3.9-5.8-5.7-8.6c-0.3-0.6-0.2-1.4,0-2c1.2-2.9,2.5-5.7,3.7-8.6c0.5-1.3,1.3-2.5,1.4-4\r\n\tc-3.5,1.7-4.7,4.6-7.3,7c-3.1-10.3-7.8-19.8-15.7-28c3.8,7.8,6.1,15.9,8.2,24c-0.4-0.2-0.6-0.2-0.7-0.3c-0.7-0.2-1.6-0.7-1.9-0.6\r\n\tc-1,0.6-0.3,1.3,0.2,1.8c0.5,0.7,1.1,1.4,1.5,2.1c0.9,1.6,1.7,3.3,2.6,4.9c-3.2,1.4-6,2.6-9,3.9c-0.6-2.6-1-5-1.6-7.4\r\n\tc-0.3-1.3-0.2-2.5,0.5-3.7c1.1-1.8,2-3.7,2.9-5.4c-0.2-0.1-0.3-0.2-0.5-0.2c-1.4,1.3-2.9,2.5-4.5,4c-0.4-2.1-0.7-3.8-1-5.5\r\n\tc-0.2,0-0.5,0-0.7,0.1c0.1,1.1,0.3,2.2,0.3,3.4c0,1.4,0.4,3-0.3,4.2c-1,1.8-2.7,3.4-4.3,5.4c-2-5.1-3-10.2-7-14.3\r\n\tc1.1,6.1,2.2,12.2,3.4,18.2c0.2,1.2,0.1,2.2-0.4,3.2c-1.5,3.1-3,6.2-4.5,9.4c-0.2,0.5-0.5,0.9-1,1.7c-0.4-2.4-0.7-4.5-1-6.5\r\n\tc-1-7.3-3.2-14.3-7-20.9c-1.9-3.4-4.6-6.6-5.4-10.3c0-0.2-0.4-0.2-0.8-0.6c0.6,3.4,1.1,6.5,1.6,9.2c-3,2.4-5.7,4.5-8.5,6.6\r\n\tc-3.5-3.9-6.3-8-10.8-11.1c0.4,2.9,2.7,5.3,3.7,8c-1.6-1.2-2-3-4.5-4.2c0.4,1.7,0.8,3,1.1,4.2c0.3,1.2,0.4,2.5,0.7,3.7\r\n\tc0.9,2.3,1.7,4.6,2.5,7c0.1,0.3-0.2,0.8-0.4,1.1c-3,5.1-5.3,10.4-6.7,16c-0.1,0.2-0.2,0.4-0.4,0.7c-0.7-3.1-1.3-6.2-1.9-9.3\r\n\tc-0.2-1-0.3-2-0.9-2.7c-1.7-2.2-0.4-3.8,1.3-5.4c2.3-2.3,4.2-4.8,6.2-7.2c-3.6,1.7-7.1,3.4-10.9,5.2c-0.8-1.4-1.5-3-2.5-4.4\r\n\tc-1.1-1.5-0.9-2.7,0.3-4.2c5.3-6.4,11.4-12.3,18.4-17.5c2.7-2,5.6-3.8,8.3-5.7c-1-0.2-2-0.1-2.7,0.2c-3,1.4-6.1,2.7-8.9,4.3\r\n\tc-7.7,4.5-14,10.1-19.4,16.3c-0.3-0.1-0.6-0.1-0.7-0.2c-0.5-0.5-1-1-1.5-1.4c-3.8-3.6-7.6-7.3-13-9.3c-4.1-1.5-8.5-2.8-12.7-4.2\r\n\tc-0.8-0.2-1.6-0.6-2.1,0.2c-0.5,0.8,0.3,1.1,1,1.4c1.4,0.6,3,1,4.2,1.8c5.5,3.4,10.6,7.2,14.8,11.7c-0.2,0.2-0.3,0.5-0.4,0.7\r\n\tc-6,5.9-10.1,12.7-12.9,20c-0.6,1.6-1.8,3-2.8,4.5c-1.7,2.5-3.5,5-5.2,7.5c-0.3,0.4-0.6,0.8-0.8,1.2c0.4-3.9,0.8-7.8,2-11.5\r\n\tc1.2-3.8,2.8-7.6,4.5-11.4c1.7-3.6,3.7-7,5.6-10.6c-8.4,5.8-11.8,13.8-14.7,22c-0.3-0.3-0.5-0.4-0.5-0.6c-0.6-3.4-1.2-6.7-1.8-10.2\r\n\tc-0.1-0.4,0.1-1,0.5-1.3c2.5-2.4,5.2-4.8,8-7.4c-3.3,0.6-6.2,1.2-9.3,1.8c-1.7-6.9-3.5-14-5.2-21c5-2.3,5-5.9,4.4-8.8\r\n\tc-0.1-0.6-0.7-1.4-1.3-1.8c-0.7-0.3-1.7-0.2-2.6-0.2c0-0.6,0-1.3,0-1.9c0-0.7,0.1-1.4,0-2.2c-0.3-2.5-1.6-3.3-4.3-2.8\r\n\tc-0.7-1.5-1.2-3-2-4.5c-0.4-0.7-1-1.4-1.8-1.8c-0.7-0.3-1.8-0.1-2.8-0.1c-0.9-1-1.5-2.5-3.7-3c0,1.5,0,3,0,4.2\r\n\tc-3.2,0.8-3.7,1.4-2.8,3.8c0.4,1,1,2.1,1.5,3.1c-1.9,1.9-1.9,2.8,0.2,4.7c1.3,1.2,2.7,2.3,4,3.4c-2.4,1-2.5,2-1.2,4.3\r\n\tc1,1.9,2.9,3.2,5.4,3.9c1.3,0.4,2.6,0.7,4.1,1.1c1.4,6,2.5,12.1,4.2,18c0.9,3-0.4,4.9-3.3,6.3c-0.1,0.1-0.2,0.1-0.6,0.2\r\n\tc-2-6.1-3.1-12.3-6.1-18.1c-3.1-5.9-7-11.5-12.1-16.2c0.8-2.1,1.6-3.9,2.3-5.8c-1.3-0.6-1.3-1.8-1.5-2.9c-0.6-3.3-2.2-4.7-5.9-5.3\r\n\tc-0.4-1-0.8-2.2-1.2-3.2c-1.2-2.7-2.6-3.2-5.7-1.9c-2.4-3-2.9-3.2-5.2-2.1c-0.7-0.6-1.4-1.4-2.1-2c-2.5-2.2-2.5-2-5.3,0.1\r\n\tc-2.1,1.5-1.6,3-0.7,4.5c0.6,1,0.9,1.7,0.5,2.8c-0.2,0.6,0.5,1.6,1.1,2.3c0.6,0.6,1.5,1,2.2,1.5c-1.2,1.9-1,3,1.2,4.2\r\n\tc1.4,0.8,2.8,1.5,4.5,2.4c-0.7,0.6-1.2,1.2-1.7,1.7c1.1,2.2,2.2,4.4,3.3,6.6c0.7,1.3,0.4,2.2-0.6,3.4c-2.5,3-5.1,6.1-7,9.4\r\n\tc-5.2,8.6-7.9,18-9.8,27.5c-0.1,0.4-0.6,0.6-0.9,1c0.1,0.4,0.4,0.7,0.4,1.1c0.1,1,0,1.8-0.4,2.8c0-1.3,0-2.6,0-3.9\r\n\tc0.2-1.5,0.4-3.1,0.7-4.6c1-5.2,2.1-10.3,3.1-15.5c0.2-1,0.2-2.2,0.3-3.8c-1.3,0.8-2.2,1.2-2.8,1.8c-1.2,1.4-2.6,2.7-3.3,4.2\r\n\tc-1.4,3.2-2.7,6.5-3.6,9.9c-0.7,2.6-0.9,5.4-1.4,8.4c-0.5-5-1-9.5-1.5-14c-0.8-7.7-3.6-15-7.9-21.9c-1.9-3-4.5-5.7-8-7.6\r\n\tc-0.9-0.5-1.9-1.1-3.2-0.8c11.3,15.9,13.6,33.3,13.7,51.2c-1.8-5.4-3.6-10.7-5.4-16c-1.6-4.8-5.2-8.7-9.1-12.5\r\n\tc-0.5-0.5-1.1-0.7-2-1.4c7.8,16.5,11.5,33.3,14.3,50.3c2.6,0,4.7,0,7,0c0.5-1,0.9-1.9,1.5-3.1c0.2,1.3,0.4,2.2,0.6,3.4\r\n\tc2.1-0.8,4.6,1,6.1-1.4c2.2,1.7,3.7,1.4,4.7-0.8c0.2-0.4,0.2-0.8,0.3-1.2c0.2-1.3,0.3-2.6,0.5-3.8c0.3-1.4,0.7-3,1-4.4\r\n\tc0.2,0,0.4,0,0.6,0.1c0.3,3.7,0.7,7.4,1,11.1c1.7,0,3,0,4.8,0c0.1-2,0.4-4,0.3-5.9c-0.2-4.7-0.8-9.4-1-14.1c-0.2-5.4,0-10.7-0.2-16\r\n\tc-0.1-2.2,0.3-4.5,1.2-6.6c2.2-5.1,4.3-10.3,6.6-15.3c0.5-1,1.3-2.1,1.9-3.1c2.2,8.2,4.4,16.2,4.1,24.7c-4.7-1.8-4.7-1.8-5.5-5.4\r\n\tc-0.5-2.2-1.2-4.6-1.8-6.8c-0.2,0-0.5,0-0.7,0c-0.7,2.5-1.3,4.9-2,7.4c-0.6,0.2-1.2,0.3-2.4,0.7c3,1.1,2.8,2.9,2.8,4.6\r\n\tc0,5.2-0.1,10.3,0,15.5c0.1,5.4,0.4,10.8,0.6,16.3c0,1,0,2.1,1.7,2.6c0.3-0.4,0.7-0.6,0.7-1c0.6-2.4,1.5-4.8,1.6-7.3\r\n\tc0.4-7.8,0.4-15.8,0.6-23.6c0-0.5,0.1-1,0.3-2.1c1,1,1.5,1.6,2.2,2c1.7,1.1,2.4,2.5,2.4,4.3c0.3,9,0.8,18.2,1.3,27.2\r\n\tc0,0.6,0.1,1.2,0.2,1.9c3.3,0,6.5,0,9.9,0c2.2-5,4.3-10,6.6-15.2c2.2,1.3,3.3,2.5,3.1,4.5c-0.3,3.3-0.2,6.6-0.3,10\r\n\tc0,0.2,0.2,0.4,0.3,0.7c0.9,0,1.8,0,2.8,0c0.7-2.2,1.3-4.4,2.1-6.8c1.8,2,3.4,3.7,4.9,5.4c0.8,1,1.8,1.4,3.2,1.4c1.9,0,3.7,0,5.6,0\r\n\tc0.7-1.4,1.2-2.6,1.8-3.8c0.1,0,0.2,0,0.3,0c-0.1,1.1-0.2,2.3-0.3,3.6c1.6,0,3,0,4.6,0c0.2-1,0.4-1.8,0.6-2.6c1-5.4,2-10.9,3-16.3\r\n\tc0.2-0.8,0.6-1.8,1.2-2.4c2.7-2.6,5.8-5,9.5-7.3c-0.1,0.9-0.1,1.4-0.3,1.9c-0.6,2.1-1.1,4.2-1.8,6.2c-0.4,1.1-1,2.2-1.7,3.3\r\n\tc-2.4,3.7-5,7.3-7.3,11c-1.2,1.9-1.8,4-1.9,6.2c1.8,0,3.5,0,5,0c1.2-1.9,2.4-3.7,3.6-5.4c0.2,0.1,0.4,0.1,0.6,0.2\r\n\tc0.2,1.8,0.4,3.5,0.5,5.3c2.8,0.2,3,0,3.2-1.8c0.4-3.4,0.8-7,1.3-10.4c0.1-0.9,0.6-1.7,0.9-2.5c0.1,2.6-0.3,5-0.5,7.4\r\n\tc-0.1,2.4-1.1,4.8-0.5,7.3c1.4,0,2.6,0,3.8,0c0.2-1.6,0.6-3,0.7-4.5c0.3-4.2,0.9-8.3,0.5-12.4c-0.2-2.5,0.9-3.8,2.7-5.3\r\n\tc0.3,0.1,0.4,0.2,0.4,0.2c0,5.3,0,10.5-0.2,15.8c-0.1,2.2-0.2,4.2,0.6,6.3c1.3,0,2.4,0,3.9,0c0.5-6.2,1-12.2,1.5-18.2\r\n\tc0.4,0.9,0.5,1.7,0.7,2.6c0.4,3.2,1.1,6.5,0.5,9.8c-0.4,1.9-0.2,3.9,0.6,5.8c1.7,0,3.2,0,4.8,0c0.3-2.2,0.6-4.1,1-6.1\r\n\tc0.1,0,0.3,0,0.4,0.1c0.5,2,1.1,4,1.6,6c3.4,0,6.5,0,9.7,0c1-4.3,1.9-8.6,4.1-12.6c-1,4.2-2.1,8.3-1.8,12.6c1.3,0,2.3,0,3.2,0\r\n\tc0.4-0.8,0.7-1.4,1.1-2.2c0.4,1,0.7,1.6,1,2.2c1.3,0,2.6,0,3.9,0c0.1-0.4,0.2-0.7,0.2-1c-0.5-4.1-0.9-8.2-1.6-12.3\r\n\tc-0.2-1.2-0.1-2.1,1.1-3.3c2.2,5.8,4.4,11.1,6.5,16.7c2.6,0,5.3,0,8.1,0c1.9-4.6,3.1-9.4,6.5-14.2c0.8,5-0.3,9.7,1.1,14.2\r\n\tc1.2,0,2.3,0,3.7,0c0.1-2,0.3-3.9,0.3-5.8c0-4.7,0-9.4,0-14.1c0-1-0.1-2.1,1.8-2.6c0.7,7.5,0.7,15.1,2.1,22.4c1.6,0,2.8,0,4.2,0\r\n\tc0.1-1.1,0.2-2.1,0.2-3c-0.2-3.3-0.4-6.5-0.6-9.8c-0.3-4.4-0.8-8.7-1.1-13.1c0-0.6,0.1-1.4,0.5-1.8c2.5-2.3,5.3-4.4,8.7-6.2\r\n\tc0.1,1,0.1,1.9-0.2,2.7c-3.9,9.4-5.9,19-6.7,28.8c-0.1,0.8,0.1,1.5,0.2,2.4c1.6,0,3,0,4.5,0c0.3-2.4,0.6-4.6,0.9-7\r\n\tc0.3-2.3,0.7-4.6,1.1-6.9c0.5-2.2,1.1-4.3,1.7-6.5c1.5,6.7,1.5,13.5,1.1,20.4c1.8,0,3.3,0,4.8,0s2.9,0,4.4,0c0.9-2.6,0.2-5.1,2-7.2\r\n\tc0.2,1.2,0,2.3-0.1,3.4c-0.2,1.2-0.4,2.3-0.7,3.6c3.4,0,6.5,0,9.8,0c0.4-2.1-0.2-3.9-1.1-5.7c-0.6-1.2-0.7-2.2-0.2-3.4\r\n\tc1.1-2.6,2.1-5.1,3.1-7.7c0.2-0.5,0.6-0.8,1.2-1.6c0.5,6.5,0.9,12.5,1.3,18.5c1.9,0,3.3,0,5,0c0.2-1.1,0.4-2.2,0.7-3.5\r\n\tc0.2,1.4,0.4,2.4,0.5,3.5c2.5,0,4.9,0,7.3,0c0.7-1.1,1.3-2.2,2.1-3.6c0.7,1.4,1.3,2.5,1.9,3.6c1.4,0,2.7,0,3.9,0\r\n\tc0.1,0,0.1-0.6,0.2-0.9c-0.1-2.8-1.8-5.1-3.1-7.6c-0.7-1.4-0.7-2.5,0.8-3.8c0.9,3.4,1.9,6.6,2.7,9.9c0.1,0.5-0.2,1-0.4,1.6\r\n\tc1.4,0.9,2.9,1,4.6,1c1.6-0.1,3.2,0,4.8,0c1.1,0,2.3-0.1,3.8-0.1c0.2-3.8,0.5-7.3,0.7-11.3c2.4,2.6,4.3,4.6,2.9,7.5\r\n\tc-0.5,1.1-0.6,2.4-0.8,3.7c10.8,0,21.4,0,32.2,0c0.4-2.6,1.1-5,1-7.4c-0.1-3,1.2-5.4,3.6-7.5c1.7-1.5,3.1-3.4,4.5-5\r\n\tc0.4-0.4,0.3-1,0.5-1.8c-3.2,0.2-5.1,2-7.3,3c-0.2-0.2-0.3-0.4-0.3-0.6c0.2-3.6,0.4-7.1,0.5-10.7c0-1.1,0.7-1.8,1.6-2.4\r\n\tc5.4-3.8,10.8-7.6,16.2-11.3c1.6-1,3.5-1.8,5.3-2.6c0.6-0.3,1.3-0.5,1.8-0.8c0.2-0.2,0.3-0.6,0.2-0.8c-0.1-0.2-0.6-0.5-0.9-0.5\r\n\tc-0.7,0.1-1.3,0.3-2,0.5c-2.7,0.9-5.4,1.6-8,2.6c-3.3,1.3-6.4,2.8-9.6,4.3c-1.3,0.6-2.5,1.4-3.9,2.3c-0.5-5.1-0.9-9.9-1.3-14.7\r\n\tc-0.3-3.1-4.1-12.4-5.7-13.9c0,0.8-0.1,1.4,0,1.9c0.3,2.4,0.9,4.7,0.9,7.1c0,3.4-0.3,6.8-0.6,10.3c-0.3,4.2-0.5,8.4-0.9,12.7\r\n\tc-0.1,1.1,0.1,2.5-2.1,3c0.2-2.9,0.3-5.6,0.5-8.3c-0.7,0.2-1,0.5-1.3,0.7c-2.8,3.5-4,7.6-5.2,11.6c-0.8,2.8-3.1,4.4-5.4,6.8\r\n\tc-2.6-11.1-5-21.8-10.1-32c-0.3,1.8-0.5,3.7-0.2,5.4c0.9,6.9,1.9,13.8,3,20.6c0.5,3.3,0,5.4-2.4,8.3c-2-2.4-4-4.8-6.1-7.1\r\n\tc-1.1-1.3-2-2.6-2.2-4.1c-0.4-3.8-2.9-7.4-0.9-11.4c0-0.1-0.2-0.2-0.3-0.4c-0.6,0.1-1.1,0.2-1.5,0.3c-2.5-5.8-5-11.6-7.6-17.6\r\n\tc0,0,0.3-0.4,0.6-0.6c2.9-2.6,5.9-5.2,8.9-7.7c0.8-0.6,1.8-1.1,3.3-0.9c3.3,0.5,6.5-0.1,9.4-1.5c2.7-1.3,3-2.1,1.8-4.4\r\n\tc4.5-0.9,5.1-1.4,4.8-3.8c1.3-0.6,2.7-1,3.9-1.7c1.5-0.8,2.1-1.8,1-3c2.4-1.7,3.3-3.4,2.1-4.4c-0.7-0.1-1.5-0.2-2.5-0.3\r\n\tc0.8-1.3,0.5-2.2-0.7-2.9c-1.7-0.8-3,0.4-4.3,0.9c-1-2-2.3-2.4-4.1-1.3c-0.5,0.3-1,0.8-1.4,1.2c-0.7,0.8-1.4,1.7-2.1,2.6\r\n\tc-2-1.2-2.7-1.4-4.1,0.2c-1.4,1.4-2.3,3.3-3.5,4.9c-0.3,0.5-0.6,1.2-1.1,1.2c-2.3,0.3-2.9,1.8-3.6,3.2c-1.4,2.7-1.7,5.5,0.1,8.2\r\n\tc-3.8,2.6-7.4,5-11,7.4c-0.4-0.5-0.7-0.7-0.9-1c-5.8-7.9-14.4-13.5-23.8-18.3c-0.7-0.3-1.3-0.7-2.1,0.1c2.8,2.3,5.8,4.4,8.4,6.9\r\n\tc2.6,2.5,4.9,5.2,7.2,7.9c2.2,2.7,4.1,5.5,6.4,8.6c-3,2.2-5.8,4.2-8.9,6.3c-2.3-0.4-2.1-3-4.3-4c-0.2,0.4-0.4,0.9-0.6,1.4\r\n\tc-3.7-1.8-7.4-3.7-11.8-4.4c4.5,3.7,9,7.3,13.6,11.1c-1.3,1.4-2.4,2.6-3.5,3.7c-2.2-0.7-2.2-0.7-2.9-1.9c-1.2-2.1-2.4-4.2-3.9-6.2\r\n\tC550.2,49.2,546,46,540.2,44.2z M400,80.7c1.3-2.2,2.6-4.2,3.7-6.2c0.3-0.6,0.2-1.3,0-1.8c-2.2-9.3-4.6-18.6-9.5-27.2\r\n\tc-1.6-2.8-3.2-5.6-5.6-8.1c-1.9-1.8-2.4-1.9-4.2-0.1c-0.4,0.5-0.8,1-1.2,1.4c-0.8,0.9-0.7,1.6-0.2,2.6c4.4,8.8,7.3,18,7.5,27.6\r\n\tc0.1,3.4,1,5.8,4.5,7.8C397,77.6,398.3,79.2,400,80.7z M414.6,72.4c-2.8,1.8-4.3,3.6-3.9,6.2c0.4,2.7,0.8,5.6,0.5,8.3\r\n\tc-0.3,3.6,0.6,6.7,3.3,9.5c1,1,1.6,2.2,2.3,3.4c0.2-0.1,0.5-0.1,0.7-0.2C417.9,90.7,415.8,81.8,414.6,72.4z M490.5,58.1\r\n\tc-3.4,2.1-4.5,5-6.4,7.4c2.4,4,4.7,7.9,7,11.9c2.5-1.2,3.2-2.6,2.6-4.7C492.5,67.9,491.6,63.1,490.5,58.1z M446.6,59.6\r\n\tc-0.3,0.1-0.5,0.1-0.8,0.2c-2.5,5.2-6.2,10.1-7.8,15.9c2.1-1,3.6-2,5.4-2.3c3.4-0.6,4.6-2.3,5.5-4.6c0.3-0.9,1-1.7,1.4-2.6\r\n\tc0.2-0.6,0.4-1.4,0.1-1.8C449.2,62.7,447.9,61.1,446.6,59.6z M578.4,57.3c-0.7,1.4-1.1,2.3-1.6,3.4c2.3,1.9,4.4,3.7,6.5,5.5\r\n\tc-1.1-5.2-3-10.2-5.7-15.2c-2.2,2-4.1,3.8-6,5.5c1.1,0.8,2,1.4,2.8,1.9C575.7,58,576.8,57.7,578.4,57.3z M573.5,87.9\r\n\tc2.2-2.9,3.3-5.5,2-8.6c-0.3-0.7-0.5-1.5-0.5-2.3c0-2.3-1.9-3.6-4.2-5c0,3.1,0.2,6-0.1,8.8C570.5,83.4,571.6,85.6,573.5,87.9z\r\n\t M392.1,98.5c1.7-4,3.3-7.8,4.8-11.7c0.2-0.6,0.4-1.4,0.1-1.8c-1.6-1.7-3.3-3.2-5-4.8C391.1,86.5,391.7,92.5,392.1,98.5z\r\n\t M619.8,101.7c0.1,0,0.3,0.1,0.4,0.1c0.6-1,1.2-2,1.8-3c1.2-1.8,1.8-3.6,1.8-5.7c0-2.7,0.4-5.4,0.5-8.1c0.1-1.4,0-2.7,0-4.2\r\n\tc-2.6,2-2.6,2-2.8,4.4c-0.5,5-1.1,10.2-1.7,15.2C619.7,100.9,619.8,101.3,619.8,101.7z M478.2,78c-0.3,0-0.5,0-0.8,0\r\n\tc-0.3,1.4-1.1,2.9-0.8,4.2c0.7,3.8,0.3,7.4-0.1,11.1c-0.2,2-0.6,4-1,6c2-3.8,3.6-7.8,5.3-11.6c0.2-0.4,0.3-0.8,0.2-1.1\r\n\tC480.1,83.8,479.2,80.9,478.2,78z M556.3,75.4c-0.2-0.1-0.4-0.1-0.7-0.2c-0.3,0.3-0.8,0.6-1,1c-2.1,3.5-4.2,7-6.3,10.5\r\n\tc-0.7,1.2,0,2.1,0.7,3.2c0.4-0.4,0.6-0.5,0.7-0.7c2.1-3.9,4.2-7.8,6.2-11.9C556.2,76.8,556.2,76,556.3,75.4z M517.4,68.7\r\n\tc-2.8,2.7-3.4,5.6-1.2,9.2C518.7,74.8,517,71.7,517.4,68.7z M584.1,83c1,4.2,1.9,8.1,2.9,12c0.5-2,0.3-4.1,0.6-6.1\r\n\tC587.9,86.5,586.4,84.8,584.1,83z M453.9,70.4c-0.2,0-0.4,0-0.6,0c-0.9,1.8-1.7,3.6-2.6,5.4c-0.3,0.6-0.4,1.4-0.7,2\r\n\tc1.5-0.8,2.7-1.9,4-2.9c1.2-0.9,1.4-1.8,0.8-3C454.5,71.5,454.2,71,453.9,70.4z M494.7,78c-2.4,3-2,6.1,1.4,9.6\r\n\tC495.6,84.3,495.1,81.2,494.7,78z M614.1,98.3c0.2-2.3,0.3-4.6,0.5-7C611.6,93.6,613.8,96,614.1,98.3z M377.2,32.8\r\n\tc-0.1,0.1-0.2,0.2-0.3,0.2c1.1,1.2,2.1,2.3,3.3,3.7c0.7-0.6,1.1-1,1.6-1.4C380.1,34.3,378.7,33.5,377.2,32.8z M564.3,84.4\r\n\tc0.1-2.4,1-4.9-0.3-7.2c-0.2,0-0.4,0-0.7,0.1C563.7,79.6,564,82,564.3,84.4z M358.7,84.3c-0.2,0-0.3,0.1-0.5,0.1\r\n\tc-0.3,2.8-0.5,5.7-0.8,8.5c0.1,0,0.3,0,0.4,0C358.1,90,358.4,87.2,358.7,84.3z M561.6,69.6c0.9-1.1,1.7-1.9,2.5-3\r\n\tc-0.8-0.2-1.5-0.5-1.7-0.4C561.4,67.1,560.5,68,561.6,69.6z M509.2,83.7c0.2,0.1,0.4,0.2,0.5,0.2c1-0.8,1.9-1.7,0.9-3.2\r\n\tC510,81.9,509.6,82.8,509.2,83.7z M573.3,67.1c0.3-0.9,0.5-1.6-0.4-2.2C571.7,65.8,571.3,66.5,573.3,67.1z M606.3,88.7\r\n\tc-0.3,0-0.6-0.1-0.9-0.1c-0.1,0.8-0.1,1.6-0.2,2.5c0.3,0,0.6,0,0.9,0.1C606.2,90.3,606.2,89.5,606.3,88.7z M485.5,80.5\r\n\tc0.3-0.1,0.5-0.2,0.8-0.2c-0.4-0.7-0.8-1.4-1.2-2.2c-0.2,0.1-0.3,0.1-0.5,0.2C484.9,79,485.2,79.8,485.5,80.5z M486.9,83.7\r\n\tc0-0.8,0-1.4,0-2.3C486.1,82.7,486.1,82.7,486.9,83.7z M580.7,72.4c0.1-0.1,0.3-0.2,0.4-0.2c-0.4-0.4-0.8-0.7-1.2-1.1\r\n\tc-0.1,0.1-0.2,0.2-0.3,0.2C580,71.6,580.3,72,580.7,72.4z M208.7,105c0.7-8.5,0-17.1-0.5-25.5c-0.1-2.1,0.5-3.9,1.8-5\r\n\tc0,5-0.1,10.3,0,15.5c0.1,5.2-0.5,10.5,0.1,15.7c2,0,3.6,0,5.4,0c2.2-8.5,1.5-17,1.4-25.5c1,2.1,2,4.2,2.9,6.4\r\n\tc0.5,1.1,0.5,2.3,0.1,3.4c-1.6,4.6-2.5,9.3-2.9,14.1c0,0.5,0.1,1,0.2,1.5c4.3,0,8.4,0,12.7,0c0.1-0.6,0.3-1,0.3-1.5\r\n\tc0.4-3.6,0-7.2-1-10.7c-0.8-2.6-0.7-5.1,0.6-7.7c0.8-1.5,1.4-3,2.1-4.6c0.2,0,0.5,0.1,0.7,0.1c2.2,8.1,4.4,16.3,6.6,24.4\r\n\tc3.3,0,6.5,0.1,9.8-0.1c0.6-4,0.7-7.7,1.8-11.9c0.8,4.2-0.2,8,1.1,11.8c1.6,0,3,0,4.5,0c0.2-0.6,0.5-1,0.5-1.4\r\n\tc0.1-3.8,0.5-7.5,0.2-11.2c-0.4-4.6-1.4-9.3-2-14c-0.4-2.9-0.2-5.7,1-8.4c0.2-0.4,0.1-1,0.1-1.4c-0.2-0.1-0.4-0.1-0.6-0.2\r\n\tc-0.8,1-1.5,1.9-2.3,2.9c-2.2-4.8-4.3-9.4-6.4-14.2c1.8-2.3,3.7-4.9,5.9-7.6c-3.6,0.4-5.9,2.2-8.5,3.3c-0.3-0.2-0.5-0.3-0.5-0.4\r\n\tc-2.8-5.4-8-9.2-12.5-13.6c-0.5-0.5-1-1.3-2.4-0.4c0.5,0.6,0.9,1.1,1.4,1.7c0.7,0.9,1.5,1.7,2.1,2.6c2,3.7,3.8,7.5,6,11.2\r\n\tc1.3,2.2,1.1,3.8-1,5.5c-1.5,1.2-2.5,2.7-3.9,4.2c-3.2-6.1-6.7-11.7-11.2-16.8c-2.4-2.8-5.3-5.2-8.6-7.2c-1.9-1.1-3.9-2.4-7.1-2.6\r\n\tc4.4,5.4,8.8,10.2,12,15.5c-1.6,1.5-3.1,2.8-4.4,4.2c-1.4,1.4-2.8,2.9-4,4.4c-1.2,1.4-2.2,2.9-3.4,4.6c-0.8-2.2-1.1-4.2-2.1-5.8\r\n\tc-1.4-2.2-0.6-3.9,1.1-5.7c0.6-0.6,1.3-1,1.9-1.5c0.3-0.3,0.6-0.6,0.8-1c-0.1-0.1-0.2-0.2-0.3-0.2c-1.9,1-3.7,1.9-5.8,3\r\n\tc-0.7-1.1-1.2-2-1.9-2.9c-0.6-0.8-0.9-1.9-2.3-2.6c0.2,2.2,0.4,4.2,0.4,6.2c0,0.7,0,1.5-0.4,2c-1.2,1.3-2.7,2.4-4.3,3.8\r\n\tc-0.5-2-0.9-3.8-1.5-5.4c-0.6-1.7-1.3-3.4-2.2-5c-0.8-1.5-1-3.3-3.3-4.7c0.3,2.6,0.6,4.7,0.7,6.8c0.1,4.6,0,9.2,0,13.9\r\n\tc0,2.2-0.5,4.2-1.8,6.2c-1,1.4-1.6,3-2.3,4.6c-0.9,2-1.7,4.1-2.7,6.5c-0.3-0.9-0.6-1.4-0.7-1.9c-0.4-1.5-0.7-3.1-1.2-4.6\r\n\tc-0.6-1.9-0.4-3.7,0.1-5.6c0.7-2.6,1.1-5.1,1.7-7.8c0.2-1.1,0.4-2.3,0.7-3.4c0.2-0.6,0.4-1.4-0.5-1.6c-0.5-0.1-1.3,0.5-1.7,1\r\n\tc-1,1.1-1.9,2.4-2.8,3.5c-3.4-0.7-5.8,1.1-8.5,1.8c-1.3-4.2-2.6-8.2-3.8-12.2c-0.3,1.4,0,2.9-0.4,4.2c-0.9,3-1.2,6.2-1.1,9.2\r\n\tc0.1,1.5-0.7,2.5-1.9,3.5c-2.7,2.3-5.2,4.8-7.7,7.3c-1.7,1.8-3.2,3.6-5.1,5.7c-0.3-1.3-0.5-2.1-0.7-2.9c-0.9-4.5-1.9-8.9-2.8-13.4\r\n\tc-0.1-0.6-0.2-1.1,0-1.6c1.3-3.4,2.7-6.6,4-9.5c3.4-1.4,6.6-2.4,9.4-3.9c2.2-1.2,4-2.9,5.6-4.6c1.4-1.4,0.7-2.3-1.6-2.9\r\n\tc-0.3-0.1-0.5-0.2-0.9-0.3c0.1-0.8,0.5-2.2,0.3-2.2c-1.5-0.6-0.7-1-0.2-1.6c2.5-2.3,2.1-5.5,4-7.9c-0.8-0.4-1.3-0.6-1.9-0.8\r\n\tc0.6-2.2,2.6-4.2,1.6-6.6c-2.3-0.3-3.3,1.2-4.8,1.9c-0.5-1,0.9-2-0.8-2.9c-0.6,1.8-1.2,3.4-1.9,5.1c-3.8-0.2-2.8,2.2-3.2,3.8\r\n\tc-0.8-0.2-1.5-0.5-2.4-0.8c-0.2,1-0.4,1.7-0.6,2.4c-2.6,0.6-2.6,0.6-2.6,3c0,0.6,0.1,1.6-0.3,1.8c-2.1,1-1.9,2.6-2.3,4.2\r\n\tc-2.2-0.5-3.4-0.1-3.3,1.4c0.3,3-0.2,6.1,2.4,8.6c-1.2,1.8-2.4,3.4-3.8,5.4c-1.3-2.1-2.5-3.9-3.7-5.7c-1.2-1.8-2.5-3.6-5.6-4.7\r\n\tc1.6,4.6,3,8.9,4.5,13.3c-7.7,3.3-10.4,9.4-14,15.5c-1.6-4.6-3.1-8.6-4.5-12.7c-0.4-1.1-0.4-2.3-0.6-3.1c-0.6-0.4-1.1-0.7-1.6-1\r\n\tc0.6-0.6,0.6-0.6,0.7-0.6c6.6-5,12.7-10.5,19.9-15.1c0.7-0.5,1.5-0.9,0.8-1.8c-0.7-0.9-1.5-0.3-2.3,0c-2.1,1-4.2,1.8-6.3,2.7\r\n\tc-2.8,1.4-5.7,2.6-8.4,4.1c-2.4,1.3-4.5,2.8-6.9,4.3c-1.3-2.2-2.5-4.4-3.8-6.4c-1.2-1.8-0.8-3.4,0.9-4.8c0.6-0.5,1.5-0.9,1.1-2\r\n\tc-1.4,1-2.7,1.8-4.2,2.8c-1.4-2.6-4.2-4.6-2.5-7.7c0.1-0.2,0-0.6,0-1c0-2.1,0-4.2,0-6.2c0-2.6-0.5-3-3.6-3.4\r\n\tc-0.5-3.6-0.5-3.6-4.1-4.5c-0.1-0.2-0.1-0.6-0.2-0.9c-1.1-3.1-2.4-3.5-5.7-2c-0.1,0.1-0.4,0-0.6-0.1c-0.1-0.2-0.3-0.4-0.3-0.6\r\n\tc-0.7-4-5.3-3.4-8.4-4.6c-0.2-0.1-0.6,0.2-0.9,0.4c-1.6-1.5-2.3-3.7-5.2-3.8c-1.9,1.4-2.1,1.9-1.3,3.6c0.3,0.6,0.6,1.4,1.1,1.9\r\n\tc0.8,0.9,0.7,1.8,0.2,2.6c-0.1,0.1,0.1,0.3,0.1,0.5c0.7,0.4,1.4,0.8,2.2,1.2c-1.6,2.2,1.4,2.6,2.5,4c-4.7,3.3-9.8,6.3-14.3,9.9\r\n\tc-4.6,3.6-8.8,7.6-12.8,11.6C49.4,48.6,46,53,42.4,57c-2.2-3.4-4.2-7-6.7-10.4c-3.4-4.4-7.9-7.6-10.7-8.1c0.3,0.4,0.5,0.7,0.7,1.1\r\n\tc5,6.9,8,14.3,11,21.9c1.1,2.8,0.6,5-1.3,7.4c-3.7,4.7-6.3,9.8-8.1,15.1c-0.1,0.4-0.4,0.7-0.8,1.2c-0.6-4.2-1-8.2-1.8-12\r\n\tc-0.9-4.7-2.1-9.4-3.2-14.1c-1.5-5.9-3.9-11.7-6.8-17.3c-1.9-3.8-4.1-7.4-6.3-11.1c-0.6-1-1.5-2.1-3.4-2.8\r\n\tc4.2,16.3,11.2,31.9,13.1,48.3c-0.2-0.2-0.4-0.5-0.5-0.7c-1.8-3.4-3.5-6.8-5.5-10c-1.2-2-2.9-3.8-4.7-5.4c-1.9-1.8-4.1-3.2-6.8-4.2\r\n\tc0,0.6,0.1,1,0.3,1.4c0.5,0.9,1.1,1.7,1.7,2.5c4.3,5.4,7.5,11.3,9.8,17.4c2.3,5.8,3,12,3.3,18.1c0.2,3.2-0.1,6.5,0.9,9.9\r\n\tc2.9,0,5.8-0.1,8.6,0c1.6,0.1,2.7-0.2,3.4-2.2c0.5,2.1,1.9,2.2,3.3,2.1c2.3,0,4.6,0,6.9,0c2.7,0,5.4,0,8.2,0\r\n\tc1.1-2.9,1.7-5.6,1.5-8.4c-0.2-2.1,1-3.4,3.1-4.8c1.1,4.5-0.1,8.8,1,13.1c1.7,0,3.3,0.7,4.7-0.6c1.5,1.4,3.3,0.6,5.2,0.6\r\n\tc0.1-1.1,0.3-2.2,0.3-3.1c0-1-0.4-2.1-0.3-3c0.1-4.2,0.5-8.2,0.4-12.4c0-2,1.1-3,3.6-3.7c-2.1,7.5-2.8,14.8-2.2,22.3\r\n\tc2.5,0,4.9,0,7.5,0c0.6-3.3,1.2-6.4,1.7-9.1c0,2.6,0,5.8,0,9.2c7.4,0,14.7,0.1,22-0.1c0.6-4.3,1.1-8.3,1.6-12.3\r\n\tc2,4,1.9,8.2,2.8,12.5c1.7-0.3,3.6,0.8,4.7-1.1c1.2,1.8,3.1,0.8,5.1,1.1c1.1-11,1.3-21.9,4.5-32.5c1.5,3.7,2.7,7.4,3.7,11.1\r\n\tc0.3,1.1,0.2,2.4-0.1,3.5c-1,4-2.2,7.9-3.2,11.9c-0.5,1.8-0.5,3.8-0.8,5.8c3.2,0,6,0,8.9,0c0.2-0.5,0.4-0.9,0.5-1.4\r\n\tc1.4-4.6,1.2-9.3,1.2-14c0-1,0.1-2.1,0.4-3c2.8-7.4,6.6-14.5,10.8-21.5c0.2-0.3,0.6-0.6,0.9-1c0.3,0.1,0.5,0.2,0.8,0.2\r\n\tc-2.7,6.5-5.1,13-5.9,19.8c-0.8,6.9-0.9,13.8-0.7,21c1.9,0,3.6,0.1,5.2,0c1.7-0.1,3.3-0.3,5-0.3c1.5,0,3.1,0.2,4.7,0.3\r\n\tc0.5-1.6,0.8-3,1.2-4.4c0.1,0,0.2,0,0.3,0c0,1.4,0,2.6,0,4.3c2.2-0.4,4.4,0.8,6.3-0.8c2,1.4,4.2,0.6,6.5,0.6c0.1-1,0.3-1.8,0.3-2.5\r\n\tc-0.1-1.8-0.4-3.7-0.3-5.4c0.2-3.9,0.5-7.8,0.8-11.7c0.1-1.5,0.6-3.1,1-4.6c0.5,0.6,0.5,1.2,0.5,1.7c-0.1,6.5-0.2,12.9-0.2,19.4\r\n\tc0,0.8,0.1,1.6,0.4,2.3c0.1,0.2,0.7,0.6,1.1,0.6c0.3,0,0.7-0.2,0.9-0.5c0.3-0.4,0.4-0.9,0.6-1.4c0.7-2.2,1.4-4.2,2.3-6.8\r\n\tc0.3,3.3-0.4,6.2,1.2,9.1c1.5-0.2,2.9-0.5,4.4-0.5s3.1,0.3,4.6,0.3c1.6,0.1,3.1,0,5,0c0.4-1.9,1-3.6,1.2-5.3c0.5-3,0.8-6,1.2-9\r\n\tc0.2-1.3,0.7-2.6,1.1-3.8c0.5,6.1-1.3,12-0.4,18c2.2,0,3.9,0,5.8,0c0.3-1.6,0.6-3,0.8-4.6c0.1,0,0.3,0,0.4,0c0.1,1.4,0.2,3,0.3,4.6\r\n\tc2.4,0,4.7,0,7.1,0c0.2-0.7,0.4-1.4,0.7-2.2c0.3,0.9,0.5,1.6,0.7,2.2c2.3,0,4.3,0,6.5,0C208.6,105.3,208.7,105.2,208.7,105z\r\n\t M168.3,84.4c0.3-0.2,0.7-0.4,0.8-0.6c1.2-4.3,2.4-8.6,3.5-13.1c0.3-1,0.4-2.2-0.2-3.3c-2.8,1.5-4.2,3.2-3.9,6\r\n\tC168.8,77.2,168.4,80.8,168.3,84.4c0.1,1.4,0.1,2.6,0.1,4c0,0,0,0-0.1,0C168.3,87.2,168.3,85.8,168.3,84.4z M76.2,52.5\r\n\tc0.9-0.4,1.5-0.7,2.1-1c5.6-3.2,12.1-4.7,18.8-5.5c1.8-0.2,3.3-0.5,4.9-1.3c-0.5-1-1-1.8-1.2-2.3c-2.8-0.7-5.3-1-7.4-1.9\r\n\tc-4.3-1.8-3.9-2-2.7-5c-2.1-0.9-4.3-1.8-6.5-2.7c-0.4,0.2-0.7,0.5-1,0.7c-4.1,4.1-6.3,9-9.4,13.5c-0.2,0.3-0.2,1,0,1.4\r\n\tC74.4,49.5,75.2,50.9,76.2,52.5z M55.3,66.6c2.6-1.8,4.6-3.5,5.5-6.2c2.3-7.3,4.8-14.5,10-20.8c2.2-2.7,4.3-5.5,6.8-8.1\r\n\tc1.5-1.6,3.4-3,4.3-5c-1.6-1.1-2.2,0-3,0.8c-3.2,3.4-6.4,6.9-9.6,10.3c-5,5.5-10.1,11.1-15.1,16.6c-1.8,2-1.7,2.1-1.1,4.7\r\n\tc0,0.1-0.1,0.2,0,0.2C53.8,61.6,54.5,64,55.3,66.6z M214.2,70.8c5.2,1.3,7,5.1,9.9,8.6c1.4-2.8,2.8-5.4,4.1-8.1\r\n\tc0.2-0.4-0.1-1.1-0.3-1.6c-1-2.2-2-4.5-3.2-6.6c-1.2-2.2-2.6-4.4-4.1-7c-2.3,3.4-4.3,6.5-6.4,9.5C212.8,67.3,212.6,69.1,214.2,70.8z\r\n\t M243.6,92.8c1.2-3.7,1.9-7,3.3-10.1c1.6-3.4,1.2-6.6-0.1-9.9c-1.2-3-2.2-6-3.9-8.9c-0.4,0.2-0.6,0.2-0.7,0.3c-0.8,1-1.4,2.2-2.3,3\r\n\tc-2.5,2.6-2.7,5.2-1.5,8.4C240.6,81.1,241.9,86.8,243.6,92.8z M105.1,97.3c0.2-2.6,0.4-4.8,0.6-7c0.2-2.2,0.5-4.2,0.8-6.4\r\n\tc0.3-2.2,0.6-4.4,1.1-6.6c0.5-2.1,1.3-4.2,1.9-6.2c0.5-2,2.5-3.6,2.1-6c-0.5,0.1-0.6,0.4-0.8,0.7c-3.4,4.4-6.8,8.8-9,13.7\r\n\tc-0.4,0.8-0.4,1.8-0.2,2.7C102.6,87.1,103.8,91.9,105.1,97.3z M71.5,63.1c-3.5,1.8-6.4,3.5-6.2,7c0,0.5-0.2,1-0.2,1.4\r\n\tc-0.4,3.3-0.7,6.6-1.1,9.9c3.6-0.1,3.7-0.2,4.6-2.4c1-2.3,1.7-4.7,3-7C73.4,69.1,71.8,66.3,71.5,63.1z M199.5,64\r\n\tc-0.2-0.1-0.4-0.1-0.6-0.2c-2.2,3.8-5.9,7.3-4.3,12.2c0.3-0.1,0.7-0.2,1.3-0.2c2.7,2.9,2,6.5,2.9,9.8c0.8-2.1,1.9-4.2,1.8-6.3\r\n\tC200.6,74.1,199.9,69.1,199.5,64z M80.1,71.5c3.4-2.6,6.2-4.7,8.9-6.9c0.5-0.4,0.8-0.9,1.1-1.4c1.7-2.9,3.5-5.7,5.2-8.6\r\n\tc0.2-0.3,0.3-0.7,0.6-1.5c-6.5,4.7-11.4,9.9-15.1,15.7C80.3,69.4,80.4,70.3,80.1,71.5z M105.8,52c-0.2,0-0.4,0-0.7,0\r\n\tc-1.1,2-2.3,3.9-3.5,6.1c2.1-0.2,3.8-0.4,5.6-0.6c-0.5,1-1.2,1.8-1.9,2.3c-2,1.5-4.1,3-6.2,4.5c-2.6,1.8-3,4.3-1,6.6\r\n\tc3.5-4.3,7-8.6,10.6-13C107.9,56.1,106.8,54.1,105.8,52z M138.2,97.1c0.2,0.1,0.5,0.1,0.7,0.2c1.2-2.2,3.2-4,3-6.6\r\n\tc-0.3-3.4-0.5-6.8-0.8-10.2c0-0.4-0.4-0.8-0.6-1.1c-0.1,0-0.3,0-0.4,0.1C139.4,85.2,138.8,91.2,138.2,97.1z M49.4,63.2\r\n\tc-0.3,0-0.5,0-0.8,0c-0.7,0.8-1.5,1.5-2,2.3c-0.5,0.6-1,1.5-0.9,2.2c0.3,2.1,0.9,4.2,1.5,6.4c2.2-1.5,3.5-2.8,2.8-5\r\n\tC49.5,67.1,49.6,65.1,49.4,63.2z M40.3,77.7c-2,3.3-3,6.8-3.4,10.4c1-1.2,1.5-2.6,2.5-3.7C41.4,82.3,41.1,80,40.3,77.7z M51.4,80.8\r\n\tc-3.5,2.2-3.1,4.8-1.9,7.6c1.1-0.9,2.7-1.2,2.5-2.6C51.8,84.3,51.6,82.8,51.4,80.8z M94.1,76.8c-2.5,5.4-4,10.7-4.2,16.3\r\n\tc1.4-4.8,2.8-9.6,4.1-14.4C94.3,78.1,94.1,77.5,94.1,76.8z M78.8,61c1.4-1.6,2.6-3,3.9-4.5c-1.3,0.2-2.2,0.8-3.1,1.2\r\n\tC78,58.4,77.8,59.5,78.8,61z M148.1,97.4c0.2-1.1,0.5-2.3,0.7-3.4c0-0.2-0.1-0.3-0.2-0.6C147.5,94.7,147.7,96.1,148.1,97.4z\r\n\t M57.4,74.4c-1.6,1.3-0.8,2.2,0,3.7C57.4,76.7,57.4,75.7,57.4,74.4z M40.8,96.8c1.1-0.4,1.9-1,1.3-2.4\r\n\tC41.5,95.5,41.1,96.1,40.8,96.8z M297.3,42.3c0.6,0.8,0.7,1.5,0.3,2.4c-1.5,3.7-2.9,7.4-4.3,11.1c-0.7,1.8-1.2,3.5-1.9,5.4\r\n\tc-1.1-3.8-2-7.3-3.3-10.7c-1.5-4.2-3.8-8.2-7.4-11.6c-2.7-2.5-6-4.2-10.5-4.9c0.6,0.6,0.9,1,1.2,1.3c8.1,7.6,11.5,16.7,12.3,26.4\r\n\tc0.7,8.9,0.2,17.9,0.3,26.7c0,1.3-0.3,2.6-0.3,3.8c-0.1,3.9-0.1,7.8-0.1,11.7c0,0.5,0.3,1,0.5,1.6c2.2,0,4.3,0,6.7,0\r\n\tc0.4-2.3,0.9-4.6,1.3-6.8c0.1,0,0.1,0,0.2,0c0.3,2.2,0.5,4.5,0.8,6.8c1.4,0,2.6,0,4,0c0.4-1.4,0.8-2.7,1.1-4.1\r\n\tc0.5-2.8,0.9-5.7,1.5-8.5c0.9-4.7,2.5-9.4,5.1-13.7c1.2-1.9,2.5-3.8,3.7-5.6c1,3.3,1.4,6.4,1.7,9.5c0.1,0.6-0.3,1.4-0.6,2\r\n\tc-3.4,6.1-5.1,12.6-6.5,19.1c-0.1,0.4,0.1,0.8,0.1,1.3c0.6,0,1.2,0.2,1.5,0c3.2-2.2,4.1-5.5,6-8.7c0.2,0.9,0.5,1.4,0.5,1.9\r\n\tc0.1,1.8,0.2,3.6,0.3,5.4c0,0.5,0.5,1,0.8,1.4c0.6-0.3,1.4-0.5,1.9-0.9c0.4-0.3,0.7-0.8,0.9-1.2c0.6-1.9,1.4-3.8,1.6-5.8\r\n\tc0.4-3.2,0.4-6.3,0.6-9.5c0.1-1.1,0.1-2.2,0.2-3.4c0.2,0,0.4,0,0.6,0c0.3,6.9,0.6,13.8,0.9,20.7c1.9,0,3.5,0,5.1,0\r\n\tc0.2-0.6,0.4-1.2,0.4-1.8c0.1-1.8,0-3.5,0.3-5.3c0.8-6.6,0.4-13.2-1.4-19.7c-0.8-2.9,0.7-4.6,2.9-6.8c0.7,3,1.2,5.8,1.9,8.4\r\n\tc1.8,7.4,3.7,14.7,3.1,22.3c-0.1,1,0.4,1.9,0.6,2.9c1.9,0,3.3,0,4.9,0c0.2-0.5,0.4-0.8,0.5-1.2c1.7-4.2,1.6-8.6,1-13.1\r\n\tc-1.2-8-3.6-15.8-7.4-23.3c-0.1-0.2-0.1-0.5-0.1-0.6c0.5-0.5,1-1,1.9-1.8c-1.4,0.3-2,0.5-3,0.6c-0.7-1.5-1.2-3-2-4.3\r\n\tc-0.2-0.4-1-0.6-1.5-0.8c-0.2,0.4-0.6,0.8-0.6,1.2c0.2,1.4,0.5,2.6,0.7,4c0.1,0.7-0.1,1.4-1,1.8c-1.5,0.7-3,1.5-4.5,2.3\r\n\tc-0.9-1-1.8-1.8-3-3.1c-0.5,1.9-0.8,3.3-1.2,4.8c-0.5-2.2-0.9-4.2-1.4-6.3c-0.3-1.4-0.4-2.6,0.6-3.8c0.9-1.1,1.9-2.2,2.7-3.4\r\n\tc0.2-0.3,0.1-0.9,0.2-1.3c-0.2-0.1-0.4-0.2-0.6-0.2c-1.3,0.9-2.6,1.8-4.1,2.7c-0.3-0.6-0.5-0.8-0.6-1.1c-1.4-5.1-3.5-10.1-6.8-14.7\r\n\tc-0.3-0.4-0.3-1.3,0-1.8c1.6-2.3,3-4.7,5-6.7c8.9-9,20.4-15.5,33.4-20.3c0.5-0.2,1-0.6,1.4-0.8c-0.1-0.2-0.2-0.3-0.3-0.5\r\n\tc-5.6,1.8-11.5,2.6-17,4.8c-11.5,4.5-21,10.8-27.9,19.6c-3.2-2.2-6-4.6-10.5-5.7C293,36.1,295.1,39.3,297.3,42.3z M294.4,86\r\n\tc0.9-2.1,1.6-4.2,2.8-6.2c2.8-4.6,6-9,8.9-13.5c0.4-0.6,0.9-1.5,0.8-2.2c-1.1-3.8-2.4-7.7-3.6-11.5c-0.1-0.5-0.6-0.9-1-1.5\r\n\tC297.6,62.7,296.3,74.4,294.4,86z M280.1,105.7c-1.4,0-2.5,0-3.9,0c-0.2-0.9-0.4-1.7-0.5-2.5c-0.3-5.6-0.5-11.3-1-17\r\n\tc-2.9,6.2-3.1,13-5.4,19.4c-3.4,0-6.7,0-10.2,0c-0.1-0.9-0.2-1.7-0.2-2.4c-0.3-6.2-0.4-12.3-0.9-18.4c-0.2-3.2-0.2-6.3,0.5-9.5\r\n\tc0.3-1.4,0.6-2.8,1-4.2c0.1-0.5,0.7-0.8,1.1-1.2c0.3,0.4,0.9,0.8,1,1.2c0.8,3.3,1.7,6.6,2.2,9.9c0.5,3.2,0.7,6.5,1,10.3\r\n\tc0.3-1,0.5-1.6,0.7-2.1c1.7-5.2,3.1-10.6,6.2-15.5c0.5-0.8,0.2-2-0.1-3c-1.3-4.2-2.8-8.5-4.2-12.7c-1.7-5-3.3-10-5.1-15\r\n\tc-0.9-2.5-2.3-4.9-3.5-7.3c-0.3-0.6-0.7-1.3-0.6-2.1c0.3,0.2,0.7,0.2,0.8,0.4c2.6,3.5,5.3,7.1,7.8,10.7c4.4,6.3,7.5,13,9.9,19.9\r\n\tc2,5.8,3.8,11.5,4.4,17.5c0.5,4.8,0.4,9.7,0.4,14.6c0,1.9-0.2,3.8-0.5,5.7C281,103.6,280.5,104.6,280.1,105.7z M540.2,44.2\r\n\tc-0.8-0.3-1.5-0.7-2.3-1c0.2-0.2,0.3-0.3,0.5-0.5C539,43.2,539.6,43.7,540.2,44.2z M860.3,14.4c0.8,0.3,1.1,0.5,1.5,0.6\r\n\tc3.6,1.3,6,3.5,7.5,6.4c2.2,4.2,3.1,8.5,3.9,12.9c0.4,1.9,0.5,3.9,0.8,5.8c0.3,2.2-0.1,3.9-2.4,5.4c-2.5,1.6-3.8,3.8-5,6.2\r\n\tc-2.4,4.6-3.4,9.5-4,14.5c-0.4,3-0.5,6.1-0.8,9.4c-1-0.6-1.3-1.5-1.9-2.2c-1.9-1.9-2.6-4.1-2.3-6.6c0.3-2.4,0.3-4.8,0.5-7.2\r\n\tc0.4-3.7,2.1-7,4.9-9.9c0.4-0.4,0.7-0.8,1.1-1.4c-1.9-0.2-3,0.6-4,1.4c-2.5,2.2-4.3,4.6-4.9,7.5c-0.5,2.1-0.7,4.2-1,6.4\r\n\tc-0.1,0.9-0.1,1.8-0.2,2.8c-2-0.9-3.1-1.8-3.3-3.5c-0.4-2.8-0.9-5.7-1.7-8.4c-0.6-2.2-1.7-4.2-2.7-6.2c-0.6-1.2-0.3-2,0.8-2.9\r\n\tc3.3-2.6,6.4-5.4,10.6-7.1c-4.8,1.4-9.1,3.4-13.1,6.2c-1.6-3-3.3-5.8-6.4-8c0.7,1.4,1.4,2.7,2.1,4.1c0.7,1.4,1.4,2.8,1.9,4.2\r\n\tc0.2,0.5,0.1,1.2-0.3,1.6c-2.2,2.2-4.5,4.3-6.9,6.6c-0.3-0.6-0.7-1-0.9-1.5c-2.6-4.9-5.6-9.6-9.6-13.9c-1.8-1.8-3.9-3.3-6.7-4.2\r\n\tc0.9,1.2,1.5,2.2,2.2,3c5.2,6,8.9,12.6,12,19.5c0.2,0.5,0.2,1.2,0,1.7c-2,3.8-4.2,7.6-6.2,11.4c-0.9-1.4-2.1-7.2-2-9.5\r\n\tc-0.6-0.5-1.1-0.9-1.3-1.3c-2-4.2-4-8.6-7.3-12.3c-0.5-0.6-0.6-1.4-0.6-2c0.3-4.1,0.8-8.2,1.1-12.3c0.2-1.6,0.3-3.3,0.4-4.9\r\n\tc0-0.5-0.2-1-0.7-1.4c-0.8,2.7-1.6,5.4-2.3,8.2c-0.6,2.7-1.1,5.4-1.6,8.3c-4.2-2.7-8-5.8-13.9-5.5c-1.7-5.3-4.1-10.3-4.5-15.8\r\n\tc-0.7,4.9-0.2,9.8,1,14.6c1.9,7.6,3.9,15.2,5.7,22.8c1.7,7.3,2.8,14.6,3.2,21.9c0.2,2.5-0.4,5-0.6,7.6c-0.3,3.3-0.5,6.5,0,9.7\r\n\tc2.3,0.3,2.3,0.3,3-2.5c0.1,0.6,0.2,1,0.2,1.4c0,0.4,0.1,0.8,0.1,1.3c0.6,0.1,1.3,0.2,1.9,0.2c0.6,0,1.3-0.1,2.1-0.1\r\n\tc0.3-1.5,0.6-3,0.8-4.4c0.1,0,0.3,0,0.4,0c0,1.1-0.1,2.2,0,3.3c0.1,1.2,0.2,1.2,2.3,1c0-2.6,0-5.1,0-7.8c0.2,0,0.3,0,0.5,0\r\n\tc0.2,2.6,0.5,5.2,0.8,7.9c1,0,1.7,0,2.8,0c0.2-1.4,0.4-2.7,0.6-4.3c1.3,1.4,0.2,2.9,0.9,4.3c2.9,0,5.8,0,9,0\r\n\tc0.3-2.7,0.4-5.4,0.9-8.1c0.2,0,0.3,0,0.5,0c0.7,2.7,1.4,5.4,2,8.1c1.4,0,2.6,0,3.9,0c0.2-0.7,0.5-1.4,0.8-2.4\r\n\tc0.3,1,0.5,1.7,0.8,2.4c0.8,0,1.5,0,2.4,0c0-0.6,0.2-1.1,0.1-1.7c-0.2-2.6-0.4-5.2-0.5-7.8c0-0.6,0.1-1.3,0.2-2c0.2,0,0.4,0,0.6,0\r\n\tc0.3,3.8,0.5,7.4,0.8,11.4c0.7,0,1.6,0,2.8,0c0.2-2.1,0.4-4.2,0.6-5.9c0.1,1.7,0.2,3.8,0.4,5.9c2.3,0,4.3,0,6.5,0\r\n\tc2-8.7,2.1-17.5,1.2-26.4c1.3,1,1.9,2.1,2.1,3.5c0.6,4.6-0.8,9.2-0.9,13.9c-0.1,2.5-0.4,5-0.5,7.4c0,0.5,0.1,1,0.1,1.6\r\n\tc0.7,0.1,1.4,0.2,2,0.1c1.6-0.1,3.2-0.2,4.9-0.4c-0.6-5.8-1.1-11.6-1.7-17.6c1.4,1,1.8,2,1.8,3.3c-0.1,4.7,0.4,9.5,1.3,14.3\r\n\tc2,0,3.9,0,6,0c0-1.3,0-2.6,0-4.1c1.4,1.4,2.5,2.5,3.6,3.5c0.3,0.2,0.6,0.6,1,0.6c3.6,0.1,7.3,0,11,0c-0.1-1.1-0.2-1.9-0.3-2.8\r\n\tc0.1,0,0.3-0.1,0.4-0.1c0.4,0.9,0.7,1.8,1.1,2.8c1.1,0,2.3,0,3.8,0c0.4-4.3,0.8-8.6,1.3-13c0.2,0,0.4,0,0.6,0\r\n\tc1,4.2,0.2,8.6,0.7,12.9c2,0,3.8,0,5.9,0c-0.2-4.1-0.3-8-0.5-12c1,1.9,1.1,3.9,1.4,5.8c0.3,2,0.5,4,0.7,6.1c1,0,1.9,0,2.9,0\r\n\tc0.1-0.7,0.3-1.5,0.4-2.6c0.1,1,0.2,1.8,0.4,2.6c1.9,0,3.7,0,5.7,0c0.2-2.3,0.4-4.6,0.6-7c0.1,0,0.2,0,0.3,0\r\n\tc0.2,2.2,0.4,4.5,0.7,6.9c1.2,0,2.4,0,3.8,0c-0.2-1.3-0.4-2.5-0.6-3.7c0.1,0,0.3-0.1,0.4-0.1c0.6,1.3,1.1,2.5,1.7,3.8\r\n\tc0.5,0,1.2,0,2,0c0.1-1.1,0.2-2.2,0.3-3.3c0.1,0,0.2,0,0.3,0c0.2,1,0.4,2.1,0.6,3.2c2,0,3.8,0,5.9,0c0.1-1.2,0.2-2.4,0.3-3.7\r\n\tc0.2-7.1-0.7-14.3-2.6-21.2c-1.2-4.6-3.2-8.9-5.7-13.1c-1.1-1.8-1-2.1,1.2-4.1c6.9,13.5,8.7,27.6,7.9,42c2.6,0,4.9,0,7.4,0\r\n\tc-0.6-16.1-1.2-32.1,2.5-48.5c1,0.9,1.8,1.6,2.6,2.2c2.7,2.1,3.2,4.4,2.5,7.4c-1.2,5.4-0.8,10.9-0.7,16.4c0,3.7,0,7.3,0,10.2\r\n\tc-0.7-1.3-1.7-3.3-2.7-5.4c-0.2-0.5-0.2-1-0.2-1.5c0-3.7,0-7.4,0-11.1c0-0.6-0.1-1.1-0.6-1.8c-0.4,0.7-0.8,1.4-1.1,2.1\r\n\tc-1.4,3.3-1.6,6.8-1.7,10.3c-0.2,6.1-0.1,12.2-0.1,18.2c0,1.6,0.1,1.6,2.5,1.4c0.2-0.5,0.4-1,0.7-1.8c0.2,0.6,0.3,1.2,0.4,1.8\r\n\tc2.3,0,4.5,0,6.7,0c0.7-1,1.4-2.2,2.1-3.3c0.2,0,0.4,0.1,0.5,0.1c0.1,1,0.2,2,0.4,3.1c2.4,0,4.8,0,7.4,0c0-5.1,0-10.2,0-15.3\r\n\tc0.1,0,0.2,0,0.3,0c1,5,2.1,10.1,3.2,15.3c1.9,0,3.8,0,5.8,0c0.1-1.3,0.2-2.5,0.3-3.8c0.3-5.2,0.6-10.4,0.7-15.6\r\n\tc0.2-7.5,1.3-15,3.3-22.3c0-0.1,0.2-0.2,0.5-0.6c0,1,0.1,1.6,0.1,2.2c0.2,4.5,0.5,9,0.5,13.5c0,2.2-0.7,4.4-1.2,6.6\r\n\tc-1.5,5.9-2.8,11.9-2.5,18c0,0.6,0.1,1.3,0.1,2c2.1,0,4.1,0,6.2,0c0.3-1.2,0.5-2.3,0.7-3.4c0.1,0,0.2,0,0.3,0\r\n\tc0.4,1.1,0.7,2.2,1.1,3.4c1.6,0,3.1,0,4.9,0c0.1-0.9,0.3-1.8,0.3-2.6c0-5.5,0.2-11.1,0-16.7c-0.3-5.9-1-11.9-1.6-17.8\r\n\tc0-0.5-0.1-1,0.1-1.5c1.8-4.1,3.7-8.2,5.6-12.3c0.1-0.2,0.3-0.3,0.7-0.6c2.3,7.4,4,14.7,4,22.3c-1.6-2.8-2.7-5.8-5.6-7.8\r\n\tc1.3,6.9,4.3,13.5,5.1,20.5c-2.4-1.3-2.4-3.3-2.9-5.4c-0.7,0.6-1.2,1-1.6,1.4c-1-0.1-1.9-0.2-3.3-0.2c0.6,1,1,1.8,1.4,2.6\r\n\tc0.5,0.8,1,1.5,0.1,2.3c-0.3,0.2-0.3,0.7-0.4,1.1c-0.3,4.6-0.5,9.1,0.2,13.7c0.1,0.4,0.2,0.7,0.3,1.1c0.4,0.1,0.7,0.1,1,0.1\r\n\tc0.5,0,1-0.1,1.5-0.1c0.4-3.6,0.7-7.2,1.1-10.8c0.2,0,0.5,0,0.7,0c0.4,3.5,0.7,7.1,1.1,10.7c1.6,0,3.2,0,5.1,0\r\n\tc0.1-0.5,0.3-1,0.3-1.4c-0.2-3.5-0.4-7-0.5-10.6c-0.1-3.8,0-7.7,0.2-11.5c1.6,7.8,1.4,15.5,1.2,23.5c2.3,0.2,4.4,0.2,6.7,0.1\r\n\tc0.1-0.9,0.2-1.8,0.2-2.6c0.2,0,0.3,0,0.5,0c0.2,0.8,0.5,1.7,0.8,2.6c2.3,0,4.5,0,7,0c0.1-1.3,0.2-2.6,0.4-3.8\r\n\tc0.4-3.4,0.9-6.9,1.2-10.3c0.4-3.4,0.6-6.7,0.9-10.2c0-0.4,0-0.8,0-1.3c0.2,0,0.3,0,0.5,0c0.3,1.7,0.6,3.4,0.8,5.1\r\n\tc0.2,1.9,0.3,3.9,0.6,5.8c0.3,2.3-0.6,4.5-1.2,6.7c-0.7,2.6-1.2,5.1-1.2,7.8c3,0,5.9,0,8.8,0c0.9-2.1,1.7-4.2,2.6-6.2\r\n\tc1.4,2,0.9,4.1,0.5,6.3c1.9,0,3.6,0,5.3,0c0.8,0,1.7,0.1,2-0.7c0.3,0.8,1.1,0.7,1.9,0.7c0.4,0,0.8-0.1,1.3-0.1\r\n\tc0.2-0.5,0.4-1,0.6-1.6c0.4,0.6,0.7,1,1.1,1.6c2.6,0,5.1,0,8,0c0-2,0-4,0-6c0.1,0,0.2,0,0.3,0c0.5,1.9,1,3.9,1.6,5.9\r\n\tc3.4,0,6.5,0,9.7,0c1-2.8,0.6-5.7,1.1-8.6c0,2.8,0,5.6,0,8.4c2.3,0.5,4.4,0.2,6.7,0.2c0.6-8.3-0.2-16.5-0.9-25.1\r\n\tc-0.3,0.5-0.4,0.6-0.5,0.8c-0.1,0.2-0.1,0.5-0.1,0.8c-1.7-0.3-1.8-1.3-1.9-2.4c-0.4-5.1-0.8-10.3-1.4-15.4c-0.5-4.6-1.6-9-3.7-13.3\r\n\tc-1.6-3.1-3.4-5.9-7.5-7.4c0.4-3.8,1.8-7.4,2.8-11.1c-4,2.8-5,6.9-6.8,10.7c-4.3-0.4-7.7,1.3-10.7,3.7c-0.3-0.6-0.5-0.8-0.6-1.1\r\n\tc-1.7-3.4-2.9-7.1-5.3-10.3c-1.9-2.5-4.3-5-7.9-6.4c-0.6-0.2-1.2-0.3-1.9-0.3c3.1,2.4,5.4,5.3,7.4,8.5c-3.8,4.3-5.3,9.3-5.6,14.6\r\n\tc-4.2,0-6.3,2.4-8.9,4.5c-2.3-3.4-3.9-7.1-7.5-9.9c1.7,4.2,3.3,8.3,5,12.5c-0.2,0.1-0.3,0.1-0.5,0.2c-1.5-1.9-1.9-4.4-4.6-6.2\r\n\tc0.8,2.9,1.5,5.4,2.3,8c0.2,0.7,0.4,1.4-0.2,2.1c-3.3,4.4-5.7,9-7.7,14.3c-0.3-0.7-0.5-1.1-0.6-1.5c-0.9-3-2-5.9-3.6-8.7\r\n\tc-0.9-1.7-1.2-3.6-1.7-5.4c-0.9-3.1-1.8-6.2-2.8-9.3c-0.4-1.2-0.4-2.2,0.3-3.4c0.6-0.8,1-1.8,1.5-2.6c-0.2-0.1-0.3-0.2-0.5-0.3\r\n\tc-0.9,0.8-1.7,1.6-2.8,2.6c-3-5.4-5.2-10.9-10.8-14.8c0.8,1.4,1.6,2.8,2.4,4.2c0.8,1.4,1.6,2.8,2.5,4.2c-1.6,1.1-3.2,2.1-4.5,3.2\r\n\tc-1.3,1.1-2.4,2.4-3.7,3.8c-1.7-2.1-3.3-4.2-5-6.3c2.1-2.6,4.2-5.2,6.3-7.8c-0.1-0.1-0.3-0.2-0.4-0.2c-3.1,1.5-5.2,4-7.7,6.2\r\n\tc-1.2-0.7-2.3-1.4-3.5-2.1c-2.8-1.4-5.9-1.9-9.1-1.1c-2,0.5-3.6,1.5-4.8,3.3c2.9-0.5,5.4-1.6,8.2-0.9c2.7,0.7,5,1.8,6.9,3.6\r\n\tc-5.2,7-7.4,14.6-9.1,22.7c-0.5-0.6-0.9-0.9-1.1-1.2c-1.8-2.4-3.6-4.8-5.3-7.2c-0.4-0.6-0.7-1.3-1.1-2c-0.2-0.1-0.8-0.1-1.1-0.3\r\n\tc-2-1.6-3.9-3.3-5.9-5c-0.6-0.5-0.8-1-0.5-1.6c0.9-2,1.8-4,2.8-6c0.2-0.4,0.4-0.8,0.4-1.3c-1.6,0.6-2.2,1.8-3.2,2.9\r\n\tc-1,1-1.7,2.2-2.4,3.4c-0.7,1.2-1.2,2.6-1.7,3.7c-2.8-1-5.4-2.1-8.1-3c-2.1-0.7-4.4-1-6.7-0.7c-3.9,0.4-6.5,2.6-6.8,5.6\r\n\tc6.4-4.2,14.2-2.6,20.3,1.3c-0.8,4.4-1.8,8.8-2.4,13.3c-0.6,4.5-0.7,9-1.1,13.9c-1.9-7.3-4.4-14-9.5-20c1.6-2.1,4-3.4,6.5-4.6\r\n\tc-3.4-0.2-5.8,1.4-8.3,3c-0.4-0.2-0.9-0.4-1.5-0.7c1.1,1.8-0.6,2.6-1.8,3.7c-0.5-0.6-0.9-1.1-1.3-1.5c-2-1.8-4-3.8-6.1-5.5\r\n\tc-0.9-0.7-1.4-1.4-1.3-2.4c0.4-5.8,1.2-11.6,3.6-17.1c0.5-1.2,1.2-2.4,1.5-3.7c-2.4,3-5.3,5.8-6.4,9.4c-1,3.4-1.8,7-2.7,10.6\r\n\tc-1.1-0.5-2.3-1-4-1.8c0.4,0.7,0.5,1.1,0.7,1.4c0.3,0.3,0.8,0.5,1.2,0.7c1.7,0.9,2.6,2,2.4,3.8c-0.2,2-0.1,4.1,0,6.1\r\n\tc0,0.9-0.2,1.7-1.1,2.2c-4.8,3.2-7.5,7.5-9.3,12.2c-0.3,0.9-0.7,1.8-1.1,2.8c-1.1-0.9-2.2-1.6-3.1-2.5c-0.3-0.3-0.3-1-0.2-1.4\r\n\tc1-4.2,2.1-8.3,3.2-12.4c0.1-0.4,0.2-0.7,0.4-1.3c-1.5,0.5-2.2,1.4-2.8,2.2c-2.3,3.2-3.3,6.8-4.1,10.4c-0.4,2-0.6,4-0.6,6\r\n\tc0,4.8,0.1,9.6,0.2,14.5c-0.2-0.3-0.5-0.7-0.7-1.1c-1.1-1.9-2.2-3.8-3.2-5.7c-0.4-0.9-0.6-1.9-0.5-2.8c0.4-6.1,1.1-12.3,1.2-18.3\r\n\tc0.1-5-0.2-10.2-0.7-15.2c-0.3-3-0.1-5.7,1.5-8.4c1.6-2.6,3.1-3.2,6.6-2.7c0.2,0,0.5,0,0.7,0c-3.6-3-6.9-2.2-9.9,1.5\r\n\tc-0.2-0.6-0.4-1-0.5-1.5c-1.2-4.4-2.4-8.8-4.9-12.9c-1.1-1.7-2.4-3.3-4.4-4.4C865.2,14.2,863.2,13.5,860.3,14.4z M830.1,73.9\r\n\tc0.5-0.8,0.8-1.3,1.2-1.8c1.2-2.1,2.3-4.2,3.7-6.2c0.6-0.9,0.8-1.6,0.3-2.6c-0.4-0.7-0.6-1.6-1.1-2.8c-2.2,3.8-4,7-5.3,10.5\r\n\tc-0.2,0.6-0.5,1-0.8,1.6c-0.2,0.6-0.3,1.3-0.6,1.8c-0.8,1.9-0.8,3.2,0,5.8c1.1-2.5,0.8-5,0.6-7.7C829.1,72.3,829.6,72.9,830.1,73.9z\r\n\t M873.3,80.7c0.2-0.1,0.3-0.1,0.5-0.2c-0.2-1.8-1.5-3.1-2.9-4.3c-0.8-1.3-1.5-2.5-2.3-3.8c-0.2,0-0.4,0.1-0.6,0.1\r\n\tc-0.2,2.4-0.5,4.8-0.7,7.2c-0.3,2.5,0.3,4.7,1.7,6.9c1.2,1.8,1.8,3.8,2.9,5.8c0-1,0.2-1.8,0-2.8c-0.9-4-1.8-8.1-2.7-12.1\r\n\tc-0.2-0.7-0.2-1.4-0.4-2.3c0.8,0.3,1.5,0.6,2.1,0.7C871.7,77.6,872.5,79.2,873.3,80.7z M1024,66.7c0.6,1,1,2,1.7,3.3\r\n\tc0.3-1.8,0.5-3.4,0.7-4.9c0.2,0,0.3-0.1,0.5-0.1c0.3,0.6,0.8,1.2,0.9,1.8c0.5,2.7,0.9,5.4,1.3,8.1c0.2,1.4,0.2,2.7,0.3,4.1\r\n\tc0.2,0,0.3,0,0.5,0c0-1.1,0-2.2,0-3.4c0.1-7.4-0.1-14.9-1-22.3c-0.8-7-2.4-13.9-5.4-20.6c-0.2-0.4-0.4-0.9-0.6-1.3\r\n\tc-0.1-0.1-0.2-0.2-0.6-0.5c-0.6,1.5-1.3,3-1.7,4.4c-0.5,1.9-0.9,3.8-1,5.8c-0.5,8.8,0.9,17.5,3,26c0,0.1,0.1,0.2,0.3,0.5\r\n\tC1023.3,67.4,1023.6,67.1,1024,66.7z M1053.2,75c0.2-0.6,0.3-0.7,0.3-1c-0.2-7.6-0.9-15.2-2.1-22.8c-0.5-3.4-1.7-6.6-3.3-9.8\r\n\tc-0.8-1.5-1.8-2.9-3.7-3.8c-1.8,4-1.7,34.5,0.3,38.1c0.2-0.6,0.3-1,0.3-1.4c0.1-4.4,0-8.9,1.1-13.3c0.7-2.6,1.7-5.3,2.6-7.9\r\n\tc0.2-0.6,0.8-1.2,1.2-1.8c0.2,0.1,0.3,0.1,0.5,0.2c0,0.7,0.1,1.5,0,2.2c-1.4,9.5-1.6,19.1-1.6,28.8c0,0.8-0.1,1.6-0.2,2.3\r\n\tc-0.4,3.2,0.2,6.2,1.7,9.2c0-8.8,0-17.6,0.1-26.4c0.2,0,0.4-0.1,0.7-0.1C1051.8,69.9,1051.6,72.4,1053.2,75z M954.2,62.8\r\n\tc2.1-4.2,2.3-8.9,4.3-13.3c0,0.5,0,1,0,1.4c0,5.4-1,10.8-2.1,16.1c-0.1,0.5-0.2,1-0.1,1.5c1.1,4.1,2.3,8.1,3.5,12.3\r\n\tc0.1-2.2,0.4-4.2,0.4-6.3c0.1-8.6,2-16.9,4.8-25.1c0.5-1.6,1.3-3.1,1.9-4.6c0.2-0.6,0.3-1.4,0-1.8c-1.3-2-2.7-3.9-4.3-6.2\r\n\tC957.3,45.2,954.8,53.8,954.2,62.8z M1017.5,78.4c-1.2-3.2-1.8-6.6-2.6-9.9c-0.1-0.3,0-0.6,0-1.3c3.7,2.9,4.4,6.5,5.7,9.9\r\n\tc0.2,0,0.3,0,0.5-0.1c0.1-0.5,0.2-0.9,0.1-1.4c-0.7-3-1.4-6.2-2.2-9.2c-1.8-6.9-3-13.9-3-21c0-0.3-0.1-0.6-0.2-1.1\r\n\tc-1.6,0.4-2.8,1.1-4,2c-0.3,0.2-0.5,0.5-0.8,0.7c-2.8,2.7-2.9,2.7-1.6,6.1c3,7.7,4.5,15.6,5.4,23.6c0.4,3.2,0.8,6.5,1.3,9.7\r\n\tC1017.7,83.9,1018.6,81.3,1017.5,78.4z M806.5,69.5c-0.2-8.2-2.4-16.3-0.6-24.8c1.6,2.6,1.8,5,2.3,7.4c1.8,8.5,2.4,17.1,3.3,25.7\r\n\tc0,0.4,0.1,0.7,0.7,1.1c0.2-1,0.6-1.8,0.5-2.8c-0.1-3.4-0.4-6.9-0.5-10.3c-0.2-5.6-0.5-11.2-0.4-16.8c0-2.2-0.6-3.8-2.5-5.2\r\n\tc-2.5-1.8-5.1-3.4-7.8-5c-0.7-0.4-1.7-0.6-2.6-0.8c-0.2,0.2-0.3,0.2-0.5,0.4C802.5,48.5,804.6,59,806.5,69.5z M1038.6,75.8\r\n\tc0.1-0.4,0-0.8,0.1-1.2c1.6-4.8,0.3-9.7,0.4-14.6c0.1-5.5,0-11.1,0.1-16.7c0.1-2.2,0.6-4.4,0.9-6.7c-1.8-0.4-3.5-0.3-5.2,0.2\r\n\tc-1.1,0.3-2.1,0.6-3.2,1c-1.9,0.6-2,0.7-1.7,2.2c0.6,2.4,1.4,4.8,1.8,7.3c0.7,3.8,1.1,7.5,1.7,11.3c1-4.2,1.7-8.6,3.7-12.8\r\n\tc0.1,0.8,0.4,1.7,0.3,2.5c-0.2,5.2-0.6,10.4-0.8,15.6c-0.2,3.8-0.5,7.7,0.3,11.5c0.2,0.7,0.5,1.4,0.7,2.2c0.1,0,0.3,0,0.4,0\r\n\tC1038.4,77,1038.5,76.4,1038.6,75.8z M998.1,84c-0.2-2.7-0.1-5.5,0.7-8.4c0.6,1,1.1,1.7,1.8,2.8c0.5-1,0.8-1.5,1.1-2.1\r\n\tc0.9-1.5,1.6-3.2,2.8-4.6c1.2-1.4,1.5-2.8,1.1-4.4c-0.7-3.2-1.3-6.4-1.9-9.6c-0.2,0-0.4-0.1-0.6-0.1c-1.1,1.8-2.3,3.7-3.3,5.5\r\n\tc-2.3,4.2-3.9,8.7-4.3,13.4c-0.1,1.4-0.1,2.7,0.2,4.1c0.4,2.1,1.2,4.2,1.8,6.3C998.2,86.1,998.2,85.1,998.1,84z M895.8,63.2\r\n\tc-0.4,3.4-0.1,7,0,10.5c0,0.2,0.1,0.6,0.2,0.7c2.5,4.2,3.8,8.6,4.8,13.1c-0.2-10.1-0.4-20.2-0.7-30.3C898,59.1,896,60.9,895.8,63.2z\r\n\t M911.9,70.7c0.2,0,0.3,0.1,0.5,0.1c-0.2,1.5-0.4,3-0.5,4.6c-0.1,0.6-0.1,1.3,0.1,1.9c0.7,2.4,1.4,4.8,2.2,7.2\r\n\tc0.1,0.2,0.3,0.4,0.5,0.7c1-1.8,0.5-3.6,0.1-5.4c-0.5-2.3-0.9-4.6-1.1-7c4.2,4.5,4.8,9.9,6,15.3c0.7-5.3-2.6-19.7-7-26.3\r\n\tc-1.2,1.8-1.7,3.8-2.1,5.6c-0.5,1.8-1.6,3.7-0.2,5.8C910.9,72.3,911.4,71.5,911.9,70.7z M948.6,80c0.2-1.2,0.2-2.5,0.5-3.7\r\n\tc0.2-0.9-0.6-2.1,1-2.6c-0.1-1.8,0.5-3.9-0.3-5.6c-1.7-3.4-4-6.6-6.1-10c-0.1-0.2-0.3-0.2-0.9-0.6c0,1.1,0,2,0,2.9\r\n\tc0,2.2,0.1,4.3,0.2,6.5c0,0.6,0.1,1.2,0.4,1.7c2.2,2.9,2.7,6.1,3.3,9.4c0.3,1.4,0.5,2.8,0.7,4.2c0.2,0,0.4,0,0.5,0.1\r\n\tC948.2,81.4,948.5,80.7,948.6,80z M972.3,41.6c1.1-0.5,2.2-1,3.2-1.4c0.1,0.1,0.2,0.2,0.3,0.2c-0.2,0.2-0.3,0.6-0.6,0.8\r\n\tc-0.4,0.5-1,0.8-1.4,1.3c-1.6,1.8-2.1,3.5-0.9,5.6c0.8,1.4,1.1,2.8,1.7,4.6c0.7-1.4,1.2-2.3,1.8-3.3c1.4-2.2,2.7-4.4,4.2-6.6\r\n\tc0.6-0.8,0.7-1.4,0.3-2.4c-1-2.1-1.9-4.2-3-6.6C975.4,36.3,973.4,38.7,972.3,41.6z M847.1,71.1c0.6-0.5,1.1-1.4,1-2.1\r\n\tc-0.5-3.5-1.2-7-1.9-10.9c-0.6,0.6-1,0.8-1.3,1.1c-1.4,1.8-2.9,3.6-4.2,5.4c-0.3,0.5-0.6,1.1-0.5,1.6c0.6,2.8,1.3,5.6,2,8.6\r\n\tC843.9,73.5,845.6,72.4,847.1,71.1z M817.2,69.7c0.5-1.5,1-3,1.9-4.4c1.5-2.2,1.3-4.2,0.3-6.3c-1.3-2.7-2.7-5.5-4.3-8.2\r\n\tc-0.8,7.8,0.2,15.4,0.8,23.1C816.3,72.5,816.7,71.1,817.2,69.7z M873,47.2c-2.7,3.8-4,8-4.9,12.4c1.1-1.4,2.2-2.7,3.3-4.1\r\n\tc0.2,0.1,0.3,0.1,0.5,0.2c-0.2,1-0.5,2.1-0.7,3.1c-0.7,2.6-1.4,5.4-2.1,8c-0.3,1.3-0.3,2.4,1,3.4c1.1,0.9,1.9,2.1,2.8,3.1\r\n\tc0.2-0.1,0.3-0.1,0.5-0.2C872.5,64.5,872.2,55.8,873,47.2z M905.9,67.4c0.9-3,2.4-5.8,3.6-8.7c0.3-0.7,0.8-1.4,0.2-2\r\n\tc-1.6-2-3.3-4.1-4.9-6.1c-0.1-0.2-0.4-0.2-0.9-0.4c-0.4,8.6,0.2,17.1,0.3,25.5C904.8,72.9,905.1,70.1,905.9,67.4z M845.7,55.9\r\n\tc-0.6-2.2-1.2-4.5-1.8-6.9c-0.2-0.1-0.4-0.2-0.7-0.3c-0.2,0.4-0.4,0.8-0.8,1.2c-1.7,1.9-3.4,3.8-5.1,5.8c-0.6,0.7-0.8,1.4-0.4,2.2\r\n\tc0.5,1.1,0.9,2.3,1.5,3.6C841.1,59.5,843.3,57.8,845.7,55.9z M835.7,85.6c0-4.2,0-8.3-0.4-12.7c-0.3,0.4-0.7,0.8-0.9,1.2\r\n\tc-0.8,1.7-1.6,3.4-2.3,5.1c-0.2,0.4-0.3,0.8-0.3,1.1c0.6,3.5,1.2,7,1.9,10.6c0.2,0,0.4,0,0.6,0C834.8,89.2,835.7,87.5,835.7,85.6z\r\n\t M972.3,76.4c0.6,4.8,1.2,9.6,1.8,14.4c0.1,1.1,0.3,2.2,0.6,3.6c0.6-1.9-0.4-24-1.2-27.7C971.4,69.9,971.9,73.1,972.3,76.4z\r\n\t M820.8,87.5c0.7-3.1,1.3-6.2,2.2-9.3c0.8-2.9-0.3-5.5-0.9-8.2C822.5,76,819.3,81.6,820.8,87.5z M936.8,46.4c1.6,1.1,2.9,2.6,4.4,4\r\n\tc0.8-0.7,1.4-1.4,0.6-2.3c-1.7-2-3.5-4-5.6-6.3C935.1,43.8,934.9,45.1,936.8,46.4z M885,86.5c0.2,0,0.4,0.1,0.6,0.1\r\n\tc0.1-0.6,0.3-1.2,0.4-1.8c0.3-2.3,0.6-4.6,1-7s-0.9-4.2-1.9-6.2C885,76.6,885,81.6,885,86.5z M943.8,53.6c2,2.6,3.8,5.3,5.7,7.9\r\n\tc0.3,0.4,0.6,0.7,1,1c-1.4-4.2-3.9-8.2-6.8-11.9C943.2,51.8,943,52.6,943.8,53.6z M843.1,81.9c0.5,2,0.4,4,0.8,6\r\n\tc0.6-4.2,1.1-8.6,1.7-13C844.2,77.2,842.5,79.2,843.1,81.9z M943.4,80.2c0,3.4,0,6.6,0,9.9C945.1,88.3,945,83,943.4,80.2z\r\n\t M836.3,71.3c0.7,2.9,1.5,5.8,2.6,8.6c0-3.3-0.9-6.4-1.6-9.6c-0.2,0-0.4,0-0.5,0C836.6,70.6,836.2,71,836.3,71.3z M848.9,81.3\r\n\tc-0.8,2.1-1,9.5-0.3,12.2C849.1,89.2,849.4,85.4,848.9,81.3z M1002.6,84.5c-1.2,2.1,0.2,4.2,0,6.3\r\n\tC1003.9,88.8,1003.2,86.7,1002.6,84.5z M1033.3,89.2c0.6-1.5,0.5-2.2-0.3-5C1033,86,1032.4,87.6,1033.3,89.2z M971.3,60.3\r\n\tc1.6-2,0.7-3.8,0-5.5C971.3,56.5,971.3,58.2,971.3,60.3z M968.3,85.7c1.1-1.4,1.8-2.5,0.7-3.8C968.8,83,968.5,84.2,968.3,85.7z\r\n\t M1057.4,90.4c0.1,0,0.1,0,0.2,0c0-1.7,0-3.4,0-5.1c-0.1,0-0.1,0-0.2,0C1057.4,86.9,1057.4,88.7,1057.4,90.4z M823.5,93.3\r\n\tc0.1,0,0.1,0,0.2,0c0-1.2,0-2.5,0-3.7c-0.1,0-0.1,0-0.2,0.1C823.5,90.9,823.5,92.1,823.5,93.3z M1045.2,94.8h0.1c0-0.8,0-1.5,0-2.3\r\n\th-0.1C1045.2,93.2,1045.2,94,1045.2,94.8z M1168.2,77.9c0.5-4.8,1.2-9.6,3.1-14.3c0.2-0.6,0.5-1.1,0.8-2c5.1,8.9,6.8,18,7.3,27.4\r\n\tc-0.6-2.6-1.1-5.4-1.8-8c-0.8-2.7-1.8-5.4-4.1-8c-0.4,1.1-0.2,2-0.1,2.9c0.2,1,0.5,2.1,0.7,3c0.5,2.2,0.7,4.3,0.3,6.6\r\n\tc-0.5,3.4-0.5,6.8-0.7,10.2c0,0.5,0.1,0.9,0.2,1.4c0.7,0,1.4,0,2.3,0c0-1.5,0-3,0-4.5c0.1,0,0.2,0,0.3,0c0.3,1.4,0.6,3,0.9,4.6\r\n\tc1.9,0,3.7,0,5.7,0c0.5-2.8,0.5-5.5,0.4-8.3c-0.2-4.7-0.9-9.4-1.9-14c-1.2-5.4-3.2-10.6-6.2-15.4c-1.1-1.8-1-3,0.8-4.5\r\n\tc1.2,1.5,1.9,3.2,2.5,4.8c3.2,7.9,5.1,16.1,5.5,24.3c0.2,3.4,0.1,6.9,0.1,10.3c0,0.9,0.1,1.7,0.2,2.6c2.4,0,4.6,0,7,0\r\n\tc-0.2-16.1-1.3-32.3,2.6-48.7c1,0.9,1.8,1.6,2.6,2.2c2.4,2,3.3,4.1,2.6,7c-1.4,6.8-0.7,13.7-0.6,20.5c0,2.1,0,4.2,0,6.4\r\n\tc-1-1.8-1.9-3.5-2.8-5.2c-0.2-0.4-0.2-0.9-0.2-1.4c0-3.8,0-7.5,0-11.4c0-0.6-0.2-1.1-0.7-1.8c-0.4,0.7-0.8,1.4-1.1,2.2\r\n\tc-1.2,3.1-1.6,6.4-1.6,9.7c-0.1,6.2,0,12.4,0,18.6c0,0.5,0.1,1,0.2,1.7c0.7,0,1.4,0.1,2.2,0.1c0.2-0.7,0.3-1.3,0.4-2.1\r\n\tc0.4,0.8,0.6,1.4,0.9,2c2.2,0,4.4,0,6.5,0c0.7-1.3,1.3-2.4,2-3.5c0.2,0,0.4,0.1,0.5,0.1c0.2,1.1,0.4,2.2,0.6,3.4\r\n\tc1.3,0.3,2.4,0.5,2.7-0.7c1,1.8,2.9,0.6,4.6,1c0-3.4,0-6.8,0-10.1s-0.9-6.6,0.4-9.9c1.6,3.1,2.6,6.4,3.3,9.7c0.7,3.3,1,6.7,1.5,10.2\r\n\tc1.2,0,2.6,0,4.1,0c0.2-3.3,0.5-6.4,0.6-9.6c0.3-6,0.3-12,1-18c0.5-4.8,1.7-9.5,2.6-14.3c0.1-0.3,0.3-0.7,0.9-1c0,3.8,0,7.7,0,11.5\r\n\tc0,0.9,0.1,1.7,0.3,2.6c0.5,2.9-0.4,5.6-1.1,8.3c-1.6,6.2-3,12.4-2.6,18.8c0,0.5,0.1,1,0.1,1.7c0.8,0,1.5,0,2.3,0\r\n\tc0.6-5.2,1.1-10.4,2.8-15.8c1,5.5,1.6,10.7,3.4,15.9c1.6,0,3.1,0,4.9,0c0.1-0.9,0.2-1.7,0.2-2.5c0-7,0.1-14.1-0.2-21.1\r\n\tc-0.1-4.1-0.7-8.2-1.2-12.3c-0.2-1.5-0.1-3,0.6-4.4c1.6-3.4,3.1-6.7,4.7-10.1c0.2-0.4,0.5-0.8,0.9-1.5c2.6,7.8,4,15.2,4.3,22.9\r\n\tc-1.6-3-2.8-6.2-5.9-8.6c2,8.2,5.3,16.3,5.8,24.8c-0.7-0.2-1.1-0.4-1.9-0.7c-0.9,4.5,0.5,8.9,0.3,13.4c1.7,0,3.3,0,5.2,0\r\n\tc0.1-2.8,0.7-5.7,0.3-8.5c-0.8-4.6-0.4-9.4-0.3-14.1c0-0.2,0.1-0.5,0.3-1.2c1,4.3,0.9,8.2,1.1,12.1c0.2,3.9,0,7.8,0,11.7\r\n\tc2.3,0,4.4,0,6.5,0c0.1-1,0.2-2.1,0.2-3c0.2,0,0.3,0,0.5,0c0.3,1,0.6,2,0.9,3c2.3,0,4.6,0,7,0c0.2-2.2,0.3-4.2,0.5-6.2\r\n\tc0.3-2.9,0.8-5.8,1.2-8.7c0.4-3.3,0.6-6.6,0.9-9.9c0-0.2,0.1-0.5,0.4-0.8c0.2,1.2,0.5,2.5,0.6,3.7c0.3,3,0.6,5.8,0.7,8.8\r\n\tc0,1.4-0.5,2.8-0.8,4.2c-0.6,3-1.2,5.9-1.9,9c2.3,0,4.2,0,6.3,0c0.1-1,0.4-2.2,0.4-3.2c0.8-14.3-1-28.4-6.4-42.1\r\n\tc-0.4-1-0.3-1.8,0.5-2.7c1-1,1.8-2,3-2.9c1.7-1.3,3.7-2.1,6.3-2.3c-4.9-1.3-5-1.2-11.6,3.6c-2.3-3.4-3.9-7.1-7.5-9.9\r\n\tc1.6,4.2,3.3,8.2,4.9,12.4c-0.2,0.1-0.3,0.1-0.5,0.2c-1.5-1.8-1.7-4.1-4.3-5.4c0.5,1.8,0.8,3.7,1.5,5.4c0.8,2.1,0.6,3.8-0.9,5.7\r\n\tc-2.6,3.4-4.4,7.3-6,11.1c-0.1,0.3-0.4,0.7-0.7,1.2c-0.8-2.3-1.2-4.6-2.3-6.6c-2.2-3.7-3.1-7.7-4.2-11.6c-0.6-2.3-1.4-4.7-2.2-7\r\n\tc-0.4-1-0.3-1.8,0.3-2.8c0.6-1,1.1-2,1.3-3.2c-0.9,0.8-1.8,1.6-2.9,2.6c-3.2-5.9-5.7-11.7-11.6-15.9c1.9,3.1,3.8,6.3,5.6,9.1\r\n\tc-2.9,2.5-5.6,4.7-8.3,7c-1.5-1.9-3.1-3.9-4.9-6.1c2.1-2.6,4.2-5.1,6.3-7.8c-2,0.2-3.1,1.4-4.4,2.5c-1.3,1-2.4,2.2-3.7,3.4\r\n\tc-1.1-0.6-2.1-1.3-3.2-1.9c-2.2-1.2-4.7-1.8-7.4-1.7c-2.8,0.2-5.1,1.2-6.8,3.4c2.9-0.4,5.5-1.5,8.2-0.7c2.6,0.7,4.9,1.8,6.8,3.6\r\n\tc-5.2,6.9-7.4,14.7-9.1,22.8c-0.5-0.6-0.8-0.9-1-1.2c-1.8-2.5-3.5-5-5.6-7.4c-0.6-0.6,0.2-1.8-1.5-2.1c-0.8-0.2-1.3-1.3-2.1-1.8\r\n\tc-1.3-1.1-2.6-2.2-4-3.1c-0.9-0.6-1.1-1.2-0.8-2.1c0.9-2,1.9-4,2.9-6c0.2-0.3,0.2-0.7,0.1-1.1c-3.8,2.7-5.9,6.2-7.3,10.3\r\n\tc-0.9-0.5-1.6-0.9-2.4-1.2c-3.4-1.6-7-2.8-11-2.8c-4.6,0-7.5,2-8.3,5.8c3.1-2,6.6-3,10.4-2.5c3.6,0.6,7,1.7,10.2,3.8\r\n\tc-2.3,8.6-3.5,17.5-3.7,26.3c-1.9-6.8-4.5-13.4-9.5-19.2c1.5-2.1,4-3.3,6.4-4.6c-3.5-0.2-5.8,1.5-8.4,3c-0.8-0.6-1.5-1.1-2.3-1.7\r\n\tc-0.1,0-0.1,0.1-0.2,0.1c0.6,0.6,1.1,1.4,1.7,2.2c-0.8,0.8-1.5,1.5-2.4,2.4c-0.5-0.6-0.9-1-1.3-1.4c-2-1.8-3.9-3.8-6.1-5.6\r\n\tc-1.1-0.9-1.6-1.7-1.5-2.9c0.6-6.7,1.5-13.4,5.1-19.6c0.1-0.2,0.1-0.5-0.2-0.9c-0.7,1-1.5,1.9-2.2,3c-0.8,1-1.6,2-2.3,3\r\n\tc-0.7,1.1-1.2,2.2-1.7,3.4c-0.5,1.1-0.8,2.2-1.1,3.4c-0.3,1.2-0.5,2.4-0.8,3.7c-0.2,1.1-0.4,2.3-0.6,3.7c-1.4-0.6-2.5-1.1-4.1-1.8\r\n\tc0.3,0.6,0.3,1,0.5,1.2c0.2,0.2,0.6,0.4,1,0.6c1.8,1,2.9,2.2,2.6,4.1c-0.2,2-0.1,4.1,0,6.1c0,0.9-0.2,1.5-1.1,2.1\r\n\tc-5,3.4-7.7,7.8-9.5,12.7c-0.3,0.7-0.6,1.4-0.9,2.2c-1.1-0.8-2.1-1.4-2.9-2.2c-0.4-0.4-0.5-1.2-0.4-1.8c1.1-4.2,2.2-8.4,3.4-12.7\r\n\tc0.1-0.3,0.2-0.6,0.4-1.1c-1.5,0.6-2.3,1.5-3,2.5c-2.5,3.6-3.7,7.5-4.3,11.5c-1.3,9.7-0.5,19.3,2,28.8c0,0.2,0.2,0.3,0.4,0.6\r\n\tc1.1,0,2.3,0,3.7,0c0.4-4.4,0.8-8.8,1.2-13.2c0.2,0,0.4,0,0.6,0c0.1,0.6,0.3,1.2,0.3,1.8c0.1,3,0.1,5.8,0.2,8.8\r\n\tc0,0.8,0.1,1.7,0.2,2.6c2,0,3.8,0,5.8,0c0.4-1.8-0.2-3.4-0.5-5c-0.6-3-1.6-6-2.2-9c-0.5-2.1-0.7-4.2-1-6.2c-0.1-0.6-0.3-1.2-0.5-2.2\r\n\tc-0.3,0.6-0.5,0.9-0.7,1.3c-0.6-1.1,0.2-1.9,0.5-3.2c0.7,1,1.5,1.6,1.7,2.3c1.1,3.6,2.1,7.2,2.9,10.9c0.6,3,0.9,5.9,1.3,9\r\n\tc0.1,0.7,0.2,1.4,0.3,2.2c0.9,0,1.7,0.1,2.8,0.2c0.1-1.6,0.2-3.1,0.3-4.5c0.2,1.4,0.4,2.8,0.5,4.4c2,0,3.8,0,5.8,0\r\n\tc0.2-2.4,0.3-4.7,0.5-7.1c1,1.1,0.6,2.3,0.7,3.4c0.2,1.1,0.3,2.3,0.5,3.6c1.3,0,2.5,0,3.9,0c-0.6-2.4-1.2-4.8-1.7-7.1\r\n\tc-0.2-1-0.4-2.1-0.4-3c0-4.6,0.2-9.1,1.1-13.7c0.1-0.8,0.1-1.5-0.3-2.5c-0.4,0.6-0.8,1.2-1,1.8c-0.6,1.4-1,2.9-1.5,4.3\r\n\tC1168.7,77.2,1168.4,77.6,1168.2,77.9z M1216.1,66.3c-0.3,1.3-0.2,2.4,0.2,3.7c1.1,3.8,2.1,7.4,3.5,11.2c0-3-0.2-5.9,0-8.9\r\n\tc0.7-9.5,2.7-18.7,6.6-27.6c0.2-0.6,0.3-1.4,0-1.8c-1.2-2-2.6-3.8-4.3-5.8c-5.3,8.1-7.8,16.7-8.4,25.6c2.1-4.4,2.3-9.2,4.2-13.6\r\n\tC1218.2,55,1217.5,60.7,1216.1,66.3z M1260.2,78.4c0.7-1.3,1.2-2.3,1.8-3.3c0.6-1.1,1.2-2.3,2.1-3.3c1.2-1.3,1.5-2.6,1.2-4.2\r\n\tc-0.5-3.3-1.2-6.5-2.4-9.7c-3.9,5.3-6.5,10.8-7.7,16.9c-0.8,4.2,0.6,8.1,1.7,12c0.2,0,0.4,0,0.6,0c0.2-3.6,0.4-7.2,0.6-10.8\r\n\tc0.2,0,0.4-0.1,0.5-0.1C1259,76.6,1259.5,77.4,1260.2,78.4z M1158.2,80.3c0.9,2.7,1.5,5.6,2.2,8.5c-0.3-10.6-0.5-21.1-0.8-31.7\r\n\tc-3,2.4-5.9,7.9-7.5,14.2C1155.9,73.5,1157.1,76.9,1158.2,80.3z M1235.6,40c-0.4,0.6-0.5,1-0.7,1.1c-1.6,1-2.2,2.4-3,3.7\r\n\tc-0.2,0.4-0.2,1,0,1.5c0.7,2,1.5,4,2.3,6.2c0.3-0.4,0.6-0.6,0.8-1c1.9-3,3.7-5.9,5.5-8.9c0.3-0.5,0.5-1.1,0.3-1.6\r\n\tc-0.9-2.3-2-4.6-3.1-7.1c-2.8,2.3-4.6,4.7-5.8,7.7C1233,41.1,1234.1,40.6,1235.6,40z M1202.5,63.9c0,0.3,0.1,0.6,0.1,1\r\n\tc-0.1,1.8,0.3,3.5,1.4,5.2c1.8,2.9,2.1,6.2,2.6,9.3c0.2,0.9,0.3,1.8,0.9,2.7c0.2-0.6,0.5-1.2,0.6-1.8c0.2-1.8,0.3-3.6,0.5-5.4\r\n\tc0-0.2-0.1-0.5,0.1-0.6c2-1.3,1.2-3.1,1.1-4.6c-0.1-1.2-0.8-2.5-1.4-3.7c-1.4-2.4-2.9-4.6-4.4-7c-0.3-0.5-0.7-0.9-1-1.3\r\n\tc-0.1,0.1-0.3,0.1-0.4,0.2C1202.5,59.9,1202.4,61.9,1202.5,63.9z M1164.8,70.5c0.6-4.1,2-8,4.3-11.8c0.6-0.9,0.6-1.6,0-2.6\r\n\tc-1.5-2.2-3-4.3-5.5-6.3c-0.4,8.7,0.2,17.2,0.3,25.6C1164.2,73.9,1164.6,72.2,1164.8,70.5z M1233.5,66.5c-1.4,1.8-2.1,3.8-2,5.4\r\n\tc0.3,3.5,0.7,7,1.1,10.5c0.4,3.3,0.9,6.6,1.3,9.9c0.1,0.8,0.4,1.5,0.5,2.2c0.1,0,0.3,0,0.4,0C1234.4,85.3,1233.9,76.1,1233.5,66.5z\r\n\t M1146.6,77.2c0.2-2-1-3.8-1.7-6.2c-0.9,2.4-0.7,12.5,0.1,16.5C1145.6,84.1,1146.3,80.7,1146.6,77.2z M1194.9,44.2\r\n\tc0,0.4,0.2,0.9,0.5,1.2c1.7,1.6,3.5,3.2,5.4,4.9c0.9-0.9,1.2-1.7,0.3-2.7c-1.7-1.9-3.2-3.8-5.5-5.7\r\n\tC1195.2,42.9,1194.9,43.5,1194.9,44.2z M1265.4,78.4c-0.2,0-0.3-0.1-0.5-0.1c-2.2,3.9-4.2,7.8-2.3,12.7\r\n\tC1263.5,86.5,1264.4,82.4,1265.4,78.4z M1203.4,50.6c-0.8,1.1-0.8,1.9-0.2,2.9c2.1,2.9,4.2,5.8,6.3,8.8c0.2,0.2,0.4,0.4,0.6,0.6\r\n\tC1208.6,58.5,1206.3,54.5,1203.4,50.6z M1204.4,87.6c-0.3-3.1-0.8-6.2-1.3-9.3c0-0.2-0.1-0.3-0.2-0.5c0,4,0,8,0,12.1\r\n\tc0.3,0,0.5,0,0.8,0C1204,89.1,1204.5,88.3,1204.4,87.6z M1230.8,59.9c1.4-1.7,1.4-2.8,0-5.4C1230.8,56.5,1230.8,58.2,1230.8,59.9z\r\n\t M1208.3,89c-1,1.1,0,2.2,0,3.2C1208.3,91.1,1208.3,90,1208.3,89z M1065.4,94.3c0.1,1,0.1,1.8,0.2,2.6c1.3,0,2.5,0,3.9,0\r\n\tc0.2-1,0.4-2.2,0.8-3.8c0.3,1.5,0.5,2.6,0.7,3.8c0.6,0,1.2,0,2.1,0c0.1-2.2,0.3-4.5,0.4-6.6c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1,0.1,2.2,0.2,3.2c0.1,1.1,0.2,2.2,0.3,3.4c1,0,1.8,0,2.9,0c0.2-1.4,0.5-2.9,0.7-4.3c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1.4,0.2,2.8,0.3,4.4c3.1,0.2,6,0.2,9.1,0.4c0.3-3,0.6-5.8,1-8.5c0.2,0,0.3,0,0.5,0c0.7,2.7,1.4,5.4,2.1,8.3c1.3,0,2.6,0,4,0\r\n\tc0.2-0.6,0.4-1.3,0.6-1.9c0.1,0,0.2,0,0.4-0.1c0.2,0.6,0.3,1.3,0.5,2c0.8,0,1.6,0,2.7,0c-0.2-3.8-0.4-7.4-0.7-11.1\r\n\tc0.2,0,0.4,0,0.6-0.1c0.8,1.7,0.6,3.6,0.8,5.4c0.2,1.8,0,3.8,0,5.8c1.1,0,1.9,0,3,0c0.5-2.6,0.4-5.2,0.3-7.8c-0.2-3-0.6-5.8-0.8-8.8\r\n\tc0-0.5-0.1-1,0.1-1.4c0.7-1.3,1.4-2.6,2.4-3.8c-1.5,7.2-1.8,14.5-0.9,21.8c1.3,0,2.3,0,3.5,0c0.3-5.6-0.5-11.2,0.8-17.1\r\n\tc0.8,5.8-0.2,11.3-0.4,17c0.9,0.1,1.7,0.1,2.7,0.2c0.2-1.4,0.4-2.6,0.6-3.8c1.2-6.9,1.1-13.8,0.5-20.7c-0.5-5.7-1.6-11.3-3-16.8\r\n\tc-0.2-0.6,0.2-1.4,0.3-2.1c0,0-0.3,0.1-0.8,0.2c-1-2.5-1.9-5-3-7.7c3.5-2.8,6.7-6,11.3-8.1c-4.6,1.1-8.5,3.2-12.3,5.8\r\n\tc-1-1.6-1.8-3-2.7-4.3c-0.9-1.3-2.1-2.5-3.2-3.7c-0.1,0.1-0.3,0.2-0.4,0.2c1.5,3,2.9,6.1,4.3,9c-2.7,2.6-5.1,5-7.6,7.4\r\n\tc-1.6-2.6-2.9-5.2-4.6-7.7c-1.8-2.6-3.9-5.3-6-7.8c-1.5-1.8-3.7-3-6.4-3.9c0.8,1,1.4,2.1,2.3,3.1c5,6,8.8,12.5,11.8,19.3\r\n\tc0.2,0.5,0.1,1.1-0.1,1.6c-2,3.8-4.1,7.6-6.4,11.8c-0.4-3.6-2.5-6.8-1.6-10.4c-0.4,0-0.8,0-1.1,0c-2.2-4.5-4.1-9-7.6-12.9\r\n\tc-0.5-0.6-0.7-1.4-0.7-2c0.2-3.8,0.6-7.5,0.9-11.3c0.2-1.9,0.5-3.9,0.7-5.8c0.1-0.6-0.2-1.2-0.3-1.8c-0.2,0-0.4,0-0.6,0\r\n\tc-1.3,5.5-2.6,11.1-4,16.6c-3.9-2.5-7.7-5.6-13.6-5.4c-1.9-5.2-3.9-10.3-4.7-15.8c-0.6,5.3,0.1,10.4,1.4,15.5c1.8,7,3.7,14,5.3,21.1\r\n\tc1.7,7.5,2.9,15.1,3.4,22.7c0.1,1.8-0.3,3.5-0.3,5.3c-0.1,3.7-0.2,7.4-0.3,11.1c0,0.2,0.1,0.5,0.1,0.8c0.7,0,1.3,0,2.1,0\r\n\tC1064.7,96.1,1065,95.3,1065.4,94.3z M1089.8,73.6c1.7-2.8,3.5-5.6,5.1-8.5c0.2-0.3,0.2-0.8,0.1-1.1c-0.3-1-0.8-2.1-1.6-3.1\r\n\tc-0.4,0.7-0.9,1.4-1.3,2.2c-1.4,2.9-2.8,5.8-4.2,8.7c-0.1,0.5,0,1-0.3,1.5c-1.4,2.2-1.2,4.6-0.6,7c1.2-2.8,0.6-5.7,0.9-8.5\r\n\tC1088.5,72.5,1089.1,73.1,1089.8,73.6z M1065.9,69.5c0,0.2,0.3,0.3,0.5,0.5c-0.4-8.3-2.8-16.5-1.1-24.7c0.2,0,0.4-0.1,0.6-0.1\r\n\tc0.4,1,0.8,2,1.1,3c1.8,8,2.9,16.1,3.5,24.3c0.2,2.3,0.4,4.6,0.7,7c1.3-1.7,1.3-3.5,1.2-5.4c-0.8-8.9-1.5-17.7-1-26.6\r\n\tc0.1-0.9-0.3-1.6-0.9-2.3c-2.5-2.8-5.9-4.8-9.5-6.6c-0.5-0.2-1-0.4-1.6-0.5c-0.3-0.1-0.6,0-1.5,0C1062.1,48.5,1064,59.1,1065.9,69.5\r\n\tz M1106.7,71.1c0.6-0.5,1.1-1.4,1-2.1c-0.5-3.5-1.2-7-2.3-10.7c-0.7,0.8-1.4,1.5-2,2.3c-1.2,1.5-2.9,3-3.4,4.7\r\n\tc-0.4,1.6,0.4,3.4,0.7,5.1c0.3,1.4,0.6,2.9,0.9,4.6C1103.5,73.5,1105.2,72.3,1106.7,71.1z M1076.9,69.5c0.8-2,1.7-3.9,2.6-5.9\r\n\tc0.2-0.6,0.5-1.1,0.4-1.7c-1-3.8-3-7.4-5.2-10.9c-0.8,7.6,0.2,15.2,0.8,22.7C1076,72.3,1076.3,70.8,1076.9,69.5z M1103.5,49\r\n\tc-0.2,0-0.4-0.1-0.6-0.1c-2,2.3-4.1,4.6-6.1,7c-0.3,0.4-0.4,1-0.3,1.4c0.4,1.3,1,2.6,1.5,4c2.4-1.8,4.7-3.5,7.2-5.4\r\n\tC1104.7,53.8,1104.1,51.4,1103.5,49z M1091.7,82.7c0.5,2.3,0.9,4.6,1.3,7c0.1,0.6,0.3,1.1,0.7,2.1c0.8-3.2,1.8-5.9,1.4-8.9\r\n\tc-0.4-3.3-0.1-6.7-0.1-10C1093.2,76,1090.9,78.9,1091.7,82.7z M1079.9,82.6c-0.2,1.4-0.4,2.8,0.6,4.3c0.8-3.4,1.7-6.7,2.3-9.9\r\n\tc0.4-2.2-0.5-4.4-1-6.6C1081.2,74.4,1080.5,78.5,1079.9,82.6z M1095.9,71.7c0.7,2.7,1.4,5.4,2.3,8.5c0.2-0.5,0.5-0.8,0.4-1.1\r\n\tc-0.5-3-1.2-5.9-1.7-8.9c-0.2,0-0.4-0.1-0.6-0.1C1096.1,70.7,1095.8,71.2,1095.9,71.7z M1083.6,88.6c-0.1,0-0.2,0-0.2,0\r\n\tc0,0.6-0.1,1.4-0.1,2c0.1,0,0.2-0.1,0.4-0.1C1083.6,89.9,1083.6,89.2,1083.6,88.6z M708.6,94.3c0.1,1,0.1,1.8,0.2,2.6\r\n\tc1.3,0,2.5,0,3.9,0c0.2-1,0.4-2.2,0.8-3.8c0.3,1.5,0.5,2.6,0.7,3.8c0.6,0,1.2,0,2.1,0c0.1-2.2,0.3-4.5,0.4-6.6c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1,0.1,2.2,0.2,3.2c0.1,1.1,0.2,2.2,0.3,3.4c1,0,1.8,0,2.9,0c0.2-1.4,0.5-2.9,0.7-4.3c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1.4,0.2,2.8,0.3,4.4c3.1,0.2,6,0.2,9.1,0.4c0.3-3,0.6-5.8,1-8.5c0.2,0,0.3,0,0.5,0c0.7,2.7,1.4,5.4,2.1,8.3c1.3,0,2.6,0,4,0\r\n\tc0.2-0.6,0.4-1.3,0.6-1.9c0.1,0,0.2,0,0.4-0.1c0.2,0.6,0.3,1.3,0.5,2c0.8,0,1.6,0,2.7,0c-0.2-3.8-0.4-7.4-0.7-11.1\r\n\tc0.2,0,0.4,0,0.6-0.1c0.8,1.7,0.6,3.6,0.8,5.4c0.2,1.8,0,3.8,0,5.8c1.1,0,1.9,0,3,0c0.5-2.6,0.4-5.2,0.3-7.8c-0.2-3-0.6-5.8-0.8-8.8\r\n\tc0-0.5-0.1-1,0.1-1.4c0.7-1.3,1.4-2.6,2.4-3.8c-1.5,7.2-1.8,14.5-0.9,21.8c1.3,0,2.3,0,3.5,0c0.3-5.6-0.5-11.2,0.8-17.1\r\n\tc0.8,5.8-0.2,11.3-0.4,17c0.9,0.1,1.7,0.1,2.7,0.2c0.2-1.4,0.4-2.6,0.6-3.8c1.2-6.9,1.1-13.8,0.5-20.7c-0.5-5.7-1.6-11.3-3-16.8\r\n\tc-0.2-0.6,0.2-1.4,0.3-2.1c0,0-0.3,0.1-0.8,0.2c-1-2.5-1.9-5-3-7.7c3.5-2.8,6.7-6,11.3-8.1c-4.6,1.1-8.5,3.2-12.3,5.8\r\n\tc-1-1.6-1.8-3-2.7-4.3c-0.9-1.3-2.1-2.5-3.2-3.7c-0.1,0.1-0.3,0.2-0.4,0.2c1.5,3,2.9,6.1,4.3,9c-2.7,2.6-5.1,5-7.6,7.4\r\n\tc-1.6-2.6-2.9-5.2-4.6-7.7c-1.8-2.6-3.9-5.3-6-7.8c-1.5-1.8-3.7-3-6.4-3.9c0.8,1,1.4,2.1,2.3,3.1c5,6,8.8,12.5,11.8,19.3\r\n\tc0.2,0.5,0.1,1.1-0.1,1.6c-2,3.8-4.1,7.6-6.4,11.8c-0.4-3.6-2.5-6.8-1.6-10.4c-0.4,0-0.8,0-1.1,0c-2.2-4.5-4.1-9-7.6-12.9\r\n\tc-0.5-0.6-0.7-1.4-0.7-2c0.2-3.8,0.6-7.5,0.9-11.3c0.2-1.9,0.5-3.9,0.7-5.8c0.1-0.6-0.2-1.2-0.3-1.8c-0.2,0-0.4,0-0.6,0\r\n\tc-1.3,5.5-2.6,11.1-4,16.6c-3.9-2.5-7.7-5.6-13.6-5.4c-1.9-5.2-3.9-10.3-4.7-15.8c-0.6,5.3,0.1,10.4,1.4,15.5c1.8,7,3.7,14,5.3,21.1\r\n\tc1.7,7.5,2.9,15.1,3.4,22.7c0.1,1.8-0.3,3.5-0.3,5.3c-0.1,3.7-0.2,7.4-0.3,11.1c0,0.2,0.1,0.5,0.1,0.8c0.7,0,1.3,0,2.1,0\r\n\tC707.8,96.1,708.2,95.3,708.6,94.3z M732.9,73.6c1.7-2.8,3.5-5.6,5.1-8.5c0.2-0.3,0.2-0.8,0.1-1.1c-0.3-1-0.8-2.1-1.6-3.1\r\n\tc-0.4,0.7-0.9,1.4-1.3,2.2c-1.4,2.9-2.8,5.8-4.2,8.7c-0.1,0.5,0,1-0.3,1.5c-1.4,2.2-1.2,4.6-0.6,7c1.2-2.8,0.6-5.7,0.9-8.5\r\n\tC731.6,72.5,732.3,73.1,732.9,73.6z M709.1,69.5c0,0.2,0.3,0.3,0.5,0.5c-0.4-8.3-2.8-16.5-1.1-24.7c0.2,0,0.4-0.1,0.6-0.1\r\n\tc0.4,1,0.8,2,1.1,3c1.8,8,2.9,16.1,3.5,24.3c0.2,2.3,0.4,4.6,0.7,7c1.3-1.7,1.3-3.5,1.2-5.4c-0.8-8.9-1.5-17.7-1-26.6\r\n\tc0.1-0.9-0.3-1.6-0.9-2.3c-2.5-2.8-5.9-4.8-9.5-6.6c-0.5-0.2-1-0.4-1.6-0.5c-0.3-0.1-0.6,0-1.5,0C705.3,48.5,707.1,59.1,709.1,69.5z\r\n\t M749.8,71.1c0.6-0.5,1.1-1.4,1-2.1c-0.5-3.5-1.2-7-2.3-10.7c-0.7,0.8-1.4,1.5-2,2.3c-1.2,1.5-2.9,3-3.4,4.7\r\n\tc-0.4,1.6,0.4,3.4,0.7,5.1c0.3,1.4,0.6,2.9,0.9,4.6C746.7,73.5,748.4,72.3,749.8,71.1z M720,69.5c0.8-2,1.7-3.9,2.6-5.9\r\n\tc0.2-0.6,0.5-1.1,0.4-1.7c-1-3.8-3-7.4-5.2-10.9c-0.8,7.6,0.2,15.2,0.8,22.7C719.1,72.3,719.5,70.8,720,69.5z M746.6,49\r\n\tc-0.2,0-0.4-0.1-0.6-0.1c-2,2.3-4.1,4.6-6.1,7c-0.3,0.4-0.4,1-0.3,1.4c0.4,1.3,1,2.6,1.5,4c2.4-1.8,4.7-3.5,7.2-5.4\r\n\tC747.9,53.8,747.3,51.4,746.6,49z M734.9,82.7c0.5,2.3,0.9,4.6,1.3,7c0.1,0.6,0.3,1.1,0.7,2.1c0.8-3.2,1.8-5.9,1.4-8.9\r\n\tc-0.4-3.3-0.1-6.7-0.1-10C736.4,76,734,78.9,734.9,82.7z M723.1,82.6c-0.2,1.4-0.4,2.8,0.6,4.3c0.8-3.4,1.7-6.7,2.3-9.9\r\n\tc0.4-2.2-0.5-4.4-1-6.6C724.3,74.4,723.7,78.5,723.1,82.6z M739.1,71.7c0.7,2.7,1.4,5.4,2.3,8.5c0.2-0.5,0.5-0.8,0.4-1.1\r\n\tc-0.5-3-1.2-5.9-1.7-8.9c-0.2,0-0.4-0.1-0.6-0.1C739.3,70.7,739,71.2,739.1,71.7z M726.7,88.6c-0.1,0-0.2,0-0.2,0\r\n\tc0,0.6-0.1,1.4-0.1,2c0.1,0,0.2-0.1,0.4-0.1C726.7,89.9,726.7,89.2,726.7,88.6z M627.7,94.3c0.1,1,0.1,1.8,0.2,2.6\r\n\tc1.3,0,2.5,0,3.9,0c0.2-1,0.4-2.2,0.8-3.8c0.3,1.5,0.5,2.6,0.7,3.8c0.6,0,1.2,0,2.1,0c0.1-2.2,0.3-4.5,0.4-6.6c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1,0.1,2.2,0.2,3.2c0.1,1.1,0.2,2.2,0.3,3.4c1,0,1.8,0,2.9,0c0.2-1.4,0.5-2.9,0.7-4.3c0.1,0,0.2,0,0.4,0\r\n\tc0.1,1.4,0.2,2.8,0.3,4.4c3.1,0.2,6,0.2,9.1,0.4c0.3-3,0.6-5.8,1-8.5c0.2,0,0.3,0,0.5,0c0.7,2.7,1.4,5.4,2.1,8.3c1.3,0,2.6,0,4,0\r\n\tc0.2-0.6,0.4-1.3,0.6-1.9c0.1,0,0.2,0,0.4-0.1c0.2,0.6,0.3,1.3,0.5,2c0.8,0,1.6,0,2.7,0c-0.2-3.8-0.4-7.4-0.7-11.1\r\n\tc0.2,0,0.4,0,0.6-0.1c0.8,1.7,0.6,3.6,0.8,5.4c0.2,1.8,0,3.8,0,5.8c1.1,0,1.9,0,3,0c0.5-2.6,0.4-5.2,0.3-7.8c-0.2-3-0.6-5.8-0.8-8.8\r\n\tc0-0.5-0.1-1,0.1-1.4c0.7-1.3,1.4-2.6,2.4-3.8c-1.5,7.2-1.8,14.5-0.9,21.8c1.3,0,2.3,0,3.5,0c0.3-5.6-0.5-11.2,0.8-17.1\r\n\tc0.8,5.8-0.2,11.3-0.4,17c0.9,0.1,1.7,0.1,2.7,0.2c0.2-1.4,0.4-2.6,0.6-3.8c1.2-6.9,1.1-13.8,0.5-20.7c-0.5-5.7-1.6-11.3-3-16.8\r\n\tc-0.2-0.6,0.2-1.4,0.3-2.1c0,0-0.3,0.1-0.8,0.2c-1-2.5-1.9-5-3-7.7c3.5-2.8,6.7-6,11.3-8.1c-4.6,1.1-8.5,3.2-12.3,5.8\r\n\tc-1-1.6-1.8-3-2.7-4.3c-0.9-1.3-2.1-2.5-3.2-3.7c-0.1,0.1-0.3,0.2-0.4,0.2c1.5,3,2.9,6.1,4.3,9c-2.7,2.6-5.1,5-7.6,7.4\r\n\tc-1.6-2.6-2.9-5.2-4.6-7.7c-1.8-2.6-3.9-5.3-6-7.8c-1.5-1.8-3.7-3-6.4-3.9c0.8,1,1.4,2.1,2.3,3.1c5,6,8.8,12.5,11.8,19.3\r\n\tc0.2,0.5,0.1,1.1-0.1,1.6c-2,3.8-4.1,7.6-6.4,11.8c-0.4-3.6-2.5-6.8-1.6-10.4c-0.4,0-0.8,0-1.1,0c-2.2-4.5-4.1-9-7.6-12.9\r\n\tc-0.5-0.6-0.7-1.4-0.7-2c0.2-3.8,0.6-7.5,0.9-11.3c0.2-1.9,0.5-3.9,0.7-5.8c0.1-0.6-0.2-1.2-0.3-1.8c-0.2,0-0.4,0-0.6,0\r\n\tc-1.3,5.5-2.6,11.1-4,16.6c-3.9-2.5-7.7-5.6-13.6-5.4c-1.9-5.2-3.9-10.3-4.7-15.8c-0.6,5.3,0.1,10.4,1.4,15.5c1.8,7,3.7,14,5.3,21.1\r\n\tc1.7,7.5,2.9,15.1,3.4,22.7c0.1,1.8-0.3,3.5-0.3,5.3c-0.1,3.7-0.2,7.4-0.3,11.1c0,0.2,0.1,0.5,0.1,0.8c0.7,0,1.3,0,2.1,0\r\n\tC627,96.1,627.3,95.3,627.7,94.3z M652,73.6c1.7-2.8,3.5-5.6,5.1-8.5c0.2-0.3,0.2-0.8,0.1-1.1c-0.3-1-0.8-2.1-1.6-3.1\r\n\tc-0.4,0.7-0.9,1.4-1.3,2.2c-1.4,2.9-2.8,5.8-4.2,8.7c-0.1,0.5,0,1-0.3,1.5c-1.4,2.2-1.2,4.6-0.6,7c1.2-2.8,0.6-5.7,0.9-8.5\r\n\tC650.8,72.5,651.4,73.1,652,73.6z M628.2,69.5c0,0.2,0.3,0.3,0.5,0.5c-0.4-8.3-2.8-16.5-1.1-24.7c0.2,0,0.4-0.1,0.6-0.1\r\n\tc0.4,1,0.8,2,1.1,3c1.8,8,2.9,16.1,3.5,24.3c0.2,2.3,0.4,4.6,0.7,7c1.3-1.7,1.3-3.5,1.2-5.4c-0.8-8.9-1.5-17.7-1-26.6\r\n\tc0.1-0.9-0.3-1.6-0.9-2.3c-2.5-2.8-5.9-4.8-9.5-6.6c-0.5-0.2-1-0.4-1.6-0.5c-0.3-0.1-0.6,0-1.5,0C624.4,48.5,626.3,59.1,628.2,69.5z\r\n\t M669,71.1c0.6-0.5,1.1-1.4,1-2.1c-0.5-3.5-1.2-7-2.3-10.7c-0.7,0.8-1.4,1.5-2,2.3c-1.2,1.5-2.9,3-3.4,4.7c-0.4,1.6,0.4,3.4,0.7,5.1\r\n\tc0.3,1.4,0.6,2.9,0.9,4.6C665.8,73.5,667.5,72.3,669,71.1z M639.2,69.5c0.8-2,1.7-3.9,2.6-5.9c0.2-0.6,0.5-1.1,0.4-1.7\r\n\tc-1-3.8-3-7.4-5.2-10.9c-0.8,7.6,0.2,15.2,0.8,22.7C638.2,72.3,638.6,70.8,639.2,69.5z M665.8,49c-0.2,0-0.4-0.1-0.6-0.1\r\n\tc-2,2.3-4.1,4.6-6.1,7c-0.3,0.4-0.4,1-0.3,1.4c0.4,1.3,1,2.6,1.5,4c2.4-1.8,4.7-3.5,7.2-5.4C667,53.8,666.4,51.4,665.8,49z\r\n\t M654,82.7c0.5,2.3,0.9,4.6,1.3,7c0.1,0.6,0.3,1.1,0.7,2.1c0.8-3.2,1.8-5.9,1.4-8.9c-0.4-3.3-0.1-6.7-0.1-10\r\n\tC655.5,76,653.2,78.9,654,82.7z M642.2,82.6c-0.2,1.4-0.4,2.8,0.6,4.3c0.8-3.4,1.7-6.7,2.3-9.9c0.4-2.2-0.5-4.4-1-6.6\r\n\tC643.4,74.4,642.8,78.5,642.2,82.6z M658.2,71.7c0.7,2.7,1.4,5.4,2.3,8.5c0.2-0.5,0.5-0.8,0.4-1.1c-0.5-3-1.2-5.9-1.7-8.9\r\n\tc-0.2,0-0.4-0.1-0.6-0.1C658.4,70.7,658.1,71.2,658.2,71.7z M645.8,88.6c-0.1,0-0.2,0-0.2,0c0,0.6-0.1,1.4-0.1,2\r\n\tc0.1,0,0.2-0.1,0.4-0.1C645.8,89.9,645.8,89.2,645.8,88.6z M770.6,38.1c-0.4-0.5-0.9-0.9-1.1-1.4c-1.5-2.9-3-5.8-4.4-8.6\r\n\tc-0.3-0.6-0.1-1.4-0.6-1.6c-2.6-1.4-3.6-3.8-6.2-5.1c-1.6-0.9-1.9-1-3.9-1.1c3.3,2.3,5.6,5.2,7.5,8.2c-0.1,0.2-0.2,0.5-0.4,0.7\r\n\tc-3.6,4.4-5,9.3-5.1,14.5c-0.2,9.3,1.7,18.3,4.1,27.3c0.8,2.9,1.2,5.8,1.8,8.6c-0.2,0-0.3,0.1-0.5,0.1c-0.5-1.4-0.9-2.7-1.4-4\r\n\tc-0.6-1.5-1-3-1.8-4.5c-0.7-1.4-1.8-2.6-3-3.8c-0.4,0.9-0.2,1.7,0,2.4c2,7.7,4,15.3,6,23c0.2,0.7,0,1.4,0,2.2\r\n\tc-0.1,0.6-0.2,1.3-0.4,2c2,0.5,3.9,0.5,5.6,0.2c1.7-0.3,3.3,0.6,5-0.1c0.1-0.5,0.3-1,0.5-1.8c0.3,0.5,0.5,0.8,0.7,1\r\n\tc0.3,0.8,1,1,2.1,1c2-0.1,4.1,0,6.4,0c0-2,0-3.8,0-5.8c0.2,0,0.3,0,0.5-0.1c0.6,1.9,1.1,3.8,1.7,5.7c3.4,0,6.5,0,9.8,0\r\n\tc0.1-1.2,0.2-2.4,0.3-3.5c0.1,0,0.1,0,0.2,0c0.2,1.1,0.4,2.3,0.7,3.6c2.1,0,4.1,0,6.4,0c0.8-8.4-0.3-16.7-1.2-24.9\r\n\tc-0.1,0.5-0.3,0.9-0.4,1.4c-0.1,0-0.3,0-0.4-0.1c-1.3-0.6-1.3-1.7-1.4-2.7c-0.3-4.5-0.6-9-1.1-13.5c-0.6-5.1-1.6-10.3-4-15.1\r\n\tc-1.5-3-3.4-5.8-7.5-7.3c0.4-3.8,1.8-7.3,3-11c-2.4,1-2.4,1-7,10.5C776.7,34.2,773.3,35.6,770.6,38.1c1.4-0.3,2.9-0.7,4.3-1.1\r\n\tc1.9-0.6,3.7-0.7,5.7-0.3c0,0.3-0.1,0.6-0.1,0.9c-1.6,8.2-1.2,16.5-0.8,24.8c0.3,5.2,0.1,10.3-1.1,15.7c-0.4-0.9-0.8-1.5-0.9-2.2\r\n\tc-0.3-2.3-0.7-4.6-0.6-7c0.2-4.6,0.7-9.1,1-13.7c0.2-3.1,0.4-6.3-0.4-9.5c-1.8,4-2.5,8.2-3.5,12.8c-0.3-0.5-0.5-0.6-0.5-0.7\r\n\tc-0.3-5.9-1.4-11.8-3.1-17.6C770.4,39.5,770.6,38.8,770.6,38.1z M760.3,38.8c-0.9,6-0.2,12,0.7,17.9c0.5,3.1,1.2,6.2,1.8,9.3\r\n\tc0.1,0.7,0.4,1.4,0.6,2.2c0.3-0.6,0.5-0.9,1-1.7c0.7,1.2,1.2,2.1,1.9,3.4c0.2-1.8,0.4-3.3,0.6-4.7c0.2,0,0.4-0.1,0.5-0.1\r\n\tc0.3,0.4,0.7,0.8,0.8,1.2c0.5,2.7,1.1,5.4,1.4,8.1c0.2,1.9,0,3.9,0,5.8c0.2,0,0.4,0,0.5,0c0.1-3.6,0.3-7.3,0.2-10.9\r\n\tc-0.1-7.9-0.6-15.9-2.2-23.8c-0.9-4.2-2.1-8.4-3.9-12.5c-0.3-0.7-0.7-1.4-1.2-2.5C761.6,33.4,760.7,36.1,760.3,38.8z M790.5,56.2\r\n\tc-0.5,7.2-0.9,14.4-1.3,21.7c-0.2,2.8,0,5.6-0.2,8.4c-0.2,2.7,0.6,5.3,1.5,7.8c0.8-8.8-0.4-17.7,0.8-26.5c1,2.3,0.7,5,2.6,7.2\r\n\tc0-1.4,0.1-2.7,0-4.1c-0.7-6.8-1.3-13.6-2.3-20.4c-0.4-3-1.8-5.8-3-8.6c-0.9-2.1-1.9-3-4-4c-1.4,6.4-1.1,12.7-1.1,19.1\r\n\tc0,11.6,0.6,17.6,1.8,18.8c0.4-8.3,0.1-16.6,4.9-24.1c0.3,0,0.5,0.1,0.8,0.1C790.8,53.1,790.6,54.6,790.5,56.2z M773.8,84.4\r\n\tc-0.6,1.6-0.9,3.2-0.2,4.9c0.2,0,0.4,0,0.5,0C774,87.6,773.9,86,773.8,84.4z M798.1,91.5c0-1,0-1.8,0-2.7c-0.1,0-0.3,0-0.4,0\r\n\tC797.8,89.6,797.9,90.4,798.1,91.5z M794.1,91.1h0.1c0-0.3,0-0.6,0-0.9c0,0-0.1,0-0.1,0.1C794.1,90.5,794.1,90.8,794.1,91.1z\r\n\t M676.5,38.1c-0.4-0.5-0.9-0.9-1.1-1.4c-1.5-2.9-3-5.8-4.4-8.6c-0.3-0.6-0.1-1.4-0.6-1.6c-2.6-1.4-3.6-3.8-6.2-5.1\r\n\tc-1.6-0.9-1.9-1-3.9-1.1c3.3,2.3,5.6,5.2,7.5,8.2c-0.1,0.2-0.2,0.5-0.4,0.7c-3.6,4.4-5,9.3-5.1,14.5C662.1,53,664,62,666.4,71\r\n\tc0.8,2.9,1.2,5.8,1.8,8.6c-0.2,0-0.3,0.1-0.5,0.1c-0.5-1.4-0.9-2.7-1.4-4c-0.6-1.5-1-3-1.8-4.5c-0.7-1.4-1.8-2.6-3-3.8\r\n\tc-0.4,0.9-0.2,1.7,0,2.4c2,7.7,4,15.3,6,23c0.2,0.7,0,1.4,0,2.2c-0.1,0.6-0.2,1.3-0.4,2c2,0.5,3.9,0.5,5.6,0.2\r\n\tc1.7-0.3,3.3,0.6,5-0.1c0.1-0.5,0.3-1,0.5-1.8c0.3,0.5,0.5,0.8,0.7,1c0.3,0.8,1,1,2.1,1c2-0.1,4.1,0,6.4,0c0-2,0-3.8,0-5.8\r\n\tc0.2,0,0.3,0,0.5-0.1c0.6,1.9,1.1,3.8,1.7,5.7c3.4,0,6.5,0,9.8,0c0.1-1.2,0.2-2.4,0.3-3.5c0.1,0,0.1,0,0.2,0\r\n\tc0.2,1.1,0.4,2.3,0.7,3.6c2.1,0,4.1,0,6.4,0c0.8-8.4-0.3-16.7-1.2-24.9c-0.1,0.5-0.3,0.9-0.4,1.4c-0.1,0-0.3,0-0.4-0.1\r\n\tc-1.3-0.6-1.3-1.7-1.4-2.7c-0.3-4.5-0.6-9-1.1-13.5c-0.6-5.1-1.6-10.3-4-15.1c-1.5-3-3.4-5.8-7.5-7.3c0.4-3.8,1.8-7.3,3-11\r\n\tc-2.4,1-2.4,1-7,10.5C682.7,34.2,679.2,35.6,676.5,38.1c1.4-0.3,2.9-0.7,4.3-1.1c1.9-0.6,3.7-0.7,5.7-0.3c0,0.3-0.1,0.6-0.1,0.9\r\n\tc-1.6,8.2-1.2,16.5-0.8,24.8c0.3,5.2,0.1,10.3-1.1,15.7c-0.4-0.9-0.8-1.5-0.9-2.2c-0.3-2.3-0.7-4.6-0.6-7c0.2-4.6,0.7-9.1,1-13.7\r\n\tc0.2-3.1,0.4-6.3-0.4-9.5c-1.8,4-2.5,8.2-3.5,12.8c-0.3-0.5-0.5-0.6-0.5-0.7c-0.3-5.9-1.4-11.8-3.1-17.6\r\n\tC676.3,39.5,676.5,38.8,676.5,38.1z M666.2,38.8c-0.9,6-0.2,12,0.7,17.9c0.5,3.1,1.2,6.2,1.8,9.3c0.1,0.7,0.4,1.4,0.6,2.2\r\n\tc0.3-0.6,0.5-0.9,1-1.7c0.7,1.2,1.2,2.1,1.9,3.4c0.2-1.8,0.4-3.3,0.6-4.7c0.2,0,0.4-0.1,0.5-0.1c0.3,0.4,0.7,0.8,0.8,1.2\r\n\tc0.5,2.7,1.1,5.4,1.4,8.1c0.2,1.9,0,3.9,0,5.8c0.2,0,0.4,0,0.5,0c0.1-3.6,0.3-7.3,0.2-10.9c-0.1-7.9-0.6-15.9-2.2-23.8\r\n\tc-0.9-4.2-2.1-8.4-3.9-12.5c-0.3-0.7-0.7-1.4-1.2-2.5C667.5,33.4,666.6,36.1,666.2,38.8z M696.5,56.2c-0.5,7.2-0.9,14.4-1.3,21.7\r\n\tc-0.2,2.8,0,5.6-0.2,8.4c-0.2,2.7,0.6,5.3,1.5,7.8c0.8-8.8-0.4-17.7,0.8-26.5c1,2.3,0.7,5,2.6,7.2c0-1.4,0.1-2.7,0-4.1\r\n\tc-0.7-6.8-1.3-13.6-2.3-20.4c-0.4-3-1.8-5.8-3-8.6c-0.9-2.1-1.9-3-4-4c-1.4,6.4-1.1,12.7-1.1,19.1c0,11.6,0.6,17.6,1.8,18.8\r\n\tc0.4-8.3,0.1-16.6,4.9-24.1c0.3,0,0.5,0.1,0.8,0.1C696.7,53.1,696.6,54.6,696.5,56.2z M679.8,84.4c-0.6,1.6-0.9,3.2-0.2,4.9\r\n\tc0.2,0,0.4,0,0.5,0C680,87.6,679.9,86,679.8,84.4z M704.1,91.5c0-1,0-1.8,0-2.7c-0.1,0-0.3,0-0.4,0\r\n\tC703.8,89.6,703.9,90.4,704.1,91.5z M700.1,91.1h0.1c0-0.3,0-0.6,0-0.9c0,0-0.1,0-0.1,0.1C700.1,90.5,700.1,90.8,700.1,91.1z\r\n\t M1130.5,97.1c0.2-1,0.3-1.8,0.5-2.6c0.2-1.5,0.7-3,0.5-4.5c-0.3-2.6-1.1-5.3-1.7-7.9c-0.5-2.2-1.1-4.6-1.6-7c3,1.3,3.4,3.7,5,5.4\r\n\tc0.3-3.8-0.5-7.4-0.6-11.1c-0.1-3.7-0.4-7.4-0.4-11.1c0-3.6,0.2-7.3,0.4-10.9c-2.7,4-4.2,8.2-5.1,12.6c1.5-1.4,2-3.3,4.2-4.6\r\n\tc-2,7-4.1,13.9-4.5,20.7c-0.5,7-0.4,13.9-0.5,21c-1.8,0-3.7,0-5.5,0c-1.4-3.8-1.9-14.3-0.9-19.5c0.4,0.4,0.7,0.7,1.3,1.4\r\n\tc0-1.1,0-1.8,0-2.4c0.3-4,0.4-8.1,0.8-12.1c0.5-4.4,1.7-8.7,3.8-12.9c1.2-2.2,2.5-4.5,4.9-6c2.2-1.4,2.8-3,2.5-5.1\r\n\tc-0.6-5-1.3-10-2.9-14.9c-1.6-4.8-4.1-9-10.3-11c-0.1,0-0.1-0.1-0.2-0.2c1.1-0.6,2.3-0.5,3.5-0.2c3.2,0.7,5.4,2.6,6.7,4.8\r\n\tc1.4,2.5,2.6,5,3.6,7.7c0.9,2.4,1.5,4.8,2.3,7.4c4-4.5,7.5-3.5,10.2-1.3c-0.8-0.1-1.4-0.2-2.1-0.2c-1.8-0.1-3.5,0.2-4.5,1.4\r\n\tc-1.9,2.4-3,5-2.7,7.9c0.4,5.4,1,11,0.9,16.4c-0.1,6.5-0.9,13.1-1.3,19.5c-0.1,0.8,0.1,1.8,0.5,2.5c2,3,3.1,6.2,3.8,9.5\r\n\tc0.6,2.4,1,4.9,1.5,7.4C1138.3,97.1,1134.5,97.1,1130.5,97.1z M657.7,97.1c0.2-1,0.3-1.8,0.5-2.6c0.2-1.5,0.7-3,0.5-4.5\r\n\tc-0.3-2.6-1.1-5.3-1.7-7.9c-0.5-2.2-1.1-4.6-1.6-7c3,1.3,3.4,3.7,5,5.4c0.3-3.8-0.5-7.4-0.6-11.1c-0.1-3.7-0.4-7.4-0.4-11.1\r\n\tc0-3.6,0.2-7.3,0.4-10.9c-2.7,4-4.2,8.2-5.1,12.6c1.5-1.4,2-3.3,4.2-4.6c-2,7-4.1,13.9-4.5,20.7c-0.5,7-0.4,13.9-0.5,21\r\n\tc-1.8,0-3.7,0-5.5,0c-1.4-3.8-1.9-14.3-0.9-19.5c0.4,0.4,0.7,0.7,1.3,1.4c0-1.1,0-1.8,0-2.4c0.3-4,0.4-8.1,0.8-12.1\r\n\tc0.5-4.4,1.7-8.7,3.8-12.9c1.2-2.2,2.5-4.5,4.9-6c2.2-1.4,2.8-3,2.5-5.1c-0.6-5-1.3-10-2.9-14.9c-1.6-4.8-4.1-9-10.3-11\r\n\tc-0.1,0-0.1-0.1-0.2-0.2c1.1-0.6,2.3-0.5,3.5-0.2c3.2,0.7,5.4,2.6,6.7,4.8c1.4,2.5,2.6,5,3.6,7.7c0.9,2.4,1.5,4.8,2.3,7.4\r\n\tc4-4.5,7.5-3.5,10.2-1.3c-0.8-0.1-1.4-0.2-2.1-0.2c-1.8-0.1-3.5,0.2-4.5,1.4c-1.9,2.4-3,5-2.7,7.9c0.4,5.4,1,11,0.9,16.4\r\n\tc-0.1,6.5-0.9,13.1-1.3,19.5c-0.1,0.8,0.1,1.8,0.5,2.5c2,3,3.1,6.2,3.8,9.5c0.6,2.4,1,4.9,1.5,7.4C665.5,97.1,661.7,97.1,657.7,97.1\r\n\tz M1112.5,96c0.3-4.2,0.6-8.5,0.9-12.7c0.2-2.4,0.5-4.8,0.6-7.2c0.1-1.5-0.2-3.1-0.3-4.7c-0.1-4.5-0.2-9,0.8-13.5\r\n\tc0.8-3.1,2.4-5.9,5.1-8.3c1-0.9,2.1-1.6,3.9-1.4c-0.1,0.2-0.1,0.4-0.2,0.5c-0.1,0.2-0.3,0.3-0.4,0.5c-2.8,2.8-4.7,6-5.1,9.6\r\n\tc-0.4,3.8-0.8,7.5-0.6,11.3c0.5,8,1.3,16,2,24c0.1,1,0.1,1.9,0.2,3c-2.4,0-4.5,0-6.8,0C1112.6,96.6,1112.5,96.3,1112.5,96z\r\n\t M751,66.4c0.2,0.2,0.4,0.5,0.5,0.8c1.9,4.6,3.4,9.4,4.3,14.3c0.8,4.7,1.6,9.5,2.4,14.1c0.1,0.5,0,1,0,1.7c-0.5-0.2-1.1-0.2-1.3-0.5\r\n\tc-0.3-0.5-0.5-1.1-0.6-1.7c-0.9-4.4-1.6-8.7-2.6-13.1c-1-4.8-2.2-9.6-3.3-14.4c-0.1-0.3,0-0.7,0-1.1C750.7,66.5,750.8,66.4,751,66.4\r\n\tz M1239.3,80.9c2.4,2.6,3.9,12.4,2.7,16.3c-0.7,0-1.4,0-2.5,0C1239,91.7,1238.4,86.4,1239.3,80.9z\"\/>\r\n<\/svg>\r\n<\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_e58a8fa9 has_text_color\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">Don&#8217;t miss our adventurous blog<\/h2>\n<\/div><\/div><div class=\"w-grid us_custom_3257a9f0 type_grid layout_14762 cols_3\" id=\"us_grid_1\" style=\"--gap:1.5rem;\" data-filterable=\"true\"><style>@media (max-width:839px){#us_grid_1 .w-grid-item{width:50%}}@media (max-width:600px){#us_grid_1 .w-grid-list{margin:0}#us_grid_1 .w-grid-item{width:100%;padding:0;margin-bottom:var(--gap,0px)}}.layout_14762 .w-grid-item-h{}.layout_14762 .usg_post_image_1{margin-bottom:1rem!important;border-radius:20px!important}.layout_14762 .usg_post_title_1{color:#ffffff!important;font-size:21px!important;font-weight:600!important;margin-top:10px!important;margin-bottom:0.5rem!important}.layout_14762 .usg_post_taxonomy_1{color:#1f1549!important;font-size:16px!important;letter-spacing:3.2px!important;font-weight:700!important;text-transform:uppercase!important}.layout_14762 .usg_btn_1{margin-top:21px!important;border-radius:10px!important;border:1px solid #ffffff!important;text-shadow:0px 4px 28px rgba(0,0,0,0.13)!important}<\/style><div class=\"w-grid-list\">\t<article class=\"w-grid-item post-12628 post type-post status-publish format-standard has-post-thumbnail hentry category-information category-tips\" data-id=\"12628\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><div style=\"padding-bottom:66.6667%\"><\/div><a href=\"https:\/\/aventouralia.com\/en\/blog\/celebrate-birthday-malaga\/\" aria-label=\"Where to Celebrate a Birthday in M\u00e1laga?\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"280\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/03\/donde-celebrar-cumpleanos-en-malaga-500x280.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"donde celebrar cumplea\u00f1os en malaga\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/03\/donde-celebrar-cumpleanos-en-malaga-500x280.jpg 500w, https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/03\/donde-celebrar-cumpleanos-en-malaga-300x168.jpg 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/03\/donde-celebrar-cumpleanos-en-malaga.jpg 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div><div class=\"w-post-elm post_taxonomy usg_post_taxonomy_1 has_text_color style_simple\"><a class=\"term-54 term-information\" href=\"https:\/\/aventouralia.com\/en\/category\/information\/\">Information<\/a><b>, <\/b><a class=\"term-97 term-tips\" href=\"https:\/\/aventouralia.com\/en\/category\/tips\/\">Tips<\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\"><a href=\"https:\/\/aventouralia.com\/en\/blog\/celebrate-birthday-malaga\/\">Where to Celebrate a Birthday in M\u00e1laga?<\/a><\/p><a class=\"w-btn us-btn-style_1 usg_btn_1 grow_ellipse filled\" href=\"https:\/\/aventouralia.com\/en\/blog\/celebrate-birthday-malaga\/\"><span class=\"w-btn-label\">Leer m\u00e1s<\/span><\/a>\t\t<\/div>\r\n\t<\/article>\r\n\t<article class=\"w-grid-item post-15116 post type-post status-publish format-standard has-post-thumbnail hentry category-information\" data-id=\"15116\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><div style=\"padding-bottom:66.6667%\"><\/div><a href=\"https:\/\/aventouralia.com\/en\/blog\/fuengirola-international-countries-fair\/\" aria-label=\"Fuengirola International Countries Fair 2026\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/feria-de-los-pueblos-fuengirola-2026-2-500x333.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"feria de los pueblos Fuengirola 2026\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/feria-de-los-pueblos-fuengirola-2026-2-500x333.jpg 500w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/feria-de-los-pueblos-fuengirola-2026-2-300x200.jpg 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/04\/feria-de-los-pueblos-fuengirola-2026-2.jpg 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div><div class=\"w-post-elm post_taxonomy usg_post_taxonomy_1 has_text_color style_simple\"><a class=\"term-54 term-information\" href=\"https:\/\/aventouralia.com\/en\/category\/information\/\">Information<\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\"><a href=\"https:\/\/aventouralia.com\/en\/blog\/fuengirola-international-countries-fair\/\">Fuengirola International Countries Fair 2026<\/a><\/p><a class=\"w-btn us-btn-style_1 usg_btn_1 grow_ellipse filled\" href=\"https:\/\/aventouralia.com\/en\/blog\/fuengirola-international-countries-fair\/\"><span class=\"w-btn-label\">Leer m\u00e1s<\/span><\/a>\t\t<\/div>\r\n\t<\/article>\r\n\t<article class=\"w-grid-item post-12970 post type-post status-publish format-standard has-post-thumbnail hentry category-information\" data-id=\"12970\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><div style=\"padding-bottom:66.6667%\"><\/div><a href=\"https:\/\/aventouralia.com\/en\/blog\/plans-san-valentin-malaga\/\" aria-label=\"5 Original Plans to Celebrate Valentine\u2019s Day in M\u00e1laga\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/planes-san-valentin-malaga-500x333.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/planes-san-valentin-malaga-500x333.jpg 500w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/planes-san-valentin-malaga-300x200.jpg 300w, https:\/\/aventouralia.com\/wp-content\/uploads\/2026\/01\/planes-san-valentin-malaga.jpg 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div><div class=\"w-post-elm post_taxonomy usg_post_taxonomy_1 has_text_color style_simple\"><a class=\"term-54 term-information\" href=\"https:\/\/aventouralia.com\/en\/category\/information\/\">Information<\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\"><a href=\"https:\/\/aventouralia.com\/en\/blog\/plans-san-valentin-malaga\/\">5 Original Plans to Celebrate Valentine\u2019s Day in M\u00e1laga<\/a><\/p><a class=\"w-btn us-btn-style_1 usg_btn_1 grow_ellipse filled\" href=\"https:\/\/aventouralia.com\/en\/blog\/plans-san-valentin-malaga\/\"><span class=\"w-btn-label\">Leer m\u00e1s<\/span><\/a>\t\t<\/div>\r\n\t<\/article>\r\n<\/div><div class=\"w-grid-preloader\"><div class=\"g-preloader type_1\">\r\n\t<div><\/div>\r\n<\/div>\r\n<\/div>\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;ajax_url&quot;:&quot;https:\\\/\\\/aventouralia.com\\\/wp-admin\\\/admin-ajax.php&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:11,&quot;pagination&quot;:&quot;none&quot;,&quot;permalink_url&quot;:&quot;https:\\\/\\\/aventouralia.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/5535\\\/&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;3&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;14762&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22url%22%3A%22%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;post&quot;],&quot;post_status&quot;:[&quot;publish&quot;,&quot;acf-disabled&quot;,&quot;complete&quot;,&quot;paid&quot;,&quot;confirmed&quot;,&quot;unpaid&quot;,&quot;pending-confirmation&quot;,&quot;cancelled&quot;,&quot;wc-partially-paid&quot;],&quot;posts_per_page&quot;:&quot;3&quot;},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;date&quot;:&quot;DESC&quot;}},&quot;type&quot;:&quot;grid&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_params&quot;:null,&quot;us_grid_index&quot;:1,&quot;_us_grid_post_type&quot;:&quot;post&quot;,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;en&quot;}}'><\/div>\r\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;12970&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;5 Original Plans to Celebrate Valentine\u2019s Day in M\u00e1laga&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"If you\u2019re looking for Valentine\u2019s Day plans in M\u00e1laga and want something different from the usual, here are 5 ideas to surprise your partner. M\u00e1laga is ideal for celebrating February 14th because it combines the sea, sunsets, a great atmosphere, and unique experiences. Below you\u2019ll find romantic and original options, from buggy or quad tours...","protected":false},"author":1,"featured_media":8708,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5535","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quads rental in Marbella and excursions : Aventouralia<\/title>\n<meta name=\"description\" content=\"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quads rental in Marbella and excursions : Aventouralia\" \/>\n<meta property=\"og:description\" content=\"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/\" \/>\n<meta property=\"og:site_name\" content=\"Excursiones en Quad y Alquiler de Quads en M\u00e1laga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/AvenTouralia\/100063686643527\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T09:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/10\/133952-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/\",\"url\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/\",\"name\":\"Quads rental in Marbella and excursions : Aventouralia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aventouralia.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/133952-2-1.jpg\",\"datePublished\":\"2023-08-31T09:31:29+00:00\",\"dateModified\":\"2026-04-28T09:15:39+00:00\",\"description\":\"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aventouralia.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/133952-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aventouralia.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/133952-2-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"133952 (2) (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/quads-rental-marbella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quads rental Marbella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/\",\"name\":\"Excursiones en Quad y Alquiler de Quads en M\u00e1laga\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#organization\",\"name\":\"Excursiones en Quad y Alquiler de Quads en M\u00e1laga\",\"url\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aventouralia.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Aventouralia-favicom.jpg\",\"contentUrl\":\"https:\\\/\\\/aventouralia.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Aventouralia-favicom.jpg\",\"width\":512,\"height\":512,\"caption\":\"Excursiones en Quad y Alquiler de Quads en M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/aventouralia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/AvenTouralia\\\/100063686643527\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aventouralia_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@aventouraliaquads8269\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quads rental in Marbella and excursions : Aventouralia","description":"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/","og_locale":"en_US","og_type":"article","og_title":"Quads rental in Marbella and excursions : Aventouralia","og_description":"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.","og_url":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/","og_site_name":"Excursiones en Quad y Alquiler de Quads en M\u00e1laga","article_publisher":"https:\/\/www.facebook.com\/people\/AvenTouralia\/100063686643527\/","article_modified_time":"2026-04-28T09:15:39+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/10\/133952-2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/","url":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/","name":"Quads rental in Marbella and excursions : Aventouralia","isPartOf":{"@id":"https:\/\/aventouralia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/#primaryimage"},"image":{"@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/#primaryimage"},"thumbnailUrl":"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/10\/133952-2-1.jpg","datePublished":"2023-08-31T09:31:29+00:00","dateModified":"2026-04-28T09:15:39+00:00","description":"Quad Tours and Quad Rental in Marbella. Discover the nature of the Costa del Sol in a different and unique way. Aventuralia.","breadcrumb":{"@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aventouralia.com\/en\/quads-rental-marbella\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/#primaryimage","url":"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/10\/133952-2-1.jpg","contentUrl":"https:\/\/aventouralia.com\/wp-content\/uploads\/2024\/10\/133952-2-1.jpg","width":1024,"height":683,"caption":"133952 (2) (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/aventouralia.com\/en\/quads-rental-marbella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aventouralia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Quads rental Marbella"}]},{"@type":"WebSite","@id":"https:\/\/aventouralia.com\/en\/#website","url":"https:\/\/aventouralia.com\/en\/","name":"Excursiones en Quad y Alquiler de Quads en M\u00e1laga","description":"","publisher":{"@id":"https:\/\/aventouralia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aventouralia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aventouralia.com\/en\/#organization","name":"Excursiones en Quad y Alquiler de Quads en M\u00e1laga","url":"https:\/\/aventouralia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aventouralia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aventouralia.com\/wp-content\/uploads\/2023\/09\/Aventouralia-favicom.jpg","contentUrl":"https:\/\/aventouralia.com\/wp-content\/uploads\/2023\/09\/Aventouralia-favicom.jpg","width":512,"height":512,"caption":"Excursiones en Quad y Alquiler de Quads en M\u00e1laga"},"image":{"@id":"https:\/\/aventouralia.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/AvenTouralia\/100063686643527\/","https:\/\/www.instagram.com\/aventouralia_\/","https:\/\/www.youtube.com\/@aventouraliaquads8269"]}]}},"_links":{"self":[{"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/pages\/5535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/comments?post=5535"}],"version-history":[{"count":10,"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/pages\/5535\/revisions"}],"predecessor-version":[{"id":15094,"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/pages\/5535\/revisions\/15094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/media\/8708"}],"wp:attachment":[{"href":"https:\/\/aventouralia.com\/en\/wp-json\/wp\/v2\/media?parent=5535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}